{"id":41567,"date":"2018-11-29T00:00:09","date_gmt":"2018-11-28T23:00:09","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=41567"},"modified":"2018-11-29T08:32:39","modified_gmt":"2018-11-29T07:32:39","slug":"la-storia-lidentita-e-limprudenza-nellagire","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/","title":{"rendered":"La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/ebrei_Roma.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-41568 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/ebrei_Roma-300x162.jpg\" alt=\"\" width=\"250\" height=\"135\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/ebrei_Roma-300x162.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/ebrei_Roma.jpg 306w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>da <a href=\"http:\/\/www.corrieredelsud.it\/nsite\/\" target=\"_blank\" rel=\"noopener\"><strong>Il Corriere del Sud<\/strong><\/a> anno XXVII<\/p>\n<p style=\"text-align: center;\">20 settembre 2018<\/p>\n<p style=\"text-align: justify;\"><em>Nel 75\u00b0 anniversario del rastrellamento tedesco della comunit\u00e0 degli ebrei romani del 1943 c\u2019\u00e8 ancora chi prova a riscrivere la storia perseguendo interessi ideologici e convenienze personali<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Giuseppe Brienza<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Non \u00e8 possibile, nell\u2019ora presente, capire qualcosa degli avvenimenti, sfuggire al disorientamento degli spiriti, evitare l\u2019imprudenza nell\u2019agire, giocare un ruolo utile nella politica o nella societ\u00e0 e persino essere semplicemente un uomo colto, un \u201canti-barbaro\u201d, senza solide conoscenze di storia e soprattutto senza avere il gusto della storia, perch\u00e9 bisogna avere il gusto della storia come si ha quello della poesia o dell\u2019arte<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Riprendiamo questa citazione del pensatore elvetico Gonzague de Reynold (1880-1970) [cfr. <em>Cercles concentriques. Etudes et morceaux sur la Suisse<\/em>, Les Editions du Chandeleir, Bienne 1943, pp. 182-183] riflettendo sulla notizia della cancellazione, da parte del Sindaco di Roma, dalla toponomastica della citt\u00e0 dei nomi di due scienziati italiani della prima met\u00e0 del XX secolo, lo psichiatra Arturo Donaggio (1868-1942), nel 1924 candidato al Nobel per la medicina ed il biologo Edoardo Zavattari (1883-1972), a lungo direttore dell&#8217;Istituto di zoologia dell&#8217;Universit\u00e0 \u201cLa Sapienza\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/leggi_raziali-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-41048 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/leggi_raziali-2-218x300.jpg\" alt=\"\" width=\"145\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/leggi_raziali-2-218x300.jpg 218w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/leggi_raziali-2.jpg 591w\" sizes=\"auto, (max-width: 145px) 100vw, 145px\" \/><\/a>\u00ab<em>Virginia Raggi ha fortemente voluto un atto eccezionale, la cancellazione dalla toponomastica dei nomi di chi aveva messo il proprio prestigio scientifico a servizio della diffusione di false e indegne teorie razziste<\/em>\u00bb. Cos\u00ec ha spiegato la decisione del primo cittadino pentastellato il Vicesindaco di Roma con delega alla \u201cCrescita Culturale\u201d Luca Bergamo, nel giorno stesso in cui l\u2019intestazione delle \u00ab<em>prime due strade<\/em>\u00bb (quindi la \u201cbonifica storico-ideologica\u201d \u00e8 destinata a continuare\u2026) di Roma sono sostituite passando dal nome di chi firm\u00f2 (in realt\u00e0 fu incluso a sua insaputa nella lista dei firmatari) il manifesto delle Leggi Razziali del 1938 a quello di due vittime della <em>Shoah<\/em> scelte dal Comune a seguito di \u00ab<em>un percorso partecipato con la Comunit\u00e0 ebraica di Roma<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u201cImprudenza nell\u2019agire\u201d causata da ignoranza? Diremmo proprio di s\u00ec, perch\u00e9 se Zavattari fu indubbiamente uno dei maggiori teorici, nel nostro Paese, dell\u2019ideologia condannabile del razzismo biologico, cancellare dalla memoria nazionale il prof. Donaggio appare un vero abuso. Dire che questo accreditato psichiatra abbia \u00ab<em>messo il proprio prestigio scientifico a servizio della diffusione di false e indegne teorie razziste<\/em>\u00bb ci sembra per lo meno una esagerazione storica.<\/p>\n<p style=\"text-align: justify;\">Direttore della clinica neuropsichiatrica dell&#8217;Universit\u00e0 di Bologna e presidente della <em>Societ\u00e0 italiana di Psichiatria<\/em>, Donaggio firm\u00f2 oltretutto il <em>Manifesto della razza<\/em> il 15 luglio 1938 (data nella quale questo documento fu pubblicato sul \u201cGiornale d\u2019Italia\u201d). A quel tempo la sua carriera scientifica era gi\u00e0 finita, se non altro perch\u00e9 era arrivato alla venerata et\u00e0 di settant\u2019anni (era nato a Falconara Marittima l\u201911 ottobre del 1868).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/leggi_raziali.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32354 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/leggi_raziali.jpg\" alt=\"\" width=\"201\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/leggi_raziali.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/leggi_raziali-150x150.jpg 150w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a>L\u2019ultimo incarico accademico-scientifico che Donaggio ricevette, quello nel 1935 di direttore della Clinica delle malattie nervose e mentali di Bologna, al tempo della promulgazione delle \u201cleggi razziali\u201d, era gi\u00e0 stato esperito e, nel luglio del 1938, lo studioso si era appunto ritirato dall&#8217;insegnamento per limiti d&#8217;et\u00e0. Morendo in un incidente automobilistico prima della caduta del regime fascista, cio\u00e8 nel 1942, non fece quindi in tempo, come provarono a fare due degli altri firmatari del Manifesto, a revocare la sua \u201cfirma\u201d e, quindi, protestare per essere stato incluso senza il suo espresso consenso nella lista dei firmatari.<\/p>\n<p style=\"text-align: justify;\">Come ha ricordato nel suo saggio del 2008 \u201cIl Manifesto della razza del 1938 e i cattolici\u201d lo storico gesuita Giovanni Sale, pare infatti, \u00ab<em>che nessuno dei firmatari sia stato interpellato prima della pubblicazione del Manifesto<\/em>\u00bb (\u00abLa Civilt\u00e0 Cattolica\u00bb, quaderno 3793, 5 luglio 2008). Questo antifascismo a scoppio ritardato, quindi, pomposamente annunciato con post, tweet e dichiarazioni varie quando non si rischia ormai pi\u00f9 niente perch\u00e9 il fascismo \u00e8 morto e sepolto da quasi un secolo, oltre che esecrabile perch\u00e9 privo di quelle \u00ab<em>solide conoscenze di storia<\/em>\u00bb che dovrebbero assistere, come ricordato dal de Reynold, chi esercita \u00ab<em>un ruolo nella politica o nella societ\u00e0<\/em>\u00bb, sembra pi\u00f9 che altro diretto a distogliere l\u2019attenzione sui veri (e grandi) problemi di Roma. Ha poco, o nulla, a che fare con l\u2019identit\u00e0, l\u2019anti-razzismo e la storia d\u2019Italia.<\/p>\n<p style=\"text-align: justify;\">Quanto detto non toglie che Papa Pio XI (1922-1939), fin dall\u2019inizio, condann\u00f2 il Manifesto della razza del 1938 come contrario alla dottrina cristiana, al diritto naturale e ad ogni elementare senso di umanit\u00e0, promuovendo una forte opera politico-diplomatica e di sensibilizzazione per scongiurare la legislazione razziale. Achille Ratti giunse persino a scrivere il 5 novembre 1938 una lettera a Vittorio Emanuele III, re d\u2019Italia, per impedire la promulgazione delle leggi razziali. rispose al Papa di aver trasmesso a Mussolini il suo messaggio, e che questo sarebbe stato tenuto &#8220;in massimo conto&#8221; per conciliare i punti di vista divergenti fra Chiesa e Stato.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/manifesto_razza.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30960 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/manifesto_razza.jpg\" alt=\"\" width=\"244\" height=\"200\" \/><\/a>Il primo provvedimento che, a torto, \u00e8 riportato nelle ricostruzioni di comodo come \u201cdi materia razziale\u201d del Regime fascista \u00e8 quello promulgato dal Governo Mussolini nell\u2019aprile del 1937 e vietava ai cittadini italiani di tenere \u00ab<em>relazione d\u2019indole coniugale con persona suddita dell\u2019Africa Orientale italiana<\/em>\u00bb. Tale legislazione, sicuramente di natura discriminatoria, non aveva per\u00f2 carattere razzista, perseguendo esclusivamente lo scopo morale di vietare il concubinato nei Paesi colonizzati. Tale tipo di convivenze coloniali avrebbero finito, si sosteneva, per snaturare il costume matrimoniale e sociale italiano introducendo oltretutto il \u201cmeticciato\u201d.<\/p>\n<p style=\"text-align: justify;\">Il Governo Mussolini fece di tutto, sia a livello sia normativo sia propagandistico, per scoraggiare e arginare tale fenomeno, chiedendo anche alla Chiesa Cattolica, e in particolare ai missionari presenti nelle colonie italiane, di collaborare con le autorit\u00e0 per dissuadere i battezzati dal contrarre \u00ab<em>matrimoni misti<\/em>\u00bb. Le autorit\u00e0 religiose, realisticamente, individuarono nei nuovi provvedimenti del Regime \u00ab<em>efficaci strumenti repressivi adatti a limitare comportamenti disordinati e a volte scandalosi dal punto di vista morale adottati dai nuovi conquistatori, i quali del resto si professavano cattolici<\/em>\u00bb (G. Sale S.I., art. cit.).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/razza_fascismo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-41569 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/razza_fascismo.jpg\" alt=\"\" width=\"250\" height=\"166\" \/><\/a>Per questo in una Nota del 1\u00b0 agosto 1938 indirizzata dal Nunzio Apostolico in Italia, il futuro cardinale Francesco Borgongini Duca (1884-1954), al Capo del Governo a tale proposito si diceva: \u00ab<em>La Santa Sede si compiace col Governo Italiano per aver colpito il concubinato fra gli italiani e gli indigeni di colore. Quanto a fiancheggiare l\u2019azione moralizzatrice del Governo, come si domanda dalle Autorit\u00e0 Coloniali, la Chiesa non si rifiuta di prestare largamente, per mezzo dei suoi missionari, l\u2019invocata opera di persuasione ad impedire tali ibride unioni, per i saggi motivi igienico sociali intesi dallo Stato, ma soprattutto per le ragioni di indole morale e religiosa, che hanno la maggiore efficacia nelle anime<\/em>\u00bb [cfr. Archivio Segreto Vaticano \u2013 Affari Ecclesiastici Straordinari (ASV &#8211; AAEESS), Italia, 1.040, 720, 22, cit. in G. Sale S.I., art. cit.].<\/p>\n<p style=\"text-align: justify;\">A chi dice che la Chiesa fece poco contro le leggi razziali del 1938 si pu\u00f2 tranquillamente rispondere che, Pio XI, fece tutto quello che poteva fare in una situazione delicata e drammatica come quella in cui fu chiamato ad operare. Di fronte ad un regime autoritario (quello fascista) che stava progressivamente andando verso l\u2019abbraccio mortale con un regime totalitario (quello nazionalsocialista tedesco), il Papa non poteva che salvaguardare la dottrina ma, insieme, operare per salvare le anime e, in prospettiva, le vite umane stesse. Compito della Chiesa non \u00e8 infatti quello di costituire fronti o fare rivoluzioni, bens\u00ec di agire gradualmente come \u201clievito\u201d per cercare di persuadere le menti e cambiare i cuori.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da Il Corriere del Sud anno XXVII 20 settembre 2018 Nel 75\u00b0 anniversario del rastrellamento tedesco della comunit\u00e0 degli ebrei romani del 1943 c\u2019\u00e8 ancora chi prova a riscrivere la storia perseguendo interessi ideologici e convenienze personali di Giuseppe Brienza<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":41568,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97,24,96],"tags":[1557,2101],"class_list":["post-41567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fascismo","category-storia","category-storia-italiana","tag-leggi-razziali","tag-m5s","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-28T23:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-29T07:32:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/ebrei_Roma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"306\" \/>\n\t<meta property=\"og:image:height\" content=\"165\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire\",\"datePublished\":\"2018-11-28T23:00:09+00:00\",\"dateModified\":\"2018-11-29T07:32:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/\"},\"wordCount\":1197,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/ebrei_Roma.jpg\",\"keywords\":[\"leggi razziali\",\"M5S\"],\"articleSection\":[\"Fascismo\",\"Storia\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/\",\"name\":\"La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/ebrei_Roma.jpg\",\"datePublished\":\"2018-11-28T23:00:09+00:00\",\"dateModified\":\"2018-11-29T07:32:39+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/ebrei_Roma.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/ebrei_Roma.jpg\",\"width\":306,\"height\":165},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-storia-lidentita-e-limprudenza-nellagire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/","og_locale":"it_IT","og_type":"article","og_title":"La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-11-28T23:00:09+00:00","article_modified_time":"2018-11-29T07:32:39+00:00","og_image":[{"width":306,"height":165,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/ebrei_Roma.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire","datePublished":"2018-11-28T23:00:09+00:00","dateModified":"2018-11-29T07:32:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/"},"wordCount":1197,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/ebrei_Roma.jpg","keywords":["leggi razziali","M5S"],"articleSection":["Fascismo","Storia","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/","name":"La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/ebrei_Roma.jpg","datePublished":"2018-11-28T23:00:09+00:00","dateModified":"2018-11-29T07:32:39+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/ebrei_Roma.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/ebrei_Roma.jpg","width":306,"height":165},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-storia-lidentita-e-limprudenza-nellagire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La storia, l\u2019identit\u00e0 e l\u2019imprudenza nell\u2019agire"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/41567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=41567"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/41567\/revisions"}],"predecessor-version":[{"id":41697,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/41567\/revisions\/41697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/41568"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=41567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=41567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=41567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}