{"id":41368,"date":"2018-11-08T00:00:03","date_gmt":"2018-11-07T23:00:03","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=41368"},"modified":"2018-10-30T15:53:38","modified_gmt":"2018-10-30T14:53:38","slug":"etica-pubblica-e-corruzione","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/","title":{"rendered":"Etica pubblica e corruzione"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-41369\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000-300x156.jpg\" alt=\"\" width=\"250\" height=\"130\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000-300x156.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000-768x400.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000-1024x533.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000.jpg 1920w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>da<strong> Il Corriere del Sud<\/strong> n. 5 anno XXVII<\/p>\n<p style=\"text-align: center;\">Crotone 15 giugno 2018<\/p>\n<p style=\"text-align: justify;\"><em>Temi centrali, oggi, letti alla luce degli insegnamenti del Catechismo della Chiesa Cattolica e del recente Magistero di Papa Francesco (e un riferimento all\u2019ordinamento italiano, in primo luogo all\u2019ANAC)<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Mauro Rotellini<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Papa Francesco, fin dall\u2019inizio del suo pontificato, ha trattato con molta frequenza i temi dell\u2019etica pubblica e della corruzione nella societ\u00e0 contemporanea. Il <em>Catechismo della Chiesa Cattolica <\/em>(CCC), del resto, fa di quest\u2019ultima degenerazione dell\u2019utilizzo dei poteri pubblici uno dei capisaldi di quel \u201crispetto dei beni altrui\u201d imposto dal settimo comandamento.<\/p>\n<p style=\"text-align: justify;\">Al n. 2409, fra l\u2019altro, tale documento universale fatto promulgare nel 1992 da San Giovanni Paolo II, ha il merito d\u2019identificare cos\u00ec i tre principali comportamenti che danno luogo ad una grave violazione dell\u2019etica pubblica:<\/p>\n<p style=\"text-align: justify;\">&#8211; sviare il giudizio di coloro che devono prendere decisioni in base al diritto;<\/p>\n<p style=\"text-align: justify;\">&#8211; operare o favorire l&#8217;appropriazione o l&#8217;uso privato dei beni sociali;<\/p>\n<p style=\"text-align: justify;\">&#8211; coprire o realizzare lavori eseguiti male, frodi fiscali, contraffazione di assegni e di fatture, spese eccessive, sperpero di risorse o beni pubblici.<\/p>\n<p style=\"text-align: justify;\">Tutto ci\u00f2, continua il CCC, arrecando \u00ab<em>volontariamente un danno alle propriet\u00e0 private o pubbliche, \u00e8 contrario alla legge morale ed esige il risarcimento<\/em>\u00bb (n. 2409).<\/p>\n<p style=\"text-align: justify;\">Nei suoi interventi in tema Papa Francesco ha avuto il merito di collegare frequentemente il fenomeno della corruzione con quello della mafia sia come organizzazione criminale sia come \u201cmentalit\u00e0\u201d. Parlando ad esempio all&#8217;udienza generale del 28 marzo 2018, il Pontefice ha condannato quei \u201c<em>cristiani finti<\/em>\u201d che dicono di essere \u201cuomini d\u2019onore\u201d mentre vivono \u00ab<em>una vita corrotta<\/em>\u00bb<em>. <\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/papa-Francesco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-33836\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/papa-Francesco.jpg\" alt=\"\" width=\"250\" height=\"186\" \/><\/a>Questi \u201c<em>cristiani finti<\/em>\u201d, proclama il Santa Padre nella stessa circostanza, \u00ab<em>finiranno male<\/em>\u00bb<em>. <\/em>E aggiunge: \u00ab<em>Il cristiano, ripeto, \u00e8 peccatore \u2013 tutti lo siamo, io lo sono \u2013 ma abbiamo la sicurezza che quando chiediamo perdono il Signore ci perdona. Il corrotto fa finta di essere una persona onorevole, ma, alla fine nel suo cuore c\u2019\u00e8 la putredine.<\/em> [\u2026]<em> Pensiamo \u2013 per non andare lontano \u2013 pensiamo a casa, pensiamo ai cosiddetti \u201ccristiani mafiosi\u201d. Ma questi di cristiano non hanno nulla: si dicono cristiani, ma portano la morte nell\u2019anima e agli altri<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Parole che mitigano quelle terribili pronunciate da Papa Francesco il 23 ottobre 2014, in Vaticano, rivolgendosi alla delegazione internazionale di diritto penale: \u00ab<em>la corruzione \u00e8 un male pi\u00f9 grande del peccato<\/em> [\u2026] <em>tuttavia il Signore non si stanca di bussare alle porte dei corrotti. La corruzione non pu\u00f2 nulla contro la speranza<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">In un intervento pi\u00f9 recente, infine, il Santo Padre \u00e8 ritornato in maniera \u201cfulminante\u201d sull\u2019argomento, invocando da Dio \u00ab<em>la forza di andare avanti <\/em>[e]<em> di continuare a lottare contro la corruzione<\/em>\u00bb (<em>tweet<\/em> del 19 luglio 2018).<\/p>\n<p style=\"text-align: justify;\">Inutile girarci intorno, il problema \u00e8 particolarmente avvertito soprattutto nei Paesi un tempo cattolici che, perdendo l\u2019identit\u00e0 e l\u2019etica cristiana, sprofondano sempre pi\u00f9, a cominciare dalle loro \u201cclassi dirigenti\u201d, nella corruzione. Ma anche quegli Stati nordici portati continuamente ad esempio dai media ed opinionisti occidentali nei confronti di quelli del Sud Europa che, a loro dire, non sarebbero stati \u201cilluminati\u201d dalla c.d. riforma protestante, hanno i loro problemi di mancanza di etica pubblica e di malaffare.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/corruzione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29503\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/corruzione.jpg\" alt=\"\" width=\"220\" height=\"200\" \/><\/a>La corruzione, infatti, non ha solamente una matrice mafiosa o camorristica, ma ha anche quella delle consorterie, pi\u00f9 o meno segrete, delle connivenze, degli aiuti interessati, dei reciproci favori che si trovano ovunque. In Francia, ad esempio, \u00e8 recentissima la denuncia di Alexis Kohler, segretario generale dell\u2019Eliseo, braccio destro del presidente Macron per \u201ctraffico di influenze\u201d. \u00c8 insomma un atteggiamento, una debolezza tipica della natura umana quella della corruzione, che non potranno certo essere vinte con sempre nuove norme o legislazioni pi\u00f9 severe.<\/p>\n<p style=\"text-align: justify;\">Potrebbe essere di aiuto il cambiamento della percezione sociale del funzionario (o imprenditore) \u201ccorrotto\u201d. Non \u00e8 facile, perch\u00e9 alla fine il corrotto \u201caiuta\u201d (se mi si passa il termine) altre persone che \u2013 in quel momento \u2013 sono in uno stato di bisogno (<em>bisogno<\/em> \u2013 sia chiaro \u2013 che spesso \u00e8 originato da loro volont\u00e0 non lecite: il costruttore che vuole utilizzare pi\u00f9 sabbia o cemento ha bisogno che il funzionario non controlli la composizione del cemento stesso etc.).<\/p>\n<p style=\"text-align: justify;\">In ultima analisi ha un ruolo \u201cpositivo\u201d per il corruttore, che \u00e8 la persona che conosce quanto accaduto ed \u00e8 quindi la sola a poterla smascherare con efficacia. Ovviamente i danni li paga la societ\u00e0 nel suo insieme. Ma questi danni, ripartiti sulla generalit\u00e0 dei cittadini non si avvertono subito, o si avvertono molto poco.<\/p>\n<p style=\"text-align: justify;\">Resterebbe poi inoltre il dubbio ruolo della \u201csanzione sociale\u201d che, come noto, pu\u00f2 essere ben indirizzata dai poteri dominanti, con esiti inquietanti. Come affrontare quindi la situazione d\u2019illiceit\u00e0 grave, gravissima, della situazione odierna? E qui si pu\u00f2 agire solo ritornando sul piano morale, a partire, mi si consenta, da quella \u201cparola ultima\u201d detta sempre da Papa Francesco, anche parlando in tema di etica pubblica e di lotta alla corruzione. Vale a dire la <em>speranza<\/em>.<\/p>\n<p style=\"text-align: justify;\">La speranza della societ\u00e0 di divenire pi\u00f9 moralmente pulita? S\u00ec certo. Ma queste sono le <em>speranze laiche<\/em> che, non vedendo il peccato originale, si riducono alla fine in meri e fatui auspici.<\/p>\n<p style=\"text-align: justify;\">Quella di cui il Santo Padre ci parla \u00e8 invece la speranza del corrotto e del corruttore di liberarsi e recuperare la propria dignit\u00e0, riconoscendo il peccato e, di conseguenza, il reato. Ma ci\u00f2 pu\u00f2 avvenire solo chiedendo perdono e perdonandosi, affrontandone le conseguenze e riscattando la propria persona. Certo, magari anche usufruendo di sconti di pena che il legislatore pu\u00f2 dare, ma soprattutto cogliendo ed alimentando la luce che la speranza del riscatto (eterno, ma anche contingente) pu\u00f2 accendere dentro di lui. Occorre allora una nuova evangelizzazione, un nuovo impegno della Chiesa, alla sequela di Papa Francesco, anche su questo versante.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/12\/corruzione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15072 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/12\/corruzione.jpg\" alt=\"\" width=\"250\" height=\"175\" \/><\/a>Per offrire un approfondimento tecnico di come gli ordinamenti pubblici possano o meno aiutare a contrastare i fenomeni degenerativi dell\u2019etica pubblica parliamo della situazione italiana e, in particolare, dell\u2019organismo-principe ideato negli ultimi anni, l\u2019<em>Autorit\u00e0 Nazionale Anticorruzione<\/em> (ANAC).<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 un argomento scelto a caso. Nel contratto di governo M5S-Lega, entrato in azione dopo le ultime elezioni politiche del 4 marzo 2018, infatti, si legge che nell&#8217;ambito delle misure anti corruzione \u00e8 necessario \u00ab<em>abbinare, oltre che un potenziamento dell\u2019Autorit\u00e0 Nazionale Anti-corruzione e del piano di prevenzione della corruzione, una modifica delle disposizioni vigenti \u2013 ad oggi non del tutto efficaci \u2013 in termini di prevenzione e repressione, anche rafforzando le tutele per il whistle-blower <\/em>[= il dipendente pubblico che segnala gli illeciti]<em>. In materia di intercettazioni \u00e8 opportuno intervenire per potenziarne l\u2019utilizzo, soprattutto per i reati di corruzione<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ma cosa \u00e8 esattamente l&#8217;<em>Autorit\u00e0 Nazionale Anticorruzione<\/em>?<\/p>\n<p style=\"text-align: justify;\">Si tratta di un&#8217;Autorit\u00e0 indipendente il cui scopo \u2013 si legge sul sito istituzionale \u2013 \u00e8 quello di prevenire la corruzione nell\u2019ambito delle amministrazioni pubbliche, cercando di diffondere e migliorare l\u2019attuazione della normativa in materia di trasparenza e svolgendo un&#8217;attivit\u00e0 di vigilanza nell\u2019ambito dei contratti pubblici, degli incarichi e comunque in ogni settore della pubblica amministrazione che potenzialmente possa sviluppare fenomeni corruttivi.<\/p>\n<p style=\"text-align: justify;\">Il nodo essenziale \u00e8 che l&#8217;ANAC agisce intervenendo in sede consultiva e di regolazione, nonch\u00e9 mediante attivit\u00e0 conoscitiva allo scopo di creare una rete di collaborazione nell\u2019ambito delle amministrazioni pubbliche e aumentare l\u2019efficienza nell\u2019utilizzo delle risorse, riducendo i controlli formali.<\/p>\n<p style=\"text-align: justify;\">La presenza di questa Autorit\u00e0 pone per\u00f2 molteplici problemi. Bisognerebbe infatti ricondurre l&#8217;ANAC all&#8217;interno dell&#8217;ordinario funzionamento della Pubblica amministrazione, comprimendone un po&#8217; i poteri, ma certamente non si prospetta un&#8217;azione facile, almeno per un governo e per un ministro, come quello della giustizia Alfonso Bonafede, che hanno fatto del giustizialismo una delle loro bandiere.<\/p>\n<p style=\"text-align: justify;\">Ma ritornando al punto: qual \u00e8 esattamente l&#8217;attivit\u00e0 cui \u00e8 istituzionalmente preposta l\u2019ANAC? Si pu\u00f2 dire che sia quella di regolare la disciplina dei contratti pubblici in Italia. Su questo punto dovrebbe intervenire e, giustamente, su questo tema verte oggi il dibattito. In merito, l&#8217;ANAC utilizza lo strumento delle \u201cLinee Guida\u201d, strumento che il Codice degli Appalti, al suo articolo 213, mette a disposizione dell&#8217;Autorit\u00e0 di Cantone per esercitare il suo potere di vigilanza e controllo sugli appalti pubblici.<\/p>\n<p style=\"text-align: justify;\">Il problema sta nel fatto che attraverso questo strumento, l&#8217;ANAC definisce e dettaglia il contenuto della norma del Codice degli Appalti. Svolge, quindi, in ultima analisi un&#8217;attivit\u00e0 legislativa, che si pone essa ai confini della legittimit\u00e0 costituzionale. Si tenga inoltre presente che alcune disposizioni contenute nelle \u201cLinee Guida\u201d hanno natura vincolante. Lo stesso Consiglio di Stato ha sottolineato nel suo parere 855\/2016 che il sistema \u00e8 contraddittorio.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione_Anac_logo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-41370\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione_Anac_logo-300x168.jpg\" alt=\"\" width=\"250\" height=\"140\" \/><\/a>Lo \u00e8 perch\u00e9 non si pu\u00f2 sostenere che delle \u201clinee guida\u201d (per loro natura generali e non di dettaglio) possano essere vincolanti e perch\u00e9 anche se potessimo considerarle atti amministrativi di natura generale e tecnica (e quindi non atti legislativi), difficilmente sarebbe sostenibile che esse possano intervenire in settori per i quali non esista o sia sconsigliato un intervento di natura legislativo (come per esempio negli interventi di regolazione del mercato dell\u2019Autorit\u00e0 sulla Concorrenza).<\/p>\n<p style=\"text-align: justify;\">E se cos\u00ec fosse, come potrebbero vincolare le Regioni nelle materie di loro competenza sulle quali la Costituzione riconosce potest\u00e0 regolamentare?<\/p>\n<p style=\"text-align: justify;\">Un esempio concreto: quando l&#8217;ANAC emana una disposizione nelle \u201cLinee Guida\u201d che definisce criteri di selezione ex art. 83 del Codice degli Appalti, svolge non un&#8217;attivit\u00e0 tecnica, ma applica principi di opportunit\u00e0 e una discrezionalit\u00e0 tipica del legislatore regolando i rapporti tra cittadini, pubblica amministrazione e imprese. Essa appare essere quindi pi\u00f9 una nuova fonte del diritto che un regolamento di applicazione\u2026 Sarebbe dunque necessario riconoscere a tali tipi di interventi normativi natura di legge. Ma questo \u00e8 escluso dalla Costituzione, che riconosce solo nei due rami del Parlamento la potest\u00e0 legislativa. E allora?<\/p>\n<p style=\"text-align: justify;\">In effetti, come abbiamo velocemente rappresentato, i rapporti tra l\u2019attuale configurazione dell\u2019ANAC e il processo legislativo sarebbero da rivedere. Nel tentativo di combattere la corruzione, quindi, ruoli, competenze e obiettivi dovrebbero essere del tutto rivisti.<\/p>\n<p style=\"text-align: justify;\">Ma tutto ci\u00f2 non toglie che per un cristiano \u00e8 evidente come anche nel fenomeno della corruzione pubblica si manifesti quel <em>mysterium iniquitatis<\/em> che \u00e8 e sar\u00e0 sempre parte ineliminabile della natura umana. Ma non possiamo accettarlo supinamente. Il Magistero di Papa Francesco \u00e8 su questo punto continuo e \u201cmobilitante\u201d. Bisognerebbe davvero ascoltarlo perch\u00e9 ridice la millenaria sapienza della Chiesa.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da Il Corriere del Sud n. 5 anno XXVII Crotone 15 giugno 2018 Temi centrali, oggi, letti alla luce degli insegnamenti del Catechismo della Chiesa Cattolica e del recente Magistero di Papa Francesco (e un riferimento all\u2019ordinamento italiano, in primo luogo all\u2019ANAC) di Mauro Rotellini<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":41370,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42,11,25],"tags":[782,2218],"class_list":["post-41368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dottrina-e-morale","category-dottrina-sociale","category-sguardo-sul-nostro-tempo","tag-corruzione","tag-etica-pubblica","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Etica pubblica e corruzione - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Etica pubblica e corruzione - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-07T23:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione_Anac_logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Etica pubblica e corruzione\",\"datePublished\":\"2018-11-07T23:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/\"},\"wordCount\":1669,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/corruzione_Anac_logo.jpg\",\"keywords\":[\"corruzione\",\"etica pubblica\"],\"articleSection\":[\"Dottrina e morale\",\"Dottrina sociale\",\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/\",\"name\":\"Etica pubblica e corruzione - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/corruzione_Anac_logo.jpg\",\"datePublished\":\"2018-11-07T23:00:03+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/corruzione_Anac_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/corruzione_Anac_logo.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/etica-pubblica-e-corruzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Etica pubblica e corruzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Etica pubblica e corruzione - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/","og_locale":"it_IT","og_type":"article","og_title":"Etica pubblica e corruzione - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-11-07T23:00:03+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione_Anac_logo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Etica pubblica e corruzione","datePublished":"2018-11-07T23:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/"},"wordCount":1669,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione_Anac_logo.jpg","keywords":["corruzione","etica pubblica"],"articleSection":["Dottrina e morale","Dottrina sociale","Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/","name":"Etica pubblica e corruzione - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione_Anac_logo.jpg","datePublished":"2018-11-07T23:00:03+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione_Anac_logo.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione_Anac_logo.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/etica-pubblica-e-corruzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Etica pubblica e corruzione"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/41368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=41368"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/41368\/revisions"}],"predecessor-version":[{"id":41371,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/41368\/revisions\/41371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/41370"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=41368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=41368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=41368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}