{"id":41110,"date":"2018-09-27T00:00:18","date_gmt":"2018-09-26T22:00:18","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=41110"},"modified":"2018-09-19T15:30:37","modified_gmt":"2018-09-19T13:30:37","slug":"idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/","title":{"rendered":"Idlib: I &#8220;Guardiani della Religione&#8221; &#8230;ovvero la nuova ala armata di Al Qaeda in Siria"},"content":{"rendered":"<div id=\"attachment_41111\" style=\"width: 250px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/Siria_Al_Qaeda.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-41111\" class=\"wp-image-41111\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/Siria_Al_Qaeda-300x167.jpg\" alt=\"\" width=\"250\" height=\"139\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/Siria_Al_Qaeda-300x167.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/Siria_Al_Qaeda.jpg 400w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><p id=\"caption-attachment-41111\" class=\"wp-caption-text\">Miliziani di Jaysh al-Badia, membri di Hurras al-Deen, che entrano in combattimento con una bandiera con il logo di &#8220;Al-Qaeda&#8221;<\/p><\/div>\n<p style=\"text-align: center;\">da <a href=\"http:\/\/www.comite-valmy.org\/spip.php?article10380\" target=\"_blank\" rel=\"noopener\">Co<strong>mit\u00e9 Valmy<\/strong><\/a>, 13 settembre 2018<\/p>\n<p style=\"text-align: center;\">Traduzione in italiano di <strong>Gb.P.<\/strong><\/p>\n<p style=\"text-align: justify;\">La complessit\u00e0 del dossier Idlib legata alla molteplicit\u00e0 delle interferenze regionali e internazionali, ai conflitti di interesse tra i belligeranti e all&#8217;escalation dei combattimenti raggiunge una nuova dimensione in relazione alle organizzazioni armate sul terreno; queste ultime stanno considerando la loro integrazione in organizzazioni meglio dotate di mezzi militari e materiali, come il Fronte di Liberazione Nazionale [al-jabhat al-watania lil&#8217;tahrir] sostenuto dalla Turchia, il Fronte al-Nusra e l&#8217;Organizzazione dei guardiani della religione [Tanzim Hurras al-Dine] tutti ideologicamente legati ad Al Qaeda.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda il Fronte Al-Nusra, avendo la Turchia alla fine accettato, sotto la pressione dei Russi, di collocarlo nella sua lista delle organizzazioni terroristiche, per un ultimo tentativo di separare i cosiddetti gruppi armati &#8220;estremisti&#8221; dai gruppi suoi alleati che essa descrive come &#8220;moderati&#8221;, molti dei suoi combattenti saranno indotti a cercare la loro salvezza unendosi al <strong>Tanzim di Hurras al-Deen [THD]<\/strong>; un&#8217;organizzazione nata nel febbraio 2018.<\/p>\n<p style=\"text-align: justify;\">Una tempistica che spinge qualsiasi osservatore della situazione siriana a interrogarsi sulle ragioni e sugli obiettivi della creazione di questo secondo braccio armato di Al-Qaeda in questo ultimo &#8220;quarto d&#8217;ora&#8221; della guerra in Siria. Domande le cui risposte derivano dall&#8217;osservazione dei conflitti tra i gruppi armati dentro Idlib che riflettono, in primo luogo, gli interessi contrastanti degli Stati che li sostengono e la necessit\u00e0 di creare un sostituto per il Fronte al-Nusra per il recupero dei suoi leader in caso di un accordo sulla sua eliminazione.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Siria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-40790\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Siria.jpg\" alt=\"\" width=\"250\" height=\"150\" \/><\/a>Da qui il ruolo svolto dalla CIA nell&#8217;emergere del THD, che \u00e8 stato schierato nelle aree precedentemente invase dall&#8217;organizzazione Jound al-Aqsa [I soldati di al-Aqsa] notoriamente sostenuta dagli Stati Uniti prima che fossero costretti a metterla nella lista delle organizzazioni terroristiche; specialmente nel nord della provincia di Hama e in alcune zone intorno a Sarmine, vicino alla citt\u00e0 di Idlib.<\/p>\n<p style=\"text-align: justify;\">Da notare che il THD si \u00e8 rivelato pi\u00f9 generoso dell&#8217;organizzazione Jound al-Aqsa, offrendo stipendi di 200.000 Lire siriane e che il suo finanziamento, di origine oscura, passa attraverso le banche kuwaitiane che sono sotto il controllo del sistema bancario statunitense.<\/p>\n<p style=\"text-align: justify;\">\u00c8 quindi molto probabile che presto vedremo aumentare l&#8217;attivit\u00e0 dei &#8216;Guardiani della Religione&#8217; THD a spese di altre organizzazioni armate, anche se l&#8217;accordo regionale e internazionale per eliminare il Fronte al-Nusra si \u00e8 rivelato simbolico. A sostegno di questa tesi:<\/p>\n<p style=\"text-align: justify;\"><strong>1<\/strong>. Lo sfruttamento da parte del THD della sua grande fedelt\u00e0 ad al Qaeda e il reclutamento di nomi diventati famosi sul campo di battaglia, per meglio accreditarsi sul mercato dei finanziatori del takfirismo e dei sostenitori preoccupati di farlo tornare al suo glorioso passato, in Siria. Tra queste celebrit\u00e0: Abu Hammam al-Shami, soprannominato &#8220;Abu Hammam al-<a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/Siria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-28790\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/Siria.jpg\" alt=\"\" width=\"250\" height=\"174\" \/><\/a>Askari&#8221;, che ha preso il comando del THD; l&#8217;ex comandante militare di al-Nusra, Samir al-Hijazi; il giordano Iyad Tubas, espulso dalla Siria meridionale due anni e mezzo or sono, soprannominato &#8220;Abu al-ourdouni Julaybib&#8221;; Bilal Khreissate soprannominato &#8220;Abu Khadija al-Urdini&#8221;; questi ultimi due hanno contribuito ad attrarre la corrente salafista giordana e altre correnti salafite dei paesi del Golfo. In questo, i &#8216;Guardiani della Religione&#8217; mostrano l&#8217;immagine che si vuole dare: quella di un&#8217;organizzazione che ha rifiutato la separazione di Al-Nusra da Al Qaeda, ha formato un corpo militare indipendente, ha dichiarato la sua fedelt\u00e0 ad Al Qaeda e agisce sotto la sua direzione e secondo la sua dottrina.<\/p>\n<p style=\"text-align: justify;\"><strong>2.<\/strong> Il reclutamento del maggior numero di combattenti stranieri e locali possibile, in modo che il THD abbia un peso importante nel nord del paese. Infatti, dal suo inizio il THD ha raccolto circa 9.000 combattenti [e quindi, tanti combattenti terroristi a Idlib quanti sono i combattenti statunitensi nella Siria nord-orientale] cifra che dovrebbe triplicare e persino quadruplicare in base alle previsioni grazie al suo finanziamento e al suo coordinamento. Tra queste reclute troviamo ex di Daesh (ISIS) che erano stanziati a Idlib, oltre a noti terroristi che hanno preso parte ai combattimenti in Iraq e in Afghanistan, dove hanno acquisito grande esperienza nei combattimenti e probabilmente nella raccolta di informazioni; abilit\u00e0 che possono rafforzare i suoi legami con la leadership centrale di Al-Qaeda ed estendere la sua rete di contatti a diverse sezioni dell&#8217;organizzazione terrorista.<\/p>\n<p style=\"text-align: justify;\"><strong>3.<\/strong> L&#8217;esasperazione delle tensioni militari e politiche a Idlib: alcune fonti indicano che <strong>i servizi segreti statunitensi <\/strong>cercano di riunire tutti gli estremisti arabi e stranieri all&#8217;interno del THD al fine di raggiungere diversi obiettiv<\/p>\n<ul>\n<li style=\"text-align: justify;\">Trasferire la maggior parte di queste reclute in quello che chiamano &#8220;Ard al-Tamkin&#8221; [la Terra del Califfato] in Libia e sul Sinai egiziano, per riciclarle poi in nuove battaglie<\/li>\n<li style=\"text-align: justify;\">Logorare il pi\u00f9 possibile l&#8217;Esercito Arabo Siriano nella battaglia imminente di Idlib, partendo dal principio che gli adepti di THD sono estremisti e stranieri con fede nella dottrina della morte, non interessati nel processo di riconciliazione.<\/li>\n<li style=\"text-align: justify;\">Tirare il tappeto sotto i piedi dei Turchi minando <a href=\"https:\/\/ejmagnier.com\/2018\/09\/14\/the-liberation-of-idlib-turkey-is-in-the-way-with-russia-slowing-down\/\" target=\"_blank\" rel=\"noopener\">il loro ruolo nei colloqui<\/a> di Astana e privandoli della carta del Fronte al-Nusra, da un lato; e torcere loro il braccio costringendoli a sottomettersi di fronte al rischio di attacchi terroristici di THD all&#8217;interno del loro territorio, dall&#8217;altro. In quest&#8217;ultimo caso, possiamo dire che Washington e Riyad sarebbero i primi beneficiari.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/06\/siria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-7679\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/06\/siria.jpg\" alt=\"\" width=\"250\" height=\"188\" \/><\/a>Quindi \u00e8 chiaro che nell&#8217;ultimo quarto d&#8217;ora della crisi siriana vedremo tutti i tipi di eventi drammatici con il ricorso a tutte le possibili mosse contorte, come le accuse sull&#8217;uso di armi chimiche da parte dell&#8217;Esercito Siriano, come si sta sbandierando al momento, al fine di giustificare una conseguente probabile aggressione straniera e cercare di salvare quelli che possono salvare tra gli estremisti armati, evacuandoli attraverso &#8220;corridoi sicuri&#8221; verso altri campi di combattimento<\/p>\n<p style=\"text-align: justify;\">Pertanto, probabilmente non sar\u00e0 una sorpresa concludere che quando Staffan de Mistura &#8211; inviato speciale delle Nazioni Unite in Siria &#8211; riduce il numero di terroristi nella provincia di Idlib a 10.000 [Consiglio di sicurezza del 7 settembre 2018] e propone di offrirsi personalmente ed andare l\u00ec egli stesso per assicurare un corridoio di uscita&#8230; tende a<a href=\"https:\/\/www.presstv.com\/DetailFr\/2018\/09\/14\/574113\/Syrie-le-tout-nouveau-plan-de-lOccident\" target=\"_blank\" rel=\"noopener\"> servire lo stesso progetto<\/a>.<\/p>\n<p style=\"text-align: justify;\">&#8220;Probabilmente ricorderete l&#8217;orribile periodo ad Aleppo, quando i combattenti di al-Nusra rifiutarono la mia offerta di accompagnarli fuori dalla citt\u00e0 &#8230; e alla fine partirono per Idlib. Per questo abbiamo perso almeno due mesi e migliaia di persone sono morte &#8230; Quindi, ancora una volta, sono pronto a impegnarmi personalmente e fisicamente. Questa volta con la cooperazione del governo [siriano] poich\u00e9 esso controlla le aree circostanti. Sono pronto a fornire un corridoio umanitario temporaneo in modo che i civili possano partire e tornare a casa incolumi quando tutto sar\u00e0 finito &#8220;[*]<\/p>\n<p style=\"text-align: justify;\"><strong><em>NdT Comit\u00e9 Valmy<\/em><\/strong>: <em>Ci ricordiamo in particolare signor de Mistura, la sua proposta di un &#8220;blocco dei combattimenti&#8221; ad Aleppo, seguita da quella di creare &#8220;commissioni locali per terroristi&#8221; nelle parti orientali della citt\u00e0. Come dimenticare? Oggi Aleppo, liberata dai terroristi, ma non ancora dalle loro bombe, vive di nuovo. E&#8217; fuori questione che il governo siriano le consenta di farla di nuovo sanguinare. Cos\u00ec come \u00e8 fuori questione che Idlib e il popolo siriano debbano continuare a essere dissanguati sotto i colpi della diplomazia dell&#8217;ONU che si pretende umanitaria, ma certamente \u00e8 inumana<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Mohammad Nader al-Oumari<\/strong> , Scrittore e ricercatore<\/p>\n<p style=\"text-align: center;\">Fonte originaria: <u><a href=\"http:\/\/alwatan.sy\/archives\/165736\" target=\"_blank\" rel=\"noopener\">Al-Watan<\/a><\/u>.Tradotto dall&#8217;arabo da Mouna Alno-Nakhal<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da Comit\u00e9 Valmy, 13 settembre 2018 Traduzione in italiano di Gb.P. La complessit\u00e0 del dossier Idlib legata alla molteplicit\u00e0 delle interferenze regionali e internazionali, ai conflitti di interesse tra i belligeranti e all&#8217;escalation dei combattimenti raggiunge una nuova dimensione in relazione alle organizzazioni armate sul terreno; queste ultime stanno considerando la loro integrazione in organizzazioni &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":41111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,19],"tags":[440,2278],"class_list":["post-41110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paesi-e-continenti","category-politica-internazionale","tag-siria","tag-stato-islamico","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Idlib: I &quot;Guardiani della Religione&quot; ...ovvero la nuova ala armata di Al Qaeda in Siria - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Idlib: I &quot;Guardiani della Religione&quot; ...ovvero la nuova ala armata di Al Qaeda in Siria - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-26T22:00:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/Siria_Al_Qaeda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"222\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Idlib: I &#8220;Guardiani della Religione&#8221; &#8230;ovvero la nuova ala armata di Al Qaeda in Siria\",\"datePublished\":\"2018-09-26T22:00:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/\"},\"wordCount\":1233,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Siria_Al_Qaeda.jpg\",\"keywords\":[\"Siria\",\"stato islamico\"],\"articleSection\":[\"Paesi e continenti\",\"Politica internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/\",\"name\":\"Idlib: I \\\"Guardiani della Religione\\\" ...ovvero la nuova ala armata di Al Qaeda in Siria - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Siria_Al_Qaeda.jpg\",\"datePublished\":\"2018-09-26T22:00:18+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Siria_Al_Qaeda.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Siria_Al_Qaeda.jpg\",\"width\":400,\"height\":222},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Idlib: I &#8220;Guardiani della Religione&#8221; &#8230;ovvero la nuova ala armata di Al Qaeda in Siria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Idlib: I \"Guardiani della Religione\" ...ovvero la nuova ala armata di Al Qaeda in Siria - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/","og_locale":"it_IT","og_type":"article","og_title":"Idlib: I \"Guardiani della Religione\" ...ovvero la nuova ala armata di Al Qaeda in Siria - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-09-26T22:00:18+00:00","og_image":[{"width":400,"height":222,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/Siria_Al_Qaeda.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Idlib: I &#8220;Guardiani della Religione&#8221; &#8230;ovvero la nuova ala armata di Al Qaeda in Siria","datePublished":"2018-09-26T22:00:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/"},"wordCount":1233,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/Siria_Al_Qaeda.jpg","keywords":["Siria","stato islamico"],"articleSection":["Paesi e continenti","Politica internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/","name":"Idlib: I \"Guardiani della Religione\" ...ovvero la nuova ala armata di Al Qaeda in Siria - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/Siria_Al_Qaeda.jpg","datePublished":"2018-09-26T22:00:18+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/Siria_Al_Qaeda.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/09\/Siria_Al_Qaeda.jpg","width":400,"height":222},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/idlib-i-guardiani-della-religione-ovvero-la-nuova-ala-armata-di-al-qaeda-in-siria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Idlib: I &#8220;Guardiani della Religione&#8221; &#8230;ovvero la nuova ala armata di Al Qaeda in Siria"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/41110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=41110"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/41110\/revisions"}],"predecessor-version":[{"id":41114,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/41110\/revisions\/41114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/41111"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=41110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=41110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=41110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}