{"id":4108,"date":"2010-09-30T00:00:00","date_gmt":"2010-09-29T22:00:00","guid":{"rendered":""},"modified":"2015-11-13T09:51:54","modified_gmt":"2015-11-13T08:51:54","slug":"la-visita-di-benedetto-xvi-in-gran-bretagna-1","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/","title":{"rendered":"La visita di Benedetto XVI in Gran Bretagna (1)"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/Benedetto-in-UK.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-27664 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/Benedetto-in-UK.jpg\" alt=\"Benedetto in UK\" width=\"200\" height=\"158\" \/><\/a>Cesnur<\/strong> 24 settembre 2010<\/div>\n<p style=\"text-align: center;\"><em>In viaggio con il beato Newman.<strong><br \/>\n<\/strong><\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Massimo Introvigne<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Il viaggio apostolico di Papa Benedetto XVI in Gran Bretagna, dal 16 al 19 settembre 2010, ha avuto lo scopo di celebrare il cardinale John Henry Newman C.O. (1801-1890) e proclamarne la beatificazione. Con il pontificato di Benedetto XVI le cerimonie di beatificazione sono normalmente affidate ai vescovi locali, e non pi\u00f9 al Pontefice.<\/div>\n<p style=\"text-align: justify;\">Per il beato Newman il Santo Padre ha inteso fare un\u2019eccezione, anzitutto perch\u00e9 \u2013 ha confidato \u2013 \u00abil cardinale Newman ha avuto da tanto tempo un influsso importante nella mia vita e nel mio pensiero\u00bb (Benedetto XVI 2010q).Pi\u00f9 in generale, si tratta di una personalit\u00e0 di \u00abeccezionale grandezza per il nostro tempo\u00bb (Benedetto XVI 2010a), \u00abuno studioso di grande levatura, un insigne scrittore e poeta, un sapiente uomo di Dio, il cui pensiero ha illuminato molte coscienze e ancora oggi esercita un fascino straordinario\u00bb (Benedetto XVI 2010v), \u00abuna figura di dottore della Chiesa\u00bb (Benedetto XVI 2010a) \u2013 ancorch\u00e9 non sia stato ancora formalmente proclamato come tale \u2013 che ha affrontato alcuni dei principali problemi della modernit\u00e0. Nel corso del viaggio Benedetto XVI \u00e8 tornato sugli stessi problemi, sia ricordando gli insegnamenti del beato Newman sia applicandoli al contesto odierno.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019omelia per la Messa di beatificazione a Birmingham, il Pontefice ha segnalato tre principali insegnamenti del beato Newman che si \u00e8 proposto d\u2019illustrare nel suo viaggio: \u00absulla relazione fra fede e ragione, sullo spazio vitale della religione rivelata nella societ\u00e0 civilizzata, e sulla necessit\u00e0 di un approccio all\u2019educazione ampiamente fondato e a lungo raggio\u00bb (Benedetto XVI 2010p). Convinto che \u00abil beato John Henry Newman, la cui figura e cui scritti conservano ancora una formidabile attualit\u00e0, merita di essere conosciuto da tutti\u00bb (Benedetto XVI 2010v), a ciascuno dei tre temi Benedetto XVI ha dedicato ampie riflessioni.<\/p>\n<p style=\"text-align: justify;\"><strong>1. Fede e ragione<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>a. Il beato Newman e la modernit\u00e0<\/em><\/p>\n<p style=\"text-align: justify;\">Il beato Newman \u00abha vissuto tutto il problema della modernit\u00e0\u00bb (Benedetto XVI 2010a) e ha \u00abancora molto da insegnarci sulla vita e la testimonianza cristiane tra le sfide del mondo contemporaneo, sfide che egli previde con eccezionale chiarezza\u00bb (Benedetto XVI 2010u). Nel corso del suo viaggio in Portogallo (cfr. Introvigne 2010a) Benedetto XVI ha affrontato il tema della modernit\u00e0, distinguendo fra istanze e domande legittime, che la Chiesa ha accolto, e risposte sbagliate che hanno dato vita a une vera e propria ideologia del moderno, denunciata dalla Chiesa come errata e pericolosa.<\/p>\n<p style=\"text-align: justify;\">\u00abIn un mondo gi\u00e0 pieno di crescente rumore e confusione, pieno di false vie che conducono solo a profondo dolore del cuore ed illusione\u00bb (Benedetto XVI 2010q), Newman ha assunto le istanze della modernit\u00e0 \u00abcon tutti i dubbi e i problemi del nostro essere di oggi\u00bb (Benedetto XVI 2010a), ma ha fornito risposte inequivocabilmente cristiane e diffidenti nei confronti di ogni forma d\u2019ideologia.<\/p>\n<p style=\"text-align: justify;\">Si pu\u00f2 ricordare qui quello che \u00e8 forse il pi\u00f9 celebre discorso del beato Newman, il <em>Biglietto Speech<\/em> (\u00abDiscorso del biglietto\u00bb), pronunciato a Roma il 12 maggio 1879 in risposta alla lettura del biglietto con cui il cardinale Segretario di Stato Lorenzo Nina (1812-1885) lo informava formalmente della sua elevazione a cardinale da parte di Papa Leone XIII (1878-1903). Qui il beato \u2013 di cui cito il testo nella nuova traduzione italiana pubblicata sull\u2019<em>Osservatore Romano <\/em>del 13 maggio 2009 \u2013 tiene a precisare che \u00abfin dall\u2019inizio mi sono opposto ad una grande sciagura. Per trenta, quaranta, cinquant\u2019anni ho cercato di contrastare con tutte le mie forze lo spirito del liberalismo nella religione.<\/p>\n<p style=\"text-align: justify;\">Mai la santa Chiesa ha avuto maggiore necessit\u00e0 di qualcuno che vi si opponesse pi\u00f9 di oggi, quando, ahim\u00e9! si tratta ormai di un errore che si estende come trappola mortale su tutta la terra; e nella presente occasione, cos\u00ec grande per me, quando \u00e8 naturale che io estenda lo sguardo a tutto il mondo, alla santa Chiesa e al suo futuro, non sar\u00e0 spero ritenuto inopportuno che io rinnovi quella condanna che gi\u00e0 cos\u00ec spesso ho pronunciato. Il liberalismo in campo religioso \u00e8 la dottrina secondo cui non c\u2019\u00e8 alcuna verit\u00e0 positiva nella religione, ma un credo vale quanto un altro, e questa \u00e8 una convinzione che ogni giorno acquista pi\u00f9 credito e forza\u00bb (Newman 2009). Parole davvero tuttora attuali nella nostra \u00abepoca in cui un pervasivo relativismo minaccia di oscurare l\u2019immutabile verit\u00e0 sulla natura dell\u2019uomo\u00bb (Benedetto XVI 2010v).<\/p>\n<p style=\"text-align: justify;\">Il liberalismo, continua il <em>Biglietto Speech<\/em>, \u00ab\u00e8 contro qualunque riconoscimento di una religione come vera. Insegna che tutte devono essere tollerate, perch\u00e9 per tutte si tratta di una questione di opinioni. La religione rivelata non \u00e8 una verit\u00e0, ma un sentimento e una preferenza personale; non un fatto oggettivo o miracoloso; ed \u00e8 un diritto di ciascun individuo farle dire tutto ci\u00f2 che pi\u00f9 colpisce la sua fantasia. La devozione non si fonda necessariamente sulla fede. Si possono frequentare le Chiese protestanti e le Chiese cattoliche, sedere alla mensa di entrambe e non appartenere a nessuna. Si pu\u00f2 fraternizzare e avere pensieri e sentimenti spirituali in comune, senza nemmeno porsi il problema di una comune dottrina o sentirne l\u2019esigenza. Poich\u00e9 dunque la religione \u00e8 una caratteristica cos\u00ec personale e una propriet\u00e0 cos\u00ec privata, si deve assolutamente ignorarla nei rapporti tra le persone. Se anche uno cambiasse religione ogni mattina, a te che cosa dovrebbe importare? Indagare sulla religione di un altro non \u00e8 meno indiscreto che indagare sulle sue risorse economiche o sulla sua vita familiare\u00bb (Newman 2009).<\/p>\n<p style=\"text-align: justify;\">L\u2019ideologia della modernit\u00e0 \u00e8 qui colpita al cuore con la denuncia del relativismo. Su questo tema Benedetto XVI \u00e8 ripetutamente tornato nel corso del viaggio in Gran Bretagna.<\/p>\n<p style=\"text-align: justify;\"><em>b. L\u2019insidia del relativismo<\/em><\/p>\n<p style=\"text-align: justify;\">\u00abAi nostri giorni \u2013 afferma Benedetto XVI \u2013, quando un relativismo intellettuale e morale minaccia di fiaccare i fondamenti stessi della nostra societ\u00e0, Newman ci rammenta che, quali uomini e donne creati ad immagine e somiglianza di Dio, siamo stati creati per conoscere la verit\u00e0, per trovare in essa la nostra definitiva libert\u00e0 e l\u2019adempimento delle pi\u00f9 profonde aspirazioni umane\u00bb (Benedetto XVI 2010q). Rifiutare il relativismo, spiega il Pontefice, comporta non soltanto il riconoscimento che esiste una verit\u00e0 ma anche \u2013 cosa che oggi rischia di riuscire ancora pi\u00f9 difficile \u2013 la denuncia dell\u2019errore. Se esiste il vero, esiste anche il falso. \u00abColoro che vivono della e nella verit\u00e0 riconoscono istintivamente ci\u00f2 che \u00e8 falso e, proprio perch\u00e9 falso, \u00e8 nemico della bellezza e della bont\u00e0 che accompagna lo splendore della verit\u00e0, <em>veritatis splendor<\/em>\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Il beato Newman \u00e8 ricordato per le sue profonde riflessioni sulla nozione di coscienza. Il suo insegnamento, pienamente conforme alla dottrina della Chiesa, \u00e8 stato per\u00f2 talora presentato in modo equivoco. Alcuni interpretano la stessa nozione di coscienza in modo relativista, come se si trattasse di seguire la propria \u00abpreferenza personale\u00bb (Newman 2009) a prescindere da ogni autorit\u00e0 esterna. Mentre la coscienza cui fa riferimento Newman \u00e8 la \u00abcoscienza retta\u00bb (Benedetto XVI 2010).<\/p>\n<p style=\"text-align: justify;\">Due articoli dell\u2019allora prefetto della Congregazione per la Dottrina della Fede, cardinale Joseph Ratzinger, chiariscono i possibili equivoci in riferimento al beato Newman. Servirsene per commentare il viaggio del Papa \u00e8 tanto meno improprio in quanto egli stesso ha voluto richiamare in Gran Bretagna il suo lungo dialogo con il beato Newman nel corso del suo itinerario di teologo. Commentando le famose \u2013 e per qualche aspetto controverse \u2013 parole del beato nella <em>Lettera al Duca di Norfolk<\/em> secondo cui \u00abse fossi obbligato a introdurre la religione nei brindisi dopo un pranzo (il che in verit\u00e0 non mi sembra proprio la cosa migliore), brinder\u00f2, se volete, al Papa; tuttavia prima alla coscienza, poi al Papa\u00bb (Newman 1999, 237), il cardinale Ratzinger commenta che la frase va inquadrata nel complessivo pensiero di Newman e nella sua fedelt\u00e0 alla \u00abtradizione medioevale [che] giustamente aveva individuato due livelli del concetto di coscienza, che si devono distinguere accuratamente, ma anche mettere sempre in rapporto l\u2019uno con l\u2019altro.<\/p>\n<p style=\"text-align: justify;\">Molte tesi inaccettabili sul problema della coscienza mi sembrano dipendere dal fatto che si \u00e8 trascurata o la distinzione o la correlazione tra i due elementi\u00bb (Ratzinger 1991, 89).<\/p>\n<p style=\"text-align: justify;\">Il Medioevo parlava di sinderesi e coscienza; il cardinale Ratzinger precisa questi due termini come \u00abanamnesi della creazione\u00bb (<em>ibid.<\/em>) e \u00abanamnesi della fede\u00bb (<em>ibid.<\/em>). La prima, l\u2019anamnesi della creazione, deriva dal fatto che con la creazione \u00ab\u00e8 stato infuso in noi qualcosa di simile ad una originaria memoria del bene e del vero\u00bb (<em>ibid.<\/em>). La seconda, l\u2019anamnesi della fede, nasce dalla redenzione a opera di Ges\u00f9 Cristo \u00abil cui raggio a partire dal Logos redentore si estende oltre il dono della creazione\u00bb (<em>ibid.<\/em>) la cui memoria \u00e8 custodita dalla Chiesa e, nella Chiesa, dal Papa. Cronologicamente, l\u2019anamnesi della creazione viene prima: \u00absi identifica col fondamento stesso della nostra esistenza\u00bb (<em>ibid.<\/em>) e fonda la possibilit\u00e0 anche dell\u2019anamnesi della memoria. Come la creazione precede storicamente la redenzione, cos\u00ec perch\u00e9 ci sia una coscienza formata e illuminata dalla Chiesa e dal Papa occorre prima che ci sia una coscienza.<\/p>\n<p style=\"text-align: justify;\">In questo senso \u00absiamo ora in grado di comprendere correttamente il brindisi di Newman prima per la coscienza e solo dopo per il Papa\u00bb (<em>ibid.<\/em>). I due brindisi stanno in sequenza, non in contrapposizione.<\/p>\n<p style=\"text-align: justify;\">Se invece si ritiene che l\u2019appello alla coscienza sia solo una giustificazione per seguire il proprio arbitrio \u2013 \u00abFai ci\u00f2 che vuoi sar\u00e0 tutta la legge\u00bb (Crowley 1938, cap. I, v. 40), secondo la celebre formula dell\u2019esoterista inglese Aleister Crowley (1875-1947), il quale non solo dava a questa proposizione un fondamento specificamente magico, ma in essa catturava l\u2019essenza stessa della magia come primato del potere \u2013 il passaggio successivo non pu\u00f2 che essere l\u2019abolizione della coscienza.<\/p>\n<p style=\"text-align: justify;\">Per fare quel che si vuole non c\u2019\u00e8 bisogno della legge, n\u00e9 della coscienza. Il relativismo liberale evolve cos\u00ec naturalmente verso il relativismo aggressivo delle ideologie del secolo XX fino all\u2019affermazione del gerarca nazional-socialista Hermann G\u00f6ring (1893-1946), citata dal cardinale Ratzinger: \u00abIo non ho nessuna coscienza! La mia coscienza \u00e8 Adolf Hitler [1889-1945]\u00bb (Ratzinger 1990, 432). La nozione relativista della coscienza porta ultimamente all\u2019eliminazione della coscienza.<\/p>\n<p style=\"text-align: justify;\">Il cattolico, nota il cardinale Ratzinger, non adotta certamente la formula di G\u00f6ring mettendo il Papa al posto di Hitler. Questa sarebbe una versione caricaturale del cattolicesimo: \u00abuna simile concezione moderna e volontaristica dell\u2019autorit\u00e0 pu\u00f2 soltanto deformare l\u2019autentico significato teologico del papato\u00bb (Ratzinger 1991, 89). Il cattolico dir\u00e0 al contrario di avere una coscienza, e di trovare in essa una memoria del bene originario e l\u2019apertura alla \u00abpossibilit\u00e0\u00bb (<em>ibid.<\/em>) di una rivelazione di Dio, che di quel bene \u00e8 fondamento.<\/p>\n<p style=\"text-align: justify;\">Nel momento in cui accetta per fede che Dio si \u00e8 rivelato in Ges\u00f9 Cristo, \u00e8 pronto ad accogliere la tesi che il Papa \u00e8 \u00abgarante della memoria\u00bb (<em>ibid.<\/em>) della rivelazione cristiana. Il Magistero del Papa entra cos\u00ec nella coscienza, per cos\u00ec dire, dall\u2019interno: \u00abtutto il potere che egli [il Papa] ha \u00e8 potere della coscienza\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Il cardinale Ratzinger cita come prova del carattere tutt\u2019altro che soggettivo e arbitrario dell\u2019idea di coscienza nel beato Newman precisamente la sua conversione dalla Comunione Anglicana alla Chiesa Cattolica del 1845. \u00abProprio perch\u00e9 Newman spiegava l\u2019esistenza dell\u2019uomo a partire dalla coscienza, ossia nella relazione tra Dio e l\u2019anima, era anche chiaro che questo personalismo non rappresentava nessun cedimento all\u2019individualismo, e che il legame alla coscienza non significava nessuna concessione all\u2019arbitrariet\u00e0 \u2013 anzi che si trattava proprio del contrario.<\/p>\n<p style=\"text-align: justify;\">Da Newman abbiamo imparato a comprendere il primato del Papa: la libert\u00e0 di coscienza \u2013 cos\u00ec ci insegnava Newman \u2013 non si identifica affatto col diritto di <em>\u201cdispensarsi dalla coscienza, di ignorare il<\/em> <em>Legislatore e il Giudice, e di essere indipendenti da doveri invisibili\u201d. <\/em>In tal modo la coscienza, nel suo significato autentico, \u00e8 il vero fondamento dell\u2019autorit\u00e0 del Papa. Infatti la sua forza viene dalla Rivelazione, che completa la coscienza naturale illuminata in modo solo incompleto, e <em>\u201cla sua <\/em>[del Papa]<em> raison d\u2019\u00eatre \u00e8 quella di<\/em> <em>essere il campione della legge morale e della coscienza\u201d <\/em>(J. H. Newman, <em>Lettera al Duca di Norfolk, Coscienza \u00e8 libert\u00e0<\/em>, a cura di V. Gambi, Paoline, Milano 1999, p. 226)\u00bb (Ratzinger 1990, 433-434).<\/p>\n<p style=\"text-align: justify;\">\u00abQuesta dottrina sulla coscienza \u2013 continuava nel 1990 il cardinale Ratzinger \u2013 \u00e8 diventata per me sempre pi\u00f9 importante nello sviluppo successivo della Chiesa e del mondo. Mi accorgo sempre di pi\u00f9 che essa si dischiude in modo completo solo in riferimento alla biografia del Cardinale, la quale suppone tutto il dramma spirituale del suo secolo. Newman, in quanto uomo della coscienza, era divenuto un convertito; fu la sua coscienza che lo condusse dagli antichi legami e dalle antiche certezze dentro il mondo per lui difficile e inconsueto del cattolicesimo.<\/p>\n<p style=\"text-align: justify;\">Tuttavia, proprio questa via della coscienza \u00e8 tutt\u2019altro che una via della soggettivit\u00e0 che afferma se stessa: \u00e8 invece una via dell\u2019obbedienza alla verit\u00e0 oggettiva. Il secondo passo del cammino di conversione che dura tutta la vita di Newman fu infatti il superamento della posizione del soggettivismo evangelico, in favore d\u2019una concezione del Cristianesimo fondata sull\u2019oggettivit\u00e0 del dogma [\u2026]. E solo cos\u00ec, attraverso il legame alla verit\u00e0, a Dio, la coscienza riceve valore, dignit\u00e0 e forza\u00bb (<em>ibid.<\/em>, 434).<\/p>\n<p style=\"text-align: justify;\">Quando a proposito della conversione al cattolicesimo ricordiamo che il beato Newman fu \u00abmosso dal seguire la propria coscienza, anche con un pesante costo personale\u00bb (Benedetto XVI 2010g), o che san Tommaso Moro (1478-1535), giustiziato per ordine del re Enrico VIII (1491-1547), di cui era stato Lord Cancelliere ma che non aveva voluto seguire nella sua rivolta contro il Papa, \u00abfu capace di seguire la propria coscienza, anche a costo di dispiacere al proprio sovrano, di cui era \u201cbuon servitore\u201d\u00bb (Benedetto XVI 2010h), non ci riferiamo a opzioni o semplici preferenze soggettive ma a un rapporto con la verit\u00e0 oggettiva \u2013 \u00abquella verit\u00e0 [che ultimamente] \u00e8 nient\u2019altro che Ges\u00f9 Cristo\u00bb (Benedetto XVI 2010g) \u2013 cos\u00ec forte da rendere disposti a sacrificare affetti, amicizie e perfino la proprio stessa vita.<\/p>\n<p style=\"text-align: justify;\">E la questione della coscienza ha un diretto collegamento con il rapporto fra fede e ragione. Il beato Newman, insegna Benedetto XVI, fu insieme \u00abintellettuale e credente, il cui messaggio spirituale si pu\u00f2 sintetizzare nella testimonianza che la via della coscienza non \u00e8 chiusura nel proprio \u201cio\u201d, ma \u00e8 apertura, conversione e obbedienza a Colui che \u00e8 Via, Verit\u00e0 e Vita\u00bb (Benedetto XVI 2010v).<\/p>\n<p style=\"text-align: justify;\"><em>c. Il corretto rapporto tra fede e ragione<\/em><\/p>\n<p style=\"text-align: justify;\">Solo una volta che si \u00e8 sgombrato il campo dal relativismo \u00e8 possibile impostare correttamente, alla scuola del beato Newman, il problema del rapporto fra fede e ragione. Sul punto, certamente non nuovo nel suo Magistero, Benedetto XVI ha offerto importanti approfondimenti nel discorso ai parlamentari e alle autorit\u00e0 nella Westminster Hall di Londra.<\/p>\n<p style=\"text-align: justify;\">\u00abLa tradizione cattolica \u2013 ha affermato il Pontefice \u2013 sostiene che le norme obiettive che governano il retto agire sono accessibili alla ragione, prescindendo dal contenuto della rivelazione\u00bb (Benedetto XVI 2010h). Dunque, queste norme possono \u00abessere conosciute dai non credenti\u00bb (<em>ibid.<\/em>), cos\u00ec che la fede non ha il compito diretto di \u00abfornire tali norme\u00bb (<em>ibid.<\/em>). Ma questo significa che la fede deve limitarsi a rimanere sullo sfondo, lasciando che sia la ragione da sola a discernere le norme del \u00abretto agire\u00bb?<\/p>\n<p style=\"text-align: justify;\">No, risponde Benedetto XVI. In effetti la ragione discerne queste norme con difficolt\u00e0. Il credente sa che la ragione della difficolt\u00e0 sta nel peccato originale, ma che il compito sia difficile \u00e8 chiaro anche a chi non crede.<\/p>\n<p style=\"text-align: justify;\">Ecco allora che la fede interviene per \u00abaiutare nel purificare e gettare luce sull\u2019applicazione della ragione nella scoperta dei principi morali oggettivi\u00bb (<em>ibid.<\/em>). \u00abLa \u201cluce gentile\u201d della fede\u00bb (Benedetto XVI 2010q), come la chiamava il beato Newman, \u00abci conduce a renderci conto della verit\u00e0\u00bb (<em>ibid.<\/em>). Se sempre vi sono stati non credenti sospettosi di fronte alla fede, oggi per\u00f2 \u00e8 sorta una difficolt\u00e0 nuova.<\/p>\n<p style=\"text-align: justify;\">\u00abQuesto ruolo \u201ccorrettivo\u201d della religione nei confronti della ragione, tuttavia, non \u00e8 sempre bene accolto, in parte poich\u00e9 delle forme distorte di religione, come il settarismo e il fondamentalismo, possono mostrarsi esse stesse causa di seri problemi sociali\u00bb (Benedetto XVI 2010h). Se si lascia che la fede abbia un ruolo nel discernere le norme dell\u2019agire, il campo \u2013 si obietta oggi \u2013 \u00e8 lasciato libero ai fondamentalisti che giustificano con la fede attentati suicidi come quelli, ispirati al fondamentalismo islamico, dell\u201911 settembre 2001 a New York e a Washington o del 7 luglio 2005 a Londra. L\u2019obiezione, rileva Benedetto XVI, va presa sul serio. In effetti, \u00abdistorsioni della religione emergono quando viene data una non sufficiente attenzione al ruolo purificatore e strutturante della ragione all\u2019interno della religione\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">L\u2019interazione fra fede e ragione non \u00e8 a senso unico. Al contrario, \u00ab\u00e8 un processo che funziona nel doppio senso\u00bb (<em>ibid.<\/em>). Da una parte, \u00absenza il correttivo fornito dalla religione, [\u2026] la ragione pu\u00f2 cadere preda di distorsioni, come avviene quando essa \u00e8 manipolata dall\u2019ideologia, o applicata in un modo parziale\u00bb (<em>ibid.<\/em>). Dall\u2019altra, se si separa dalla ragione, la fede degenera in fondamentalismo. \u00abPer questo vorrei suggerire che il mondo della ragione ed il mondo della fede \u2013 il mondo della secolarit\u00e0 razionale e il mondo del credo religioso \u2013 hanno bisogno l\u2019uno dell\u2019altro e non dovrebbero avere timore di entrare in un profondo e continuo dialogo, per il bene della nostra civilt\u00e0\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\"><em>d. Verit\u00e0 ed ecumenismo<\/em><\/p>\n<p style=\"text-align: justify;\">Il beato Newman, come si \u00e8 accennato, nacque nella comunit\u00e0 anglicana e fu sacerdote anglicano dal 1825 al 1845, quando fu accolto nella Chiesa Cattolica dal beato Domenico Barberi C.P. (1792-1849). La sua beatificazione in terra inglese non poteva dunque non essere occasione per una riflessione di Benedetto XVI sull\u2019ecumenismo, tanto pi\u00f9 in un contesto segnato dai molti anglicani che, delusi dalle aperture della loro comunit\u00e0 al sacerdozio femminile e al matrimonio omosessuale, sono riaccolti, ripercorrendo cos\u00ec il percorso del beato Newman, nella Chiesa di Roma.<\/p>\n<p style=\"text-align: justify;\">La materia \u00e8 ora regolata nella Chiesa Cattolica dalla Costituzione apostolica <em>Anglicanorum coetibus<\/em>, del 4 novembre 2009, nei cui confronti \u2013 a fronte di obiezioni secondo le quali l\u2019accoglienza di questi anglicani nuocerebbe all\u2019ecumenismo \u2013 Benedetto XVI ha esortato i vescovi cattolici britannici a \u00abessere generosi\u00bb (Benedetto XVI 2010t), ricordando che \u00abscopo ultimo di ogni attivit\u00e0 ecumenica [\u00e8] la restaurazione della piena comunione ecclesiale\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Benedetto XVI ha voluto dare al suo viaggio un carattere marcatamente ecumenico, moltiplicando i gesti di simpatia nei confronti delle autorit\u00e0 anglicane, e ricordando in Scozia \u00abil centenario della Conferenza Missionaria Mondiale di Edimburgo [ del 1910], che \u00e8 generalmente considerata come la nascita del movimento ecumenico moderno\u00bb (Benedetto XVI 2010c).<\/p>\n<p style=\"text-align: justify;\">Nello stesso tempo, proprio ricordando l\u2019intransigente opposizione a ogni forma di relativismo del beato Newman, il Pontefice ha pure ricordato, visitando l\u2019Arcivescovo di Canterbury, primate della Comunione Anglicana, che \u00abla Chiesa \u00e8 chiamata ad essere inclusiva, ma mai a scapito della verit\u00e0 cristiana. Qui si colloca il dilemma che sta davanti a tutti coloro che sono genuinamente impegnati nel cammino ecumenico\u00bb (Benedetto XVI 2010g).<\/p>\n<p style=\"text-align: justify;\">Visitando l\u2019Abbazia di Westminster, il cuore storico della Comunione Anglicana, il Papa non si \u00e8 astenuto dal ricordare che la sua visita avviene \u00abin fedelt\u00e0 al mio ministero di Vescovo di Roma e Successore di San Pietro, incaricato di una cura particolare per l\u2019unit\u00e0 del gregge di Cristo\u00bb (Benedetto XVI 2010l).<\/p>\n<p style=\"text-align: justify;\">L\u2019ecumenismo fra le Chiese e comunit\u00e0 cristiane non pu\u00f2 che avere al suo centro \u2013 a fronte di tante dubbie formulazioni \u2013 il riconoscimento come fatto storico della morte e resurrezione di Ges\u00f9 Cristo, figlio di Dio e Dio egli stesso. \u00abIl nostro impegno per l\u2019unit\u00e0 dei cristiani non ha altro fondamento che la nostra fede in Cristo, in <em>questo<\/em> Cristo, risorto da morte e assiso alla destra del Padre, che torner\u00e0 nella gloria per giudicare i vivi e i morti. \u00c8 la <em>realt\u00e0 <\/em>della persona di Cristo, la sua opera salvifica e soprattutto il fatto storico della sua risurrezione, che \u00e8 il contenuto del kerygma apostolico e di quelle formule di fede che, a partire dal Nuovo Testamento stesso, hanno garantito l\u2019integrit\u00e0 della sua trasmissione. L\u2019unit\u00e0 della Chiesa, in una parola, non pu\u00f2 mai essere altro che una unit\u00e0 nella fede apostolica\u00bb (<em>ibid<\/em>.).<\/p>\n<p style=\"text-align: justify;\">Il mancato riconoscimento del carattere essenziale e non negoziabile di questi fondamenti della fede \u00e8 alla radice delle \u00abdelusioni\u00bb (<em>ibid.<\/em>) che l\u2019ecumenismo ha sperimentato nella sua storia recente.<\/p>\n<p style=\"text-align: justify;\"><em>e. Verit\u00e0 e dialogo interreligioso<\/em><\/p>\n<p style=\"text-align: justify;\">Il primato della verit\u00e0 deve contraddistinguere anche il dialogo interreligioso con i non cristiani, un tema di particolare attualit\u00e0 nella Gran Bretagna di oggi caratterizzata dal multiculturalismo, un\u2019espressione ambigua che indica sia un fatto \u2013 la compresenza sullo stesso territorio di tante diverse religioni e culture \u2013 sia un\u2019ideologia relativista, per cui le culture e religioni sarebbero tutte di uguale valore e non esisterebbero criteri tali da permettere un discernimento.<\/p>\n<p style=\"text-align: justify;\">Il Papa propone una preziosa distinzione tra tre diversi livelli di dialogo interreligioso. Non tutti e tre i livelli sono possibili con tutti gli interlocutori. Con alcuni non si potr\u00e0 che limitarsi al primo: il \u00abdialogo della vita\u00bb (Benedetto XVI 2010f), il quale \u00abimplica semplicemente vivere fianco a fianco ed imparare l\u2019uno dall\u2019altro in maniera da crescere nella reciproca comprensione e nel reciproco rispetto\u00bb (<em>ibid<\/em>.), coesistendo pacificamente e astenendosi da ogni insulto o violenza. Gi\u00e0 questo primo dialogo non \u00e8 semplice, e comporta problemi delicati.<\/p>\n<p style=\"text-align: justify;\">Anzitutto \u2013 il Papa lo afferma a Londra, di fronte tra l\u2019altro ad alcuni dei pi\u00f9 autorevoli rappresentanti del mondo islamico britannico \u2013 \u00aboccorre reciprocit\u00e0 da parte di tutte le componenti in dialogo e da parte dei seguaci delle altre religioni. Penso in particolare a situazioni in alcune parti del mondo, in cui la collaborazione e il dialogo fra religioni richiede il rispetto reciproco, la libert\u00e0 di praticare la propria religione e di compiere atti di culto pubblico, come pure la libert\u00e0 di seguire la propria coscienza senza soffrire ostracismo o persecuzione, anche dopo la conversione da una religione ad un\u2019altra\u00bb (<em>ibid<\/em>.). \u00abUn dialogo sincero [\u2026] ha bisogno del rispetto del principio di reciprocit\u00e0\u00bb (Benedetto XVI 2010v).<\/p>\n<p style=\"text-align: justify;\">Il secondo livello \u00e8 quello del \u00abdialogo dell\u2019azione\u00bb (Benedetto XVI 2010f), possibile quando \u2013 sia pure sulla base di motivazioni diverse \u2013 si condividono obiettivi comuni e si riconoscono principi della legge naturale, di per s\u00e9 accessibili anche alla sola ragione. In questo caso diventano possibili \u00abforme concrete di collaborazione\u00bb (<em>ibid<\/em>.). Gli esempi scelti da Benedetto XVI sono significativi. Si pu\u00f2 per esempio, afferma, \u00abesplorare assieme come difendere la vita umana ad ogni stadio e come assicurare la non esclusione della dimensione religiosa di individui e comunit\u00e0 dalla vita della societ\u00e0\u00bb (<em>ibid<\/em>.).<\/p>\n<p style=\"text-align: justify;\">Il terzo livello, infine, \u00e8 quello del dialogo delle idee, delle \u00abdiscussioni formali\u00bb (<em>ibid<\/em>.) per un riavvicinamento teologico, di cui Benedetto XVI non manca di sottolineare i limiti. In queste conversazioni, nota pure il Pontefice, \u00abnon vi \u00e8 solo la necessit\u00e0 dello scambio teologico, ma anche il porre alla reciproca considerazione le proprie ricchezze spirituali, il parlare della propria esperienza di preghiera e di contemplazione\u00bb (<em>ibid<\/em>.). Questo potrebbe effettivamente diventare una forma di testimonianza a favore della rilevanza della religione in un mondo che, come notava il beato Newman, sempre pi\u00f9 spesso pensa di poterne fare a meno.<\/p>\n<p style=\"text-align: justify;\"><strong>2. La rilevanza pubblica della religione<\/strong><\/p>\n<p style=\"text-align: justify;\">Nel <em>Biglietto Speech <\/em>del 1879 il beato Newman lamenta la perdita di rilevanza pubblica del cristianesimo nella Gran Bretagna del suo tempo. \u00abFinora \u2013 afferma \u2013 il potere civile \u00e8 stato cristiano. Anche in Nazioni separate dalla Chiesa, come nella mia, quand\u2019ero giovane valeva ancora il <em>detto<\/em>: \u201cIl cristianesimo \u00e8 la legge del Paese\u201d. Ora questa struttura civile della societ\u00e0, che \u00e8 stata creazione del cristianesimo, sta rigettando il cristianesimo.<\/p>\n<p style=\"text-align: justify;\">Il <em>detto<\/em>, e tanti altri che ne conseguivano, \u00e8 scomparso o sta scomparendo, e per la fine del secolo, se Dio non interviene, sar\u00e0 del tutto dimenticato. Finora si pensava che bastasse la religione con le sue sanzioni soprannaturali ad assicurare alla nostra popolazione la legge e l\u2019ordine; ora filosofi e politici tendono a risolvere questo problema senza l\u2019aiuto del cristianesimo. Al posto dell\u2019autorit\u00e0 e dell\u2019insegnamento della Chiesa, essi sostengono innanzitutto un\u2019educazione totalmente secolarizzata, intesa a far capire ad ogni individuo che essere ordinato, laborioso e sobrio torna a suo personale vantaggio.<\/p>\n<p style=\"text-align: justify;\">Poi si forniscono i grandi principi che devono sostituire la religione e che le masse cos\u00ec educate dovrebbero seguire, le verit\u00e0 etiche fondamentali nel loro senso pi\u00f9 ampio, la giustizia, la benevolenza, l\u2019onest\u00e0, ecc; l\u2019esperienza acquisita; e quelle leggi naturali che esistono e agiscono spontaneamente nella societ\u00e0 e nelle cose sociali, sia fisiche che psicologiche, ad esempio, nel governo, nel commercio, nella finanza, nel campo sanitario e nei rapporti tra le Nazioni.<\/p>\n<p style=\"text-align: justify;\">Quanto alla religione, essa \u00e8 un lusso privato, che uno pu\u00f2 permettersi, se vuole, ma che ovviamente deve pagare, e che non pu\u00f2 n\u00e9 imporre agli altri n\u00e9 infastidirli praticandola lui stesso. Le caratteristiche generali di questa grande <em>apostasia<\/em> sono identiche dovunque; ma nei particolari variano a seconda dei Paesi. Parler\u00f2 del mio Paese perch\u00e9 lo conosco meglio. Temo che essa avr\u00e0 qui un grande seguito, anche se non si pu\u00f2 immaginare come finir\u00e0\u00bb (Newman 2009).<\/p>\n<p style=\"text-align: justify;\">In teoria, i principi di benevolenza e di onest\u00e0 che sono pubblicamente proclamati non sono falsi. \u00ab\u00c8 solo quando ci accorgiamo che questo bell\u2019elenco di principi \u00e8 inteso a mettere da parte e cancellare completamente la religione, che ci troviamo costretti a condannare il liberalismo. Invero, non c\u2019\u00e8 mai stato un piano del Nemico cos\u00ec abilmente architettato e con pi\u00f9 grandi possibilit\u00e0 di riuscita. E, di fatto, esso sta ampiamente raggiungendo i suoi scopi, attirando nei propri ranghi moltissimi uomini capaci, seri ed onesti, anziani stimati, dotati di lunga esperienza, e giovani di belle speranze\u00bb (<em>ibid<\/em>.).<\/p>\n<p style=\"text-align: justify;\">La situazione dei nostri giorni non \u00e8 molto diversa da quella dei tempi del beato Newman. Per molti versi, \u00e8 perfino peggiorata. Riproponendo un\u2019espressione gi\u00e0 usata in altri discorsi, il Papa denuncia \u00abuna \u201cdittatura del relativismo\u201d [che] minaccia di oscurare l\u2019immutabile verit\u00e0 sulla natura dell\u2019uomo, il suo destino e il suo bene ultimo. Vi sono oggi alcuni che cercano di escludere il credo religioso dalla sfera pubblica, di privatizzarlo o addirittura di presentarlo come una minaccia all\u2019uguaglianza e alla libert\u00e0\u00bb (Benedetto XVI 2010c).<\/p>\n<p style=\"text-align: justify;\">Beninteso, questi \u00abalcuni\u00bb rappresentano i poteri forti e la cultura dominante. Vi \u00e8 ancora un popolo cristiano britannico che si ribella alla cultura egemone o almeno ha nostalgia di una cultura diversa, come dimostra lo stesso entusiasmo che ha fatto della visita del Papa un successo al di l\u00e0 di ogni previsione, e ha colto di sorpresa <em>media<\/em> in gran parte prevenuti e ostili. Tornando sulla visita tre giorni dopo la sua conclusione, Benedetto XVI ha osservato che \u00abnelle quattro intense e bellissime giornate trascorse in quella nobile terra ho avuto la grande gioia di parlare al cuore degli abitanti del Regno Unito, ed essi hanno parlato al mio, specialmente con la loro presenza e con la testimonianza della loro fede. Ho potuto infatti constatare quanto l\u2019eredit\u00e0 cristiana sia ancora forte e tuttora attiva in ogni strato della vita sociale. Il cuore dei britannici e la loro esistenza sono aperti alla realt\u00e0 di Dio e vi sono numerose espressioni di religiosit\u00e0 che questa mia visita ha posto ancora pi\u00f9 in evidenza. Sin dal primo giorno della mia permanenza nel Regno Unito, e durante tutto il periodo del mio soggiorno, ovunque ho ricevuto una calorosa accoglienza\u00bb (Benedetto XVI 2010v).<\/p>\n<p style=\"text-align: justify;\"><em>a. Ritornare alle radici<\/em><\/p>\n<p style=\"text-align: justify;\">Per riaffermare la rilevanza pubblica del cristianesimo in Gran Bretagna, il beato Newman aveva deciso di lanciare una collana di volumetti dedicata ai santi britannici. Ne sarebbe emerso che la storia britannica era strettamente legata ai santi e alla Chiesa. Il venerabile Giovanni Paolo II (1978-2005) e Benedetto XVI hanno fatto di questo programma un metodo. In qualunque Paese di tradizione cristiana si siano recati, sempre hanno insistito sul fatto che le origini e la storia di questo Paese sono segnate dall\u2019opera dei santi e da una particolare presenza della Madonna.<\/p>\n<p style=\"text-align: justify;\">Infatti, \u00able antiche nazioni dell&#8217;Europa hanno <em>un\u2019anima cristiana<\/em>, che costituisce un tutt\u2019uno col \u201cgenio\u201d e la storia dei rispettivi popoli, e la Chiesa non cessa di lavorare per mantenere continuamente desta questa tradizione spirituale e culturale\u00bb (Benedetto XVI 2010v).<\/p>\n<p style=\"text-align: justify;\">Sulla scia di Newman, Benedetto XVI ritorna sistematicamente nel suo viaggio al tema della \u00ablunga storia dell\u2019Inghilterra, cos\u00ec profondamente segnata dalla predicazione del Vangelo e dalla cultura cristiana dalla quale \u00e8 nata\u00bb (Benedetto XVI 2010i), e delle \u00abprofonde radici cristiane che sono tuttora presenti in ogni strato della vita britannica\u00bb (Benedetto XVI 2010b).<\/p>\n<p style=\"text-align: justify;\">La stessa architettura e l\u2019arte, cui Benedetto XVI non manca mai di essere attento, \u00abparlano in maniera tanto eloquente della nostra comune eredit\u00e0 di fede\u00bb (Benedetto XVI 2010l), e dalle abbazie e cattedrali \u00abnon possiamo non essere richiamati a come la fede cristiana abbia plasmato in modo cos\u00ec profondo l\u2019unit\u00e0 e la cultura dell\u2019Europa ed il cuore e lo spirito del popolo inglese\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Questa memoria si articola in quattro diversi passaggi. In primo luogo, il Pontefice \u2013 proprio per sottolineare il rilievo pubblico e politico della fede \u2013 ricorda i re, le regine e le principesse canonizzate, che non si ritrovano soltanto in Gran Bretagna ma qui hanno espresso pi\u00f9 di una figura di grande rilievo spirituale e storico. Rivolgendosi alla regina Elisabetta II il Papa cos\u00ec si esprime: \u00abI monarchi d\u2019Inghilterra e Scozia erano cristiani sin dai primissimi tempi ed includono straordinari Santi come Edoardo il Confessore [1002-1066] e Margherita di Scozia [1045-1093]. Come Le \u00e8 noto, molti di loro hanno esercitato coscienziosamente i loro doveri sovrani alla luce del Vangelo, modellando in tal modo la nazione nel bene al livello pi\u00f9 profondo.<\/p>\n<p style=\"text-align: justify;\">Ne risult\u00f2 che il messaggio cristiano \u00e8 diventato parte integrale della lingua, del pensiero e della cultura dei popoli di queste isole per pi\u00f9 di un millennio. Il rispetto dei vostri antenati per la verit\u00e0 e la giustizia, per la clemenza e la carit\u00e0 giungono a voi da una fede che rimane una forza potente per il bene nel vostro regno\u00bb (<em>ibid<\/em>.). In particolare, Sant\u2019Edoardo il Confessore, \u00abre d\u2019Inghilterra, rimane un modello di testimonianza cristiana ed un esempio di quella vera grandezza alla quale il Signore nelle Scritture chiama i suoi discepoli\u00bb (Benedetto XVI 2010l).<\/p>\n<p style=\"text-align: justify;\">In secondo luogo \u2013 citando esplicitamente il suo viaggio in Francia del 2008, dove aveva affermato che le radici dell\u2019Europa non sono solo cristiane, ma monastiche (cfr. Introvigne 2008) \u2013 Benedetto XVI richiama il ruolo essenziale svolto per la nascita delle nazioni che compongono la Gran Bretagna dai \u00abmonaci che hanno cos\u00ec tanto contribuito alla evangelizzazione di queste isole. Sto pensando ai Benedettini che accompagnarono Sant\u2019Agostino [di Canterbury, 534-604] nella sua missione in Inghilterra, ai discepoli di San Columba [521-597], che hanno diffuso la fede in Scozia e nell\u2019Inghilterra del Nord, a San Davide [ca. 512-601] e ai suoi compagni nel Galles\u00bb (Benedetto XVI 2010d).<\/p>\n<p style=\"text-align: justify;\">Salutando i cattolici del Galles, che il Papa non ha potuto includere nella sua visita, convenuti nella cattedrale di Westminster a Londra, Benedetto XVI afferma che il loro patrono \u00abSan Davide fu uno dei grandi santi del sesto secolo, quell\u2019epoca d\u2019oro di santi e missionari in queste isole, e fu per questo un fondatore della cultura cristiana che sta alle radici dell\u2019Europa moderna\u00bb (Benedetto XVI 2010).<\/p>\n<p style=\"text-align: justify;\">Ancora prima la Scozia fu evangelizzata dal monaco san Mungo (518-603), presentato da Benedetto XVI come continuatore dell\u2019opera di san Ninian (di cui s\u2019ignorano le date di nascita e di morte), di cui afferma che \u00abnon ebbe paura di essere una voce solitaria. [\u2026] Ninian fu uno dei primissimi missionari cattolici a portare ai suoi connazionali la buona novella di Ges\u00f9 Cristo. La sua missione a Galloway divenne un centro per la prima evangelizzazione di questo Paese\u00bb ( Benedetto XVI 2010c). Il Papa prende cos\u00ec posizione nella controversia sull\u2019esistenza storica di san Ninian, oggi considerato da alcuni una figura meramente mitologica.<\/p>\n<p style=\"text-align: justify;\">E nel secolo successivo all\u2019epoca d\u2019oro dei santi inglesi, il settimo, il Papa evoca la figura del benedettino san Beda il Venerabile (672-735), il quale \u00abcomprese sia l\u2019importanza della fedelt\u00e0 alla parola di Dio come trasmessa dalla tradizione apostolica, sia la necessit\u00e0 di un\u2019apertura creativa ai nuovi sviluppi e alle esigenze di un adeguato radicamento del Vangelo nel linguaggio e nella cultura del suo tempo\u00bb (Benedetto XVI 2010l). Il santo benedettino \u00e8 tanto pi\u00f9 meritevole di essere ricordato oggi, quando \u00abquesta nazione, e l\u2019Europa che Beda e i suoi contemporanei hanno contribuito ad edificare, ancora una volta si trova alle soglie di una nuova epoca\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">I monaci hanno davvero diritto a essere ricordati come edificatori delle nazioni britanniche e dell\u2019Europa. \u00abPoich\u00e9 la ricerca di Dio che si colloca nel cuore della vocazione monastica, richiede un attivo impegno coi mezzi tramite i quali egli si fa conoscere \u2013 la sua creazione e la sua parola rivelata \u2013 era semplicemente naturale che il monastero dovesse avere una biblioteca ed una scuola\u00bb (Benedetto XVI 2010d), e che dunque ne sia nata una cultura. \u00abFu l\u2019impegno dei monaci nell\u2019imparare la via sulla quale incontrare la Parola Incarnata di Dio che gett\u00f2 le fondamenta della nostra cultura e civilt\u00e0 occidentali\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">In terzo luogo, Benedetto XVI ricorda che la storia della Gran Bretagna cristiana riposa sulle pi\u00f9 solide delle fondamenta, quelle bagnate dal sangue sacro dei martiri. \u00abL\u2019Inghilterra ha una grande tradizione di Santi martiri, la cui coraggiosa testimonianza ha sostenuto ed ispirato la comunit\u00e0 cattolica locale per secoli\u00bb (Benedetto XVI 2010r). Ai martiri uccisi dai pagani al tempo della prima evangelizzazione fanno seguito i due Lord Cancellieri del Regno che preferirono obbedire alla propria coscienza e al Papa piuttosto che al loro sovrano: il gi\u00e0 citato san Tommaso Moro e prima di lui san Tommaso Becket (1118-1170) che, anch\u2019egli, \u00abrese testimonianza a Cristo versando il proprio sangue\u00bb nella cattedrale di Canterbury (Benedetto XVI 2010).<\/p>\n<p style=\"text-align: justify;\">Vengono poi i cattolici che pagarono con la vita la fedelt\u00e0 a Roma dopo lo scisma di Enrico VIII. Il Papa ricorda i martiri di Tyburn, presso Londra, beatificati nel 1987, i quali \u00abmorirono per la fede; la testimonianza della loro fedelt\u00e0 sino alla fine fu ben pi\u00f9 potente delle parole ispirate che molti di loro dissero prima di abbandonare ogni cosa al Signore\u00bb (Benedetto XVI 2010q). Tanti altri furono in quei secoli \u00abimpiccati, affogati e squartati\u00bb (<em>ibid<\/em>.) per la loro indomita \u00abfedelt\u00e0 al Vangelo\u00bb (<em>ibid<\/em>.).<\/p>\n<p style=\"text-align: justify;\">Il martirio non appartiene solo al passato. Anzitutto, vi sono luoghi nel mondo dove il martirio cruento continua ancora oggi. Il Papa celebra i \u00abmartiri di ogni tempo, che hanno bevuto al calice da cui Cristo stesso ha bevuto, ed il cui sangue, sparso in unione al suo sacrificio, d\u00e0 nuova vita alla Chiesa. Ci\u00f2 \u00e8 anche riflesso nei nostri fratelli e sorelle nel mondo, che ancora oggi soffrono discriminazioni e persecuzioni per la loro fede cristiana\u00bb (Benedetto XVI 2010m). In secondo luogo, non c\u2019\u00e8 solo il martirio cruento. Talora \u00abil prezzo da pagare per la fedelt\u00e0 al Vangelo\u00bb (Benedetto XVI 2010q) non \u00e8 quello di essere torturati e uccisi ma \u00abimplica l\u2019essere additati come irrilevanti, ridicolizzati o fatti segno di parodia\u00bb (<em>ibid<\/em>.).<\/p>\n<p style=\"text-align: justify;\">La stessa vita del beato Newman, che dopo la conversione al cattolicesimo fu ripudiato da amici e perfino da familiari, \u00abci insegna che la passione per la verit\u00e0, per l\u2019onest\u00e0 intellettuale e per la conversione genuina comportano un grande prezzo da pagare\u00bb (<em>ibid<\/em>.). Ma il sangue dei martiri \u00e8 sempre fondamento di cristianit\u00e0 rinnovate. \u00abNella vita della Chiesa, nelle sue prove e tribolazioni, Cristo continua, secondo l\u2019incisiva espressione di [Blaise] Pascal [1623-1662], ad essere in agonia fino alla fine del mondo (<em>Pens\u00e9es<\/em>, 553, \u00e9d. [a cura di L\u00e8on] Brunschvicg [1869-1944])\u00bb (Benedetto XVI 2010m).<\/p>\n<p style=\"text-align: justify;\">Una terza memoria, che il Papa non omette mai nei suoi viaggi in Europa, \u00e8 quella \u2013 tanto cara al beato Newman \u2013 delle radici mariane delle nazioni britanniche. \u00abQuando il Beato John Henry Newman venne a vivere a Birmingham, diede il nome di \u201cMaryvale\u201d alla sua prima casa. L\u2019Oratorio da lui fondato \u00e8 dedicato all\u2019Immacolata Concezione della Beata Vergine. E l\u2019Universit\u00e0 Cattolica dell\u2019Irlanda venne da lui posta sotto la protezione di Maria, <em>Sedes sapientiae<\/em>\u00bb (Benedetto XVI 2010s). E ai gallesi il Papa ricorda che \u00abnella sua secolare storia, la gente del Galles si \u00e8 distinta per la sua devozione alla Madre di Dio; ci\u00f2 \u00e8 posto in evidenza dagli innumerevoli luoghi del Galles chiamati \u201cLlanfair\u201d \u2013 Chiesa di Maria\u00bb (Benedetto XVI 2010o), nonch\u00e9 dall\u2019importanza nella storia del Paese del \u00abSantuario Nazionale di Nostra Signora di Cardigan\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Vi \u00e8, infine, una quarta memoria storica che Benedetto XVI ricorda. \u00c8 l\u2019eredit\u00e0 giuridica e politica di quello che chiama il \u00abdesiderio di raggiungere un giusto equilibrio tra le legittime esigenze del potere dello Stato e i diritti di coloro che gli sono soggetti. Se da un lato, nella vostra storia, sono stati compiuti a pi\u00f9 riprese dei passi decisivi per porre dei limiti all\u2019esercizio del potere, dall\u2019altro le istituzioni politiche della nazione sono state in grado di evolvere all\u2019interno di un notevole grado di stabilit\u00e0\u00bb (Benedetto XVI 2010h).<\/p>\n<p style=\"text-align: justify;\">Questa tradizione, che parte almeno dalla <em>Magna Charta Libertatum<\/em> del 1215 e trova una base nel \u00absenso istintivo di moderazione presente nella Nazione\u00bb (<em>ibid.<\/em>), apprezzato pure dal beato Newman, nella sua parte essenziale e migliore secondo Benedetto XVI \u00abha molto in comune\u00bb (<em>ibid.<\/em>) con \u00abla dottrina sociale cattolica, pur formulata in linguaggio diverso\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Al di l\u00e0 delle singole, complesse vicende storiche il Papa vede in due episodi della storia moderna l\u2019impronta della passione della libert\u00e0 che caratterizza la storia istituzionale britannica. Il primo \u00e8 il contributo della Gran Bretagna all\u2019\u00ababolizione del commercio degli schiavi. La campagna che port\u00f2 a questa legislazione epocale, si bas\u00f2 su principi morali solidi, fondati sulla legge naturale, e ha costituito un contributo alla civilizzazione di cui questa nazione pu\u00f2 essere giustamente orgogliosa\u00bb (<em>ibid.<\/em>), e alle cui origini si situano peraltro cristiani mossi da motivazioni religiose, \u00abfigure come [l\u2019uomo politico anglicano] William Wilberforce [1759-1833] e [il missionario ed esploratore riformato scozzese] David Livingstone [1813-1873]\u00bb (Benedetto XVI 2010b).<\/p>\n<p style=\"text-align: justify;\">Il secondo episodio riguarda il modo con cui il popolo inglese e molti suoi <em>leader<\/em> percepirono la Seconda guerra mondiale: una lotta contro \u00abuna tirannia nazista che aveva in animo di sradicare Dio dalla societ\u00e0\u00bb (<em>ibid.<\/em>). Beatificando il cardinale Newman proprio nel \u00abgiorno prescelto per commemorare il 70<sup>mo<\/sup> anniversario della \u201cBattle of Britain\u201d\u00bb \u2013 la battaglia aerea combattuta nel 1940 fra le aviazioni britannica e tedesca per il controllo dello spazio aereo sopra la Gran Bretagna \u2013, il Papa tedesco confida: \u00abPer me, che ho vissuto e sofferto lungo i tenebrosi giorni del regime nazista in Germania, \u00e8 profondamente commovente essere qui con voi in tale occasione, e ricordare quanti dei vostri concittadini hanno sacrificato la propria vita, resistendo coraggiosamente alle forze di quella ideologia maligna\u00bb (Benedetto XVI 2010r).<\/p>\n<p style=\"text-align: justify;\"><em>b. Rispondere al secolarismo<\/em><\/p>\n<p style=\"text-align: justify;\">Ma c\u2019\u00e8 anche un&#8217;altra storia. Se \u00e8 vero che \u00abi Paesi occidentali hanno tutti, ognuno nel loro modo specifico e secondo la loro propria storia, forti correnti anticlericali e anticattoliche\u00bb (Benedetto XVI 2010a), \u00abnaturalmente la Gran Bretagna ha una sua propria storia di anticattolicesimo\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">E l\u2019anticattolicesimo oggi diventa parte di un pi\u00f9 generale secolarismo che mira a emarginare la religione dalla vita pubblica riducendola a un mero fatto privato, secondo una tendenza che, come si \u00e8 visto, gi\u00e0 il beato Newman aveva denunciato nel suo <em>Biglietto Speech<\/em>. \u00abAlla fine della vita, Newman avrebbe descritto il proprio lavoro come una lotta contro la tendenza crescente a considerare la religione come un fatto puramente privato e soggettivo, una questione di opinione personale\u00bb (Benedetto XVI 2010l).<\/p>\n<p style=\"text-align: justify;\">\u00abNon posso che esprimere la mia preoccupazione \u2013 ha detto Benedetto XVI ai parlamentari inglesi \u2013 di fronte alla crescente marginalizzazione della religione, in particolare del Cristianesimo, che sta prendendo piede in alcuni ambienti, anche in nazioni che attribuiscono alla tolleranza un grande valore. Vi sono alcuni che sostengono che la voce della religione andrebbe messa a tacere, o tutt\u2019al pi\u00f9 relegata alla sfera puramente privata. Vi sono alcuni che sostengono che la celebrazione pubblica di festivit\u00e0 come il Natale andrebbe scoraggiata, secondo la discutibile convinzione che essa potrebbe in qualche modo offendere coloro che appartengono ad altre religioni o a nessuna. E vi sono altri ancora che \u2013 paradossalmente con lo scopo di eliminare le discriminazioni \u2013 ritengono che i cristiani che rivestono cariche pubbliche dovrebbero, in determinati casi, agire contro la propria coscienza. Questi sono segni preoccupanti dell\u2019incapacit\u00e0 di tenere nel giusto conto non solo i diritti dei credenti alla libert\u00e0 di coscienza e di religione, ma anche il ruolo legittimo della religione nella sfera pubblica\u00bb (Benedetto XVI 2010h).<\/p>\n<p style=\"text-align: justify;\">\u00abMentre riflettiamo sui moniti dell\u2019estremismo ateo del ventesimo secolo, non possiamo mai dimenticare come l\u2019esclusione di Dio, della religione e della virt\u00f9 dalla vita pubblica conduce in ultima analisi ad una visione monca dell\u2019uomo e della societ\u00e0\u00bb (Benedetto XVI 2010b). Oggi viviamo \u00abin una societ\u00e0 che \u00e8 divenuta sempre pi\u00f9 indifferente e perfino ostile al messaggio cristiano\u00bb (Benedetto XVI 2010l), giacch\u00e9 \u00abvede il Vangelo come un limite alla libert\u00e0 umana, invece che come verit\u00e0 che libera\u00bb (Benedetto XVI 2010m), e in cui \u00abla cultura che ci circonda si sviluppa in modo sempre pi\u00f9 distante dalle sue radici cristiane, nonostante una profonda e diffusa fame di nutrimento spirituale\u00bb (Benedetto XVI 2010g).<\/p>\n<p style=\"text-align: justify;\">Nella Gran Bretagna \u00abmulticulturale\u00bb (<em>ibid<\/em>.), che \u00abcos\u00ec spesso sembra a rischio di frammentazione\u00bb (<em>ibid.<\/em>), c\u2019\u00e8 il pericolo che venga meno il \u00abrispetto per quei valori tradizionali e per quelle espressioni culturali che forme pi\u00f9 aggressive di secolarismo non stimano pi\u00f9, n\u00e9 tollerano pi\u00f9. Non si lasci oscurare il fondamento cristiano che sta alla base delle sue libert\u00e0\u00bb (Benedetto XVI 2010b). Di questo oscuramento sono talora agenti primari i <em>media<\/em>: e \u00abpoich\u00e9 le loro opinioni raggiungono un cos\u00ec vasto uditorio, i <em>media<\/em> britannici hanno una responsabilit\u00e0 pi\u00f9 grave di altri\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Richiamando la sua enciclica <em>Caritas in veritate<\/em>, del 2009, Benedetto XVI ricorda pure come l\u2019esclusione del fondamento religioso \u2013 e quindi, inevitabilmente, di quello etico \u2013 della societ\u00e0 e dell\u2019economia sia stata fra le cause della crisi economica del 2008, che ha colpito duramente la Gran Bretagna. \u00abL\u2019inadeguatezza di soluzioni pragmatiche, di breve termine, ai complessi problemi sociali ed etici \u00e8 stata messa in tutta evidenza dalla recente crisi finanziaria globale. Vi \u00e8 un vasto consenso sul fatto che la mancanza di un solido fondamento etico dell\u2019attivit\u00e0 economica abbia contribuito a creare la situazione di grave difficolt\u00e0 nella quale si trovano ora milioni di persone nel mondo\u00bb (Benedetto XVI 2010h).<\/p>\n<p style=\"text-align: justify;\">Come risultato, \u00ablo spettro della disoccupazione sta stendendo le proprie ombre sulla vita di molta gente, ed il costo a lungo termine di pratiche d\u2019investimento dei tempi recenti, mal consigliate, sta diventando quanto mai evidente\u00bb (Benedetto XVI 2010s). Ne deriva purtroppo \u00abun retroterra di crescente cinismo addirittura circa la possibilit\u00e0 di una vita virtuosa\u00bb (<em>ibid.<\/em>). Ma dal messaggio del beato Newman emerge un invito a reagire e a \u00ablavorare strenuamente per difendere le immutabili verit\u00e0 morali che, riprese, illuminate e confermate dal Vangelo, stanno alla base di una societ\u00e0 veramente umana, giusta e libera\u00bb (Benedetto XVI 2010v).<\/p>\n<p style=\"text-align: justify;\">Il beato \u00abNewman ci insegna che se abbiamo accolto la verit\u00e0 di Cristo e abbiamo impegnato la nostra vita per lui, non vi pu\u00f2 essere separazione tra ci\u00f2 che crediamo ed il modo in cui viviamo la nostra esistenza\u00bb (Benedetto XVI 2010l). Anche per questo compito \u2013 ricorda il Papa ai vescovi britannici \u2013 \u00ab\u00e8 stato di recente costituito un Pontificio Consiglio per la Nuova Evangelizzazione dei Paesi di lunga tradizione cristiana, e desidero incoraggiarvi ad avvalervi dei suoi servigi per affrontare i compiti che vi stanno innanzi\u00bb (Benedetto XVI 2010t).<\/p>\n<p style=\"text-align: justify;\">Con i parlamentari, Benedetto XVI ritorna sul caso esemplare di san Tommaso Moro. \u00abIl dilemma con cui Tommaso Moro si confrontava, in quei tempi difficili, la perenne questione del rapporto tra ci\u00f2 che \u00e8 dovuto a Cesare e ci\u00f2 che \u00e8 dovuto a Dio, mi offre l\u2019opportunit\u00e0 di riflettere brevemente con voi sul giusto posto che il credo religioso mantiene nel processo politico\u00bb (Benedetto XVI 2010h).<\/p>\n<p style=\"text-align: justify;\">\u00abIn verit\u00e0, le questioni di fondo che furono in gioco nel processo contro Tommaso Moro continuano a presentarsi, in termini sempre nuovi, con il mutare delle condizioni sociali. Ogni generazione, mentre cerca di promuovere il bene comune, deve chiedersi sempre di nuovo: quali sono le esigenze che i governi possono ragionevolmente imporre ai propri cittadini, e fin dove esse possono estendersi? A quale autorit\u00e0 ci si pu\u00f2 appellare per risolvere i dilemmi morali? Queste questioni ci portano direttamente ai fondamenti etici del discorso civile\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Come il venerabile Giovanni Paolo II e lo stesso Benedetto XVI hanno pi\u00f9 volte ricordato, non \u00e8 sufficiente rispondere che l\u2019autorit\u00e0 suprema \u00e8 costituita dalla democrazia e dal voto liberamente espresso dalla maggioranza dei cittadini. \u00abSe i principi morali che sostengono il processo democratico non si fondano, a loro volta, su nient\u2019altro di pi\u00f9 solido che sul consenso sociale, allora la fragilit\u00e0 del processo si mostra in tutta la sua evidenza. Qui si trova la reale sfida per la democrazia\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">\u00abLa questione centrale in gioco, dunque, \u00e8 la seguente: dove pu\u00f2 essere trovato il fondamento etico per le scelte politiche?\u00bb (<em>ibid.<\/em>). La risposta del Papa \u00e8 che questo fondamento pu\u00f2 essere trovato soltanto nella legge naturale, che la ragione \u2013 come si \u00e8 accennato \u2013 pu\u00f2 conoscere, ma con difficolt\u00e0, cos\u00ec che l\u2019aiuto offerto dalla fede non pu\u00f2 essere rifiutato senza grave pericolo. \u00abLa religione, in altre parole, per i legislatori non \u00e8 un problema da risolvere, ma un fattore che contribuisce in modo vitale al dibattito pubblico nella nazione\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Benedetto XVI, rispondendo a polemiche non solo inglesi, ha espresso soddisfazione perch\u00e9 \u2013 a differenza di quanto avvenne per la visita del venerabile Giovanni Paolo II nel 1982 \u2013 il suo viaggio apostolico \u00e8 stato considerato dal Regno Unito come visita di Stato. \u00abSono molto grato a Sua Maest\u00e0 la Regina Elisabetta II, che ha voluto dare a questa visita il rango di una visita di Stato, che sa esprimere il carattere pubblico di questa visita e anche la responsabilit\u00e0 comune tra politica e religione\u00bb (Benedetto XVI 2010a).<\/p>\n<p style=\"text-align: justify;\">Non si tratta di una questione di mera forma. Infatti \u00abmette al centro dell\u2019attenzione, questo carattere di visita di Stato, le coincidenze tra l\u2019interesse della politica e della religione. La politica sostanzialmente \u00e8 creata per garantire giustizia, e con la giustizia libert\u00e0, ma giustizia \u00e8 un valore morale, un valore religioso e cos\u00ec la fede, l\u2019annuncio del Vangelo, si collega, nel punto \u201cgiustizia\u201d, con la politica\u00bb (<em>ibid.<\/em>). \u00abNaturalmente questo fatto che giuridicamente \u00e8 una visita di Stato non rende la mia visita un fatto politico, perch\u00e9 se il Papa \u00e8 capo di Stato, questo \u00e8 solo uno strumento per garantire l\u2019indipendenza del suo annuncio e il carattere pubblico del suo lavoro di Pastore\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Il Papa non ha mancato di fare cenno anche a problemi specifici. Cos\u00ec, ha ricordato ai parlamentari che \u00able istituzioni religiose, comprese quelle legate alla Chiesa cattolica, devono essere libere di agire in accordo con i propri principi e le proprie specifiche convinzioni, basate sulla fede e sull\u2019insegnamento ufficiale della Chiesa\u00bb (Benedetto XVI 2010h). L\u2019allusione \u00e8 qui a leggi che pretendono d\u2019imporre agli ospedali cattolici di praticare aborti e alle agenzie cattoliche che si occupano di adozioni di offrire bambini per l\u2019adozione anche a coppie omosessuali.<\/p>\n<p style=\"text-align: justify;\">Particolarmente toccanti sono state le parole che Benedetto XVI ha rivolto agli anziani di una casa di riposo di Londra, che ha tenuto a includere fra le mete del suo viaggio. \u00abLa vita \u00e8 un dono unico, ad ogni stadio, dal concepimento fino alla morte naturale, e spetta solo a Dio darla e toglierla\u00bb (Benedetto XVI 2010p). La condanna dell\u2019eutanasia diventa per\u00f2 una profonda riflessione del Papa ottantatreenne sulla condizione degli anziani.<\/p>\n<p style=\"text-align: justify;\">\u00abUno pu\u00f2 godere buona salute in tarda et\u00e0; ma ugualmente i Cristiani non dovrebbero avere paura di partecipare alle sofferenze di Cristo se Dio vuole che affrontiamo l\u2019infermit\u00e0. Il mio predecessore il Papa Giovanni Paolo, ha sofferto pubblicamente negli ultimi anni della sua vita. Appariva chiaro a tutti che viveva questo in unione alle sofferenze del nostro Salvatore. La sua letizia e pazienza nell\u2019affrontare i suoi ultimi giorni furono un significativo e commovente esempio per tutti noi che dobbiamo portare il carico degli anni che avanzano\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">Occorre dunque, all\u2019estremo opposto della mentalit\u00e0 eutanasica, \u00abriconoscere la presenza di un crescente numero di anziani come una benedizione per la societ\u00e0. Ogni generazione pu\u00f2 imparare dall\u2019esperienza e saggezza della generazione che l\u2019ha preceduta. Inoltre il provvedere alla cura delle persone anziane non dovrebbe essere anzitutto considerata come un atto di generosit\u00e0, ma come il ripagare un debito di gratitudine\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\">\u00abMentre cresce il nostro normale periodo di vita \u2013 ha voluto aggiungere Benedetto XVI \u2013 le nostre capacit\u00e0 fisiche spesso vengono meno; e tuttavia questi periodi possono essere fra gli anni spiritualmente pi\u00f9 fruttuosi della nostra vita. Questi anni sono un\u2019opportunit\u00e0 per ricordare in una preghiera affettuosa tutti quelli che abbiamo amato in questa vita e porre tutto quello che siamo stati e abbiamo fatto davanti alla grazia e alla tenerezza di Dio\u00bb (<em>ibid.<\/em>).<\/p>\n<p style=\"text-align: justify;\"><em>c. Valorizzare il ruolo dei laici<\/em><\/p>\n<p style=\"text-align: justify;\">Contemplando il grande crocifisso che domina la navata della cattedrale cattolica di Westminster, a Londra, realizzato a Bruges in Belgio su disegni dell\u2019architetto della cattedrale John Francis Bentley (1839-1902) nello stile neo-medievale del secolo XIX per cui Benedetto XVI ha espresso pi\u00f9 volte apprezzamento, il Papa \u2013 rivolgendosi in particolare ai fedeli laici \u2013 nota come \u00able mani di nostro Signore, stese sulla Croce, ci invitano a contemplare anche la nostra partecipazione al suo eterno sacerdozio e la responsabilit\u00e0 che abbiamo, in quanto membra del suo corpo, di portare al mondo in cui viviamo il potere riconciliante del suo sacrificio. Il Concilio Vaticano II parl\u00f2 in maniera eloquente dell\u2019indispensabile ruolo del laicato di portare avanti la missione della Chiesa, attraverso lo sforzo di servire da fermento del Vangelo nella societ\u00e0, lavorando per l\u2019avanzamento del Regno di Dio nel mondo\u00bb (Benedetto XVI 2010m). \u00abIl richiamo del Concilio ai fedeli laici ad assumere il loro impegno battesimale partecipando alla missione di Cristo richiama le intuizioni e gli insegnamenti di John Henry Newman\u00bb (Benedetto XVI 2010m).<\/p>\n<p style=\"text-align: justify;\">N\u00e9 si tratta solo della partecipazione dei laici, tramite il sacerdozio comune \u2013 che, naturalmente, \u00e8 cosa ben distinta dal sacerdozio ministeriale dei presbiteri \u2013, all\u2019ufficio sacerdotale di Ges\u00f9 Cristo e, tramite la <em>consecratio mundi<\/em>, al Suo ufficio regale. I laici partecipano anche al terzo ufficio di Ges\u00f9 Cristo, quello profetico. Il beato Newman \u00abfu il grande campione dell\u2019ufficio profetico del laicato cristiano\u00bb (Benedetto XVI 2010l).<\/p>\n<p style=\"text-align: justify;\">E ai laici, sulla scia di Newman, il Papa si rivolge accoratamente da Glasgow: \u00abFaccio appello in particolare a voi, fedeli laici, affinch\u00e9, in conformit\u00e0 con la vostra vocazione e missione battesimale, non solo possiate essere esempio pubblico di fede, ma sappiate anche farvi avvocati nella sfera pubblica della promozione della sapienza e della visione del mondo che derivano dalla fede. La societ\u00e0 odierna necessita di voci chiare, che propongano il nostro diritto a vivere non in una giungla di libert\u00e0 auto-distruttive ed arbitrarie, ma in una societ\u00e0 che lavora per il vero benessere dei suoi cittadini, offrendo loro guida e protezione di fronte alle loro debolezze e fragilit\u00e0\u00bb (Benedetto XVI 2010c).<\/p>\n<p style=\"text-align: justify;\">Le riflessioni del beato Newman sui laici si radicano in un suo profondo accostamento alla tematica della vocazione. Il beato \u00abci dice che il nostro divino Maestro ha assegnato un compito specifico a ciascuno di noi, un \u201cservizio ben definito\u201d, affidato unicamente ad ogni singolo: \u201cio ho la mia missione \u2013 scrisse \u2013 sono un anello in una catena, un vincolo di connessione fra persone. Egli non mi ha creato per niente. Far\u00f2 il bene, compir\u00f2 la sua opera; sar\u00f2 un angelo di pace, un predicatore di verit\u00e0 proprio nel mio posto\u2026 se lo faccio obbedir\u00f2 ai suoi comandamenti e lo servir\u00f2 nella mia vocazione\u201d (<em>Meditations and devotions<\/em>, 301-2)\u00bb (Benedetto XVI 2010r).<\/p>\n<p style=\"text-align: justify;\">\u00abUna delle pi\u00f9 amate meditazioni del Cardinale contiene queste parole: \u201cDio mi ha creato per offrire a lui un certo specifico servizio. Mi ha affidato un certo lavoro che non ha affidato ad altri\u201d (<em>Meditations on Christian Doctrine<\/em>). Vediamo qui il preciso realismo cristiano di Newman, il punto nel quale la fede e la vita inevitabilmente si incrociano. [\u2026] Nessuno che guardi realisticamente al nostro mondo d\u2019oggi pu\u00f2 pensare che i cristiani possano continuare a far le cose di ogni giorno, ignorando la profonda crisi di fede che \u00e8 sopraggiunta nella societ\u00e0, o semplicemente confidando che il patrimonio di valori trasmesso lungo i secoli cristiani possa continuare ad ispirare e plasmare il futuro della nostra societ\u00e0. [\u2026] Ciascuno di noi, secondo il proprio stato di vita, \u00e8 chiamato ad operare per la diffusione del Regno di Dio impregnando la vita temporale dei valori del Vangelo\u00bb (Benedetto XVI 2010q).<\/p>\n<p style=\"text-align: justify;\">Per realizzare la sua vocazione d\u2019instaurazione cristiana dell\u2019ordine temporale il laicato, insegnava il beato Newman, dev\u2019essere formato. \u00ab\u201cVoglio un laicato non arrogante, non precipitoso nei discorsi, non polemico, ma uomini che conoscono la propria religione, che in essa vi entrino, che sappiano bene dove si ergono, che sanno cosa credono e cosa non credono, che conoscono il proprio credo cos\u00ec bene da dare conto di esso, che conoscono cos\u00ec bene la storia da poterlo difendere\u201d (<em>The Present Position of Catholics in England<\/em>, IX, 390)\u00bb (Benedetto XVI 2010r).<\/p>\n<p style=\"text-align: justify;\">E i laici non possono essere formati se mancano santi e dotti sacerdoti. \u00abPi\u00f9 si sviluppa l\u2019apostolato dei laici, pi\u00f9 urgente viene sentito il bisogno di sacerdoti, e pi\u00f9 il laicato approfondisce la consapevolezza della propria specifica vocazione, pi\u00f9 si rende evidente ci\u00f2 che \u00e8 proprio del sacerdote\u00bb (Benedetto XVI 2010m). Nel beato Newman non vi \u00e8 contrasto fra promozione dei laici e consapevolezza della dignit\u00e0 straordinaria e unica del sacerdozio.<\/p>\n<p style=\"text-align: center;\"><strong><a href=\"modules.php?name=News&amp;file=article&amp;sid=4103\" target=\"_blank\">continua<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cesnur 24 settembre 2010 In viaggio con il beato Newman. di Massimo Introvigne<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27664,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,5],"tags":[1844,458],"class_list":["post-4108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-benedetto-xvi","category-chiesa","tag-card-john-h-newman","tag-dottrina-e-morale-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La visita di Benedetto XVI in Gran Bretagna (1) - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La visita di Benedetto XVI in Gran Bretagna (1) - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-29T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-13T08:51:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/Benedetto-in-UK.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"158\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"44 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La visita di Benedetto XVI in Gran Bretagna (1)\",\"datePublished\":\"2010-09-29T22:00:00+00:00\",\"dateModified\":\"2015-11-13T08:51:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/\"},\"wordCount\":8791,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/Benedetto-in-UK.jpg\",\"keywords\":[\"card. John H.Newman\",\"dottrina e morale\"],\"articleSection\":[\"Benedetto XVI\",\"Chiesa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/\",\"name\":\"La visita di Benedetto XVI in Gran Bretagna (1) - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/Benedetto-in-UK.jpg\",\"datePublished\":\"2010-09-29T22:00:00+00:00\",\"dateModified\":\"2015-11-13T08:51:54+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/Benedetto-in-UK.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/Benedetto-in-UK.jpg\",\"width\":200,\"height\":158},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La visita di Benedetto XVI in Gran Bretagna (1)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La visita di Benedetto XVI in Gran Bretagna (1) - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/","og_locale":"it_IT","og_type":"article","og_title":"La visita di Benedetto XVI in Gran Bretagna (1) - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2010-09-29T22:00:00+00:00","article_modified_time":"2015-11-13T08:51:54+00:00","og_image":[{"width":200,"height":158,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/Benedetto-in-UK.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"44 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La visita di Benedetto XVI in Gran Bretagna (1)","datePublished":"2010-09-29T22:00:00+00:00","dateModified":"2015-11-13T08:51:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/"},"wordCount":8791,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/Benedetto-in-UK.jpg","keywords":["card. John H.Newman","dottrina e morale"],"articleSection":["Benedetto XVI","Chiesa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/","name":"La visita di Benedetto XVI in Gran Bretagna (1) - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/Benedetto-in-UK.jpg","datePublished":"2010-09-29T22:00:00+00:00","dateModified":"2015-11-13T08:51:54+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/Benedetto-in-UK.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/Benedetto-in-UK.jpg","width":200,"height":158},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-visita-di-benedetto-xvi-in-gran-bretagna-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La visita di Benedetto XVI in Gran Bretagna (1)"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4108"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4108\/revisions"}],"predecessor-version":[{"id":27665,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4108\/revisions\/27665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27664"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}