{"id":40732,"date":"2018-07-19T00:00:05","date_gmt":"2018-07-18T22:00:05","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=40732"},"modified":"2018-07-17T10:39:27","modified_gmt":"2018-07-17T08:39:27","slug":"dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/","title":{"rendered":"Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Aleteia<\/strong> 17 Luglio 2018<\/p>\n<p style=\"text-align: center;\"><em>La presenza jihadista nel Sahel, una minaccia che non va presa alla leggera<\/em><\/p>\n<p style=\"text-align: center;\"><u>\u00a0<\/u><strong>Paul De Maeyer<\/strong><u>\u00a0<\/u><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-40733\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Africa_Sahell.jpg\" alt=\"\" width=\"500\" height=\"222\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Africa_Sahell.jpg 784w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Africa_Sahell-300x133.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Africa_Sahell-768x341.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">E\u2019 uno sbaglio pensare che dopo la sconfitta in Iraq e Siria, la \u201cbrutale ideologia\u201d dello Stato Islamico (IS) sia morta. Sta infatti prendendo piede in Africa, cos\u00ec avverte la nota rivista britannica <a href=\"https:\/\/www.economist.com\/leaders\/2018\/07\/12\/jihadists-are-trying-to-take-over-the-sahel\" target=\"_blank\" rel=\"noopener\"><em>Economist,<\/em><\/a> in un articolo pubblicato il 12 luglio scorso sul sito Internet.<\/p>\n<p style=\"text-align: justify;\">Dopo la caduta del \u201ccaliffato\u201d \u2014 proclamato il 29 giugno 2014 dalla Grande Moschea di Al Nuri, a Mosul, da Abu Bakr al-Baghdadi \u2014 \u00e8 iniziata una fase di decentramento o frammentazione, la quale ha visto molti combattenti fuggire o trasferirsi in Africa, in particolare verso la zona del <a href=\"http:\/\/www.treccani.it\/enciclopedia\/sahel\/\" target=\"_blank\" rel=\"noopener\">Sahel<\/a>, questa arida fascia di transizione dal deserto del Sahara alla savana.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-9528\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/09\/isis.jpg\" alt=\"\" width=\"250\" height=\"140\" \/>La letalit\u00e0 dei combattenti dell\u2019IS in Africa supera quella dei loro compagni di guerra in Iraq, cos\u00ec sostiene l\u2019<em>Economist<\/em>. L\u2019anno scorso hanno ucciso circa 10.000 persone, soprattutto civili. I loro <em>fighters<\/em> sono anche numerosi. Il gruppo ISWAP (<em>Islamic State West Africa Province<\/em> o \u201cProvincia dell\u2019Africa occidentale dello Stato Islamico\u201d) conta in Nigeria circa 3.500 militanti, probabilmente un numero pi\u00f9 elevato di quello dei combattenti dell\u2019IS originale ancora presenti in Iraq e Siria.<\/p>\n<p style=\"text-align: justify;\">Anche se la minaccia costituita dall\u2019IS agli interessi occidentali nella fascia del Sahel \u00e8 ridotta, cos\u00ec continua l\u2019<em>Economist<\/em>, i suoi tentacoli arrivano fino in Occidente, come dimostrano gli attentati del 22 maggio 2017 a Manchester e del 19 dicembre 2016 a Berlino, in cui morirono rispettivamente 23 e 12 persone. In entrambi i casi gli attentatori avevano legami con la Libia, dove l\u2019IS \u00e8 presente a sud di Sirte.<\/p>\n<p style=\"text-align: justify;\"><strong>Presenza jihadista nel Sahel<\/strong><\/p>\n<p style=\"text-align: justify;\">Si tratta infatti di una minaccia che non va presa alla leggera. Come spiega il sito <a href=\"https:\/\/www.difesaesicurezza.com\/difesa-e-sicurezza\/africa-la-jihad-sahel-si-allea-isis-g5-ce-anche-al-qaeda\/\" target=\"_blank\" rel=\"noopener\"><em>Difesa &amp; Sicurezza<\/em><\/a>, vari gruppi jihadisti attivi nella zona si sono infatti uniti sotto il nome di Stato Islamico nel Grande Sahara (<em>Islamic State<\/em> <em>Greater Sahara <\/em>o ISGS) per combattere la forza congiunta antiterrorismo costituita da cinque Paesi del Sahel, ossia Burkina Faso, Ciad, Mali, Mauritania e Niger.<\/p>\n<p style=\"text-align: justify;\">Nota con la sigla FC-G5S (dal francese<em> Force Conjointe du G5 Sahel<\/em>), questa forza lotta insieme con le truppe francesi dell\u2019Operazione <em>Barkhane<\/em>e le forze di altri Paesi, fra cui Stati Uniti e Germania, contro i gruppi jihadisti e ha raggiunto di recente la sua piena capacit\u00e0 operativa (FOC o <em>Full Operational<\/em> <em>Capability <\/em>in gergo militare).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30340 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Africa_islam.jpg\" alt=\"\" width=\"200\" height=\"226\" \/>Che il pericolo costituito dall\u2019ISGS non vada preso sottogamba lo dimostra ad esempio l\u2019imboscata tesa il 4 ottobre del 2017 in Niger nei pressi del villaggio di Tongo Tongo, vicino al confine con il Mali, in cui quattro soldati delle forze USA e cinque militari nigeriani sono rimasti uccisi.<\/p>\n<p style=\"text-align: justify;\">A dirigere l\u2019ISGS \u00e8 <a href=\"https:\/\/www.counterextremism.com\/extremists\/adnan-al-sahrawi\" target=\"_blank\" rel=\"noopener\">Adnan Abu Walid al-Sahrawi<\/a>. L\u2019ex portavoce e sedicente emiro del gruppo armato jihadista <em>Al Mourabitoun<\/em> ha giurato nel maggio 2015 fedelt\u00e0 all\u2019IS e al califfo Abu Bakr al-Baghdadi (riconosciuta ufficialmente soltanto nell\u2019ottobre 2016), una mossa che ha provocato una scissione con l\u2019altro ramo del movimento, guidato dall\u2019algerino Mokhtar Belmokhtar. Quest\u2019ultimo gruppo diventa nel dicembre 2015 una brigata o <em>katiba <\/em>di <em>Al-Qaida nel Maghreb Islamico <\/em>(AQMI).<\/p>\n<p style=\"text-align: justify;\"><em>Al Mourabitoun<\/em> \u00e8 il movimento armato legato ad <em>Al Qaeda<\/em>, che ha rivendicato l\u2019attacco terroristico lanciato contro l\u2019albergo <em>Radisson Blu<\/em> nella capitale del Mali, Bamako, in cui morirono nel marzo 2015 ben 20 persone (pi\u00f9 due attentatori).<\/p>\n<p style=\"text-align: justify;\">Infine, nel marzo 2017, quattro gruppi armati legati ad <em>Al Qaeda<\/em> \u2014 <em>Ansar Dine<\/em>, inoltre <em>Al-Qaida nel Maghreb Islamico<\/em> (AQMI), il ramo di <em>Al Mourabitoun<\/em> di Mokhtar Belmokhtar e infine il gruppo jihadista dell\u2019etnia Peul, il <em>Fronte di Liberazione della Macina<\/em> \u2014 hanno annunciato la loro fusione nel nuovo movimento <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Groupe_de_soutien_%C3%A0_l%27islam_et_aux_musulmans\" target=\"_blank\" rel=\"noopener\"><em>Jama\u2019at Nusrat al-Islam wal Muslimeen<\/em><\/a>, che tradotto significa \u201cGruppo di Supporto all\u2019Islam e ai Musulmani\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 il Sahel?<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-8116\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/07\/Isil.jpg\" alt=\"\" width=\"250\" height=\"187\" \/>Come ricorda l\u2019<em>Economist<\/em>, il fenomeno del jihadismo destabilizza nella zona del Sahel tutta una serie di Paesi poveri e spesso mal governati, ma anche con una elevata crescita demografica. \u201cSe cadono nel caos \u2014 avverte la rivista \u2014 l\u2019Europa pu\u00f2 aspettarsi milioni di rifugiati in pi\u00f9.\u201d<\/p>\n<p style=\"text-align: justify;\">\u201cL\u2019ascesa del jihadismo in Africa \u00e8 radicata nel malgoverno, aggravata dalla pressione demografica e dai cambiamenti climatici\u201d, continua l\u2019articolo, il quale aggiunge che in questo tipo di situazione \u201cla promessa di giustizia religiosa da parte degli insorti pu\u00f2 sembrare allettante\u201d.<\/p>\n<p style=\"text-align: justify;\">Il 26 giugno scorso, il ministro marocchino degli Affari Esteri e della Cooperazione Internazionale, <a href=\"https:\/\/www.businesstimes.com.sg\/government-economy\/more-than-10000-jihadists-in-africa-us-led-coalition-hears\" target=\"_blank\" rel=\"noopener\">Nasser Bourita<\/a>, si \u00e8 rivolto a Skhirat (tra Casablanca e Rabat) ai partecipanti dell\u2019incontro dei direttori politici della coalizione globale contro l\u2019IS, dicendo che l\u2019Africa conta pi\u00f9 di 10.000 combattenti o jihadisti, che sfruttano abilmente le vulnerabilit\u00e0 del continente.<\/p>\n<p style=\"text-align: justify;\"><strong>Rapporto della Fondazione Mo Ibrahim<\/strong><\/p>\n<p style=\"text-align: justify;\">A confermare queste preoccupazioni \u00e8 un rapporto presentato nell\u2019aprile dell\u2019anno scorso dalla Fondazione Mo Ibrahim. Intitolato <a href=\"https:\/\/allafrica.com\/download\/resource\/main\/main\/idatcs\/00101935:5129995725e8c4478bcf049bfcfa24ae.pdf\" target=\"_blank\" rel=\"noopener\"><em>Africa at a tipping point<\/em><\/a> (\u201cL\u2019Africa al punto di non ritorno\u201d), il documento presenta una serie di dati impressionanti, che aiutano a capire le proporzioni della sfida che attende il continente.<\/p>\n<p style=\"text-align: justify;\">Dal 2015 al 2050, il numero di giovani africani quasi raddoppier\u00e0, da 230 a 452 milioni. Nel 2015, il 60% della popolazione africana \u2014 pi\u00f9 della met\u00e0, anzi quasi due terzi (!) \u2014 aveva meno di 25 anni. In media quasi la met\u00e0 della popolazione africana non ha ancora raggiunto la soglia d\u2019et\u00e0 per esercitare il diritto di voto. Inoltre, meno di un quarto della giovent\u00f9 africana si dichiara \u201cmolto interessata agli affari pubblici\u201d.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-32614\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/05\/attentato_islam.jpg\" alt=\"\" width=\"250\" height=\"166\" \/>Per la mancanza di prospettive, tra un terzo e la met\u00e0 della popolazione con livello di istruzione terziaria di Kenya, Uganda, Liberia, Mozambico e Ghana lascia il Paese in cerca di una vita migliore altrove. Negli ultimi dieci anni, il numero di proteste e di rivolte \u00e8 aumentato pi\u00f9 di dieci volte in Africa.<\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda il terrorismo, quattro Paesi africani risultano nella <em>Top Ten<\/em> mondiale col pi\u00f9 alto livello di terrorismo. Si tratta di Nigeria, Somalia, Egitto e Libia. Nell\u2019ultimo decennio il numero di attacchi o attentati terroristici ha conosciuto del resto in Africa un aumento di pi\u00f9 del 1.000%, rivela il rapporto.<\/p>\n<p style=\"text-align: justify;\">I Paesi africani con il maggior numero di vittime sono la Nigeria e la Somalia, con rispettivamente 17.930 e 6.278 vittime nel periodo che va dal 2006 al 2015. I gruppi terroristici pi\u00f9 attivi in questi due Paesi sono il gruppo anti-occidentale <em>Boko Haram<\/em> (diventato poi ISWAP nel 2015) in Nigeria e <em>Al Shabaab<\/em> in Somalia.<\/p>\n<p style=\"text-align: justify;\">In quest\u2019ultimo Paese, che non fa parte del Sahel (anche se alcuni vorrebbero includerlo), sono emersi <a href=\"https:\/\/ctc.usma.edu\/sub-saharan-africas-three-new-islamic-state-affiliates\/\" target=\"_blank\" rel=\"noopener\">due altri relativamente nuovi gruppi legati all\u2019IS<\/a>. Si tratta dello <em>Stato Islamico in Somalia<\/em> (abbreviato ISS) e di <em>Jahba East Africa<\/em>, chiamato anche <em>Stato Islamico in Somalia, Kenya, Tanzania e Uganda<\/em> (ISISSKTU). In entrambi i casi si tratta di gruppi secessionisti di <em>Al Shabaab<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>Il dramma dei bambini<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31385\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/bambini_africa.jpg\" alt=\"\" width=\"234\" height=\"200\" \/>Particolare attenzione va data al dramma dei bambini che vivono sulla propria pelle la cieca violenza dei gruppi terroristici. Secondo il rapport <a href=\"https:\/\/www.unicef.org\/wcaro\/nigeriaregionalcrisis\/UNICEF_Silent_shame.pdf\" target=\"_blank\" rel=\"noopener\"><em>Silent Shame. Bringing out the voices of children caught in the Lake Chad crisis<\/em><\/a> (\u201cLa vergogna silenziosa. Far emergere le voci dei bambini catturati nella crisi del lago Ciad\u201d), reso pubblico nell\u2019aprile del 2017 dall\u2019UNICEF, nella regione del Lago Ciad (che si sta del resto prosciugando) ben 1,3 milioni di bambini sono sfollati e 123.000 sono profughi in Paesi vicini.<\/p>\n<p style=\"text-align: justify;\">Una prassi diffusa \u00e8 il sequestro di bambini e soprattutto di bambine. Ben viva \u00e8 la memoria delle 276 ragazze rapite nel 2014 a <a href=\"https:\/\/en.wikipedia.org\/wiki\/Chibok_schoolgirls_kidnapping\" target=\"_blank\" rel=\"noopener\">Chibok<\/a>, nello Stato nigeriano di Borno, da miliziani di <em>Boko Haram<\/em>. Che il gruppo terroristico non sia ancora stato sconfitto in Nigeria lo dimostra la scomparsa di 111 studentesse dopo un attacco effettuato a <a href=\"https:\/\/www.independent.co.uk\/news\/world\/africa\/bolo-haram-attack-nigeria-schoolgirls-abducted-a8221981.html\">Dapchi<\/a>, nello Stato di Yobe.<\/p>\n<p style=\"text-align: justify;\">Come emerge dal rapporto UNICEF, alle bambine rapite dai jihadisti viene spesso assegnato un \u201cmarito\u201d, vengono inoltre stuprate e sottoposte a maltrattamenti, e se sono incinte \u2014 anche in giovanissima et\u00e0 \u2014 sono costrette a partorire senza alcuna assistenza.<\/p>\n<p style=\"text-align: justify;\">Raccapricciante \u00e8 un\u2019altra cifra fornita dal rapporto del Fondo per l\u2019Infanzia delle Nazioni Unite. Sin dall\u2019inizio del mese di gennaio 2014, ben 117 bambini, di cui pi\u00f9 dell\u201980% bambine (a causa delle loro lunghe e coprenti vesti), sono stati usati in attacchi \u201csuicidi\u201d in Nigeria, Niger, Ciad e Camerun.<\/p>\n<p style=\"text-align: justify;\">Tutto questo dimostra che la sfida posta dal jihadismo \u00e8 seria. Anche se la lotta contro il terrorismo islamico \u00e8 pericolosa \u2014 <a href=\"http:\/\/www.lefigaro.fr\/international\/2018\/02\/21\/01003-20180221ARTFIG00246-deux-soldats-francais-de-l-operation-barkhane-tues-au-mali.php\" target=\"_blank\" rel=\"noopener\">due militari francesi<\/a> sono morti nel febbraio scorso, quando il loro blindato ha colpito una mina artigianale \u2013, non bisogna ripetere l\u2019errore commesso nel 1993 dall\u2019allora presidente americano Bill Clinton, che decise di ritirare le truppe USA dalla Somalia, lasciando il Paese alla deriva, cos\u00ec sostiene l\u2019<em>Economist<\/em>. E\u2019 pi\u00f9 facile lasciar andare in pezzi il Sahel, che ricomporlo, avverte la rivista.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aleteia 17 Luglio 2018 La presenza jihadista nel Sahel, una minaccia che non va presa alla leggera \u00a0Paul De Maeyer\u00a0<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":40733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,16,36],"tags":[2393,161,501],"class_list":["post-40732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-islam","category-fondamentalismo-islamico","tag-africa","tag-islam-2","tag-islam-fondamentalismo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-18T22:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Africa_Sahell.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"784\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa\",\"datePublished\":\"2018-07-18T22:00:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/\"},\"wordCount\":1407,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Africa_Sahell.jpg\",\"keywords\":[\"Africa\",\"islam\",\"Islam fondamentalismo\"],\"articleSection\":[\"Africa\",\"Islam\",\"Islam fondamentalismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/\",\"name\":\"Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Africa_Sahell.jpg\",\"datePublished\":\"2018-07-18T22:00:05+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Africa_Sahell.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Africa_Sahell.jpg\",\"width\":784,\"height\":348},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/","og_locale":"it_IT","og_type":"article","og_title":"Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-07-18T22:00:05+00:00","og_image":[{"width":784,"height":348,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Africa_Sahell.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa","datePublished":"2018-07-18T22:00:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/"},"wordCount":1407,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Africa_Sahell.jpg","keywords":["Africa","islam","Islam fondamentalismo"],"articleSection":["Africa","Islam","Islam fondamentalismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/","name":"Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Africa_Sahell.jpg","datePublished":"2018-07-18T22:00:05+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Africa_Sahell.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/07\/Africa_Sahell.jpg","width":784,"height":348},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/dopo-la-sconfitta-in-iraq-e-siria-lis-alla-conquista-dellafrica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Dopo la sconfitta in Iraq e Siria, l\u2019IS alla conquista dell\u2019Africa"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=40732"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40732\/revisions"}],"predecessor-version":[{"id":40734,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40732\/revisions\/40734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/40733"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=40732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=40732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=40732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}