{"id":40390,"date":"2018-05-24T00:00:03","date_gmt":"2018-05-23T22:00:03","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=40390"},"modified":"2018-05-21T18:21:04","modified_gmt":"2018-05-21T16:21:04","slug":"gli-usa-che-aiutano-lirlanda-prolife","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/","title":{"rendered":"Gli USA che aiutano l\u2019Irlanda prolife"},"content":{"rendered":"<div id=\"attachment_40391\" style=\"width: 250px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-40391\" class=\"wp-image-40391\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Emily-Faulkner.jpg\" alt=\"\" width=\"250\" height=\"166\" \/><p id=\"caption-attachment-40391\" class=\"wp-caption-text\">Emily Faulkner<\/p><\/div>\n<p style=\"text-align: center;\"><strong>La Croce<\/strong> quotidiano 18 maggio 2018<\/p>\n<p style=\"text-align: justify;\"><em>Intervista a Emily Faulkner, giovane biologa del Colorado che, assieme ad altri attivisti dell\u2019associazione \u201cLetThemLive.org\u201d, sta aiutando la grande mobilitazione unitaria dei prolifers irlandesi in vista della consultazione del 25 maggio. I sondaggi danno l\u2019Ottavo Emendamento della Costituzione per spacciato ma, grazie a Dio, si parla di \u201crimonta\u201d dei \u201cNO vote\u201d\u2026<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Giuseppe Brienza<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Un gruppo di attivisti prolife americani, guidati dalla ventitreenne Emily Faulkner e dal suo fidanzato Nathan Berning (25 anni), sta dando una grossa mano alla mobilitazione unitaria dei prolifers irlandesi in vista della consultazione referendaria del 25 maggio. I due vivono in Colorado dove gestiscono il gruppo anti-abortista \u201cLetThemLive.org\u201d, collegato con il \u201cLeadership Institute\u201d, un\u2019organizzazione conservatrice operante in Virginia, fondata nel 1979 dal repubblicano Morton C. Blackwell.<\/p>\n<p style=\"text-align: justify;\">In un&#8217;intervista concessa in esclusiva a <em><a href=\"http:\/\/www.lacrocequotidiano.it\" target=\"_blank\" rel=\"noopener\">La Croce quotidiano<\/a><\/em> la Faulkner, che sta ultimando i suoi studi in biologia all\u2019universit\u00e0 del Colorado, ci ha spiegato perch\u00e9 \u00e8 venuta in Irlanda e come sia necessario che tutti gli attivisti prolife d\u2019Europa e dell\u2019Occidente intero si sentano come minimo chiamati in causa dall\u2019ormai imminente referendum sull\u2019Ottavo Emendamento.<\/p>\n<p style=\"text-align: justify;\"><strong>Ciao Emily, ci puoi dire quando e \u201ccome\u201d sei diventata un\u2019attivista prolife?<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-40392\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Irlanda_prolife.jpg\" alt=\"\" width=\"250\" height=\"153\" \/>Sono diventata un\u2019attivista prolife al tempo del secondo anno in college. Sebbene cresciuta in una famiglia prolife, non avevo infatti fino allora compreso fino in fondo le reali motivazioni per essere contro l\u2019aborto e in favore del diritto alla vita. Ho iniziato quindi a collaborare con un gruppo pro-life attivo nel mio college, frequentando la Colorado State University. E cos\u00ec sono entrata appieno nel mondo ideale dei prolife ma sono una convinta assertrice della difesa della vita del concepito perch\u00e9 da biologa ho studiato e compiuto un sacco di ricerche in materia risultandomi chiaro che la vita umana inizia dal concepimento. I miei studi di biologia e la scienza medica in generale confermano la giustezza delle battaglie prolife, ed \u00e8 per questo che direi che sono diventata quello che sono in maniera piuttosto \u201clogica\u201d!<\/p>\n<p style=\"text-align: justify;\"><strong>Ripeti spesso che la posizione anti-abortista non dovrebbe primariamente essere sostenuta sulla base di motivazioni religiose bens\u00ec etiche e scientifiche, puoi spiegarci meglio?<\/strong><\/p>\n<p style=\"text-align: justify;\">Certo. Sono assolutamente certa che moltissime persone religiose sono contrarie all\u2019aborto a motivo della loro Fede. Anch\u2019io personalmente sono Cattolica e lascio che la mia Fede com\u2019\u00e8 naturale informi tutto ci\u00f2 che penso e vivo. Allo stesso tempo, per\u00f2, sono fortemente convinta che sia la biologia sia l\u2019embriologia contemporanee siano degli strumenti invincibili per dimostrare a tutti, credenti e non credenti, che l\u2019inizio della vita umana coincide con il concepimento e che, pertanto, anche al non-nato sia da riconoscere eguali diritti della persona che vive al di fuori del grembo materno.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 con gli altri attivisti dell\u2019associazione che hai fondato, \u201c<\/strong><strong>LetThemLive.org<\/strong><strong>\u201d<\/strong><strong>, avete deciso di venire dagli Stati Uniti in Irlanda per fare campagna contro il referendum abortista del 25 maggio<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-29690\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/aborto.jpg\" alt=\"\" width=\"168\" height=\"200\" \/>Semplice, perch\u00e9 l\u2019aborto \u00e8 un tema che, volenti o nolenti, \u00e8 entrato a far parte della tematica della tutela internazionale dei diritti umani e, quindi, essendo quello che succede in un Paese strettamente collegato a tutto il resto, ci \u00e8 parsa piuttosto scontata la decisione di venire in Irlanda per poter condividere e divulgare quella che \u00e8 la nostra conoscenza e sensibilit\u00e0 acquisita circa il tema della difesa della vita umana innocente.<\/p>\n<p style=\"text-align: justify;\"><strong>Pensi che tutte le organizzazioni anti-abortiste occidentali dovrebbero unirsi e collaborare per difendere la causa dell\u2019integrit\u00e0 e della santit\u00e0 della vita umana innocente?<\/strong><\/p>\n<p style=\"text-align: justify;\">S\u00ec! Penso che tutte le organizzazioni prolife dovrebbero unirsi in qualche modo e collaborare per difendere insieme i diritti del bambino non-nato. Qui in Irlanda stiamo ora tutti lottando, senza distinzioni n\u00e9 personalismi, per assicurare la protezione del concepito e, secondo me, il movimento prolife internazionale potrebbe divenire molto, ma molto pi\u00f9 forte se decidessimo tutti di collaborare l\u2019uno con l\u2019altro.<\/p>\n<p style=\"text-align: justify;\"><strong>Cosa rispondere alle obiezioni di quei medici irlandesi che, durante questa campagna referendaria, stanno affermando che l\u2019Ottavo Emendamento della Costituzione \u00e8 da abrogare perch\u00e9 genera per loro incertezza dal punto di vista legale?<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-26815\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/aborto.jpg\" alt=\"\" width=\"250\" height=\"168\" \/>Anche in qualit\u00e0 di persona che sta per diventare medico, ricordo che io come loro abbiamo la responsabilit\u00e0 di salvare e non porre volontariamente fine alla vita umana. L\u2019Ottavo Emendamento della Costituzione irlandese non ha mai impedito ad ostetrici e ginecologi di praticare la loro professione medica in pieno favore della salute della donna. Non a caso stiamo diffondendo un Appello firmato da 5 autorevoli ostetrici e ginecologi irlandesi, tutti gi\u00e0 presidenti dell\u2019Istituto Nazionale di Ostetricia e Ginecologia, che dichiarano di non essere mai stati finora impediti nell\u2019esercizio della loro professione dall\u2019applicazione dell\u2019Ottavo Emendamento. [Il testo dell\u2019Appello si pu\u00f2 trovare sul sito <a href=\"http:\/\/www.irishtimes.com\" target=\"_blank\" rel=\"noopener\">www.irishtimes.com<\/a>].<\/p>\n<p style=\"text-align: justify;\"><strong>Poche settimane fa \u00e8 stato pubblicato in Irlanda un sondaggio Millward Brown nel quale risultava che il voto NO al referendum abortista \u00e8 cresciuto ultimamente di circa il 10% e, quello prochoice per il SI, \u00e8 invece crollato di circa il 18%. Cosa ci puoi dire a proposito della situazione attuale? Pensi davvero che sar\u00e0 possibile \u201csalvare\u201d l\u2019Ottavo Emendamento? <\/strong><\/p>\n<p style=\"text-align: justify;\">Una cosa \u00e8 certa, penso che tutti i prolife coinvolti in questa campagna stiano facendo il massimo per sostenere il voto anti-abortista. E sono anche convinta che l\u2019Irlanda \u00e8 una nazione prolife che continuer\u00e0 a difendere il non-nato nel grembo materno!<\/p>\n<p style=\"text-align: justify;\"><strong>Per concludere, puoi raccontarci qualcosa di particolare che stai imparando da quest\u2019esperienza prolife irlandese?<\/strong><\/p>\n<p style=\"text-align: justify;\">Beh, mi stanno colpendo molto i rapporti fecondi che stiamo intessendo con gli irlandesi incontrati. Infatti, distribuendo assieme agli altri amici e collaboratori di \u201cLetThemLive.org\u201d la letteratura scientifica a disposizione per spiegare l\u2019inizio e lo sviluppo della vita umana nel grembo materno, ho notato una grande volont\u00e0 di conoscere e mobilitarsi da parte della gente d\u2019Irlanda. In particolare, quando vengono a sapere che un feto di 12 settimane ha gi\u00e0 impulsi celebrali pienamente avvertibili e pu\u00f2 avere persino avere il singhiozzo vedo i loro occhi letteralmente strabuzzare!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Croce quotidiano 18 maggio 2018 Intervista a Emily Faulkner, giovane biologa del Colorado che, assieme ad altri attivisti dell\u2019associazione \u201cLetThemLive.org\u201d, sta aiutando la grande mobilitazione unitaria dei prolifers irlandesi in vista della consultazione del 25 maggio. I sondaggi danno l\u2019Ottavo Emendamento della Costituzione per spacciato ma, grazie a Dio, si parla di \u201crimonta\u201d dei &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":40391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2386],"class_list":["post-40390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","tag-aborto","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gli USA che aiutano l\u2019Irlanda prolife - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gli USA che aiutano l\u2019Irlanda prolife - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-23T22:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Emily-Faulkner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Gli USA che aiutano l\u2019Irlanda prolife\",\"datePublished\":\"2018-05-23T22:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/\"},\"wordCount\":996,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Emily-Faulkner.jpg\",\"keywords\":[\"Aborto\"],\"articleSection\":[\"Aborto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/\",\"name\":\"Gli USA che aiutano l\u2019Irlanda prolife - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Emily-Faulkner.jpg\",\"datePublished\":\"2018-05-23T22:00:03+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Emily-Faulkner.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Emily-Faulkner.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-usa-che-aiutano-lirlanda-prolife\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gli USA che aiutano l\u2019Irlanda prolife\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli USA che aiutano l\u2019Irlanda prolife - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/","og_locale":"it_IT","og_type":"article","og_title":"Gli USA che aiutano l\u2019Irlanda prolife - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-05-23T22:00:03+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Emily-Faulkner.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Gli USA che aiutano l\u2019Irlanda prolife","datePublished":"2018-05-23T22:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/"},"wordCount":996,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Emily-Faulkner.jpg","keywords":["Aborto"],"articleSection":["Aborto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/","name":"Gli USA che aiutano l\u2019Irlanda prolife - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Emily-Faulkner.jpg","datePublished":"2018-05-23T22:00:03+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Emily-Faulkner.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/Emily-Faulkner.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-usa-che-aiutano-lirlanda-prolife\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Gli USA che aiutano l\u2019Irlanda prolife"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=40390"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40390\/revisions"}],"predecessor-version":[{"id":40393,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40390\/revisions\/40393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/40391"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=40390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=40390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=40390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}