{"id":40318,"date":"2018-05-17T00:00:52","date_gmt":"2018-05-16T22:00:52","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=40318"},"modified":"2018-05-17T08:17:43","modified_gmt":"2018-05-17T06:17:43","slug":"schiavi-e-cooperative","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/","title":{"rendered":"Schiavi e Cooperative"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Italiani.<\/strong> Rivista che ignora il politicamente corretto n. 202- del 12 Maggio 2018<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-40319\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/cooperative-sociali.jpg\" alt=\"\" width=\"250\" height=\"169\" \/><\/p>\n<p style=\"text-align: center;\">di <strong>Luigi Fressoia<\/strong><\/p>\n<p style=\"text-align: center;\">(<a href=\"mailto:archifress@tiscali.it\">archifress@tiscali.it<\/a>)<\/p>\n<p style=\"text-align: right;\"><em>\u201cLo Stato \u00e8 quella finzione dietro la quale tutti cercano di campare alle spalle degli altri\u201d.<\/em><\/p>\n<p style=\"text-align: right;\"><strong>Basti\u00e0t,<\/strong> 1851.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Sar\u00e0 bene gettare un occhio finalmente attento sul mondo variegato e misterioso delle cooperative sociali sorte come funghi nei primi anni \u201890 ufficialmente per dare opportunit\u00e0 a soggetti svantaggiati come disabili, ex tossicodipendenti, alcolisti, carcerati e simili. Nobile intendimento che subito si \u00e8 coniugato con un altro grande ragionamento appioppato all&#8217;opinione pubblica: il risparmio sulla spesa pubblica, che notoriamente \u00e8 argomento molto sentito dal cittadino contribuente e si presta benissimo a manovre demagogiche come questa delle cosiddette Esternalizzazioni.<\/p>\n<p style=\"text-align: justify;\">Dietro demagogia e pelosa umanit\u00e0 come vedremo si nascondono le eterne furbizie del clientelismo partitico, del voto di scambio e soprattutto del parassitismo. Esaminando tali cooperative sociali emerge una grande, grandissima, distinzione tra impiegati e dirigenti da un lato e forza lavoro dall\u2019altro. Solo i secondi infatti provengono dalle categorie protette mentre i primi sono senz\u2019altro \u201cnormali\u201d.<\/p>\n<p style=\"text-align: justify;\">La virt\u00f9 di pescare tra le categorie protette giustifica tasse molto abbassate e iva ridotta. Il meccanismo economico \u00e8 che gli enti pubblici scelgono di stipulare un contratto con ditte esterne, appunto tali cooperative sociali, per prestazioni che prima venivano svolte direttamente da dipendenti dell\u2019ente stesso: addetti alle pulizie, guardiani, apertura e chiusura, facchinaggio, biglietteria, etc. I dipendenti costavano agli enti molto pi\u00f9 delle cooperative sicch\u00e9 la politica ha potuto fregiarsi del merito del risparmio.<\/p>\n<p style=\"text-align: justify;\">In concreto l\u2019ente pubblico concorda con la cooperativa un tot ore di servizio ad un prezzo convenuto. Tale prezzo nel caso da noi esaminato \u00e8 \u20ac 17,80\/ora lordo e \u20ac 16,20 netto (iva ridotta). In busta paga l\u2019operatore della cooperativa -come anzidetto proveniente dalle categorie protette- si ritrova \u20ac 7,05 quindi significa che i rimanenti \u20ac 9,15 vanno alla sede della cooperativa e suoi impiegati e dirigenti.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-29528\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/lavoro_Africa.jpg\" alt=\"\" width=\"250\" height=\"150\" \/>Per le magie che le leggi apposite consentono, gli operatori sul campo (quelli delle categorie protette, giova ripetere) sono inquadrati con la qualifica di socio-lavoratore, termine che contiene, come vedremo, autentiche perle.<\/p>\n<p style=\"text-align: justify;\">Diverso \u00e8 invece il rapporto di lavoro per impiegati e dirigenti con la stessa propria cooperativa, non retribuito a ore bens\u00ec di normale contratto tabellare. Mentre questi ultimi hanno tutte le certezze e garanzie di un consueto rapporto di lavoro dipendente, e per di pi\u00f9 pubblico di fatto, i primi anche se a tempo indeterminato devono risentire dell\u2019andamento di mercato, infatti possono subire riduzioni d\u2019orario ma soprattutto per fregiarsi della qualifica di socio (socio-lavoratore abbiamo detto), devono pagare una quota sociale di ingresso che nel caso da noi esaminato ammonta a \u20ac 2.500 (!), che il poveretto potr\u00e0 comodamente pagare -bont\u00e0 loro- a rate mensili con trattenuta sul magro stipendio.<\/p>\n<p style=\"text-align: justify;\">Succede che la cooperativa per le crescenti difficolt\u00e0 dovute ai sempre meno soldi che gli enti pubblici possono spendere, ogni tanto devono fallire e riaprire con nome diverso, con che il socio-lavoratore perde la sua quota sociale, ma non la perde l\u2019impiegato\/dirigente per il semplice motivo che non dovette mai versarla, essendo il suo rapporto di lavoro, gi\u00e0 detto, dipendente e non \u201cimprenditoriale\u201d come il socio-lavoratore.<\/p>\n<p style=\"text-align: justify;\">Naturalmente il socio-lavoratore di imprenditore non ha proprio nulla, essendo ogni cosa gestita e decisa in sede dagli impiegati e dirigenti, che ogni tanto a comando, per quanto serve, gli comunicano quanto lavorare, quando e come chiudere e riaprire la cooperativa, cosa firmare, quanto mettere e versare.<\/p>\n<p style=\"text-align: justify;\">Per i soci-lavoratori mille euro al mese sono un miraggio lontano, gli altri invece viaggiano con gli stessi stipendi del pubblico impiego con i dirigenti che superano facilmente i 3.000 euro\/mese.<\/p>\n<p style=\"text-align: justify;\">Naturalmente gli enti pubblici in questi 25 anni non hanno risparmiato un bel nulla con tali sistematiche esternalizzazioni che riguardano migliaia di edifici pubblici, musei, mense, asili, etc, per il semplice motivo che il numero dei propri dipendenti non \u00e8 mai diminuito bens\u00ec gli interessati sono stati semplicemente spostati ad altro incarico dentro lo stesso ente, magari e rigirarsi tra le mani cartacce burocratiche, e quindi il costo delle cooperative esterne per quanto inferiore ai corrispondenti dipendenti pubblici, \u00e8 risultato semplicemente aggiuntivo.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-26395\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/06\/madre_lavoro.jpg\" alt=\"\" width=\"250\" height=\"147\" \/>Costola non secondaria del tracollo finanziario dello stato italiano, costola non secondaria della crisi e i suoi molti corollari: tasse altissime (per mantenere i molti eserciti del parassitismo italiano) e conseguente impossibilit\u00e0 a fare vera impresa, quindi disoccupazione, sottooccupazione, lavoro nero, corruzione, apatia, malattia mentale.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 \u00e8 nato questo scempio sociale delle esternalizzazioni? Il motivo \u00e8 semplice: la politica cio\u00e8 partiti e sindacati hanno un bisogno costante e crescente di fare clientelismo ovvero di comprare, accattivarsi, il voto degli elettori. Hanno sperimentato da anni che le chiacchiere ideologiche sono molto meno efficaci del clientelismo, i cittadini elettori ricompensano col voto chi gli fa un favore personale\/familiare molto pi\u00f9 di chi governa bene.<\/p>\n<p style=\"text-align: justify;\">E per fare clientelismo non c\u2019\u00e8 niente di meglio che usare (sperperare) denaro pubblico per assunzioni non necessarie nella pubblica amministrazione, appalti gonfiati di opere pubbliche, forniture fasulle, incarichi e nomine allegre, pensioni regalate a intere categorie, appalti esterni non indispensabili come questi di cui stiamo parlando, e molte altre cose.<\/p>\n<p style=\"text-align: justify;\">Se alla fine si va in crisi nera (come adesso) il sistema fa spallucce e d\u00e0 la colpa a qualcun altro (al Capitalismo cinico e baro, alla Merkel, all\u2019America\u2026), tutto tranne che smettere di farsi e farci del male, esattamente come tossicodipendenti in astinenza. Sicch\u00e9 dopo aver gonfiato gli enti pubblici e para-pubblici fino all\u2019inverosimile gi\u00e0 negli anni \u201980, ormai in crisi finanziaria e impossibilitati a ulteriori assunzioni di massa, ecco si sono inventati le esternalizzazioni che a ben vedere sono un pubblico impiego indiretto, di secondo livello, mascherato, che ci vuoi fare, gi\u00e0 \u00e8 qualcosa, non si pu\u00f2 avere tutto nella vita, bisogna sapersi accontentare\u2026<\/p>\n<p style=\"text-align: justify;\">Ma di cui ab origine non c\u2019era alcun bisogno, i soggetti bisognosi di protezione sociale potevano benissimo continuare ad essere assunti direttamente negli enti come si fece dal dopoguerra coi mutilati e simili.<\/p>\n<p style=\"text-align: justify;\">Soprattutto i meccanismi clientelari che premono ai partiti e sindacati padroni dello Stato erano assicurati: i nuovi schiavi delle cooperative per quanto con paghe di fame potranno sempre essere avvicinati\/ricattati per ringraziare\/votare i padrini politici della cooperativa; gli impiegati e i dirigenti delle cooperative avranno finalmente trovato un buon impiego (di fatto pubblico) seppure pagato dagli schiavi coi loro bassissimi salari; specie i posti da dirigente saranno ulteriore mercato di primo livello per sistemare rampolli e raccomandati speciali (nel mucchio c\u2019\u00e8 perfino la moglie di un sindaco), n\u00e9 pi\u00f9 n\u00e9 meno come negli agognati enti pubblici, anzi, con tali cooperative sociali possono perfino darsi arie da imprenditori e farsi belli quando vanno al mare.<\/p>\n<p style=\"text-align: justify;\">Perfino si spacciano da amici e grandi benefattori dei loro stessi schiavi, essendo \u201criusciti a trovargli\u201d un lavoro. Chiss\u00e0 per\u00f2 se lo specchio riesce a dirgli qualcosa di vero la mattina.<\/p>\n<p style=\"text-align: justify;\"><strong>P.S.<\/strong> Queste cooperative sociali non vanno confuse con l\u2019universo parallelo delle altre che si occupano di immigrati, che attingono a capitoli di spesa del tutto diversi, non degli enti locali bens\u00ec direttamente dello Stato (circa 6 miliardi\/anno\u2026 bruscolini\u2026 benedetti col nome santo della Solidariet\u00e0), ne parliamo in un prossimo numero.<\/p>\n<p style=\"text-align: center;\">_______________<\/p>\n<p>La rivista telematica Italians puo\u2019 essere richiesta inviando una mail a:\u00a0<strong><a href=\"mailto:archifress@tiscali.it\" target=\"_blank\" rel=\"noopener\">archifress@tiscali.it<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Italiani. Rivista che ignora il politicamente corretto n. 202- del 12 Maggio 2018 di Luigi Fressoia (archifress@tiscali.it) \u201cLo Stato \u00e8 quella finzione dietro la quale tutti cercano di campare alle spalle degli altri\u201d. Basti\u00e0t, 1851.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":40319,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,25],"tags":[2318],"class_list":["post-40318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-sguardo-sul-nostro-tempo","tag-cooperazione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schiavi e Cooperative - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schiavi e Cooperative - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-16T22:00:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-17T06:17:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/cooperative-sociali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"203\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Schiavi e Cooperative\",\"datePublished\":\"2018-05-16T22:00:52+00:00\",\"dateModified\":\"2018-05-17T06:17:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/\"},\"wordCount\":1189,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/cooperative-sociali.jpg\",\"keywords\":[\"cooperazione\"],\"articleSection\":[\"Economia\",\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/\",\"name\":\"Schiavi e Cooperative - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/cooperative-sociali.jpg\",\"datePublished\":\"2018-05-16T22:00:52+00:00\",\"dateModified\":\"2018-05-17T06:17:43+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/cooperative-sociali.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/cooperative-sociali.jpg\",\"width\":300,\"height\":203},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/schiavi-e-cooperative\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schiavi e Cooperative\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schiavi e Cooperative - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/","og_locale":"it_IT","og_type":"article","og_title":"Schiavi e Cooperative - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-05-16T22:00:52+00:00","article_modified_time":"2018-05-17T06:17:43+00:00","og_image":[{"width":300,"height":203,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/cooperative-sociali.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Schiavi e Cooperative","datePublished":"2018-05-16T22:00:52+00:00","dateModified":"2018-05-17T06:17:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/"},"wordCount":1189,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/cooperative-sociali.jpg","keywords":["cooperazione"],"articleSection":["Economia","Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/","name":"Schiavi e Cooperative - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/cooperative-sociali.jpg","datePublished":"2018-05-16T22:00:52+00:00","dateModified":"2018-05-17T06:17:43+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/cooperative-sociali.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/05\/cooperative-sociali.jpg","width":300,"height":203},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/schiavi-e-cooperative\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Schiavi e Cooperative"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=40318"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40318\/revisions"}],"predecessor-version":[{"id":40375,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40318\/revisions\/40375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/40319"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=40318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=40318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=40318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}