{"id":40188,"date":"2018-04-26T09:18:16","date_gmt":"2018-04-26T07:18:16","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=40188"},"modified":"2018-04-26T09:18:16","modified_gmt":"2018-04-26T07:18:16","slug":"altro-che-25-aprile","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/","title":{"rendered":"Altro che 25 Aprile"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40189 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/25-Aprile.jpg\" alt=\"\" width=\"279\" height=\"181\" \/>Newletter di <strong>Alleanza cattolica<\/strong><\/p>\n<p style=\"text-align: center;\">24 Aprile 2018<\/p>\n<p style=\"text-align: center;\">Una data prima ignorata, poi ideologizzata, quindi inutile. Molto meglio celebrare il 18 Aprile<\/p>\n<p style=\"text-align: center;\"><strong>di Marco Invernizzi<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Secondo un sondaggio svolto dall\u2019istituto di ricerca Eumetra MR ripreso da\u00a0<a href=\"http:\/\/www.ilgiornale.it\/news\/politica\/falso-mito-25-aprile-italiano-su-tre-che-cos-1518317.html\" target=\"_blank\" rel=\"noopener\"><em>il Giornale<\/em>\u00a0del 23 aprile,<\/a>\u00a0il 33% degli italiani non sa che cosa sia veramente accaduto il 25 aprile 1945. La notizia, se vera, induce a una riflessione.<\/p>\n<p style=\"text-align: justify;\">L\u2019ignoranza sul 25 Aprile riguarda soprattutto l\u2019et\u00e0 di mezzo, quella che ha maggiormente subito la propaganda pubblica che ha posto il 25 Aprile come evento fondamentale per comprendere l\u2019identit\u00e0 italiana attraverso un autentico bombardamento scolastico e mediatico. Ci\u00f2 significa che questo evento non \u00e8 penetrato nel corpo sociale, non ha attecchito. Ha cio\u00e8 prodotto un\u2019avversione a prescindere contro la Liberazione, come capita spesso quando la propaganda \u00e8 troppo faziosa.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-29572\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Togliatti.jpg\" alt=\"\" width=\"177\" height=\"200\" \/>Ma che cosa ha rappresentato il 25 Aprile? In questa data viene celebrata la festa della Liberazione del Paese dall\u2019occupazione dell\u2019esercito tedesco dopo una guerra civile tra fascisti e antifascisti durata dal 1943 al 1945. L\u2019Italia usc\u00ec quindi definitivamente dal regime costruito da Benito Mussolini (1883-1945) e ritorn\u00f2 a essere uno Stato democratico, in particolare una repubblica parlamentare basata sui partiti dopo il referendum istituzionale del 1946. Forse, visto che un italiano su tre non conosce cosa abbia rappresentato il 25 Aprile, vale la pena ricordarlo. Ma quello che certamente gli italiani conoscono molto meno \u00e8 l\u2019uso del 25 Aprile fatto nei decenni successivi a partire dagli anni 1950 da parte della propaganda governativa.<\/p>\n<p style=\"text-align: justify;\">Fino ai governi di Centro-Sinistra degli anni 1960, il 25 Aprile era una data importante per la storia italiana, ma non fondamentale. Diventa invece il cuore dell\u2019identit\u00e0 italiana con i governi di Centro-Sinistra e soprattutto dopo il 1968. Se prima il pericolo per la giovane democrazia italiana veniva dall\u2019Unione Sovietica e dall\u2019ideologia comunista, gli anni 1960 individuano il pericolo per la stabilit\u00e0 democratica nel neo-fascismo, supposto in crescita quanto a pericolosit\u00e0.<\/p>\n<p style=\"text-align: justify;\">E allora la Resistenza partigiana diventa il modello di riferimento a livello politico con la grande alleanza antifascista aperta al Partito Comunista Italiano e chiusa invece alla destra, in nome dell\u2019arco costituzionale al quale possono appartenere soltanto i partiti antifascisti. La Resistenza diventa per\u00f2 un modello non soltanto politico, bens\u00ec anche ideale. Dopo la fine della guerra civile che aveva diviso il PCI fra una componente minoritaria \u2013 che faceva capo a Pietro Secchia (1903-1973), dirigente del partito, e che voleva continuare la Resistenza fino alla Rivoluzione, anche armata \u2013 e chi adott\u00f2 la svolta democratica imposta dal segretario del partito Palmiro Togliatti (1893-1964), con la benedizione di Stalin (Iosif Vissarionovi\u010d D\u017euga\u0161vili, 1878-1953).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-31331\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/DC-1.jpg\" alt=\"\" width=\"283\" height=\"178\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-40190\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/18-aprile-48.jpg\" alt=\"\" width=\"300\" height=\"168\" \/>Evocare la Resistenza significava insomma richiamare la stagione dell\u2019insurrezione armata e prendere le distanze dal PCI del compromesso con le istituzioni democratiche. Il mito della Resistenza, evocato cos\u00ec senza troppo riflettere sulle possibili conseguenze, portava alla violenza rivoluzionaria: se ne impossesseranno infatti le Brigate Rosse.<\/p>\n<p style=\"text-align: justify;\">Alla Resistenza avevano partecipato molti che non erano comunisti, cos\u00ec come la maggioranza degli italiani fu estranea alla guerra civile, aspettando solo che finisse tanta violenza: ma dopo gli anni 1960 essere anticomunista venne fatto coincidere con l\u2019essere fascista e agli anticomunisti vennero preclusi i pi\u00f9 elementari diritti alla libert\u00e0 nelle scuole, nelle universit\u00e0 e nelle fabbriche, spesso nelle stesse strade delle principali citt\u00e0 del Nord.<\/p>\n<p style=\"text-align: justify;\">Ricordare il 25 Aprile dovrebbe comportare anche il ricordo di cosa quell\u2019evento, divenuto un simbolo, abbia significato nei decenni successivi, altrimenti non si comprende un pezzo importante della storia italiana, peraltro uno dei pi\u00f9 bui, dominato dal terrorismo e dalla sopraffazione, dal venire meno degli spazi di libert\u00e0, che ha generato un clima di intimidazione che ha spesso provocato una reazione violenta uguale e contraria, come bene spiega Enzo Peserico (1959-2008) in\u00a0 G<em>li anni del desiderio e del piombo. Sessantotto, terrorismo e Rivoluzione<\/em>\u00a0(Sugarco, Milano 2008).<\/p>\n<p style=\"text-align: justify;\">Personalmente, credo che la data che andrebbe ripresa e rivalutata sia invece il\u00a0<a href=\"http:\/\/alleanzacattolica.org\/18-aprile-1948-memoria-e-speranza\/\" target=\"_blank\" rel=\"noopener\">18 aprile 1948<\/a>. Soltanto tre anni dopo il 25 Aprile, gli italiani scelsero, attraverso elezioni libere, da che parte stare, si identificarono con la Chiesa Cattolica e con l\u2019Occidente, e posero l\u2019anticomunismo nel cuore della propria identit\u00e0. Ma 20 anni dopo tutto sarebbe nuovamente cambiato.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Newletter di Alleanza cattolica 24 Aprile 2018 Una data prima ignorata, poi ideologizzata, quindi inutile. Molto meglio celebrare il 18 Aprile di Marco Invernizzi<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":40189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100,96],"tags":[1233],"class_list":["post-40188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resistenza","category-storia-italiana","tag-25-aprile","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Altro che 25 Aprile - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Altro che 25 Aprile - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-26T07:18:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/25-Aprile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"279\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Altro che 25 Aprile\",\"datePublished\":\"2018-04-26T07:18:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/\"},\"wordCount\":677,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/25-Aprile.jpg\",\"keywords\":[\"25 aprile\"],\"articleSection\":[\"Resistenza\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/\",\"name\":\"Altro che 25 Aprile - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/25-Aprile.jpg\",\"datePublished\":\"2018-04-26T07:18:16+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/25-Aprile.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/25-Aprile.jpg\",\"width\":279,\"height\":181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-25-aprile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Altro che 25 Aprile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Altro che 25 Aprile - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/","og_locale":"it_IT","og_type":"article","og_title":"Altro che 25 Aprile - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-04-26T07:18:16+00:00","og_image":[{"width":279,"height":181,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/25-Aprile.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Altro che 25 Aprile","datePublished":"2018-04-26T07:18:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/"},"wordCount":677,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/25-Aprile.jpg","keywords":["25 aprile"],"articleSection":["Resistenza","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/","name":"Altro che 25 Aprile - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/25-Aprile.jpg","datePublished":"2018-04-26T07:18:16+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/25-Aprile.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/25-Aprile.jpg","width":279,"height":181},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Altro che 25 Aprile"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=40188"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40188\/revisions"}],"predecessor-version":[{"id":40191,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40188\/revisions\/40191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/40189"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=40188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=40188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=40188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}