{"id":40181,"date":"2018-04-26T00:00:28","date_gmt":"2018-04-25T22:00:28","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=40181"},"modified":"2018-04-23T13:38:37","modified_gmt":"2018-04-23T11:38:37","slug":"da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/","title":{"rendered":"Da maniaco a grande artista dell&#8217;omicidio: cos\u00ec l&#8217;ideologia ha stravolto anche il Male"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-40182\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/Hannibal-Lecter.jpg\" alt=\"\" width=\"187\" height=\"200\" \/>Il Giornale<\/strong> 7 Novembre 2017<\/p>\n<p style=\"text-align: center;\"><em>Hannibal Lecter e Dexter sono icone di una societ\u00e0 che rinuncia a giudicare<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Rino Cammilleri<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Tra le sue frequentazioni, che comprendevano il jet-set del cinema ma anche i surrealisti emigrati negli States, si \u00e8 sempre sospettato si nascondesse un serial killer. Che per\u00f2 non aveva ancora questo nome. Oggi invece pervade in lungo e in largo il nostro immaginario.<\/p>\n<p style=\"text-align: justify;\">Protagonista di film, romanzi, graphic novel e serie televisive, nella cultura pop il serial killer \u00e8 ritratto come una persona astuta, spesso come un vero artista della morte. Eppure l&#8217;omicidio seriale \u00e8 tutt&#8217;altro che frequente, anzi \u00e8 proprio raro. Come si spiega, allora, questa presenza sempre pi\u00f9 invadente nella fiction? Da dove proviene questa attrazione nel pubblico per criminali estremi e i delitti pi\u00f9 orrendi?<\/p>\n<p style=\"text-align: justify;\"><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35942\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/morte.jpg\" alt=\"\" width=\"250\" height=\"187\" \/>Meglio regnare all&#8217;inferno<\/em> (Lindau, pagg. 256, euro 34) di Mario A. Iannaccone \u00e8 la pi\u00f9 completa storia del fenomeno. \u00c8, soprattutto, una riflessione sull&#8217;uso ideologico della narrazione di questi crimini (dal XIX secolo a oggi). Assassini per puro piacere, perch\u00e9 folli o malvagi, sono presenti da sempre (si pensi al famoso Jack lo Squartatore) ma \u00e8 solo dalla fine degli anni Sessanta che la cosa \u00e8 affrontata in modo nuovo.<\/p>\n<p style=\"text-align: justify;\">Negli Ottanta \u00e8 l&#8217;era Reagan a vedere nell&#8217;omicida seriale l&#8217;esito ultimo della controcultura trasgressiva, promiscua, drogata (si pensi al film Natural born killers, ispirato a un fatto vero). Durante il caso degli Atlanta Child Murders (omicidi di bambini) fu creata la Behavioral Science Unit, sezione apposita dell&#8217;Fbi e venne inaugurato il termine serial killer. Che divent\u00f2 il nuovo nemico interno. L&#8217;Accademia Fbi di Quantico form\u00f2 specialisti che stilavano \u00abprofili\u00bb: i mindhunter, che dovevano pensare come gli assassini ed essere esperti in indagine procedurale (i vari Csi o i romanzi di Kathy Reichs, quasi una mitologia contemporanea). Nella finzione l&#8217;unica persona che si salvava dalla furia del killer era la pi\u00f9 morigerata, di solito una ragazza, la Final girl (l&#8217;archetipo, nel film Halloween del 1978).<\/p>\n<p style=\"text-align: justify;\">Negli anni Novanta, con l&#8217;era Clinton, le forze progressiste spazzarono via la breve stagione conservatrice reaganiana. L&#8217;industria dello spettacolo, liberata dai lacci della condanna morale, propose il serial killer come eroe sadiano, intelligente e manipolatore, figlio di un male superiore. Hannibal Lecter \u00e8 l&#8217;archetipo del serial killer del nuovo tipo: da ragazzo ha visto la sorellina mangiata da nazisti cannibali, si \u00e8 convinto che il mondo \u00e8 governato da forze malvagie ed ha abbracciato una filosofia ispirata a De Sade.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-29798\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/pena_morte.jpg\" alt=\"\" width=\"156\" height=\"200\" \/>Questo tipo di serial killer immaginario \u00e8 diventato molto presente nella cultura pop e ha avuto incarnazioni di grande successo come nelle serie tv Dexter o Hannibal, complessa e disturbante riflessione sull&#8217;arte di uccidere. Il serial killer di nuovo genere \u00e8 non di rado visto con simpatia: \u00e8 favorevole all&#8217;eutanasia, colto, svincolato da convinzioni religiose (talvolta \u00e8 persino un giusto pur nella sua ingiustizia). Ed \u00e8 un artista. Gli esempi sono decine.<\/p>\n<p style=\"text-align: justify;\">Allo stesso tempo, per\u00f2, \u00e8 spuntato un secondo tipo di nuovo serial killer: il padre di famiglia, l&#8217;uomo ossessionato dalla religione (cattolica, prevalentemente, o comunque cristiana). In questo senso il cinema dei serial killer, ma anche il romanzo nei suoi maggiori esponenti (come Patricia Cornwell), \u00e8 diventato un mezzo di condanna della \u00abcultura patriarcale\u00bb e della famiglia tradizionale. In decine di serie televisive alcune, va detto, molto ben realizzate- e centinaia di film degli ultimi trent&#8217;anni \u00e8 il \u00abpadre\u00bb ad essere messo sotto accusa, in tutti i sensi.<\/p>\n<p style=\"text-align: justify;\">La donna \u00e8 quasi sempre una vittima, il maschio sempre colpevole, soprattutto se legato a una societ\u00e0 patriarcale, tradizionale e religiosa che \u00e8 vista come la fonte di tutti i mali. La famiglia \u00e8 malata: cos\u00ec \u00e8 rappresentata in molte serie americane, inglesi (Broadchurch o Happy Valley), norvegesi, svedesi e persino francesi. E la famiglia genera mostri: padri pedofili e\/o assassini, figli degenerati. Ci sono poi intere serie in cui scene clou di omicidio e violazione avvengono in chiese e luoghi di culto. Un caso? O soltanto un altro modo che le sinistre culturali e del regresso irrazionale hanno scelto per combattere l&#8217;antico nemico?<\/p>\n<p style=\"text-align: justify;\">Da questo punto di vista Meglio regnare all&#8217;inferno (frase tratta dall&#8217;opera di Milton, Paradiso perduto) \u00e8 una riflessione impressionante.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Giornale 7 Novembre 2017 Hannibal Lecter e Dexter sono icone di una societ\u00e0 che rinuncia a giudicare di Rino Cammilleri<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":40182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[174,2670],"class_list":["post-40181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sguardo-sul-nostro-tempo","tag-ideologia","tag-serial-killer","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Da maniaco a grande artista dell&#039;omicidio: cos\u00ec l&#039;ideologia ha stravolto anche il Male - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Da maniaco a grande artista dell&#039;omicidio: cos\u00ec l&#039;ideologia ha stravolto anche il Male - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-25T22:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/Hannibal-Lecter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"217\" \/>\n\t<meta property=\"og:image:height\" content=\"232\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Da maniaco a grande artista dell&#8217;omicidio: cos\u00ec l&#8217;ideologia ha stravolto anche il Male\",\"datePublished\":\"2018-04-25T22:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/\"},\"wordCount\":695,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Hannibal-Lecter.jpg\",\"keywords\":[\"ideologia\",\"serial killer\"],\"articleSection\":[\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/\",\"name\":\"Da maniaco a grande artista dell'omicidio: cos\u00ec l'ideologia ha stravolto anche il Male - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Hannibal-Lecter.jpg\",\"datePublished\":\"2018-04-25T22:00:28+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Hannibal-Lecter.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Hannibal-Lecter.jpg\",\"width\":217,\"height\":232},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Da maniaco a grande artista dell&#8217;omicidio: cos\u00ec l&#8217;ideologia ha stravolto anche il Male\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Da maniaco a grande artista dell'omicidio: cos\u00ec l'ideologia ha stravolto anche il Male - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/","og_locale":"it_IT","og_type":"article","og_title":"Da maniaco a grande artista dell'omicidio: cos\u00ec l'ideologia ha stravolto anche il Male - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-04-25T22:00:28+00:00","og_image":[{"width":217,"height":232,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/Hannibal-Lecter.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Da maniaco a grande artista dell&#8217;omicidio: cos\u00ec l&#8217;ideologia ha stravolto anche il Male","datePublished":"2018-04-25T22:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/"},"wordCount":695,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/Hannibal-Lecter.jpg","keywords":["ideologia","serial killer"],"articleSection":["Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/","name":"Da maniaco a grande artista dell'omicidio: cos\u00ec l'ideologia ha stravolto anche il Male - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/Hannibal-Lecter.jpg","datePublished":"2018-04-25T22:00:28+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/Hannibal-Lecter.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/Hannibal-Lecter.jpg","width":217,"height":232},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-maniaco-a-grande-artista-dellomicidio-cosi-lideologia-ha-stravolto-anche-il-male\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Da maniaco a grande artista dell&#8217;omicidio: cos\u00ec l&#8217;ideologia ha stravolto anche il Male"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=40181"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40181\/revisions"}],"predecessor-version":[{"id":40183,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40181\/revisions\/40183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/40182"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=40181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=40181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=40181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}