{"id":4014,"date":"2010-09-01T12:52:45","date_gmt":"2010-09-01T10:52:45","guid":{"rendered":""},"modified":"2015-03-12T11:45:21","modified_gmt":"2015-03-12T10:45:21","slug":"la-messa-al-cantiere-lenin","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/","title":{"rendered":"La Messa al cantiere Lenin"},"content":{"rendered":"<div style=\"text-align: center;\"><strong>CSEO documentazione<br \/>\n<\/strong>(mensile del Centro Studi Europa Orientale)<br \/>\nn. 152\/153 luglio-settembre 1980<\/div>\n<p style=\"text-align: center;\"><strong>Questo da noi nessuno se l&#8217;aspettava<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/cantieri-Lenin.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21332\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/cantieri-Lenin.jpg\" alt=\"cantieri Lenin\" width=\"130\" height=\"200\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><em>Ogni giorno nelle fabbriche in sciopero viene celebrata la Messa. Le immagini degli operai che pregano, si confessano, fanno la comunione, arrivano in Occidente e fanno scalpore. Questa \u00e8 la cronaca di una messa a Danzica, il 31 agosto<\/em><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Danzica. A cinquecento metri dalla stazione centrale, in diagonale, sulla sinistra, c&#8217;\u00e8 un&#8217;enorme scritta che va da una parte all&#8217;altra della strada: \u00abCantiere navale Lenin di Danzica\u00bb. Sotto, un po&#8217; a sinistra, c&#8217;\u00e8 uno striscione rosso con uno slogan scritto a caratteri bianchi: \u00abProletari di tutti gli stabilimenti unitevi\u00bb.<\/div>\n<p style=\"text-align: justify;\">A destra, sull&#8217;entrata laterale del cantiere, l&#8217;immagine della Madonna di Czgstochowa, minuscola, pi\u00f9 piccola di una qualsiasi delle lettere della grande scritta sopra l&#8217;entrata.La cornice dell&#8217;effigie \u00e8 ornata di fiori. Cos\u00ec si presenta l&#8217;entrata principale al cantiere, il cancello n. 2, oggi, domenica 31 agosto 1980. I due battenti del cancello assomigliano da lontano a dei tappeti rettangolari appesi, a due colori. Da vicino \u00e8 una parete di fiori.<\/p>\n<p style=\"text-align: justify;\">In gran parte sono mazzi di fiori, modesti, quotidiani, umili. Si vedono in mezzo anche dei fiori di campo, colti sicuramente dai bambini per i loro babbi che stanno dietro i cancelli. Molti mazzi di fiori hanno gi\u00e0 fatto in tempo a seccarsi. Niente di strano, essendo guardie d&#8217;onore del ricordo <em>e <\/em>dell&#8217;amore gi\u00e0 da due settimane, col sole e col maltempo.<\/p>\n<p style=\"text-align: justify;\">Volta per volta la mano di qualcuno pone nelle refrattarie sbarre di ferro un mazzo di fiori freschi. Ore 8.30 del mattino. Il megafono trasmette comunicati senza interruzione. Qualcuno \u00e8 chiamato al cancello, lo cercano la moglie e i figli. Qualcun altro \u00e8 atteso ai cancelli dalla madre. Lo speaker si corregge: dalla \u00abmamma\u00bb. \u00c8 giusto che si sia corretto. Qui le parole fredde colpiscono.<\/p>\n<p style=\"text-align: justify;\">Vicino alle grate infiorate ci sono due file di persone, per entrambe le parti del cancello. Sono persone singole o piccoli gruppi Si sente un bisbiglio, qualche volta una parola staccata, isolata. Il cancello ricorda ora un gigantesco confessionale. \u00c8 un luogo delle confidenze, di una buona parola, della fiducia. Non si vedono lacrime. \u00c8 giusto cos\u00ec. Questo non \u00e8 il muro del pianto. Non si rimpiange qui il passato.<\/p>\n<p style=\"text-align: justify;\">Non piange neppure il gruppetto delle donne in lutto, a poca distanza dal cancello. Tutti sono consapevoli e convinti che in questo luogo, al di l\u00e0 del cancello, si stia preparando un futuro migliore per la patria. Ci si fida in questa faccenda non solo della prudenza dell&#8217;uomo, ma anche di Colei che \u00ab\u00e8 stata posta in difesa della Nazione polacca\u00bb, e la cui immagine sormonta l&#8217;angolo destro del cancello. Forse che Nostra Signora di Jasna G\u00f2ra ha trasferito il suo trono qui a Danzica, in questi giorni di agitazione?<\/p>\n<p style=\"text-align: justify;\">I Polacchi sono abituati da secoli ad andare in pellegrinaggio da lei. Anch&#8217;essa \u00e8 solita andare in pellegrinaggi da loro, ovunque la Storia \u00e8 dolorosa. Non \u00e8 solo Nostra Signora di Jasna G\u00f2ra che regna qui. Si alternano sul cancello molte immagini sacre. C&#8217;\u00e8 un&#8217;icona autentica, di fronte alla quale si compie l&#8217;ufficio sacro: la ricerca di una maggiore verit\u00e0, di una giustizia pi\u00f9 equa, di un amore pi\u00f9 grande. C&#8217;\u00e8 l&#8217;immagine della Madonna col Bambino. La Madre di Dio di profilo, che guarda lontano.<\/p>\n<p style=\"text-align: justify;\">L\u00e0, in grosse cornici nere, stanno vicine l&#8217;una all&#8217;altra due immaginette tratte da un libro di preghiere: II cuore di Ges\u00f9 e Cristo Buon Pastore. Poco lontano due ritratti del Santo Padre. In uno Giovanni Paolo II in meditazione; nell&#8217;altro il Santo Padre che distende ampiamente la mano, come se volesse dire: Mai pi\u00f9 cancelli, mai pi\u00f9 barriere per Cristo e tra gli uomini. Anche se dovessero essere barriere adornate di fiori.<\/p>\n<p style=\"text-align: justify;\">Ore 8.40. Da entrambe le parti del cancello si \u00e8 gi\u00e0 radunata parecchia folla. Improvvisamente risuona la voce del megafono: \u00abPer favore fare posto. Per favore scostarsi. Lasciare passare il carico del pane\u00bb. L&#8217;autocarro con il pane fresco si fa strada a fatica. Non si sente neppure l&#8217;odore della macchina. Il profumo del pane \u00e8 pi\u00f9 forte. La macchina \u00e8 gi\u00e0 oltre il cancello. Ora cautamente gira attorno all&#8217;altare collocato nel centro del viale, vicino all&#8217;entrata al cantiere. Incontro significativo. Il pane incontra l&#8217;altare. Questi due beni sono indivisibili: Cristo e il pane.<\/p>\n<p style=\"text-align: justify;\">Senza pane non ci sarebbe il Cristo dell&#8217;Eucarestia, e senza Cristo il pane perderebbe il suo sapore. Il pane \u00e8 anche il frutto del lavoro dell&#8217;uomo. Non c&#8217;\u00e8 Cristo senza lavoro, e il lavoro senza Cristo perde il suo significato pi\u00f9 profondo. Diventa il lavoro di Sisifo. Non si pu\u00f2 dunque separare Cristo dagli uomini che lavorano \u2014 ha detto una volta Giovanni Paolo II, quando era ancora Cardinale. E questo postulato ha trova\u00adto la sua diretta collocazione nella lista delle richieste del mondo del lavoro.<\/p>\n<p style=\"text-align: justify;\">Ore 8.50. Il piazzale antistante il cancello \u00e8 pieno di gente. I nuovi arrivati, che giungono come ruscelli multicolori da tutte le parti verso il cantiere, sono costretti a prendere posto in angoli scomodi della piazza<em>. <\/em>Infatti qui \u00e8 tutto pieno di fosse, buchi, scavi per terra: qui si gettano le fondamenta per un nuovo edificio, l\u00e0 invece \u00e8 stata posta una croce di legno e del materiale. Ovunque \u00e8 gremito di gente. Si crea una specie di anfiteatro.<\/p>\n<p style=\"text-align: justify;\">Dall&#8217;altra parte dei cancelli-iconostasi si sono radunati gli operai. Prevale il colore grigio-azzurro delle bluse e dei calzoni. Non c&#8217;\u00e8 pi\u00f9 posto nel viale principale che conduce all&#8217;altare. Sono occupate anche le sponde. Gli operai sono saliti persino sulle casupole e sui muri di cemento. Qua e l\u00e0 in mezzo alla folla va una macchina con degli uomini su una piattaforma. Il tutto crea un semicerchio ovale, similmente a quello al di qua dei cancelli. Se non ci fosse il cancello sarebbe un unico, grande cerchio. Questi di qua e quelli di l\u00e0 del cancello non si vedono. Li unisce solo la preghiera. Anche dalla parte del cantiere \u00e8 appeso un ritratto del Papa sul cancello pieno di fiori. Regna un&#8217;atmosfera di seriet\u00e0.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/Solidarnosc_Messa_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-21333\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/Solidarnosc_Messa_2.jpg\" alt=\"Solidarnosc_Messa_2\" width=\"250\" height=\"181\" \/><\/a>Ore 8.55. L&#8217;altare \u00e8 pronto per il servizio divino. Un semplice tavolo con una tovaglia, posto sul rimorchio di un veicolo. Il piano del rimorchio \u00e8 tappezzato di carta da pacchi. Perch\u00e9 dovrebbe essere altrimenti? Tutto qui infonde semplicit\u00e0 e autenticit\u00e0. Perfino il piano dell&#8217;altare parla della vita normale e del lavoro di ogni giorno. Dalla parte della citt\u00e0, sopra il cancello del cantiere, si vedono corone di alberi e due grandi blocchi di abitazioni. In molte finestre, la gente.<\/p>\n<p style=\"text-align: justify;\">Si annuncia che tutti quelli che sono nel raggio di ascolto possono partecipare alla Santa Messa. Dalla parte del cantiere ci sono gli edifici dell&#8217;amministrazione, i reparti di lavoro e dei boschetti di alberi. All&#8217;orizzonte, in lontananza, si vedono giganteschi elevatori e gru. La loro inattivit\u00e0 testimonia l&#8217;agitazione che ha sconvolto questo luogo, la citt\u00e0 <em>e <\/em>la regione. Ricordano i pugni chiusi. Ma forse non sono simili alle mani congiunte nella preghiera, alzate verso il Cie-lo? Non solo le gru ferme testimoniano che qui sta accadendo qualcosa di insolito. Nel terrazzo sull&#8217;entrata coperta del cantiere, accanto ai cancelli, due o tre gruppi di pi\u00f9 di una decina di fotografi l&#8217;uno, al lavoro. Sono arrivati persine dei giapponesi.<\/p>\n<p style=\"text-align: justify;\">Ore 9. Si accendono le candele sull&#8217;altare. Migliaia di voci intonano un canto: \u00abQuando si lever\u00e0 l&#8217;aurora mattutina\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00c8 nuvoloso e minaccia la pioggia. Oggi si lever\u00e0 l&#8217;aurora. Dalla ferrovia echeggia \u00abCo-m&#8217;\u00e8 felice tutta la Polonia\u00bb. L&#8217;atmosfera cambia. La croce non \u00e8 l&#8217;ultima parola di Dio. L&#8217;ultima parola \u00e8 la Risurrezione. Il coro della Parrocchia del Mare esegue \u00abMadre di Dio\u00bb. Accanto all&#8217;altare sta il rev. Jankowski, figlio di questa terra, parroco della chiesa di S. Brigida, nel cui territorio sorge il cantiere. Tra coloro che servono all&#8217;altare ci sono due operai del cantiere. La Santa Messa viene qui celebrata con l&#8217;approvazione del voivoda di Danzica, su richiesta del vescovo. \u00abIl Signore sia con voi\u00bb, risuona la voce vigorosa del celebrante, riecheggiando dai reparti di lavoro e dalle abitazioni. \u00abE con il tuo spirito\u00bb, rispondono come un sol uomo.<\/p>\n<p style=\"text-align: justify;\">Il rev. Jankowski annuncia che celebra la Santa Messa in ringraziamento. Ancora prima della firma dell&#8217;accordo. Introduce l&#8217;assemblea nello spirito del sacrificio di Cristo. Il miracolo sul Baltico \u00e8 stato possibile grazie alla fede degli operai dei cantieri, grazie alla fede della gente della Costa. Ci sono parole di ringraziamento per la testimonianza di amore e di fede, per la pace, per la memoria dei bisogni di tutti. Gli operai, uomini d&#8217;azione, non hanno dimenticato neppure coloro che sono costretti sul letto di dolore, i malati, chiedendo per loro la Santa messa per radio.<\/p>\n<p style=\"text-align: justify;\">L&#8217;oratore rammenta all&#8217;assemblea di pensare innanzitutto al regno di Dio, e tutto il resto sar\u00e0 dato loro; di camminare sulla strada maestra, che \u00e8 Cristo, e avranno la verit\u00e0 e la vita. In abbondanza. \u00abChiediamo perdono a Dio per le nostre colpe\u00bb. Chiediamo perdono a Dio per le nostre colpe e per le colpe di coloro che non chiedono perdono. Tutti siamo peccatori. Dio stesso ha gi\u00e0 sconfitto la colpa nella coscienza di ogni uomo, a seconda delle sue opere, annotate nel Libro della Vita e della Morte. Non sediamo con Lui sul banco del giudice, sediamo con Lui piuttosto al banchetto comune della vita, nell&#8217;amore, nella verit\u00e0 e nella pace.<\/p>\n<p style=\"text-align: justify;\">Giungono i primi raggi di sole sull&#8217;altare. Il cielo si rischiara. Apparir\u00e0 forse l&#8217;arcobaleno? Le letture liturgiche sono tratte dalla XXII domenica dopo Pentecoste,. \u00c8 come se fossero state scelte proprio per le esigenze del momento. Il canto del versetto del salmista \u00abTu sei un Dio buono, protettore del povero\u00bb introduce il Vangelo. Leggiamo l&#8217;esortazione a non aspirare ai primi posti e allo spirito di servizio. Non ci si pu\u00f2 sedere comodamente alla mensa conviviale della Nazione a scapito dei deboli, di coloro che stanno zitti. Verr\u00e0 un giorno in cui i pi\u00f9 piccoli e i deboli diranno: \u00abAmico, spadroneggia di meno\u00bb.<\/p>\n<p style=\"text-align: justify;\">Dopo il Vangelo, viene letto il comunicato del Consiglio Generale dell&#8217;Episcopato. Sono strane le strade della Provvidenza e originale il modo di pensare dei Ministri di Dio. Quando a un certo punto delle attuali agitazioni sociali ed economiche tutti parlavano dei propri diritti, c&#8217;\u00e8 stato Qualcuno che ha ricordato a tutti i doveri, e quando la voce dei doveri, sollevata da altre voci chiassose, sembrava superare l&#8217;invocazione dei diritti, vennero parole di avvertimento sui diritti della Nazione e della persona umana. \u00c8 stata ad essi dedicata una lunga lettera, che viene letta oggi nelle chiese.<\/p>\n<p style=\"text-align: justify;\">La preghiera dei fedeli: per la Chiesa, per il santo Padre, per coloro che governano, affinch\u00e8 si adoperino per il bene comune della Nazione, per i malati, affinch\u00e8 la Parola di Dio possa raggiungerli per radio, per coloro che lavorano di domenica, per tutto ci\u00f2 che concerne l&#8217;atteggiamento cristiano nella vita di ogni giorno.<\/p>\n<p style=\"text-align: justify;\">Quando c&#8217;\u00e8 stata l&#8217;elevazione della patena col pane e del calice col vino, affinch\u00e8 il Padre Celeste accetti questi doni e li trasformi, e quando sulla patena scoperta e il calice col vino cominciarono a cadere le offerte, le sofferenze e i torti subiti dall&#8217;assemblea, affinch\u00e8 si unissero al sacrificio di Cristo, risuon\u00f2 il versetto del salmo: \u00abSi porr\u00e0 sotto la protezione del suo Dio\u00bb. Salmo della speranza, contro la disperazione.<\/p>\n<p style=\"text-align: justify;\">Solo l&#8217;insolenza di alcuni fotoreporter disturba il raccoglimento dell&#8217;assemblea. Senza ombra di dubbio, pare che l&#8217;impegno professionale faccia da padrone in questo luogo santo. Forse un giorno la nostra civilt\u00e0 la smetter\u00e0 con questo fenomeno. Sar\u00e0 permesso fare fotografie solo dai satelliti, per non disturbare la gente che prega.<\/p>\n<p style=\"text-align: justify;\">Uno dei fotografi che aspettano che per l&#8217;offertorio tutti si inginocchino (confondendo l&#8217;offertorio con l&#8217;elevazione) si rivolge con impazienza ad un suo collega: \u00abAllora, quando si mettono in ginocchio?\u00bb \u00c8 evidente che \u00e8 venuto solo per questo. \u00c8 sempre pi\u00f9 difficile vedere ginocchia piegate a questo mondo, e ancor pi\u00f9 difficile \u00e8 vedere le ginocchia piegate degli operai.<\/p>\n<p style=\"text-align: justify;\">Quelli che ancora pregano, lo fanno spesso in piedi. Sono stati promossi amici del Creatore e Signore. Non vedono che il loro tempio \u00e8 deserto. Rimangono soli nella piazza della preghiera. Soli con se stessi. Girando solo intorno a se stessi. Nessuno in questo luogo santo intralcia il fotoreporter nel suo lavoro, davanti al cancello del cantiere Lenin. Che il mondo sappia che l&#8217;operaio polacco va a testa alta perch\u00e9 le sue ginocchia sono piegate.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/solidarnosc_logo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-15221 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/solidarnosc_logo.jpg\" alt=\"solidarnosc_logo\" width=\"240\" height=\"104\" \/><\/a>\u00c8 il momento della consacrazione. Il celebrante leva il Corpo del Signore e il Suo Sangue, descrivendo un movimento circolare, per abbracciare tutti quelli che il cancello divide, per abbracciare il paese. \u00c8 il momento di accostarsi al Corpo di Cristo. Il Celebrante porta il Cristo fuori dal cancello.<\/p>\n<p style=\"text-align: justify;\">Un altro dei sacerdoti porta l&#8217;Eucarestia agli operai del cantiere. In questo giorno i bambini non possono ricevere la Santa Comunione accanto ai padri, i mariti accanto alle mogli. Non \u00e8 Cristo che divide. Egli va incontro agli emarginati. La Santa Comunione \u00e8 distribuita in una parte del cantiere, in mezzo al viale. Gli operai si mettono in fila. Uno degli operai che si accostano alla Santa Comunione, di circa cinquant&#8217;anni, in tuta, dopo aver ricevuto il Corpo di Cristo, si mette in ginocchio, si piega leggermente verso terra. Sulla guancia gli scende una lacrima. Si prende il viso tra le mani.<\/p>\n<p style=\"text-align: justify;\">Accorre un fotografo. Vuole tentare di riprendere un viso in preghiera. Non gli riesce. Ha troppe macchine fotografiche. Infine gli balena un&#8217;idea. Si inginocchia davanti all&#8217;uomo che prega e gli infila l&#8217;obiettivo sotto il viso. Un gesto istintivo di adorazione dell&#8217;uomo che adora Dio. Si inchina leggermente indietro e scatta una foto dopo l&#8217;altra.<\/p>\n<p style=\"text-align: justify;\">Dopo un attimo si alza e se ne va. Si \u00e8 alzato anche quell&#8217;operaio che era assorto nella preghiera. Si asciuga gli occhi col fazzoletto. Non sa che il suo viso \u00e8 stata la causa di strenui sforzi del fotoreporter. Se l&#8217;avesse visto, non vi avrebbe creduto. Forse le sue fotografie invaderanno il mondo intero. Questo ha pi\u00f9 importanza di taluni libri di teologia. Una foto un apostolo. Forse non bisognerebbe essere cos\u00ec severi nei confronti dei fotografi.<\/p>\n<p style=\"text-align: justify;\">La preghiera finale: per la Chiesa, per il mondo. Il rev. Jankowski da la benedizione. L&#8217;assemblea si inginocchia. Il viale sembra ora un tappeto fatto di volti umani. Ognuno di questi \u00e8 irripetibile, perch\u00e9 la Croce di Cristo introduce ognuno alla Gerusalemme celeste. L\u00e0 risplenderanno pi\u00f9 del sole. Per concludere il celebrante ricorda che ha celebrato la Santa Messa coi paramenti che gli avevano dato in regalo gli operai che scioperarono nel dicembre 1970. Sui paramenti \u00e8 ricamata l&#8217;immagine della Madonna di Czestochowa. Colei \u00abche \u00e8 stata data in difesa della Nazione\u00bb.<\/p>\n<p style=\"text-align: justify;\">La commozione \u00e8 visibile sul volto di molti operai, qua e l\u00e0 lacrime agli occhi. Le mani incallite stringo\u00adno il rosario. Nessuno qui si vergogna del rosario, come nessuno si vergogna degli arnesi di lavoro. C&#8217;\u00e8 anche qualcuno che lo porta al petto, sulla giacca, come un&#8217;arma. \u00abAndate, la Messa \u00e8 finita\u00bb. \u00abBoze cos Polske\u00bb. \u00abLa patria, la libert\u00e0\u00bb. Portiamo la Polonia davanti al tuo altare. Signore&#8230; Andate&#8230; al lavoro&#8230; al dialogo.<\/p>\n<p style=\"text-align: justify;\">Ci sar\u00e0 un&#8217;ulteriore ripresa delle trattative. Ma anche una \u00abripresa\u00bb della preghiera. Attraverso il megafono si annuncia che una Santa Messa verr\u00e0 celebrata nel Cantiere delle Riparazioni. Le cose di Dio si intrecciano con le cose degli uomini. E solo questo incontro genera un amore e una pace durevoli per gli uomini.<\/p>\n<p style=\"text-align: right;\">Stanislaw Musial SJ da <strong><em>Tygodnik Powszechny,<\/em> <\/strong>n 37 \/ 14 settembre 1980.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CSEO documentazione (mensile del Centro Studi Europa Orientale) n. 152\/153 luglio-settembre 1980 Questo da noi nessuno se l&#8217;aspettava Ogni giorno nelle fabbriche in sciopero viene celebrata la Messa. Le immagini degli operai che pregano, si confessano, fanno la comunione, arrivano in Occidente e fanno scalpore. Questa \u00e8 la cronaca di una messa a Danzica, il &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":21332,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,108],"tags":[830,1092],"class_list":["post-4014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filosofia-del-comunismo","category-paesi-e-continenti","tag-polonia","tag-solidarnosc","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Messa al cantiere Lenin - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Messa al cantiere Lenin - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-01T10:52:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-12T10:45:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/cantieri-Lenin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"181\" \/>\n\t<meta property=\"og:image:height\" content=\"279\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La Messa al cantiere Lenin\",\"datePublished\":\"2010-09-01T10:52:45+00:00\",\"dateModified\":\"2015-03-12T10:45:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/\"},\"wordCount\":2581,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/cantieri-Lenin.jpg\",\"keywords\":[\"Polonia\",\"Solidarnosc\"],\"articleSection\":[\"Comunismo\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/\",\"name\":\"La Messa al cantiere Lenin - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/cantieri-Lenin.jpg\",\"datePublished\":\"2010-09-01T10:52:45+00:00\",\"dateModified\":\"2015-03-12T10:45:21+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/cantieri-Lenin.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/cantieri-Lenin.jpg\",\"width\":181,\"height\":279},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-messa-al-cantiere-lenin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Messa al cantiere Lenin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Messa al cantiere Lenin - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/","og_locale":"it_IT","og_type":"article","og_title":"La Messa al cantiere Lenin - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2010-09-01T10:52:45+00:00","article_modified_time":"2015-03-12T10:45:21+00:00","og_image":[{"width":181,"height":279,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/cantieri-Lenin.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La Messa al cantiere Lenin","datePublished":"2010-09-01T10:52:45+00:00","dateModified":"2015-03-12T10:45:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/"},"wordCount":2581,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/cantieri-Lenin.jpg","keywords":["Polonia","Solidarnosc"],"articleSection":["Comunismo","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/","name":"La Messa al cantiere Lenin - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/cantieri-Lenin.jpg","datePublished":"2010-09-01T10:52:45+00:00","dateModified":"2015-03-12T10:45:21+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/cantieri-Lenin.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/09\/cantieri-Lenin.jpg","width":181,"height":279},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-messa-al-cantiere-lenin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La Messa al cantiere Lenin"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=4014"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4014\/revisions"}],"predecessor-version":[{"id":21334,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/4014\/revisions\/21334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/21332"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=4014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=4014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=4014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}