{"id":40013,"date":"2018-04-05T00:00:30","date_gmt":"2018-04-04T22:00:30","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=40013"},"modified":"2018-03-26T13:02:53","modified_gmt":"2018-03-26T11:02:53","slug":"cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/","title":{"rendered":"Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-40014\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/68_universit\u00e0.jpg\" alt=\"\" width=\"250\" height=\"196\" \/>Tempi<\/strong> n.3 Marzo 2018<\/p>\n<p style=\"text-align: center;\"><em>Il Sessantotto in cattedra<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Giancarlo Cesana<\/strong><\/p>\n<p style=\"text-align: justify;\">Nella puntata precedente ho indicato senza mezzi termini il comunismo come fenomeno espressivo di quel che \u00e8 accaduto nelle universit\u00e0 nel &#8217;68. L&#8217;ho fatta un po&#8217; breve, ma ho descritto l&#8217;esperienza che ho vissuto e, non essendo n\u00e9 filosofo, n\u00e9 sociologo, non mi sono soffermato nell&#8217;analisi delle motivazioni di quella insurrezione giovanile.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Da tempo sono usciti contributi in tal senso e ancora di pi\u00f9 ne usciranno in questo anno cinquantenario. Io ne segnalo uno vecchio, di Augusto Del Noce (1910-1989), pubblicato su Vita e Pensiero, la rivista dell&#8217;Universit\u00e0 Cattolica, nel numero 5 del 1968, quindi mentre le cose stavano succedendo. Le considerazioni di Del Noce sono acute e, visto il tempo in cui sono state pensate, profetiche. Le riassumo molto brevemente per invogliare a leggerle.<\/p>\n<p style=\"text-align: justify;\">Del Noce individu\u00f2 l&#8217;insurrezione giovanile del &#8217;68 come una &#8220;rivolta contro la societ\u00e0 del benessere&#8221; &#8211; o &#8220;tecnocratica&#8221; &#8211; fine a stessa, ovvero priva di tensione a una verit\u00e0 pi\u00f9 grande, religiosa. Il marxismo venne adottato come sostituto religioso, tuttavia in quanto ateo e inevitabilmente relativista, impotente a questo fine. Di qui la degenerazione nell&#8217;estremismo e il riassorbimento della rivolta nei miti tanto criticati della societ\u00e0 opulenta.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-39570\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/68_contestazione.jpg\" alt=\"\" width=\"250\" height=\"170\" \/>Altre analisi, a mio avviso meno profonde, hanno sottolineato come elementi dell&#8217;esplosione studentesca la ribellione contro il tradizionalismo oppressivo e autoritario dell&#8217;accademia, della cultura e dell&#8217;educazione delle generazioni precedenti, quindi la liberazione del desiderio e il percorso della vita come avventura e costruzione nuova, sia degli individui che della convivenza. Nelle interpretazioni moderne il comunismo non \u00e8 quasi pi\u00f9 citato o lo \u00e8 come fatto di rilevanza non decisiva nella comprensione del fenomeno.<\/p>\n<p style=\"text-align: justify;\">Tali interpretazioni sono alquanto indulgenti perch\u00e9 \u00e8 diffusa la tendenza a dar ragione ai giovani e soprattutto perch\u00e9, come gi\u00e0 detto, i giovani di allora sono frequentemente gli intellettuali che commentano adesso.<\/p>\n<p style=\"text-align: justify;\">Comunque non voglio entrare in merito dettagliato alle analisi e al loro tono. Sono disposto ad ammettere che tutte le motivazioni individuate siano poco o tanto giuste. Quel che mi interessa mettere in evidenza qui sono le conseguenze, quel che \u00e8 successo dopo. Per due motivi: le conseguenze fanno comprendere la chiarezza e la sincerit\u00e0 delle motivazioni; mettono in evidenza il valore attuale delle motivazioni e dei fatti da queste prodotti nel passato. Non voglio celebrare il &#8217;68, voglio capire a cosa e se \u00e8 servito, a me e a tutti.<\/p>\n<p style=\"text-align: justify;\"><strong>La trasformazione dell&#8217;universit\u00e0<\/strong><\/p>\n<p style=\"text-align: justify;\">Le prime conseguenze che prendo in considerazione sono quelle verificatesi dove tutto \u00e8 cominciato: l&#8217;universit\u00e0, appunto. Come brevemente descritto nella puntata precedente, alla fine degli anni Sessanta, l&#8217;universit\u00e0 italiana era il terminale di un processo di selezione marcata. La sua impostazione tradizionale era sicuramente elitaria, sia da un punto di vista culturale, che di censo. Essa pretendeva di fornire a chi la frequentava il titolo di &#8220;dottore&#8221;, ovvero non solo di esperto, ma anche di professionista, insegnante e ricercatore al massimo livello nella materia studiata. Di qui l&#8217;insistenza su un&#8217;accurata formazione metodologica di base, tanto selettiva quanto produttiva di conoscenze, che gli studenti stranieri non avevano rispetto ai loro coetanei italiani.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-18002\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/68.jpg\" alt=\"\" width=\"250\" height=\"187\" \/>L&#8217;universit\u00e0 italiana era concepita come il punto di arrivo di una scuola inferiore e media, anch&#8217;essa dotata di standard formativi molto alti, sconosciuti all&#8217;estero. Arrivarci era un duro cammino, che, in una societ\u00e0 uscita da una guerra persa e con uno sviluppo non omogeneo, era difficilmente possibile ai meno abbienti, il cui impegno nello studio doveva andare di pari passo con i sacrifici economici loro e delle loro famiglie.<\/p>\n<p style=\"text-align: justify;\">A mia mamma, che, soprattutto lei, voleva mandarmi all&#8217;universit\u00e0, nonostante l&#8217;unico occupato della famiglia &#8211; eravamo in quattro &#8211; fosse mio pap\u00e0, bigliettaio sul tram, dicevano che era matta. Bastava ed era gi\u00e0 tanto studiare da perito.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec, gli studenti, di fronte a una simile situazione, insorsero rivendicando per tutti il diritto allo studio, ovvero per tutti il diritto all&#8217;accesso ai gradi pi\u00f9 alti dell&#8217;istruzione. E gli accessi vennero liberalizzati, ovvero tutti gli studenti con diploma di scuola media superiore poterono iscriversi all&#8217;universit\u00e0, alla facolt\u00e0 che volevano. Pertanto la frequenza della scuola media superiore, che in quegli anni era gi\u00e0 in sensibile crescita, si rivers\u00f2 nelle universit\u00e0, che cominciarono, se cos\u00ec si pu\u00f2 dire, a scoppiare.<\/p>\n<p style=\"text-align: justify;\">Gli studenti erano assai pi\u00f9 numerosi dei posti a diposizione nelle aule e le aule erano insufficienti. Si ascoltavano le lezioni seduti per terra e anche fuori della porta. Per trovare spazio rettori e presidi prenotarono i cinema. Gli studenti dopo un po&#8217; si stufavano e non andavano pi\u00f9 a lezione, perch\u00e9 era difficoltoso e inutile. Si diffuse l&#8217;autodidattismo, il lavoro accoppiato allo studio, il fenomeno tutto italiano dei fuoricorso.<\/p>\n<p style=\"text-align: justify;\">Come disse Giorgio Amendola, storico esponente del Pci di &#8220;destra&#8221;, in un&#8217;intervista tv a Costanzo &#8211; Bont\u00e0 loro mi pare si chiamasse la trasmissione; era il 1977 o gi\u00f9 di l\u00ec &#8211; \u00abnon \u00e8 la scuola che seleziona, ma la vita\u00bb. E infatti la selezione non scomparve, semplicemente si spost\u00f2 a durante e dopo l&#8217;universit\u00e0. Si abbass\u00f2 sensibilmente la percentuale di studenti che si laureavano negli anni prescritti e si abbass\u00f2 allo stesso modo la percentuale di laureati che riuscivano a trovare un&#8217;occupazione corrispondente alle loro aspirazioni e all&#8217;ampiezza delle nozioni acquisite.<\/p>\n<p style=\"text-align: justify;\"><strong>Il senso del numero chiuso<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-32049\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/sessantotto.jpg\" alt=\"\" width=\"250\" height=\"168\" \/>Merito e qualit\u00e0 dell&#8217;insegnamento passarono in secondo piano rispetto alla rivendicazione del diritto allo studio. Di numero chiuso nemmeno a parlarne. Alla facolt\u00e0 di medicina della Statale di Milano, negli anni Settanta, a strutture didattiche praticamente invariate rispetto agli anni precedenti, si iscrisse un numero di matricole superiore a tutte quelle iscritte nel Regno Unito. E and\u00f2 avanti cos\u00ec per anni, facendo s\u00ec che diventassimo il paese con il pi\u00f9 alto numero di medici dopo Cuba &#8211; loro 7 per mille abitanti, noi 6. Da allora si intasarono progressivamente d\u00ec assunzioni gli ospedali pubblici, che oggi presentano il personale medico con l&#8217;et\u00e0 media pi\u00f9 alta in Europa.<\/p>\n<p style=\"text-align: justify;\">I medici giovani faticano molto a entrare, a essere come si suol dire strutturati, assunti a tempo indeterminato, che, come mostra Quo Vado? di Zalone, sembra essere l&#8217;aspirazione fondamen\u00adtale degli italiani. Gli specializzandi nelle varie branche della medicina sono medici laureati e abilitati a tutti gli effetti, ma sono considerati come studenti, ovvero negli ospedali non possono esercitare autonomamente. Questo per evitare che i giovani, a costo minore e pi\u00f9 disponibili all&#8217;impegno spesso gravoso degli ospedali, sopravanzino i pi\u00f9 anziani o siano preferiti a loro.<\/p>\n<p style=\"text-align: justify;\">La ragione proclamata \u00e8 che gli specializzandi sono ancora professionalmente immaturi e quindi non in grado di affrontare la complessit\u00e0 della clinica. \u00c8 vero, ma essendo inseriti strutturalmente nell&#8217;ospedale possono imparare e rendersi progressivamente pi\u00f9 utili. \u00c8 quanto avviene in tutto il mondo civile. D&#8217;altra parte la cautela nell&#8217;assunzione dei giovani medici non impedisce che essi, anche se non sono n\u00e9 specializzandi, n\u00e9 specializzati, vengano adibiti alla cosiddetta continuit\u00e0 assistenziale, ovvero ai turni di guardia notturni e festivi che i medici di famiglia da tempo non coprono pi\u00f9.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29800\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/medici.jpg\" alt=\"\" width=\"250\" height=\"172\" \/>Cos\u00ec medici non buoni per un&#8217;attivit\u00e0 ospedaliera relativamente protetta dalla presenza o dalla reperibilit\u00e0 di colleghi pi\u00f9 esperti, sono buoni per interventi solitari su pazienti che possono presentare di tutto, anche nel senso della gravit\u00e0. Poi ci si lamenta dell&#8217;affollamento e delle attese in pronto soccorso.<\/p>\n<p style=\"text-align: justify;\">Mi scuso se mi dilungo un po&#8217; sulla medicina, ma \u00e8 il mio campo e un ottimo esempio delle conseguenze sessantot\u00adtesche. Comunque, quanto sopra \u00e8 per sottolineare che primo compito di una scuola \u00e8 dire il numero di studenti che pu\u00f2 formare e quindi accettare. Questa seriet\u00e0 \u00e8 la ragione fondamentale del numero chiuso ed \u00e8 appunto compito della singola scuola e non del ministero, che con stime da piano quinquennale staliniano, stabilisce il fabbisogno di medici, dentisti, architetti e veterinari, che sono le lauree a numero programmato nazionale.<\/p>\n<p style=\"text-align: justify;\">Certo, come gi\u00e0 succede, le scuole possono essere accreditate preventivamente in base alle dotazioni. La loro qualit\u00e0 sar\u00e0 poi dimostrata dai risultati ottenuti nella attrazione e formazione degli studenti, che le scuole devono poter scegliere in base a criteri da loro stesse determinati.<\/p>\n<p style=\"text-align: justify;\"><strong>Merito e disuguaglianza<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-40015\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/numero_chiuso_universit\u00e0.jpg\" alt=\"\" width=\"250\" height=\"187\" \/>Qui entra in gioco il problema del merito, che formalmente \u00e8 sempre sottolineato come primario criterio di avanzamento nello studio e nella professione. Dico formalmente perch\u00e9 il &#8217;68 ha sensibilmente ridimensionato il dovere del merito rispetto al diritto ad accedere al titolo di studio. Ci\u00f2 in parte giustamente perch\u00e9 lo studente povero che deve lavorare per mantenersi fa ovviamente grande fatica a ottenere risultati brillanti nello studio. Tuttavia il superamento di questa disuguaglianza non si ottiene dando borse di studio a tutti coloro che sono in difficolt\u00e0 economiche a prescindere dal merito. La diseguaglianza infatti persiste come minor preparazione e non \u00e8 abbattuta, ma solo spostata a dopo la fine degli studi.<\/p>\n<p style=\"text-align: justify;\">Il merito, come dicono in molti, non pu\u00f2 essere stabilito con quiz a crocette, come nei test di ammissione all&#8217;universit\u00e0 e nemmeno con una media di voti, ma richiede una valutazione della persona, pi\u00f9 completa e accurata. Questa valutazione non pu\u00f2 essere fatta contempora\u00adneamente in un maxi concorso pubblico, svolto nello stesso giorno per 63 mila candidati, come \u00e8 avvenuto quest&#8217;anno a medicina<\/p>\n<p style=\"text-align: justify;\">Appunto, devono essere le singole scuole a scegliere valutando test, curriculum e se possibile altri criteri espressivi del carattere e delle inclinazioni individuali. Ma a questo punto interviene un&#8217;altra bandiera sventolata nel &#8220;68, quella dell&#8217;uguaglianza.<\/p>\n<p style=\"text-align: right;\">(2. continua)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempi n.3 Marzo 2018 Il Sessantotto in cattedra di Giancarlo Cesana Nella puntata precedente ho indicato senza mezzi termini il comunismo come fenomeno espressivo di quel che \u00e8 accaduto nelle universit\u00e0 nel &#8217;68. L&#8217;ho fatta un po&#8217; breve, ma ho descritto l&#8217;esperienza che ho vissuto e, non essendo n\u00e9 filosofo, n\u00e9 sociologo, non mi sono &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":40014,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98,23,24,96],"tags":[971],"class_list":["post-40013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-il-68","category-scuola-ed-educazione","category-storia","category-storia-italiana","tag-universita","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-04T22:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/68_universit\u00e0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"254\" \/>\n\t<meta property=\"og:image:height\" content=\"199\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea\",\"datePublished\":\"2018-04-04T22:00:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/\"},\"wordCount\":1562,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/68_universit\u00e0.jpg\",\"keywords\":[\"universit\u00e0\"],\"articleSection\":[\"Il 68\",\"Scuola ed educazione\",\"Storia\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/\",\"name\":\"Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/68_universit\u00e0.jpg\",\"datePublished\":\"2018-04-04T22:00:30+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/68_universit\u00e0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/68_universit\u00e0.jpg\",\"width\":254,\"height\":199},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/","og_locale":"it_IT","og_type":"article","og_title":"Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-04-04T22:00:30+00:00","og_image":[{"width":254,"height":199,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/68_universit\u00e0.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea","datePublished":"2018-04-04T22:00:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/"},"wordCount":1562,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/68_universit\u00e0.jpg","keywords":["universit\u00e0"],"articleSection":["Il 68","Scuola ed educazione","Storia","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/","name":"Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/68_universit\u00e0.jpg","datePublished":"2018-04-04T22:00:30+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/68_universit\u00e0.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/68_universit\u00e0.jpg","width":254,"height":199},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cosi-il-diritto-allo-studio-fini-per-demolire-il-valore-della-laurea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Cos\u00ec il diritto allo studio fin\u00ec per demolire il valore della laurea"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=40013"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40013\/revisions"}],"predecessor-version":[{"id":40016,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/40013\/revisions\/40016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/40014"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=40013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=40013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=40013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}