{"id":39725,"date":"2018-02-22T00:00:40","date_gmt":"2018-02-21T23:00:40","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=39725"},"modified":"2018-02-16T09:46:43","modified_gmt":"2018-02-16T08:46:43","slug":"mais-ogm-nessun-rischio-per-la-salute","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/","title":{"rendered":"\u00abMais Ogm, nessun rischio per la salute\u00bb"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-39726\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/ogm.jpg\" alt=\"\" width=\"250\" height=\"187\" \/>Avvenire<\/strong> Venerd\u00ec 16 Febbraio 2018<\/p>\n<p style=\"text-align: center;\"><em>Studio italiano su 21 anni di coltivazioni nel mondo<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Marco Girardo<\/strong><\/p>\n<p style=\"text-align: justify;\">Non ci sono evidenze scientifiche che il mais geneticamente modificato possa risultare rischioso per la salute umana, animale o ambientale. Questa la conclusione della prima e pi\u00f9 vasta analisi dei dati relativi a ventun anni di coltivazioni Ogm nel mondo, uno studio condotto dalla Scuola Superiore Sant&#8217;Anna e dall&#8217;Universit\u00e0 di Pisa &#8211; ricerca indipendente, senza committenti in potenziale conflitto d&#8217;interesse, dunque &#8211; appena pubblicato sulla rivista intemazionale Scientific Reports.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Coordinati da Laura Ercoli, docente di Agronomia e Coltivazioni Erbacee all&#8217;Istituto di Scienze della Vita della Scuola Superiore Sant&#8217;Anna, Elisa Pellegrino, Stefano Bedini e Marco Nuti hanno analizzato i dati sulle colture di mais transgenico dal loro inizio, nel 1996, fino al 2016 negli Stati Uniti, in Europa, Sud America, Asia, Africa e Australia. \u00abL&#8217;analisi fornisce una sintesi efficace su un problema specifico molto discusso pubblicamente\u00bb, ha spiegato Laura Ercoli.<\/p>\n<p style=\"text-align: justify;\">Le colture Ogm hanno raggiunto infatti &#8211; sono i dati aggiornati al 2016 del Servizio internazionale per l&#8217;acquisizione delle applicazioni agro-biotecnologiche (Isaa) &#8211; i 185,1 milioni di ettari complessivi, sono distribuite in 26 Paesi e tengono impegnati circa 18 milioni di agricoltori. I maggiori incrementi si riscontrano in Africa dove, in particolare, Sudafrica e Sudan hanno aumentato la piantagione di mais, soia e cotone bio-tech a 2,66 milioni di ettari dai 2,29 milioni del 2015.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30455\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/ogm.jpg\" alt=\"\" width=\"250\" height=\"166\" \/>Attualmente le coIture Ogm sono vietate in molti Paesi Ue, Italia inclusa, e sopravvivono di fatto solo in Spagna e Portogallo. Lo studio pubblicato su Scientific Reports \u00abha riguardato esclusivamente l&#8217;elaborazione rigorosa dei dati scientifici e non l&#8217;interpretazione &#8220;politica&#8221; dei medesimi\u00bb, sostengono i ricercatori, rilevando che i risultati appena pubblicati permettono di \u00abtrarre conclusioni univoche, aiutando ad aumentare la fiducia del pubblico nei confronti del cibo prodotto con piante geneticamente modificate\u00bb.<\/p>\n<p style=\"text-align: justify;\">La meta-analisi si \u00e8 basata su 11.699 osservazioni che interessano le produzioni, la qualit\u00e0 della granella (incluso il contenuto in micotossine), l&#8217;effetto sugli insetti target e non-target, i cicli biogeochimici come contenuto di lignina negli stocchi e nelle foglie, perdite di peso della biomassa, emissione di C02 dal suolo. Su queste basi lo studio dimostra, \u00abin maniera decisa\u00bb, che \u00abil mais transgenico \u00e8 notevolmente pi\u00f9 produttivo (5,6-24,5%), non ha effetto sugli organismi non-target (non bersagli della modificazione genetica), tranne la naturale diminuzione del Braconide parassitoide dell&#8217;insetto dannoso target Ostrinia nubilalis &#8211; spiega una nota di accompagnamento alla ricerca &#8211; e contiene concentrazioni minori di micotossine (-28,8%) efumonisine (-30,6%) nella granella\u00bb, cio\u00e8 nei chicchi.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35646\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/07\/no_ogm.png\" alt=\"\" width=\"250\" height=\"151\" \/>Il team italiano precisa di avere applicato \u00able moderne tecniche matematico-statistiche di meta-analisi su risultati provenienti da studi indipendenti, per trarre conclusioni pi\u00f9 forti rispetto a quelle ottenute da ogni singolo studio\u00bb.<\/p>\n<p style=\"text-align: justify;\">Gli aspetti inerenti la salute, in ogni caso, non sono gli unici a dividere opinione pubblica e decisori politici sugli Ogm. Se da un lato, intatti, la maggior resistenza di queste colture permette potenzialmente di dare una risposta ai problemi alimentari in molti Paesi colpiti da carestie e fame endemica, dall&#8217;altro c&#8217;\u00e8 il rischio di una drastica riduzione della biodiversit\u00e0 e delle comunit\u00e0 agricole locali.<\/p>\n<p style=\"text-align: justify;\">Commentando lo studio scientifico, Greenpeace sottolinea ad esempio come le colture transgeniche, considerate una panacea per la produzione di cibo, costituiscano in realt\u00e0 un freno per l&#8217;innovazione ecologica in agricoltura: \u00abSottopongono l&#8217;agricoltura al controllo e ai brevetti di poche aziende agrochimiche &#8211; sostiene Federica Ferrario &#8211; a danno della biodiversit\u00e0 e del nostro made in Italy.<\/p>\n<p style=\"text-align: center;\">_______________________<\/p>\n<p style=\"text-align: center;\"><strong>Nella UE coltivato un solo prodotto. Cinquanta invece le autorizzazioni <\/strong><\/p>\n<p style=\"text-align: center;\"><strong>per importare mangimi transgenetici<\/strong><\/p>\n<p style=\"text-align: center;\">di<strong> Giovanni Maria Del Re<\/strong><\/p>\n<p style=\"text-align: justify;\">BRUXELLES _ In Europa un solo prodotto Ogm \u00e8 coltivato: \u00e8 il famoso mais MON810 (prodotto da Monsanto) e unicamente in Spagna e Portogallo. Circa una cinquantina sono invece gli ogm importati autorizzati a livello Ue per i mangimi animale (in alcuni casi l&#8217;autorizzazione vale anche per l&#8217;alimentazione umana, ma non risulta che ogm siano effettivamente utilizzati a questo scopo).<\/p>\n<p style=\"text-align: justify;\">Sulla questione l&#8217;Europa \u00e8 divisa, come si \u00e8 visto nel caso del rinnovo dell&#8217;autorizzazione del mais MON810: nel comitato di esperti sulla sicurezza alimentare, in cui siedono i rappresentanti di tutti gli Stati membri, non si \u00e8 raggiunta la maggioranza qualificata (il 55% degli Stati che per\u00f2 deve corrispondere al 65% della popolazione) n\u00e9 a favore, n\u00e9 contro, e il rinnovo dell&#8217;autorizzazione delle semenze per la coltivazione resta \u00abin attesa\u00bb (rimane in vigore la vecchia).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-30309\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/agricolt_Africa.jpg\" alt=\"\" width=\"250\" height=\"166\" \/>A luglio la Commissione (cui toccherebbe l&#8217;ultima parola in caso di stallo) ha per\u00f2 intanto rinnovato l&#8217;autorizzazione del MON810 gi\u00e0 prodotto per usi alimentari animali e umani. Analogo il caso di altri due mais ogm, il Pioneer 1507 e il Syngenta Bt 11, anche qui le semenze sono in attesa di rinnovo in mancanza di un accordo. Sempre a luglio la Commissione ha comunque autorizzato quattro nuove piante ogm per alimentazione e mangimi (due cotoni e due mais).<\/p>\n<p style=\"text-align: justify;\">Quanto alla normativa generale, nel 2015 Stati membri e Parlamento Europeo hanno approvata una modifica alla direttiva sulla coltivazione di piante ogm: gli Stati sono liberi di vietarla a livello nazionale anche per ogm autorizzati a livello Ue.<\/p>\n<p style=\"text-align: justify;\">Bloccata, per il no sia del Parlamento Europeo sia degli Stati membri \u00e8 invece una seconda direttiva proposta dalla Commissione, che avrebbe esteso la facolt\u00e0 di divieto nazionale anche all&#8217;importazione di ogm gi\u00e0 prodotti in paesi terzi. La spiega\u00adzione: mentre \u00e8 possibile vietare la coltivazione a livello nazionale, \u00e8 pressoch\u00e9 impossibile attuare il divieto nazionale di importazione in un&#8217;Europa pienamente integrata con libera circolazioni delle merci.<\/p>\n<p style=\"text-align: justify;\">Certo \u00e8 che cresce l&#8217;opposizione popolare, e di qui di molti Stati, per gli ogm. Non abbastanza, per\u00f2, almeno per ora, per arrivare a maggioranze qualificate per il divieto. Il Parlamento Europeo ha comunque approvato lo scorso anno a vasta maggioranza una risoluzione per la messa al bando dei prodotti ogm, che per\u00f2 non \u00e8 vincolante.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avvenire Venerd\u00ec 16 Febbraio 2018 Studio italiano su 21 anni di coltivazioni nel mondo di Marco Girardo Non ci sono evidenze scientifiche che il mais geneticamente modificato possa risultare rischioso per la salute umana, animale o ambientale. Questa la conclusione della prima e pi\u00f9 vasta analisi dei dati relativi a ventun anni di coltivazioni Ogm &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":39726,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,22],"tags":[1928,274],"class_list":["post-39725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambientalismo","category-scienza","tag-agricoltura","tag-ogm","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00abMais Ogm, nessun rischio per la salute\u00bb - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abMais Ogm, nessun rischio per la salute\u00bb - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-21T23:00:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/ogm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"\u00abMais Ogm, nessun rischio per la salute\u00bb\",\"datePublished\":\"2018-02-21T23:00:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/\"},\"wordCount\":962,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/ogm.jpg\",\"keywords\":[\"agricoltura\",\"ogm\"],\"articleSection\":[\"Ambientalismo\",\"Scienza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/\",\"name\":\"\u00abMais Ogm, nessun rischio per la salute\u00bb - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/ogm.jpg\",\"datePublished\":\"2018-02-21T23:00:40+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/ogm.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/ogm.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mais-ogm-nessun-rischio-per-la-salute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abMais Ogm, nessun rischio per la salute\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abMais Ogm, nessun rischio per la salute\u00bb - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/","og_locale":"it_IT","og_type":"article","og_title":"\u00abMais Ogm, nessun rischio per la salute\u00bb - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-02-21T23:00:40+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/ogm.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"\u00abMais Ogm, nessun rischio per la salute\u00bb","datePublished":"2018-02-21T23:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/"},"wordCount":962,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/ogm.jpg","keywords":["agricoltura","ogm"],"articleSection":["Ambientalismo","Scienza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/","name":"\u00abMais Ogm, nessun rischio per la salute\u00bb - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/ogm.jpg","datePublished":"2018-02-21T23:00:40+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/ogm.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/ogm.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mais-ogm-nessun-rischio-per-la-salute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"\u00abMais Ogm, nessun rischio per la salute\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=39725"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39725\/revisions"}],"predecessor-version":[{"id":39727,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39725\/revisions\/39727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/39726"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=39725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=39725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=39725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}