{"id":39662,"date":"2018-02-08T00:00:09","date_gmt":"2018-02-07T23:00:09","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=39662"},"modified":"2018-02-08T08:34:04","modified_gmt":"2018-02-08T07:34:04","slug":"il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/","title":{"rendered":"Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde"},"content":{"rendered":"<p style=\"text-align: center;\">Osservatorio Internazionale Cardinale Van Thu\u00e2n<\/p>\n<p style=\"text-align: center;\"><strong>Newsletter <\/strong>n.861 del 6 Febbraio 2018<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39663 aligncenter\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/dottrina_sociale.jpg\" alt=\"\" width=\"323\" height=\"156\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/dottrina_sociale.jpg 323w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/dottrina_sociale-300x145.jpg 300w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/p>\n<p style=\"text-align: justify;\"><em>Sabato scorso 3 febbraio si \u00e8 tenuto a Milano, presso il teatro Don Guanella, l\u2019Incontro nazionale delle Scuole di Dottrina sociale della Chiesa \u201cMater et Magistra\u201d dell\u2019Osservatorio. La giornata dal titolo \u201cConoscere la verit\u00e0, praticare la giustizia\u201d \u00e8 stata organizzata insieme al quotidiano online La Nuova Bussola Quotidiana. Pubblichiamo qui il testo integrale dell\u2019intervento dell\u2019Arcivescovo Giampaolo Crepaldi, presidente dell\u2019Osservatorio<\/em><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\">S.E. Mons. <strong>Giampaolo Crepaldi<\/strong><\/p>\n<p style=\"text-align: center;\">Intervento a Milano \u2013 Teatro don Guanella<\/p>\n<p style=\"text-align: center;\">3 febbraio 2018<\/p>\n<p style=\"text-align: justify;\">Cari amici,<\/p>\n<p style=\"text-align: justify;\">sono lieto di trovarmi qui oggi, assieme a voi, in questa Giornata particolare. Direi, anzi, molto particolare, in cui ho la possibilit\u00e0 di incontrare molti partecipanti alle nostre Scuole di Dottrina sociale della Chiesa che andiamo organizzando in vari punti d\u2019Italia. Si tratta di una iniziativa molto bella: la partecipazione comune alle Scuole ci ha fatto fare esperienza di una nostra unit\u00e0 e comunione spirituale e di intenti, anche se eravamo fisicamente lontani, dato che molti hanno partecipato online e, quindi, a distanza.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 \u00e8 capitato in particolare per la Scuola che ho tenuto io stesso, in collaborazione con <em>La Nuova Bussola Quotidiana<\/em>. Mentre le altre Scuole avevano una prevalente partecipazione in loco, nel mio caso invece il contatto \u00e8 avvenuto solo a distanza. E\u2019 stata quindi una buona idea, di cui ringrazio soprattutto il direttore Riccardo Cascioli e il prof. Stefano Fontana, organizzare questa giornata.<\/p>\n<p style=\"text-align: justify;\">Oggi non far\u00f2 un discorso di grandi contenuti teologici. Per questo abbiamo chiamato il prof. Don Mauro Gagliardi. Il mio sar\u00e0 invece un discorso pastorale. Parler\u00f2 da Vescovo, da Vescovo che ha sempre lavorato nel campo della Dottrina sociale della Chiesa e che anche ora, sia per la Presidenza del nostro Osservatorio sia per l\u2019incarico in Europa, ancora lo fa.<\/p>\n<div id=\"attachment_28013\" style=\"width: 250px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-28013\" class=\"wp-image-28013\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/11\/Crepaldi.jpg\" alt=\"\" width=\"250\" height=\"140\" \/><p id=\"caption-attachment-28013\" class=\"wp-caption-text\">mons Giampaolo Crepaldi<\/p><\/div>\n<p style=\"text-align: justify;\">E non cessa di interrogarsi e di riflettere sulla situazione della Dottrina sociale della Chiesa oggi. L\u2019ho fatto, recentemente, in un libretto dal titolo \u201cLa Chiesa italiana e il futuro della pastorale sociale\u201d edito da Cantagalli, di cui tra breve riprender\u00f2 qualche idea. Vi dico questo per confermare che, nonostante i miei impegni pastorali di Vescovo di Trieste mi occupino molto, seguo da vicino l\u2019attivit\u00e0 dell\u2019Osservatorio, ho seguito con attenzione l\u2019avvio e la conduzione delle nostre Scuole di Dottrina sociale della Chiesa a cui anche voi avete partecipato e sono qui oggi per dirvi di continuare e per dare, appunto, qualche motivazione pastorale di questo rinnovato impegno che vi chiedo.<\/p>\n<p style=\"text-align: justify;\">Il titolo del mio intervento inizia con questa frase: \u201cIl fare segue l\u2019essere\u201d. <em>Agere seguitur esse<\/em>, si diceva una volta. Si agisce in base a ci\u00f2 che si \u00e8. Prima bisogna porsi il problema di essere \u2026 e poi ci si porr\u00e0 il problema di cosa fare. La cosa \u00e8 molto importante, perch\u00e9 mentre il fare potremmo considerarlo cosa che dipende da noi, l\u2019essere, invece, ci appare subito come un dono. Per questo Benedetto XVI nella <em>Caritas in veritate<\/em> ha sviluppato il concetto che il ricevere precede il fare. Proprio perch\u00e9 il fare procede dall\u2019essere e l\u2019essere lo si \u00e8 ricevuto, il dono ha la priorit\u00e0. Un corollario di questo principio \u00e8 che la volont\u00e0 segue l\u2019intelletto.<\/p>\n<p style=\"text-align: justify;\">L\u2019essere dell\u2019uomo \u00e8 fatto di intelletto e di volont\u00e0, ma l\u2019intelletto prevale, essendo la luce per la volont\u00e0 retta. Ecco allora la corretta successione delle cose: abbiamo ricevuto l\u2019essere e quindi bisogna prima di tutto curarsi di essere e poi di fare; bisogna quindi capire cosa siamo con l\u2019intelletto per poi agire con la forza della volont\u00e0 retta.<\/p>\n<p style=\"text-align: justify;\">Questo, cari amici, vale per ogni persona, ma vale anche per la Chiesa nel suo insieme. Ed \u00e8 qui che si inserisce la Dottrina sociale della Chiesa e la necessit\u00e0 di una formazione sistematica ad essa. Molti oggi pensano che i cattolici debbano soprattutto agire, operare secondo una buona volont\u00e0 animata dalla carit\u00e0. La cosa ritenuta pi\u00f9 importante \u00e8 esserci sul terreno delle emergenze e dei bisogni del nostro prossimo.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-26406\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/06\/dottrina-sociale.png\" alt=\"\" width=\"250\" height=\"171\" \/>E\u2019 positivo questo senso di contribuire alla pace e alla giustizia, ma in base a quanto abbiamo appena osservato, il fare non \u00e8 sufficiente. Se non \u00e8 espressione dell\u2019essere e se non \u00e8 guidato dalla luce della verit\u00e0, il fare si dimostra cieco. Si pensa che sia costruttivo e invece rischia di essere decostruttivo. Si prova una soddisfazione individuale intima perch\u00e9 si pensa di aver fatto il bene, ma in realt\u00e0 non \u00e8 stato proprio cos\u00ec.<\/p>\n<p style=\"text-align: justify;\">La Dottrina sociale della Chiesa \u00e8 espressione prima di tutto dell\u2019essere della Chiesa e del suo intimo carattere missionario. La Dottrina sociale della Chiesa si nutre prima di tutto della vita della Chiesa. Da ci\u00f2 nascono poi i criteri d\u2019azione, che a questo punto non sono un mero fare, ma un \u201cfare essendo\u201d. La Chiesa non pu\u00f2 agire prima di essere o senza essere. Ci\u00f2 vale anche per i laici cattolici impegnati nell\u2019azione sociale e politica tramite la Dottrina sociale della Chiesa. Quest\u2019ultima ha un valore pratico, ma prima ne ha uno dottrinale e contenutistico che l\u2019intelletto conosce e che indica alla volont\u00e0 per poi agire. Senza appropriarsi di questi contenuti e senza considerare la Dottrina sociale della Chiesa connessa con l\u2019essere della Chiesa stessa ci si agiter\u00e0 nel fare, ma con scarsi risultati oggettivi.<\/p>\n<p style=\"text-align: justify;\">Nel mio libro sopra ricordato ho esaminato il percorso della pastorale sociale dal Concilio ad oggi. Mi sono soffermato sul grandioso tentativo di rilancio della Dottrina sociale della Chiesa di Giovanni Paolo al quale ho partecipato anch\u2019io dato il mio incarico in Santa Sede in quegli anni. Mi sono soffermato anche sugli ostacoli a questo rilancio, molti dei quali perdurano anche oggi. Uno di questi \u00e8 considerare la Dottrina sociale della Chiesa come una generica spinta a fare, l\u2019anima di un generico umanesimo, lo spunto per una presenza pastorale non meglio qualificata sul piano dei contenuti. In questo modo, per\u00f2, la Dottrina sociale della Chiesa, intesa come corpus dottrinale, viene messa da parte.<\/p>\n<p style=\"text-align: justify;\">Eccoci allora alla seconda parte del titolo di questo mio intervento: \u201csenza formazione il popolo cattolico si disperde\u201d. Il problema non \u00e8 mai quanti si \u00e8, anche se pure noi cattolici ameremmo essere in tanti.<\/p>\n<p style=\"text-align: justify;\">Il problema principale \u00e8 se si \u00e8 uniti o dispersi, se si \u00e8 radicati insieme nell\u2019essere o se si \u00e8 dispersi nel fare fine a se stesso. Credo di poter dire che oggi i cattolici nella societ\u00e0 e specialmente nella politica siano dispersi. Troveremo la soluzione con stravaganti formule o col recupero per il nostro essere? N\u00e9 si creda che la dispersione riguardi solo le cose da fare. Essa ha una ricaduta anche nel modo di essere, perch\u00e9 questo \u00e8 il paradosso: scavalcare il problema dell\u2019essere per dedicarsi primariamente al fare, alla fine ha delle ripercussioni negative anche sull\u2019essere.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31783\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/03\/compendio_dottrina_sociale.jpg\" alt=\"\" width=\"125\" height=\"200\" \/>La messa da parte del corpus della Dottrina sociale della Chiesa frammenta e disperde l\u2019agire e, contemporaneamente e di rimbalzo, incrina il nostro essere uniti nella fede. Non siamo gli unici a fare formazione alla Dottrina sociale della Chiesa e quanto facciamo non \u00e8 in concorrenza con nessun\u2019altra iniziativa. Teniamo, per\u00f2, ad aver chiare le motivazioni profonde della nostra attivit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Ho cercato, con queste mie brevi riflessioni, di comunicarvi lo spirito e l\u2019intento con cui il nostro Osservatorio ha messo in piedi le Scuole di Dottrina sociale della Chiesa che abbiamo tenuto finora a Trieste (per il terzo anno), a Verona, a Staggia Senese, a Schio e a Lerici. Con lo stesso spirito stiamo iniziando la Scuola dell\u2019Emilia che inizier\u00e0 in marzo.<\/p>\n<p style=\"text-align: justify;\">Ringrazio tutte le associazioni e i centri culturali che hanno collaborato con noi e che cos\u00ec hanno permesso che le nostre Scuole avessero un contatto con un territorio e una comunit\u00e0. Se la Nuova Bussola \u00e8 d\u2019accordo, io personalmente sono ancora disposto a mettermi in gioco per questo progetto di formazione per una nuova edizione della Scuola online che ho tenuto quest\u2019anno&#8230; mentre invito anche voi a farvi promotori di nuove iniziative nei luoghi in cui vivete. Grazie ancora a tutti e buon lavoro da fare insieme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Osservatorio Internazionale Cardinale Van Thu\u00e2n Newsletter n.861 del 6 Febbraio 2018 Sabato scorso 3 febbraio si \u00e8 tenuto a Milano, presso il teatro Don Guanella, l\u2019Incontro nazionale delle Scuole di Dottrina sociale della Chiesa \u201cMater et Magistra\u201d dell\u2019Osservatorio. La giornata dal titolo \u201cConoscere la verit\u00e0, praticare la giustizia\u201d \u00e8 stata organizzata insieme al quotidiano online &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":39663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,11],"tags":[146],"class_list":["post-39662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-dottrina-sociale","tag-dottrina-sociale-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-07T23:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-08T07:34:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/dottrina_sociale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"323\" \/>\n\t<meta property=\"og:image:height\" content=\"156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde\",\"datePublished\":\"2018-02-07T23:00:09+00:00\",\"dateModified\":\"2018-02-08T07:34:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/\"},\"wordCount\":1344,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dottrina_sociale.jpg\",\"keywords\":[\"dottrina sociale\"],\"articleSection\":[\"Chiesa\",\"Dottrina sociale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/\",\"name\":\"Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dottrina_sociale.jpg\",\"datePublished\":\"2018-02-07T23:00:09+00:00\",\"dateModified\":\"2018-02-08T07:34:04+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dottrina_sociale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dottrina_sociale.jpg\",\"width\":323,\"height\":156},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/","og_locale":"it_IT","og_type":"article","og_title":"Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-02-07T23:00:09+00:00","article_modified_time":"2018-02-08T07:34:04+00:00","og_image":[{"width":323,"height":156,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/dottrina_sociale.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde","datePublished":"2018-02-07T23:00:09+00:00","dateModified":"2018-02-08T07:34:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/"},"wordCount":1344,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/dottrina_sociale.jpg","keywords":["dottrina sociale"],"articleSection":["Chiesa","Dottrina sociale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/","name":"Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/dottrina_sociale.jpg","datePublished":"2018-02-07T23:00:09+00:00","dateModified":"2018-02-08T07:34:04+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/dottrina_sociale.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/02\/dottrina_sociale.jpg","width":323,"height":156},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fare-segue-lessere-senza-formazione-il-popolo-cattolico-si-disperde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il fare segue l\u2019essere. Senza formazione il popolo cattolico si disperde"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=39662"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39662\/revisions"}],"predecessor-version":[{"id":39684,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39662\/revisions\/39684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/39663"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=39662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=39662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=39662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}