{"id":39569,"date":"2018-01-25T00:00:22","date_gmt":"2018-01-24T23:00:22","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=39569"},"modified":"2018-01-15T13:30:29","modified_gmt":"2018-01-15T12:30:29","slug":"le-false-liberta-del-68","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/","title":{"rendered":"Le false libert\u00e0 del &#8217;68"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.interris.it\/\" target=\"_blank\" rel=\"noopener\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-39570\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/68_contestazione.jpg\" alt=\"\" width=\"252\" height=\"171\" \/>In Terris<\/strong><\/a> venerd\u00ec 12 gennaio 2018<\/p>\n<p style=\"text-align: justify;\"><em>Marcello Veneziani demolisce l&#8217;anno della contestazione: &#8220;Produsse gravi danni, alcuni irreparabili&#8221;<\/em><\/p>\n<p style=\"text-align: center;\"><strong>\u00a0<\/strong><strong>Federico Cenci<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Il 1968 non \u00e8 una data come tante. \u00c8 come una lapide fissata sul percorso della storia. Che sancisce un prima e un dopo. Ma una lapide significa anche altro. \u00c8 una pietra tombale su un mondo, su una serie di valori e di costumi, di linguaggi e di sistemi, messi in discussione e in parte estirpati dal vortice rivoluzionario innescato da un irrefrenabile impulso di contestazione verso tutto ci\u00f2 che rappresentava autorit\u00e0, disciplina, identit\u00e0.<\/p>\n<p style=\"text-align: justify;\">A cinquant\u2019anni da quella data che ha inaugurato un&#8217;epoca, ne ha parlato in toni tutt\u2019altro che entusiastici Papa Francesco, davanti al Corpo diplomatico riunito in Vaticano per il tradizionale scambio d\u2019auguri d\u2019inizio anno. <em>In Terris<\/em> ha intervistato sul tema lo scrittore e filosofo Marcello Veneziani, che dieci anni fa diede alle stampe un libro dall\u2019eloquente titolo <em>\u201cRovesciare il \u201868\u201d <\/em>(ed. Mondadori).<\/p>\n<p style=\"text-align: justify;\"><strong>Su quale forma di libert\u00e0 si poggiava ideologicamente il \u201968?<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-28063\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/68.jpg\" alt=\"\" width=\"250\" height=\"192\" \/>\u201cLa libert\u00e0 assume nel &#8217;68 il significato globale di liberazione. Liberazione del soggetto, della sessualit\u00e0 repressa, dei popoli oppressi, degli istinti e degli impulsi incatenati. Liberazione dallo Stato e dalla Norma, dalla Famiglia e dai suoi obblighi e rituali, liberazione dai vincoli di ogni tipo, elogio dell&#8217;infedelt\u00e0 e del camaleontismo come mutazione permanente. \u00c8 la passione per l&#8217;illimitato, la libert\u00e0 come vietato vietare, come desiderio di creazione e di autocreazione permanente, senza alcun confine.<\/p>\n<p style=\"text-align: justify;\">Ma dietro la promessa della liberazione da tutto, dietro la marcusiana denuncia della tolleranza repressiva (proprio quel Marcuse che aveva scritto un saggio sulla liberazione), si celava nel &#8217;68 anche il suo rovescio arrogante, l&#8217;intolleranza permissiva; ovvero permissivismo estremo ma guai a chi non accetta il nuovo comandamento della liberazione e della contestazione. Quel fondo di intolleranza dette vita poi all&#8217;estremismo politico, alla violenza del radicalismo, alla giustificazione di regimi come quello di Mao e di Pol Pot, che nel nome della rivoluzione culturale e della liberazione da ogni passato, compirono stermini che nemmeno Hitler e Stalin insieme hanno compiuto\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c8 possibile elencare una rassegna dei danni provocati dalla contestazione?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cIl &#8217;68 fall\u00ec come rivoluzione politica ed economica, perch\u00e9 gli assetti di potere e il sistema capitalistico restarono saldamente in sella. Ma si accan\u00ec sul costume, sul sesso e sul linguaggio, sulla famiglia e sul rapporto tra le generazioni, sulla scuola e sull&#8217;universit\u00e0. E l\u00ec produsse i suoi pi\u00f9 gravi danni, alcuni irreparabili. La societ\u00e0 entrata nel \u201868 aveva molte pecche e molti arcaismi, molte ipocrisie e molte contraddizioni, ma quella che ne usc\u00ec, soprattutto in quegli ambiti citati, fu peggio.\u00a0L&#8217;errore d&#8217;origine fu la scissione tra diritti e doveri, tra libert\u00e0 e responsabilit\u00e0, tra risultati e meriti, e il predominio assoluto dei desideri su ogni altra considerazione\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Per una sorta di eterogenesi dei fini, il sistema capitalistico ne usc\u00ec persino rafforzato dal \u201968. Come \u00e8 stato possibile?<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-18002\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/68.jpg\" alt=\"\" width=\"250\" height=\"187\" \/>\u201cPerch\u00e9 il \u201868, al di l\u00e0 del massimalismo che ostentava e della passione per le rivoluzioni esotiche, nell&#8217;America latina, in Cina e in Cambogia, nacque e mor\u00ec come rivoluzione intraborghese e non antiborghese; una rivoluzione interna alla borghesia che us\u00f2 la contestazione per liberarsi dei suoi residui valori cristiani, morali e tradizionali. In questa chiave, il &#8217;68 sgombr\u00f2 la societ\u00e0 degli ultimi argini che si opponevano al trionfo assoluto e definitivo del capitalismo globale: gli argini rappresentati dai valori tradizionali, dalla famiglia, dal legame nazionale, dal senso religioso&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>Quali le radici ideologiche di questo odio verso certi valori?<\/strong><\/p>\n<p style=\"text-align: justify;\">&#8220;Il movimento sessantottino riteneva che la tradizione facesse parte di una \u2018santa alleanza\u2019 della reazione guidata dal capitale: invece la tradizione era l&#8217;ultimo baluardo per impedire che i cittadini, i credenti, i patrioti, i connazionali, i genitori, fossero ridotti solo a consumatori, pedine intercambiabili, atomi senza identit\u00e0. Di conseguenza il capitalismo trionf\u00f2 e spesso assunse come suoi agenti e funzionari i sessantottini di ieri. In fondo il racconto presente del &#8217;68 come una radicale modernizzazione significa proprio questo: una societ\u00e0 radicale di massa, concepita su valori radicali e interessi capitalistici globali\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Come e quanto ha inciso sulla societ\u00e0 la contestazione della figura del padre e dell\u2019istituto familiare?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cLa famiglia \u00e8 stato l&#8217;ambito in cui il &#8217;68 ha prodotto pi\u00f9 devastazioni. E il padre inteso come auctoritas, come pater familias, ma anche come santo padre, come patria \u2013 cio\u00e8 terra dei padri \u2013 come docente, veniva simbolicamente soppresso. Il \u201868 &#8211; scrissi nel mio libro \u2013 fu il movimento del parricidio gioioso che port\u00f2 a compimento quella tendenza parricida insita nella modernit\u00e0 e pi\u00f9 volte manifestatasi nel Novecento. Ma la societ\u00e0 senza padre del &#8217;68 produsse anche la societ\u00e0 senza figli, con una denatalit\u00e0 record e con l&#8217;idea che il sessantottino sia un adolescente permanente che non si proietta in nessun figlio perch\u00e9 \u00e8 lui eterno Peter Pan\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Sono dati Istat di questi giorni: una donna italiana in et\u00e0 fertile su due non ha figli. Il prezzo dell\u2019emancipazione femminile \u00e8 stata la rinuncia alla maternit\u00e0 e l\u2019atroce crisi demografica dell\u2019Italia odierna?<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-32069\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Terrorismo_rosso.jpg\" alt=\"\" width=\"250\" height=\"144\" \/>\u201cSi, in gran parte \u00e8 cos\u00ec. L&#8217;emancipazione femminile ha prodotto innegabili frutti e riconosciuto diritti fondamentali alle donne; ma con la stessa onest\u00e0 si riconosca che tutto questo \u00e8 avvenuto a scapito della maternit\u00e0 , della coesione familiare e dell&#8217;equilibrio fondato sulla diversit\u00e0 dei ruoli. Poi si pu\u00f2 pur dire che le conquiste valevano le perdite, ma si abbia la lealt\u00e0 di dire che quelle conquiste comportarono delle perdite ingenti e significative\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Dal \u201968 \u00e8 scaturita &#8211; ha detto lei &#8211; una \u201csociet\u00e0 radicale di massa\u201d. Questo trionfo dei valori libertari \u00e8 avvenuto nonostante il consenso elettorale del Partito Radicale sia stato sempre mediamente basso\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cDopo il &#8217;68 nessun movimento rivoluzionario and\u00f2 al potere in Occidente e tantomeno in Italia; in compenso si avvi\u00f2 quel percorso \u2013 divorzio, aborto, depenalizzazione di reati legati alla droga e altri concernenti la famiglia, unioni omosessuali, per poi proseguire con altri pi\u00f9 recenti. In sostanza ha vinto l&#8217;anima radicale del &#8217;68. E la stessa sinistra oggi non riesce pi\u00f9 a rappresentare le classi povere e oppresse, i proletari e le borgate, gli operai e le masse, ma concentra le sue battaglie sulle unioni civili, eutanasia, femminicidio ecc. La rivoluzione sociale si \u00e8 fatta rivoluzione sessuale\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Nel suo libro ricorda Jan Palach, sottolineando che mentre \u201cgli altri incendiarono il mondo pensando a se stessi, lui incendi\u00f2 se stesso pensando al mondo\u201d. Il \u201968 produsse anche qualcosa di buono?<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-23451\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/02\/partito_radicale.jpg\" alt=\"\" width=\"250\" height=\"169\" \/>\u201cA Est, la rivolta giovanile fu concepita nel segno di un binomio, patria e libert\u00e0, ovvero indipendenza nazionale, sovranit\u00e0 politica e libera espressione del dissenso. E questo produsse frutti. In fondo il gesto di Jan Palach come la denuncia di Solzenicyn e di Papa Wojtyla, produssero quel movimento popolare che poi coincise col crollo del comunismo. Non so se definirlo &#8217;68 ma quello fu un effetto largamente positivo\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Un sentimento di rifiuto verso questa sorta di bulimia di libert\u00e0 individuali sembra diffondersi. A dieci anni dall\u2019uscita del suo libro, rileva che si sia infoltita la schiera di quanti vorrebbero \u201crovesciare il \u201868\u201d?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cNon lo so. A volte sarei tentato di dir di no, c&#8217;\u00e8 assuefazione al processo in corso e alle tappe forzate subite, c&#8217;\u00e8 rassegnazione, convinzione che sia un flusso inarrestabile e potente. Ma a volte noto una consapevolezza della partita in gioco che non c&#8217;era dieci anni fa e pi\u00f9, una maggiore sensibilit\u00e0 su questi temi, un&#8217;insofferenza e una ribellione al <em>poltically correct<\/em>, che \u00e8 poi il lascito del &#8217;68, una scia di risultati politici in tutto l&#8217;Occidente ma anche nell\u2019Est Europa che lascia pensare a un rovesciamento del &#8217;68. Si tratta, naturalmente, di una rivoluzione culturale, alla quale per\u00f2 mancano i leader, gli esempi, i linguaggi, i mezzi, soprattutto i media per farlo. E laboratori in cui formare una generazione post-sessantottina, anti-sessantottina ma non per istinto e pulsione, ma con cognizione di causa e capacit\u00e0 di agire. Difficile quanto necessaria\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Terris venerd\u00ec 12 gennaio 2018 Marcello Veneziani demolisce l&#8217;anno della contestazione: &#8220;Produsse gravi danni, alcuni irreparabili&#8221; \u00a0Federico Cenci<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":39570,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98,96],"tags":[1496,386],"class_list":["post-39569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-il-68","category-storia-italiana","tag-il-68-2","tag-rivoluzione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le false libert\u00e0 del &#039;68 - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le false libert\u00e0 del &#039;68 - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-24T23:00:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/68_contestazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"272\" \/>\n\t<meta property=\"og:image:height\" content=\"185\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Le false libert\u00e0 del &#8217;68\",\"datePublished\":\"2018-01-24T23:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/\"},\"wordCount\":1292,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/68_contestazione.jpg\",\"keywords\":[\"il 68\",\"Rivoluzione\"],\"articleSection\":[\"Il 68\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/\",\"name\":\"Le false libert\u00e0 del '68 - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/68_contestazione.jpg\",\"datePublished\":\"2018-01-24T23:00:22+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/68_contestazione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/68_contestazione.jpg\",\"width\":272,\"height\":185},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/le-false-liberta-del-68\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le false libert\u00e0 del &#8217;68\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le false libert\u00e0 del '68 - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/","og_locale":"it_IT","og_type":"article","og_title":"Le false libert\u00e0 del '68 - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2018-01-24T23:00:22+00:00","og_image":[{"width":272,"height":185,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/68_contestazione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Le false libert\u00e0 del &#8217;68","datePublished":"2018-01-24T23:00:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/"},"wordCount":1292,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/68_contestazione.jpg","keywords":["il 68","Rivoluzione"],"articleSection":["Il 68","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/","name":"Le false libert\u00e0 del '68 - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/68_contestazione.jpg","datePublished":"2018-01-24T23:00:22+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/68_contestazione.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/68_contestazione.jpg","width":272,"height":185},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/le-false-liberta-del-68\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Le false libert\u00e0 del &#8217;68"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=39569"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39569\/revisions"}],"predecessor-version":[{"id":39571,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39569\/revisions\/39571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/39570"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=39569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=39569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=39569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}