{"id":39423,"date":"2017-12-28T00:00:31","date_gmt":"2017-12-27T23:00:31","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=39423"},"modified":"2017-12-21T12:54:54","modified_gmt":"2017-12-21T11:54:54","slug":"i-due-volti-dellambientalismo-intervista-a-antonio-gaspari","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/","title":{"rendered":"I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari"},"content":{"rendered":"<div id=\"attachment_39424\" style=\"width: 224px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-39424\" class=\"wp-image-39424\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/12\/Antonio_Gaspari.jpg\" alt=\"\" width=\"224\" height=\"200\" \/><p id=\"caption-attachment-39424\" class=\"wp-caption-text\">Antonio Gaspari<\/p><\/div>\n<p style=\"text-align: center;\">Dal blog<strong> <a href=\"https:\/\/mariomasi.wordpress.com\/\" target=\"_blank\" rel=\"noopener\">Uomo &amp; ambiente<\/a><\/strong> 10 Dicembre 2006<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong>A due anni dalla presentazione del primo capitolo, <em>Riccardo Cascioli<\/em> e <em>Antonio Gaspari<\/em> pubblicano \u201c<em>Le bugie degli ambientalisti 2<\/em>\u201d in cui riaffermano il proprio dissenso rispetto a gran parte degli assiomi formulati dal mondo ambientalista.<\/p>\n<p style=\"text-align: justify;\">Un libro fuori dal coro, che si inserisce nella controversia in atto fra quelli che potremmo chiamare \u201ccatastrofisti\u201d ed \u201ceco-ambientalisti\u201d che sta travalicando gli argini della difesa dell\u2019ambiente per assumere il vigore di una appassionato confronto tra due diversi sistemi di pensiero. La concezione biocentrica ed ecocentrica viene cos\u00ec ad infrangersi contro lo scoglio dell\u2019etica antropologica travolgendo tutti i temi di pubblico interesse.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Ne parliamo con <strong>Antonio Gaspari<\/strong>, direttore del Dipartimento Uomo e Ambiente del CESPAS e del Master in Scienze Ambientali dell\u2019Ateneo Pontificio Regina Apostolorum, \u00e8 tra i fondatori dell\u2019agenzia quindicinale di informazione ambientale \u201cGreenwatch News\u201d e cura l\u2019edizione in italiano dell\u2019agenzia quotidiana \u201cZenit\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Ultimamente al concetto di sviluppo sostenibile \u00e8 stato affiancato quello di impronta ecologica. Cosa esprimono questi termini?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Sviluppo sostenibile e impronta ecologica sono delle terminologie che vengono utilizzate per porre severi limiti allo sviluppo dei Paesi emergenti. \u201cSviluppo sostenibile\u201d \u00e8 una traduzione impropria del termine inglese \u201c<em>sustainable development<\/em>\u201d che intende condizionare i processi di sviluppo secondo variabili quali la crescita demografica, il prodotto interno lordo, la disponibilit\u00e0 di materie prime. Il pregiudizio nasce dall\u2019idea che lo sviluppo \u00e8 esclusivamente inquinante e per questo va fortemente condizionato.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32501 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Terra_ambientalismo.jpg\" alt=\"\" width=\"179\" height=\"200\" \/>Questa idea \u00e8 conseguente alla concezione neomalthusiana di uomo come mero consumatore, secondo cui la crescita demografica ed economica delle nazioni \u00e8 il peggiore dei mali. Si tratta di una deformazione ideologica del concetto di sviluppo, imposta dagli inizi degli anni ottanta.<\/p>\n<p style=\"text-align: justify;\">Nei decenni precedenti le stesse Nazioni Unite parlavano di \u201cd\u00e9veloppement durable\u201d cio\u00e8 sviluppo durevole, indicando nel superamento del sottosviluppo la via per vincere la fame, la povert\u00e0 e garantire il risanamento ambientale.<\/p>\n<p style=\"text-align: justify;\">La concezione di sviluppo durevole contrapposta a quella di sviluppo sostenibile \u00e8 stata fortemente indicata nel corso della Conferenza delle Nazioni Unite di Johannesburg svoltasi nel 2002. La totalit\u00e0 dei paesi in via di sviluppo e gran parte di quelli avanzati hanno indicato nel progresso tecnologico, scientifico, economico e morale la via per innalzare il livello di vita dell\u2019umanit\u00e0 nel pieno rispetto e sviluppo della natura.<\/p>\n<p style=\"text-align: justify;\">L\u2019impronta ecologia \u00e8 una barzelletta, inventata con l\u2019intenzione di spaventare le persone al fine di limitare lo sviluppo. Secondo i parametri indicati dai sostenitori dell\u2019impronta ecologica, ogni persona per non inquinare il pianeta dovrebbe abitare in una casa al massimo di 30 metri quadri, senza acqua corrente n\u00e9 elettricit\u00e0, dovrebbe diventare vegetariana e raccogliere il proprio cibo direttamente dalla terra, dovrebbero muoversi solo a piedi o al massimo in bicicletta.<\/p>\n<p style=\"text-align: justify;\"><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30514\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/02\/assoc_ambiente.jpg\" alt=\"\" width=\"250\" height=\"200\" \/>E\u2019 vero che la natura inquina pi\u00f9 dell\u2019uomo?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Ma certo!. Basta pensare ai vulcani in attivit\u00e0 che secondo gli ultimi dai sarebbero 1500 in tutto il pianeta. In una sola eruzione il Monte Merapi in Indonesia ha distrutto una citt\u00e0 e emesso una colonna di fumo alta pi\u00f9 di tremila metri. In Ecuador il Tungurahua ha lanciato tonnellate di cenere fino a 12.000 metri. Altro che emissioni delle auto o Pm10. Ci si preoccupa delle allergie, dimenticandosi che per pi\u00f9 della met\u00e0 dipendono dai pollini delle piante. Pensiamo ai rifiuti organici. Ogni animale dal pi\u00f9 piccolo insetto fino all\u2019elefante ed alla balena, mangia in proporzione al peso molto di pi\u00f9 degli uomini e anche in rifiuti non scherza.<\/p>\n<p style=\"text-align: justify;\">All\u2019inizio del 900 a New York c\u2019erano 1 milione e 200 mila cavalli, considerando che ogni giorno un cavallo produce almeno nove chili tra escrementi e urina, si capisce bene perch\u00e9 i rifiuti erano maggiori di quelli odierni. Si ha paura delle radiazioni, dimenticandosi che noi viviamo di \u201cradiazioni\u201d grazie ad una piccola stella, il sole, che \u00e8 una esplosione termonucleare continua. Il suo raggio all\u2019equatore \u00e8 pari a pi\u00f9 di 100 volte quello della Terra e la sua massa \u00e8 743 volte quella totale di tutti i pianeti che gli girano attorno. Tutto questo mostra che la concezione di \u201cinquinamento\u201d normalmente utilizzata \u00e8 inadeguata e ideologicamente finalizzata solo a criminalizzare le attivit\u00e0 e il lavoro umano.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Nel libro \u00e8 descritta una iniziativa europea denominata \u201cDiplomazia Verde\u201d. Pu\u00f2 spiegarci in cosa consiste e qual \u00e8 il suo scopo?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Le istituzioni internazionali cos\u00ec come molti governi nazionali sono pesantemente condizionati da una \u201clobby verde\u201d la cui ideologia \u00e8 pesantemente contraria alla crescita demografica ed allo sviluppo scientifico ed economico. In questo momento l\u2019Unione europea, cos\u00ec come nel passato l\u2019amministrazione Clinton, utilizza la diplomazia verde per imporre misure commerciali \u201cprotezioniste\u201d e impedire ai paesi emergenti di arrivare con le proprie merci sui mercati pi\u00f9 ricchi.<\/p>\n<p style=\"text-align: justify;\">Tale diplomazia verde sta penalizzando pesantemente anche l\u2019Italia, basta dire che il ministro degli esteri Massimo D\u2019Alema dice si al \u201cnucleare civile\u201d del dittatore iraniano Mahmud Ahmadinejad, ed \u00e8 per\u00f2 contrario alla costruzione di impianti nucleari in Italia.<\/p>\n<p style=\"text-align: justify;\"><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-35355\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/catastrofe_ambiente.jpg\" alt=\"\" width=\"250\" height=\"140\" \/>Alcuni paesi emergenti sostengono che talvolta le argomentazioni ecologiste vengono utilizzate strumentalmente per limitare il loro sviluppo. Quanto c\u2019\u00e8 di vero in questa tesi?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">I Paesi emergenti parlano apertamente di \u201cecoimperialismo\u201d, cio\u00e8 l\u2019utilizzazione dell\u2019ideologia verde per limitare il loro sviluppo, mantenere posizioni di privilegio nel mercato e imporre forme di ingiustizia economica e produttiva.<\/p>\n<p style=\"text-align: justify;\">Tanti i casi eclatanti, tra cui il divieto di utilizzare il DDT per combattere la malaria che ogni anno infetta trecento milioni di persone e ne uccide un milione e centomila, e la richiesta sempre pi\u00f9 vasta di contadini che intendono utilizzare sementi OGM.<\/p>\n<p style=\"text-align: justify;\">La denuncia dell\u2019ecoimperialismo \u00e8 sostenuta tra gli altri da movimenti per i diritti civili americani e da ricercatori e contadini africani.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Perch\u00e9 in Italia i rifiuti sono un problema mentre in Europa costituiscono una risorsa?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 a forza di diffondere paure irrazionali le comunit\u00e0 locali sono spaventate e confuse. La cattiva informazione e l\u2019opposizione preconcetta contro i termovalorizzatori sta favorendo solo i gruppi che non vogliono risolvere il problema e pensano di fare grandi affari speculando sulle discariche esistenti.<\/p>\n<p style=\"text-align: justify;\">Di questo passo, noi italiani pagheremo la raccolta rifiuti sempre di pi\u00f9, senza mai averne un bench\u00e9 minimo beneficio. I tedeschi ridono di noi perch\u00e9 siamo l\u2019unico paese che paga il biglietto del treno ai rifiuti, che poi vanno a produrre energia per la Germania. Tutti in Europa utilizzano e costruiscono termovalorizzatori. In Austria il termovalorizzatore di Spittelau fornisce acqua calda a 200.000 famiglie ed \u00e8 inserito nei tour turistici della citt\u00e0. Mentre nella nostra bella Italia, continuiamo a raccogliere rifiuti e portarli in discarica.<\/p>\n<p style=\"text-align: justify;\"><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-26630\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/10\/nuova-ecologia.jpeg\" alt=\"\" width=\"161\" height=\"200\" \/>Mentre la Chiesa individua l\u2019uomo come custode responsabile del creato un certo ambientalismo lo considera come un ospite indesiderato. Al concetto di capitale umano viene contrapposta la visione dell\u2019uomo come cancro del pianeta. Cosa determina una differenziazione ideologica e ontologica cos\u00ec marcata?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">La concezione biocentrica o ecocentrica delle maggiori associazioni ambientaliste \u00e8 simile alle concezioni pagane precristiane. Per placare le ire di Gaia chiedono sacrifici, limitando le nascite e impedendo lo sviluppo.\u00a0 Dal punto di vista etico poi \u00e8 drammatico constatare che la \u201cnuova etica animalista\u201d che filosofi come Peter Singer propongono prende origine e propaganda tesi eugenetiche.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Cosa serve per sconfiggere il catastrofismo di certe major ambientaliste?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Smettere di credere alle loro bugie e provare a vedere che esiste un mondo reale fatto di persone che lavorano, ricercano e propongono soluzioni anche per i problemi ambientali. Dopo tanti anni di ricerche posso assicuravi che la realt\u00e0 \u00e8 molto pi\u00f9 avvincente e affascinante degli scenari catastrofici disegnati dai profeti di sventura.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal blog Uomo &amp; ambiente 10 Dicembre 2006 \u00a0A due anni dalla presentazione del primo capitolo, Riccardo Cascioli e Antonio Gaspari pubblicano \u201cLe bugie degli ambientalisti 2\u201d in cui riaffermano il proprio dissenso rispetto a gran parte degli assiomi formulati dal mondo ambientalista. Un libro fuori dal coro, che si inserisce nella controversia in atto &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":39424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1306,1375,1126],"class_list":["post-39423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambientalismo","tag-eco-imperialismo","tag-ecobufale","tag-ecocatastrofismo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-27T23:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/12\/Antonio_Gaspari.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"237\" \/>\n\t<meta property=\"og:image:height\" content=\"212\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari\",\"datePublished\":\"2017-12-27T23:00:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/\"},\"wordCount\":1239,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Antonio_Gaspari.jpg\",\"keywords\":[\"eco-imperialismo\",\"ecobufale\",\"ecocatastrofismo\"],\"articleSection\":[\"Ambientalismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/\",\"name\":\"I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Antonio_Gaspari.jpg\",\"datePublished\":\"2017-12-27T23:00:31+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Antonio_Gaspari.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Antonio_Gaspari.jpg\",\"width\":237,\"height\":212},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/","og_locale":"it_IT","og_type":"article","og_title":"I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-12-27T23:00:31+00:00","og_image":[{"width":237,"height":212,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/12\/Antonio_Gaspari.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari","datePublished":"2017-12-27T23:00:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/"},"wordCount":1239,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/12\/Antonio_Gaspari.jpg","keywords":["eco-imperialismo","ecobufale","ecocatastrofismo"],"articleSection":["Ambientalismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/","name":"I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/12\/Antonio_Gaspari.jpg","datePublished":"2017-12-27T23:00:31+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/12\/Antonio_Gaspari.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/12\/Antonio_Gaspari.jpg","width":237,"height":212},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-due-volti-dellambientalismo-intervista-a-antonio-gaspari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I due volti dell\u2019ambientalismo \u2013 intervista a Antonio Gaspari"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=39423"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39423\/revisions"}],"predecessor-version":[{"id":39425,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/39423\/revisions\/39425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/39424"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=39423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=39423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=39423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}