{"id":38946,"date":"2017-11-30T00:00:10","date_gmt":"2017-11-29T23:00:10","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=38946"},"modified":"2017-11-22T10:28:42","modified_gmt":"2017-11-22T09:28:42","slug":"il-vestito-megafono-del-corpo-e-dellanima","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/","title":{"rendered":"Il vestito, megafono del corpo e dell\u2019anima"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-38947\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/11\/abbigliamento.jpg\" alt=\"\" width=\"250\" height=\"170\" \/>Dal sito <a href=\"http:\/\/alleanzacattolica.org\/\" target=\"_blank\" rel=\"noopener\"><strong>Alleanza Cattolica <\/strong><\/a>maggio 2017<\/p>\n<p style=\"text-align: center;\">di <strong>Stefano Chiappalone<\/strong><\/p>\n<p style=\"text-align: justify;\">La moda esiste da quando esiste l\u2019uomo. Da secoli, da millenni, fino ai nostri giorni, uomini e donne comunicano mediante l\u2019abbigliamento: alla funzione materiale del vestito (coprirsi dal caldo e dal freddo) e a quella morale (custodire il pudore), si affianca da sempre quella terza finalit\u00e0 che il ven. Papa Pio XII (1939-1958) indicava come \u00ab<em style=\"font-weight: inherit;\">decoro<\/em>\u00bb nel senso che \u00ab<em style=\"font-weight: inherit;\">risponde all\u2019esigenza innata, dalla donna maggiormente sentita, di dar risalto alla bellezza e dignit\u00e0 della persona, coi medesimi mezzi che provvedono a soddisfare le altre due<\/em>\u00bb.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Questa dimensione estetica del vestito \u00e8 multiforme, come spiegava il pontefice: \u00ab<em style=\"font-weight: inherit;\">ad esso la giovent\u00f9 chiede quel risalto di splendore che canta il lieto tema della primavera della vita ed agevola, in armonia coi dettami della pudicizia, le premesse psicologiche necessarie alla formazione di nuove famiglie; mentre l\u2019et\u00e0 matura dall\u2019appropriato\u00a0vestito intende ottenere un\u2019aura di dignit\u00e0, di seriet\u00e0 e di serena letizia<\/em>\u00bb (Discorso all\u2019Unione Latina Alta Moda, 8 novembre 1957).<\/p>\n<p style=\"text-align: justify;\">In altre parole, il vestito \u00e8 il primo messaggio estetico che inconsapevolmente comunica chi siamo, a noi stessi e agli altri: ogni mattina aprendo l\u2019armadio, abbinando capi e colori, scegliamo cosa dire di noi; non tutto, certamente, ma molto e per tutta la giornata \u2013 a differenza della buona musica o di un\u2019opera d\u2019arte o di una bella tavola, che occupano la nostra attenzione solo in dati momenti.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-18290\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/medioevo.jpg\" alt=\"\" width=\"291\" height=\"173\" \/>Nel Medioevo i diversi capi di vestiario ci avrebbero rivelato anche mestieri e professioni; oggi accade pi\u00f9 di rado, ma sempre l\u2019abbigliamento rivela una personalit\u00e0, talvolta caratterizzata da ordine, armonia, eleganza, oppure seduzione, talaltra da trasandatezza o ribellione. E pur vivendo in un\u2019epoca di \u201ccrisi\u201d della divisa, possiamo dire, per\u00f2, che ciascuno finisce per assumerne una propria: le persone che conosciamo hanno tutte un modo di vestire pi\u00f9 o meno riconoscibile \u2013 al di l\u00e0 di casi eclatanti, come l\u2019imprenditore Steve Jobs (1955-2011), che si dice avesse centinaia di maglioni dolce vita neri (anche d\u2019estate?), con funzione allo stesso tempo pratica (limitare il <em>decision fatigue <\/em>mattutino) e soprattutto identificativa.<\/p>\n<p style=\"text-align: justify;\">Difficilmente vedremo l\u2019amico che veste \u201cclassico\u201d, con un paio di jeans strappati; mentre il ragazzino dai capelli \u201ca cresta\u201d e i pantaloni in stile \u201ccasa allagata\u201d non indosserebbe neanche sotto tortura una giacca o una cravatta \u2013 peccato, per\u00f2: l\u2019abito non solo comunica, ma ci plasma, e tutti possono migliorare\u2026 Il potenziale comunicativo dell\u2019abito \u00e8 evidenziato in negativo dall\u2019uniforme dei prigionieri, la cui condizione \u00e8 sottolineata dal non poter scegliere come vestirsi.<\/p>\n<p style=\"text-align: justify;\">Al contempo non tutte le uniformi sono\u2026uniformi! Se quella dei detenuti \u00e8 una \u201cmoda piatta\u201d (forzatamente) e quella attuale \u00e8 una \u201cmoda liquida\u201d \u2013 il cui minimo comun denominatore consiste, cio\u00e8, nell\u2019assenza di elementi comuni \u2013 almeno nell\u2019ambito ecclesiastico e militare resta in gran parte valida quella \u201cmoda organica\u201d, tipica di una gerarchia viva, visibile nei dipinti medievali che identifica ogni categoria, o\u00a0<em style=\"font-weight: inherit;\">status<\/em>, dall\u2019abbigliamento, non per standardizzare, bens\u00ec per esaltarne e ricordarne la funzione.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35191\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/sacerdoti.jpg\" alt=\"\" width=\"135\" height=\"200\" \/>L\u2019abito del militare parla, dicendoci se \u00e8 un soldato o un carabiniere o un paracadutista e indicandocene il grado. Cos\u00ec l\u2019abito del sacerdote, del vescovo, del cardinale: a tale proposito ricordo un pretino molto anziano, dall\u2019abito clericale semplice e dimesso e una gran croce pendente al collo a testimonianza di una vita consumata e di una fede testimoniata a caro prezzo tra le \u201ccarezze\u201d del comunismo, come mi descrisse in un paio di colloqui che ebbi con lui. E provai una certa commozione \u2013 e sano orgoglio per averlo conosciuto \u2013 vedendolo in tv qualche tempo dopo, cambiato d\u2019abito e rivestito di rosso: era il cardinal Ernest Simoni e quella porpora che indossava parlava ancora di lui, del sangue versato quale martire vivente del regime comunista albanese.<\/p>\n<p style=\"text-align: justify;\">L\u2019abito parla, grida chi siamo, anche a chi non ci conosce. Anzi, chi non ci ha mai visto n\u00e9 sentito parlare, intuisce qualcosa della nostra personalit\u00e0 proprio dal nostro modo di vestire. L\u2019abito ci esprime e ci plasma, nella misura in cui definisce il nostro ordine (o disordine) interiore, i nostri sentimenti e atteggiamenti. Nel suo celebre saggio <em>Le porte regali <\/em>(trad. it., Adelphi, Milano 2009)<em style=\"font-weight: inherit;\">,<\/em> lo studioso e sacerdote russo Pavel Aleksandrovi\u010d Florenskij giunge ad affermare che \u00ab\u201c<em style=\"font-weight: inherit;\">La carne e il sangue non ereditano il Regno di Dio\u201d, ma il vestito eredita<\/em>\u00bb (p. 131), fino a definirlo \u00ab<em style=\"font-weight: inherit;\">un megafono che proclama e amplifica la parola della testimonianza, pronunciata intorno alla propria idea dal corpo<\/em>\u00bb (p. 132).<\/p>\n<p style=\"text-align: justify;\">E, per concludere con la propria idea del corpo, sar\u00e0 un caso che proprio ai nostri tempi si vada diffondendo quella moda unisex che vorrebbe eliminare dall\u2019abito la primordiale e complementare distinzione tra linee maschili e femminili, per adattarsi ad un corpo indistinto? Se \u00ab<em style=\"font-weight: inherit;\">la bocca parla dalla pienezza del cuore<\/em>\u00bb (Mt 12, 34), le \u201cparole\u201d che fuoriescono dal nostro armadio esprimono in qualche modo, nel bene e nel male, la condizione spirituale dei singoli e delle societ\u00e0.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal sito Alleanza Cattolica maggio 2017 di Stefano Chiappalone La moda esiste da quando esiste l\u2019uomo. Da secoli, da millenni, fino ai nostri giorni, uomini e donne comunicano mediante l\u2019abbigliamento: alla funzione materiale del vestito (coprirsi dal caldo e dal freddo) e a quella morale (custodire il pudore), si affianca da sempre quella terza finalit\u00e0 &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":38947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,25],"tags":[2646,1154],"class_list":["post-38946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-costume","category-sguardo-sul-nostro-tempo","tag-abbigliamento","tag-moda","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il vestito, megafono del corpo e dell\u2019anima - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il vestito, megafono del corpo e dell\u2019anima - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-29T23:00:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/11\/abbigliamento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"272\" \/>\n\t<meta property=\"og:image:height\" content=\"185\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il vestito, megafono del corpo e dell\u2019anima\",\"datePublished\":\"2017-11-29T23:00:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/\"},\"wordCount\":826,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/abbigliamento.jpg\",\"keywords\":[\"abbigliamento\",\"moda\"],\"articleSection\":[\"Costume\",\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/\",\"name\":\"Il vestito, megafono del corpo e dell\u2019anima - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/abbigliamento.jpg\",\"datePublished\":\"2017-11-29T23:00:10+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/abbigliamento.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/abbigliamento.jpg\",\"width\":272,\"height\":185},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-vestito-megafono-del-corpo-e-dellanima\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il vestito, megafono del corpo e dell\u2019anima\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il vestito, megafono del corpo e dell\u2019anima - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/","og_locale":"it_IT","og_type":"article","og_title":"Il vestito, megafono del corpo e dell\u2019anima - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-11-29T23:00:10+00:00","og_image":[{"width":272,"height":185,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/11\/abbigliamento.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il vestito, megafono del corpo e dell\u2019anima","datePublished":"2017-11-29T23:00:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/"},"wordCount":826,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/11\/abbigliamento.jpg","keywords":["abbigliamento","moda"],"articleSection":["Costume","Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/","name":"Il vestito, megafono del corpo e dell\u2019anima - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/11\/abbigliamento.jpg","datePublished":"2017-11-29T23:00:10+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/11\/abbigliamento.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/11\/abbigliamento.jpg","width":272,"height":185},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-vestito-megafono-del-corpo-e-dellanima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il vestito, megafono del corpo e dell\u2019anima"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/38946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=38946"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/38946\/revisions"}],"predecessor-version":[{"id":38948,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/38946\/revisions\/38948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/38947"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=38946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=38946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=38946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}