{"id":3868,"date":"2010-06-17T00:00:00","date_gmt":"2010-06-16T22:00:00","guid":{"rendered":""},"modified":"2015-03-13T15:18:41","modified_gmt":"2015-03-13T14:18:41","slug":"apologia-della-crociata","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/","title":{"rendered":"Apologia della crociata"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/06\/crociate.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-21128\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/06\/crociate.jpg\" alt=\"crociate\" width=\"146\" height=\"200\" \/><\/a>Corrispondenza Romana<\/strong> marted\u00ec 8 giugno 2010<\/div>\n<p style=\"text-align: justify;\"><em>(<\/em><strong>Roberto de Mattei<\/strong> <em>su Il Foglio dell&#8217; 8 giugno 2010) &#8211; L\u2019irenismo ecumenico \u00e8 una distorsione della dottrina della chiesa e della sua storia. Il vero spirito del cristianesimo \u00e8 combattere per la verit\u00e0 e per difendere le radici che affondano nei secoli luminosi del medioevo<\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>&#8220;L\u2019addio della chiesa allo spirito di crociata\u201d<\/strong> \u00e8 un refrain che ricorre da almeno quarant\u2019anni e che condensa la concezione del mondo di un certo cristianesimo, che ha fatto del dialogo ecumenista il suo vangelo. Questa visione si basa su di una distorsione storica e su di un\u2019altrettanto grave deformazione della dottrina della chiesa.<\/em><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Nel caso dell\u2019articolo di Giancarlo Zizola su <em>Repubblica<\/em> del 7 giugno, si aggiunge a ci\u00f2 un impervio tentativo di attribuire allo stesso Papa regnante questo slittamento storico e dottrinale. Benedetto XVI, come egli disse nella sua prima udienza del 27 aprile 2005, ha assunto questo nome, non solo in onore di Benedetto XV, ma anche e soprattutto per evocare la straordinaria figura del grande \u201cPatriarca del monachesimo occidentale\u201d, san Benedetto da Norcia, che \u201ccostituisce un fondamentale punto di riferimento per l\u2019unit\u00e0 dell\u2019Europa e un forte richiamo alle irrinunciabili radici cristiane della sua cultura e della sua civilt\u00e0\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma quali sono quelle radici cristiane<\/strong> che, secondo Benedetto XVI, come per il suo predecessore Giovanni Paolo II, non solo i cattolici, ma anche i laici, hanno il diritto e il dovere di difendere? Queste radici, o se si preferisce, i frutti di queste radici, sono sotto i nostri occhi: sono cattedrali, monumenti, palazzi, piazze, strade, ma anche musica, letteratura, poesia, scienza, arte. Questa visibile mappa della memoria \u00e8 impressa nel codice genetico della nostra civilt\u00e0. Ebbene le crociate fanno parte, come le cattedrali, del paesaggio spirituale europeo e ne esprimono la stessa concezione del mondo.<\/p>\n<p style=\"text-align: justify;\"><strong>Lo storico dell\u2019arte Erwin Panofsky<\/strong> ha studiato il rapporto tra le vetrate gotiche e la filosofia scolastica, sottolineando come la luminosit\u00e0 delle cattedrali medievali corrisponda alla trasparenza di pensiero di opere come la \u201cSomma Teologica\u201d di san Tommaso d\u2019Aquino (Erwin Panofsky, \u201cArchitettura gotica e filosofia scolastica\u201d). Dall\u2019epopea delle crociate traspare \u2013 potremmo aggiungere \u2013 la stessa luminosit\u00e0, la stessa diafana bellezza, lo stesso slancio verso l\u2019alto, la stessa forza creatrice, delle opere di san Tommaso d\u2019Aquino e di Dante. Anche le crociate fanno parte di quel patrimonio di valori che, come scriveva Giovanni Paolo II, sono derivati dal Vangelo e si sono sviluppati in coerenza con esso (\u201cMemoria e identit\u00e0\u201d).<\/p>\n<p style=\"text-align: justify;\"><strong>\u201cI capolavori artistici nati in Europa<\/strong> <strong>nei secoli passati<\/strong> sono incomprensibili se non si tiene conto dell\u2019anima religiosa che li ha ispirati (\u2026)\u201d \u2013 ha affermato ancora Benedetto XVI (udienza generale del 18 novembre 2009). Lo stesso potrebbe dirsi delle crociate, che hanno inciso nei campi di battaglia della Palestina quella stessa scala di valori che gli architetti infondevano in quegli anni nella pietra delle cattedrali. N\u00e9 le crociate, n\u00e9 le cattedrali possono essere comprese da chi ignora il modo di pensare, e soprattutto, la fede vissuta, che animava i loro artefici.<\/p>\n<p style=\"text-align: justify;\">Nella cattedrale il popolo cristiano si raccoglieva attorno a un sacerdote che, celebrando la Messa su di un altare rivolto a oriente, rinnovava in maniera incruenta il mistero stesso del cristianesimo: l\u2019Incarnazione, Passione e morte di Ges\u00f9 Cristo. Nelle crociate, questo stesso popolo prendeva le armi per liberare la Citt\u00e0 Sacra di Gerusalemme, caduta nelle mani dei maomettani. La tomba vuota del Santo Sepolcro era, con la Sindone, la testimonianza viva della Resurrezione e la reliquia pi\u00f9 preziosa della cristianit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>La prima crociata fu predicata come meditazione<\/strong> all\u2019appello di Cristo che dice: \u201cChi vuole venire dietro di me rinunci a se stesso, prenda la sua croce e mi segua\u201d (Mt. 16, 21-27). Quella stessa Croce, attorno a cui si riuniva il popolo delle cattedrali, era impressa sulla veste dei crociati ed esprimeva l\u2019atto con cui il cristiano si diceva disposto ad offrire la propria vita, per il bene soprannaturale del prossimo, impugnando le armi. Lo spirito delle crociate era, e rimane, lo spirito stesso del cristianesimo: l\u2019amore al mistero incomprensibile della Croce.<\/p>\n<p style=\"text-align: justify;\"><strong>Il professor Jonathan Riley-Smith,<\/strong> caposcuola del rinnovamento degli studi sulle crociate, riferendosi a coloro che avevano risposto all\u2019appello della prima crociata, afferma che essi erano \u201cinfiammati dall\u2019ardore della carit\u00e0\u201d, e alla carit\u00e0, all\u2019amor di Dio, fa risalire la motivazione profonda di questa impresa. Offrire la propria vita \u00e8 infatti la pi\u00f9 grande forma di amore e il pi\u00f9 perfetto atto di carit\u00e0, poich\u00e9 ci fa perfetti imitatori di Ges\u00f9 secondo le parole del Vangelo, secondo cui \u201cnessuno ha pi\u00f9 grande amore di colui che d\u00e0 la sua vita per Lui e per i suoi fratelli\u201d (Gv. 3, 16; 15, 13).<\/p>\n<p style=\"text-align: justify;\">Solo l\u2019amore, riassunto dal sacrificio di Cristo sulla Croce, \u00e8 in grado di sconfiggere la morte, che \u00e8 la suprema sofferenza fisica, e il peccato, che \u00e8 il supremo male morale. Tale spirito e stato d\u2019animo, abbondantemente documentato dalle fonti, non sorge come un fiume limaccioso dall\u2019inconscio collettivo dell\u2019occidente, ma dall\u2019atto libero di singoli uomini che nei secoli luminosi del medioevo rispondono ad un appello che si rivolge alla loro coscienza.<\/p>\n<p style=\"text-align: justify;\"><strong>La risposta a questo appello <\/strong>pu\u00f2 essere considerata una \u201ccategoria dello spirito\u201d che non tramonta. L\u2019idea di crociata infatti non \u00e8 solo un evento storico circoscritto al medioevo, ma \u00e8 una costante dell\u2019animo cristiano che nella storia conosce momenti di eclissi, ma che sotto diverse forme \u00e8 destinata a riaffiorare. Espungere l\u2019idea di crociata dalla propria \u201cpiattaforma programmatica\u201d significa espungere l\u2019idea stessa del combattimento cristiano.<\/p>\n<p style=\"text-align: justify;\">L\u2019insegnamento che la vita spirituale \u00e8 lotta \u00e8 particolarmente svolto nelle lettere di san Paolo dove si trovano in molti luoghi metafore e immagini tratte dalla vita del guerriero; l\u2019Apostolo spiega come la vita del cristiano sia un bonum certamen che va combattuto \u201cda buon soldato di Ges\u00f9 Cristo\u201d (II Tim. 2, 3). \u201cSpogliamoci \u2013 egli dice \u2013 dalle opere delle tenebre e indossiamo l\u2019armatura della luce\u201d (Rom. 13, 12); \u201cRivestitevi dell\u2019armatura di Dio per potere resistere agli assalti del diavolo (\u2026). State dunque cinti della verit\u00e0, rivestiti della lorica della giustizia, calzati della saldezza del Vangelo della pace, impugnando lo scudo della fede, col quale potrete estinguere i dardi infuocati del Maligno, prendere l\u2019elmo della salvezza e il gladio dello spirito, che \u00e8 la parola di Dio\u201d (Ef. 6, 11, 14-17).<\/p>\n<p style=\"text-align: justify;\">Lo spirito di crociata e quello del martirio hanno una comune origine in questa dimensione profonda del combattimento spirituale. Il martirio, come ogni sofferenza, presuppone il combattimento. La vita stessa di Ges\u00f9 Cristo pu\u00f2 essere considerata come un costante combattimento contro l\u2019insieme delle forze ostili al Regno di Dio: il peccato, il mondo e il demonio.<\/p>\n<p style=\"text-align: justify;\">Che la vita del cristiano sia una lotta \u00e8 uno dei concetti che pi\u00f9 spesso risuona nel Nuovo Testamento dove si legge: \u201cNon sar\u00e0 coronato se non colui che avr\u00e0 legittimamente combattuto\u201d (II Tim. 2, 5). Il Vangelo del resto, nel suo significato originario, \u00e8 annuncio di vittoria militare, in questo caso la vittoria di Cristo sul male e sulle potenze delle tenebre.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 la chiesa non<\/strong> <strong>pu\u00f2 abbandonare lo spirito di crociata? <\/strong>Molto semplicemente perch\u00e9 non pu\u00f2 rinnegare la propria storia e la propria dottrina. La storia delle crociate non \u00e8 una appendice insignificante della storia della chiesa, ma si intreccia strettamente con la storia del papato. Le crociate non sono legate a un singolo Papa, ma ad una storia ininterrotta di pontefici, per lo pi\u00f9 santi, dal Beato Urbano II, che promulg\u00f2 la prima crociata, a san Pio V e al Beato Innocenzo XI, che promossero \u201cleghe sante\u201d contro i Turchi a Lepanto, Budapest e Vienna, tra il XVI e il XVII secolo. Non \u00e8 ignoto agli storici che, ancora nel XX secolo, Pio XII studi\u00f2 la possibilit\u00e0 di bandire una \u201ccrociata\u201d anticomunista dopo la rivolta di Ungheria nel 1956.<\/p>\n<p style=\"text-align: justify;\"><strong>A quella dei Papi, si aggiunge la testimonianza dei santi,<\/strong> a cominciare da Luigi IX, il re crociato per eccellenza, che con Giovanna d\u2019Arco, anch\u2019essa a suo modo \u201ccrociata\u201d, \u00e8 patrono della Francia, la \u201cfiglia primogenita della chiesa\u201d. Contrapporre a queste figure il nostro san Francesco denota, se non malafede, una notevole misconoscenza storica. La pi\u00f9 attendibile fonte che abbiamo del viaggio di Francesco \u00e8 la testimonianza del suo compagno, frate Illuminato, che ci racconta come il santo difese l\u2019opera dei crociati e propose al Sultano la conversione. E come dimenticare le legioni di francescani che si unirono, nei secoli ai crociati, a cominciare da san Giovanni da Capestrano (1386-1456), predicatore della grande crociata del XV secolo, culminata con la liberazione di Belgrado?<\/p>\n<p style=\"text-align: justify;\"><strong>Al nome di san Francesco dovremmo affiancare quello di santa Caterina da Siena,<\/strong> patrona d\u2019Italia e Dottore della chiesa di cui in un recente saggio Massimo Viglione ha mostrato l\u2019animo profondamente \u201ccrociato\u201d (\u201cL\u2019idea di crociata in Santa Caterina da Siena\u201d). A Lei potremmo aggiungere un altro dottore di sesso femminile, questa volta contemporaneo, santa Teresina del Bambin Ges\u00f9, che in una pagina toccante, rivolgendosi a Ges\u00f9, afferma di voler \u201cpercorrere la terra, predicare il tuo nome, e piantare sul suolo infedele la tua Croce gloriosa\u201d, riunendo in un\u2019unica vocazione quelle dell\u2019apostolo, del crociato, del martire.<\/p>\n<p style=\"text-align: justify;\">\u201cSento \u2013 ella scrive \u2013 la vocazione di Guerriero, di Sacerdote, di Apostolo, di Dottore, di Martire; insomma, sento il bisogno, il desiderio di compiere per te, Ges\u00f9, tutte le opere pi\u00f9 eroiche. Sento nella mia anima il coraggio di un Crociato, di uno Zuavo Pontificio: vorrei morire su un campo di battaglia per la difesa della Chiesa\u2026\u201d. E il 4 agosto 1897, sul letto di morte, rivolgendosi alla Superiora, mormora: \u201cOh, no, non avrei avuto paura di andare in guerra. Per esempio, ai tempi delle crociate, con quale felicit\u00e0 sarei partita per combattere gli eretici\u201d (\u201cStoria di un\u2019anima\u201d, in \u201cOpere complete\u201d).<\/p>\n<p style=\"text-align: justify;\"><strong>La chiesa non ha mai professato il pacifismo. <\/strong>Il combattimento cristiano, che \u00e8 prima di tutto un atteggiamento spirituale, ma che comprende la possibilit\u00e0 della legittima difesa, della guerra giusta e perfino della \u201cguerra santa\u201d, appartiene alla pi\u00f9 pura tradizione cattolica. Chi professa l\u2019ecumenismo e il pacifismo a oltranza dimentica che esistono mali pi\u00f9 profondi di quelli fisici e materiali, e confonde le conseguenze rovinose della guerra sul piano fisico, con le sue cause, che sono morali e risalgono alla violazione dell\u2019ordine, in una parola a quel peccato che solo pu\u00f2 essere sconfitto dalla Croce. Il mondo moderno, che \u00e8 immerso nell\u2019edonismo e ha perso la fede, giudica come mali, e come mali assoluti, solo quelli fisici, dimenticando che il male e il dolore accompagna inevitabilmente la vita dell\u2019uomo, spesso elevandola.<\/p>\n<p style=\"text-align: justify;\">Lo spirito delle crociate e di Lepanto ci trasmette un messaggio di fortezza cristiana che \u00e8 disposizione d\u2019animo a sacrificare i beni terreni, di fronte a beni pi\u00f9 alti, quali la giustizia, la verit\u00e0, l\u2019avvenire della nostra civilt\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Oggi il nemico che minaccia la chiesa e l\u2019occidente<\/strong> \u00e8 l\u2019attitudine mentale di chi ritiene che sia finito il tempo di Lepanto e delle crociate e allo spirito del combattimento cristiano contrappone una visione del mondo secondo la quale nulla esiste di assoluto e di vero, ma tutto \u00e8 relativo ai tempi, ai luoghi e alle circostanze. E\u2019 questo il relativismo denunciato da Giovanni Paolo II quando nelle sue encicliche \u201cSplendor Veritatis\u201d ed \u201cEvangelium Vitae\u201d parla di quella \u201cconfusione del bene e del male, che rende impossibile costruire e conservare l\u2019ordine morale dei singoli e delle comunit\u00e0\u201d (SV n. 93).<\/p>\n<p style=\"text-align: justify;\">La battaglia contro il relativismo in difesa delle radici cristiane della societ\u00e0, a cui ha chiamato Giovanni Paolo II e oggi invita Benedetto XVI, \u00e8 una battaglia in difesa della nostra memoria storica, senza la quale non c\u2019\u00e8 identit\u00e0 nel presente, perch\u00e9 \u00e8 sulla memoria che si fonda l\u2019identit\u00e0 degli uomini e dei popoli. Ma le radici cristiane non appartengono solo alla memoria o alla storia: esse sono viventi perch\u00e9 il Crocifisso, che le riassume, non \u00e8 solo un simbolo storico e culturale, ma \u00e8 una fonte attuale e perenne di verit\u00e0 e di vita, di sofferenza e di lotta.<\/p>\n<p style=\"text-align: justify;\"><strong>La chiesa ha nemici, anche se noi tendiamo a dimenticarlo<\/strong> perch\u00e9 abbiamo perso quella concezione militante della vita cristiana, fondata sulla Croce, che ha sempre caratterizzato il cristianesimo. La perdita di questo spirito militante \u00e8 la conseguenza dell\u2019edonismo e del relativismo in cui sono immersi purtroppo anche molti uomini di chiesa. Benedetto XVI ha parlato spesso di minoranze \u201ccreative\u201d; potremmo aggiungere \u201cmilitanti\u201d, perch\u00e9 quella in corso \u00e8 una guerra culturale e morale in cui ci si affronta in termini di principi di concezioni del mondo. La storia del resto \u00e8 fatta da minoranze militanti e anche Zizola appartiene a una di esse. Si pu\u00f2 militare per il bene o per il male, in un campo o nell\u2019altro, ma solo chi milita lascia il suo segno nelle vicende storiche.<\/p>\n<p style=\"text-align: justify;\"><strong>Non si illuda Zizola: <\/strong>si pu\u00f2 e si deve sfuggire, per quanto possibile, allo scontro delle armi, ma non si pu\u00f2 sfuggire allo scontro delle idee. Egli stesso ne brandisce una come una clava che vorrebbe abbattere sulle teste dure dei cristiani fondamentalisti o \u201clepantiani\u201d. D\u2019altra parte, le idee che non si scontrano, non si \u201cincontrano\u201d, ma si fondono, formando a loro volta nuove idee all\u2019insegna dell\u2019indifferentismo e del sincretismo.<\/p>\n<p style=\"text-align: justify;\">La chiesa \u00e8 una societ\u00e0 soprannaturale che ha la missione di annunciare una Verit\u00e0 salvifica e liberatrice. Essendo un\u2019istituzione immersa nel mondo si serve, come \u00e8 giusto, anche di strumenti politici e diplomatici, ma la politica per lei \u00e8 mezzo, mai fine. Giuliano Ferrara nel Foglio del 7 giugno lo ha ben visto. Non bisogna confondere un viaggio diplomatico, come \u00e8 stato quello recente del Papa a Cipro, con il messaggio teologico e spirituale che la chiesa ha il dovere di annunziare.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019omelia a Nicosia, il 5 giugno, Benedetto XVI ha peraltro sottolineato che il legno della Croce non \u00e8 semplicemente un simbolo privato di devozione, non \u00e8 un distintivo di appartenenza a qualche gruppo all\u2019interno della societ\u00e0, ma \u00e8 un segno di speranza, di amore, di vittoria. \u201cUn mondo senza Croce \u2013 ha detto \u2013 sarebbe un mondo senza speranza\u201d. Anche un mondo senza spirito di crociata sarebbe un mondo senza speranza, perch\u00e9 significherebbe la rinunzia alla lotta per fare della Croce la salvezza di un mondo in rovine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corrispondenza Romana marted\u00ec 8 giugno 2010 (Roberto de Mattei su Il Foglio dell&#8217; 8 giugno 2010) &#8211; L\u2019irenismo ecumenico \u00e8 una distorsione della dottrina della chiesa e della sua storia. Il vero spirito del cristianesimo \u00e8 combattere per la verit\u00e0 e per difendere le radici che affondano nei secoli luminosi del medioevo &#8220;L\u2019addio della chiesa &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":21128,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,91,24],"tags":[1793],"class_list":["post-3868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crociate","category-medioevo","category-storia","tag-criciate","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apologia della crociata - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apologia della crociata - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-16T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-13T14:18:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/06\/crociate.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"192\" \/>\n\t<meta property=\"og:image:height\" content=\"263\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Apologia della crociata\",\"datePublished\":\"2010-06-16T22:00:00+00:00\",\"dateModified\":\"2015-03-13T14:18:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/\"},\"wordCount\":2333,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/06\\\/crociate.jpg\",\"keywords\":[\"criciate\"],\"articleSection\":[\"Crociate\",\"Medioevo\",\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/\",\"name\":\"Apologia della crociata - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/06\\\/crociate.jpg\",\"datePublished\":\"2010-06-16T22:00:00+00:00\",\"dateModified\":\"2015-03-13T14:18:41+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/06\\\/crociate.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/06\\\/crociate.jpg\",\"width\":192,\"height\":263},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/apologia-della-crociata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apologia della crociata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apologia della crociata - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/","og_locale":"it_IT","og_type":"article","og_title":"Apologia della crociata - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2010-06-16T22:00:00+00:00","article_modified_time":"2015-03-13T14:18:41+00:00","og_image":[{"width":192,"height":263,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/06\/crociate.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Apologia della crociata","datePublished":"2010-06-16T22:00:00+00:00","dateModified":"2015-03-13T14:18:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/"},"wordCount":2333,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/06\/crociate.jpg","keywords":["criciate"],"articleSection":["Crociate","Medioevo","Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/","name":"Apologia della crociata - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/06\/crociate.jpg","datePublished":"2010-06-16T22:00:00+00:00","dateModified":"2015-03-13T14:18:41+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/06\/crociate.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/06\/crociate.jpg","width":192,"height":263},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/apologia-della-crociata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Apologia della crociata"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3868"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3868\/revisions"}],"predecessor-version":[{"id":21524,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3868\/revisions\/21524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/21128"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}