{"id":3833,"date":"2010-05-20T00:00:00","date_gmt":"2010-05-19T22:00:00","guid":{"rendered":""},"modified":"2016-05-06T11:51:36","modified_gmt":"2016-05-06T09:51:36","slug":"nuove-considerazioni-sulla-legge-194","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/","title":{"rendered":"Nuove considerazioni sulla legge 194"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-33952 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/legge_194.jpg\" alt=\"legge_194\" width=\"240\" height=\"160\" \/>Corrispondenza Romana<\/strong> n.1142<\/div>\n<div style=\"text-align: center;\">15 maggio 2010<\/div>\n<p style=\"text-align: justify;\">Il recente caso di Rossano, in cui un bimbo di 22 settimane sopravvissuto all\u2019aborto \u00e8 stato lasciato agonizzare nella sala operatoria per un giorno intero, e che solamente in seguito alle proteste di un religioso \u00e8 stato posto in un\u2019incubatrice dove \u00e8 morto poco tempo dopo, oltre ad accendere i riflettori sull\u2019orrore dell\u2019aborto, consente delle riflessioni pi\u00f9 approfondite sulla legge 194\/1978 che da oltre trent\u2019anni regolamenta la cosiddetta interruzione volontaria di gravidanza nel nostro Paese.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">L\u2019episodio in questione ha sollevato accese discussioni ed ha innescato delle indagini conoscitive per verificare se, nel caso specifico, siano state rispettate le linee guida dettate dalla legge 194.\u00c8 utile rilevare come sull\u2019episodio di Rossano pesino le ambiguit\u00e0 e le contraddizione della legge, che sebbene formalmente ponga dei limiti, sembra essere strutturata in modo tale da permettere l\u2019aborto anche in quelle particolari circostanze.<\/div>\n<p style=\"text-align: justify;\">Nel caso in questione il medico \u00e8 stato accusato di non aver prestato soccorso al bambino sopravvissuto all\u2019aborto e si \u00e8 invocato il mancato rispetto delle condizioni necessarie per autorizzare l\u2019aborto, dato che la mamma non era in pericolo di vita e l\u2019et\u00e0 del feto intorno alle 22 settimane, dunque con possibilit\u00e0 di vita autonoma fuori dell\u2019utero materno.<\/p>\n<p style=\"text-align: justify;\">Occorre per\u00f2 sottolineare come la legge non preveda un limite cronologico preciso oltre cui non sia possibile interrompere la gravidanza, ma come tale limite venga identificato con l\u2019epoca nella quale sussiste la possibilit\u00e0 di vita autonoma del feto (194\/1978 art. 6, 7).<\/p>\n<p style=\"text-align: justify;\">Secondo la stessa Societ\u00e0 Italiana di Ginecologia e Ostetricia non \u00e8 possibile stabilire un limite certo di vitalit\u00e0 valido per tutti i feti (Atti della Societ\u00e0 di Ginecologia e Ostetricia \u2013 vol. LXXXV).<\/p>\n<p style=\"text-align: justify;\">Il Decreto direzione generale sanit\u00e0 n\u00b0 327 del 22\/01\/2008 della Regione Lombardia, afferma che \u00abI dati scientifici oggi a disposizione indicano che a 23 settimane di et\u00e0 gestazionale \u00e8 possibile la vita autonoma del neonato. Considerato per\u00f2 che \u00e8 dimostrato un margine di errore nella datazione della gravidanza, anche se effettuata in epoca gestazionale precoce, e che la possibilit\u00e0 di vita autonoma del neonato migliora, tra la 22\u00aa e la 24\u00aa settimana, del 2-3 percento per ogni giorno di gravidanza, si ritiene che l\u2019interruzione di gravidanza di cui all\u2019art. 6 b non debba essere effettuata oltre la 22a settimana + 3 giorni\u00bb.<\/p>\n<p style=\"text-align: justify;\">Data l\u2019evidente inconsistenza e provvisoriet\u00e0 dei \u201cpaletti\u201d indicati, non si capisce come tale atto di indirizzo possa costituire un argine giuridico contro possibili violazioni della legge e, soprattutto, come possa essere considerato un criterio etico di riferimento. D\u2019altronde, la legge 194 \u00e8 stata pensata per permettere l\u2019eliminazione del bambino indesiderato o \u201cdifettato\u201d, non certo per salvaguardare la sua vita.<\/p>\n<p style=\"text-align: justify;\">Certamente, viene da chiedersi, e lecitamente, come possa un medico disinteressarsi della sorte di un bimbo indifeso a tal punto da lasciarlo morire di stenti. Dovremmo per\u00f2 prima chiederci come possa il medico trasformarsi nell\u2019assassino di un innocente; dovremmo anche chiederci come possa uno Stato legittimare e finanziare tale abominevole delitto e come l\u2019opinione pubblica sia disposta a scandalizzarsi solo in presenza di possibili violazioni della legge e mai per l\u2019olocausto degli innocenti che si consuma giornalmente negli ospedali italiani, proprio a causa della legge.<\/p>\n<p style=\"text-align: justify;\">Effettivamente, la finalit\u00e0 della legge 194 \u00e8 quella di tutelare la salute fisica e\/o psichica della donna, a danno dell\u2019innocente che porta nel grembo, soprattutto se portatore di una malformazione reale o presunta (incredibilmente, alcuni \u201cpro-life\u201d si ostinano a dichiarare che la 194 non contempla la pratica eugenetica).<\/p>\n<p style=\"text-align: justify;\">Dunque non pu\u00f2 destare alcuna meraviglia il fatto che l\u2019equipe medica non abbia prestato soccorso al piccolo; infatti, qualora egli fosse sopravvissuto, la responsabilit\u00e0 sarebbe stata del medico che l\u2019ha fatto nascere prematuramente con l\u2019intento, non raggiunto, di sopprimerlo. Il numero delle vittime innocenti dal 1978 ad oggi in Italia (oltre cinque milioni) ben evidenzia l\u2019ipocrisia della legge 194, il cui spirito \u00e8 quello di sancire e garantire la piena autodeterminazione della donna, contrariamente a quanto indicato nel titolo e nel preambolo della legge stessa, dietro cui il legislatore ha astutamente ritenuto di trincerarsi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corrispondenza Romana n.1142 15 maggio 2010 Il recente caso di Rossano, in cui un bimbo di 22 settimane sopravvissuto all\u2019aborto \u00e8 stato lasciato agonizzare nella sala operatoria per un giorno intero, e che solamente in seguito alle proteste di un religioso \u00e8 stato posto in un\u2019incubatrice dove \u00e8 morto poco tempo dopo, oltre ad accendere &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33952,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1047],"class_list":["post-3833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","tag-legge-194","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuove considerazioni sulla legge 194 - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuove considerazioni sulla legge 194 - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-19T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-06T09:51:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/legge_194.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Nuove considerazioni sulla legge 194\",\"datePublished\":\"2010-05-19T22:00:00+00:00\",\"dateModified\":\"2016-05-06T09:51:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/\"},\"wordCount\":662,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/legge_194.jpg\",\"keywords\":[\"legge 194\"],\"articleSection\":[\"Aborto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/\",\"name\":\"Nuove considerazioni sulla legge 194 - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/legge_194.jpg\",\"datePublished\":\"2010-05-19T22:00:00+00:00\",\"dateModified\":\"2016-05-06T09:51:36+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/legge_194.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/legge_194.jpg\",\"width\":240,\"height\":160},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/nuove-considerazioni-sulla-legge-194\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuove considerazioni sulla legge 194\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuove considerazioni sulla legge 194 - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/","og_locale":"it_IT","og_type":"article","og_title":"Nuove considerazioni sulla legge 194 - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2010-05-19T22:00:00+00:00","article_modified_time":"2016-05-06T09:51:36+00:00","og_image":[{"width":240,"height":160,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/legge_194.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Nuove considerazioni sulla legge 194","datePublished":"2010-05-19T22:00:00+00:00","dateModified":"2016-05-06T09:51:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/"},"wordCount":662,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/legge_194.jpg","keywords":["legge 194"],"articleSection":["Aborto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/","name":"Nuove considerazioni sulla legge 194 - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/legge_194.jpg","datePublished":"2010-05-19T22:00:00+00:00","dateModified":"2016-05-06T09:51:36+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/legge_194.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/legge_194.jpg","width":240,"height":160},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/nuove-considerazioni-sulla-legge-194\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Nuove considerazioni sulla legge 194"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3833"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3833\/revisions"}],"predecessor-version":[{"id":33953,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3833\/revisions\/33953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33952"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}