{"id":38326,"date":"2017-09-07T00:00:43","date_gmt":"2017-09-06T22:00:43","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=38326"},"modified":"2017-08-03T10:28:44","modified_gmt":"2017-08-03T08:28:44","slug":"piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/","title":{"rendered":"Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-38327\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/cristiani_arabia.jpg\" alt=\"cristiani_arabia\" width=\"250\" height=\"193\" \/>La Nuova Bussola quotidiana<\/strong><\/p>\n<p style=\"text-align: center;\">3 Agosto 2017<\/p>\n<p style=\"text-align: center;\">di <strong>Giorgio Bernardelli<\/strong><\/p>\n<p style=\"text-align: justify;\">Nonostante le persecuzioni dell&#8217;Isis e le altre durissime prove vissute in questi ultimi anni, il numero dei cristiani in Medio Oriente tiene. E se poi dall&#8217;area storica della loro presenza si allarga lo sguardo anche al Golfo Persico, ci si accorge che addirittura crescono. E&#8217; il quadro sorprendente offerto da un nuovo rapporto pubblicato dal Cnewa &#8211; Catholic Near East Welfare Association, associazione di diritto pontificio che \u00e8 uno tra i principali punti di riferimento a livello mondiale per la vicinanza e la solidariet\u00e0 alle Chiese d&#8217;Oriente.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>Mettendo a confronto una serie di dati forniti<\/strong> da fonti diverse e soppesandoli a partire dalla propria esperienza sul campo il Cnewa ha tratto per ciascuno dei nove Paesi in cui opera in questa regione (dall&#8217;Egitto alla Siria, da Israele all&#8217;Iraq, dalla Giordania al Libano&#8230;) alcune stime sulla presenza dei cristiani aggiornate al 2017. E ha quindi messo a confronto questi dati con una medesima rilevazione compiuta nel 2010, prima della stagione delle primavere arabe. Il risultato \u00e8 che in questi Paesi del Medio Oriente dove le Chiese locali sono presenti ininterrottamente dai tempi degli apostoli oggi i cristiani sarebbero 14.525.880, vale a dire appena 213,780 in meno (-1,45%) rispetto a sette anni fa.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-32572\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/cristiani_mussulmani.jpg\" alt=\"cristiani_mussulmani\" width=\"250\" height=\"134\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/cristiani_mussulmani.jpg 307w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/cristiani_mussulmani-300x160.jpg 300w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/>Si tratta di un numero che esprime un attaccamento impressionante<\/strong> alle proprie radici, se si pensa a quanto le ragioni che spingerebbero in favore di un esodo massiccio siano state serie e quanto anche la stessa pulizia etnica messa in atto dai gruppi jihadisti avesse proprio questo preciso obiettivo. Va specificato che, se si analizza il dato nel dettaglio, le ferite si vedono comunque a occhio nudo. Il grosso della tenuta \u00e8 data infatti dai cristiani dell&#8217;Egitto &#8211; i copti, la pi\u00f9 popolosa delle delle comunit\u00e0 cristiane d&#8217;Oriente &#8211; che dal 2010 al 2017 sarebbero aumentati da 8,1 a 9,4 milioni; un&#8217;avanzata che segue i ritmi di crescita della popolazione locale, mantenendo la quota dei cristiani nel Paese intorno al 10 per cento. Un dato comunque non scontato, se si pensa a tutto quanto \u00e8 accaduto al Cairo dalla vittoria dei Fratelli Musulmani nelle elezioni del 2012 in poi.<\/p>\n<p style=\"text-align: justify;\"><strong>Dove invece l&#8217;emorragia si vede chiaramente \u00e8 nella Siria<\/strong> provata da ormai oltre sei anni di guerra: secondo le stime del Cnewa qui la presenza dei cristiani si sarebbe assottigliata sensibilmente, passando da 2,2 a 1,2 milioni di persone. Discorso analogo per l&#8217;Iraq che sarebbe sceso ulteriormente a quota 250 mila cristiani, lontanissimi dal milione e mezzo di inizio anni Novanta. E per di pi\u00f9 si tratta di comunit\u00e0 tuttora in gran parte profughe nel proprio stesso Paese e alle prese con le incertezze che anche dopo la sconfitta dell&#8217;Isis tuttora circondano il futuro di Mosul e della Piana di Ninive.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-29860\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/cristiani_islam.jpg\" alt=\"cristiani_islam\" width=\"250\" height=\"147\" \/>Vi sono per\u00f2 altre realt\u00e0 del Medio Oriente<\/strong> dove le comunit\u00e0 cristiane conoscono oggi una nuova vitalit\u00e0: il caso pi\u00f9 evidente \u00e8 quello della Giordania, Paese dove il cristianesimo \u00e8 presente ininterrottamente dai tempi della predicazione di Ges\u00f9 e divenuto &#8211; non senza fatiche &#8211; casa anche per molte famiglie cristiane fuggite dall&#8217;Iraq e dalla Siria. Oggi in Giordania secondo il Cnewa vi sono 350.000 cristiani, che vuol dire molti pi\u00f9 di quelli presenti in Israele e in Palestina messi insieme (realt\u00e0 dove comunque il numero dei cristiani sarebbe tornato a crescere leggermente, dopo la contrazione dei primi anni Duemila).<\/p>\n<p style=\"text-align: justify;\"><strong>Ma il vero fatto nuovo per il Medio Oriente sta succedendo molto pi\u00f9 lontano<\/strong>, nel Golfo Persico, dove neppure il Cnewa \u00e8 presente. In Paesi come il Kuwait, gli Emirati Arabi Uniti, la stessa Arabia Saudita stanno continuando a crescere i numeri dei lavoratori cristiani immigrati portati fino a qui dalle nuove rotte del mercato del lavoro globale. Filippini, indiani, sudanesi, eritrei che lavorano negli alberghi o nei cantieri di Dubai, Doha o Abu Dhabi, spesso in condizioni durissime.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-13509\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/11\/cristiani-in-MO.jpg\" alt=\"cristiani in MO\" width=\"250\" height=\"145\" \/>Il Cnewa calcola che dal 2010 a oggi siano quasi raddoppiati raggiungendo complessivamente la cifra di 3,8 milioni di persone. Una presenza precaria ma ormai impossibile da nascondere: in Kuwait sarebbero ormai l&#8217;equivalente del 17% della popolazione, in Bahrein il 14,5%, dati impensabili solo ieri. Vivono la propria fede rigorosamente all&#8217;interno della manciata di chiese che hanno avuto il premesso di costruire; ogni anno che passa, per\u00f2, sono una presenza sempre meno invisibile.<\/p>\n<p style=\"text-align: justify;\"><strong>Oggi, dunque, non si pu\u00f2 pi\u00f9 tracciare<\/strong> una fotografia dei cristiani del Medio Oriente senza tener conto anche di loro. E con loro anche i numeri complessivi cambiano: ci si accorge che dal 2010 il saldo complessivo \u00e8 di quasi 1,6 milioni di cristiani in pi\u00f9, con un incremento del 9,5%. E che oggi un cristiano del Medio Oriente su cinque vive tra la Penisola Arabica e il Golfo Persico. Piccolo seme fragile e precario. Ma che nella logica del Vangelo non potr\u00e0 non portare frutto.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>La Nuova Bussola quotidiana 3 Agosto 2017 di Giorgio Bernardelli Nonostante le persecuzioni dell&#8217;Isis e le altre durissime prove vissute in questi ultimi anni, il numero dei cristiani in Medio Oriente tiene. E se poi dall&#8217;area storica della loro presenza si allarga lo sguardo anche al Golfo Persico, ci si accorge che addirittura crescono. E&#8217; &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":38327,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,33],"tags":[259],"class_list":["post-38326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-cristiani-nell-islam","tag-conversioni","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-06T22:00:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/cristiani_arabia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"255\" \/>\n\t<meta property=\"og:image:height\" content=\"197\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente\",\"datePublished\":\"2017-09-06T22:00:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/\"},\"wordCount\":795,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cristiani_arabia.jpg\",\"keywords\":[\"conversioni\"],\"articleSection\":[\"Chiesa\",\"Cristiani nell'islam\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/\",\"name\":\"Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cristiani_arabia.jpg\",\"datePublished\":\"2017-09-06T22:00:43+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cristiani_arabia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cristiani_arabia.jpg\",\"width\":255,\"height\":197},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/","og_locale":"it_IT","og_type":"article","og_title":"Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-09-06T22:00:43+00:00","og_image":[{"width":255,"height":197,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/cristiani_arabia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente","datePublished":"2017-09-06T22:00:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/"},"wordCount":795,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/cristiani_arabia.jpg","keywords":["conversioni"],"articleSection":["Chiesa","Cristiani nell'islam"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/","name":"Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/cristiani_arabia.jpg","datePublished":"2017-09-06T22:00:43+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/cristiani_arabia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/cristiani_arabia.jpg","width":255,"height":197},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/piu-forte-della-pulizia-etnica-jihadista-la-crescita-impressionante-dei-cristiani-in-medio-oriente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Pi\u00f9 forte della pulizia etnica jihadista: la crescita impressionante dei Cristiani in Medio Oriente"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/38326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=38326"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/38326\/revisions"}],"predecessor-version":[{"id":38328,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/38326\/revisions\/38328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/38327"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=38326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=38326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=38326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}