{"id":38304,"date":"2017-09-07T00:00:56","date_gmt":"2017-09-06T22:00:56","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=38304"},"modified":"2017-08-02T09:53:05","modified_gmt":"2017-08-02T07:53:05","slug":"la-sindone-un-uomo-torturato-morto-di-infarto","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/","title":{"rendered":"La Sindone: un uomo torturato morto di infarto"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-38305\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/sindone.jpg\" alt=\"sindone\" width=\"189\" height=\"200\" \/>La Nuova Bussola quotidiana<\/strong> 2 Agosto 2017<\/p>\n<p style=\"text-align: center;\">di <strong>Emanuela Marinelli<\/strong><\/p>\n<p style=\"text-align: justify;\">Il recente congresso scientifico svoltosi a Pasco (USA) dal 19 al 22 luglio ha portato nuovi risultati che avvalorano l\u2019autenticit\u00e0 della Sindone, il lenzuolo conservato a Torino che la tradizione attribuisce alla sepoltura di Cristo. Gli studiosi presenti provenivano da diversi Paesi e il contributo di quelli italiani \u00e8 stato notevole, sia nel settore storico che in quello scientifico.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>La storia antica della Sindone si identifica con quella dell\u2019Immagine di Edessa<\/strong>, che fu chiamata <em>Mandylion<\/em> dai Bizantini. Alfonso Caccese, Emanuela Marinelli, Laura Provera e don Domenico Repice hanno studiato l\u2019<em>Imago Pietatis<\/em>, ovvero il Cristo a mezzo busto che sorge da una tomba a pozzo con il capo reclinato sulla sua spalla destra e le braccia incrociate davanti. Varie testimonianze scritte e iconografiche confermano l\u2019ipotesi che questo tipo iconografico si ispiri alla Sindone, esposta in verticale a Costantinopoli con un meccanismo simile a quello del trono della Magnaura, con cui l\u2019imperatore poteva essere sollevato in alto per impressionare i presenti.<\/p>\n<p style=\"text-align: justify;\"><strong>La Sindone era a Costantinopoli nel 1204<\/strong>. Alessandro Piana ha portato nuovi elementi a conferma della presenza della reliquia ad Atene nel 1205, dopo il saccheggio perpetrato dai Crociati nella capitale bizantina. In quell\u2019anno era diventato Signore di Atene Othon de la Roche, che torn\u00f2 in Francia dopo il 1225, con ogni probabilit\u00e0 recando con s\u00e9 la Sindone. Dopo la sua morte, nel 1234, la Sindone rest\u00f2 propriet\u00e0 della sua famiglia fino ad arrivare a Jeanne de Vergy, sua discendente alla quinta generazione, che insieme al marito Geoffroy de Charny la espose a Lirey a met\u00e0 del XIV secolo.<\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019indagine genetica condotta su campioni sindonici<\/strong> si conferma molto promettente. Gianni Barcaccia ha rilevato la cospicua presenza di DNA di origine indiana e mediorientale. In particolare \u00e8 interessante l\u2019aplogruppo H33, molto raro, perch\u00e9 si trova principalmente presso i Drusi, una minoranza etnica presente in Israele, Giordania, Libano e Siria. La possibile origine indiana della Sindone pu\u00f2 essere confermata dal nome stesso, che pu\u00f2 derivare da Sindia o Sindien, termini usati per indicare un tessuto proveniente dall\u2019India.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-27330\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/06\/sindone.jpg\" alt=\"sindone\" width=\"153\" height=\"200\" \/>\u00c8 noto dagli studi di Ada Grossi<\/strong> che il pomeriggio dello Yom Kippur il Sommo Sacerdote si vestiva di pregiato lino indiano. Maria Luisa Rigato ritiene che per la sepoltura di Ges\u00f9 fu usato uno dei preziosi lini disponibili nel Tempio di Gerusalemme.<\/p>\n<p style=\"text-align: justify;\"><strong>Il volto di Cristo ispirato alla Sindone<\/strong> \u00e8 presente su numerose monete bizantine. Giulio Fanti ha dimostrato come numerosi dettagli, derivati dall\u2019osservazione della reliquia, caratterizzino le monete bizantine a partire dal 692, anno in cui l\u2019imperatore Giustiniano II per la prima volta fece rappresentare il volto di Cristo su tali monete. Con il tempo questa somiglianza si affievol\u00ec, ma si rinforz\u00f2 di nuovo in concomitanza con l\u2019arrivo della Sindone a Costantinopoli nel 944.<\/p>\n<p style=\"text-align: justify;\"><strong>Gli interventi di Giulio Fanti<\/strong> al congresso hanno spaziato dal campo storico a quello scientifico. Nei giorni precedenti, il nome di Fanti aveva fatto il giro del mondo per un\u2019importante ricerca <a href=\"http:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0180487\" target=\"_blank\">pubblicata su PlosOne<\/a>:<\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019indagine \u00e8 stata condotta dal Dipartimento di Ingegneria<\/strong> Industriale di Padova, dove insegna Fanti, in collaborazione con Elvio Carlino, dell\u2019Istituto Officina dei materiali del CNR di Trieste, e Liberato De Caro e Cinzia Giannini, dell\u2019Istituto di Cristallografia del CNR di Bari. Questo gruppo di scienziati, che si avvale degli strumenti di microscopia pi\u00f9 avanzati, ha trovato su una fibra della Sindone tracce di nanoparticelle biologiche di creatinina, una sostanza chimica prodotta dal metabolismo muscolare, legate a nanoparticelle di ossido di ferro. Il tipo, la dimensione e la distribuzione delle nanoparticelle di ossido di ferro rivela che non possono essere coloranti per la pittura, ma sono piccole particelle di ferridrite della ferritina, una proteina che costituisce la riserva di ferro dell&#8217;organismo nei tessuti. Il legame costante della ferritina con la creatinina si verifica nell&#8217;organismo umano in caso di grave politrauma. Questa ricerca conferma, quindi, che l\u2019Uomo della Sindone \u00e8 stato vittima di pesanti torture prima di una morte cruenta.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-23468\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/03\/Sindone-3.jpg\" alt=\"Sindone 3\" width=\"150\" height=\"200\" \/>Al congresso, Fanti ha anche presentato i risultati sperimentali<\/strong> di uno studio, condotto con Gianmaria Concheri e Sergio Rodella su una statua appositamente realizzata, che dimostra come l\u2019Uomo della Sindone fosse avvolto in modo stretto dalla Sindone; il lenzuolo non era semplicemente appoggiato sul cadavere come ipotizzato da alcuni in passato. Inoltre Fanti ha portato i risultati della datazione della Sindone condotta presso l\u2019Universit\u00e0 di Padova con un metodo meccanico e due metodi chimici (FT-IR e Raman). In base a questi esami, la Sindone risale all\u2019epoca di Cristo. Da altri suoi studi sulle caratteristiche dell\u2019immagine sindonica, risulta che deve essere stata formata da una radiazione direzionale ma complessa, come pu\u00f2 essere una scarica elettrica che ha prodotto un effetto corona.<\/p>\n<p style=\"text-align: justify;\"><strong>Il colore delle macchie di sangue<\/strong>, che si \u00e8 mantenuto nei secoli pi\u00f9 rosso di quanto ci si aspetterebbe, \u00e8 stato discusso da Paolo Di Lazzaro che presentava un lavoro condotto in collaborazione con Antonio Di Lascio, Paola Iacomussi, Mauro Missori e Daniele Murra. Lo scopo del lavoro era quello di verificare le varie ipotesi formulate in passato. La pi\u00f9 valida \u00e8 risultata quella di Carlo Goldoni: la radiazione ultravioletta pu\u00f2 cambiare la struttura della bilirubina; ci\u00f2 rafforza il colore rosso delle macchie di sangue durante un lungo periodo. L\u2019irradiazione con una lampada UV di macchie di sangue ricche di bilirubina ha generato una colorazione rosso-giallastra permanente a distanza di quattro anni.<\/p>\n<p style=\"text-align: justify;\">Di Lazzaro ha anche messo in guardia dalle illusioni ottiche create dalle elaborazioni di rafforzamento dell\u2019immagine, che hanno portato alcuni a vedere tracce di monete, scritte, fiori e un\u2019immagine del volto sul retro della Sindone, che in realt\u00e0 non esistono. Infine ha fatto alcune puntualizzazioni in merito agli esperimenti condotti con il laser a eccimeri presso l\u2019ENEA di Frascati, che sono stati talvolta fraintesi da alcuni giornalisti e anche da altri scienziati: con una radiazione VUV (ultravioletto da vuoto) \u00e8 stata ottenuta una colorazione simile a quella dell\u2019immagine sindonica; questo non significa che l\u2019immagine sindonica \u00e8 stata generata da un flash di luce VUV, ma che non \u00e8 impossibile che una radiazione VUV possa aver avuto un ruolo nella formazione dell\u2019immagine.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-23464\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/Sindone.jpg\" alt=\"Sindone\" width=\"189\" height=\"200\" \/>Ad una intensa radiazione come causa della formazione dell\u2019immagine<\/strong>, durante un processo di annichilazione materia-antimateria al momento della Resurrezione, Giuseppe Baldacchini ha affiancato, nella sua ipotesi, un flusso di neutroni che ha falsato il risultato della datazione radiocarbonica del 1988, collocando l\u2019origine della Sindone nel medioevo.<\/p>\n<p style=\"text-align: justify;\"><strong>Per quanto riguarda le cause della morte di Ges\u00f9<\/strong>, Pietro Pescetelli si \u00e8 basato sulla sua esperienza di cardiologo per formulare l\u2019ipotesi, ben fondata, che il grido finale sulla croce e l\u2019uscita di sangue e siero dal fianco trafitto siano spiegabili con un infarto cui consegue la rottura del cuore e l\u2019allagamento del pericardio.<\/p>\n<p style=\"text-align: justify;\"><strong>Notevoli sono stati anche i contributi degli altri congressisti<\/strong>, provenienti da Spagna, Francia, Stati Uniti, Messico e Australia, che hanno fornito altre motivazioni storiche e scientifiche a conferma dell\u2019autenticit\u00e0 della venerata reliquia. Gli abstract di tutti gli interventi <a href=\"http:\/\/shroudresearch.net\/conference-2017\/\" target=\"_blank\">si trovano qui<\/a>: Alcuni interventi sono disponibili <a href=\"http:\/\/www.lanuovabq.it\/it\/%20https:\/www.youtube.com\/playlist?list=PLNXqdetrAZYxTFDcR8h1NFfhBLQq3Rrzp\" target=\"_blank\">su Youtube<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Nuova Bussola quotidiana 2 Agosto 2017 di Emanuela Marinelli Il recente congresso scientifico svoltosi a Pasco (USA) dal 19 al 22 luglio ha portato nuovi risultati che avvalorano l\u2019autenticit\u00e0 della Sindone, il lenzuolo conservato a Torino che la tradizione attribuisce alla sepoltura di Cristo. Gli studiosi presenti provenivano da diversi Paesi e il contributo &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":38305,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,22],"tags":[1735],"class_list":["post-38304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-scienza","tag-sindone","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Sindone: un uomo torturato morto di infarto - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Sindone: un uomo torturato morto di infarto - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-06T22:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/sindone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"218\" \/>\n\t<meta property=\"og:image:height\" content=\"231\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La Sindone: un uomo torturato morto di infarto\",\"datePublished\":\"2017-09-06T22:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/\"},\"wordCount\":1173,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/sindone.jpg\",\"keywords\":[\"Sindone\"],\"articleSection\":[\"Chiesa\",\"Scienza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/\",\"name\":\"La Sindone: un uomo torturato morto di infarto - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/sindone.jpg\",\"datePublished\":\"2017-09-06T22:00:56+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/sindone.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/sindone.jpg\",\"width\":218,\"height\":231},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-sindone-un-uomo-torturato-morto-di-infarto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Sindone: un uomo torturato morto di infarto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Sindone: un uomo torturato morto di infarto - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/","og_locale":"it_IT","og_type":"article","og_title":"La Sindone: un uomo torturato morto di infarto - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-09-06T22:00:56+00:00","og_image":[{"width":218,"height":231,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/sindone.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La Sindone: un uomo torturato morto di infarto","datePublished":"2017-09-06T22:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/"},"wordCount":1173,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/sindone.jpg","keywords":["Sindone"],"articleSection":["Chiesa","Scienza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/","name":"La Sindone: un uomo torturato morto di infarto - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/sindone.jpg","datePublished":"2017-09-06T22:00:56+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/sindone.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/08\/sindone.jpg","width":218,"height":231},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindone-un-uomo-torturato-morto-di-infarto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La Sindone: un uomo torturato morto di infarto"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/38304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=38304"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/38304\/revisions"}],"predecessor-version":[{"id":38306,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/38304\/revisions\/38306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/38305"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=38304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=38304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=38304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}