{"id":3828,"date":"2010-05-18T09:38:50","date_gmt":"2010-05-18T07:38:50","guid":{"rendered":""},"modified":"2015-11-10T14:29:47","modified_gmt":"2015-11-10T13:29:47","slug":"risorgimento-e-resistenza-due-nodi-della-storia-italiana","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/","title":{"rendered":"Risorgimento e Resistenza, due nodi della storia italiana"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/museo-risorgimento.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-27335\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/museo-risorgimento.jpg\" alt=\"museo risorgimento\" width=\"250\" height=\"187\" \/><\/a>Dalla <strong>newsletter<\/strong> dell\u2019Istituto Storico dell&#8217;Insorgenza e per l&#8217;Identit\u00e0 Nazionale (ISIIN)<\/div>\n<div style=\"text-align: center;\">del 9 maggio 2010<\/div>\n<p style=\"text-align: justify;\"><em>I due &#8220;pilastri&#8221; del sentimento di appartenenza nazionale: Risorgimento e Resistenza, non sono considerati del tutto tali dalla comunit\u00e0 nazionale. Ecco perch\u00e8.<br \/>\n<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Marco Invernizzi <\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Parto da un dato di fatto che per certi versi \u00e8 all\u2019origine del problema dell\u2019identit\u00e0 degl\u2019italiani nel nostro tempo, a centocinquant\u2019anni dalla formazione dello Stato unitario. Quando parliamo di Risorgimento e di Resistenza indubbiamente ci troviamo di fronte ai due eventi storici che vengono evocati dalle istituzioni dello Stato \u2014 il 15 aprile 2010 Giorgio Napolitano ha parlato dell\u2019unit\u00e0 del 1861 come <em>&#8220;una grande stella polare&#8221;<\/em> (1), che guidato il cambiamento nel Paese \u2014 e dalla maggior parte degli storici accademici come punti di riferimento imprescindibili per determinare il sentimento di appartenenza nazionale.<\/div>\n<p style=\"text-align: justify;\">Ma \u00e8 altrettanto vero che questi due &#8220;pilastri&#8221;, nonostante le massicce dosi di &#8220;educazione civica&#8221; impartita obbligatoriamente in tutte le scuole di ogni ordine e grado, pubbliche e private, non sono considerati del tutto tali dalla comunit\u00e0 nazionale. Ci\u00f2 si verifica naturalmente in grado diverso a misura dell\u2019istruzione, dell\u2019ideologizzazione e del vissuto di ciascuno, ma in misura sufficiente per poter affermare che entrambi gli eventi non riescono a svolgere il ruolo esemplare che \u00e8 stato loro assegnato.<\/p>\n<p style=\"text-align: justify;\">Il motivo di questa insufficiente adesione credo sia da ricercare nel carattere mitologico, <em>ergo<\/em> ideologico, che accomuna i due momenti della storia italiana, cio\u00e8 nella loro sostanziale astrattezza e non rispondenza ai sentimenti e \u2014 perch\u00e9 no? \u2014 agl\u2019interessi concreti della maggioranza dei cittadini. Infatti sia il Risorgimento sia la Resistenza hanno contribuito in maniera cospicua al venir meno di una concezione della vita condivisa perch\u00e9 fondata su principi e su esperienze universali \u2014 quello che alcuni studiosi hanno sintetizzato con il termine &#8220;senso comune&#8221; \u2014 diffondendo, spesso con l\u2019uso della violenza, visioni del mondo e della societ\u00e0 lontane e mutuate da filosofie sociali utopistiche.<\/p>\n<p style=\"text-align: justify;\">Provo a esaminare le due questioni, separandole anche per cercare di mostrare le similitudini e le differenze.<\/p>\n<p style=\"text-align: justify;\"><strong>1. <em>Il Risorgimento<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Il Risorgimento aveva alle spalle, in senso cronologico, e davanti a s\u00e9, almeno come punto di riferimento ideale, la madre di tutte le rivoluzioni, almeno nella modernit\u00e0, la Rivoluzione francese. Non tutti gli studiosi concordano nel fare in qualche modo dipendere il Risorgimento dalla Rivoluzione francese e, soprattutto i sostenitori di un\u2019interpretazione moderata, nazionalista e sabauda del processo di unificazione politica dell\u2019Italia, tendono a privilegiare le radici e i protagonisti autoctoni del moto risorgimentale.<\/p>\n<p style=\"text-align: justify;\">Queste radici indubbiamente vi furono e possono essere racchiuse in uno dei termini con cui si definisce, a torto, il Risorgimento, ossia l\u2019unit\u00e0. L\u2019unificazione della Penisola, prima divisa in diversi Stati regionali, alcuni plurisecolari, in un unico organismo politico fu certamente uno dei due motivi che hanno dominato la nascita dell\u2019Italia moderna ed \u00e8 una caratteristica assente nella Rivoluzione del 1789 in Francia.<\/p>\n<p style=\"text-align: justify;\">Ma l\u2019unificazione sarebbe potuta avvenire in modi diversi, per esempio secondo lo schema federalistico del movimento neo-guelfo, che non voleva contrapporsi alla Chiesa, oppure, al contrario, seguendo la prospettiva repubblicana, sostenuta dalle forze che si ispiravano a Giuseppe Mazzini e a Carlo Cattaneo.<\/p>\n<p style=\"text-align: justify;\">Invece venne attuata in obbedienza ai teoremi della prospettiva ispirata a una forma temperata di liberalismo e a un forte nazionalismo, che si intrecciavano e si mescolavano agl\u2019interessi geo-politici del Regno di Sardegna. Che tale prospettiva ideologica avesse un debito evidente nei confronti della Rivoluzione francese e in particolare del ventennio della dominazione napoleonica in Italia (1796-1815), mi sembra evidente.<\/p>\n<p style=\"text-align: justify;\">L\u2019unificazione, fatto in s\u00e9 positivo, venne attuata in maniera inseparabile da un progetto di rinnovamento degli assetti culturali e politici, che ebbe modalit\u00e0 ed effetti dirompenti nei confronti di un passato plurisecolare comune dei popoli italiani.<\/p>\n<p style=\"text-align: justify;\">Il Risorgimento dell\u2019Italia, quello che avvenne nella realt\u00e0, si tradusse invece in emarginazione completa delle classi politiche preunitarie, in mortificazione delle antiche capitali, in esproprio totale delle risorse materiali e immateriali \u2014 pensiamo ai codici, agli statuti delle autonomie, alle opere di carit\u00e0 \u2014 dei vari regni e principati soppressi, in dispersione totale dei patrimoni di esperienza accumulati in secoli di unit\u00e0 culturale, in eversione radicale dei cicli economico-sociali \u2014 incluse le migrazioni \u2014 regionali e interregionali.<\/p>\n<p style=\"text-align: justify;\">A vantaggio di un forte accentramento politico e di una pesante uniformit\u00e0 amministrativa, attuando una secolarizzazione esasperata e combattendo con l\u2019esercito ogni conato di resistenza.<\/p>\n<p style=\"text-align: justify;\">Il che portava inevitabilmente a uno scontro diretto con la Chiesa cattolica, non soltanto a causa del potere temporale che il Pontefice esercitava su una parte del territorio italiano, ma anche e soprattutto perch\u00e9 l\u2019ideologia risorgimentale prevedeva che il Paese attuasse uno stacco pi\u00f9 o meno radicale dalle sue radici cristiane.<\/p>\n<p style=\"text-align: justify;\">Si apr\u00ec cos\u00ec una serie di questioni, meglio, di ferite, che la comunit\u00e0 nazionale non ha ancora risolto centocinquant\u2019anni dopo la sua unificazione politica.<\/p>\n<p style=\"text-align: justify;\">Nacque allora \u2014 certamente almeno a partire dal 1848, dopo il rifiuto di Papa Pio IX (1846-1878) di muovere guerra a fianco dei sardi contro l\u2019Impero austriaco \u2014 una &#8220;questione cattolica&#8221;, questione pi\u00f9 ampia di quella che verr\u00e0 chiamata &#8220;questione romana&#8221; nata a seguito della conquista militare di Roma nel 1870 da parte dell\u2019esercito italiano.<\/p>\n<p style=\"text-align: justify;\">La &#8220;questione romana&#8221; non \u00e8 stata risolta compiutamente dai Patti Lateranensi del 1929, che hanno sanato gli aspetti giuridici e politici, accettando con l\u2019esistenza di un minuscolo ma reale Stato vaticano e regolamentando, con il Concordato, i rapporti nelle materie miste fra Stato italiano e Santa Sede.<\/p>\n<p style=\"text-align: justify;\">La &#8220;questione cattolica&#8221; \u00e8 pi\u00f9 ampia perch\u00e9 affonda nel corpo sociale italiano e si esplica non solo nella separazione fra Stato e Chiesa, ma anche nella scristianizzazione della sfera pubblica e nel ridimensionamento della presenza organizzata dei cattolici \u2014 che in buona parte rappresentano, almeno fino alla fine del XIX secolo, il &#8220;Paese reale&#8221;\u2014 che lo Stato, il Paese legale, attua nei decenni successivi all\u2019unificazione e poi, ancor di pi\u00f9, dopo il 1870.<\/p>\n<p style=\"text-align: justify;\">Questa deriva non si \u00e8 estinta dal punto di vista culturale n\u00e9 durante il fascismo, n\u00e9 nei regimi cosiddetti democratico-cristiani della Prima Repubblica, dove il cattolicesimo venne indubbiamente rispettato \u2014 anzi, la sfera religioso-clericale ottenne appoggi prima insperabili \u2014, ma mai effettivamente ripreso come fondamento delle origini della nazione e quale componente vitale della vita pubblica.<\/p>\n<p style=\"text-align: justify;\">Nacque allora anche una &#8220;questione meridionale&#8221;, a causa della guerra civile che sconvolse il Mezzogiorno nel decennio 1860-1870 e che cost\u00f2 almeno diecimila morti, quasi tutti fra i contadini ribelli, e uno strascico di rancori etnico-classisti ancora oggi percepibile nelle viscere del Sud, per esempio nell\u2019insofferenza popolare verso lo Stato, nella sensazione di persecuzione ed esclusione che affligge la popolazione e nel ricorso alla protezione delle organizzazioni criminali di tipo mafioso.<\/p>\n<p style=\"text-align: justify;\">Si cre\u00f2 inoltre \u2014 e forse si tratta della questione meno nota o, comunque, affiorata pi\u00f9 tardi \u2014 una &#8220;questione federalista&#8221;, relativa alla forma dello Stato che i primi governi italiani vollero centralizzata, sulla base del modello francese, quando invece il &#8220;vestito&#8221; politico adatto al Paese-Italia avrebbe palesemente dovuto essere di carattere federale, nel rispetto delle profonde diversit\u00e0 delle popolazioni, delle loro varie storie e dei rispettivi governi pre-unitari.<\/p>\n<p style=\"text-align: justify;\">Una questione che l\u2019istituzione delle regioni nel 1970 non ha affatto risolto, visto l\u2019impronta verticistica, astratta \u2014 il ritaglio del territorio fatto nel 1861 andava ancora bene un secolo dopo? \u2014, burocratica e pleonastica \u2014 perch\u00e9 mantenere le province? \u2014 che l\u2019ha accompagnata.<\/p>\n<p style=\"text-align: justify;\">Queste tre &#8220;questioni&#8221; hanno prodotto altrettante ferite che non si sono mai del tutto rimarginate nel corso della storia unitaria del Paese, si sono impresse nella memoria collettiva e nella tradizione familiare, anche se hanno assunto diverse espressioni nelle successive epoche storiche. E qui sta la radice della freddezza e dell\u2019indifferenza agli appelli patriottistici delle autorit\u00e0, che ignorano imperterrite questi spessi &#8220;rovesci di medaglia&#8221; e continuano a propagandare una mitologia oleografica e inverificata \u2014 anzi, verificandola, si vanifica ancor di pi\u00f9 \u2014 e che puzza sempre pi\u00f9 di falso ideologico.<\/p>\n<p style=\"text-align: justify;\"><strong>2. <em>La Resistenza<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c8 significativo che le diverse famiglie ideologiche riaffiorate dopo il fascismo abbiano letto la Resistenza come &#8220;secondo Risorgimento&#8221;.<\/p>\n<p style=\"text-align: justify;\">Questo vale per il radicalismo liberale del Partito d\u2019Azione \u2014 che nella Resistenza assume lo stesso nome dell\u2019aggregazione che nel Risorgimento un\u00ec Casa Savoia a Camillo di Cavour (1810-1861) e a Giuseppe Garibaldi (1807-1885) \u2014, che voleva portare a termine il processo risorgimentale attraverso una radicale riforma della cultura del Paese che lo allontanasse definitivamente dalle sue radici cattoliche e &#8220;controriformistiche&#8221;, ritenute il principale ostacolo al suo processo di modernizzazione.<\/p>\n<p style=\"text-align: justify;\">Vale anche per gli stessi comunisti, che faranno propria la lettura rivoluzionaria del Risorgimento proposta da Antonio Gramsci (1891-1937), e vedranno nella Resistenza l\u2019occasione per fare quella rivoluzione sociale mai definitivamente attuatasi nel Paese.<\/p>\n<p style=\"text-align: justify;\">Lo stesso fascismo, pure essendo un &#8220;fascio&#8221; appunto di diverse ideologie e correnti politiche, si consider\u00f2 sempre, almeno attraverso il pensiero di Giovanni Gentile (1875-1944) e dei principali intellettuali nazionalisti, in virt\u00f9 della &#8220;nazionalizzazione delle masse&#8221; da esso attuata, come erede, continuatore e ultimatore del Risorgimento.<\/p>\n<p style=\"text-align: justify;\">Un discorso diverso, molto pi\u00f9 complesso e difficile da riassumere, riguarda il mondo cattolico. Indubbiamente il partito della Democrazia Cristiana e i suoi principali intellettuali di riferimento non enfatizzarono mai le posizioni contrarie al Risorgimento assunte a suo tempo dalla Chiesa, <em>in primis<\/em> dal beato Papa Pio IX, poi dal movimento cattolico intransigente, che lo storico liberale Giovanni Spadolini (1925-1994) ha chiamato l\u2019&#8221;opposizione cattolica&#8221;, perch\u00e9 i democratici cristiani temevano che ci\u00f2 lasciasse credere che il partito di maggioranza relativa, ormai stabilmente alla direzione dello Stato, avesse nostalgie temporalistiche e nutrisse la stessa diffidenza verso le istituzioni statali liberali che aveva sempre contraddistinto il movimento cattolico. I cattolici insomma erano entrati ai vertici dello Stato dopo il 1945 e non avevano nessuna intenzione di andarsene, anche se questo comport\u00f2 sorvolare su una ferita nazionale profonda e importante.<\/p>\n<p style=\"text-align: justify;\">Oltre a essere stata una guerra fra il fascismo e le forze che, dopo l\u20198 settembre 1943, diedero vita al Comitato di Liberazione Nazionale (CLN) nell\u2019Italia occupata dai tedeschi e governata dalla Repubblica Sociale Italiana, la Resistenza ha assunto anche il carattere di uno scontro ideologico-politico fra le diverse forze del CLN vittorioso, ognuna delle quali, peraltro, si riteneva degna erede e continuatrice del Risorgimento e dello Stato prefascista \u2014 con le riserve cui ho accennato riguardo al mondo cattolico \u2014 e voleva cogliere l\u2019opportunit\u00e0 della sconfitta militare del Paese e delle drammatiche sofferenze che la guerra aveva inflitto alle popolazioni al fine di conquistarvi l\u2019egemonia politica.<\/p>\n<p style=\"text-align: justify;\">La lotta antifascista e antitedesca, lungi dall\u2019essere quel moto corale di liberazione e quel generale anelito di democrazia che ne sostanziano la mitologizzazione, ha coinvolto solo una parte della nazione. Ne sono rimasti ovviamente esclusi i fascisti e chi prestava loro consenso, cio\u00e8 molti ben pensanti, le centinaia di migliaia di sodati italiani rinchiusi nei campi di prigionia in India, in Sudafrica, in Inghilterra, negli Stati Uniti \u2014molti di meno, per ovvi motivi quelli prigionieri in Russia \u2014, gl\u2019italiani che vivevano nella zona di occupazione alleata e, nel resto d\u2019Italia, quella maggioranza &#8220;grigia&#8221; e attendista della popolazione, presente anche fra chi scelse di rifugiarsi sulle montagne per sfuggire alla deportazione in Germania o alla coscrizione fascista.<\/p>\n<p style=\"text-align: justify;\">Ma, soprattutto, per come \u00e8 stata condotta, ha prodotto gravi lacerazioni e lasciato ingenti strascichi nel dopoguerra.<\/p>\n<p style=\"text-align: justify;\">Anzitutto una grande ferita si \u00e8 formata a seguito della guerra scatenata dalle formazioni terroristiche e partigiane comuniste nel Nord del Paese, un conflitto feroce, che ha coinvolto italiani quartiere per quartiere, caseggiato per caseggiato \u2014 soprattutto gli alloggi popolari delle grandi citt\u00e0 come Milano, Torino e Roma.<\/p>\n<p style=\"text-align: justify;\">Una guerra fatta di omicidi politici, di attentati terroristici \u2014 da via Rasella a Roma in poi \u2014 e rinfocolata dalle rappresaglie provocate. Una guerra che aggravava lo scontro bellico fra i due eserciti stranieri, quello a guida nazionalsocialista al nord e quello alleato che risaliva dalla Sicilia \u2014 ciascuno con la sua &#8220;appendice&#8221; di formazioni italiane \u2014 che si combattevano lungo la Penisola.<\/p>\n<p style=\"text-align: justify;\">Una guerra che macchiava lo sforzo reale di liberare il Paese che tanti militari e civili nelle formazioni partigiane disinteressatamente perseguivano. Una guerra civile che la parte vittoriosa ha continuato anche dopo la fine delle ostilit\u00e0, proseguendo con omicidi e &#8220;pulizie di classe&#8221;, umiliazioni e minacce per i vinti, fino almeno al 1948: i molti volumi di Giampaolo Pansa ne sono la pi\u00f9 recente e sensazionale riscoperta.<\/p>\n<p style=\"text-align: justify;\">La grave lacerazione non deve fare tuttavia dimenticare la parentela che esiste fra le diverse ideologie che hanno operato durante la guerra civile e che operativamente le assocer\u00e0 all\u2019interno del Cln e poi nell\u2019Assemblea Costituente e nei governi nazionali e locali: l\u2019espulsione dei comunisti per ragioni internazionali dal governo dello Stato nel 1947 sar\u00e0 alla lunga &#8220;ricuperata&#8221; per iniziativa del partito democristiano e sar\u00e0 del tutto dimenticata nei governi &#8220;di unit\u00e0 nazionale&#8221; della fine degli anni 1970.<\/p>\n<p style=\"text-align: justify;\">La stessa ideologia del regime sconfitto, il fascismo, nasce dal socialismo, si unisce al nazionalismo dopo la Grande Guerra e soltanto durante il ventennio assume posizioni conservatrici \u2014 per interesse o per convinzione \u00e8 difficile da valutare \u2014, ostili al processo di ideologizzazione sviluppatosi nel Paese appunto a partire dal Risorgimento.<\/p>\n<p style=\"text-align: justify;\">Forse questo \u2014 una rivalit\u00e0 fra &#8220;cugini&#8221; \u2014 pu\u00f2 spiegare meglio la ferocia della guerra civile su un piano strettamente umano, anche perch\u00e9 coloro che cambiano partito devono assumere velocemente credibilit\u00e0 nella nuova formazione partitica che hanno sposato.<\/p>\n<p style=\"text-align: justify;\">Tuttavia anche questo merita una ulteriore riflessione: il via vai di socialisti diventati interventisti, nazionalisti e poi fascisti negli anni attorno alla Grande Guerra, cos\u00ec come gli intellettuali fascisti diventati, senza grandi traumi, antifascisti o di diverso orientamento ideologico o persino comunisti, durante e dopo la seconda guerra mondiale, dovrebbe favorire una riflessione sul fatto che tutte le diverse ideologie moderne che hanno attraversato la storia italiana facevano tutte riferimento al ceppo risorgimentale, s\u00ec che il passaggio da una all\u2019altra non ha mai implicato radicali conversioni, cambiamenti nella vita e nel modo di pensare paragonabili alle grandi conversioni religiose, per esempio a quelle celebri di sant\u2019Agostino e san Paolo, ma anche a quelle moderne, di quegli stessi anni, penso per esempio a Giovanni Papini (1881-1956).<\/p>\n<p style=\"text-align: justify;\">Naturalmente questa considerazione non diminuisce il grande trauma della guerra civile ma, in un certo senso, lo rende ancora pi\u00f9 incomprensibile, proprio per il fatto che gli attori di questa ferita inferta al corpo della nazione nella realt\u00e0, nel loro modo di pensare e di vivere, si distinguevano fra loro molto meno di quanto si creda.<\/p>\n<p style=\"text-align: justify;\"><strong>Indicazioni bibliografiche<\/strong><\/p>\n<p style=\"text-align: justify;\">Su entrambi i temi la bibliografia \u00e8 sterminata. Mi limito a segnalare i testi che hanno ispirato queste note e quelli che mi paiono utili a &#8220;introdursi&#8221; nel problema del rapporto fra Risorgimento e Resistenza.<\/p>\n<p style=\"text-align: justify;\">Sulla &#8220;questione romana&#8221;, cfr. Renato Cirelli, <em><a href=\"http:\/\/www.alleanzacattolica.org\/idis_dpf\/voci\/q_questione_romana.htm\" target=\"_blank\">La Questione romana (1860-1929)<\/a><\/em> in <em>Voci per un Dizionario del Pensiero Forte<\/em>. (<a target=\"_self\">www.alleanzacattolica.org<\/a>), e Idem, <em>La Questione Romana. Il compimento dell\u2019unificazione che ha diviso l\u2019Italia<\/em>, Mimep-Docete, Pessano (Milano) 1997. Sulla &#8220;questione meridionale&#8221; cfr. Francesco Pappalardo, <em><a href=\"http:\/\/www.alleanzacattolica.org\/idis_dpf\/voci\/q_questione_mezzogiorno.htm\" target=\"_blank\">La questione meridionale<\/a><\/em> in <em>Voci per un Dizionario del Pensiero Forte<\/em> (<a target=\"_self\">www.alleanzacattolica.org<\/a>), e Idem, <em>Giuseppe Garibaldi<\/em>, Sugarco, Milano 2010.<\/p>\n<p style=\"text-align: justify;\">Una cronaca scritta da un contemporaneo e critica del Risorgimento \u00e8 quella di Patrick Keyes O\u2019 Clery, <em>La Rivoluzione italiana. Come fu fatta l\u2019unit\u00e0 della nazione<\/em>, trad. it., Ares, Milano 2000. Di F. Pappalardo sar\u00e0 disponibile dal mese di giugno <em>Il Risorgimento<\/em>, Quaderni del Timone, Milano 2010, una introduzione accessibile al tema con bibliografia. Molto utile, per le recensioni di opere sul Risorgimento e per altri articoli sul tema, il sito dell\u2019Istituto Storico dell\u2019Insorgenza e per l\u2019Identit\u00e0 Nazionale <em>Storia&amp;Identit\u00e0. Annali Italiani<\/em> online (<span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.identitanazionale.it\/\">http:\/\/www.identitanazionale.it\/<\/a><\/span>).<\/p>\n<p style=\"text-align: justify;\">Uso il termine &#8220;senso comune&#8221; nel significato esposto nelle opere di mons. Antonio Livi, sintetizzate nella voce <em><a href=\"http:\/\/www.alleanzacattolica.org\/idis_dpf\/voci\/s_senso_comune.htm\" target=\"_blank\">senso comune<\/a><\/em>, redatta da Giovanni Cantoni in <em>Voci per un Dizionario del Pensiero Forte<\/em> (<a target=\"_self\">www.alleanzacattolica.org<\/a>).<\/p>\n<p style=\"text-align: justify;\">Sulla Resistenza una introduzione importante e accessibile anche al non specialista \u00e8 l\u2019opera di Renzo De Felice (1929-1996), <em>Rosso e Nero<\/em>, a cura di Pasquale Chessa, Baldini &amp; Castoldi, Milano 1995. Pi\u00f9 complessa ma di grande importanza per chi volesse approfondire \u00e8 l\u2019opera dello stesso De Felice, <em>Mussolini l\u2019alleato<\/em>, vol. II, <em>La guerra civile (1943-1945)<\/em>, Einaudi, Torino 1997.<\/p>\n<p style=\"text-align: justify;\"><strong>Nota<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(1)<\/strong> Cfr. Giorgio Napolitano, <em>Allocuzione rivolta al Ministro per lo Sviluppo Economico e ai componenti della Consulta per l\u2019emissione di Carte Valori Postali e la Filatelia e della Commissione per lo Studio e l\u2019Elaborazione delle Carte Valori Postali, in occasione della presentazione dei quattro francobolli celebrativi del 150\u00b0 anniversario della Spedizione dei Mille<\/em>, Roma, 15 aprile 2010, in http:\/\/ www.quirinale.it\/ qrnw\/ statico\/ eventi\/ 150italia-unita\/ documenti\/ quirinale15aprile2010.htm, consultato il 4-5-2010.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalla newsletter dell\u2019Istituto Storico dell&#8217;Insorgenza e per l&#8217;Identit\u00e0 Nazionale (ISIIN) del 9 maggio 2010 I due &#8220;pilastri&#8221; del sentimento di appartenenza nazionale: Risorgimento e Resistenza, non sono considerati del tutto tali dalla comunit\u00e0 nazionale. Ecco perch\u00e8. di Marco Invernizzi<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27335,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100,101,96],"tags":[423,2406],"class_list":["post-3828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resistenza","category-risorgimento","category-storia-italiana","tag-resistenza-2","tag-risorgimento","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Risorgimento e Resistenza, due nodi della storia italiana - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risorgimento e Resistenza, due nodi della storia italiana - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-18T07:38:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-10T13:29:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/museo-risorgimento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Risorgimento e Resistenza, due nodi della storia italiana\",\"datePublished\":\"2010-05-18T07:38:50+00:00\",\"dateModified\":\"2015-11-10T13:29:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/\"},\"wordCount\":2705,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/museo-risorgimento.jpg\",\"keywords\":[\"resistenza\",\"Risorgimento\"],\"articleSection\":[\"Resistenza\",\"Risorgimento\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/\",\"name\":\"Risorgimento e Resistenza, due nodi della storia italiana - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/museo-risorgimento.jpg\",\"datePublished\":\"2010-05-18T07:38:50+00:00\",\"dateModified\":\"2015-11-10T13:29:47+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/museo-risorgimento.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/museo-risorgimento.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Risorgimento e Resistenza, due nodi della storia italiana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risorgimento e Resistenza, due nodi della storia italiana - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/","og_locale":"it_IT","og_type":"article","og_title":"Risorgimento e Resistenza, due nodi della storia italiana - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2010-05-18T07:38:50+00:00","article_modified_time":"2015-11-10T13:29:47+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/museo-risorgimento.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Risorgimento e Resistenza, due nodi della storia italiana","datePublished":"2010-05-18T07:38:50+00:00","dateModified":"2015-11-10T13:29:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/"},"wordCount":2705,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/museo-risorgimento.jpg","keywords":["resistenza","Risorgimento"],"articleSection":["Resistenza","Risorgimento","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/","name":"Risorgimento e Resistenza, due nodi della storia italiana - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/museo-risorgimento.jpg","datePublished":"2010-05-18T07:38:50+00:00","dateModified":"2015-11-10T13:29:47+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/museo-risorgimento.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/05\/museo-risorgimento.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/risorgimento-e-resistenza-due-nodi-della-storia-italiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Risorgimento e Resistenza, due nodi della storia italiana"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3828"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3828\/revisions"}],"predecessor-version":[{"id":27336,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3828\/revisions\/27336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27335"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}