{"id":37870,"date":"2017-06-15T00:00:50","date_gmt":"2017-06-14T22:00:50","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=37870"},"modified":"2017-06-06T09:58:52","modified_gmt":"2017-06-06T07:58:52","slug":"un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/","title":{"rendered":"Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929)"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-37871\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/06\/Dosi_cover.jpg\" alt=\"Dosi_cover\" width=\"139\" height=\"200\" \/>Dal sito<strong> Amici del Timone di Ferrara<\/strong> venerd\u00ec 2 giugno 2017<\/p>\n<p><strong>Paolo M. Siano<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00ab<em>In un certo senso ognuno di noi \u00e8 pertanto un poliziotto-nato, per la propria costituzione psicofisiologica ereditaria [&#8230;]. Possiamo cio\u00e8 non conoscere qualche cosa, ma non vi \u00e8 nulla di occulto; col tenace lavoro tutto si pu\u00f2 sapere<\/em>\u00bb [1] (Commissario-Capo Giuseppe Dosi)<\/p>\n<p style=\"text-align: center;\">* * *<\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>1. Brevi note biografiche<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Giuseppe Dosi (1891-1981)<\/strong> \u00e8 stato un brillante investigatore della Polizia italiana in servizio dal 1912 al 1956. Nell\u2019arco di 43 anni ha vissuto successi investigativi, promozioni (Delegato di PS, Commissario, Commissario-Capo, Vice-Questore, Questore, Capo dell\u2019Interpol italiana, Ispettore Generale Capo) ma anche grandi sofferenze. Tra il 1927 e il 1941, <em>a<\/em><em> causa della sua tenacia e perspicacia nelle indagini sul<\/em> \u00abMostro di Roma\u00bb (che indicher\u00f2 con la sigla: <strong>MdR<\/strong>), ha sub\u00ecto da parte di superiori: trasferimenti; sospensioni dal servizio e dallo stipendio (con grandi disagi familiari); ostruzione alle indagini; controlli e pedinamenti; scassinamento della scrivania del suo ufficio (al Ministero degli Interni, <em>Divisione Affari Generali e Riservati<\/em> \u2013 DAGR) da parte di ignoti in cerca del suo dossier sul \u00abMostro di Roma\u00a0[2]; cacciato improvvisamente dal suo ufficio DAGR; sequestro di una sua pubblicazione; arresto, diffamazione, calunnia, internamento in un manicomio (per 17 mesi, dal 1939 al 1941)\u00a0[3], perdita del lavoro di poliziotto&#8230; Con la liberazione di Roma (1944), in veste di giornalista e informatore sar\u00e0 assunto dal Servizio di controspionaggio americano in Italia, e finalmente, grazie agli Alleati, nel 1947 (guarda caso, dopo la morte del Rev. Brydges, di cui parler\u00f2 pi\u00f9 avanti) Dosi ottiene la riabilitazione nella Polizia italiana e ulteriori promozioni.<\/p>\n<p style=\"text-align: justify;\">Per uno sguardo complessivo su questa storia avvincente (di cui si potrebbe fare un film!) segnalo anzitutto il libro autobiografico di Dosi, incentrato, come la sua carriera, sul caso MdR, \u201c<strong><em>Il mostro e il detective<\/em><\/strong>\u201d (Vallecchi editore, Firenze <strong>1973)<\/strong>. Rimando anche ai contributi raccolti nel volume, scaricabile <em>on-line<\/em>, \u201c<strong><em>Giuseppe Dosi, il poliziotto artista che invent\u00f2 l\u2019Interpol italiana<\/em><\/strong>\u201d, pubblicato nel <strong>2015<\/strong> dall\u2019Ufficio Storico della Polizia di Stato a cura del Dr. Raffaele Camposano\u00a0[4].<\/p>\n<p style=\"text-align: justify;\"><strong>2. Commissario Dosi <em>vs<\/em>. Rev. Brydges<\/strong><\/p>\n<p style=\"text-align: justify;\">Tra il 1924 e il 1927, a Roma, vengono seviziate 7 bambine (la pi\u00f9 piccola, 18 mesi; la pi\u00f9 grande, 9 anni) di cui 4 rimangono uccise (per strangolamento o choc traumatico); probabilmente le altre 3 evitano la morte per circostanze fortuite che hanno costretto l\u2019aggressore ad allontanarsi [5]. Tali delitti, attribuiti ad uno stesso individuo, il \u00abMostro di Roma\u00bb, rischiano di minare la credibilit\u00e0 del Governo di Mussolini che promette all\u2019Italia ordine e sicurezza. Autorit\u00e0, stampa e opinione pubblica premono perch\u00e9 si trovi il colpevole, al pi\u00f9 presto.<\/p>\n<p style=\"text-align: justify;\"><strong>2.1. Breve cronologia delle indagini di Dosi<\/strong><\/p>\n<p style=\"text-align: justify;\">Nel <strong>1927<\/strong> Dosi, Commissario-Capo dalla <em>Divisione Affari Generali e Riservati<\/em> (DAGR) del Ministero dell\u2019Interno, riceve dal Capo della Polizia, <strong>Arturo Bocchini (1880-1940)<\/strong>, l\u2019incarico di occuparsi del MdR. Dosi esamina atti e verbali dei delitti e dei soprallugohi, esegue nuovi sopralluoghi, ascolta testimoni.<\/p>\n<p style=\"text-align: justify;\">Verso il <strong>24<\/strong> <strong>aprile 1927<\/strong>, da Capri, il Commissario di PS Raffaele Ferraro informa Dosi di aver arrestato a Capri un pastore anglicano, il <strong>Rev. Ralph Lyonel Brydges<\/strong> <strong>[1856-1946]<\/strong>, colto in flagrante mentre violentava una bambina inglese (Patricia, 9 anni). Trasferito a Napoli, difeso dall\u2019Ambasciata britannica, poi scarcerato per \u00abdemenza senile\u00bb, senza nessuna misura cautelare, Brydges lascia indisturbato l\u2019Italia. Dosi indaga coadiuvato in particolare dal maresciallo di PS cav. Angelo Bollici e giunge a trovare, contro il Rev. Brydges, ben 43 indizi che col passare del tempo diventano 90.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-37872\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/06\/Girolimoni.jpg\" alt=\"Girolimoni\" width=\"167\" height=\"200\" \/>Il <strong>02 maggio 1927<\/strong> viene arrestato come MdR <strong>Gino Girolimoni<\/strong> <strong>(1889-1961)<\/strong>, un mediatore di cause per infortuni, ma non tutti i poliziotti sono convinti della sua colpevolezza&#8230; Dosi entra in contrasto con alcuni suoi superiori di PS (soprattutto con Bocchini) e con la Questura di Roma che invece avevano sostenuto la colpevolezza di Girolimoni. <em>Brydges viene \u201ccoperto\u201d, pare, per motivi politici: \u00e8 un ecclesiastico anglicano, suddito del Regno Unito col quale Mussolini vuole avere buoni rapporti\u00a0<\/em>[6].<\/p>\n<p style=\"text-align: justify;\">Dopo 11 mesi di carcere, l\u2019<strong>8 marzo 1928 <\/strong>Girolimoni, difeso dall\u2019Avv. Ottavio Libotte, viene assolto dal giudice istruttore Rosario Marciano, dopo che anche il pubblico ministero Mariangeli ne aveva chiesto l\u2019assoluzione per non aver commesso il fatto. C\u2019erano discordanze tra le varie testimonianze raccolte contro Girolimoni sia prima che dopo l\u2019arresto. La notizia dell\u2019assoluzione non riceve risonanza mediatica, per non compromettere la credibilit\u00e0 delle Autorit\u00e0 che lo avevano accusato\u00a0[7].<\/p>\n<p style=\"text-align: justify;\">Tra il <strong>1927<\/strong> e il <strong>1928<\/strong>, vengono trasferiti i poliziotti che si sono occupati di Brydges: il Commissario Ferraro e i due brigadieri che lo hanno arrestato a Capri, poi il commissario Dosi e il maresciallo Bollici, che hanno indagato su di lui [8]. La scrivania dell\u2019ufficio di Dosi al Ministero dell\u2019Interno (DAGR) viene <strong>scassinata<\/strong> da ignoti in cerca del dossier sul <em>MdR-Brydges<\/em> che Dosi provvidenzialmente aveva lasciato a casa&#8230;[9]<\/p>\n<p style=\"text-align: justify;\">Le indagini di Dosi vengono ostacolate, ma dopo varie peripezie, riesce a venire assunto e protetto dal Consigliere Istruttore di Roma, il magistrato Rosario Marciano, il quale dopo le informative di Dosi, si convincer\u00e0 a imputare Brydges come MdR [10]. Dosi riesce a scoprire che Brydges sta per ritornare, sia pure di passaggio, in Italia. E cos\u00ec il <strong>13 aprile 1928<\/strong>, nel porto di Genova, con il mandato del Consigliore Istruttore Rosario Marciano, e l\u2019ausilio di colleghi fidati (tra cui il Questore di Genova), Dosi ferma Brydges a bordo di uno scafo inglese diretto dal Sud Africa a Londra. Brydges viene arrestato e trasferito a Roma. Dosi vuol far perquisire anche altri luoghi legati alla presenza del pastore anglicano. Brydges viene internato nel padiglione criminale del nosocomio di Santa Maria della Piet\u00e0, poi viene dimesso e lascia definitivamente l\u2019Italia (<strong>1929<\/strong>), sempre protetto dall\u2019Ambasciata britannica di Roma\u00a0[11].<\/p>\n<p style=\"text-align: justify;\">Dosi scopre anche che verso il <strong>1927<\/strong> \u00e8 avvenuto un tentativo <strong>depistaggio <\/strong>delle indagini da parte di un giornalista de \u201c<em>L\u2019Italie<\/em>\u201d (Silvio M.) che \u00e8 riescito a ottenere da Mussolini e dalla Polizia il permesso di consultare i verbali sui delitti e sui sopralluoghi&#8230; Sulla scena del delitto Leonardi (<strong>1927<\/strong>) vengono rinvenuti <em>pezzi bruciati di un catalogo di libri inglesi e allegati al fascicolo<\/em>, ma in seguito non vengono pi\u00f9 trovati. Spariti! Dosi scopre che quel giornalista \u00e8 nato a Malta, perci\u00f2 \u00e8 <em>un suddito (agente?) britannico<\/em>! Silvio M. cerca di convincere il giudice Marciano che il MdR non pu\u00f2 essere Brydges (su cui Marciano stava istruendo il procedimento penale!), n\u00e9 Girolimoni (in precedenza accusato da Silvio M.), ma uno spazzino che lavorava vicino alla redazione del suo giornale&#8230; [12]<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35542 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/01\/Roma.jpg\" alt=\"Roma\" width=\"282\" height=\"179\" \/>Poco dopo il delitto Leonardi, Brydges lascia Roma e va a Capri (1927), dove verr\u00e0 arrestato in flagranza di pedofilia\u00a0[13]. Dosi sospetta che quel Silvio abbia sottratto quei pezzi di cataloghi..[14] In seguito <em>anche il magistrato Marciano verr\u00e0<\/em>\u00abinquisito, pedinato, diffamato\u00bb da coloro che volevano Girolimoni \u00a0colpevole&#8230;[15]<\/p>\n<p style=\"text-align: justify;\">Nel <strong>1928<\/strong>, il famoso gesuita P. Tacchi Venturi, molto stimato da Mussolini, comunica a Dosi che (parole di Dosi) \u00abil Vaticano era rimasto indignato per il trattamento di favore che, su intervento dell\u2019ambasciata britannica, era stato prodigato, all\u2019immondo pastore anglicano, delle cui sconcezze conosceva i dettagli!\u00bb\u00a0[16].<\/p>\n<p style=\"text-align: justify;\">Il <strong>23 ottobre 1929<\/strong>, la Corte d\u2019Appello di Roma assolve Brydges da ogni imputazione, anche dal reato di oltraggio al pudore [Roma, agosto 1925; Capri, aprile 1927 [17]. Eppure (osserva Dosi), la Corte ammette che l\u2019alibi di Brydges per il delitto Tagliaferri (agosto \u201925) potrebbe essere falso e precostituito&#8230; [18]<\/p>\n<p style=\"text-align: justify;\"><strong>2.2. Elementi investigativi sul Rev. Brydges<\/strong><\/p>\n<p style=\"text-align: justify;\">Nel corso delle sue indagini, Dosi scopre e raccoglie numerosi elementi sul conto di Brydges (che Dosi, ancora nel 1973, definisce \u00abimmondo pastore\u00bb\u00a0[19]) di cui elenco solo alcuni:<\/p>\n<p><strong>\u00a0<\/strong><strong>&#8211; Pedofilo notorio.<\/strong><\/p>\n<p style=\"text-align: justify;\">Brydges \u00e8 dedito all\u2019alcol\u00a0[20] ed \u00e8 notoriamente un pedofilo molestatore di bambine (gi\u00e0 in America). A Capri, il 23 aprile <strong>1927<\/strong> Brydges violenta una bambina inglese di 9 anni e fugge al sopraggiungere di una signorina che lo segnaler\u00e0 alle Autorit\u00e0. La bimba aveva arrossamenti ed escoriazioni alla zona pubica, come se fosse stata \u00ab<strong>succhiata<\/strong>\u00bb<span style=\"color: #074d7c;\"><span style=\"background-color: #d5d5d5;\">\u00a0<\/span><\/span>\u00a0[21]. Poi la Polizia lo arresta in flagrante mentre cerca di violentare nuovamente quella bambina a cui succhia e morde i genitali, ed \u00e8 cos\u00ec preso dalla passione da non accorgersi che in quel momento piombano su di lui il Commissario di PS Ferraro con due brigadieri e il podest\u00e0 di Capri il quale \u00e8 costretto a sferrargli un pugno per strappargli la bambina. Gi\u00e0 il podest\u00e0, marchese Marino Dusmet, e il Commissario Ferraro intuiscono che Brydges possa essere il MdR\u00a0[22] ! Almeno l\u2019ultima vittima del MdR (la Leonardi-<strong>1927<\/strong>) fu \u2013 rileva l\u2019autopsia \u2013 anche \u00ab<strong>succhiata<\/strong>\u00bb\u00a0[23].<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30221 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/marcia_Roma.jpg\" alt=\"marcia_Roma\" width=\"260\" height=\"194\" \/>Il <strong>27 aprile 1927<\/strong> il Commissario Ferraro segnala Brydges ai superiori romani di PS, ma questi rispondono che <em>non pu\u00f2 essere il MdR anche perch\u00e9 \u00e8 conosciuto favorevolmente dal console inglese<\/em>&#8230; Eppure era notorio che Brydges molestava anche le bambine delle famiglie che frequentavano la sua chiesa anglicana in Roma. Intanto si preferisce seguire la pista Girolimoni, arrestato proprio pochi giorni dopo, il 02 maggio [24]. In una lettera del 1930 indirizzata a Dosi, il Dr. Raffaele Gasbarri, ex direttore generale di PS (gi\u00e0 superiore e amico di Dosi), deplora che dopo l\u2019arresto caprese non venne effettuata la necessaria perquisizione al domicilio romano di Brydges, <em>in cui era impossibile non rinvenire elementi utili a identificare il MdR\u00a0<\/em>[25].<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Presenza in Italia<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Brydges \u00e8 <strong>certamente <\/strong>in Italia all\u2019epoca dei 7 crimini romani; inoltre pu\u00f2 essere stato anche sulla scena dello stupro di Celeste Tagliaferri (agosto 1925), avendo tutto l\u2019agio di scendere da Cortina d\u2019Ampezzo a Roma e poi risalire a Cortina d\u2019Ampezzo dov\u2019era in villeggiatura (senza esser visto n\u00e9 dalla moglie, assente, n\u00e9 dalla servit\u00f9 impegnata con tanti clienti, data l\u2019alta stagione estiva). A Roma, nell\u2019agosto 1925, Brydges \u00e8 riconosciuto da due signorine metodiste [26] mentre cerca di adescare delle bambine a Villa Borghese (Roma), poco dopo il caso Tagliaferri\u00a0[27]. <strong><em>I delitti del MdR si sono svolti tra l\u2019arrivo in Italia e la partenza dall\u2019Italia del Rev. Brydges. Dopo, quei delitti non sono pi\u00f9 avvenuti\u00a0<\/em><\/strong>[28].<\/p>\n<p><strong>&#8211; Sempre in giorni feriali<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Adescamenti e delitti del MdR non avvengono mai nelle domeniche e nei giorni festivi (giorni in cui Brydges era impegnato nel culto anglicano)&#8230;[29]<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong>Descrizione fisica del mostro<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Brydges corrisponde alle descrizioni del MdR fornite da vari testimoni. Il MdR \u00e8 un uomo alto, circa 1, 70 o pi\u00f9, di mezza et\u00e0, piccoli baffi biondi, agile nei movimenti, ben vestito, elegante<a name=\"_ftnref30\"><\/a> [30]; portava \u00ab<strong><em>occhiali a stanghetta di metallo bianco<\/em><\/strong>\u00bb\u00a0[31]; non parlava romanesco ma italiano\u00a0[32], \u00ab<strong>non capiva bene l\u2019italiano<\/strong>\u00bb\u00a0[33]; viso lentigginoso, scarpe gialle, colorito bruno, pi\u00f9 alto di Girolimoni \u00abcon <strong>baffi all\u2019americana<\/strong>, brizzolati\u00bb\u00a0[34]. Alcune testimonianze indicano il MdR come un giovane di 30-40 anni. Al riguardo Dosi osserva che Brydges <strong>si tingeva baffi e capelli (con una tintura fatta venire dall\u2019Inghilterra)<\/strong>, aveva pelle rosea, fisico aitante, camminatore, nuotatore, alpinista, guardaroba ben fornito, insomma capace di modificare il suo aspetto\u00a0[35]. In effetti Brydges \u00e8 alto 1,77, molto svelto nei movimenti, sebbene abbia 71 anni, ne mostra non pi\u00f9 di 50-55, con cappelli bianco-biondicci, pelle semolata e sanguigna, corporatura robusta, nell\u2019insieme appare giovanile. Talvolta usa <strong>occhiali a stanghetta\u00a0<\/strong>[36]. Dosi osserva che per tentare di adescare una bambina piccola non era necessario un lungo discorso e varie testimonianze dicono che il MdR parlava italiano ma con accento straniero\u00a0[37].<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Occhiali con stanghetta<\/strong>.<\/p>\n<p>Il MdR viene visto con \u00abocchiali con fusto bianco\u00bb. Nel perquisire il bagaglio di Brydges, Dosi rinvenne undici paia di occhiali, \u00abfra cui uno con montatura in celluloide bianca!\u00bb [38].<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong>Un <\/strong>\u00ab<strong>fiumarolo<\/strong>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il MdR deve avere dimestichezza col fiume, muovendosi di sera, ai margini della corrente impetuosa, scavalcando un rigagnolo di fogna (es. scena delitto Berni)\u00a0[39]. Al tempo dei delitti del MdR, Brydges era <em>socio di una societ\u00e0 romana di nuoto e frequentava assiduamente il fiume <\/em>[40].<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; I quattro fazzoletti<\/strong>.<\/p>\n<p style=\"text-align: justify;\">I quattro fazzoletti rinvenuti rispettivamente sui luoghi di quattro delitti sono simili a quelli rinvenuti nel bagaglio di Brydges durante la perquisizione (1928)\u00a0[41]. Cito solo un reperto. Nel sopralluogo del caso Giacomini (31-3-1924) viene rinvenuto anche <strong>un fazzoletto colorato<\/strong> con cui il mostro aveva stretto il collo della piccola Emma. Era un fazzoletto di tipo \u201cscozzese\u201d, prodotto a Manchester (Inghilterra) e, all\u2019epoca, a Roma non ce n\u2019erano pi\u00f9 in vendita [42]. Nel <strong>1928<\/strong>, dinanzi a Dosi e a due magistrati, la cameriera valdese di Brydges depone sotto giuramento che conosceva quel fazzoletto avendolo lavato e stirato pi\u00f9 volte in casa del suddetto pastore\u00a0[43].<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Bottone.<\/strong><\/p>\n<p style=\"text-align: justify;\">Sulla scena del crimine del 31-3-1924, viene trovato anche un bottone d\u2019osso bianco, diametro 16 mm, di mutande da uomo<a name=\"_ftnref44\"><\/a> [44]. Dosi trova un bottone uguale nel bagaglio di Brydges\u00a0[45].<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Alcuni luoghi frequentati<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Lydia, cameriera valdese dei Brydges, riferisce a Dosi che il suo padrone andava talvolta anche a Monte Mario e Piazza Cavour&#8230; Dosi osserva che proprio in quelle zone iniziarono i crimini del MdR\u00a0[46].<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Pezzi di catalogo di libri ascetici inglesi<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Sul luogo del delitto Leonardi (1927) vengono ritrovati pezzi bruciati di recente di un catalogo di libri ascetici inglesi, simile a quelli che Brydges riceveva\u00a0[47]. A Roma Dosi sequestra il catalogo di libri inglesi <em>per l\u2019anno 1928<\/em>, che la libreria Mowbrary di Londra inviava ai primi di Quaresima ai 4 pastori anglicani cappellani in Roma. In effetti anche il delitto di Armanda Leonardi, 12 marzo <strong>1927<\/strong>, coincideva con gli inizi della Quaresima\u00a0[48].<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Valigetta quadrata ai lati<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Il MdR \u00e8 stato visto con quel tipo di valigetta. Dosi scopre che si tratta di una valigetta chiamata <strong>\u201cLondon\u201d<\/strong>, usata da preti stranieri e cappellani militari. In effetti Brydges era stato cappellano militare del contingente britannico nelle Fiandre, durante la prima guerra mondiale, e aveva una valigetta di quel tipo [49].<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Abito grigio puntellato di bianco<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Al tempo del delitto Carlieri, quell\u2019abito di stoffa tipicamente inglese viene visto indosso al MdR. Dosi sequestr\u00f2 quell\u2019abito al portiere di un albergo di Capri a cui Brydges l\u2019aveva regalato&#8230; [50]<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Taccuino<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Nel bagaglio di Brydges sequestrato da Dosi, c\u2019\u00e8 un taccuino con foglietti strappati, dove sono annotati: la parola \u00abCharlieri\u00bb (con l\u2019acca), praticamente il cognome della seconda vittima; la parola \u201cCol\u201d (via del Colonnato, dove abitava Rosina Pelli), e l\u2019annotazione precisa della casa della vittima (\u00ab<em>Piazza San Pietro-House, at end, big, old, 4 piano<\/em>\u00bb\u00a0[51].<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Capace di compiere i delitti del MdR<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Tale il giudizio del prof. Sante De Santis (psichiatra e docente universitario) sul Brydges arrestato e rinchiuso nel padiglione 18 del manicomio criminale romano\u00a0[52]. Ma dopo tre mesi, Brydges \u00e8 rimesso in libert\u00e0 e parte per Toronto\u00a0[53].<\/p>\n<p><strong>&#8211; Massone<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-32999 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/massoneria.jpg\" alt=\"massoneria\" width=\"180\" height=\"180\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/massoneria.jpg 180w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/massoneria-150x150.jpg 150w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/>Ecco un particolare interessante, non evidenziato negli articoli <em>on-line <\/em>sul caso MdR: nella perquisizione della cabina di Brydges, tra i vari documenti personali del pastore anglicano, Dosi (che dice di menzionarne solo alcuni) ha rinvenuto \u00ab<strong>un certificato della\u00a0<em>Gran Loggia Massonica<\/em>, di New-York, dal quale risultava che il Brydges era iscritto, dal 1910, ad una loggia di quella metropoli<\/strong>\u00bb\u00a0[54]. Brydges era anche membro della \u00abSociet\u00e0 protezione animali di Roma\u00bb\u00a0[55]. Sul Brydges massone, Dosi non dice niente di pi\u00f9.<\/p>\n<p style=\"text-align: justify;\">A questo punto aggiungo alcuni approfondimenti personali. Una <em>societ\u00e0 regia per la protezione degli animali<\/em> \u00e8 stata fondata a Torino nel 1871 da Giuseppe Garibaldi e lady Anna Winter. Nella fondazione ebbe parte anche il medico personale di Garibaldi, Timoteo Riboli\u00a0[56]<em>.<\/em> Garibaldi e Riboli erano massoni. <em>A Roma, Brydges ebbe contatti massonici?<\/em><\/p>\n<p style=\"text-align: justify;\">Mi chiedo anche: <em>oltre alla cittadinanza britannica e al suo <\/em>status <em>clericale nella Chiesa Anglicana, anche l\u2019appartenenza alla Massoneria, in quell\u2019epoca, \u00e8 stata per Brydges un \u201cpass-partout\u201d di impunit\u00e0?<\/em> <em>I diplomatici britannici che si attivarono per proteggere il Rev. Brydges<span style=\"color: #1772af;\"><span style=\"background-color: #d5d5d5;\">\u00a0<\/span><\/span><\/em>[57] (sono riuscito a rintracciarne i nomi), <em>ossia l\u2019allora Console di Napoli (dal 1927 al 1930) Victor Henry St. John HUCKIN (1880-1943) e l\u2019allora Ambasciatore del Regno Unito in Italia, Sir Ronald William Graham (1870-1949) erano massoni?<\/em> Domande, per ora, senza risposta.<\/p>\n<p style=\"text-align: justify;\">\u00c8 interessante notare che un giornale romano del 1924 (Dosi non precisa quale) asser\u00ec, circa l\u2019assassino della bambina [Carlieri]: \u00ab<strong>l\u2019ignoto mostro, recante in s\u00e9 due immagini: quella dell\u2019Angelo e quella di Satana!<\/strong>\u00bb\u00a0[58]. Perch\u00e9 quel giornale ha fatto ricorso a una <em>tale unione degli Opposti<\/em>? <em>Allusioni esoteriche<\/em>&#8230;? Forse gi\u00e0 si percepiva (o si sapeva?) che l\u2019assassino appariva come una persona assai distinta e quasi \u201cangelica\u201d ? Un tale identikit psico-spirituale poteva applicarsi pi\u00f9 al Brydges (ministro di culto anglicano) che al Girolimoni&#8230;<\/p>\n<p style=\"text-align: justify;\">\u00c8 interessante sapere che Dosi ha indagato anche sulla Massoneria. Nel dettagliato studio sull\u2019Archivio Dosi, presso il Museo Storico della Liberazione (sito a Roma in Via Tasso, laddove c\u2019era il quartier generale delle SS tedesche che fuggendo nel 1944 abbandonarono molta documentazione, poi recuperata da Dosi e consegnata agli Alleati), la Dr.ssa Alessia Glielmi (responsabile degli Archivi del suddetto Museo) annovera tra il materiale non ancora inventariato (II versamento, N. 22):<\/p>\n<p style=\"text-align: justify;\">\u00ab22. \u201cN. 15. I miei rapporti di non massone con la massoneria ed il suo Gran Maestro. Studi ed investigazione massoniche a Roma Parigi, Bruxelles, documenti e stampa massonica. Roma 1922\/23, 1924\/25\u201d. Album con ritagli, manifesti, opuscoli sull\u2019attivit\u00e0 delle logge massoniche italiane ed europee. 1922-1945\u201d\u00bb [59].<\/p>\n<p style=\"text-align: justify;\">Dunque, dal 1922 al 1945, Dosi, non massone, ha avuto rapporti con la Massoneria e con un non precisato Gran Maestro, compiendo investigazioni in quelle tre citt\u00e0 europee e raccogliendo documentazione massonica. Suppongo si tratti di materiale interessantissimo, purtroppo, al momento, non ancora inventariato. Attendiamo.<\/p>\n<p style=\"text-align: justify;\">In un breve ma documentato saggio, il prof. Aldo Mola mostra che molti massoni erano inseriti nel Fascismo&#8230; Tra gli informatori dell\u2019OVRA (la polizia politica segreta, dipendente dal Capo PS, Arturo Bocchini) figurava anche (secondo una lista) il Gran Maestro della Massoneria di Piazza del Ges\u00f9, Raoul Vittorio Palermi (1864-1948), poi il massone Mario Pistocchi, il mago e massone rosacrociano Giuseppe Cambareri (1901-1972)&#8230; Cambareri propose a Mussolini di usare la sua <em>Fraternitas Rosicruciana Antiqua<\/em> come strumento di collegamento col mondo anglo-americano e l\u2019esperimento and\u00f2 avanti almeno fino al 1938&#8230; [60]<\/p>\n<p style=\"text-align: justify;\">Pertanto vien da chiedersi se <em>all\u2019interno della rete OVRA (dipendente da Bocchini, superiore della PS e quindi della DAGR cui apparteneva Dosi) qualche massone abbia influito su Bocchini per indurlo a render difficile la vita a Dosi, \u201ccolpevole\u201d di perseguire un \u201cFratello\u201d inglese<\/em>&#8230; Chiss\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>3. Fede, umanit\u00e0 e professionalit\u00e0 di un Commissario<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-15090\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/01\/Pio-XII.jpg\" alt=\"Pio XII\" width=\"151\" height=\"200\" \/>Dosi \u00e8 stato giustamente definito: \u00abun uomo dalle mille doti, doti non sempre comprese ed apprezzate\u00bb, \u00abun grande poliziotto ed un investigatore come pochi\u00bb, dotato di \u00abcaparbiet\u00e0 nel seguire una pista\u00bb e di \u00abgrande istinto\u00bb e \u00abintuizione\u00bb\u00a0[61]. Dosi non si \u00e8 mai piegato \u00aballe lusinghe politiche e alla logica dei comodi opportunismi\u00bb\u00a0[62].<\/p>\n<p style=\"text-align: justify;\">Dal libro autobiografico del 1973, emerge l\u2019aspetto umano di Dosi, la sua grande esperienza di uomo e poliziotto, e anche la sua fede cristiana. Ha ricevuto buona educazione familiare, ha sempre fuggito da frasi scurrili, parolacce e bestemmie, pur avendo dovuto frequentare ambienti luridi quali quelli malavitosi\u00a0[63].<\/p>\n<p style=\"text-align: justify;\">Dosi crede, non nel Destino, ma in Dio e nella Sua Divina Provvidenza [64]. Ha ricevuto una sana educazione ed istruzione religiosa, conosce \u00abil Vaticano e i problemi di quell\u2019ambiente\u00bb, e la fede cattolica gli \u00e8 di grande aiuto e conforto. Dosi, cattolico, fa il suo dovere anche quando deve arrestare dei consacrati (es.: un frate novizio e studente di teologia alla Porziuncola, minorenne, ladro di monete antiche; e un prete di Assisi, omosessuale, adescatore di circa 37 ragazzi di cui abusava dopo avere somministrato loro certi liquori, che dava anche a suore&#8230;) [65].<\/p>\n<p style=\"text-align: justify;\">Dosi ha goduto di \u00abstima e benevolenza\u00bb anche da parte di Papa Pio XII al quale (quando era capo dell\u2019Interpol) presentava tutti i suoi colleghi esteri, \u00abanche protestanti e massoni\u00bb che giungevano a Roma per motivi di servizio o per gite di piacere\u00a0[66]. Come Pio XII, anche Dosi ha avuto buoni rapporti col mondo ebraico dell\u2019epoca\u00a0[67].<\/p>\n<p style=\"text-align: justify;\">Dosi \u00e8 ben consapevole dei propri limiti\u00a0[68] e degli insuccessi cui pu\u00f2 andare incontro \u00abmagari troppo spesso e facilmente, anche il pi\u00f9 diligente ed onesto ufficiale di polizia giudiziaria&#8230;\u00bb [69].<\/p>\n<p style=\"text-align: justify;\">\u00c8 un grande devoto di San Francesco d\u2019Assisi, il \u00abPoverello\u00bb,\u00a0[70] definendolo persino suo \u00abinspiratore\u00bb nelle indagini poliziesche e negli studi per la laurea universitaria conseguita quando era Commissario-Capo ad Assisi. Amico dei frati francescani di Assisi\u00a0[71], Dosi \u00e8 anche esperto cultore degli studi e dei luoghi francescani, socio della \u201c<em>Societ\u00e0 Internazionale di Studi Francescani<\/em>\u201d\u00a0[72]. In un certo senso condivider\u00e0 anche la povert\u00e0 francescana restando senza stipendio (a causa della persecuzione sub\u00ecta per le sue indagini sul MdR)\u00a0[73], fino ad essere \u00abridotto in miseria, con molti debiti\u00bb [74].<\/p>\n<p style=\"text-align: justify;\">Nel secondo dopoguerra, Dosi visita la tomba solitaria e desolata del suo ex superiore Arturo Bocchini (che Dosi chiama: \u00abmio ostinato persecutore\u00bb), morto d\u2019infarto nel 1940, mentre Dosi era internato\u00a0[75]. Dosi gli porta dei fiori dandogli \u00abgeneroso e sincero, un perdono cristiano\u00bb [76], a sua volta chiedendogli perdono dei propri \u00abdifetti di carattere\u00bb che \u2013 ammette Dosi \u2013 avevano potuto concorrere a provocargli i suddetti abusi (trasferimenti, sospensioni&#8230;) [77]. Con fede e umilt\u00e0, l\u2019anziano Dosi commenta: \u00abSiamo tutti \u201cdottori\u201d, ma ci dovremmo considerare ignoranti di tante cose, imperscrutabili, come la volont\u00e0 di Dio&#8230;\u00bb\u00a0[78].<\/p>\n<p style=\"text-align: justify;\">Il credente non far\u00e0 fatica a comprendere che, davvero, Dio e San Francesco hanno aiutato tanto il Dr. Giuseppe Dosi.<\/p>\n<p style=\"text-align: justify;\">__________________________<\/p>\n<p style=\"text-align: justify;\"><strong>[1]<\/strong> G. Dosi, <em>Le informazioni di Polizia<\/em>, in <em>Il Magistrato dell\u2019Ordine<\/em>, Anno VI, n\u00b0 8, 1 agosto 1929, p. 118<\/p>\n<p style=\"text-align: justify;\"><strong>[2]<\/strong> L\u2019episidio \u00e8 descritto da Giuseppe Dosi nel suo libro <em>Il mostro e il detective<\/em>, Vallecchi editore, Firenze 1973, pp. 142-143.<\/p>\n<p style=\"text-align: justify;\"><strong>[3]<\/strong> Commovente e preciso il commento di Ennio Di Francesco (gi\u00e0 Primo Dirigente della Polizia di Stato, alto funzionario dell\u2019Interpol e dell\u2019Europol italiana) sull\u2019ingiusto internamento di Dosi:<\/p>\n<p style=\"text-align: justify;\">\u00abMi sono commosso leggendo presso l\u2019Archivio Centrale di Stato, nel suo ormai logoro fascicolo personale, le 21 fitte sottili pagine della perizia psichiatrica scritte dallo zelante Ispettore Generale Alienista, Dr. Saporito, che con le sue interpretazioni lombrosiane costituir\u00e0 la base della \u201cdispensa dal servizio\u201d di Dosi, con atto firmato dallo stesso Capo della Polizia. Nel fascicolo personale emerge una lettera in cui Dosi parla della sua famiglia, della disperazione che lo porta persino a pensare al suicidio. Altro che mobbing, concetto allora inesistente; tortura psicologica di un uomo caratterialmente tenace che non vuole piegare la sua ansia di verit\u00e0 alla supina obbedienza al Capo e al sistema. Nella silenziosa sala studio dell\u2019Archivio Centrale di Stato mi sono sentito vicino a quel collega di tanti anni addietro che urlava dentro, quasi in un intimo percorso per entrambi catartico\u00bb [E. Di Francesco, <em>Affinit\u00e0 di un Collega e Maestro<\/em>, in R. Camposano (a cura di), <em>Giuseppe Dosi, il poliziotto artista che invent\u00f2 l\u2019Interpol italiana<\/em>, Quaderno 2\/2014, Ufficio Storico della Polizia di Stato, Roma 2015, p. 189 (181-200)].<\/p>\n<p style=\"text-align: justify;\"><strong>[4]<\/strong> <a href=\"https:\/\/www.poliziadistato.it\/statics\/32\/dosi_con_copertine.pdf\">https:\/\/www.poliziadistato.it\/statics\/32\/dosi_con_copertine.pdf<\/a>. Contributi di: Alessandro Pansa (l\u2019allora Capo della Polizia), Carlo Mosca, Raffaele Camposano, Maurizio De Giovanni, Maria Letizia Dosi, Alessia A. Glielmi, Ornella Di Tondo, Michele Di Giorgio, Natale Fusaro, Luca Guardabascio, Ennio Di Francesco.<\/p>\n<p style=\"text-align: justify;\"><strong>[5] <\/strong>Segnalo anzitutto le <strong>7 vittime<\/strong> rapite e stuprate dal MdR, d<strong> cui 4 uccise (2 nel 1924, 1 <\/strong>nel <strong>\u201925, 1 <\/strong>nel <strong>\u201927) <\/strong><\/p>\n<p><strong>&#8211; 31 marzo 1924 <\/strong>(sera): Emma <strong>Giacomini<\/strong> (4 anni e mezzo).<\/p>\n<p><strong>&#8211; 4 giugno 1924 <\/strong>(sera), Bianca <strong>Carlieri<\/strong> (3 anni e 8 mesi), rapita, ritrovata il giorno dopo, nuda, violentata, soffocata, morta per choc traumatico. Nessuna traccia di sperma suoi luoghi dei crimini.<\/p>\n<p><strong>&#8211; 24 novembre 1924<\/strong>: Rosina <strong>Pelli<\/strong> (4 anni), violentata (anche al retto) e uccisa.<\/p>\n<p><strong>&#8211; 30 maggio 1925<\/strong>: Elsa <strong>Berni<\/strong> (6 anni), strangolata.<\/p>\n<p><strong>&#8211; 26 agosto 1925<\/strong>: Celeste Tagliaferri (18 mesi), violentata.<\/p>\n<p><strong>&#8211; 12 febbraio 1926<\/strong>: Elvira Coletti (6 anni), violentata.<\/p>\n<p><strong>&#8211; 12 marzo 1927<\/strong>: Armanda <strong>Leonardi<\/strong> (9 anni), uccisa (asfissia o choc traumatico).<\/p>\n<p>Sulla scena del caso Tagliaferri \u00e8 rinvenuta un\u2019impronta di scarpa cm 27,4 x cm 10,9, con suola a punta larga, semicircolare; simile impronta anche sulla scena delitto Berni. Dosi deduce che si tratta dello stesso individuo (Cf. G. Dosi, <em>Il mostro e il detective<\/em>, op. cit., p. 86).<\/p>\n<p><strong>[6]<\/strong> Cf. N. Fusaro, <em>Giuseppe Dosi e l\u2019arte dell\u2019investigazione<\/em>, in R. Camposano, <em>Giuseppe Dosi, il poliziotto artista che invent\u00f2 l\u2019Interpol italiana<\/em>, op. cit., p. 152 (145-161).<\/p>\n<p style=\"text-align: justify;\"><strong>[7]<\/strong> <a href=\"https:\/\/it.wikipedia.org\/wiki\/Gino_Girolimoni\">https:\/\/it.wikipedia.org\/wiki\/Gino_Girolimoni<\/a>. Girolimoni non riuscir\u00e0 pi\u00f9 a riprendersi, nemmeno economicamente, da quella macchia di infamia. Morir\u00e0 povero e solo nel 1961. Al suo funerale oltre ai pochi amici c\u2019erano il suo avvocato storico Ottavio Libotte e il Dr. Giuseppe Dosi.<\/p>\n<p style=\"text-align: justify;\"><strong>[8]<\/strong> Cf. G. Dosi, <em>Il mostro e il detective<\/em>, op. cit., pp. 145-146.<\/p>\n<p style=\"text-align: justify;\"><strong>[9]<\/strong> Cf. <em>ivi<\/em>, pp. 142-143.<\/p>\n<p style=\"text-align: justify;\"><strong>[10]<\/strong> Cf. <em>ivi<\/em>, p. 187.<\/p>\n<p style=\"text-align: justify;\"><strong>[11]<\/strong> Cf. <em>ivi<\/em>, pp. 189-199.<\/p>\n<p style=\"text-align: justify;\"><strong>[12]<\/strong> Cf. <em>ivi<\/em>, pp. 206-207.<\/p>\n<p style=\"text-align: justify;\"><strong>[13]<\/strong> Cf. <em>ivi<\/em>, p. 162.<\/p>\n<p style=\"text-align: justify;\"><strong>[14]<\/strong> Cf. <em>ivi<\/em>, pp. 207-208.<\/p>\n<p style=\"text-align: justify;\"><strong>[15]<\/strong> Cf. <em>ivi<\/em>, pp. 272-273.<\/p>\n<p style=\"text-align: justify;\"><strong>[16]<\/strong> <em>Ivi<\/em>, p. 213.<\/p>\n<p style=\"text-align: justify;\"><strong>[17]<\/strong> Cf. <em>ivi<\/em>, p. 235.<\/p>\n<p><strong>[18]<\/strong> Cf. <em>ivi<\/em>, p. 239.<\/p>\n<p><strong>[19]<\/strong> Cf. <em>Ivi<\/em>, p. 71.<\/p>\n<p><strong>[20]<\/strong> Cf. <em>ivi<\/em>, p. 211.<\/p>\n<p><strong>[21]<\/strong> Cf. <em>ivi<\/em>, pp. 121-123, neretto mio.<\/p>\n<p><strong>[22]<\/strong> Cf. <em>ivi<\/em>, pp. 124-126.<\/p>\n<p><strong>[23]<\/strong> Cf. <em>ivi<\/em>, p. 95, neretto mio.<\/p>\n<p><strong>[24]<\/strong> Cf. <em>ivi<\/em>, pp. 125-126.<\/p>\n<p><strong>[25]<\/strong> Cf. <em>ivi<\/em>, p. 127.<\/p>\n<p><strong>[26]<\/strong> Cf. <em>ivi<\/em>, pp. 202-205, 210-211.<\/p>\n<p><strong>[27]<\/strong> Cf. <em>ivi<\/em>, p. 235<\/p>\n<p><strong>[28]<\/strong> Cf. <em>ivi<\/em>, pp. 162-163.<\/p>\n<p><strong>[29]<\/strong> Cf. <em>ivi<\/em>, p. 94. Dosi ritiene che il MdR fosse impegnato in quei giorni nelle cerimonie pubbliche della sua chiesa&#8230;<\/p>\n<p><strong>[30]<\/strong> Cf. <em>ivi<\/em>, pp. 74-80.<\/p>\n<p><strong>[31]<\/strong> <em>Ivi<\/em>, p. 81, neretto mio.<\/p>\n<p><strong>[32]<\/strong> Cf. <em>ivi<\/em>, pp. 87-89.<\/p>\n<p><strong>[33]<\/strong> <em>Ivi<\/em>, p. 157, neretto mio.<\/p>\n<p><strong>[34]<\/strong> <em>Ivi<\/em>, p. 158, neretto mio.<\/p>\n<p><strong>[35]<\/strong> Cf. <em>ivi<\/em>, p. 167, p. 240. Dosi osserva anche nel segnalamento descrittivo di polizia, si fa riferimento all\u2019et\u00e0 apparente non a quella anagrafica (cf. <em>ivi<\/em>, p. 240).<\/p>\n<p><strong>[36]<\/strong> Cf. <em>ivi<\/em>, pp. 123-124.<\/p>\n<p><strong>[37]<\/strong> Cf. <em>ivi<\/em>, p. 178.<\/p>\n<p><strong>[38]<\/strong> <em>Ivi<\/em>, p. 161.<\/p>\n<p><strong>[39]<\/strong> Cf. <em>ivi<\/em>, p. 83.<\/p>\n<p><strong>[40]<\/strong> Cf. <em>ivi<\/em>, p. 85.<\/p>\n<p><strong>[41]<\/strong> Cf. <em>ivi<\/em>, p. 45, p. 82, p. 177, p. 197.<\/p>\n<p><strong>[42<\/strong><strong>]<\/strong> Cf. <em>ivi<\/em>, p. 75.<\/p>\n<p><strong>[43]<\/strong> Cf. <em>ivi<\/em>, p. 76.<\/p>\n<p><strong>[44]<\/strong> Cf. <em>ivi<\/em>, p. 75.<\/p>\n<p><strong>[45]<\/strong> Cf. <em>ivi<\/em>, p. 197.<\/p>\n<p><strong>[46]<\/strong> Cf. <em>ivi<\/em>, p. 167.<\/p>\n<p><strong>[47]<\/strong> Cf. <em>ivi<\/em>, p. 43, p. 126, p. 192.<\/p>\n<p><strong>[48]<\/strong> Cf. <em>ivi<\/em>, p. 201.<\/p>\n<p style=\"text-align: justify;\"><strong>[49]<\/strong> Cf. <em>ivi<\/em>, p. 175. Il Canada ottenne l\u2019indipendenza dal Regno Unito nel 1931 e con la costituzione del 1982 ebbe piena sovranit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>[50]<\/strong> Cf. <em>ivi<\/em>, pp. 160-161.<\/p>\n<p style=\"text-align: justify;\"><strong>[51]<\/strong> Cf. <em>ivi<\/em>, p. 181, p. 194. A p. 194, Dosi scrive: \u00abRipeto che su una paginetta d\u2019un taccuino scrisse: \u201c<em>Piazza San Pietro-House at end, big, old, Col&#8230; 4\u00b0 piano<\/em>\u201d e sotto \u201cCharlieri\u201d (con l\u2019acca)\u00bb (<em>ivi<\/em>, p. 194).<\/p>\n<p style=\"text-align: justify;\"><strong>[52]<\/strong> Cf. <em>ivi<\/em>, p. 205.<\/p>\n<p style=\"text-align: justify;\"><strong>[53]<\/strong> Cf. <em>ivi<\/em>, p. 209.<\/p>\n<p style=\"text-align: justify;\"><strong>[54]<\/strong> <em>Ivi<\/em>, p. 193, neretto mio. Nella perquisizione Dosi rinvenne anche un certificato dell\u2019esercito canadese rilasciato a Ottawa nel 1919, in cui si attestava che Brydges era stato capitano cappellano di classe A, dello stesso esercito. Inoltre Dosi scopr\u00ec anche che con lettera raccomandata, il 03 luglio 1925 fu spedita a Brydges, da New York, un atto di \u201cnaturalizzazione\u201d come cittadino degli USA. La missiva gli fu girata a Cortina d\u2019Ampezzo il 24 luglio (cf. <em>ibidem<\/em>).<\/p>\n<p style=\"text-align: justify;\"><strong>[55]<\/strong><em>Ibidem<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>[56]<\/strong> <a href=\"https:\/\/it.wikipedia.org\/wiki\/Ente_Nazionale_Protezione_Animali\">https:\/\/it.wikipedia.org\/wiki\/Ente_Nazionale_Protezione_Animali<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>[57]<\/strong> Cf. G. Dosi, <em>Il mostro e il detective<\/em>, op. cit., p. 202.<\/p>\n<p style=\"text-align: justify;\"><strong>[58]<\/strong> Cf. <em>ivi<\/em>, pp. 209-210, neretto mio.<\/p>\n<p style=\"text-align: justify;\"><strong>[59]<\/strong> A. Glielmi, <em>L&#8217;Archivio Giuseppe Dosi. Appendice documentaria<\/em>, in R. Camposano, <em>Giuseppe Dosi, il poliziotto artista che invent\u00f2 l\u2019Interpol italiana<\/em>, op. cit., pp. 213-214 (207-219).<\/p>\n<p style=\"text-align: justify;\"><strong>[60]<\/strong> Cf. Aldo Alessandro Mola, <em>Massoni e \u201crosacruciani\u201d&#8230; a regime<\/em>, in Gianfranco\u00a0de Turris (a cura di), <em>Esoterismo e Fascismo. Storia, interpretazioni, documenti<\/em>, Edizioni Mediteranee, Roma 2006, pp. 43-47.<\/p>\n<p><strong>[61]<\/strong> Cf. N. Fusaro, <em>Giuseppe Dosi e l\u2019arte dell\u2019investigazione<\/em>, in R. Camposano, <em>Giuseppe Dosi, il poliziotto artista che invent\u00f2 l\u2019Interpol italiana<\/em>, op. cit., pp. 155-156 (145-161).<\/p>\n<p><strong>[62]<\/strong> C. Mosca, <em>Introduzione<\/em>, in R. Camposano, <em>Giuseppe Dosi, il poliziotto artista che invent\u00f2 l\u2019Interpol italiana<\/em>, op. cit., p. 10 (9-10).<\/p>\n<p><strong>[63]<\/strong> G. Dosi, <em>Il mostro e il detective<\/em>, op. cit., p. 71.<\/p>\n<p><strong>[64]<\/strong> Cf. <em>ivi<\/em>, p. 85.<\/p>\n<p><strong>[65]<\/strong> Cf. <em>ivi<\/em>, pp. 214-218.<\/p>\n<p><strong>[66]<\/strong> Cf. <em>ibidem<\/em>.<\/p>\n<p><strong>[67]<\/strong> Cf. Ornella Di Tondo, <em>Giuseppe Dosi, la polizia internazionale e la nascita dell\u2019Interpol<\/em>, in R. Camposano, <em>Giuseppe Dosi, il poliziotto artista che invent\u00f2 l\u2019Interpol italiana<\/em>, op. cit., p. 94, nota 61 (67-112).<\/p>\n<p><strong>[68]<\/strong> Cf. G. Dosi, <em>Il mostro e il detec<\/em>tive, op. cit., pp. 269-270.<\/p>\n<p><strong>[69]<\/strong> <em>Ivi<\/em>, p. 219.<\/p>\n<p><strong>[70]<\/strong> <em>Ivi<\/em>, p. 220.<\/p>\n<p><strong>[71]<\/strong> <em>Ivi<\/em>, p. 221.<\/p>\n<p><strong>[72<\/strong><strong>]<\/strong> Cf. <em>ivi<\/em>, pp. 242-243.<\/p>\n<p><strong>[73]<\/strong> Cf. <em>ibidem<\/em>.<\/p>\n<p><strong>[74]<\/strong> <em>Ivi<\/em>, p. 255.<\/p>\n<p><strong>[75]<\/strong> Cf. <em>ivi<\/em>, p. 267.<\/p>\n<p><strong>[76]<\/strong> <em>Ivi<\/em>, p. 268.<\/p>\n<p><strong>[77]<\/strong> Cf. <em>ivi<\/em>, p. 269.<\/p>\n<p><strong>[78]<\/strong> <em>Ivi<\/em>, p. 269.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal sito Amici del Timone di Ferrara venerd\u00ec 2 giugno 2017 Paolo M. Siano \u00abIn un certo senso ognuno di noi \u00e8 pertanto un poliziotto-nato, per la propria costituzione psicofisiologica ereditaria [&#8230;]. Possiamo cio\u00e8 non conoscere qualche cosa, ma non vi \u00e8 nulla di occulto; col tenace lavoro tutto si pu\u00f2 sapere\u00bb [1] (Commissario-Capo Giuseppe &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":37871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,18,24,96],"tags":[2617],"class_list":["post-37870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-massoneria","category-personaggi","category-storia","category-storia-italiana","tag-giuseppe-dosi","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929) - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929) - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-14T22:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/06\/Dosi_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"187\" \/>\n\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"22 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929)\",\"datePublished\":\"2017-06-14T22:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/\"},\"wordCount\":4407,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Dosi_cover.jpg\",\"keywords\":[\"Giuseppe Dosi\"],\"articleSection\":[\"Massoneria\",\"Personaggi\",\"Storia\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/\",\"name\":\"Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929) - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Dosi_cover.jpg\",\"datePublished\":\"2017-06-14T22:00:50+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Dosi_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Dosi_cover.jpg\",\"width\":187,\"height\":269},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929) - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/","og_locale":"it_IT","og_type":"article","og_title":"Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929) - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-06-14T22:00:50+00:00","og_image":[{"width":187,"height":269,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/06\/Dosi_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"22 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929)","datePublished":"2017-06-14T22:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/"},"wordCount":4407,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/06\/Dosi_cover.jpg","keywords":["Giuseppe Dosi"],"articleSection":["Massoneria","Personaggi","Storia","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/","name":"Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929) - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/06\/Dosi_cover.jpg","datePublished":"2017-06-14T22:00:50+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/06\/Dosi_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/06\/Dosi_cover.jpg","width":187,"height":269},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-poliziotto-francescano-contro-il-mostro-di-roma-1927-1929\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Un poliziotto \u201cfrancescano\u201d contro il \u00abMostro di Roma\u00bb (1927-1929)"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=37870"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37870\/revisions"}],"predecessor-version":[{"id":37873,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37870\/revisions\/37873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/37871"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=37870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=37870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=37870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}