{"id":37645,"date":"2017-05-04T00:00:13","date_gmt":"2017-05-03T22:00:13","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=37645"},"modified":"2017-05-03T08:30:43","modified_gmt":"2017-05-03T06:30:43","slug":"geert-wilders-fallaci-olandese","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/","title":{"rendered":"Geert Wilders Fallaci olandese"},"content":{"rendered":"<div id=\"attachment_37646\" style=\"width: 250px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-37646\" class=\"wp-image-37646\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Wilders.jpg\" alt=\"Wilders\" width=\"250\" height=\"187\" \/><p id=\"caption-attachment-37646\" class=\"wp-caption-text\">Geert Wilders<\/p><\/div>\n<p style=\"text-align: center;\"><strong>Il Borghese<\/strong> n. 5 &#8211; Roma maggio 2017<\/p>\n<p style=\"text-align: center;\"><em>\u00a0<\/em>di <strong>Giuseppe Brienza<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Wilders \u00e8 <\/em><em>la versione politica di Oriana Fallaci, che \u00e8 stata la grande profetessa della nostra epoca<\/em>\u00bb. Parole di Geerten Waling, giovane ricercatore olandese dell\u2019universit\u00e0 di Leiden, di commento all\u2019esito delle elezioni politiche nei Paesi Bassi che si sono tenute il 15 marzo. Geert Wilders, ex liberale che nel 2004 ha fondato il partito sovranista PVV (<em>Partito per la libert\u00e0<\/em>), ha ottenuto in queste ultime consultazioni ben 20 seggi parlamentari, 5 in pi\u00f9 rispetto alle precedenti politiche del 2012, divenendo cos\u00ec il secondo partito a livello nazionale.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Nel momento in cui scriviamo (inizio aprile), dalle elezioni non \u00e8 ancora scaturito un nuovo governo, sebbene sia dato per scontato che l\u2019attuale premier Mark Rutte, leader del <em>Partito popolare per la libert\u00e0 e la democrazia<\/em> (VVD), che ha ottenuto soli 33 seggi, continuer\u00e0 a fare il Primo Ministro, senza per\u00f2 poter riproporre la linea politica filo-Ue e filo-immigrazione finora adottata. Nonostante il crollo dei laburisti, che sono riusciti a portare a casa a malapena 9 seggi rispetto ai 38 seggi conquistati nel 2012, la coalizione governativa continuer\u00e0 a essere di centro-sinistra, perch\u00e9 la maggioranza parlamentare sar\u00e0 frutto di un accordo diretto del VVD con i cristiano democratici del CDA (<em>Appello Cristiano Democratico<\/em>) e i socialdemocratici del D66, i quali hanno ottenuto entrambi 19 eletti.<\/p>\n<p style=\"text-align: justify;\">Dall\u2019intervista citata all\u2019inizio di questo articolo usciamo confermati circa la lettura dell\u2019attuale situazione politico-sociale dell\u2019Olanda che abbiamo offerto, in totale contro-tendenza rispetto a quella propinata dai grandi media italiani e internazionali, che rende del tutto fuori luogo l\u2019esultanza nel dopo-voto da parte degli eurocrati ed euro-entusiasti. Come ho avuto modo di scrivere sul giornale diretto da Mario Adinolfi, infatti, \u00ab<em>a<\/em><em>l suo debutto elettorale nel 2006, il PVV conquist\u00f2 6 seggi, offrendo per un breve periodo un supporto parlamentare esterno al governo di minoranza del premier Rutte. Alle elezioni del 2012 i seggi furono soltanto 15 e, alle europee del 2014, il partito di Wilders ottenne per la prima volta una rappresentanza con 4 seggi su 26. Per questo i 20 seggi che gli riconoscono queste politiche, tanto pi\u00f9 nel frammentato panorama elettorale olandese, costituiscono una sostanziale affermazione<\/em>. [\u2026] <em>Lo spauracchio dell\u2019uscita dell\u2019Olanda all\u2019Unione Europea (Nexit), non \u00e8 del tutto annullata<\/em>\u00bb (G. Brienza, <em>Olanda: un voto da leggere bene<\/em>, in <em>La Croce quotidiano<\/em>, 16 marzo 2017, pp. 1-2).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-37442 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/pvv_olanda-1.jpg\" alt=\"pvv_olanda\" width=\"267\" height=\"188\" \/>Non pu\u00f2 essere negata l\u2019importanza storica, in un Paese come l\u2019Olanda che nel 1957 \u00e8 stata fra i membri fondatori della CEE (attuale Ue), del grande credito riconosciuto dalla popolazione alle proposte anti-islamiste di Wilders, come ad esempio quella di vietare il Corano e chiudere tutte le moschee presenti sul territorio nazionale.<\/p>\n<p style=\"text-align: justify;\">Anche secondo la testata <em>VoteWatch<\/em>, un <em>think tank<\/em> che monitora le votazioni degli Stati membri dell\u2019Unione europea, \u00ab<em>sarebbe una lettura semplicistica inquadrare il voto olandese come una vittoria per l\u2019Ue e una sconfitta per l\u2019euroscetticismo<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">A parere del ricercatore Waling, che \u00e8 studioso di orientamento molto lontano dalle posizioni anti-Ue e di destra, l\u2019essenza del PVV \u00e8 la riproposizione dell\u2019idea politica <em>sovranista<\/em>, avendo vinto le elezioni con il motto \u00ab<em>L\u2019Olanda agli Olandesi<\/em>\u00bb e con una decisa battaglia contro il <em>politically correct, <\/em>la finanza e la tecnocrazia internazionale. \u00ab<em>Mi fanno un po\u2019 ridere <\/em>&#8211; ha affermato giustamente Waling &#8211; <em>quei leader europei che applaudono alla sconfitta del nazionalismo. Ancora pi\u00f9 ridere se sono dell\u2019area socialista, come Hollande o Renzi, quando i laburisti sono pressoch\u00e9 spariti dal panorama politico<\/em>\u00bb (cit. in Marzio G. Mian, \u00ab<em>Wilders? \u00c8 <\/em><em>la nostra versione di Oriana Fallaci<\/em>\u00bb, <em>Il Giornale<\/em>, 17 marzo 2017).<\/p>\n<p style=\"text-align: justify;\">Wilders, che dal 2004 \u00e8 costretto a vivere sotto scorta perch\u00e9 risultato nella \u201clista nera\u201d di <em>Al-Q\u0101\u02bfida<\/em>, negli ultimi giorni della campagna elettorale si \u00e8 visto arrestare uno dei poliziotti addetti alla sua sicurezza perch\u00e9 scoperto a passare informazioni a un gruppo criminale marocchino operante in Olanda. Anche se ora \u00e8 demonizzato dall\u2019intero establishment, fino a pochi anni fa l\u2019attuale leader del PVV militava tranquillamente nel partito attualmente al governo, il VVD, che nel 2004 dovette abbandonare perch\u00e9 dichiaratosi improvvidamente a favore dell\u2019ingresso della Turchia nell\u2019Ue, posizione oggi in gran parte rivista.<\/p>\n<p style=\"text-align: justify;\">Dunque il primo ministro liberale uscente, Mark Rutte, per la formazione del nuovo governo di coalizione potr\u00e0 vantare una maggioranza risicata di 76 seggi sui 150 alla Camera dei rappresentanti. I capofila delle formazioni politiche hanno indicato nel ministro della sanit\u00e0 uscente, Edith Schippers, del VVD, la persona incaricata di compiere le lunghe consultazioni. Se il processo si concluder\u00e0 positivamente, il governo prester\u00e0 giuramento davanti al sovrano e potr\u00e0 entrare in funzione. In occasione delle ultime elezioni del 2012 \u2013 ricordano gli osservatori &#8211; il processo di formazione del nuovo esecutivo dur\u00f2 54 giorni. Il record di lunghezza delle trattative \u00e8 del 1977 con 208 giorni, durante i quali rest\u00f2 in carica il governo uscente.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29651 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/islam_Olanda.jpg\" alt=\"islam_Olanda\" width=\"268\" height=\"188\" \/>Dato il perdurare iniziale delle negoziazioni, l\u2019ipotesi che pi\u00f9 si accredita in questi ultimi giorni \u00e8 una formula a quattro, guidata dal VVD assieme a CDA e D66 ma imbarcando anche i verdi. Ma il premier Rutte dovr\u00e0 gestire anche la prima assoluta alla Camera di 3 parlamentari del <em>Denk<\/em>, partito accreditato come \u201cantirazzista\u201d che ha conquistato il 2,1% dei consensi a livello nazionale, con punte del 7% nei grandi centri urbani. In realt\u00e0, fondato da due turco-olandesi fuoriusciti dal laburismo, si tratta in tutto e per tutto del primo partito islamico d\u2019Olanda, anche se nessuno, o quasi, osa riconoscerlo.<\/p>\n<p style=\"text-align: justify;\">A leggere il suo programma politico (<strong>l<\/strong>a parola \u201cdenk\u201d, in olandese, si traduce in \u201cpensiero\u201d ma, in turco, corrisponde a \u201cuguaglianza\u201d), vi si ritrovano tutto sommato tematiche e parole-talismano tipiche della galassia buonista e sinistreggiante. Come riconosciuto dagli osservatori <em>politicamente scorretti<\/em>, invece, il \u00ab<em>Denk \u00e8 la Quinta Colonna della penetrazione islamica nel tessuto politico olandese. Se si va a leggere in profondit\u00e0 il programma politico del \u201cPartito antirazzista\u201d si scoprono aspetti inquietanti che i media, ossessionati dal pericolo xenofobo, fanno finta di non vedere: Denk vuole la parificazione delle scuole islamiche con quelle pubbliche olandesi, mantenendo alcune prerogative come la separazione dei sessi e l\u2019insegnamento del Corano in arabo. Denk vuole l\u2019istituzione di un corpo di \u201cPolizia del Razzismo\u201d il cui compito \u00e8 la repressione di qualsiasi frase o idea ritenuta offensiva per i musulmani, attraverso la creazione di un \u201cRegistro del razzismo\u201d per monitorare i discorsi dei personaggi pubblici e affibbiare multe e percorsi rieducativi a chi non \u00e8 conforme al pensiero unico. Denk vuole la riduzione dei vincoli di riconoscimento dello status di rifugiato; l\u2019aumento delle quote di accoglienza e maggiori risorse economiche per l\u2019emergenza profughi<\/em>\u00bb (Giampaolo Rossi, <em>Ecco Denk, il primo partito islamico d\u2019Europa<\/em>,<em> Il Giornale<\/em>, 25 marzo 2017).<\/p>\n<p style=\"text-align: justify;\">In un momento di forte tensione fra Olanda e Turchia e con il problema dell\u2019integrazione sollevato di gruppi sovranisti e di destra, l\u2019ingresso del neonato partito rappresenta un\u2019ulteriore segnale di destabilizzazione del panorama politico. Adesso l\u2019attenzione \u00e8 tutta rivolta alle presidenziali in Francia del 23 aprile (con il ballottaggio previsto per il 7 maggio) e alle politiche in Germania del 24 settembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Borghese n. 5 &#8211; Roma maggio 2017 \u00a0di Giuseppe Brienza \u00abWilders \u00e8 la versione politica di Oriana Fallaci, che \u00e8 stata la grande profetessa della nostra epoca\u00bb. Parole di Geerten Waling, giovane ricercatore olandese dell\u2019universit\u00e0 di Leiden, di commento all\u2019esito delle elezioni politiche nei Paesi Bassi che si sono tenute il 15 marzo. Geert &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":37646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,108,19],"tags":[2408,1643],"class_list":["post-37645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa-e-ue","category-paesi-e-continenti","category-politica-internazionale","tag-islam-in-europa","tag-olanda","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geert Wilders Fallaci olandese - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geert Wilders Fallaci olandese - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-03T22:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Wilders.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Geert Wilders Fallaci olandese\",\"datePublished\":\"2017-05-03T22:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/\"},\"wordCount\":1148,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Wilders.jpg\",\"keywords\":[\"Islam in Europa\",\"Olanda\"],\"articleSection\":[\"Europa e UE\",\"Paesi e continenti\",\"Politica internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/\",\"name\":\"Geert Wilders Fallaci olandese - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Wilders.jpg\",\"datePublished\":\"2017-05-03T22:00:13+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Wilders.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Wilders.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/geert-wilders-fallaci-olandese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geert Wilders Fallaci olandese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geert Wilders Fallaci olandese - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/","og_locale":"it_IT","og_type":"article","og_title":"Geert Wilders Fallaci olandese - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-05-03T22:00:13+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Wilders.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Geert Wilders Fallaci olandese","datePublished":"2017-05-03T22:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/"},"wordCount":1148,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Wilders.jpg","keywords":["Islam in Europa","Olanda"],"articleSection":["Europa e UE","Paesi e continenti","Politica internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/","name":"Geert Wilders Fallaci olandese - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Wilders.jpg","datePublished":"2017-05-03T22:00:13+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Wilders.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Wilders.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/geert-wilders-fallaci-olandese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Geert Wilders Fallaci olandese"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=37645"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37645\/revisions"}],"predecessor-version":[{"id":37647,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37645\/revisions\/37647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/37646"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=37645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=37645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=37645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}