{"id":37641,"date":"2017-05-04T00:00:05","date_gmt":"2017-05-03T22:00:05","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=37641"},"modified":"2017-05-02T17:10:52","modified_gmt":"2017-05-02T15:10:52","slug":"immigrati-neanche-uno-che-dica-grazie","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/","title":{"rendered":"Immigrati, neanche uno che dica grazie"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-37642\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/mostra_locandina.jpg\" alt=\"mostra_locandina\" width=\"139\" height=\"200\" \/>La Nuova Bussola<\/strong> quotidiana 1 maggio 2017<\/p>\n<p style=\"text-align: center;\">di <strong>Anna Bono<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c8 una mostra fotografica, in una citt\u00e0 italiana come potrebbero essercene tante, si intitola \u201cMa dove sono finito? Frontiere tra visibile e invisibile\u201d. Ci si sono messi in tanti per realizzarla: un comune, una cooperativa che si occupa di immigrati illegali, lo Sprar, che \u00e8 il Sistema di protezione per richiedenti asilo e rifugiati, il GEC, Gruppo di educazione alla cittadinanza, formato da richiedenti asilo seguiti dalla cooperativa di cui sopra, e gli animatori di una associazione.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Dopo quattro mesi di incontri settimanali la mostra era pronta ed \u00e8 stata presentata al pubblico. Consiste in 18 fotografie scattate in vari punti della citt\u00e0: \u201cNon una mostra per raccontare i migranti \u2013 spiega il testo di presentazione dell\u2019evento \u2013 non una mostra per parlare \u2018di loro\u2019, ma una mostra fatta \u2018da loro\u2019. Una mostra per poter entrare in contatto con la cittadinanza, uscire cos\u00ec dalla dimensione di oggetto della discussione, ed assumere quella propria di essere umano, ovvero di soggetto sovrano della propria esistenza\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Entrare in contatto con la cittadinanza,<\/strong>\u00a0\u201ccreare occasioni di fratellanza\u201d: questo \u00e8 l\u2019obiettivo dichiarato, ma quello effettivo \u00e8 piuttosto suscitare sensi di colpa, far rimarcare le nostre colpe di ospiti, inadeguati, deludenti, se non peggio, dominati \u201ctroppo spesso dalla paura e dai pregiudizi\u201d. Un approccio parziale che, purtroppo, ha trovato ancora eco nelle parola di papa Francesco sull&#8217;aereo di ritorno dall&#8217;Egitto quando ha parlato di &#8220;campi di concentramento&#8221; riferendosi ai centri di accoglienza dei migranti.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-36249\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/08\/immigrati.jpg\" alt=\"immigrati\" width=\"250\" height=\"159\" \/>Le fotografie sono accompagnate da frasi attribuite a loro, gli immigrati<\/strong>, per raccontarli, nel loro rapporto con la citt\u00e0, con il nostro paese. Per lo pi\u00f9 parlano di barriere, indifferenza, ingiustizie. Un ragazzo che dal nome si direbbe originario della Costa d\u2019Avorio dice: \u201cDall\u2019Africa in Italia tanti km percorsi e tante storie vissute. Ma alla fine ridotto a zero km e zero storie dall\u2019indifferenza\u201d. Sotto a una fotografia che mostra l\u2019insegna di un negozio di telefonia mobile c\u2019\u00e8 scritto: \u201cUn luogo in cui senza documento non puoi comprare una sim card e non puoi fare un abbonamento wifi per il cellulare e per la casa\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Diallo, un giovane Fulani, commenta:<\/strong>\u00a0\u201cSe non hai il documento ci sono molte barriere: tutte le porte sono chiuse per te. C\u2019\u00e8 una barriera che non mi fa spostare e viaggiare. C\u2019\u00e8 una barriera che non mi fa lavorare\u201d; e poi, insieme a un altro immigrato che si chiama Manga: \u201cAnche noi immaginiamo il nostro futuro, ma per immaginarlo abbiamo bisogno dei documenti e del lavoro\u201d. Un ragazzo dal nome islamico, Manaf, dice. \u201cNon serve a niente mettere una barriera tra di noi\u201d. Un altro commenta cos\u00ec la fotografia di una stazione: \u201cPer voi \u00e8 invisibile il fatto che senza documento non posso prendere il treno e superare il confine verso la Germania\u201d. E ancora, la didascalia di una fotografia che mostra un cartello di \u201cVietato l\u2019ingresso\u201d dice: \u201cLa natura crea gli uomini liberi e uguali. La vita li rende ingiusti e diversi\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Di quali barriere parlano, l\u2019indifferenza di chi li turba tanto<\/strong>, che ingiustizie subiscono, che cosa hanno da rimproverarci, proprio loro che in Italia sono arrivati e fin dal primo giorno hanno avuto tutto senza muovere un dito, senza sborsare un centesimo; anzi, ricevono in pi\u00f9 una diaria per le piccole spese? Questa \u00e8 l\u2019ovvia reazione degli italiani che visitano la mostra.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-27766\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/11\/immigrati_Africa.jpg\" alt=\"immigrati_Africa\" width=\"250\" height=\"166\" \/>Avendo tempo di riflettere sulle didascalie, sorgono poi altre perplessit\u00e0.<\/strong> Se sono dei richiedenti asilo, come affermano di essere, di quali documenti lamentano la mancanza? Forse reclamano lo status di rifugiato, una risposta pi\u00f9 rapida da parte delle commissioni territoriali? Per\u00f2 nel frattempo godono degli stessi diritti dei rifugiati, anche se alla fine quasi nessuno otterr\u00e0 asilo perch\u00e9 quasi nessuno \u00e8 profugo. Vogliono lavorare, dicono. Trascorsi 60 giorni dalla presentazione della richiesta, possono farlo. Ma, per trovare lavoro, devono parlare italiano, saper fare qualcosa che serva. E non glielo ha detto nessuno che oggi pi\u00f9 di tre milioni di italiani, soprattutto giovani della loro et\u00e0, vorrebbero lavorare e invece sono disoccupati?<\/p>\n<p style=\"text-align: justify;\"><strong>18 fotografie, altrettante frasi, non un grazie per quel che ricevono,<\/strong>\u00a0non una parola di gratitudine verso la comunit\u00e0 che li ospita e li mantiene. Ci si aspetterebbe di trovare frasi come: \u201cAncora ieri non sapevate neanche che esistessi, sono entrato violando le vostre leggi, eppure mi avete soccorso e adesso vi preoccupate del mio benessere, della mia dignit\u00e0 di persona\u201d. Oppure: \u201cGrazie a voi posso parlare con la mia famiglia tutti i giorni, non mi sento solo e loro non sono in pensiero\u201d. O ancora: \u201cNon dimenticher\u00f2 mai quel che state facendo per me, se un giorno avrete bisogno di aiuto, spero di poter ricambiare il bene che adesso ricevo\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Niente del genere. Certo non c\u2019\u00e8 bisogno che ringrazino<\/strong>, ci prendiamo cura di loro comunque, per carit\u00e0 cristiana, per rispetto umano. Ma cos\u00ec sembra che siano inconsapevoli o incuranti di essere entrati in Italia illegalmente e che non diano valore al fatto di essere tuttavia ospitati, assistiti.<\/p>\n<p style=\"text-align: justify;\"><strong>Una frase si differenzia dalle altre:<\/strong> \u201cL\u2019Italia \u00e8 un posto dove ci sono belle case e dove le persone vivono bene\u201d. Dal nome, Sylla, a scriverla deve essere stato un cittadino del Mali, proprio uno degli stati africani che dal 2014 cercano di far capire alla gente che emigrare pensando di far fortuna in Italia \u00e8 un\u2019illusione. La campagna governativa maliana contro l\u2019emigrazione, soprattutto quella illegale, si intitola \u201cIl mio Eldorado \u00e8 il Mali\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Nuova Bussola quotidiana 1 maggio 2017 di Anna Bono \u00c8 una mostra fotografica, in una citt\u00e0 italiana come potrebbero essercene tante, si intitola \u201cMa dove sono finito? Frontiere tra visibile e invisibile\u201d. Ci si sono messi in tanti per realizzarla: un comune, una cooperativa che si occupa di immigrati illegali, lo Sprar, che \u00e8 &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":37642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[240],"class_list":["post-37641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-immigrazione","tag-immigrati","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Immigrati, neanche uno che dica grazie - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Immigrati, neanche uno che dica grazie - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-03T22:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/mostra_locandina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"187\" \/>\n\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Immigrati, neanche uno che dica grazie\",\"datePublished\":\"2017-05-03T22:00:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/\"},\"wordCount\":901,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/mostra_locandina.jpg\",\"keywords\":[\"immigrati\"],\"articleSection\":[\"Immigrazione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/\",\"name\":\"Immigrati, neanche uno che dica grazie - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/mostra_locandina.jpg\",\"datePublished\":\"2017-05-03T22:00:05+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/mostra_locandina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/mostra_locandina.jpg\",\"width\":187,\"height\":269},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/immigrati-neanche-uno-che-dica-grazie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immigrati, neanche uno che dica grazie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Immigrati, neanche uno che dica grazie - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/","og_locale":"it_IT","og_type":"article","og_title":"Immigrati, neanche uno che dica grazie - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-05-03T22:00:05+00:00","og_image":[{"width":187,"height":269,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/mostra_locandina.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Immigrati, neanche uno che dica grazie","datePublished":"2017-05-03T22:00:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/"},"wordCount":901,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/mostra_locandina.jpg","keywords":["immigrati"],"articleSection":["Immigrazione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/","name":"Immigrati, neanche uno che dica grazie - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/mostra_locandina.jpg","datePublished":"2017-05-03T22:00:05+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/mostra_locandina.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/mostra_locandina.jpg","width":187,"height":269},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/immigrati-neanche-uno-che-dica-grazie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Immigrati, neanche uno che dica grazie"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=37641"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37641\/revisions"}],"predecessor-version":[{"id":37643,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37641\/revisions\/37643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/37642"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=37641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=37641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=37641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}