{"id":37623,"date":"2017-05-04T00:00:30","date_gmt":"2017-05-03T22:00:30","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=37623"},"modified":"2017-05-01T13:38:34","modified_gmt":"2017-05-01T11:38:34","slug":"joseph-il-gigante","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/","title":{"rendered":"Joseph-il-gigante"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-37624\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Papa-emerito.jpg\" alt=\"Papa emerito\" width=\"250\" height=\"166\" \/>Gente, <\/strong>16 aprile 2017,<\/p>\n<p style=\"text-align: center;\">di <strong>Riccardo Caniato<\/strong><\/p>\n<p style=\"text-align: justify;\">Sedici aprile 2017: proprio nel giorno di Pasqua, Joseph Ratzinger compie 90 anni. <em>Gente<\/em> af\ufb01da i suoi auguri al Papa emerito a Vittorio Messori, il pi\u00f9 qualificato giornalista e scrittore &#8211; nato pure lui il 16 aprile, del 1941 per\u00f2 &#8211; al quale chiedere un ritratto dell\u2019uomo, prima ancora che del Pontefice che ha governato la Chiesa cattolica dall\u2019aprile 2005 alla \ufb01ne di febbraio 2013.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Impostosi nel 1976 con <em>Ipotesi su Ges\u00f9<\/em> (quasi due milioni di copie vendute solo in Italia), Messori \u00e9 stato, infatti, il primo vaticanista a pubblicare un volume a quattro mani con un Papa (<em style=\"font-weight: inherit;\">Varcare la soglia della speranza<\/em>, scritto con Giovanni Paolo II nel 1993), preceduto nel 1985 da un altro primato, il libro intervista, per quei tempi impensabile, con l\u2019allora prefetto della \ufb01n li impenetrabile Congregazione per la Dottrina della Fede: il cardinale Ratzinger per l\u2019appunto. \u201c<em style=\"font-weight: inherit;\">Rapporto sulla fede<\/em> fu il frutto di tre giorni a stretto contatto con Joseph Ratzinger, che hanno stabilito un legame mai pi\u00f9 interrotto fra noi\u201d, dice lo scrittore.<\/p>\n<p style=\"text-align: justify;\"><strong>Che ricordo ha di quei giorni?<\/strong><\/p>\n<p style=\"text-align: justify;\">Il prefetto dell\u2019ex Sant\u2019Uf\ufb01zio mi convoc\u00f2 a Bressanone per la sera dell\u2019Assunta del 1984. Ratzinger stava trascorrendo le sue vacanze estive nel locale seminario, dividendosi fra studio e meditazione. Quando giunsi, prima di cena, mi dissero che Sua Eminenza era ancora fuori per le cresime. Arrivo a bordo di una vecchia Volkswagen maggiolino targata Monaco di Baviera. Ne usc\u00ec vestito di tutto punto da cardinale, in rosso porpora, e fui colpito dal contrasto generato dalla sua figura austera e intelligente e la povert\u00e0 espressa dalla sua auto e dall\u2019anziano sacerdote con semplice camicia nera e collarino che la guidava. Seppi poi che era suo fratello. A ripensarci, questa immagine dice molto del fraintendimento di cui Ratzinger \u00e9 stato vittima un po\u2019 per tutta la sua vita.<\/p>\n<p style=\"text-align: justify;\"><strong>Pu\u00f2 spiegarci meglio cosa?<\/strong><\/p>\n<p style=\"text-align: justify;\">Quando lo incontri bastano poche battute per percepirne la statura umana. La sapienza e la vastit\u00e0 della cultura, non solo dottrinale, della persona, e ti senti un nano al confronto. Tanti nemici della Chiesa, ben consapevoli di aver di fronte un cavallo di razza capace di poggiare la fede nell\u2019acume della ragione, non potendo competere sul fronte delle argomentazioni ne hanno stravolto alcuni aspetti a partire dalla nazionalit\u00e0 e dalla sua profonda timidezza, per creare uno stereotipo mediatico. L\u2019immagine del \u201cpastore tedesco\u201d, del \u201cgrande inquisitore\u201d, del \u201cpanzer cardinal\u201d o del \u201cprefetto di ferro\u201d sono figlie di questa leggenda nera.<\/p>\n<p style=\"text-align: justify;\"><strong>Invece?<\/strong><\/p>\n<p style=\"text-align: justify;\">Invece Joseph Ratzinger \u00e9 una delle persone pi\u00f9 amabili, discrete e buone che io abbia conosciuto. Come tutti i veri sapienti non si vanta e sa ascoltare gli altri. Ed \u00e9 dotato di humour anche verso se stesso. Lo sa che quando ci vedevamo in trattoria nei pressi del Vaticano, mi chiedeva di raccontargli le barzellette che circolavano su di lui? Rideva di gusto. Chiss\u00e0 che direbbero i detrattori a vederlo cosi.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma Papa Ratzinger \u00e9 ricordato anche per i principi non negoziabili e la fermezza di alcune posizioni\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">Certamente \u00e9 un uomo che non deroga alla verit\u00e0. Quando gli consegnai le bozze del libro, insistetti che le rileggesse di persona perch\u00e9 aveva rilasciato delle dichiarazioni esplosive e c\u2019era una condanna molto ferma in merito a una certa contestazione postconciliare e a nuove correnti di pensiero come la teologia della liberazione. Ma lui non corresse quasi nulla, n\u00e9 addolci le posizioni pi\u00f9 dure. Rest\u00f2 sorpreso per la mia preoccupazione: \u201cPolemiche?\u201d, mi chiese in tedesco, scrutandomi con i suoi occhi azzurri innocenti. \u201cWarum? E perch\u00e9 mai?\u201d. E qui si intuisce quella trasparenza evangelica che l\u2019ha caratterizzato anche da Papa, per la quale ci si stupisce che l\u2019annuncio della verit\u00e0 possa suscitare polemiche.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma le polemiche non sono mancate, come dopo il discorso di Ratisbona su fede e ragione con il famoso passaggio su Islam e violenza.<\/strong><\/p>\n<p style=\"text-align: justify;\">Se \u00e9 per questo, anche quando era cardinale fece discutere. Per le condanne di cui ho fatto cenno fu minacciato di morte. Per la sua incolumit\u00e0, gli imposero di prendere alloggio all\u2019ambasciata americana presso la Santa Sede e quando mi invitava da lui dovevo sottostare alle perquisizioni dei <em>marines<\/em>. Ma l\u2019apparato di sicurezza contrastava con l\u2019uomo che incontravo nella quiete serena della sua casa.<\/p>\n<p style=\"text-align: justify;\"><strong>Ci dica qualcosa di pi\u00f9 sulla delicatezza umana di Joseph Ratzinger.<\/strong><\/p>\n<p style=\"text-align: justify;\">Tornando all\u2019abito, a Bressanone non lo vidi pi\u00f9 in divisa: aveva indossato la porpora in ossequio alla liturgia e per rispetto ai cresimandi che aspettavano con trepidazione di incontrare un principe della Chiesa. Ma subito si cambi\u00f2, mettendomi a mio agio con un informale <em>clergyman<\/em> un po\u2019 sdrucito. Durante il soggiorno, poi, lavoravamo tutto il\u00a0giorno e la sera rivedevamo insieme gli appunti prima di coricarci.<\/p>\n<p style=\"text-align: justify;\">Infaticabile, Ratzinger si svegliava molto prima di me per celebrare la Messa e si tratteneva la sera in cappella per il rosario, mentre io mi ritiravo nella mia camera a preparare le domande dell\u2019indomani. Non insistette mai perch\u00e9 mi adeguassi ai suoi ritmi. Mesi dopo, a Roma, avendo maturato una maggiore confidenza, gli rivelai sorridendo che a Bressanone avevo compiuto un grosso sacri\ufb01cio, rinunciando a fumare per tre giomi nel timore di arrecargli fastidio. Ci rest\u00f2 male e con fare sincero mi disse: \u201cMa perch\u00e9 non me l\u2019ha detto? Io non fumo, \u00e9 vero, ma mi piace il profumo del tabacco che brucia\u201d. Sono certo che non fosse vero, ma per lui era il modo di non offendermi.<\/p>\n<p style=\"text-align: justify;\"><strong>Mangiavate insieme?<\/strong><\/p>\n<p style=\"text-align: justify;\">Certo, se cosi si pu\u00f2 dire. Io ero poco pi\u00f9 che quarantenne e a pranzo mi rintuzzava perch\u00e9 mangiassi di pi\u00f9, mentre lui si conteneva. Ogni pomeriggio si preoccupava anche di organizzare una pausa intorno a uno <em>strudel<\/em> strepitoso preparato dalle suore tirolesi che ci assistevano. Non tardai ad accorgermi che la merenda era pensata apposta per me, dal momento che Ratzinger si faceva portare dell\u2019acqua che sorseggiava con calma, dandomi cosi il tempo di finire. Gli chiesi perch\u00e9 non assaggiasse quelle torte buonissime, ma si ritrasse con garbo, avanzando un\u2019altra piccola bugia: \u201cVede, caro dottore, \u00e9 preferibile che io non mangi dolci\u201d. Esigente e austero con se stesso, ma pieno di attenzioni verso gli altri che quasi non si accorgono della sua costante capcit\u00e0 di mortificazione: \u00e8 fatto cos\u00ec Joseph Ratzinger.<\/p>\n<p style=\"text-align: justify;\"><strong>Quando avvenne il primo incontro con lui dopo l\u2019elezione a Papa?<\/strong><\/p>\n<p style=\"text-align: justify;\">In udienza a piazza San Pietro. Mi aveva invitato dopo la pubblicazione del volume <em>Perch\u00e9 credo<\/em>, scritto insieme con Andrea Tornielli. Mi abbracci\u00f2 e trovai il coraggio di chiedergli se non fosse giunto ii tempo di aggiornare <em>Rapporto sulla fede<\/em>. \u201cMa come facciamo?\u201d, chiese. \u201cCome l\u2019altra volta\u201d, risposi. \u201cSantit\u00e0, se Lei mi d\u00e0 tre giorni\u2026\u201d. \u201cVittorio\u201d, mi interruppe sorridendo, \u201ccome posso darle tre giorni, se nessuno lascia tre ore di tregua al Papa?\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>E l\u2019ultimo incontro?<\/strong><\/p>\n<p style=\"text-align: justify;\">Mesi fa, da emerito. Ancora una volta l\u2019occasione \u00e9 stata la pubblicazione di un mio libro e sua l\u2019iniziativa, perch\u00e9 da quando \u00e9 Papa non ho pi\u00f9 trovato il coraggio di fare io il primo passo. Mi ha ricevuto al <em>Mater Ecclesiae<\/em>, la palazzina nei giardini vaticani dove ci fu la sede del convento di suore di clausura volute da Giovanni Paolo II.<\/p>\n<p style=\"text-align: justify;\"><strong>Come vive adesso Benedetto?<\/strong><\/p>\n<p style=\"text-align: justify;\">Fra i suoi libri, il piano, la musica: Mozart, Beethoven, Bruckner\u2026 Riceve qualche ospite e si occupa della corrispondenza che gli arriva da tutto il mondo. Ho visto anche due quotidiani sul suo tavolo: il <em>Corriere della Sera<\/em> e il bavarese <em>Suddeutsche Zeitung.<\/em> La sera guarda il Tg1. La villetta \u00e8 un luogo luminoso, pieno di fiori, che comunica pace. Benedetto \u00e9 attorniato da rispetto e affetto. Con lui ci sono sempre le <em>memores domini<\/em> di CL e il suo segretario, l\u2019arcivescovo Georg G\u00e9nswein, quando non \u00e9 impegnato con Papa Francesco.<\/p>\n<p style=\"text-align: justify;\"><strong>Proprio padre Georg\u00a0 lo scorso anno, allarm\u00f2 un po\u2019 tutti dichiarando che Benedetto \u00e9 come una candela che si spegne lentamente.<\/strong><\/p>\n<p style=\"text-align: justify;\">Nel nostro ultimo incontro ci siamo intrattenuti fin dopo le 13. Speravo potessimo pranzare insieme, invece sono stato congedato per non affaticarlo e non so se e cosa mangi. Benedetto ora \u00e8 magrissimo, anche in casa si appoggia a un girello e per un po\u2019 d\u2019aria in giardino di solito \u00e9 spinto su una carrozzella. Ma nel dialogo fra noi si \u00e9 riaffermato uomo dalla mente fuori dal comune, dalla conversazione lucida, appassionata e coinvolgente. Non a caso, nell\u2019ultimo anno, ha seguito da vicino la pubblicazione di un libro intervista e di una biografia. La metafora con la candela calza, ma, per quanto sia esile, la luce che emana \u00e9 sempre folgorante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gente, 16 aprile 2017, di Riccardo Caniato Sedici aprile 2017: proprio nel giorno di Pasqua, Joseph Ratzinger compie 90 anni. Gente af\ufb01da i suoi auguri al Papa emerito a Vittorio Messori, il pi\u00f9 qualificato giornalista e scrittore &#8211; nato pure lui il 16 aprile, del 1941 per\u00f2 &#8211; al quale chiedere un ritratto dell\u2019uomo, prima &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":37624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,5],"tags":[1036],"class_list":["post-37623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-benedetto-xvi","category-chiesa","tag-joseph-ratzinger","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joseph-il-gigante - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joseph-il-gigante - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-03T22:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Papa-emerito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Joseph-il-gigante\",\"datePublished\":\"2017-05-03T22:00:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/\"},\"wordCount\":1410,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Papa-emerito.jpg\",\"keywords\":[\"Joseph Ratzinger\"],\"articleSection\":[\"Benedetto XVI\",\"Chiesa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/\",\"name\":\"Joseph-il-gigante - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Papa-emerito.jpg\",\"datePublished\":\"2017-05-03T22:00:30+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Papa-emerito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Papa-emerito.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/joseph-il-gigante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joseph-il-gigante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joseph-il-gigante - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/","og_locale":"it_IT","og_type":"article","og_title":"Joseph-il-gigante - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-05-03T22:00:30+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Papa-emerito.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Joseph-il-gigante","datePublished":"2017-05-03T22:00:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/"},"wordCount":1410,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Papa-emerito.jpg","keywords":["Joseph Ratzinger"],"articleSection":["Benedetto XVI","Chiesa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/","name":"Joseph-il-gigante - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Papa-emerito.jpg","datePublished":"2017-05-03T22:00:30+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Papa-emerito.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Papa-emerito.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/joseph-il-gigante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Joseph-il-gigante"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=37623"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37623\/revisions"}],"predecessor-version":[{"id":37626,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37623\/revisions\/37626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/37624"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=37623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=37623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=37623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}