{"id":37347,"date":"2017-03-16T00:00:50","date_gmt":"2017-03-15T23:00:50","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=37347"},"modified":"2017-03-09T14:38:37","modified_gmt":"2017-03-09T13:38:37","slug":"fabo-un-omicidio-politico","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/","title":{"rendered":"Fabo, un omicidio politico"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-37348\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/Fabo_eutanasia.jpg\" alt=\"Fabo_eutanasia\" width=\"250\" height=\"179\" \/>La Nuova bussola quotidiana<\/strong><\/p>\n<p style=\"text-align: center;\">28 Febbraio 2017<\/p>\n<p style=\"text-align: justify;\"><em>Fabiano, noto come dj Fabo, volto della campagna pro eutanasia dell&#8217;associazione Luca Coscioni, \u00e8 stato ucciso ieri in una clinica svizzera dell&#8217;eutanasia. Ad accompagnarlo \u00e8 stato il politico radicale Marco Cappato che ne ha dato notizia via Twitter.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Benedetta Frigerio<\/strong><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>C\u2019\u00e8 qualcosa di profondamente diabolico nella<\/strong> spettacolarizzazione della soppressione di un disabile che ha preteso di essere eliminato in mondovisione per dire che lo Stato dovrebbe uccidere le persone che, come lui, non sopportano di vivere diversamente da come vogliono. C\u2019\u00e8 qualcosa di malefico perch\u00e9, se questa \u00e8 l\u2019ottica, che differenza c\u2019\u00e8 fra l\u2019autodeterminazione di chi vuole essere ammazzato perch\u00e9 inchiodato ad un letto e perch\u00e9 \u201cuna vita cos\u00ec non la accetto\u201d e un altro che magari non sopporta di essere basso o grasso o irascibile? Attenzione, perch\u00e9 teoricamente non ce n\u2019\u00e8 alcuna. E si sa che dalla teoria basta una legge per passare alla pratica.<\/p>\n<p style=\"text-align: justify;\"><strong>Si potrebbe dire: \u201cMettiamo dei limiti, permettiamo l\u2019eutanasia solo in certi casi<\/strong> estremamente drammatici, come quello di dj Fabo\u201d. Sono questi i discorsi che riempivano ieri i media a proposito del ddl sulle Dichiarazioni anticipate di trattamento mentre, guarda caso proprio i Radicali, annunciavano l\u2019omicidio di Fabiano, da loro inviato in una clinica della \u201cdolce morte\u201d svizzera, dove per quasi 20 mila euro \u00e8 stato avvelenato con soluzioni che costerebbero pochi euro. Ma chi determina qual \u00e8 il limite e che cosa sia drammatico e cosa no?<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-36421\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/eutanasia.jpg\" alt=\"eutanasia\" width=\"240\" height=\"165\" \/>Basti pensare che in Olanda e Belgio si cominci\u00f2<\/strong> a permettere il suicidio assistito e l\u2019eutanasia solo per i malati in fin di vita, mentre ora in questi Stati vengono soppressi perfino i bambini, i depressi o gli anziani in salute. Infatti, quando si sceglie di fondare una legge sull\u2019autodeterminazione, e non sull\u2019oggettivit\u00e0 di un bene e un male iscritti nel cuore umano e nella legge naturale, di fatto si consegna la propria vita in mano al potere che determina (a seconda dei propri scopi) cosa sia degno o meno di esistere, inculcando nelle nostre teste l\u2019odio per ci\u00f2 che la mondanit\u00e0 non tollera: la nostra debolezza e quella di chi ci circonda, promemoria del fatto che siamo esseri amati non perch\u00e9 perfetti, ma perch\u00e9 creati. Amati nonostante i nostri limiti. Anzi compatiti da Dio con trasporto e commozione proprio perch\u00e9 fragili, peccatori e bisognosi.<\/p>\n<p style=\"text-align: justify;\"><strong>E\u2019 questo il malanno da cui siamo pi\u00f9 o meno afflitti da quando la modernit\u00e0 ha rifiutato<\/strong> Dio: vediamo il male in noi e intorno a noi e siccome desideriamo il paradiso, invece che cercare la salvezza nel Creatore, proviamo orgogliosamente a produrla con i soli nostri sforzi qui in terra. Ma, poi, siccome il male \u00e8 ineliminabile diventiamo violenti contro noi stessi e il mondo. Esattamente come Hitler, Stalin o i vari Cappato. Non a caso l\u2019estremo di questa posizione che tenta da sempre l\u2019uomo, sono le ideologie dei gulag, dei lager e oggi dell\u2019eutanasia, dell\u2019aborto, dell\u2019anoressia, della chirurgia estetica, della fecondazione in provetta, dell\u2019eliminazione del sesso di nascita. Artifici della perfezione impossibile, che non fanno che incrementare la disperazione dipinta sui volti dei cittadini occidentali, usati spesso inconsapevolmente come mezzi per un fine preciso: distruggere le creature di Dio.<\/p>\n<p style=\"text-align: justify;\"><strong>Poche ore prima di morire Dj Fabo ha lasciato un messaggio inquietante, dove con una voce<\/strong> che pareva gi\u00e0 venire dall\u2019oltretomba, ringraziava Marco Cappato di avergli pagato la morte assistita, senza rendersi conto (o forse s\u00ec?) che i Radicali lo hanno strumentalizzato per un fine politico. S\u00ec, lo hanno sacrificato sull\u2019altare della modernit\u00e0 che non sopporta la miseria, la malattia, la povert\u00e0. Tutte cose che ricordano anche a Cappato la verit\u00e0: pu\u00f2 cos\u00ec ribellarsi ma non sar\u00e0 mai Dio e anche se lo rifiutasse fino alla morte non ne avr\u00e0 scampo, perch\u00e9 anche all\u2019inferno non si pu\u00f2 scappare dalla sua paternit\u00e0 innamorata della nostra debolezza. Si pu\u00f2 bestemmiarla come fa il Capaneo dantesco, ma resta un dato ineliminabile, per l\u2019eternit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Questa tentazione, per\u00f2, non \u00e8 solo degli atei,<\/strong>\u00a0che spesso sanno invece dipendere dal mistero lasciandosi amare dai propri cari, ma anche dei \u201ccredenti\u201d che invitano a \u201ccostruire un mondo migliore\u201d, magari invocando lo spirito di Pannella (come ha fatto recentemente monsignor Vincenzo Paglia, capo della Pontificia accademia per la vita) invece di richiamare al fatto che la felicit\u00e0 piena sar\u00e0 solo in Paradiso e che per salvarci abbiamo bisogno unicamente di uno Spirito e della Sua Croce, quelli di Ges\u00f9. Non certo dei Radicali che per eliminare i problemi e i limiti eliminano gli uomini.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-27554\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/eutanasia.jpg\" alt=\"eutanasia\" width=\"240\" height=\"158\" \/>Ci sono diverse persone, malate da anni o che da tempo si fanno carico di parenti in<\/strong>\u00a0situazioni difficilissime, che nei giorni scorsi avrebbero voluto gridare a Fabiano che la vita vale la pena. Ma la stampa non gli ha dato la risonanza riservata all\u2019ex dj. Fra tutti \u00e8 impressionante la storia di un giovane in condizioni terribili che urla il suo amore per l\u2019esistenza. Questa gente non colpisce solo perch\u00e9 dimostra che esiste chi la pensa diversamente (cosa che non disturba affatto i radicali o la Lega di Salvini che riducono certe testimonianze a una fra le tante scelte), ma perch\u00e9 rivela che la posizione vera \u00e8 solo una.<\/p>\n<p style=\"text-align: justify;\"><strong>Matteo Nassigh \u00e8 un diciannovenne milanese<\/strong> che nei giorni scorsi ha provato a spiegare a dj Fabo: \u201cSe usi quelle dei Radicali noi siamo dei poverini, se scopri categorie che prevedono la libert\u00e0 di essere diversi noi siamo la massima espressione della libert\u00e0\u201d. Libert\u00e0? Matteo \u00e8 fermo su una carrozzina e dalla nascita non \u00e8 in grado di fare nulla da solo, tanto che pareva privo di coscienza. Invece, rinchiuso in quel corpo deforme c\u2019\u00e8 un\u2019intelligenza, scoperta dagli occhi amorevoli di alcuni medici e della sua famiglia, che hanno liberato la sua mente attraverso un sistema di scrittura con cui comunica aiutato dalla madre. Matteo continua cos\u00ec: \u201cE\u2019 vero, noi non possiamo fare niente da soli\u201d, ma \u201cFabo noi siamo il cambiamento che il mondo chiede per evolvere\u201d. E\u2019 proprio cos\u00ec, quanto bisogno hanno le persone di non essere misurate \u201cper ci\u00f2 che fanno\u201d, se no \u201c\u00e8 ovvio che uno come me o dj Fabo vuole solo morire\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>E\u2019 questo il pericolo di una legge, come quella sulle Dat, che legalizzerebbe l\u2019autodeterminazione<\/strong>\u00a0diffondendo lo sguardo nazista descritto da Matteo. Il giovane ha quindi incalzato parlando di ci\u00f2 che serve al mondo per guarire da questa ferocia autolesionista: \u201cSe avesse (dj Fabo, <em>ndr<\/em>) attorno a s\u00e9 tutto l\u2019amore che ho io, non cadrebbe nella trappola di misurarsi sulla perfezione fisica\u201d, ossia sui criteri mondani, \u201cma sulla sua anima intatta\u201d, come hanno fatto i suoi genitori che sono \u201cstati capaci di guardare oltre\u201d. Chi non vorrebbe essere amato cos\u00ec? Scoprendo che quello che non sopporta di s\u00e9, in realt\u00e0 serve a conoscere l\u2019abbraccio di Qualcuno che vinca il suo limite? Qualcuno che non ci vuole perfetti o diversi ma che chiede solo di permettergli di amarci cos\u00ec, miseri come siamo? Ogni uomo \u00e8 creato per scoprire, come Matteo, che questo Qualcuno esiste, venendo a dirci che \u201cciascuno di noi \u00e8 un prodigio di bellezza\u201d. Lui lo ha capito grazie a mamma e pap\u00e0, riflesso di un bene pi\u00f9 grande e motivo per cui \u201cil mio rapporto con Dio \u00e8 costante\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Tutti, appunto, siamo fatti per questo amore, anche se, come Lucifero, possiamo scegliere<\/strong>\u00a0di voler essere il Dio di noi stessi facendoci del male. Insomma, finch\u00e9 vivremo, saremo continuamente messi di fronte all\u2019alternativa posta da Matteo e dj Fabo, rappresentata dall\u2019umilt\u00e0 della Madonna, che accetta di essere un nulla innalzato da Dio, e la ribellione del diavolo, che lo fa sprofondare nell\u2019inferno. Ma in Italia sta accadendo di pi\u00f9: quando questa ribellione non \u00e8 pi\u00f9 opzione del singolo ma viene eretta a valore e norma di uno societ\u00e0, e quindi della cultura di un popolo, si sta consegnado di fatto il proprio Paese al pi\u00f9 grande nemico dell\u2019uomo. E\u2019 istituire l\u2019inferno quaggi\u00f9 mentre ci si illude di poter costruire paradisi artificiali, dove insieme alla debolezza faremo scomparire anche la carit\u00e0 che le si accompagna. Quella di cui oggi avremmo pi\u00f9 che mai bisogno per risorgere da una crisi senza pari.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Nuova bussola quotidiana 28 Febbraio 2017 Fabiano, noto come dj Fabo, volto della campagna pro eutanasia dell&#8217;associazione Luca Coscioni, \u00e8 stato ucciso ieri in una clinica svizzera dell&#8217;eutanasia. Ad accompagnarlo \u00e8 stato il politico radicale Marco Cappato che ne ha dato notizia via Twitter. di Benedetta Frigerio<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":37348,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[141],"class_list":["post-37347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eutanasia","tag-eutanasia-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fabo, un omicidio politico - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fabo, un omicidio politico - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-15T23:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/Fabo_eutanasia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"265\" \/>\n\t<meta property=\"og:image:height\" content=\"190\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Fabo, un omicidio politico\",\"datePublished\":\"2017-03-15T23:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/\"},\"wordCount\":1357,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Fabo_eutanasia.jpg\",\"keywords\":[\"eutanasia\"],\"articleSection\":[\"Eutanasia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/\",\"name\":\"Fabo, un omicidio politico - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Fabo_eutanasia.jpg\",\"datePublished\":\"2017-03-15T23:00:50+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Fabo_eutanasia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Fabo_eutanasia.jpg\",\"width\":265,\"height\":190},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fabo-un-omicidio-politico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fabo, un omicidio politico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fabo, un omicidio politico - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/","og_locale":"it_IT","og_type":"article","og_title":"Fabo, un omicidio politico - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-03-15T23:00:50+00:00","og_image":[{"width":265,"height":190,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/Fabo_eutanasia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Fabo, un omicidio politico","datePublished":"2017-03-15T23:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/"},"wordCount":1357,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/Fabo_eutanasia.jpg","keywords":["eutanasia"],"articleSection":["Eutanasia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/","name":"Fabo, un omicidio politico - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/Fabo_eutanasia.jpg","datePublished":"2017-03-15T23:00:50+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/Fabo_eutanasia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/Fabo_eutanasia.jpg","width":265,"height":190},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fabo-un-omicidio-politico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Fabo, un omicidio politico"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=37347"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37347\/revisions"}],"predecessor-version":[{"id":37349,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37347\/revisions\/37349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/37348"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=37347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=37347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=37347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}