{"id":37218,"date":"2017-02-23T00:00:59","date_gmt":"2017-02-22T23:00:59","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=37218"},"modified":"2023-01-31T11:33:07","modified_gmt":"2023-01-31T10:33:07","slug":"saper-scrivere-e-cosi-importante","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/","title":{"rendered":"Saper scrivere \u00e8 cos\u00ec importante?"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-37219\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/snoopy.png\" alt=\"snoopy\" width=\"250\" height=\"214\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/snoopy.png 320w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/snoopy-300x257.png 300w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><span style=\"color: #000000;\">Il Sole 24 Ore<\/span><\/strong><span style=\"color: #000000;\"> 12 12 Febbraio 2017<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Claudio Giunta<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tra i colpevoli della notevole inabilit\u00e0 alla scrittura di buona parte degli studenti italiani ci sono anch\u2019io.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ho appena messo 18 al compito scritto di uno studente della laurea magistrale in Lettere (quinto anno di universit\u00e0) che meritava invece di essere bocciato perch\u00e9, a parte conoscere maluccio il programma, ha grosse difficolt\u00e0 nello scrivere: mette male la punteggiatura, usa i verbi sbagliati, confonde le preposizioni (scrive per esempio che \u00abla squadra ha l\u2019intenzione a partecipare\u00bb, anzich\u00e9 \u201cdi partecipare\u201d) non sa fare un riassunto, nel senso che invece di riassumere l\u2019intero brano assegnato sintetizzandone il contenuto lo riassume frase per frase: \u00abL\u2019autore di questo brano dice che&#8230; Poi dice che&#8230; Poi dice che&#8230;\u00bb, e cos\u00ec via.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><!--more--><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-54136 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/05\/Universit\u00e0_Russia_studenti.jpg\" alt=\"\" width=\"323\" height=\"241\" \/>Lo studente che io adesso promuovo potrebbe prima o poi diventare un insegnante, e con un insegnante simile i suoi futuri studenti certamente non impareranno a scrivere (ci si potrebbe domandare: pu\u00f2 questo aspirante insegnante imparare a scrivere nei prossimi anni, tra il suo quinto anno di universit\u00e0 e la sua eventuale, speriamo scongiurabile, entrata in servizio? No, non pu\u00f2, non s\u2019impara a scrivere a ventitr\u00e9 anni).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">E allora perch\u00e9 l\u2019ho promosso? Dato che si discute, in questi giorni, della cattiva scrittura degli studenti, mi pare che la risposta a questa domanda possa interessare tutti. Ma non c\u2019\u00e8 una sola risposta, ce ne sono molte, o meglio c\u2019\u00e8 una risposta che si complica, si sfrangia in tante risposte pi\u00f9 piccole, una causa che si pu\u00f2 scomporre in concause.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55556 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/scrittura.jpg\" alt=\"\" width=\"335\" height=\"235\" \/>Diciamo intanto che lo studente a cui ho dato 18 ha ripetuto l\u2019esame quattro volte. La quarta \u00e8 andata meglio delle tre precedenti, nel senso che lo studente non ha smesso di impegnarsi: ha letto, ha studiato. Ma, quanto alla scrittura, non pu\u00f2 fare pi\u00f9 di cos\u00ec: avrebbe dovuto imparare a scrivere decentemente molti anni fa, ma non ha imparato, e adesso \u00e8 tardi. Alla quarta volta l\u2019ho promosso perch\u00e9, come mi ha ripetuto fino alla nausea, il mio \u00e8 \u00abil suo ultimo esame\u00bb, la tesi \u00e8 gi\u00e0 pronta da tempo, ed \u00e8 una tesi che non riguarda la mia materia: lo studente si laureer\u00e0 in storia contemporanea.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Bocciarlo ancora (e poi ancora, e ancora) avrebbe voluto dire impedirgli di laurearsi, fargli buttare via gli studi di cinque anni, rovinargli l\u2019esistenza. Tra l\u2019altro, lo studente non \u00e8 affatto sciocco, e ha un libretto pi\u00f9 che dignitoso. Non sa scrivere in un italiano decente, ma ha una media del 27-28, alcuni 30. Esami orali, voti in parte anche meritati. Di fatto, il mio \u00e8 uno dei non molti esami scritti che ci siano a Lettere; i pochi altri sono test a crocette, o sono esami scritti in cui il docente (legittimamente?) bada pi\u00f9 al contenuto che alla forma.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ma insomma, alla quarta volta \u2013 lo studente \u00e8 civile, \u00e8 anche, ripeto, intelligente \u2013 non me la sono sentita di bocciarlo ancora, e gli ho regalato un voto.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55558 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/giovani_scuola_universit\u00e0-300x166.jpg\" alt=\"\" width=\"381\" height=\"211\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/giovani_scuola_universit\u00e0-300x166.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/giovani_scuola_universit\u00e0.jpg 301w\" sizes=\"auto, (max-width: 381px) 100vw, 381px\" \/>Quattro volte? S\u00ec, perch\u00e9 l\u2019universit\u00e0 italiana \u00e8 quel luogo felice in cui gli studenti possono ripetere lo stesso esame virtualmente <em>all\u2019infinito<\/em>. Tre sessioni l\u2019anno, uno o due appelli a sessione, pi\u00f9 eventuali sessioni straordinarie: i miei studenti possono, come si dice, \u201ctentare\u201d il mio esame cinque o sei volte l\u2019anno, finch\u00e9 non lo passano (e infatti quattro non \u00e8 il record: ci sono studenti che lo hanno ripetuto sei, sette volte). In altre nazioni, chi viene bocciato all\u2019esame per due volte deve ripetere l\u2019intero anno; in alcune, una pluri-bocciatura comporta l\u2019espulsione dall\u2019universit\u00e0. Non in Italia. In Italia, una volta entrati, si ha il diritto di ripetere gli esami quante volte si vuole, cos\u00ec come si ha il diritto di non frequentare le lezioni. \u00c8 la libert\u00e0.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>Una volta entrati<\/em>, ho detto, e qui sta l\u2019altro problema, perch\u00e9 la porta dei dipartimenti di Lettere, a differenza di quella \u2013 poniamo \u2013 delle facolt\u00e0 di Medicina, \u00e8 sempre aperta. Ci sono in alcuni atenei, come mini-deterrenti, dei test d\u2019ingresso, ma sono test che hanno l\u2019obiettivo di permettere allo studente di autovalutarsi, di capire se quella \u00e8 davvero la sua strada, pi\u00f9 che di stabilire chi pu\u00f2 o non pu\u00f2 frequentare i corsi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55559 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/universit\u00e0.jpg\" alt=\"\" width=\"296\" height=\"222\" \/>Di fatto, \u00e8 normale leggere, nei bandi, che \u00abl\u2019esito del test non preclude la successiva immatricolazione al Corso di Laurea\u00bb (cito dal sito dell\u2019Universit\u00e0 di Bologna); e di fatto accade spesso che a Lettere finiscano per iscriversi ragazzi e ragazze che non hanno passato l\u2019esame d\u2019ammissione a corsi universitari o para-universitari pi\u00f9 selettivi ma di tutt\u2019altra indole, come Fisioterapia. Lettere \u00e8 un ripiego, magari momentaneo, in attesa di riprovare il test di Fisioterapia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Perch\u00e9 questa generosit\u00e0, questa politica di accoglienza <em>erga omnes<\/em>? Per varie ragioni. La prima \u00e8 che non si pu\u00f2 mettere il numero chiuso a tutti gli indirizzi di studio, altrimenti molti studenti non saprebbero che fare, dopo le superiori. A differenza dei corsi di medicina o di fisioterapia, i corsi di Lettere e Filosofia non hanno bisogno di laboratori, perci\u00f2 non esistono ragioni oggettive che impongano un filtro agli iscritti: dove si formano venti latinisti \u2013 questa la <em>ratio<\/em> (non molto razionale, in verit\u00e0) \u2013 se ne possono formare quaranta.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30459 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/libri.jpg\" alt=\"\" width=\"334\" height=\"221\" \/>La seconda \u00e8 che gli studi umanistici sono spesso intesi come una sorta di viatico all\u2019emancipazione personale, non solo cio\u00e8 un percorso professionalizzante ma l\u2019occasione per una crescita culturale, per migliorare se stessi: negare questa <em>chance<\/em> a studenti magari non manifestamente vocati alla carriera di intellettuali ma volenterosi, zelanti, davvero capaci di trarre profitto da lezioni su Aristotele, Shakespeare, Michelangelo, pu\u00f2 apparire ingiusto, anche odioso.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La terza, la pi\u00f9 importante, \u00e8 che qualsiasi universit\u00e0 ha tutto l\u2019interesse ad avere \u2013 nei limiti (assai elastici) imposti dalle sue strutture, e dall\u2019ampiezza del suo corpo docente \u2013 il maggior numero possibile di studenti, un po\u2019 perch\u00e9 gli studenti pagano le tasse e un po\u2019 (soprattutto) perch\u00e9 il ministero dell\u2019Istruzione finanzia le universit\u00e0 in proporzione al numero dei loro iscritti. Pochi studenti vogliono dire pochi soldi per aprire corsi di studio, assumere docenti, reclutare giovani ricercatori, organizzare congressi eccetera.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-52742 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/10\/Universit\u00e0_studenti_giovani-300x168.jpg\" alt=\"\" width=\"341\" height=\"191\" \/>Questa spiegabile politica delle \u201cporte aperte\u201d ha il suo prezzo: a Lettere s\u2019iscrivono molti studenti che non avrebbero bisogno di fare l\u2019universit\u00e0 ma di fare o rifare un buon liceo, e che \u2013 tra le altre cose \u2013 non sanno scrivere in italiano perch\u00e9 nessuno glielo ha mai insegnato.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Lo studente a cui ho dato 18 \u00e8 uno dei tanti: nelle sue condizioni, o peggio, si trova la maggior parte degli studenti che s\u2019iscrivono a Lettere. Bocciarli tutti? \u00c8 quasi impossibile. (1) Perch\u00e9 bocciare a ripetizione la met\u00e0 o pi\u00f9 dei candidati all\u2019esame di Letteratura italiana vorrebbe dire in pratica bloccare le carriere di decine e decine di studenti, con ovvie ripercussioni sulla vita dell\u2019intero dipartimento. (2) Perch\u00e9 le universit\u00e0 vengono premiate dal Ministero anche in ragione della <em>rapidit\u00e0<\/em> con cui gli studenti concludono i loro studi, cio\u00e8 arrivano alla tesi: vale a dire che le universit\u00e0 sono fortemente motivate a licenziare in fretta i loro studenti, a non avere fuori-corso; e i docenti sono tacitamente invitati ad aderire a questa <em>policy<\/em>, nel loro stesso interesse. (3) Perch\u00e9 bocciare qualcuno perch\u00e9 non sa scrivere non \u00e8 cos\u00ec facile. Abituati a \u201cbadare al contenuto e non alla forma\u201d, molti studenti non riescono a capire perch\u00e9 io dia tanta importanza ai loro errori o alla loro sciatteria nello scrivere.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-55560 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/scrittura_scuola_compito.jpg\" alt=\"\" width=\"355\" height=\"236\" \/>Se anche lo capiscono, se arrivano ad ammettere che la forma \u00e8 importante, possono non capire perch\u00e9 ci\u00f2 che scrivono non va bene, o possono obiettare che si tratta di errori veniali, di pura distrazione, che non giustificano la bocciatura. Offesi da questa ingiusta persecuzione, possono, a norma di regolamento, rivolgersi al rettore o al direttore di dipartimento per chiedere di fare l\u2019esame (oralmente) con un altro docente della stessa materia. Supereranno l\u2019esame, si laureeranno; e alcuni andranno a insegnare.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tutta questa spiegazione per dire che una delle ragioni per cui gli studenti non sanno scrivere (insieme alla disaffezione alla lettura, al contagio del linguaggio affrettato degli sms e di Facebook, alla prevalenza del visivo sullo scritto, eccetera) \u00e8 che non sanno scrivere molti dei laureati in Lettere che andranno a insegnare nelle scuole, laureati che non potranno ovviamente insegnare ad altri ci\u00f2 che loro stessi non sanno fare.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-27170 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Universit\u00e0_ME.jpg\" alt=\"\" width=\"343\" height=\"258\" \/>Questo accade perch\u00e9, come ho cercato di spiegare, tutti gli attori coinvolti (gli studenti, le famiglie, i docenti universitari, l\u2019amministrazione universitaria) hanno interesse a far s\u00ec che le cose vadano in questo modo, ragion per cui non si vede proprio come sia possibile uscire da questa situazione, salvo un ripensamento complessivo della formazione scolastica e universitaria, con enormi investimenti e progetti di medio-lungo periodo che ignorino l\u2019utilit\u00e0 immediata e le mode: niente che sia realistico aspettarsi (l\u2019idea che, come recita il manifesto steso dal \u00abGruppo di Firenze per la scuola del merito e della responsabilit\u00e0\u00bb, la salvezza possa venire da \u00abuna revisione delle indicazioni nazionali che dia grande rilievo all\u2019acquisizione delle competenze di base, fondamentali per tutti gli ambiti disciplinari\u00bb mi pare molto ingenua).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Oppure no? La soluzione potrebbe arrivare, sta gi\u00e0 arrivando forse, da tutt\u2019altra direzione, il nodo potrebbe essere tagliato anzich\u00e9 sciolto. Provo a spiegarmi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55561 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/scrittura-1-300x168.jpg\" alt=\"\" width=\"354\" height=\"198\" \/>La competenza nella scrittura, il saper scrivere decentemente, declina anche per una ragione molto semplice e concreta, una ragione che \u2013 magari inconsciamente \u2013 \u00e8 ben chiara agli studenti che hanno fretta di laurearsi (e pi\u00f9 ancora alle loro famiglie che li mantengono), e cio\u00e8 che saper scrivere decentemente, alla fine, non \u00e8 cos\u00ec importante. Lo era senz\u2019altro nell\u2019Epoca della Scarsit\u00e0, quando coloro che avevano accesso alla sfera pubblica erano pochi, e soprattutto quando il sapere tecnico-scientifico era percepito come meno rilevante rispetto a quella infarinatura umanistica che dava accesso alle professioni di prestigio sia nel settore pubblico sia in quello privato, un\u2019infarinatura della quale il saper scrivere non bene, magari, ma \u201celegante\u201d costituiva una parte non secondaria (che poi l\u2019elegante confliggesse spesso con il bene, onde l\u2019atrocissimo bellettrismo italiano, \u00e8 un altro discorso).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Era un saper scrivere che implicava, prima ancora della cura nello stile, la calligrafia (abolita come materia alle elementari nel 1985, quando Disegno e scrittura diventano Educazione all\u2019immagine) e la consapevolezza di come andava strutturato un testo \u201cben fatto\u201d (accapo, rientri, maiuscole, corsivi, formule protocollari ed escatocollari, eccetera).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-49635 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/01\/Dante_divina_commedia-1.jpg\" alt=\"\" width=\"341\" height=\"195\" \/>Non \u00e8 invece molto importante, saper scrivere, nell\u2019Epoca dell\u2019Abbondanza, quando ogni individuo ha infinite possibilit\u00e0 di scrivere e di essere letto da un pubblico infinitamente pi\u00f9 ampio di quello sul quale potevano contare gli scrittori del passato. Dato che lo scrivere (e anche lo scrivere per un pubblico) \u00e8 diventato un\u2019attivit\u00e0 ordinaria come parlare o come leggere, molti di coloro che scrivono sono indifferenti alle regole della buona forma, o non le hanno mai veramente imparate.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Per esempio. Scrivere direttamente al computer \u00e8 una cosa tanto normale, per gli studenti di oggi, che far loro osservare che sarebbe meglio scrivere prima su carta, e solo in un secondo tempo passare alla \u201cbella\u201d sullo schermo, suona come una bizzarria. Di fatto, \u00e8 una raccomandazione che faccio spesso ai miei studenti, ed \u00e8 significativo che, come mi spiegano, nessun altro \u2013 genitore o insegnante \u2013 gliel\u2019abbia mai fatta prima. Si pensa evidentemente che i \u201cnativi digitali\u201d siano cos\u00ec abituati al pc da essere in grado di scrivere direttamente su schermo: ma basta leggere quello che scrivono per capire che non \u00e8 cos\u00ec. O meglio, basta leggere quello che scrivono se chi legge \u00e8 in grado di distinguere una frase corretta da una frase scorretta, e una frase ben congegnata da una frase sbilenca: una competenza che, per le ragioni che ho detto, manca a molti insegnanti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-45232 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/computer-300x168.jpg\" alt=\"\" width=\"348\" height=\"195\" \/>Ma non \u00e8 che si scrive peggio perch\u00e9 si scrive di pi\u00f9, o pi\u00f9 in fretta. Si scrive peggio soprattutto perch\u00e9 l\u2019infarinatura umanistica che era tenuta in gran conto fino a qualche generazione fa \u00e8 diventata secondaria, a fronte di altre competenze, o a fronte di niente, ed \u00e8 per esempio perfettamente possibile entrare a far parte della \u201cclasse dirigente\u201d senza aver letto dei libri e senza saper scrivere in italiano.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il deputato Alessandro Di Battista (laurea al DAMS di Roma Tre), che aspira alla carica di Presidente del Consiglio, o perlomeno di ministro, critica durante la trasmissione televisiva <em>DiMarted\u00ec<\/em> (La7, 24 gennaio 2017), \u00abcoloro che hanno magari paura che potremo svelare alcune porcate reali e molto molto grandi che <em>appunto inficiano l\u00ec, sulla carne dei cittadini italiani e sui diritti di tutti noi italiani<\/em>\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55562 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/scuola.jpg\" alt=\"\" width=\"316\" height=\"203\" \/>Evidentemente, nella sua formazione, Di Battista non ha investito molto sull\u2019italiano parlato e scritto. Gli si pu\u00f2 dare torto, considerando la carriera che ha fatto? E del resto: quale messaggio, quale idea di formazione trapela dal progetto di Alternanza Scuola-Lavoro, che sostituisce alcune decine di ore curricolari con esperienze lavorative all\u2019interno di aziende o uffici pubblici?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Se davvero fossimo convinti che studiare con seriet\u00e0 e continuit\u00e0 discipline come l\u2019italiano o la storia o la biologia o la matematica \u00e8 il modo migliore per crescere e per trovarsi un lavoro, accetteremmo davvero di farci rosicchiare il tempo-scuola dalla gita d\u2019istruzione, dal Campus sulla Legalit\u00e0, dalla Settimana della Cittadinanza, dalla Giornata della Memoria, dallo stage in biblioteca?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">C\u00e0pita che la devozione continui anche molto tempo dopo che il dio che si prega \u00e8 morto.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-55563 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/alluvione_Firenze.jpg\" alt=\"\" width=\"261\" height=\"193\" \/>Mancando, per cos\u00ec dire, la domanda sociale del prodotto, non c\u2019\u00e8 dunque neppure ragione di coltivarlo, ovvero non c\u2019\u00e8 ragione per non accontentarsi di un prodotto meno curato, e insomma di testi brutti, ma comunque comprensibili, anzich\u00e9 di testi ben scritti. Non coltivando il prodotto, non si coltiva neppure la sensibilit\u00e0 idonea ad apprezzarlo, ed ecco che non solo si fanno errori che passano inosservati tanto a chi scrive quanto a chi legge (cinquantenario dell\u2019alluvione di Firenze, cartello commemorativo: gli \u201cangeli del fango\u201d salvarono il patrimonio artistico della citt\u00e0 \u00ablavorando giorno e notte <em>in condizioni affatto favorevoli<\/em>\u00bb), ma si generalizza anche il vizio italianissimo della <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-55564 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/scrittura-2-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/>\u201celeganza\u201d, della parola scelta l\u00e0 dove starebbe meglio la parola comune (stazione di Firenze: \u00ab<em>Discendere<\/em> dal lato opposto\u00bb, anzich\u00e9 scendere), si adoperano a casaccio le preposizioni (articolo del noto giornalista X: \u00abHo avuto come <em>un soprassalto a trovare<\/em>&#8230; Una mattina <em>mi telefon\u00f2 a offrirmi<\/em> un contratto&#8230; Una malattia <em>contro cui non c&#8217;\u00e8 scampo<\/em>\u00bb), si usano a sproposito le locuzioni idiomatiche (pagina di un manuale scolastico: \u00ab<em>Angelica cadde a gambe levate<\/em>\u00bb), e pi\u00f9 in generale, senza che la sciatteria comporti veri e propri errori, si scrive male, e si accettano testi scritti male, anche l\u00e0 dove, data la sede, ci si aspetterebbe un po&#8217; di cura.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-35760 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/01\/giornali.jpg\" alt=\"\" width=\"329\" height=\"206\" \/>Alla cattiva scrittura corrisponde un cattivo contenuto? Non \u00e8 detto: l\u2019articolo del noto giornalista X che ho appena citato \u00e8 mal scritto, ma contiene osservazioni interessanti. Del resto, scrivere per il web (il giornalista X scrive per il web) non \u00e8 come scrivere un articolo per un giornale di carta, e scrivere un articolo per un giornale di carta non \u00e8 come scrivere un libro: \u00e8 comprensibile che l\u2019attenzione e la cura aumentino progressivamente, dal primo all\u2019ultimo passaggio, a mano a mano che aumentano il tempo d\u2019esecuzione e l\u2019ipotetica \u201cdurata\u201d del testo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00c8 un fatto per\u00f2 che la gran parte dei testi che si scrivono e si leggono oggi si scrivono e si leggono direttamente su uno schermo. Il 18 gennaio 2017, sul quotidiano che riportava con grande evidenza l\u2019appello allarmato dei \u00ab600 professori\u00bb sugli studenti che non sanno scrivere, ho letto questo titolo: \u00ab40 anni fa la morte di Re Cecconi, l\u2019eroe della Lazio ucciso perch\u00e9 <em>confuso per un ladro<\/em>\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-55565 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/scrittura-3-300x167.jpg\" alt=\"\" width=\"300\" height=\"167\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/scrittura-3-300x167.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/scrittura-3.jpg 301w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>A parte il misterioso epiteto di <em>eroe<\/em> (perch\u00e9 mai?), chi ha scritto il titolo non sa, evidentemente, che si pu\u00f2 dire \u201cpreso per un ladro\u201d, ma non si pu\u00f2 dire \u201cconfuso per un ladro\u201d. \u00c8 il genere di errore che anni fa sarebbe stato inconcepibile, sulle pagine di un grande giornale. Ma oggi, in rete, i titoli cambiano ogni cinque minuti, e semplicemente non c\u2019\u00e8 tempo per verificare tutto, e non \u00e8 economico farlo: i lettori e gli abbonati non diminuiscono per una preposizione sbagliata, dunque non sono cose per le quali abbia senso darsi molta pena.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55566 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/compiuter.jpg\" alt=\"\" width=\"325\" height=\"193\" \/>Su un altro pi\u00f9 decisivo piano, la tendenza, anche nelle scuole, ad affidarsi sempre pi\u00f9 spesso all\u2019<em>ebook<\/em> o alla rete, abolendo o marginalizzando i libri di testo, e obliterando cos\u00ec quella distinzione tra, in breve, libro di carta autorevole e testi effimeri da consumarsi su schermo (notizie, giochi, email, video), una distinzione che molti si sono sforzati di conservare in questa primissima et\u00e0 del web, questa tendenza non sembra poter avere se non un\u2019influenza negativa sulla qualit\u00e0 <em>media<\/em> dell\u2019espressione scritta dei futuri adulti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Questo non vuol dire che saper scrivere bene non possa restare, per alcuni, un traguardo da raggiungere, e un requisito da parte di datori di lavoro particolarmente esigenti; ma, parlando sempre di medie e non di picchi, di scriventi e non di scrittori, sono del parere che in futuro diventer\u00e0 qualcosa di simile a una bella virt\u00f9 privata, come saper dipingere o cantare bene. Ma perch\u00e9 parlare di futuro? Per molti versi, come mostrano gli esempi che ho citato, \u00e8 gi\u00e0 cos\u00ec. E il sole non ha smesso di sorgere, direbbero gli ottimisti: senza avere tutti i torti.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Sole 24 Ore 12 12 Febbraio 2017 di Claudio Giunta Tra i colpevoli della notevole inabilit\u00e0 alla scrittura di buona parte degli studenti italiani ci sono anch\u2019io. Ho appena messo 18 al compito scritto di uno studente della laurea magistrale in Lettere (quinto anno di universit\u00e0) che meritava invece di essere bocciato perch\u00e9, a &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":37219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,8],"tags":[2566,812,2567],"class_list":["post-37218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-costume","category-cultura-e-tradizioni","tag-lingua-italiana","tag-linguaggio","tag-scrittura","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saper scrivere \u00e8 cos\u00ec importante? - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saper scrivere \u00e8 cos\u00ec importante? - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-22T23:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-31T10:33:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/snoopy.png\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Saper scrivere \u00e8 cos\u00ec importante?\",\"datePublished\":\"2017-02-22T23:00:59+00:00\",\"dateModified\":\"2023-01-31T10:33:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/\"},\"wordCount\":2828,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/snoopy.png\",\"keywords\":[\"lingua italiana\",\"linguaggio\",\"scrittura\"],\"articleSection\":[\"Costume\",\"Cultura e tradizioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/\",\"name\":\"Saper scrivere \u00e8 cos\u00ec importante? - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/snoopy.png\",\"datePublished\":\"2017-02-22T23:00:59+00:00\",\"dateModified\":\"2023-01-31T10:33:07+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/snoopy.png\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/snoopy.png\",\"width\":320,\"height\":274},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/saper-scrivere-e-cosi-importante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saper scrivere \u00e8 cos\u00ec importante?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saper scrivere \u00e8 cos\u00ec importante? - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/","og_locale":"it_IT","og_type":"article","og_title":"Saper scrivere \u00e8 cos\u00ec importante? - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2017-02-22T23:00:59+00:00","article_modified_time":"2023-01-31T10:33:07+00:00","og_image":[{"width":320,"height":274,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/snoopy.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"14 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Saper scrivere \u00e8 cos\u00ec importante?","datePublished":"2017-02-22T23:00:59+00:00","dateModified":"2023-01-31T10:33:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/"},"wordCount":2828,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/snoopy.png","keywords":["lingua italiana","linguaggio","scrittura"],"articleSection":["Costume","Cultura e tradizioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/","name":"Saper scrivere \u00e8 cos\u00ec importante? - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/snoopy.png","datePublished":"2017-02-22T23:00:59+00:00","dateModified":"2023-01-31T10:33:07+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/snoopy.png","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/02\/snoopy.png","width":320,"height":274},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/saper-scrivere-e-cosi-importante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Saper scrivere \u00e8 cos\u00ec importante?"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=37218"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37218\/revisions"}],"predecessor-version":[{"id":55567,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/37218\/revisions\/55567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/37219"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=37218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=37218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=37218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}