{"id":36449,"date":"2016-10-06T00:00:19","date_gmt":"2016-10-05T22:00:19","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=36449"},"modified":"2016-09-30T18:31:15","modified_gmt":"2016-09-30T16:31:15","slug":"investire-sui-figli-genera-ricchezza","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/","title":{"rendered":"Investire sui figli genera ricchezza"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-36450\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/famiglia_numerosa.jpg\" alt=\"famiglia_numerosa\" width=\"240\" height=\"181\" \/>A cura dell\u2019<strong>Associazione famiglie numerose <\/strong><\/p>\n<p style=\"text-align: center;\">(<a href=\"http:\/\/www.famiglienumerose.org\/\">http:\/\/www.famiglienumerose.org\/<\/a>)<\/p>\n<p style=\"text-align: center;\">28 settembre 2016<\/p>\n<p><em>In uno studio Anfn avanza 26 proposte per sostenere le famiglie con figli, ridare speranza alla generazione core e favorire il rilancio della natalit\u00e0<\/em><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Investire sul benessere familiare e sui figli \u2013 almeno fino alla loro autonomia \u2013 genera ricchezza: maggiori consumi e pi\u00f9 posti di lavoro. Rimuovere ostacoli culturali ed economici per allineare il numero dei figli desiderati (almeno due) a quelli effettivamente portati alla luce (oggi una media di 1.3 per ogni donna fertile) garantisce il <strong>ricambio generazionale <\/strong>dunque la sopravvivenza dell\u2019Italia ed evita la frantumazione del welfare. Ne \u00e8 convinta Anfn, l\u2019associazione che raduna e d\u00e0 voce alle famiglie numerose in Italia.<\/p>\n<p style=\"text-align: justify;\">\u00abLa rinascita dell\u2019Italia\u00bb \u00e8 il titolo di un documento elaborato dal centro studi Anfn che si conclude con 26 idee: per mettere i giovani nella condizione di metter su famiglia e di generare futuro. E per sostenere quelle coppie che decidono di mettere al mondo uno o pi\u00f9 figli. Proposte messe a disposizione di governo e parlamento per l\u2019elaborazione di una legge organica sulle politiche familiari, specie quelle destinate alle coppie che decidono di mettere al mondo pi\u00f9 figli.<\/p>\n<p style=\"text-align: justify;\">Il documento \u2013 presentato nelle scorse settimane al ministro Enrico Costa \u2013 \u00e8 anche a disposizione della conferenza stato-regioni, perch\u00e9 l\u2019attuazione di molte delle proposte \u00e8, appunto, di competenza regionale.<\/p>\n<p style=\"text-align: justify;\"><strong>Le ragioni della crisi di un modello \u2013 <\/strong>Fino al dopoguerra \u2013 ricostruisce l\u2019Associazione nazionale famiglie numerose \u2013 l\u2019Italia viveva grazie soprattutto all\u2019agricoltura. I figli erano visti come una ricchezza, perch\u00e9 manodopera fondamentale per il lavoro nei campi. Erano dunque un bene sociale da tutelare, come espresso dai padri costituenti negli articoli 29, 30 e 31 della Costituzione.<\/p>\n<p style=\"text-align: justify;\">Nel passaggio all\u2019economia industriale, \u00e8 arrivato il benessere ed il consumismo. Con il \u201968 si \u00e8 affermato il movimento politico e sociale che ha portato alla graduale affermazione dei diritti individuali. I figli non sono stati percepiti come un bene pubblico da tutelare, ma una scelta privata.<\/p>\n<p style=\"text-align: justify;\"><strong>La riduzione delle politiche familiari \u2013 <\/strong>Il primo risultato \u00e8 stata la progressiva riduzione dei fondi destinati alla famiglia: il nostro Stato destina appena l\u20191,3% del suo Pil in politiche per la famiglia, contro il 2,1% dei 27 paesi della Unione europea (fonte Universit\u00e0 Cattolica).<\/p>\n<p style=\"text-align: justify;\"><strong>Fisco iniquo <\/strong>\u2013 Anche la fiscalit\u00e0, orientata all\u2019individuo e non alla famiglia tiene conto \u2013 ricostruisce Anfn \u2013 solo del principio di equit\u00e0 verticale (chi pi\u00f9 guadagna, pi\u00f9 paga) ma non di quello di equit\u00e0 orizzontale (cio\u00e8 di quante persone vivono su quel reddito).<\/p>\n<p style=\"text-align: justify;\"><strong>Il gap con i cugini francesi \u2013 <\/strong>In Italia una coppia che vive con un reddito imponibile di 35mila euro l\u2019anno paga al Fisco 8.951 euro, se ha un figlio paga 7.726 euro, se ne ha due 7.140 euro, se ne ha tre 6.505 euro, se ne ha quattro 4.031 euro. Nella vicina Francia, a parit\u00e0 di reddito imponibile, la famiglia con tre figli paga 692 euro, con quattro 380 euro.<\/p>\n<p style=\"text-align: justify;\">E il motivo \u00e8 semplice: in Italia il primo figlio vale, secondo la scala di equivalenza Isee 0,47, il secondo 0.42, il terzo 0.39, il quarto 0.35. In Francia i primi due figli, se osserviamo il quoziente familiare, valgono 0.50, dal terzo in poi ogni figlio vale 1<\/p>\n<p style=\"text-align: justify;\">Una condizione non pi\u00f9 sostenibile. Prova ne \u00e8 che in occasione del sondaggio somministrato da Anfn alle famiglie associate, alla domanda <em>avete mai pensato di trasferirvi in alcuni paesi dell\u2019estero dove c\u2019\u00e8 un fisco pi\u00f9 family friendly? <\/em>Due famiglie su tre intervistate hanno risposto di averci pensato ma di aver deciso di non farne di niente e una su sei di aver intenzione di farlo.<\/p>\n<p style=\"text-align: justify;\"><strong>FAMIGLIE POVERE <\/strong>\u2013 Sar\u00e0 per la fiscalit\u00e0 verticale e non orizzontale che, come certifica l\u2019Istat, la possibilit\u00e0 che una coppia cada sulla soglia della povert\u00e0 aumenta \u2013 seguendo un trend esponenziale \u2013 con la crescita del numero dei figli. Secondo un sondaggio Anfn la busta paga che entra in una famiglia numerosa ogni mese si svuota, in un caso su sei, entro i primi dieci giorni, e in un caso su due entro i primi venti. In media un introito in una famiglia numerosa basta per sedici giorni del mese.<\/p>\n<p style=\"text-align: justify;\">Conclusioni prevedibili se diamo ragione ad uno studio Anfn \u2013 ancora in sintonia con il Libro bianco dell\u2019ex ministro al welfare Roberto Maroni \u2013 secondo cui ogni figlio costa ai suoi genitori poco pi\u00f9 di 8.400 euro l\u2019anno.<\/p>\n<p style=\"text-align: justify;\"><strong>FAMIGLIE PANDA <\/strong>\u2013 Sono 4.628.991 oggi, in Italia, le coppie senza figli, 8 milioni e 6226 quelle con figli. Le famiglie numerose sono una rarit\u00e0: quelle con almeno tre figli sono 742.871, le coppie che risiedono insieme ad almeno 4 figli sono appena 131.646. 55 anni fa, dunque nel censimento Istat del 1961, le grandi famiglie (composte da pap\u00e0, mamma ed almeno quattro figli) erano circa tre milioni.<\/p>\n<p style=\"text-align: justify;\"><strong>GENERAZIONE CORE <\/strong>\u2013 Anche in questo caso le azioni mirate al contrasto alla povert\u00e0 messe in campo negli ultimi decenni dai governi di ogni colore si sono indirizzate a target precisi: single ed anziani. Trascurando le famiglie, specie quelle pi\u00f9 numerose. E i giovani, la cosiddetta generazione core \u2013 quella che va dai 20 ai 39 anni \u2013 la pi\u00f9 produttiva, la pi\u00f9 importante per lo sviluppo del Pil, in Italia in progressiva diminuzione.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.famiglienumerose.org\/anfn-ha-presentato-oggi-a-montecitorio-la-sua-piattaforma-26-idee-per-la-ri-nascita-dellitalia\/\" target=\"_blank\">26 PROPOSTE PER UNA INVERSIONE DI ROTTA<\/a> <\/strong>\u2013 Pi\u00f9 fondi per le politiche di natalit\u00e0. Un reddito di nativit\u00e0. Un fisco a misura di famiglia. Assegni familiari pi\u00f9 pesanti. Contributi figurativi per chi mette al mondo diversi figli. L\u2019aumento del limite di reddito perch\u00e9 i figli vengano considerati a carico. Ticket sanitari e tariffe di acqua, luce e gas che tengano conto del numero delle persone che abitano in casa: sono alcune delle 26 proposte che Anfn mette alla discussione dei parlamentari.<\/p>\n<p style=\"text-align: justify;\">Anfn fa sua la campagna europea per l\u2019abbattimento dell\u2019Iva sui pannolini. Chiede corsie preferenziali per l\u2019accesso al lavoro di pap\u00e0 e figli che vivono in famiglie numerose (una normativa che esisteva in passato e che poi \u00e8 stata abolita). Una edilizia agevolata a misura anche di famiglie XXL: Altra proposta originale: un voto per ogni componente della famiglia.<\/p>\n<p style=\"text-align: justify;\">E poi voucher per gli studi, tenendo conto che una famiglia con pi\u00f9 figli su cinque, secondo un sondaggio Anfn, non pu\u00f2 permettersi di inviare i propri figli all\u2019universit\u00e0.<\/p>\n<p style=\"text-align: justify;\">La carta famiglia nazionale: il decreto attuativo doveva essere partorito entro marzo, ancora non \u00e8 stato varato. Un ritardo vergognoso.<\/p>\n<p style=\"text-align: justify;\">Ogni normativa dovrebbe essere sottoposta ad una preventiva valutazione sul suo impatto sulla famiglia.<\/p>\n<p style=\"text-align: justify;\">Su addizionali, ticket sanitari, trasporti, diritto allo studio la richiesta \u2013 rivolta alle regioni \u2013 domani convocate dal ministro Costa nella conferenza stato-regioni, di tener conto dei carichi familiari.<\/p>\n<p style=\"text-align: justify;\">Sostenere i nostri figli dai primi mesi di vita fino all\u2019autonomia produce ricchezza. Secondo gli esperti Anfn investire \u2013 contemporaneamente \u2013 su generazione core, famiglia e figli genera un aumento del Pil pari all\u20191,65% su base annua. E un milione di posti di lavoro in cinque anni.<\/p>\n<p style=\"text-align: justify;\">Insomma: i figli sono un investimento sul futuro. E per la tenuta dello Stato sociale: senza di loro chi pagher\u00e0 le pensioni dei loro padri e delle loro madri? E chi assister\u00e0 i loro vecchi? Per non parlare della spesa sanitaria e sociale, che non sar\u00e0 pi\u00f9 sostenibile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cura dell\u2019Associazione famiglie numerose (http:\/\/www.famiglienumerose.org\/) 28 settembre 2016 In uno studio Anfn avanza 26 proposte per sostenere le famiglie con figli, ridare speranza alla generazione core e favorire il rilancio della natalit\u00e0<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":36450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,15],"tags":[1261],"class_list":["post-36449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-demografia","category-famiglia","tag-denatalita","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investire sui figli genera ricchezza - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investire sui figli genera ricchezza - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-05T22:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/famiglia_numerosa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"258\" \/>\n\t<meta property=\"og:image:height\" content=\"195\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Investire sui figli genera ricchezza\",\"datePublished\":\"2016-10-05T22:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/\"},\"wordCount\":1154,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/famiglia_numerosa.jpg\",\"keywords\":[\"denatalit\u00e0\"],\"articleSection\":[\"Demografia\",\"Famiglia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/\",\"name\":\"Investire sui figli genera ricchezza - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/famiglia_numerosa.jpg\",\"datePublished\":\"2016-10-05T22:00:19+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/famiglia_numerosa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/famiglia_numerosa.jpg\",\"width\":258,\"height\":195},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/investire-sui-figli-genera-ricchezza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investire sui figli genera ricchezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investire sui figli genera ricchezza - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/","og_locale":"it_IT","og_type":"article","og_title":"Investire sui figli genera ricchezza - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2016-10-05T22:00:19+00:00","og_image":[{"width":258,"height":195,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/famiglia_numerosa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Investire sui figli genera ricchezza","datePublished":"2016-10-05T22:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/"},"wordCount":1154,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/famiglia_numerosa.jpg","keywords":["denatalit\u00e0"],"articleSection":["Demografia","Famiglia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/","name":"Investire sui figli genera ricchezza - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/famiglia_numerosa.jpg","datePublished":"2016-10-05T22:00:19+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/famiglia_numerosa.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/famiglia_numerosa.jpg","width":258,"height":195},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/investire-sui-figli-genera-ricchezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Investire sui figli genera ricchezza"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/36449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=36449"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/36449\/revisions"}],"predecessor-version":[{"id":36451,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/36449\/revisions\/36451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/36450"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=36449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=36449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=36449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}