{"id":36434,"date":"2016-10-06T00:00:31","date_gmt":"2016-10-05T22:00:31","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=36434"},"modified":"2016-09-26T10:36:31","modified_gmt":"2016-09-26T08:36:31","slug":"te-lo-do-io-lamore-per-gli-animali","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/","title":{"rendered":"Te lo do io l\u2019amore per gli animali"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-36435\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/cacciatori.jpg\" alt=\"cacciatori\" width=\"250\" height=\"159\" \/>Tempi.it<\/strong> 13 giugno 2016<\/p>\n<p style=\"text-align: justify;\"><em>Intervista a Massimiliano Filippi, fondatore di FederFauna, paladino di allevatori, cacciatori, zoo e circhi. Lettura sconsigliata a un pubblico sensibile alle campagne politicamente corrette e a chi condivide foto di gattini su Facebook<\/em><\/p>\n<p style=\"text-align: center;\"><strong>Pietro Piccinini<\/strong><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">A Massimiliano Filippi bisogna riconoscere come minino che ha del coraggio. Veneto, allevatore rampollo di una famiglia di allevatori, nel 2008 davanti alla marea montante animalista ha deciso di suonare una sveglia per l\u2019associazionismo del suo mondo, dando vita \u00abcon alcuni amici volenterosi\u00bb a una confederazione sindacale un po\u2019 pi\u00f9 \u201cspinta\u201d, per cos\u00ec dire. A guardarli con freddezza sito web e vetrine social di FederFauna sono uno spasso. Oltre ai contenuti da classica battaglia di rappresentanza, Filippi e i suoi pubblicano un sacco di cose politicamente scorrettissime.<\/p>\n<p style=\"text-align: justify;\">Articoli che sembrano barzellette (\u201cMonaco, struzzo del circo liberato dagli animalisti viene investito e ucciso da un\u2019auto\u201d), scherzi da gelo in sala (vedi il disegno fanciullesco della chioccia che mangia becchime con la didascalia \u201cla campagna \u00e8 quella cosa dove le galline vanno in giro crude\u201d, copyright del gruppo Facebook \u201cVegano stammi lontano\u201d), consigli che rasentano la provocazione (\u201cMondo barbecue: 10 ricette con l\u2019agnello per Pasqua\u201d), rappresentazioni della realt\u00e0 abbastanza originali (\u201cIl vento cambia! Nel 2015 in Italia il numero dei cacciatori \u00e8 cresciuto\u201d). Celeberrimo il Premio Hitler, una targa con il F\u00fchrer che accarezza due caprioli davanti al cancello di Auschwitz sotto il motto \u201cAnimal Reich\u201d, assegnato ogni anno da FederFauna a personalit\u00e0 che si distinguono per capacit\u00e0 di \u00abcalpestare i Diritti Umani in nome di ideologici diritti degli animali\u00bb.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30503 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/animalisti.jpg\" alt=\"animalisti\" width=\"170\" height=\"117\" \/>FederFauna difende gli allevamenti, le macellerie, la caccia, lo zoo, il circo. Tutto ci\u00f2 che \u00e8 diventato indifendibile nell\u2019era dei gattini di Facebook. Ma quel che alimenta l\u2019impegno di Filippi non \u00e8 la faccia tosta del tale che si diverte a marciare contromano. Sembra tanto una battaglia culturale la sua. E in effetti \u00ablo \u00e8\u00bb, dice lui a Tempi. \u00abNoi difendiamo e promuoviamo quella che io chiamo la \u201ccultura rurale\u201d. Sono le nostre radici: la societ\u00e0 le sta perdendo e con esse perde un fondamento della nostra umanit\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 combattete gli animalisti?<\/strong><\/p>\n<p style=\"text-align: justify;\">Premetto che noi siamo assolutamente per il benessere animale: per me che faccio l\u2019allevatore \u00e8 un ottimo investimento. Se la vacca non sta bene, non fa mica il latte. Per\u00f2, siccome molta gente vivendo nelle citt\u00e0 ha perso il contatto con la natura, cio\u00e8 con la realt\u00e0, ecco che si fanno strada le ideologie fuorvianti, prima fra tutte l\u2019animalismo che noi combattiamo a spada tratta. Eravamo stufi di sentirci dire: \u201cMa dai, sono quattro gatti, che male vi fanno se vanno dietro ai cagnolini?\u201d. FederFauna \u00e8 nata per questo, perch\u00e9 questi quattro gatti, con la tattica del salame, una fetta alla volta sono arrivati a insidiare tutta la filiera zootecnica, tutte le imprese e le professioni connesse.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-34439\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/animalisti.jpg\" alt=\"animalisti\" width=\"170\" height=\"127\" \/>Sono cos\u00ec fastidiosi?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sono una lobby potente. Meglio: c\u2019\u00e8 un gruppetto tutto sommato ristretto di faccendieri che sanno gestire il potere e trarne beneficio. Accusano noi di sfruttare gli animali, ma loro cosa fanno? Pubblicano una fotografia e chiedono i soldi. E mentre la mia vacca deve star bene per fare il latte, il cagnolino della foto pi\u00f9 \u00e8 malconcio e pi\u00f9 frutta donazioni. Ma non sfruttano solo gli animali, sfruttano anche tutta una serie di mentecatti (e questi s\u00ec che sono tanti) che va da quelli che offendono e minacciano di morte su internet fino a quelli che fanno azioni di ecoterrorismo.<\/p>\n<p style=\"text-align: justify;\"><strong>E voi quanti siete?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sommando tutte le confederate rappresentiamo circa 100 mila persone. Ma quelli che in Italia hanno attivit\u00e0 economiche o ludiche con gli animali sono oltre 3 milioni. Saremmo una vera potenza. Purtroppo siamo disorganizzati. Quando si va in piazza si fa sempre una fatica micidiale a mettere insieme le persone.<\/p>\n<p style=\"text-align: justify;\"><strong>Non c\u2019\u00e8 bisogno di arrivare fino in piazza. Basta vedere Facebook: la Lega Antivivisezione vi straccia in quanto a fan.<\/strong><\/p>\n<p style=\"text-align: justify;\">Lasci perdere i \u201cmi piace\u201d, quelli si fa presto a gonfiarli. Comunque io sono il primo a essere convinto che la stragrande maggioranza degli italiani ami gli animali. Per\u00f2 tra gli amanti degli animali ci metto anche me che faccio l\u2019allevatore, mangio la carne e ho le scarpe in pelle.<\/p>\n<p style=\"text-align: justify;\"><strong>Quanti episodi di ecoterrorismo si sono registrati in Italia?<\/strong><\/p>\n<p style=\"text-align: justify;\">Decine e decine, da perdere il conto. Tra i pi\u00f9 grossi che mi vengono in mente, uno recente \u00e8 avvenuto l\u2019anno scorso, quando hanno dato fuoco ai camion di Veronesi. Ha presente, no? Veronesi Mangimi a Ospedaletto, provincia di Padova.<\/p>\n<p style=\"text-align: justify;\"><strong>Sinceramente no.<\/strong><\/p>\n<p style=\"text-align: justify;\">Vede? \u00c8 perch\u00e9 anche la stampa dedica poco interesse a questo problema. Sappia che a questa azienda hanno dato fuoco a 15 camion. Qualcosa di simile era successo al Centro Latticini di Montelupo Fiorentino nel 2013, stesso anno dell\u2019assalto allo stabulario del dipartimento di Farmacologia dell\u2019Universit\u00e0 di Milano. Nel novembre scorso sono entrati nell\u2019allevamento Rossi, nel Modenese. Gli hanno scavalcato il muro in pieno giorno, roba dell\u2019altro mondo. Ti svegli una mattina e trovi distrutto quello per cui hai lavorato anni. E spesso resti l\u00ec senza sapere cosa fare.<\/p>\n<p style=\"text-align: justify;\"><strong>Si pu\u00f2 cominciare dal denunciare questi reati alla magistratura.<\/strong><\/p>\n<p style=\"text-align: justify;\">Ma finch\u00e9 resteranno catalogati come atti di vandalismo, le forze dell\u2019ordine avranno sempre di meglio da fare. Non per niente sono anni che noi chiediamo una norma contro l\u2019ecoterrorismo come quella che c\u2019\u00e8 negli Stati Uniti e in altri paesi europei. \u00c8 l\u2019unico modo di arginare il problema. Non \u00e8 possibile che questi entrino nelle aziende di notte per rubare gli animali, distruggere le attrezzature, a volte mettendo a repentaglio la vita umana. Per non parlare poi di quella animale, visto che gli animali sgabbiati nove su dieci crepano, e crepano male.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Il Fatto quotidiano<\/strong><\/em> <strong>poche settimane fa ha riconosciuto che le lobby animaliste sono le pi\u00f9 efficaci in Italia. Anche voi fate lobbying?<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30114 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/animalisti.jpg\" alt=\"animalisti\" width=\"180\" height=\"120\" \/>Abbiamo cominciato, certo. Sottolineo per\u00f2 che noi ci muoviamo cercando di difendere l\u2019esistente, soprattutto le imprese e i lavoratori. Le lobby animaliste invece inventano leggi per far soldi. Credo che la 189 sia l\u2019unica legge al mondo che consente a uno stesso soggetto di denunciare un presunto reato di maltrattamento di animali, di collaborare al sequestro degli animali coinvolti, di diventare affidatario degli stessi, nonch\u00e9 destinatario dell\u2019introito delle sanzioni nel caso in cui il processo porti a una condanna, e infine di costituirsi parte civile e chiedere i danni.<\/p>\n<p style=\"text-align: justify;\"><strong>Niente male.<\/strong><\/p>\n<p style=\"text-align: justify;\">Se il vigile incassasse le multe che fa, ne farebbe centomila.<\/p>\n<p style=\"text-align: justify;\"><strong>Lei personalmente ha sub\u00ecto attacchi?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sono venuti dentro l\u2019allevamento due o tre anni fa. Non hanno trovato niente da denunciare, hanno solo pubblicato le foto e scritto che ho quattromila visoni. Han contato male: sono seimila.<\/p>\n<p style=\"text-align: justify;\"><strong>Le \u00e8 andata bene che non ci fosse neanche un animale ferito?<\/strong><\/p>\n<p style=\"text-align: justify;\">Ma sarebbe stata una cosa normale. L\u2019altro giorno ho visto un servizio di Report: una donna \u00e8 entrata di nascosto in una fattoria per far vedere che c\u2019erano degli animali malati. Ma \u00e8 andata dentro un locale infermeria, e si vedeva benissimo che era un locale infermeria. Poi mostravano un operaio che faceva pip\u00ec dentro un pollaio. Ma i polli l\u00ec di fianco mica uscivano per andare al gabinetto\u2026 Per scandalizzarsi di certe cose bisogna proprio non aver mai messo piede in una stalla. Lei ce l\u2019ha un cane?<\/p>\n<p style=\"text-align: justify;\"><strong>No.<\/strong><\/p>\n<p style=\"text-align: justify;\">Va b\u00e8, se avesse un cane saprebbe che quando un animale sta poco bene si vede innanzitutto dalla pelliccia, che diventa opaca. Perci\u00f2 \u00e8 chiaro che chi come me alleva animali da pelliccia deve badare al loro benessere: io vendo pelo, mica posso vendere pelo opaco.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-22668\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/07\/animalismo.jpg\" alt=\"animalismo\" width=\"142\" height=\"114\" \/>Vuole fare un commento sulla<\/strong> <strong>strage degli animali dell\u2019Oasi di Spinea?<\/strong><\/p>\n<p style=\"text-align: justify;\">Ecco, prima si parlava di mentecatti e faccendieri. I mentecatti sono quelli che devono trovare per forza il nemico nell\u2019uomo. Un sacco di gente si \u00e8 affrettata a scrivere su internet che voleva uccidere il presunto killer di Spinea. Si dicono animalisti ma non hanno un\u2019idea di cosa sia la natura. Non c\u2019era bisogno neanche di scomodare l\u2019Istituto Zooprofilattico, tutti i contadini dei dintorni che hanno le galline sanno benissimo che in certi periodi dell\u2019anno le volpi insegnano ai cuccioli a cacciare. E quando si \u00e8 accertato che effettivamente gli autori della strage erano volpi, i mentecatti zitti. Mentre i faccendieri avevano gi\u00e0 trovato il sistema di raccogliere soldi.<\/p>\n<p style=\"text-align: justify;\"><strong>E sul caso del gorilla abbattuto allo zoo di Cincinnati per salvare il bambino caduto nel suo recinto, con somma rabbia degli animalisti?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sto con i gestori dello zoo. C\u2019era in gioco una vita umana e uccidere il gorilla era l\u2019unico sistema sicuro per salvarla. Gli animalisti non capiscono che io sarei pronto ad ammazzare il gorilla anche se la vita in pericolo fosse la loro. Tanti di loro con me non farebbero altrettanto probabilmente.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma come si fa a schierarsi dalla parte di uno zoo?<\/strong><\/p>\n<p style=\"text-align: justify;\">Che domande. Lo zoo ha un valore unico, \u00e8 una delle poche manifestazioni rimaste di cultura materiale degli animali. Lo ha detto anche il grande entomologo Giorgio Celli prima di morire, tanto \u00e8 vero che gli animalisti lo avevano isolato. Un documentario non ti d\u00e0 la materialit\u00e0 che ti offre lo zoo, non ti consente di sentire l\u2019odore dell\u2019animale.<\/p>\n<p style=\"text-align: justify;\"><strong>Per\u00f2 arrivare a difendere la caccia \u00e8 paradossale perfino per voi.<\/strong><\/p>\n<p style=\"text-align: justify;\">No che non lo \u00e8. La caccia \u00e8 una forma di conservazione e-c-c-e-z-i-o-n-a-l-e. I paesi africani dove non sono minacciati i leoni e gli elefanti, sono quelli dove i cacciatori ne ammazzano di pi\u00f9. Io sono stato in Sudafrica e in Namibia: c\u2019\u00e8 una gestione faunistica straordinaria. L\u00ec certi animali ci sono ancora. In Europa \u00e8 l\u2019Ungheria che la fa da leader in questo campo.<\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019Ungheria?<\/strong><\/p>\n<p style=\"text-align: justify;\">Non so se lei \u00e8 cacciatore, ma sapr\u00e0 che quasi tutti i cacciatori almeno una volta nella vita sono andati a caccia in Ungheria. Si vedono animali dappertutto lass\u00f9.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-30207\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/specie-animali.jpg\" alt=\"specie animali\" width=\"182\" height=\"120\" \/>Merito della caccia?<\/strong><\/p>\n<p style=\"text-align: justify;\">Merito della caccia. La caccia non \u00e8 predazione illimitata, ormai \u00e8 gestione scientifica: vuol dire fare censimenti, determinare l\u2019incremento utile annuo della popolazione e gestirla. Come si farebbe con un frutteto: gli alberi vanno potati se si vuole che diano frutti anche l\u2019anno successivo.<\/p>\n<p style=\"text-align: justify;\"><strong>Per le nutrie invece nessuna piet\u00e0. Voi parlate di \u201ceradicazione\u201d.<\/strong><\/p>\n<p style=\"text-align: justify;\">Le nutrie vanno eradicate perch\u00e9 non sono autoctone e dove sono fanno danni. Fanno danni alla fauna autoctona, all\u2019agricoltura, agli argini dei fiumi. Fanno danni a tutti. Mi viene da ridere perch\u00e9 per difenderle gli animalisti dicono che sono stati gli allevatori a liberarle nelle nostre regioni. Ma la nutria \u00e8 un animale da pelliccia che vale pi\u00f9 da morto che da vivo. Io conosco degli ex allevatori di castorini: quando il mercato ha smesso di tirare, li hanno abbattuti per incassare il poco possibile. Se li avessero liberati non avrebbero preso neanche quello.<\/p>\n<p style=\"text-align: justify;\"><strong>Vuole dire qualcosa sul Premio Hitler?<\/strong><\/p>\n<p style=\"text-align: justify;\">Il Premio Hitler \u00e8 nato come una provocazione ma lo \u00e8 fino a un certo punto. \u00c8 stato Hitler, nel 1933, a firmare la prima legge che parlava dei cosiddetti diritti degli animali che non esistono. Il Reich vietava la sperimentazione animale in patria e poi sperimentava sugli ebrei nei lager. Ebbene anche oggi c\u2019\u00e8 chi propone di fare la sperimentazione sui carcerati. Pensare di salvare un topo sacrificando una persona perch\u00e9 \u00e8 \u201ccattiva\u201d: capisce perch\u00e9 parlo di una perdita di umanit\u00e0?<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30507\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Hitler_col_cane.jpg\" alt=\"Hitler_col_cane\" width=\"110\" height=\"150\" \/>Perch\u00e9 criticate anche il boom di accessori per animali?<\/strong><\/p>\n<p style=\"text-align: justify;\">Non siamo contrari agli accessori in generale. Ci sono accessori che sono utilissimi alla gestione dell\u2019animale. Gabbie, trasportine, ciottole e guinzagli servono. Il cappottino coi diamanti un po\u2019 meno. Ci siamo capiti? Noi abbiamo fatto degli esposti contro quelli che volevano dare le crocchette vegane ai cani. Siamo contrari a tutto quello che snatura l\u2019animale: \u00e8 una forma di maltrattamento. Che fa del male all\u2019animale e fa del male a noi, perch\u00e9 aumenta il nostro distacco dalla realt\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Per questo avete messo il Papa sulla copertina del vostro ultimo bollettino?<\/strong><\/p>\n<p style=\"text-align: justify;\">Il Papa \u00e8 stato meraviglioso quando ha detto in piazza San Pietro che non si pu\u00f2 avere compassione verso i cani e i gatti e ignorare il vicino che ha bisogno. Tante volte noi abbiamo ripreso il passo del Catechismo che parla dell\u2019utilit\u00e0 della creazione. In quattro righe c\u2019\u00e8 tutto: allevamento, caccia, pellicce, tutto. Posso leggerglielo?<\/p>\n<p style=\"text-align: justify;\"><strong>Prego.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abDio ha consegnato gli animali a colui che egli ha creato a sua immagine. \u00c8 dunque legittimo servirsi degli animali per provvedere al nutrimento o per confezionare indumenti. Possono essere addomesticati, perch\u00e9 aiutino l\u2019uomo nei suoi lavori e anche a ricrearsi negli svaghi. Le sperimentazioni mediche e scientifiche sugli animali sono pratiche moralmente accettabili, se rimangono entro limiti ragionevoli e contribuiscono a curare o salvare vite umane. \u00c8 contrario alla dignit\u00e0 umana far soffrire inutilmente gli animali e disporre indiscriminatamente della loro vita. \u00c8 pure indegno dell\u2019uomo spendere per gli animali somme che andrebbero destinate, prioritariamente, a sollevare la miseria degli uomini. Si possono amare gli animali; ma non si devono far oggetto di quell\u2019affetto che \u00e8 dovuto soltanto alle persone\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Chi sono gli intellettuali di riferimento di Federfauna?<\/strong><\/p>\n<p style=\"text-align: justify;\">Deve parlare con Massimo Zaratin. \u00c8 lui il filosofo, io sono un povero contadino.<\/p>\n<p style=\"text-align: justify;\"><strong>E i vostri peggiori nemici?<\/strong><\/p>\n<p style=\"text-align: justify;\">No guardi, noi non abbiamo nemici. Nemica \u00e8 l\u2019ideologia.<\/p>\n<p style=\"text-align: justify;\"><strong>Secondo lei gli animali hanno un\u2019anima?<\/strong><\/p>\n<p style=\"text-align: justify;\">Domanda complicata, credo che una risposta definitiva non esista. Se per anima intendiamo quel \u201csoffio di vita\u201d di cui parlava Giovanni Paolo II, rispondo di s\u00ec. Se parliamo di anima con le alucce e le nuvolette, probabilmente no. Per\u00f2 io gliel\u2019ho detto che faccio il contadino e non il filosofo.<\/p>\n<p style=\"text-align: justify;\"><strong>Non teme di passare per quello cattivo?<\/strong><\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 mai? Io amo tantissimo i miei animali. Ma veramente. La parte pi\u00f9 bella del mio lavoro sono le nascite, la nuova vita. \u00c8 una cosa che ti riempie il cuore di gioia. Poi per\u00f2 quando \u00e8 il momento gli animali li macello, li mangio, mi ci vesto, faccio tutte le cose che sono normali. La natura non \u00e8 n\u00e9 buona n\u00e9 cattiva. \u00c8 la natura, punto. E in natura qualunque essere vivente vive a spese di altri esseri viventi. Negarlo \u00e8 negare la realt\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempi.it 13 giugno 2016 Intervista a Massimiliano Filippi, fondatore di FederFauna, paladino di allevatori, cacciatori, zoo e circhi. Lettura sconsigliata a un pubblico sensibile alle campagne politicamente corrette e a chi condivide foto di gattini su Facebook Pietro Piccinini<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[198],"class_list":["post-36434","post","type-post","status-publish","format-standard","hentry","category-ambientalismo","tag-animalisti","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Te lo do io l\u2019amore per gli animali - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Te lo do io l\u2019amore per gli animali - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-05T22:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/cacciatori.jpg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Te lo do io l\u2019amore per gli animali\",\"datePublished\":\"2016-10-05T22:00:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/\"},\"wordCount\":2316,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/cacciatori.jpg\",\"keywords\":[\"animalisti\"],\"articleSection\":[\"Ambientalismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/\",\"name\":\"Te lo do io l\u2019amore per gli animali - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/cacciatori.jpg\",\"datePublished\":\"2016-10-05T22:00:31+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/cacciatori.jpg\",\"contentUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/cacciatori.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/te-lo-do-io-lamore-per-gli-animali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Te lo do io l\u2019amore per gli animali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Te lo do io l\u2019amore per gli animali - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/","og_locale":"it_IT","og_type":"article","og_title":"Te lo do io l\u2019amore per gli animali - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2016-10-05T22:00:31+00:00","og_image":[{"url":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/cacciatori.jpg","type":"","width":"","height":""}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Te lo do io l\u2019amore per gli animali","datePublished":"2016-10-05T22:00:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/"},"wordCount":2316,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/#primaryimage"},"thumbnailUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/cacciatori.jpg","keywords":["animalisti"],"articleSection":["Ambientalismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/","name":"Te lo do io l\u2019amore per gli animali - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/#primaryimage"},"thumbnailUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/cacciatori.jpg","datePublished":"2016-10-05T22:00:31+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/#primaryimage","url":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/cacciatori.jpg","contentUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/cacciatori.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/te-lo-do-io-lamore-per-gli-animali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Te lo do io l\u2019amore per gli animali"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/36434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=36434"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/36434\/revisions"}],"predecessor-version":[{"id":36436,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/36434\/revisions\/36436"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=36434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=36434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=36434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}