{"id":3641,"date":"2009-12-29T16:17:16","date_gmt":"2009-12-29T15:17:16","guid":{"rendered":""},"modified":"2015-07-28T09:41:10","modified_gmt":"2015-07-28T07:41:10","slug":"domande-e-risposte-sul-problema-dellomosessualit-parte-2","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/","title":{"rendered":"Domande e risposte sul problema dell&#8217;omosessualit&agrave; (parte 2)"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/omosex.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-26580\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/omosex.jpg\" alt=\"omosex\" width=\"250\" height=\"143\" \/><\/a>Articolo pubblicato su <strong>Cristianit\u00e0<\/strong> N. 314 novembre-dicembre 2002<\/div>\n<p style=\"text-align: center;\">di <strong>Bruto Maria Bruti<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: center;\"><strong>VII. L\u2019OMOSESSUALIT\u00c0 NELL\u2019ANTICHIT\u00c0 CLASSICA<\/strong><\/div>\n<p style=\"text-align: justify;\"><strong><strong>26. Come sostengono alcuni intellettuali, favorevoli al vizio omosessuale, il comportamento omosessuale nell\u2019antichit\u00e0 classica era considerato normale e solo il cristianesimo ha introdotto il concetto di comportamento sessualmente disordinato per l\u2019omosessualit\u00e0?<\/strong><\/strong><\/p>\n<p style=\"text-align: justify;\">La storia dei costumi sessuali, in realt\u00e0, non \u00e8 cos\u00ec semplice. Nella Grecia antica, per esempio, non era ammessa l\u2019omosessualit\u00e0 fra adulti, ma solo la \u00abpederastia\u00bb, cio\u00e8 il rapporto fra l\u2019adulto e l\u2019adolescente, il ragazzo dai 12 ai 16 anni. Non erano ammesse relazioni con i pi\u00f9 piccoli o con gli adulti. Il legislatore ateniese Solone (640-560 a.C.) aveva imposto la pena di morte da applicare a qualsiasi maschio adulto sorpreso, senza autorizzazione, nei locali di una scuola dove i ragazzi erano al di sotto dell\u2019et\u00e0 pubere.<\/p>\n<p style=\"text-align: justify;\">L\u2019omosessualit\u00e0 fra adulti era considerata depravazione e comportamento depravato era giudicato l\u2019atteggiamento sessualmente \u00abpassivo\u00bb dell\u2019adulto. Quindi il ruolo \u00abpassivo\u00bb era considerato normale solo per le donne e per gli adolescenti. La pederastia era tollerata solo se non si protraeva oltre i limiti di et\u00e0 previsti: il giovane poi, una volta superata l\u2019adolescenza, doveva assumere un atteggiamento sessualmente \u00abattivo\u00bb; inoltre \u2014 come si deduce dal dialogo <em>Simposio <\/em>di Platone (427-347 a.C.) \u2014, tale giudizio positivo sulla pederastia non era condiviso da tutta la societ\u00e0 ateniese; una parte di essa, anzi, la considerava una manifestazione di <em>\u00abspudoratezza\u00bb<\/em>.<\/p>\n<p style=\"text-align: justify;\">Probabilmente la pederastia era circoscritta ad ambienti intellettuali (68). Alla base del giudizio favorevole sulla pederastia, vi era l\u2019idea che tale relazione preparasse l\u2019adolescente alla maturit\u00e0 intellettuale e psicologica: la si potrebbe qualificare come una \u00abpederastia pedagogica\u00bb (69). Una tale convinzione si trova anche presso alcune popolazioni selvagge, convinzione dovuta, probabilmente, a un pensiero di tipo magico, nato da meccanismi mentali di pura e semplice associazione di idee.<\/p>\n<p style=\"text-align: justify;\">Come nella magia detta \u00abcontagiosa\u00bb \u2014 in quanto l\u2019atto compiuto su una parte diffonde il suo effetto sul tutto \u2014 si finisce per credere che \u00e8 possibile uccidere il nemico compiendo atti ostili sulla sua immagine o su ciocche dei suoi capelli, cos\u00ec, per contatto sessuale con l\u2019adulto, si pensa che il giovane possa assorbire la virilit\u00e0 dell\u2019adulto stesso.<\/p>\n<p style=\"text-align: justify;\">Inoltre, i tratti delicati e non ancora virili dell\u2019adolescente facilitano questa associazione e facilitano pure l\u2019instaurarsi verso di lui di meccanismi attrattivi.<\/p>\n<p style=\"text-align: justify;\">Presso molte trib\u00f9 la \u00abpederastia pedagogica\u00bb viene praticata nei rituali d\u2019iniziazione, mentre \u00e8 vietata nella vita di tutti i giorni: cos\u00ec in Australia, nella Polinesia, nelle isole Ebridi, nelle trib\u00f9 dei Marind-Anim e dei Keraki in Nuova Guinea. Casi analoghi sono registrati in Marocco, in Siberia e in America Settentrionale. Sempre da un pensiero di tipo magico nasce, per esempio, in alcune societ\u00e0 il \u00absulamitismo\u00bb, ovvero la credenza che attraverso il congiungimento con un fanciullo si possa allungare la propria vita, assorbendo l\u2019essenza vitale del giovane (70).<\/p>\n<p style=\"text-align: justify;\">In Marocco, per esempio, \u00e8 stata registrata l\u2019esistenza di una credenza secondo cui le relazioni omosessuali con un uomo conosciuto per la sua <em>baraka <\/em>\u2014 \u00abfortuna\u00bb, \u00abpotere\u00bb \u2014, permettono al soggetto sessualmente passivo di ricevere la sua fortuna (71). Nella Grecia antica, dunque, l\u2019omosessualit\u00e0 fra adulti e il ruolo sessualmente passivo del maschio erano proibiti; ugualmente proibito era il cosiddetto \u00abmatrimonio\u00bb omosessuale<em>.<\/em><\/p>\n<p style=\"text-align: justify;\">Nel mondo romano classico il padrone poteva abusare sessualmente dello schiavo o della schiava, ma fra uomini liberi la legge proibiva la pederastia, anche se gli adolescenti erano consenzienti: si parlava di <em>\u00abstuprum cum puero\u00bb<\/em>. Fra gli uomini liberi, inoltre, la legge puniva anche la passivit\u00e0 sessuale del maschio: cos\u00ec la <em>lex Scatinia <\/em>(72).<\/p>\n<p style=\"text-align: center;\"><strong>VIII. APPENDICE SUL PROBLEMA DEGL\u2019ISTINTI E DEI BISOGNI UMANI<\/strong><\/p>\n<p style=\"text-align: justify;\">Gl\u2019istinti dell\u2019uomo non sono, in s\u00e9 stessi, n\u00e9 buoni n\u00e9 cattivi: sono componenti naturali dello psichismo umano, che devono essere integrati e coordinati con la volont\u00e0 e la ragione e posti al servizio di quanto \u00e8 buono. In ogni esperienza specificamente umana dell\u2019istinto in quanto tale, accanto a forme \u00abinferiori\u00bb e biologiche di bisogni, coesistono sempre forme \u00absuperiori\u00bb di bisogni e l\u2019essere umano pu\u00f2 spostare, mediante l\u2019intervento della volont\u00e0 e della ragione, la spinta ad agire, l\u2019energia, determinata da un bisogno, verso altre forme di bisogno.<\/p>\n<p style=\"text-align: justify;\">Questo lavoro della volont\u00e0 e della ragione, quando \u00e8 coscientemente finalizzato, provoca, nel tempo, una progressiva integrazione e sottomissione delle forme inferiori di bisogno a quelle superiori e pu\u00f2 anche determinare la volontaria diminuzione di alcune forme d\u2019interesse verso realt\u00e0 ritenute d\u2019importanza secondaria.<\/p>\n<p style=\"text-align: justify;\">Questa diminuzione lascia via libera all\u2019azione di altri \u00abdinamismi\u00bb, quali la grazia e l\u2019ispirazione divina e promuove la crescita dell\u2019interesse verso attivit\u00e0 superiori e pi\u00f9 nobili, verso cui diventa progressivamente pi\u00f9 facile spostare l\u2019energia determinata dai bisogni \u00abinferiori\u00bb: questa \u00e8 la nozione corretta della \u00abmortificazione\u00bb nell\u2019ascetismo cristiano.<\/p>\n<p style=\"text-align: justify;\">Non si tratta, come sostiene la psicoanalisi freudiana, della \u00absublimazione\u00bb, cio\u00e8 del processo che attua la trasformazione dell\u2019energia sessuale, o <em>libido<\/em>, in attivit\u00e0 superiori, spirituali o culturali, ma della sottomissione dell\u2019\u00abinferiore\u00bb al \u00absuperiore\u00bb, dello spostamento volontario dell\u2019energia dall\u2019\u00abinferiore\u00bb al \u00absuperiore\u00bb, della liberazione e dello sviluppo d\u2019interessi pi\u00f9 alti, di disposizioni interiori superiori.<\/p>\n<p style=\"text-align: justify;\">Lo sviluppo di motivazioni superiori determina l\u2019\u00abatrofia\u00bb degl\u2019interessi verso realt\u00e0 considerate d\u2019importanza secondaria. Ho parlato di lavoro della volont\u00e0 e della ragione, che devono intervenire nella gestione degl\u2019istinti, degl\u2019interessi e dei bisogni \u00abumani\u00bb.<\/p>\n<p style=\"text-align: justify;\">Infatti, la pura e semplice \u00abrepressione\u00bb di un istinto, di un\u2019idea o di un interesse finisce per ossessionare e per tormentare chi li reprime. La repressione pu\u00f2 essere solo la fase iniziale di un processo, che porta l\u2019uomo a costruire e a sviluppare la sua personalit\u00e0, altrimenti non si ha una vera \u00abmortificazione\u00bb nel senso cristiano, ma una pseudo-mortificazione, che \u00e8 un surrogato, una contraffazione di quella vera.<\/p>\n<p style=\"text-align: justify;\">Per distinguere una mortificazione vera da una pseudo-mortificazione un buon metro di misura \u00e8 la pace del cuore e l\u2019umilt\u00e0, con l\u2019assenza delle manie di perfezionismo. Il perfezionismo nasce dalla confusione fra il modello ideale verso cui camminare e l\u2019impeccabilit\u00e0, cio\u00e8 il proprio \u00abio\u00bb idealizzato.<\/p>\n<p style=\"text-align: justify;\">Nel perfezionismo vi \u00e8 la continua preoccupazione che nasce dal pensiero dei propri difetti, vi \u00e8 il rifiuto di s\u00e9 stessi e il desiderio di essere un altro. Il perfezionista non sa accettare la crescita progressiva che, in quanto progressiva, non sar\u00e0 mai perfettamente compiuta in questo mondo; per questo il perfezionista si rattrista spesso, ma la tristezza non nasce mai dall\u2019amore di Dio ma dall\u2019amor proprio che agisce camuffandosi dietro le apparenze dell\u2019umilt\u00e0.<\/p>\n<p style=\"text-align: justify;\">Un maestro di spiritualit\u00e0 come sant\u2019Ignazio di Loyola (1491-1556) ricorda che, nella via dello spirito, la tristezza, i tormenti di coscienza, i dubbi, lo scoraggiamento e ogni atteggiamento che toglie la pace non provengono mai da Dio, che \u00e8 pace, gioia, certezza, serenit\u00e0, ma provengono dall\u2019amor proprio o dall\u2019azione demoniaca.<\/p>\n<p style=\"text-align: justify;\">Ho detto che la repressione pu\u00f2 essere solo la fase iniziale di un processo, che porta l\u2019uomo a costruire e a sviluppare la sua personalit\u00e0. Quando si guida un\u2019automobile, per esempio, non basta non andare in una certa direzione, ma occorre imboccare un\u2019altra strada e bisogna amare la meta da raggiungere.<\/p>\n<p style=\"text-align: justify;\">Non fare qualcosa di negativo \u00e8 soltanto la condizione indispensabile e iniziale per poter fare qualcosa di positivo. Cos\u00ec, non si pu\u00f2 soltanto rinunciare a un piacere ritenuto sbagliato, perch\u00e9 il desiderio per questo piacere aumenterebbe e finirebbe per ossessionarci.<\/p>\n<p style=\"text-align: justify;\">Dopo aver detto no, bisogna cercare di diventare sempre pi\u00f9 consapevoli dei motivi per cui l\u2019oggetto del desiderio al quale abbiamo rinunciato \u00e8 sbagliato, sempre pi\u00f9 consapevoli della sua illusoriet\u00e0, del fatto che rappresenta soltanto un soddisfacimento momentaneo, che non risolve i problemi pi\u00f9 profondi della persona e che, alla lunga, impedisce la propria realizzazione e felicit\u00e0, in modo analogo a quanto succede nel caso del fenomeno della tossicodipendenza.<\/p>\n<p style=\"text-align: justify;\">Questo itinerario di progressiva consapevolezza presuppone \u2014 con l\u2019aiuto della grazia divina, che, ordinariamente, svolge un\u2019azione sussidiaria illuminante e incoraggiante, facendoci amare la strada da percorrere, ma senza sostituirsi all\u2019impegno che dobbiamo profondere \u2014 non solo il fuggire le cattive occasioni, non solo il non fare il male, ma richiede di fare il bene prima di tutto all\u2019interno del proprio cuore.<\/p>\n<p style=\"text-align: justify;\">Queste opere buone, da svolgere all\u2019interno del proprio cuore, consistono nel ragionamento, nell\u2019osservazione oggettiva, nella contemplazione del reale e nel dissolvimento critico delle illusioni.<\/p>\n<p style=\"text-align: justify;\">Nostro Signore Ges\u00f9 Cristo afferma che la sorgente del male che affligge l\u2019uomo sta dentro la sua personalit\u00e0: <em>\u00abDal cuore, infatti, provengono i propositi malvagi, gli omicidi, gli adult\u00e8ri, le prostituzioni, i furti, le false testimonianze, le bestemmie\u00bb <\/em>(<em>Mt<\/em>. 15, 19).<\/p>\n<p style=\"text-align: justify;\">La cultura ebraica concepisce il cuore come l\u2019interno dell\u2019uomo in un senso molto ampio. Oltre ai sentimenti il cuore comprende anche i ricordi, le idee, i progetti e le decisioni: il cuore \u00e8 il centro dell\u2019essere, dove l\u2019uomo dialoga con s\u00e9 stesso e assume le proprie responsabilit\u00e0 (73).<\/p>\n<p style=\"text-align: justify;\">All\u2019interno dell\u2019uomo avviene il conflitto fra le passioni, la volont\u00e0 e la ragione; all\u2019interno nascono i tentativi di riportare ordine fra queste potenze dell\u2019anima e sempre dal cuore hanno origine i dialoghi che l\u2019uomo intraprende con s\u00e9 stesso, dialoghi interiori che lo portano prima a interpretare i \u00abmessaggi\u00bb interni ed esterni, poi a decidere e ad agire.<\/p>\n<p style=\"text-align: justify;\">Solo dopo un corretto lavoro svolto nel proprio cuore \u2014 cio\u00e8 dopo un continuo e perseverante dialogo interiore, finalizzato a dissolvere in maniera critica le illusioni e a diventare consapevoli della realt\u00e0 \u2014 la rinuncia a un piacere disordinato si trasforma nella \u00abpreferenza\u00bb verso un altro piacere, un piacere ordinato che non contrasta con la verit\u00e0 e con la giustizia. Solo allora la rinuncia si trasforma nella scelta di un altro obiettivo e di un\u2019altra direzione di marcia. In questo modo la persona progredisce dirigendo, regolando, mettendo in equilibrio e utilizzando costruttivamente tutte le proprie energie.<\/p>\n<p style=\"text-align: justify;\">Si tratta di un\u2019opera simile a quella che l\u2019essere umano svolge nei confronti delle forze della natura, come quando incanala verso una centrale di energia le acque torrenziali. Nessuno pu\u00f2 progredire senza conservare l\u2019indicazione di una direzione valida in cui muoversi.<\/p>\n<p style=\"text-align: justify;\">La ragione, dopo il peccato originale, pu\u00f2 sbagliare nei suoi giudizi sia per difetto di conoscenza sia perch\u00e9 il conflitto fra le passioni e la volont\u00e0 pu\u00f2 ostacolare e confondere l\u2019itinerario della ragione, con il rischio continuo e reale che le nostre debolezze diventino la misura del bene e del male in modo da farci ritenere falso quanto non vorremmo fosse vero.<\/p>\n<p style=\"text-align: justify;\">Il cattolico, attraverso la guida e il sostegno della fede, pu\u00f2 conservare l\u2019indicazione valida delle strade in cui inserire la ricerca razionale. Il razionalismo \u2014 la ragione senza la fede \u2014, che non riconosce l\u2019importanza della fede come guida e sostegno, finisce per dimenticare che la ragione non \u00e8 una facolt\u00e0 dotata d\u2019infallibilit\u00e0 ma che, al pari delle altre facolt\u00e0 umane, \u00e8 soggetta all\u2019imperfezione e al limite; pertanto, nella sua ricerca, non riesce a rimanere per molto tempo nella giusta direzione senza incontrare ostacoli che possono, gradualmente, portarla fuori strada.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 forse vero che tanti sistemi di pensiero, nati con l\u2019intenzione di aiutare l\u2019uomo, hanno finito per costruire strutture oppressive per l\u2019uomo stesso e tanti itinerari della ragione sono giunti a negare valore alla ragione stessa? (74).<\/p>\n<p style=\"text-align: justify;\">Non basta conservare la fede, che dev\u2019essere pienamente vissuta, deve svilupparsi insieme a tutte le facolt\u00e0 dell\u2019uomo, deve accompagnare tutte le fasi e le vicende della sua vita. Se la fede viene separata dalla vita e dalla cultura dell\u2019uomo, diventa inutile e viene persa.<\/p>\n<p style=\"text-align: justify;\">Per sviluppare il dono della fede il credente deve meditare sulla Sacra Scrittura e sul Magistero della Chiesa e deve inserire costantemente la ricerca della ragione nell\u2019orizzonte fornito dalla fede, in modo da amare Dio con l\u2019intelletto, con la volont\u00e0 e con le opere. Questo lavoro ha bisogno di essere sostenuto dal continuo dialogo con Dio, che il cattolico incontra attraverso la preghiera e, in modo speciale, attraverso i sacramenti, forze vive che escono dal corpo di Cristo per nutrire l\u2019anima e per curarla.<\/p>\n<p style=\"text-align: justify;\">Tornando al problema degl\u2019istinti, giova ripetere che la loro corretta gestione \u00e8 fondamentale per la costruzione della personalit\u00e0. L\u2019istinto di aggressivit\u00e0, per esempio, non solo \u00e8 fondamentale per difendersi, ma l\u2019energia, da esso prodotta, pu\u00f2 venire utilizzata, grazie al controllo e all\u2019orientamento della volont\u00e0 e della ragione, per \u00abaggredire\u00bb, nel senso pi\u00f9 lato, un compito o un problema e pu\u00f2 essere messa al servizio della giustizia e dei diritti degli altri.<\/p>\n<p style=\"text-align: justify;\">Il bisogno sociale e il bisogno di giustizia sono forme superiori di bisogni, che sempre accompagnano nell\u2019uomo l\u2019istinto puramente biologico di aggressivit\u00e0.<\/p>\n<p style=\"text-align: justify;\">L\u2019istinto sessuale non solo \u00e8 fondamentale per unire l\u2019uomo e la donna fisicamente, ma l\u2019energia da esso determinata pu\u00f2 essere utilizzata, grazie al controllo, all\u2019orientamento e alla consapevolezza della volont\u00e0 e della ragione per integrare l\u2019impulso copulativo con il bisogno di tenerezza e di affetto, in modo che l\u2019unione genitale diventi segno e strumento di reciproca donazione fra due persone di sesso complementare e possa soddisfare il bisogno d\u2019amore.<\/p>\n<p style=\"text-align: justify;\">L\u2019energia generata dall\u2019istinto copulativo pu\u00f2 anche essere messa a servizio d\u2019amore verso i fratelli e verso la verit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Lo sviluppo di una forma superiore e spirituale di bisogno, come quella che spinge verso i significati pi\u00f9 alti della stessa sessualit\u00e0 umana \u2014 l\u2019amore per gli altri e la donazione di s\u00e9 stessi agli altri \u2014 fa diminuire l\u2019interesse verso la relazione coniugale e in questo caso \u00e8 pi\u00f9 facile spostare l\u2019energia determinata dall\u2019istinto copulativo su di un piano pi\u00f9 alto.<\/p>\n<p style=\"text-align: justify;\">Insegna Papa Giovanni Paolo II che \u00ab<em>nella verginit\u00e0 e nel celibato la castit\u00e0 mantiene il suo significato originario, quello cio\u00e8 di una sessualit\u00e0 umana vissuta come autentica manifestazione e prezioso servizio all\u2019amore di comunione e di donazione interpersonale<\/em>\u00bb (75). Il bisogno di affetto, di amore e di donazione sono forme superiori di bisogni, che sempre accompagnano nell\u2019uomo l\u2019istinto puramente biologico della sessualit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Significative del bisogno di amore sono le parole di un poeta, che ha fatto della lussuria una ragione di vita. Scrive Gabriele D\u2019Annunzio (1863-1938):<\/p>\n<p>\u00ab<em>Tristezza atroce de la carne Immonda<br \/>\n<\/em><em>quando la fiamma del des\u00eco nel gelo<br \/>\n<\/em><em>del disgusto si spegne e nessun velo<br \/>\n<\/em><em>d\u2019amor l\u2019inerte nudit\u00e0 circonda!<\/em><\/p>\n<p><em>(E tu sorgi ne l\u2019anima profonda,<br \/>\n<\/em><em>pura Imagine. Come su lo stelo<br \/>\n<\/em><em>\u00e8sile piega un funebre asfodelo,<br \/>\nsu\u2019l collo inclini la tua testa<br \/>\n<\/em><em>bionda<\/em>\u00bb<em>.<\/em><\/p>\n<p><em>\u00abTristezza immensa de la carne bruta<br \/>\nquando nel petto il cor fievole batte<br \/>\n<\/em><em>lontano e solo come in una tomba<\/em>\u00bb<br \/>\n<em><br \/>\n<\/em><em>\u00abE tu guardi, tu sempre guardi,<br \/>\no muta Imagine, tu pura come il latte,<br \/>\n<\/em><em>con i tuoi teneri occhi di colomba\u00bb <\/em>(76).<\/p>\n<p style=\"text-align: justify;\">Lo psicologo belga don Joseph Nuttin (1909-1988) afferma che ogni bisogno d\u00e0 origine a un\u2019energia di tipo generico, a uno stato di generica tensione energetica dell\u2019organismo, che pu\u00f2 essere momentaneamente dissolta attraverso una qualsiasi soddisfazione o attivit\u00e0 organica, e ci\u00f2 anche nei confronti di bisogni vitali.<\/p>\n<p style=\"text-align: justify;\">Certo, esistono meccanismi riflessi automatici, per esempio l\u2019istinto di evacuare e di respirare, che non possono essere repressi oltre una certa soglia critica. Ma l\u2019uomo mostra una grande possibilit\u00e0 di scelta anche nei confronti degl\u2019istinti di necessit\u00e0 vitale individuale, come la fame e la sete.<\/p>\n<p style=\"text-align: justify;\">L\u2019essere umano pu\u00f2 esercitare verso questi istinti anche una repressione totale, fino a giungere alla\u00a0 morte e senza bisogno di ricorrere all\u2019uso di mezzi coercitivi esterni alla sua persona. Nell\u2019uomo, a differenza dell\u2019animale, attraverso il controllo della volont\u00e0 e della ragione, l\u2019energia originata da un bisogno inferiore pu\u00f2 anche essere messa a disposizione di una finalit\u00e0 superiore.<\/p>\n<p style=\"text-align: justify;\">Tale finalit\u00e0 nasce da motivazioni intellettuali e spirituali che, nell\u2019essere umano, si trovano sempre mescolate con bisogni di natura inferiore. Questo provoca la graduale integrazione e sottomissione dei bisogni inferiori a quelli superiori e anche, se necessario, l\u2019atrofia di certe forme d\u2019interesse verso realt\u00e0 secondarie, che provoca la liberazione e lo sviluppo di altre disposizioni interiori pi\u00f9 elevate e pi\u00f9 nobili.<\/p>\n<p style=\"text-align: justify;\">Il concetto di sublimazione, nel senso della psicoanalisi freudiana, \u00e8 erroneo perch\u00e9 non esiste un\u2019energia specifica di tipo sessuale che si converte in attivit\u00e0 di altro genere, ma esiste il fenomeno della trasposizione, cio\u00e8 dello spostamento dell\u2019energia insita in un bisogno, la sottomissione dei bisogni inferiori ai superiori e anche l\u2019atrofia d\u2019interessi secondari e la conseguente liberazione e crescita di forme superiori d\u2019interesse e di motivazione (77).<\/p>\n<p style=\"text-align: justify;\">Don Nuttin sostiene che in una stessa attivit\u00e0 umana forme \u00abinferiori\u00bb di bisogni si trovano sempre mescolate a forme \u00absuperiori\u00bb: si tratta di manifestazioni di uno stesso dinamismo trapassante i diversi piani della vita psichica.<\/p>\n<p style=\"text-align: justify;\">Gli elementi spirituali costituiscono vere \u00abcomponenti\u00bb di un\u2019esperienza specificamente umana dell\u2019istinto in quanto tale.<\/p>\n<p style=\"text-align: justify;\">A questo proposito scrive: <em>\u00ab<\/em>[&#8230;] <em>uno psicologo ci ha detto, descrivendo la sua esperienza personale: \u201cHo costatato spesso che la soddisfazione e il piacere, provati nel corso delle relazioni coniugali, sono infinitamente pi\u00f9 intensi e pi\u00f9 \u2018ricchi\u2019 ogni volta che realizzo i legami umani e spirituali che mi uniscono alla moglie, e cio\u00e8 quando mi rendo conto di ci\u00f2 che \u2018significa\u2019 per me la \u2018persona\u2019 con cui mi unisco. \u00abTutte le volte, invece, che tali relazioni si svolgono su un piano pi\u00f9 esclusivamente sessuale e <\/em><em>istintivo, il piacere \u00e8 meno intenso e duraturo\u201d\u00bb <\/em>(78).<\/p>\n<p style=\"text-align: justify;\">Lo psichiatra monsignor Joan Baptista Torell\u00f3 afferma che lo studio del comportamento umano <em>\u00ab<\/em>[&#8230;] <em>ha permesso alla psicologia pi\u00f9 recente di riconoscere, nella repressione e nella soddisfazione dei cosiddetti istinti, fenomeni ugualmente propri e confacenti alla natura dell\u2019essere umano, che solo in rapporto ad un\u2019altra serie di valori umani sono in grado di causare salute o malattia, serenit\u00e0 o tensione, piacere o disagio. Ci\u00f2 che decide la loro positivit\u00e0 o negativit\u00e0, la loro sanit\u00e0 o azione patogena \u00e8 il quadro d\u2019insieme in cui s\u2019inseriscono, l\u2019atteggiamento fondamentale dell\u2019esistente, le motivazioni libere dello spirito. \u00abPer quanto si riferisce concretamente al cosiddetto \u201cistinto\u201d sessuale, decisivo sar\u00e0 il ruolo dell\u2019\u201camore\u201d: continenza per amore \u00e8 rasserenante e soddisfacente, cos\u00ec come rasserenante e soddisfacente \u00e8 il rapporto sessuale per amore\u00bb <\/em>(79).<\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=1505\" target=\"_blank\">vai alle note<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Articolo pubblicato su Cristianit\u00e0 N. 314 novembre-dicembre 2002 di Bruto Maria Bruti<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":26580,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[322],"class_list":["post-3641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-omosessualit","tag-omosessualita","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Domande e risposte sul problema dell&#039;omosessualit&agrave; (parte 2) - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Domande e risposte sul problema dell&#039;omosessualit&agrave; (parte 2) - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-12-29T15:17:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-28T07:41:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/omosex.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Domande e risposte sul problema dell&#8217;omosessualit&agrave; (parte 2)\",\"datePublished\":\"2009-12-29T15:17:16+00:00\",\"dateModified\":\"2015-07-28T07:41:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/\"},\"wordCount\":3001,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/omosex.jpg\",\"keywords\":[\"omosessualit\u00e0\"],\"articleSection\":[\"Omosessualit&agrave;\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/\",\"name\":\"Domande e risposte sul problema dell'omosessualit&agrave; (parte 2) - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/omosex.jpg\",\"datePublished\":\"2009-12-29T15:17:16+00:00\",\"dateModified\":\"2015-07-28T07:41:10+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/omosex.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/omosex.jpg\",\"width\":280,\"height\":160},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domande e risposte sul problema dell&#8217;omosessualit&agrave; (parte 2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Domande e risposte sul problema dell'omosessualit&agrave; (parte 2) - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/","og_locale":"it_IT","og_type":"article","og_title":"Domande e risposte sul problema dell'omosessualit&agrave; (parte 2) - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-12-29T15:17:16+00:00","article_modified_time":"2015-07-28T07:41:10+00:00","og_image":[{"width":280,"height":160,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/omosex.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Domande e risposte sul problema dell&#8217;omosessualit&agrave; (parte 2)","datePublished":"2009-12-29T15:17:16+00:00","dateModified":"2015-07-28T07:41:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/"},"wordCount":3001,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/omosex.jpg","keywords":["omosessualit\u00e0"],"articleSection":["Omosessualit&agrave;"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/","name":"Domande e risposte sul problema dell'omosessualit&agrave; (parte 2) - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/omosex.jpg","datePublished":"2009-12-29T15:17:16+00:00","dateModified":"2015-07-28T07:41:10+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/omosex.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/omosex.jpg","width":280,"height":160},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/domande-e-risposte-sul-problema-dellomosessualit-parte-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Domande e risposte sul problema dell&#8217;omosessualit&agrave; (parte 2)"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3641"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3641\/revisions"}],"predecessor-version":[{"id":26582,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3641\/revisions\/26582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/26580"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}