{"id":36390,"date":"2014-08-16T00:00:42","date_gmt":"2014-08-15T22:00:42","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=36390"},"modified":"2016-09-16T09:31:53","modified_gmt":"2016-09-16T07:31:53","slug":"sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/","title":{"rendered":"Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-36391\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/comunione_Franesco.jpg\" alt=\"comunione_franesco\" width=\"250\" height=\"143\" \/>Petrus<\/strong>, quotidiano on-line sul pontificato di Benedetto XVI, 24 marzo 2008<\/p>\n<p style=\"text-align: center;\">don <strong>Marcello Stanzione<\/strong><\/p>\n<p style=\"text-align: center;\">Presidente dell&#8217;Associazione &#8216;Milizia di San Michele Arcangelo&#8217;<\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">CITTA\u2019 DEL VATICANO &#8211; Sono nato nel 1963, sono entrato in seminario nel 1983 e sono stato ordinato sacerdote nel 1990. La mia formazione teologica non \u00e8 stata assolutamente \u201cconservatrice\u201d o \u201cpreconciliare\u201d, ma fin da ragazzo ho sentito istintivamente un senso di disagio nel dare o ricevere la Santa Comunione sulla mano.<\/p>\n<p style=\"text-align: justify;\">Poche sere fa, insieme al Direttore Gianluca Barile, ho avuto modo di discutere dell\u2019argomento a cena con il Cardinale Francis Arinze, Prefetto della Congregazione per il Culto Divino e la Disciplina dei Sacramenti, che si \u00e8 detto assolutamente contrario all\u2019amministrazione della particola sulla mano. Attraverso i secoli, illustri teologi e grandi mistici ci hanno insegnato che la Santa Eucarestia \u00e8 veramente il Corpo, il Sangue, l\u2019Anima e la Divinit\u00e0 di Ges\u00f9 Cristo.<\/p>\n<p style=\"text-align: justify;\">I Padri del Concilio di Trento definirono il Divino Sacramento con precisione e cura, San Tommaso d\u2019Aquino ci ha insegnato che, al di l\u00e0 della venerazione verso questo Sacramento, toccare ed amministrare il Sacramento spetta solo al sacerdote o al diacono. Per secoli, i genitori cattolici, a casa, cos\u00ec come le suore docenti a scuola e le catechiste in parrocchia, hanno insegnato che era sacrilegio per chiunque toccare l\u2019Ostia Santa, tranne che per il sacerdote o il diacono. Attraverso i secoli, i Papi, i vescovi, i preti ci hanno insegnato la stessa cosa, non tanto con le parole, ma con l\u2019esempio, specialmente con la celebrazione della Messa secondo il rito di San Pio V, in cui c\u2019era, in ogni gesto che il sacerdote faceva, profondo rispetto per il Divino Sacramento, in quanto vero Corpo di Cristo.<\/p>\n<p style=\"text-align: justify;\">Dunque, l\u2019introduzione della Comunione sulla mano dimostra un\u2019inosservanza di quanto i nostri Padri, lungo i secoli, ci hanno insegnato. E bench\u00e9 questa pratica sia stata introdotta ed erroneamente presentata come uno sviluppo liturgico autentico del Concilio Vaticano II, in realt\u00e0 la Comunione sulla mano non solo non \u00e8 uno sviluppo liturgico autentico ordinato dal Concilio Vaticano II, ma mostra disobbedienza e disprezzo totali nei confronti di secoli di insegnamento e pratica.<\/p>\n<p style=\"text-align: justify;\">La Comunione sulla mano fu introdotta sotto un falso ecumenismo, attraverso compromessi e falso senso di tolleranza, portando ad una profonda irriverenza ed indifferenza verso il Santissimo Sacramento. La Comunione sulla mano non \u00e8 menzionata in nessun documento del Vaticano II, n\u00e9 se ne parl\u00f2 nei dibattiti conciliari. Prima del Vaticano II non c\u2019\u00e8 testimonianza storica di vescovi, preti o laici che abbiano richiesto ad alcuno l\u2019introduzione della Comunione sulla mano.<\/p>\n<p style=\"text-align: justify;\">Al contrario, chiunque crebbe nella Chiesa preconciliare, ricorder\u00e0 chiaramente che gli fu insegnato che era sacrilegio per chiunque, tranne che per il prete, toccare l\u2019Ostia Sacra. Lo mette in evidenza l\u2019insegnamento di San Tommaso d\u2019Aquino, il quale nella sua Summa Teologica spiega : \u201cDispensare il Corpo di Cristo spetta al sacerdote per tre ragioni: perch\u00e9 egli consacra nella persona di Cristo. Ma come Cristo consacr\u00f2 il Suo Corpo nell\u2019Ultima Cena e fu Lui che ne diede agli altri per essere condiviso da loro, cos\u00ec, come la consacrazione del Corpo di Cristo spetta al sacerdote, anche la distribuzione spetta a lui; perch\u00e9 il prete \u00e8 l\u2019intermediario stabilito tra Dio e il popolo, quindi spetta a lui offrire i doni del popolo a Dio, cos\u00ec spetta a lui distribuire i doni consacrati al popolo; perch\u00e9, al di l\u00e0 del rispetto per questo Sacramento, nulla lo pu\u00f2 toccare tranne ci\u00f2 che \u00e8 consacrato; allo stesso modo solo le mani del sacerdote lo possono toccare. Quindi a nessun altro \u00e8 lecito toccarlo, tranne che per necessit\u00e0, per esempio se stesse per cadere a terra, o altro, in qualche caso di emergenza\u201d (ST. III, Q 82, Art. 13).<\/p>\n<p style=\"text-align: justify;\">San Tommaso, che nella Chiesa \u00e8 il principe dei teologi, la cui Summa Theologica fu posta sull\u2019altare vicino alle Scritture durante il Concilio di Trento, chiaramente insegna che spetta al prete e soltanto a lui toccare e distribuire l\u2019Ostia Sacra, che solo ci\u00f2 che \u00e8 consacrato (le mani del sacerdote) deve toccare il Consacrato (l\u2019Ostia Sacra).<\/p>\n<p style=\"text-align: justify;\">La Comunione sulla mano certamente fu praticata nella Chiesa antica, ma attenzione: gli uomini potevano ricevere l\u2019Eucarestia sulla mano, mentre le donne non potevano riceverla sulle mani nude e dovevano coprirle con un indumento chiamato domenicale. Nel quarto secolo, San Cirillo di Gerusalemme insegnava ai fedeli che si doveva ricevere il Santissimo Sacramento con rispetto e attenzione.<\/p>\n<p style=\"text-align: justify;\">Con il passare del tempo, man mano che il rispetto ed il discernimento della vera natura del Santissimo Sacramento, grazie alla guida dello Spirito Santo, crebbe e si perfezion\u00f2, la pratica di porre l\u2019Ostia sulla lingua del comunicando divenne sempre pi\u00f9 diffusa, cos\u00ec che non ci fosse la pi\u00f9 remota possibilit\u00e0 che la pi\u00f9 piccola particella cadesse a terra e fosse dissacrata. La Comunione sulla mano fu condannata come un abuso al Sinodo di Rouen nell\u2019anno 650, cos\u00ec che si pu\u00f2 dire con ragionevole certezza che, grazie al desiderio di maggior rispetto e come salvaguardia contro la dissacrazione, era la norma ricevere l\u2019Ostia sulla lingua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Petrus, quotidiano on-line sul pontificato di Benedetto XVI, 24 marzo 2008 don Marcello Stanzione Presidente dell&#8217;Associazione &#8216;Milizia di San Michele Arcangelo&#8217;<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":36391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,115],"tags":[1487],"class_list":["post-36390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-liturgia","tag-comunione-sulla-mano","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-15T22:00:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-16T07:31:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/comunione_Franesco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"297\" \/>\n\t<meta property=\"og:image:height\" content=\"170\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione\",\"datePublished\":\"2014-08-15T22:00:42+00:00\",\"dateModified\":\"2016-09-16T07:31:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/\"},\"wordCount\":853,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/comunione_Franesco.jpg\",\"keywords\":[\"comunione sulla mano\"],\"articleSection\":[\"Chiesa\",\"Liturgia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/\",\"name\":\"Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/comunione_Franesco.jpg\",\"datePublished\":\"2014-08-15T22:00:42+00:00\",\"dateModified\":\"2016-09-16T07:31:53+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/comunione_Franesco.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/comunione_Franesco.jpg\",\"width\":297,\"height\":170},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/","og_locale":"it_IT","og_type":"article","og_title":"Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-08-15T22:00:42+00:00","article_modified_time":"2016-09-16T07:31:53+00:00","og_image":[{"width":297,"height":170,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/comunione_Franesco.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione","datePublished":"2014-08-15T22:00:42+00:00","dateModified":"2016-09-16T07:31:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/"},"wordCount":853,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/comunione_Franesco.jpg","keywords":["comunione sulla mano"],"articleSection":["Chiesa","Liturgia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/","name":"Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/comunione_Franesco.jpg","datePublished":"2014-08-15T22:00:42+00:00","dateModified":"2016-09-16T07:31:53+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/comunione_Franesco.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/09\/comunione_Franesco.jpg","width":297,"height":170},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/sulla-lingua-e-non-sulle-mani-ecco-il-modo-piu-corretto-per-prendere-la-comunione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Sulla lingua e non sulle mani: ecco il modo pi\u00f9 corretto per prendere la Comunione"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/36390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=36390"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/36390\/revisions"}],"predecessor-version":[{"id":36392,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/36390\/revisions\/36392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/36391"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=36390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=36390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=36390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}