{"id":3585,"date":"2009-12-03T00:00:00","date_gmt":"2009-12-02T23:00:00","guid":{"rendered":""},"modified":"2016-01-22T14:08:32","modified_gmt":"2016-01-22T13:08:32","slug":"rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/","title":{"rendered":"Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959."},"content":{"rendered":"<div style=\"text-align: justify;\"><em><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/Plinio_Correa_cover.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29633\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/Plinio_Correa_cover.jpg\" alt=\"Plinio_Correa_cover\" width=\"138\" height=\"200\" \/><\/a>Il 21 novembre 2009, all\u2019Augustinianum &#8211; a pochi passi dal Vaticano &#8211; , si sono incontrati tutti gli esponenti, italiani e non, di Alleanza Cattolica e di Tradizione Famiglia Propriet\u00e0 (TFP). L&#8217;occasione dell&#8217;incontro \u00e8 stato l&#8217;anniversario del cinquantenario dell\u2019uscita della principale opera di <strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=2604\" target=\"_blank\">Plinio Correa de Oliveira<\/a><\/strong>, \u201c<strong>Rivoluzione e Contro-Rivoluzione<\/strong>\u201d . <\/em><\/div>\n<p style=\"text-align: center;\"><em>Proponiamo di seguito la relazione del professor Massimo Introvigne\u00a0<\/em>dal sito del <strong>Cesnur<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>La bellezza della Cristianit\u00e0 contro la volgarit\u00e0 del moderno<\/strong><\/p>\n<p style=\"text-align: center;\">di <strong>Massimo Introvigne<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>1. La bellezza di <em>Rivoluzione e Contro-Rivoluzione<br \/>\n<\/em><\/strong><\/div>\n<p style=\"text-align: justify;\"><em>\u00abL\u2019espressione di<\/em> [F\u00ebdor Michajlovi\u010d] <em>Dostoevskij<\/em> [1821-1881] <em>che sto per citare \u00e8 senz\u2019altro ardita e paradossale, ma invita a riflettere: \u201cL\u2019umanit\u00e0 pu\u00f2 vivere \u2013 egli dice \u2013 senza la scienza, pu\u00f2 vivere senza pane, ma soltanto senza la bellezza non potrebbe pi\u00f9 vivere, perch\u00e9 non ci sarebbe pi\u00f9 nulla da fare al mondo. Tutto il segreto \u00e8 qui, tutta la storia \u00e8 qui\u201d\u00bb<\/em>[1]. Cos\u00ec Benedetto XVI nell\u2019incontro con gli artisti nella Cappella Sistina, del 21 novembre 2009.<\/p>\n<p style=\"text-align: justify;\">Di fronte all\u2019edizione del cinquantenario, curata da Giovanni Cantoni, di <em>Rivoluzione e Contro-Rivoluzione<\/em>[2] di Plinio Corr\u00eaa de Oliveira (1908-1995) ci viene spontaneo dire che si tratta di un <em>bel<\/em> libro, di una <em>bella<\/em> iniziativa. Non abbiamo dubbi sul fatto che si tratti di un libro <em>vero<\/em> e di un libro <em>buono<\/em>: e tuttavia, figli del secolo XXI, il nostro modo di esprimerci fa anzitutto riferimento al bello. Il linguaggio non \u00e8 mai casuale o irrilevante.<\/p>\n<p style=\"text-align: justify;\">Nel fatto che ci viene naturale parlare <em>anzitutto<\/em> di libro bello \u2014 e <em>solo<\/em> in seconda battuta, dopo avere riflettuto, di libro vero e buono \u2014 c\u2019\u00e8 tutta un\u2019epoca, il cui spirito non possiamo fare a meno di respirare quotidianamente per quanto sul piano intellettuale ci sforziamo di criticarlo.<\/p>\n<p style=\"text-align: justify;\">Seguire la pista che il nostro stesso linguaggio ci segnala significa entrare in uno dei dibattiti pi\u00f9 vivaci della sociologia contemporanea. Oggi di ciascuno di noi si dice che \u00abha le sue idee\u00bb, che segue le \u00absue\u00bb teorie \u2014 pi\u00f9 o meno intelligenti e articolate \u2014 sulla societ\u00e0 e sulla storia. Non \u00e8 sempre stato cos\u00ec. In una societ\u00e0 tradizionale quasi tutti condividono le stesse idee. C\u2019\u00e8 un pluralismo sociale \u2014 articolato in un\u2019infinit\u00e0 di mestieri, professioni, condizioni \u2014 ma non c\u2019\u00e8 a rigore un pluralismo ideologico.<\/p>\n<p style=\"text-align: justify;\">Quest\u2019ultimo nasce con la modernit\u00e0. Nello stesso spazio geografico iniziano a coesistere teorie contraddittorie e inconciliabili: non sui dettagli, ma sull\u2019essenziale. Emerge la societ\u00e0 complessa, la societ\u00e0 del pluralismo ideologico: ciascuno, appunto, \u00abha le sue idee\u00bb. Come si formano queste idee? Come sono scelte le teorie che, pi\u00f9 o meno consapevolmente, orientano la nostra vita?<\/p>\n<p style=\"text-align: justify;\">I sociologi hanno da tempo messo in discussione l\u2019immagine banale secondo cui ogni persona che vive nella societ\u00e0 complessa moderna sarebbe sia capace sia disposta a esaminare le diverse idee che cercano d\u2019imporsi alla sua attenzione \u2014 culturali, politiche, religiose \u2014, pesarle con un severo esame dottrinale su un\u2019ideale bilancia e scegliere quelle che sembrano pi\u00f9 vere.<\/p>\n<p style=\"text-align: justify;\">In realt\u00e0, pochissimi compiono le loro scelte in questo modo, persino in materia di religione. Le scelte sono fatte in modo assai meno meditato. La fiducia, l\u2019amicizia, il rapporto affettivo o di parentela con chi ci propone un sistema d\u2019idee \u00e8 spesso pi\u00f9 importante del suo contenuto[3].<\/p>\n<p style=\"text-align: justify;\">Inoltre, nello scegliere un\u2019idea o una teoria \u2014 che ce ne rendiamo conto o meno \u2014 non ci lasciamo attrarre solo dal suo contenuto informativo e normativo ma anche dal suo potenziale allusivo e dalla sua eleganza. Dire che un libro che propone idee \u2014 non solo un romanzo \u2014 \u00e8 bello, che \u00e8 bella una teoria o un\u2019idea indica allora qualche cosa di molto importante.<\/p>\n<p style=\"text-align: justify;\">Le teorie non sono fotografie della realt\u00e0. Una teoria sociale non \u00e8 una semplice fotografia della societ\u00e0. Non la rappresenta tutta. Un grande storico come Marco Tangheroni (1946-2004) \u2014 socio fondatore di Alleanza Cattolica, che di Corr\u00eaa de Oliveira fu attento e affezionato lettore \u2014 ci ricorda che anche chi ha la storia per professione <em>\u00abdeve fare una scelta tra gli infiniti fatti: se volesse riprodurli tutti egli non sarebbe meno pazzo di un geografo che volesse riprodurre la Terra in scala 1:1 e avrebbe bisogno, pertanto, di un altro pianeta di analoghe dimensioni!\u00bb\u00a0<\/em>[4].<\/p>\n<p style=\"text-align: justify;\">Chi elabora una teoria sceglie alcuni elementi di cui propone una rappresentazione, una riduzione a unit\u00e0 e una spiegazione. Il risultato di questo processo \u00e8 una figura che \u2014 secondo l\u2019espressione del filosofo italiano Enrico di Robilant \u2014 rappresenta e spiega la realt\u00e0 in modo non figurativo [5].<\/p>\n<p style=\"text-align: justify;\">Se le figure prodotte dalle teorie non sono semplicemente figurative, e hanno un potenziale allusivo, l\u2019attrazione che esse esercitano sull\u2019uomo moderno non \u00e8 esclusivamente di carattere cognitivo, ma implica anche un elemento estetico. Nel modello proposto da di Robilant, che cita numerosi esempi, questo non vale solo per le scienze sociali: pure teorie matematiche o fisiche si sono affermate anche per la loro singolare eleganza.<\/p>\n<p style=\"text-align: justify;\">Un micro-sociologo come Randall Collins, in un\u2019opera monumentale sulla sociologia della filosofia, \u00e8 arrivato alla stessa conclusione per le teorie filosofiche[6]. Sull\u2019\u00abestetica cognitiva\u00bb applicata alla storiografia c\u2019\u00e8 una vasta letteratura [7].<\/p>\n<p style=\"text-align: justify;\">Tutto questo avviene, sostiene Collins, perch\u00e9 nella societ\u00e0 moderna e postmoderna sono venute meno le gerarchie capaci di certificare certe idee come superiori ad altre sulla base di un argomento di autorit\u00e0. Poich\u00e9 tuttavia di gerarchie l\u2019uomo continua ad avere bisogno, queste sono ricreate attraverso rituali inconsapevoli che generano emozioni, alcune delle quali sono pi\u00f9 forti e coinvolgenti di altre [8].<\/p>\n<p style=\"text-align: justify;\">Quello che apprezziamo come elegante, inoltre \u2014 suggeriscono queste analisi \u2014, non \u00e8 meramente soggettivo. La percezione che abbiamo di qualcosa come bello e armonioso \u00e8 culturalmente negoziata e dipende in una certa misura da una tradizione. Esistono certo forme di bellezza universali, ma chi \u00e8 stato educato in Giappone si entusiasma per elementi artistici e musicali di quel Paese che a noi almeno a una prima percezione dicono poco.<\/p>\n<p style=\"text-align: justify;\">Il pensiero cattolico contro-rivoluzionario \u00e8 un pensiero della crisi. Nasce appunto quando la Rivoluzione ha iniziato a distruggere le gerarchie. Senza la Rivoluzione, non ci sarebbe evidentemente bisogno di un pensiero esplicitamente contro-rivoluzionario. Questo nasce nella societ\u00e0 complessa moderna dove ciascuno \u00abha le sue idee\u00bb.<\/p>\n<p style=\"text-align: justify;\">La visione della storia della Contro-Rivoluzione, pur contestandone le premesse, entra fatalmente nel \u00abmercato delle idee\u00bb della societ\u00e0 complessa, dove le teorie \u2014 che non possono pi\u00f9 contare sul solo argomento di autorit\u00e0 \u2014 competono fra loro cercando di presentarsi come pi\u00f9 plausibili e attraenti di altre. Qui la teoria contro-rivoluzionaria ottiene successo \u2014 non piccolo, come la sua storia dimostra \u2014 <em>anche<\/em> per la sua intrinseca eleganza, che la carica di un potenziale allusivo capace di suscitare un apprezzamento che \u00e8 <em>anche<\/em> estetico.<\/p>\n<p style=\"text-align: justify;\">Corr\u00eaa de Oliveira propone lo schema di tre \u2014 poi quattro \u2014 Rivoluzioni che attaccano l\u2019ordine naturale e cristiano cercando di spezzare prima i legami religiosi con la Riforma protestante (I Rivoluzione), poi i legami politici con la Rivoluzione francese (II Rivoluzione), quindi i legami economici con la Rivoluzione comunista (III Rivoluzione) [9], infine i legami micro-sociali della famiglia, quelli fra madre e figlio con l\u2019aborto e perfino quelli dell\u2019uomo con s\u00e9 stesso e interni al corpo umano con la droga e l\u2019ideologia di genere (IV Rivoluzione)[10].<\/p>\n<p style=\"text-align: justify;\">Il gesto del medico abortista che taglia il cordone ombelicale non per la vita ma per la morte simboleggia in un modo che pi\u00f9 tragicamente eloquente non potrebbe essere l\u2019opera della Rivoluzione, che non sopporta i legami e li distrugge.<\/p>\n<p style=\"text-align: justify;\">Il quadro nella storia del pensiero contro-rivoluzionario pre-esiste, almeno per le prime tre Rivoluzioni, a Corr\u00eaa de Oliveira, ma egli ha il merito di averlo presentato con una chiarezza e un\u2019eleganza per molti versi nuove. Il modo semplice e insieme profondo di presentare la storia dell\u2019Occidente moderno ha affascinato molti, ed \u00e8 passato anche nel Magistero pontificio.<\/p>\n<p style=\"text-align: justify;\">Papa Pio XII (1939-1958), nel suo celebre discorso <em>Nel contemplare<\/em> agli Uomini di Azione Cattolica d\u2019Italia, del 12 ottobre 1952, si serve di una formula che descrive la sequenza dell\u2019allontanamento dell\u2019Occidente dalla verit\u00e0 cattolica precisamente attraverso tre tappe che corrispondono al protestantesimo che nega la Chiesa, al deismo illuminista e all\u2019ateismo marxista: <em>\u00abCristo s\u00ec, Chiesa no. Poi: Dio s\u00ec, Cristo no. Finalmente il grido empio: Dio \u00e8 morto; anzi: Dio non \u00e8 mai stato\u00bb\u00a0<\/em>[11].<\/p>\n<p style=\"text-align: justify;\">Il regnante Pontefice Benedetto XVI non \u00e8 forse lettore dei classici della scuola contro-rivoluzionaria. Lo \u00e8 per\u00f2, in modo costante e appassionato, di Pio XII, che con questa scuola aveva un contatto intellettuale diretto. Nel discorso di Ratisbona del 2006, Benedetto XVI parla di quattro fasi della rottura dell\u2019armonia occidentale fra fede e ragione che si presentano come attacco alla cultura filosofica classica greca che era entrata in fecondo dialogo con il cristianesimo: quattro <em>\u00abdeellenizzazioni\u00bb\u00a0<\/em>[12], che riferisce rispettivamente al fideismo protestante, al razionalismo che culmina nell\u2019Illuminismo laicista, alle ideologie moderne e al nichilismo postmoderno.<\/p>\n<p style=\"text-align: justify;\">E nell\u2019enciclica <em>Spe salvi<\/em> ripercorre le tappe della perdita della nozione cristiana di speranza, anch\u2019essa fondata sull\u2019armonia fra fede e ragione, articolandole nell\u2019attacco alla ragione di Martin Lutero (1483-1546), nello scientismo illuminista che culmina con la Rivoluzione francese, nel sanguinoso mito comunista del Paradiso politico da realizzare sulla Terra, e nella disperazione postmoderna successiva alla caduta delle ideologie[13].<\/p>\n<p style=\"text-align: justify;\">Certo, i Pontefici \u2014 e molti altri \u2014 hanno apprezzato questo schema per la sua capacit\u00e0 di capire e spiegare la storia. E tuttavia la storia \u00e8 pi\u00f9 grande di qualsiasi schema, e pu\u00f2 essere rappresentata e ridotta a unit\u00e0 \u2014 senza necessariamente falsificarla \u2014 in mille modi diversi. Lo schema contro-rivoluzionario \u00e8 particolarmente adatto a essere presentato all\u2019uomo moderno per la sua chiarezza, semplicit\u00e0 e \u2014 appunto \u2014 eleganza.<\/p>\n<p style=\"text-align: justify;\">Quando si completa, come avviene in <em>Rivoluzione e Contro-Rivoluzione<\/em>, con uno schema del processo contro-rivoluzionario capace di rispettare la stessa simmetria parlare di teoria \u00abbella\u00bb non \u00e8 arbitrario, ed \u00e8 anzi pienamente giustificato.<\/p>\n<p style=\"text-align: justify;\">Un documento del 2006 del Pontificio Consiglio della Cultura dedicato alla bellezza, <em>La Via pulchritudinis<\/em>, ripropone una citazione dello scrittore e dissidente anti-comunista russo Aleksandr Isaevi\u010d Sol\u017eenicyn (1918-2008) nel suo <em>Discorso per la consegna del Premio Nobel per la Letteratura<\/em>: <em>\u00abQuesta antica triunit\u00e0 della Verit\u00e0, del Bene e della Bellezza non \u00e8 semplicemente una caduca formula da parata, come ci era sembrato ai tempi della nostra presuntuosa giovinezza materialistica. Se, come dicevano i sapienti, le cime di questi tre alberi si riuniscono, mentre i germogli della Verit\u00e0 e del Bene, troppo precoci e indifesi, vengono schiacciati, strappati e non giungono a maturazione, forse strani, imprevisti, inattesi saranno i germogli della Bellezza a spuntare e crescere nello stesso posto e saranno loro in tal modo a compiere il lavoro per tutti e tre\u00bb<\/em>[14].<\/p>\n<p style=\"text-align: justify;\">Questa riflessione di Sol\u017eenicyn ci aiuta a superare la prospettiva della sociologia della cultura contemporanea che, per quanto interessante, non pu\u00f2 assolutamente essere sufficiente. Alla scuola di san Tommaso d\u2019Aquino (1225 ca.-1274) la buona dottrina sa che ultimamente il vero, il bello e il buono <em>convertuntur<\/em>. <em>Devono<\/em> convergere, o c\u2019\u00e8 qualcosa che non va. Nelle parole del teologo svizzero Hans Urs von Balthasar (1905-1988), pure ricordate dal documento <em>La Via pulchritudinis<\/em>, forse nel mondo moderno <em>\u00abgli argomenti in favore della verit\u00e0 hanno esaurito la loro forza di conclusione logica\u00bb<\/em>[15] e il bene <em>\u00abha perduto la sua forza di attrazione\u00bb<\/em>[16], cos\u00ec che non resta che partire dal bello.<\/p>\n<p style=\"text-align: justify;\">Per non scadere in una prospettiva estetizzante che sarebbe a sua volta sovversiva, si dovr\u00e0 per\u00f2 <em>partire<\/em> dal bello per <em>arrivare<\/em> al vero e al buono, o meglio alla convergenza di vero, bello e buono. L\u2019uomo moderno, dopo le devastazioni della Rivoluzione, non \u00e8 pi\u00f9 capace di partire dal vero o dal buono? Benissimo \u2014 o malissimo \u2014: parta pure dal bello. Ma purch\u00e9 arrivi anche al vero e al buono.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec, che ci piaccia o no, in un mondo dove \u2014 per dirla con Sol\u017eenicyn \u2014 \u00ab<em>i germogli della Verit\u00e0 e del Bene, troppo precoci e indifesi, vengono schiacciati, strappati e non giungono a maturazione\u00bb<\/em>[17], la filosofia e la teologia della storia di <em>Rivoluzione e Contro-Rivoluzione<\/em> ci colpiscono anzitutto, e riescono a farsi largo in un mercato di beni simbolici incredibilmente affollato \u2014 milioni di libri, migliaia di teorie \u2014, grazie alla loro intrinseca coerenza ed eleganza. Ma questa bellezza non \u00e8 fine a s\u00e9 stessa.<\/p>\n<p style=\"text-align: justify;\">Come soleva dire Platone (427-347 a.C.), e ripete Papa Giovanni Paolo II (1978-2005), la bellezza \u00e8 <em>\u00abveritatis splendor\u00bb<\/em>[18]. Il bello \u00e8 la porta del vero, che conquista e spinge al buono. La convergenza dei valori non \u00e8 una pia aspirazione di san Tommaso: la constatiamo nella realt\u00e0, se solo abbiamo occhi per vedere e orecchie per intendere.<\/p>\n<p style=\"text-align: justify;\">Naturalmente anche tesi aberranti sono talora presentate con una certa grazia. Spesso questa deriva dalla familiarit\u00e0 di chi le propone con una tradizione estetica e letteraria che pure combatte, ma di cui si \u00e8 in qualche modo appropriato. Cos\u00ec, per esempio, si afferma spesso che la propaganda a favore dell\u2019ateismo del filosofo marxista tedesco Ernst Bloch (1885-1977) colpisce pi\u00f9 per l\u2019eleganza del linguaggio che per il rigore degli argomenti.<\/p>\n<p style=\"text-align: justify;\">L\u2019eleganza degli scritti di Bloch \u00e8 reale, ma \u00e8 pi\u00f9 poetica che architettonica e ricorda quella dei <em>Salmi<\/em>. E in effetti Bloch era stato allevato in una famiglia ebraica e conosceva molto bene la Bibbia. Pur proponendosi di combattere la religione, aveva assimilato stili e modi dalla Sacra Scrittura. Tuttavia un\u2019elegante costruzione sofistica ci abbaglia per qualche ora, ma finisce per lasciarci l\u2019amaro in bocca.<\/p>\n<p style=\"text-align: justify;\">Non ogni eleganza \u00e8 un autentico <em>splendor<\/em>. Splende davvero solo l\u2019eleganza dietro cui brilla la verit\u00e0: il resto ha la luce effimera del fuoco fatuo. Chi si accosta a <em>Rivoluzione e Contro-Rivoluzione<\/em> attratto dalla sua architettura coerente ed elegante comprende ben presto che questa limpida simmetria \u00e8 il riflesso di un ordine superiore, il quale \u2014 perch\u00e9 non dirlo? \u2014 regna anzitutto nell\u2019anima e nella vita spirituale dell\u2019autore. Il libro \u00e8 bello perch\u00e9 \u00e8 vero; e, in quanto vero, \u00e8 buono.<\/p>\n<p style=\"text-align: justify;\"><strong>2. La bellezza in <em>Rivoluzione e Contro-Rivoluzione<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">La Rivoluzione, naturalmente, ha inciso anche sulla percezione del bello. La Rivoluzione, si pu\u00f2 dire,\u00e8 la via della bruttezza. Nel citato documento vaticano <em>La Via pulchritudinis<\/em> leggiamo che oggi <em>\u00abuna certa abitudine alla bruttezza, al cattivo gusto, alla volgarit\u00e0, si vede promossa sia dalla pubblicit\u00e0 sia da alcuni \u201cartisti folli\u201d che fanno dell\u2019immondo e del brutto un valore, al fine di suscitare scandalo\u00bb\u00a0<\/em>[19].<\/p>\n<p style=\"text-align: justify;\">Incalza Benedetto XVI: <em>\u00abTroppo spesso, per\u00f2, la bellezza che viene propagandata \u00e8 illusoria e mendace, superficiale e abbagliante fino allo stordimento e, invece di far uscire gli uomini da s\u00e9 e aprirli ad orizzonti di vera libert\u00e0 attirandoli verso l\u2019alto, li imprigiona in se stessi e li rende ancor pi\u00f9 schiavi, privi di speranza e di gioia. Si tratta di una seducente ma ipocrita bellezza, che ridesta la brama, la volont\u00e0 di potere, di possesso, di sopraffazione sull\u2019altro e che si trasforma, ben presto, nel suo contrario, assumendo i volti dell\u2019oscenit\u00e0, della trasgressione o della provocazione fine a se stessa\u00bb\u00a0<\/em>[20].<\/p>\n<p style=\"text-align: justify;\">Quest\u2019opera di sovversione non ha sempre successo, come dimostra il fascino che continuano a esercitare anche presso il pubblico moderno, pure tecnicamente \u00abmale educato\u00bb, espressioni dell\u2019arte tradizionale e cristiana. Ma questo non significa che la promozione della bruttezza non sia stata, in certe epoche storiche, al centro degli sforzi della Rivoluzione.<\/p>\n<p style=\"text-align: justify;\">In Brasile un autentico assalto alla nozione tradizionale di bellezza nasce con il modernismo, versione brasiliana del futurismo lanciata con la Semana de arte moderna tenuta a San Paolo dall\u201911 al 18 febbraio 1922. Se non tutte le manifestazioni artistiche del modernismo sono spregevoli \u2014 e in anni successivi si vedr\u00e0 di molto peggio \u2014 lo scopo \u00e8 di schierarsi <em>\u00abcontro il tradizionalismo, il \u201cpassatismo\u201d\u00bb<\/em>[21] attraverso la provocazione e lo scandalo.<\/p>\n<p style=\"text-align: justify;\">Nel 1928 \u00ab<em>esce a S. Paulo la \u201cRevista de antropofagia\u201d con il contributo dei nomi pi\u00f9 significativi del Modernismo brasiliano. Il <\/em>Manifesto<em> era firmato da \u201c<\/em>[Jos\u00e9] <em>Oswald de Andrade<\/em> [1890-1954]. <em>A Piratininga. Anno 374 dalla deglutizione del Vescovo<\/em> [mons. Pedro Fernandes] <em>Sardinha<\/em> [1496-1556]<em>\u201d. E il Vescovo Sardinha era il prelato che nel 1554 (1554 + 374 = 1928) era stato deglutito da un antropofago<\/em> caet\u00e9<em>. Il nome del movimento nasceva da un quadro di Tarsila do Amaral<\/em> [1886-1973]<em>, diventato poi celebre, che rappresentava l\u2019indio antropofago, simbolo del nuovo Brasile modernista\u00bb\u00a0<\/em>[22].<\/p>\n<p style=\"text-align: justify;\">Certo, il riferimento al cannibalismo \u00e8 anche metaforico, nel senso che il Brasile \u00e8 invitato a \u00abdeglutire\u00bb la pi\u00f9 moderna cultura europea e ad assimilarla. Tuttavia ci sono qui due elementi importanti, che non sfuggiranno a Corr\u00eaa de Oliveira: il modernismo, nel suo tentativo di scardinare la nozione tradizionale di bellezza, esalta il brutto e il ripugnante \u2014 che cosa ci pu\u00f2 essere di pi\u00f9 ripugnante della <em>\u00abdeglutizione\u00bb\u00a0<\/em>[23] di un cannibale? \u2014 e nel contesto brasiliano \u00e8 anche \u00abtribalista\u00bb, in quanto considera la cultura selvaggia ma genuina dell\u2019indio della foresta antropofago come superiore a quella del vescovo Sardinha che pensa di civilizzarlo.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 privo d\u2019interesse notare che il modernismo artistico determina una spaccatura nell\u2019ambito della destra brasiliana. Jackson de Figueiredo (1891-1928) \u2014 l\u2019intellettuale decadentista convertito al cattolicesimo e alla Contro-Rivoluzione che \u00e8 per alcuni versi un precursore di Corr\u00eaa de Oliveira \u2014 si schiera decisamente contro il modernismo, mentre Pl\u00ednio Salgado (1895-1975), il fondatore del cosiddetto \u00abfascismo brasiliano\u00bb delle \u00abcamicie verdi\u00bb, l\u2019Azione Integralista Brasiliana, scende in campo a favore dei modernisti. Il movimento di Salgado \u00e8 anche tribalista. Il suo saluto romano, imitato dal fascismo italiano, \u00e8 accompagnato dalla ripetizione della parola \u00ab<em>Anahu\u00e9<\/em>\u00bb, che vorrebbe riprendere un presunto grido di guerra degli indios <em>tupi\u00a0<\/em>[24]<em>.<\/em><\/p>\n<p style=\"text-align: justify;\">Plinio Corr\u00eaa de Oliveira dedica molte energie a cercare di convincere i vescovi brasiliani che l\u2019Integralismo di Salgado \u00e8 pericoloso per la fede cattolica[25], nonostante il rispetto che professa per la Chiesa e il fatto che per un certo periodo il segretario nazionale del partito sia un sacerdote, don H\u00e9lder Pessoa C\u00e2mara (1909-1999), pi\u00f9 tardi vescovo ausiliare di Rio de Janeiro e poi arcivescovo di Olinda e Recife [26].<\/p>\n<p style=\"text-align: justify;\">La battaglia di Corr\u00eaa de Oliveira contro la \u00abfalsa destra\u00bb modernista e futurista che vuole ricostruire la societ\u00e0 su fondamenta diverse da quelle cristiane \u00e8 oggi di grande attualit\u00e0, in un momento in cui anche in Italia false destre che vogliono prescindere dal cristianesimo sono riproposte da quelli che un tempo si chiamavano \u00abspiriti forti\u00bb e che oggi forse dovremmo chiamare \u00abspiriti fini\u00bb [27].<\/p>\n<p style=\"text-align: justify;\">Negli spunti anti-tradizionali e modernisti delle \u00abcamicie verdi\u00bb c\u2019\u00e8 gi\u00e0 un preannuncio della fase successiva del processo rivoluzionario in Brasile, il populismo, cos\u00ec come nel populismo c\u2019\u00e8 un preannuncio del socialismo. Tutti gli studi della situazione politica e culturale iberoamericana intorno alla seconda guerra mondiale e nei decenni successivi fanno riferimento alla categoria di \u00abpopulismo\u00bb [28].<\/p>\n<p style=\"text-align: justify;\">La definizione della categoria si rivela per\u00f2 particolarmente elusiva. Anzitutto, mentre concetti come \u00absocialismo\u00bb o \u00abdemocratismo cristiano\u00bb sono definiti in prima istanza dai loro sostenitori \u2014 e solo in un secondo tempo dai critici \u2014 quasi nessun movimento si auto-proclama \u00abpopulista\u00bb. L\u2019etichetta \u00e8 applicata <em>ex post<\/em> da osservatori esterni, spesso critici.<\/p>\n<p style=\"text-align: justify;\">Si corre cos\u00ec il grave rischio che \u00abpopulismo\u00bb \u2014 quando \u00e8 applicato a qualunque esponente politico o <em>leader<\/em> culturale capace di ottenere un notevole successo e consenso personale, dal presidente della Repubblica Argentina Juan Domingo Per\u00f3n (1895-1974) al presidente del Consiglio dei Ministri italiano Silvio Berlusconi [29] \u2014 rischi, a rigore, di non significare pi\u00f9 nulla.<\/p>\n<p style=\"text-align: justify;\">La categoria generale di \u00abpopulismo\u00bb \u00e8 diventata cos\u00ec ambigua da far sorgere il dubbio se non sia pi\u00f9 opportuno che la scienza politica l\u2019abbandoni. Rimane tuttavia ineludibile come categoria storica, che designa un certo stile culturale e politico iberoamericano degli anni 1940-1960.<\/p>\n<p style=\"text-align: justify;\">In generale questo populismo \u00e8 l\u2019appello al \u00abpopolo\u00bb contro le <em>\u00e9lite<\/em> politiche, religiose e culturali, fondato sull\u2019argomento che i mali del \u00abpopolo\u00bb derivano dall\u2019eccessivo potere e dalla malizia delle <em>\u00e9lite<\/em> cos\u00ec che, trasferendo il potere dalle <em>\u00e9lite <\/em>al \u00abpopolo\u00bb, tutti i problemi saranno risolti. Un elemento costitutivo del populismo iberoamericano \u00e8 il \u00abnuovismo\u00bb: il popolo, per definizione, rappresenta il nuovo e le <em>\u00e9lite<\/em> rappresentano il vecchio.<\/p>\n<p style=\"text-align: justify;\">La fase storica brasiliana dal 1945 al 1964 \u00e8 comunemente chiamata \u00abRepubblica populista\u00bb. Quest\u2019epoca comprende la seconda fase della carriera politica di Get\u00falio Dornelles Vargas (1882-1954), pi\u00f9 volte presidente della Repubblica Federativa del Brasile, e \u2014 dopo il suo suicidio, nel 1954 \u2014 i mandati dei presidenti suoi successori \u2014 quasi tutti, suoi antichi collaboratori \u2014 nel decennio 1954-1964. A politiche economiche demagogiche \u2014 giustificate con il mito redistributivo della riforma agraria \u2014 corrisponde sul piano culturale un disprezzo per il \u00abvecchio Brasile\u00bb e un generale involgarimento della vita sociale e culturale.<\/p>\n<p style=\"text-align: justify;\">Nulla testimonia meglio l\u2019idea di fare piazza pulita della storia e di ricominciare <em>ex novo<\/em> tipica del populismo della decisione del presidente Juscelino Kubitschek (1902-1976) di costruire dal nulla una nuova capitale, Brasilia \u2014 \u00abinaugurata\u00bb il 21 aprile 1960 \u2014, abbandonando la capitale storica Rio de Janeiro. Qualunque cosa si pensi del valore artistico dei suoi principali edifici, Brasilia resta un simbolo della volont\u00e0 della \u00abRepubblica populista\u00bb di rompere con il passato, con la tradizione e con la storia.<\/p>\n<p style=\"text-align: justify;\">Per la volgarit\u00e0 culturale degli anni 1950 il quadro di riferimento non pu\u00f2 essere solo quello nazionale del populismo brasiliano, ma si deve tener conto anche della situazione internazionale. Negli Stati Uniti d\u2019America gli anni 1950 sono quelli di una nuova <em>popular culture<\/em> generalmente considerata di livello pi\u00f9 discutibile di quella dei decenni precedenti [30], la cui icona di riferimento \u00e8 il cantante Elvis Presley (1935-1977). I miti diffusi da una Hollywood che progressivamente s\u2019involgarisce non esauriscono peraltro la cultura statunitense dell\u2019epoca.<\/p>\n<p style=\"text-align: justify;\">Il Magistero di Papa Pio XII propone una serrata critica della sostanza del populismo, pur senza usare questo termine che, va sempre ricordato, \u00e8 una costruzione <em>ex post<\/em> degli storici. La critica si fonda sulla distinzione, enunciata nel celebre <em>Radiomessaggio natalizio ai popoli del mondo intero<\/em> del 24 dicembre 1944[31], fra il <em>\u00abpopolo\u00bb<\/em>[32], realt\u00e0 positiva ma diversa e armonica, e la <em>\u00abmoltitudine amorfa o, come suol dirsi, \u201cmassa\u201d\u00bb<\/em>[33], dove scompaiono le differenze in una falsa unit\u00e0 facilmente plasmabile dalla politica totalitaria.<\/p>\n<p style=\"text-align: justify;\">L\u2019atteggiamento anti-populista di Pio XII emerge anche nelle ripetute allocuzioni al patriziato e alla nobilt\u00e0 romana[34], dove difende il ruolo sia storico sia attuale delle <em>\u00e9lite<\/em> e della loro cultura \u2014 non, evidentemente, l\u2019eventuale manipolazione e cattivo uso di questo ruolo da parte di <em>\u00e9lite<\/em> immorali e prevaricatrici \u2014 a fronte di ogni critica preconcetta di tipo populista.<\/p>\n<p style=\"text-align: justify;\">Al contrario negli anni 1950 del populismo brasiliano <em>\u00abil vertice della Chiesa Cattolica brasiliana fu cooperatore e legittimatore\u00bb<\/em>[35]. La Conferenza Episcopale Brasiliana, fondata nel 1952, \u00e8 la creazione del vescovo ausiliare di Rio de Janeiro mons. C\u00e2mara, il quale ne fa il primo esempio mondiale d\u2019istituzione la cui voce sovrasta quasi completamente quella dei singoli vescovi. Fino alla morte di Pio XII nei suoi documenti il Magistero del Papa \u00e8 sostanzialmente ignorato.<\/p>\n<p style=\"text-align: justify;\">Mons. C\u00e2mara \u00e8 lo stesso sacerdote che abbiamo incontrato come segretario del partito delle \u00abcamicie verdi\u00bb, e che diventer\u00e0 poi una celebrit\u00e0 mondiale come arcivescovo di Olinda e Recife e alto protettore della \u00abteologia della liberazione\u00bb d\u2019ispirazione marxista[36]. Sbaglia chi liquida la sua avventura nelle \u00abcamicie verdi\u00bb come un peccato di giovent\u00f9. Al contrario l\u2019itinerario dal modernismo culturale del partito di Salgado al populismo, e dal populismo al socialismo, ha una sua coerenza interna e C\u00e2mara non \u00e8 stato certo l\u2019unico intellettuale brasiliano a percorrerlo.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019<em>Autoritratto filosofico<\/em> che arricchisce \u2014 insieme a tanti altri documenti pertinenti \u2014 l\u2019edizione italiana del cinquantenario, Corr\u00eaa de Oliveira afferma di <em>Rivoluzione e Contro-Rivoluzione<\/em> che <em>\u00abil suo tema non aveva relazioni prossime con una qualche problematica dell\u2019attualit\u00e0 brasiliana nel 1959, anno in cui \u00e8 stata pubblicata\u00bb\u00a0<\/em>[37].<\/p>\n<p style=\"text-align: justify;\">In un\u2019attenta ricostruzione della sua genesi \u2014 anch\u2019essa pubblicata in occasione del cinquantenario \u2014 Caio Vidigal Xavier da Silveira, uno dei collaboratori pi\u00f9 vicini all\u2019autore, riferisce che semmai <em>\u00abla redazione \u00e8 legata ai viaggi che il dottor Plinio <\/em>[Corr\u00eaa de Oliveira]<em> fece in Europa nel 1950 e 1952\u00bb\u00a0<\/em>[38].<\/p>\n<p style=\"text-align: justify;\">Nel corso di questi viaggi si rese conto che alcuni interlocutori europei di scuola contro-rivoluzionaria <em>\u00ablo guardavano un po\u2019 dall\u2019alto in basso\u00bb\u00a0<\/em>[39]: la loro genealogia intellettuale risaliva almeno al secolo XIX, mentre <em>\u00abil piccolo movimento brasiliano sembrava nato ieri\u00bb<\/em>[40]<em>. <\/em>Venne cos\u00ec in mente a Corr\u00eaa de Oliveira di predisporre una sorta di <em>\u00abbiglietto da visita\u00bb<\/em>[41] da lasciare a questi interlocutori: fu questa la prima idea di <em>Rivoluzione e Contro-Rivoluzione<\/em>.<\/p>\n<p style=\"text-align: justify;\">Chi scrive, tuttavia, lo fa sempre in un contesto storico e geografico determinato, per quanto il suo scopo non sia quello di affrontare i problemi del contesto. E il contesto brasiliano degli anni 1950 \u00e8 quello del populismo. Il gruppo di amici di Corr\u00eaa de Oliveira che aveva contrastato fin dagli anni 1920 il modernismo artistico-letterario e l\u2019\u00abintegralismo\u00bb delle \u00abcamicie verdi\u00bb prende la guida della lotta contro il populismo.<\/p>\n<p style=\"text-align: justify;\">La rivista diretta da Corr\u00eaa de Oliveira, <em>Catolicismo<\/em>, costituisce di fatto negli anni 1950 il principale veicolo in Brasile della presentazione articolata e apologetica del magistero di Pio XII, e di una critica cattolica sistematica \u2014 senza che siano attaccati in esplicito n\u00e9 vescovi n\u00e9 singoli uomini politici \u2014 alle idee populiste sul piano sia culturale sia religioso e politico.<\/p>\n<p style=\"text-align: justify;\">Nel clima del populismo, <em>Catolicismo<\/em> svolge un\u2019opera sistematica di difesa del ruolo delle <em>\u00e9lite<\/em> e di lotta contro l\u2019involgarimento della cultura. Vanno in questa direzione anzitutto i commenti di Corr\u00eaa de Oliveira alle allocuzioni alla nobilt\u00e0 e al patriziato romano di Pio XII[42], i quali suscitano fra l\u2019altro l\u2019apprezzamento di Don Pedro Henrique de Orl\u00e9ans e Bragan\u00e7a (1909-1981), capo della Casa Imperiale del Brasile, due dei cui figli diventeranno poi stretti collaboratori di Corr\u00eaa de Oliveira.<\/p>\n<p style=\"text-align: justify;\">Quest\u2019ultimo \u2014 pur ribadendo l\u2019insegnamento del Magistero cattolico secondo cui la regalit\u00e0 sociale di Ges\u00f9 Cristo pu\u00f2 essere perseguita attraverso qualunque forma legittima di governo \u2014 \u00e8 di famiglia monarchica, partecipa a iniziative monarchiche fin dagli anni del Liceo e considera l\u2019avversione di principio per la monarchia come un aspetto fra i pi\u00f9 deteriori dell\u2019odio populista per le <em>\u00e9lite<\/em>. Don Pedro Henrique firma nel 1960 un\u2019importante prefazione all\u2019edizione francese di <em>Rivoluzione e Contro-Rivoluzione<\/em>[43], ora tradotta in italiano per l\u2019edizione del cinquantenario curata da Cantoni[44].<\/p>\n<p style=\"text-align: justify;\">Sempre nel filone anti-populista di <em>Catolicismo<\/em> si situa la serie <em>Ambientes, costumes, civiliza\u00e7oes<\/em> in cui partendo da immagini, fotografie, opere artistiche, episodi storici e <em>film<\/em> il pensatore brasiliano mostra l\u2019influsso delle tendenze, dell\u2019ambiente, dell\u2019arte e del gusto nella formazione della mentalit\u00e0 e della cultura.<\/p>\n<p style=\"text-align: justify;\">L\u2019architettura di <em>Rivoluzione e Contro-Rivoluzione<\/em> riposa su due architravi. La prima, gi\u00e0 menzionata e per cos\u00ec dire orizzontale, \u00e8 quella delle tre fasi della Rivoluzione, cui poi sar\u00e0 aggiunta la IV Rivoluzione. La seconda, verticale, scava in profondit\u00e0 all\u2019interno di ciascuna fase del processo rivoluzionario e svela come la Rivoluzione non si riduca alla sua parte pi\u00f9 visibile, i fatti. Contrariamente a quanto afferma la teoria marxista del primato della prassi, dietro i fatti ci sono le idee.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 la prassi a produrre le dottrine, ma sono le dottrine a produrre la prassi. Ma neppure le dottrine costituiscono la radice ultima del processo rivoluzionario. Dietro le idee vi sono quelle che il pensatore brasiliano chiama \u00abtendenze\u00bb, rappresentate principalmente dall\u2019orgoglio e dalla sensualit\u00e0. Secondo una citazione prediletta da Corr\u00eaa de Oliveira, tratta dal romanzo del 1914 <em>Le D\u00e9mon de midi<\/em> di Paul Bourget (1852-1935), <em>\u00abbisogna vivere come si pensa se no, prima o poi, si finisce col pensare come si \u00e8 vissuto\u00bb\u00a0<\/em>[45].<\/p>\n<p style=\"text-align: justify;\">Anche questo secondo elemento architettonico dell\u2019opera fondamentale di Corr\u00eaa de Oliveira vale sia per la Rivoluzione sia per la Contro-Rivoluzione. Il processo contro-rivoluzionario di riconquista della verit\u00e0 cattolica non pu\u00f2 partire semplicemente dalla politica, ma deve rifare tutto il cammino all\u2019inverso: restaurare buone tendenze, perch\u00e9 ne nascano buone idee e quindi buone pratiche tanto nella vita personale come in quella culturale, sociale e politica.<\/p>\n<p style=\"text-align: justify;\">Se aspetto essenziale del populismo \u00e8 l\u2019involgarimento degli ambienti e dei costumi, al cuore di <em>Rivoluzione e Contro-Rivoluzione<\/em> si situa l\u2019idea che, nella logica del partire dalle tendenze per arrivare alle idee e ai fatti, un processo contro-rivoluzionario non potr\u00e0 che muovere da una riforma dei gusti, dell\u2019educazione, dell\u2019arte, degli ambienti e della cultura: una riforma, in altre parole, del modo di accostarsi alla bellezza.<\/p>\n<p style=\"text-align: justify;\">Mentre il populismo \u2014 attaccando e deridendo le <em>\u00e9lite<\/em> \u2014 proclama di volere abbassare la cultura di <em>\u00e9lite<\/em> al livello della cultura di massa, la Contro-Rivoluzione secondo Corr\u00eaa de Oliveira deve piuttosto mirare a elevare la moderna cultura di massa, per quanto possibile, al livello della cultura delle <em>\u00e9lite<\/em>.<\/p>\n<p style=\"text-align: justify;\">Con queste riflessioni Corr\u00eaa de Oliveira s\u2019inserisce in un dibattito culturale tipico degli anni 1950 e 1960. La discussione sul ruolo negativo o positivo della <em>popular culture<\/em> \u00e8 in quegli anni al centro della riflessione della Scuola di Francoforte con i filosofi e sociologi tedeschi Theodor Wiesengrund Adorno (1903-1969) e Max Horkheimer (1895-1973), due autori letti con attenzione e ripetutamente citati \u2014 quanto all\u2019impostazione dei problemi, e senza condividerne le soluzioni \u2014 anche dal Pontefice regnante [46].<\/p>\n<p style=\"text-align: justify;\">Il maggiore sociologo brasiliano del secolo XX, Gilberto de Mello Freyre (1900-1987), negli stessi anni riflette sul ruolo dell\u2019arte, della cultura, del costume e perfino della cucina nel conferire ai popoli la loro peculiare identit\u00e0 e nello spiegarne scelte storiche fondamentali che rimarrebbero altrimenti incomprensibili[47]. Alcune idee di Freyre sono molto lontane da Corr\u00eaa de Oliveira, ma i due pensatori si conoscevano e si stimavano. Con Adorno e Horkheimer la lontananza \u00e8 ancora maggiore.<\/p>\n<p style=\"text-align: justify;\">Se per\u00f2 le risposte sono molto lontane \u2014 molti oggi direbbero che quelle di Horkheimer e Adorno sono semplicemente sbagliate[48] \u2014 sono vicine le domande: quanto influiscono sulle idee e sui fatti le tendenze, e quindi l\u2019arte, il costume, gli ambienti? Freyre, i pensatori della Scuola di Francoforte e Corr\u00eaa de Oliveira sono d\u2019accordo nel rispondere che influiscono molto, e che chi trascura questa influenza sbaglia.<\/p>\n<p style=\"text-align: justify;\">L\u2019edizione italiana del cinquantenario di <em>Rivoluzione e Contro-Rivoluzione<\/em> include opportunamente tra le appendici l\u2019opera postuma, pubblicata per la prima volta nel 1998, in italiano, <em>Note sul concetto di Cristianit\u00e0<\/em>[49]. Qui Corr\u00eaa de Oliveira ritorna su questo aspetto essenziale di <em>Rivoluzione e Contro-Rivoluzione<\/em>: <em>\u00able forme, i colori, i suoni, gli odori e i sapori\u00bb\u00a0<\/em>[50] e <em>\u00abgli oggetti di cui<\/em> [l\u2019uomo] <em>si circonda\u00bb\u00a0<\/em>[51] sono elementi essenziali nella formazione delle tendenze: <em>\u00abUn mobile comodo \u00e8 quello che<\/em> <em>serve solo al corpo: un mobile elegante \u00e8 quello che serve anche all\u2019anima. Un tessuto resistente, gradevole al tatto, adatto al clima, soddisfa il corpo. Ma l\u2019anima ha esigenze proprie e chiede che sia bello\u00bb\u00a0<\/em>[52].<\/p>\n<p style=\"text-align: justify;\">Secondo Cantoni, \u00e8 questo <em>\u00ab<\/em>forse <em>il principale aspetto di novit\u00e0\u00bb\u00a0<\/em>[53] di <em>Rivoluzione e Contro-Rivoluzione<\/em>. Se la tematica delle tendenze e della loro formazione trova antecedenti remoti nel dibattito antico e medioevale sulle <em>inclinationes<\/em> e in quello sociologico sulla ritualit\u00e0 della vita quotidiana a partire da \u00c9mile Durkheim (1858-1917), precedenti e contesti pi\u00f9 prossimi dicono riferimento alla polemica di de Figueiredo contro l\u2019imbarbarimento della cultura in Brasile, al populismo degli anni 1950 e alle controversie suscitate da scelte di organismi e di dirigenze ecclesiastiche che avevano aderito <em>toto corde<\/em> al populismo.<\/p>\n<p style=\"text-align: justify;\">Vidigal Xavier da Silveira sottolinea anche l\u2019importanza di una letteratura di lingua francese nell\u2019itinerario che porta il giovane Corr\u00eaa de Oliveira a scoprire il ruolo cruciale degli ambienti, dell\u2019arte e delle memorie nel formare le tendenze[54]. A chi conosce l\u2019opera di Corr\u00eaa de Oliveira \u00e8 noto il riferimento al romanziere belga Joris-Karl Huysmans (1848-1907) [55] il cui itinerario dal decadentismo, che nel suo caso lo aveva portato perfino a esplorare il satanismo [56], alla fede cattolica anticipa quello di de Figueiredo in Brasile.<\/p>\n<p style=\"text-align: justify;\">Vidigal Xavier da Silveira aggiunge il riferimento alla lettura di Marcel Proust (1871-1922)[57], le cui idee sono evidentemente lontane da <em>Rivoluzione e Contro-Rivoluzione<\/em>, ma che incuriosisce Corr\u00eaa de Oliveira per la sua capacit\u00e0 di mostrare come i comportamenti e le idee nascono da atmosfere cariche di simboli e di memoria.<\/p>\n<p style=\"text-align: justify;\"><em>Rivoluzione e Contro-Rivoluzione<\/em> \u2014 come le appendici scelte da Cantoni per l\u2019edizione italiana del cinquantenario confermano \u2014 non \u00e8 dunque solo un bel libro: un\u2019espressione che, come abbiamo visto, il riferimento all\u2019estetica cognitiva permette di considerare tutt\u2019altro che generica. \u00c8 anche un libro sulla bellezza e sulla <em>via pulchritudinis<\/em>, che Corr\u00eaa de Oliveira percorre attraverso tutti i suoi sentieri [58].<\/p>\n<p style=\"text-align: justify;\">Dalla bellezza della natura a quella dell\u2019arte, dalla bellezza delle vite sante \u2014 l\u2019edizione curata da Cantoni moltiplica giustamente i documenti che ripercorrono l\u2019epopea del santo prediletto dal pensatore brasiliano, san Luigi Maria Grignion de Montfort (1673-1716) \u2014 fino alla bellezza delle istituzioni della Cristianit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Il tema della <em>via pulchritudinis <\/em>ha un ruolo centrale nel magistero di Benedetto XVI. A proposito, per esempio, delle <em>\u00abcattedrali, vera gloria del Medioevo cristiano\u00bb<\/em>[59], il Pontefice ha sottolineato nel corso dell\u2019udienza generale del 18 novembre 2009 come i capolavori del romanico mirassero a <em>\u00absuscitare nelle anime impressioni forti, sentimenti che potessero incitare a fuggire il vizio, il male, e a praticare la virt\u00f9, il bene\u00bb\u00a0<\/em>[60] e perfino a fare <em>\u00abgustare un anticipo della beatitudine eterna\u00bb\u00a0<\/em>[61].<\/p>\n<p style=\"text-align: justify;\">Quanto alle <em>\u00abcattedrali gotiche\u00bb\u00a0<\/em>[62], <em>\u00abmostravano una sintesi di fede e di arte armoniosamente espressa attraverso il linguaggio universale e affascinante della bellezza, che ancor oggi suscita stupore.<\/em> [\u2026] <em>Lo slancio verso l\u2019alto voleva invitare alla preghiera ed era esso stesso una preghiera<\/em>. [\u2026]\u00a0 <em>Dalle vetrate dipinte una cascata di luce si riversava sui fedeli per narrare loro la storia della salvezza e coinvolgerli in questa storia\u00bb<\/em>[63].<\/p>\n<p style=\"text-align: justify;\"><em>\u00abPossiamo comprendere meglio il senso che veniva attribuito a una cattedrale gotica, considerando il testo dell\u2019iscrizione incisa sul portale centrale di Saint-Denis, a Parigi: \u201cPassante, che vuoi lodare la bellezza di queste porte, non lasciarti abbagliare n\u00e9 dall\u2019oro, n\u00e9 dalla magnificenza, ma piuttosto dal faticoso lavoro. Qui brilla un\u2019opera famosa, ma voglia il cielo che quest\u2019opera famosa che brilla faccia splendere gli spiriti, affinch\u00e9 con le verit\u00e0 luminose s\u2019incamminino verso la vera luce, dove il Cristo \u00e8 la vera porta\u201d\u00bb<\/em>[64].<\/p>\n<p style=\"text-align: justify;\"><em>\u00abLa forza dello stile romanico e lo splendore delle cattedrali gotiche ci rammentano che la <\/em>via pulchritudinis<em>, la via della bellezza, \u00e8 un percorso privilegiato e affascinante per avvicinarsi al Mistero di Dio. Che cos\u2019\u00e8 la bellezza, che scrittori, poeti, musicisti, artisti contemplano e traducono nel loro linguaggio, se non il riflesso dello splendore del Verbo eterno fatto carne? <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Afferma sant\u2019Agostino <\/em>[354-430]<em>:<\/em> <em>\u201cInterroga la bellezza della terra, interroga la bellezza del mare, interroga la bellezza dell\u2019aria diffusa e soffusa. Interroga la bellezza del cielo, interroga l\u2019ordine delle stelle, interroga il sole, che col suo splendore rischiara il giorno; interroga la luna, che col suo chiarore modera le tenebre della notte. Interroga le fiere che si muovono nell&#8217;acqua, che camminano sulla terra, che volano nell&#8217;aria: anime che si nascondono, corpi che si mostrano; visibile che si fa guidare, invisibile che guida. Interrogali! Tutti ti risponderanno: Guardaci: siamo belli! La loro bellezza li fa conoscere. Questa bellezza mutevole chi l\u2019ha creata, se non la Bellezza Immutabile?\u201d<\/em> (Sermo CCXLI<em>, 2: PL 38, 1134)\u00bb<\/em>[65].<\/p>\n<p style=\"text-align: justify;\">Sulla bellezza il Papa \u00e8 tornato nel viaggio che ha compiuto nella Repubblica Ceca dal 26 al 28 settembre 2009. <em>\u00abChe cosa attira tante persone a Praga<\/em> \u2014 si \u00e8 chiesto il Pontefice \u2014 <em>se non la sua bellezza?\u00bb\u00a0<\/em>[66]. <em>\u00abLa stupefacente bellezza delle sue chiese, del castello, delle piazze e dei ponti non possono che orientare a Dio le nostre menti. La loro bellezza esprime fede; sono epifanie di Dio che giustamente ci permettono di considerare le grandi meraviglie alle quali noi creature possiamo aspirare quando diamo espressione alla dimensione estetica e conoscitiva del nostro essere pi\u00f9 profondo\u00bb\u00a0<\/em>[67].<\/p>\n<p style=\"text-align: justify;\">Meditazione sulla memoria storica della cristianit\u00e0 e sulla bellezza, sul buono e sul bello s\u2019incontrano a proposito del Castello di Praga, su cui il Papa torna nell\u2019udienza del 30 settembre 2009 in Piazza San Pietro, in cui traccia un bilancio del suo viaggio nella Repubblica Ceca. <em>\u00abIl Castello di Praga, straordinario sotto il profilo storico e architettonico, suggerisce un\u2019ulteriore riflessione pi\u00f9 generale: esso racchiude nel suo vastissimo spazio molteplici monumenti, ambienti e istituzioni, quasi a rappresentare una<\/em> polis<em>, in cui convivono in armonia la Cattedrale e il Palazzo, la piazza e il giardino<\/em> [\u2026] <em>l\u2019ambito civile e quello religioso, non giustapposti, ma in armonica vicinanza nella distinzione\u00bb\u00a0<\/em>[68].<\/p>\n<p style=\"text-align: justify;\">Vi \u00e8 qui una profonda lezione sulla bellezza non solo degli edifici ma delle istituzioni dell\u2019Europa cristiana, costruite nei secoli dall\u2019incontro fra fede e ragione, distinte ma armonicamente vicine, che diventa incontro \u2014 non fusione, e tanto meno confusione \u2014 della Cattedrale e del Palazzo o, come si sarebbe detto in altra epoca e in altro linguaggio, dell\u2019altare e del trono.<\/p>\n<p style=\"text-align: justify;\">La bellezza della Cristianit\u00e0 \u2014 la bellezza delle cattedrali e dei castelli \u2014 rifulge, a vent\u2019anni dalla fine dell\u2019impero comunista sovietico nel 1989, sulle sinistre rovine del comunismo, esito ultimo della sanguinosa volgarit\u00e0 del moderno. \u00c8 una riflessione che il Papa ci ha voluto proporre da Praga. \u00c8 anche il cuore di <em>Rivoluzione e Contro-Rivoluzione<\/em> che ancora batte per la Chiesa, per la Cristianit\u00e0 e per ogni militante contro-rivoluzionario disposto a combattere la buona, la vera, la bella battaglia sotto la bandiera di Cristo Re e di Maria Regina. per la maggior gloria di Dio anche sociale.<\/p>\n<p style=\"text-align: justify;\"><strong>Note<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[1]<\/strong> Benedetto XVI, <em>Incontro con gli artisti nella Cappella Sistina<\/em>, del 21-11-2009.<\/p>\n<p style=\"text-align: justify;\"><strong>[2]<\/strong> Cfr. Plinio Corr\u00eaa de Oliveira, <em>Rivoluzione e Contro-Rivoluzione. Edizione del cinquantenario (1959-2009) con materiali della \u00abfabbrica\u00bb del testo e documenti integrativi<\/em>, a cura di Giovanni Cantoni, Sugarco, Milano 2009.<\/p>\n<p style=\"text-align: justify;\"><strong>[3]<\/strong> Il dibattito sul tema, per quanto riguarda la conversione religiosa, inizia con un articolo del 1965 che suscita un vasto dibattito: John Lofland &#8211; Rodney Stark, <em>Becoming a World-Saver. <\/em><em>A Theory of Conversion to a Deviant Perspective<\/em>, in <em>American Sociological Review<\/em>, vol. 30, 1965, pp. 862-875.<\/p>\n<p style=\"text-align: justify;\"><strong>[4]<\/strong> Marco Tangheroni, <em>Della storia. In margine ad aforismi di Nicol\u00e1s Gomez D\u00e1vila<\/em>, Sugarco, Milano 2008, p. 88.<\/p>\n<p style=\"text-align: justify;\"><strong>[5]<\/strong> Cfr. Enrico di Robilant, <em>Scelte e figure nelle teorie<\/em>, in Giorgio Derossi &#8211; Marco M. Olivetti &#8211; Andrea Poma &#8211; Giuseppe Riconda (a cura di), <em>Trascendenza Trascendentale Esperienza. Studi in onore di Vittorio Mathieu<\/em>, CEDAM, Padova 1995, pp. 543-552.<\/p>\n<p style=\"text-align: justify;\"><strong>[6]<\/strong> Cfr. Randall Collins, <em>The Sociology of Philosophies. A Global Theory of Intellectual Change<\/em>, The Belknap Press of Harvard University Press, Cambridge (Massachusetts) &#8211; Londra 2002.<\/p>\n<p style=\"text-align: justify;\"><strong>[7]<\/strong> Cfr. per esempio Richard H. Brown &#8211; Stanford M. Lyman (a cura di),<em> Structure, Consciousness, and History<\/em>, Cambridge University Press, Cambridge 1978.<\/p>\n<p style=\"text-align: justify;\"><strong>[8]<\/strong> Cfr. R. Collins, <em>Interaction Ritual Chains<\/em>, Princeton University Press, Princeton 2004.<\/p>\n<p style=\"text-align: justify;\"><strong>[9]<\/strong> Sulla I, II e III Rivoluzione cfr. P. Corr\u00eaa de Oliveira, <em>op. cit<\/em>., pp. 46-51.<\/p>\n<p style=\"text-align: justify;\"><strong>[10]<\/strong> Cfr. <em>ibid<\/em>., pp. 177-185.<\/p>\n<p style=\"text-align: justify;\"><strong>[11]<\/strong> <strong>Pio XII, <\/strong><em>Discorso \u00abNel contemplare\u00bb agli uomini di Azione Cattolica d\u2019Italia<\/em>, del 12-10-1952, in <em>Discorsi e Radiomessaggi di Sua Santit\u00e0 Pio XII,<\/em> vol. XIV, pp. 353-362.<\/p>\n<p style=\"text-align: justify;\"><strong>[12]<\/strong> Benedetto XVI, <em>Discorso ai rappresentanti della scienza<\/em>, Aula Magna dell\u2019Universit\u00e0 di Regensburg [Ratisbona], del 12-9-2006, in <em>Insegnamenti di Benedetto XVI<\/em>, vol. II, 2, Libreria Editrice Vaticana, Citt\u00e0 del Vaticano 2007, pp. 257-267 [testo tedesco; traduzione italiana disponibile sul sito Internet della Santa Sede all\u2019indirizzo abbreviato www.tinyurl.com\/hmq6w].<\/p>\n<p style=\"text-align: justify;\"><strong>[13]<\/strong> Cfr. Idem, <em>Lettera enciclica <\/em>Spe salvi<em> sulla speranza cristiana<\/em>, del 30-11-2007.<\/p>\n<p style=\"text-align: justify;\"><strong>[14]<\/strong> Pontificio Consiglio per la Cultura, <em>La<\/em> Via pulchritudinis<em>, Cammino privilegiato di evangelizzazione e di dialogo<\/em>, documento finale dell\u2019Assemblea Plenaria del 27-28 marzo 2006, disponibile sul sito Internet della Santa Sede all\u2019indirizzo abbreviato http:\/\/tinyurl.com\/yfzf6xl, II.3, che cita <em>\u00ab<\/em>Lezione per il Premio Nobel<em>, in<\/em> Opere<em>, t. IX, YMCA Press, Vermont-Paris 1981, p. 9\u00bb<\/em> (<em>ibid.<\/em>, nota 13: il titolo \u00e8 citato in italiano ma si tratta evidentemente di traduzione dall\u2019inglese).<\/p>\n<p style=\"text-align: justify;\"><strong>[15]<\/strong> Pontificio Consiglio per la Cultura, <em>op. cit<\/em>., II.3, che cita Hans Urs von Balthasar,<em> Gloria. I. Gli aspetti estetici della Rivelazione<\/em>, trad. it., Jaca Book, Milano 1975, pp. 10-11.<\/p>\n<p style=\"text-align: justify;\"><strong>[16]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[17]<\/strong> Cfr. <em>supra<\/em>, nota 14.<\/p>\n<p style=\"text-align: justify;\"><strong>[18]<\/strong> Cfr. Giovanni Paolo II, <em>Lettera enciclica<\/em> Veritatis Splendor <em>circa alcune questioni fondamentali dell\u2019insegnamento morale della Chiesa<\/em>, del 6-8-1993.<\/p>\n<p style=\"text-align: justify;\"><strong>[19]<\/strong> Pontificio Consiglio per la Cultura, <em>op. cit<\/em>., II, 2.<\/p>\n<p style=\"text-align: justify;\"><strong>[20]<\/strong> Benedetto XVI, <em>Incontro con gli artisti nella Cappella Sistina<\/em>, cit.<\/p>\n<p style=\"text-align: justify;\"><strong>[21]<\/strong> Amina Di Munno, <em>Letteratura e arti visive nel modernismo luso-brasiliano<\/em>, in Antonella Cancellier &#8211; Renata Londero (a cura di), <em>Atti del XIX convegno AISPI <\/em>[Associazione Ispanisti Italiani]<em>, Roma, (16-18 settembre 1999)<\/em>, Unipress, Padova, 2001, pp. 267-274 (p. 271).<\/p>\n<p style=\"text-align: justify;\"><strong>[22]<\/strong> <em>Ibid<\/em>., p. 272.<\/p>\n<p style=\"text-align: justify;\"><strong>[23]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[24]<\/strong> Nota l\u2019importanza del mito tribalista e indio nella costruzione dell\u2019ideologia delle \u00abcamicie verdi\u00bb Jo\u00e3o Alfredo de Sousa Montenegro, <em>O Integralismo no Cear\u00e1. Varia\u00e7\u00f5es Ideol\u00f3gicas<\/em>, Secretaria de Cultura e Desporto, Fortaleza 1986. Sui \u00abriti\u00bb e simboli dell\u2019Integralismo cfr. pure H\u00e9lgio Trindade, <em>Integralismo (O fascismo brasileiro na d\u00e9cada de 30)<\/em>, Difus\u00e3o Europ\u00e9ia do Livro, San Paolo 1974; e Rosa Maria Feiteiro Cavalari, <em>Integralismo. Ideologia e organiza\u00e7\u00e3o de um partido de massa no Brasil (1932-1937)<\/em>, EDUSC, Bauru (San Paolo) 1999.<\/p>\n<p style=\"text-align: justify;\"><strong>[25]<\/strong> Nel 1937 Corr\u00eaa de Oliveira scrive un ampio <em>Relatorio Imparcial ao Episcopato Brasileiro<\/em> contro l\u2019integralismo (rimasto inedito, del cui dattiloscritto la mia collezione conserva una copia), da cui mons. Gast\u00e3o Liberal Pinto (1884-1945), vescovo di S\u00e3o Carlos, nello Stato di San Paolo, ricava \u2014 trascrivendone integralmente numerosi paragrafi e riassumendone altri \u2014 una <em>Carta de Dom Gast\u00e3o Liberal Pinto aos Bispos do Brasil sobre o Integrismo<\/em>, del 26 agosto 1937, inviata a tutti i confratelli vescovi brasiliani ma rimasta anch\u2019essa inedita fino alla pubblicazione nel 1984 sul <em>Boletim do CEPEHIB (Centro de Pesquisas e Estudios de Historia da Igreja no Brasil)<\/em>, anno VI, n. 3 (22), luglio 1984, pp. 3-9.<\/p>\n<p style=\"text-align: justify;\"><strong>[26]<\/strong> Su queste vicende cfr. il mio <em>Una battaglia nella notte. Plinio Corr\u00eaa de Oliveira e la crisi del secolo XX nella Chiesa<\/em>, Sugarco, Milano 2008, pp. 57-60.<\/p>\n<p style=\"text-align: justify;\"><strong>[27]<\/strong> L\u2019allusione al presidente della Camera dei Deputati, on. Gianfranco Fini, <em>non <\/em>\u00e8 casuale.<\/p>\n<p style=\"text-align: justify;\"><strong>[28]<\/strong> Cfr., in particolare, Michael L. Conniff, <em>Urban Politics in Brazil. <\/em><em>The Rise of Populism, 1925-1945<\/em>, University of Pittsburgh Press, Pittsburgh 1981; Idem (a cura di), <em>Latin American Populism in Comparative Perspective<\/em>, University of New Mexico Press, Albuquerque (New Mexico) 1982; Idem (a cura di), <em>Populism in Latin America<\/em>, University of Alabama Press, Tuscaloosa (Alabama) 1999.<\/p>\n<p style=\"text-align: justify;\"><strong>[29]<\/strong> Cfr. sul punto Pierre-Andr\u00e9 Taguieff, <em>L\u2019Illusion populiste. <\/em><em>Essai sur les d\u00e9magogies de l\u2019\u00e2ge d\u00e9mocratique<\/em>, Flammarion, Parigi 2007<sup>2<\/sup>.<\/p>\n<p style=\"text-align: justify;\"><strong>[30]<\/strong> Cfr., con riferimento specifico ai rapporti con le religioni, Robert S. Ellwood, <em>The Fifties Spiritual Marketplace. <\/em><em>American Religion in a Decade of Conflict<\/em>, Rutgers University Press, New Brunswick (New Jersey) 1997.<\/p>\n<p style=\"text-align: justify;\"><strong>[31]<\/strong> Ripubblicato da Alleanza Cattolica nel 1991: Pio XII, <em>I sommi postulati morali di un retto e sano ordinamento democratico. Radiomessaggio natalizio \u00abBenignitas et humanitas\u00bb, del 24-12-1944<\/em>, Cristianit\u00e0, Piacenza 1991.<\/p>\n<p style=\"text-align: justify;\"><strong>[32]<\/strong> <em>Ibid<\/em>., p. 11.<\/p>\n<p style=\"text-align: justify;\"><strong>[33]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[34]<\/strong> Le allocuzioni sono raccolte e commentate in P. Corr\u00eaa de Oliveira, <em>Nobilt\u00e0 ed \u00e9lites tradizionali analoghe nelle allocuzioni di Pio XII al patriziato e alla nobilt\u00e0 romana<\/em>, trad. it., Marzorati, Milano 1993.<\/p>\n<p style=\"text-align: justify;\"><strong>[35]<\/strong> Cos\u00ec Rodrigo Coppe Caldeira, <em>O influxo ultramontano no Brasil. O pensamento de Pl\u00ednio Corr\u00eaa de Oliveira<\/em>, tesi di laurea in Scienze Religiose, Universidade Federal de Juiz de Fora, Juiz de Fora (Minas Gerais) 2005, p. 78.<\/p>\n<p style=\"text-align: justify;\"><strong>[36]<\/strong> Cfr. il mio <em>Come i progressisti \u00abnon\u00bb vinsero al Concilio Ecumenico Vaticano II. Una recensione di \u00abRoma, due del mattino\u00bb di mons. H\u00e9lder C\u00e2mara<\/em>, in <em>Cristianit\u00e0. Organo ufficiale di Alleanza Cattolica<\/em>, anno XXXVI, n. 346, marzo-aprile 2008, pp. 3-8.<\/p>\n<p style=\"text-align: justify;\"><strong>[37]<\/strong> P. Corr\u00eaa de Oliveira, <em>Autoritratto filosofico<\/em>, in Idem, <em>Rivoluzione e Contro-Rivoluzione. Edizione del cinquantenario (1959-2009) con materiali della \u00abfabbrica\u00bb del testo e documenti integrativi<\/em>, cit., pp. 365-426 (p. 385).<\/p>\n<p style=\"text-align: justify;\"><strong>[38]<\/strong> Caio Vidigal Xavier da Silveira, <em>Como nasceu a providential obra<\/em> Revolu\u00e7\u00e3o e Contra-Revolu\u00e7\u00e3o, in <em>Catolicismo<\/em>, anno LIX, n. 706, ottobre 2009, pp. 26-34 (p. 32). Una traduzione italiana, con lievi modifiche, \u00e8 stata pubblicata su <em>Tradizione Famiglia Propriet\u00e0<\/em>, anno 15, n. 3, ottobre 2009, pp. 14-19 con il titolo <em>Come nacque<\/em> Rivoluzione e Contro-Rivoluzione.<\/p>\n<p style=\"text-align: justify;\"><strong>[39]<\/strong> <em>Ibid.<\/em>, p. 33.<\/p>\n<p style=\"text-align: justify;\"><strong>[40]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[41]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[42]<\/strong> Saranno rielaborati e raccolti pi\u00f9 tardi nell\u2019ultima opera dell\u2019autore: P. Corr\u00eaa de Oliveira, <em>Nobilt\u00e0 ed \u00e9lites tradizionali analoghe nelle allocuzioni di Pio XII al patriziato e alla nobilt\u00e0 romana<\/em>, cit.<\/p>\n<p style=\"text-align: justify;\"><strong>[43]<\/strong> Cfr. Don Pedro Henrique di Orl\u00e9ans e Bragan\u00e7a, <em>Pr\u00e9fac<\/em>e a Plinio Corr\u00eaa de Oliveira, <em>R\u00e9volution et Contre-R\u00e9volution<\/em>, trad. francese, \u00c9ditions <em>Catolicismo<\/em>, Campos (Rio de Janeiro) 1960, pp. 11-15.<\/p>\n<p style=\"text-align: justify;\"><strong>[44]<\/strong> Cfr. Don Pedro Henrique di Orl\u00e9ans e Bragan\u00e7a, <em>Pr\u00e9fac<\/em>e, in P. Corr\u00eaa de Oliveira, <em>Rivoluzione e Contro-Rivoluzione. Edizione del cinquantenario (1959-2009) con materiali della \u00abfabbrica\u00bb del testo e documenti integrativi<\/em>, cit., pp. 433-437.<\/p>\n<p style=\"text-align: justify;\"><strong>[45]<\/strong> Paul Bourget, <em>Il demone meridiano<\/em>, trad. it., Salani, Firenze 1956, p. 395.<\/p>\n<p style=\"text-align: justify;\"><strong>[46]<\/strong> Cfr. per esempio Benedetto XVI, Lettera enciclica <em>Spe salvi<\/em>, cit., n. 42.<\/p>\n<p style=\"text-align: justify;\"><strong>[47]<\/strong> Lo studio monumentale della transizione brasiliana dalla monarchia alla repubblica di Gilberto Freyre, <em>Ordem e progresso. Processo de desintegra\u00e7\u00e3o das sociedades patriarcal e semipatriarcal no Brasil sob o regime de trabalho livre. Aspectos de um quase meio s\u00e9culo de transi\u00e7\u00e3o do trabalho escravo para o trabalho livre; e da monarquia para a rep\u00fablica<\/em>, Jos\u00e9 Olympio, Rio de Janeiro 1957, esempio tipico del metodo del sociologo brasiliano che d\u00e0 rilievo agli elementi culturali e di ambiente, e non solo a quelli economici, per spiegare i processi sociali, precede di soli due anni <em>Rivoluzione e Contro-Rivoluzione.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[48]<\/strong> Cfr. il mio <em>Brainwashing the Working Class: Vampire Comics and Criticism from Dr. Occult to Buffy<\/em>, in <em>Slayage<\/em>, n. 7, dicembre 2002. La rivista \u00e8 disponibile esclusivamente <em>online<\/em>: l\u2019articolo citato si trova all\u2019indirizzo http:\/\/slayageonline.com\/essays\/slayage7\/Introvigne.htm.<\/p>\n<p style=\"text-align: justify;\"><strong>[49]<\/strong> P.Corr\u00eaa de Oliveira, <em>Note sul concetto di Cristianit\u00e0. Carattere spirituale e sacrale della societ\u00e0 temporale e sua \u00abministerialit\u00e0\u00bb<\/em>, ed. it. a cura di G. Cantoni, Thule, Palermo 1998; ora in <em>Rivoluzione e Contro-Rivoluzione. Edizione del cinquantenario (1959-2009) con materiali della \u00abfabbrica\u00bb del testo e documenti integrativi<\/em>, cit., pp. 219-242.<\/p>\n<p style=\"text-align: justify;\"><strong>[50]<\/strong> <em>Ibid.<\/em>, p. 232.<\/p>\n<p style=\"text-align: justify;\"><strong>[51]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[52]<\/strong> <em>Ibid.<\/em>, p. 233.<\/p>\n<p style=\"text-align: justify;\"><strong>[53]<\/strong> G. Cantoni, <em>Il contributo di Plinio Corr\u00eaa de Oliveira e di \u00abRivoluzione e Contro-Rivoluzione\u00bb allo sviluppo del pensiero e dell\u2019azione contro-rivoluzionari<\/em>, in <em>Cristianit\u00e0. Organo ufficiale di Alleanza Cattolica<\/em>, anno XXXIII, n. 330-331, luglio-ottobre 2005, pp. 33-45, oggi in Idem, <em>Per una civilt\u00e0 cristiana nel terzo millennio. La coscienza della Magna Europa e il quinto viaggio di Colombo, <\/em>Sugarco, Milano 2008, pp. 221-248 (p. 237).<\/p>\n<p style=\"text-align: justify;\"><strong>[54]<\/strong> Cfr. C. Vidigal Xavier da Silveira, <em>op. cit.<\/em>, p. 30.<\/p>\n<p style=\"text-align: justify;\"><strong>[55]<\/strong> Cfr. P. Corr\u00eaa de Oliveira, <em>Huysmans \u2014 I<\/em>, in <em>O Legion\u00e1rio<\/em>, n. 93, 31 gennaio 1932, p. 1; Idem, <em>Huysmans \u2014 II<\/em>, in <em>O Legion\u00e1rio<\/em>, n. 94, 21 febbraio 1932, p. 2.<\/p>\n<p style=\"text-align: justify;\"><strong>[56]<\/strong> Cfr. sul punto il mio <em>I satanisti. Storia, miti e riti del satanismo<\/em>, Sugarco, Milano 2010.<\/p>\n<p style=\"text-align: justify;\"><strong>[57]<\/strong> Cfr. C. Vidigal Xavier da Silveira, <em>op. cit.<\/em>, p. 30.<\/p>\n<p style=\"text-align: justify;\"><strong>[58]<\/strong> Cfr. pure la raccolta postuma di testi sul tema di Corr\u00eaa de Oliveira di Paulo Corr\u00eaa de Brito Filho &#8211; L. Nino Daniele &#8211; Antonio Augusto Borelli Machado &#8211; Jos\u00e9 Antonio Ureta (a cura di), <em>A Inoc\u00eancia Primeva e a contempla\u00e7ao sacral do Universo no pensamento de Plinio Corr\u00eaa de Oliveira<\/em>, Instituto Plinio Corr\u00eaa de Oliveira, San Paolo 2008; cfr. la mia presentazione di questo testo, <em>\u00abVia pulchritudinis\u00bb e spiritualit\u00e0 della Contro-Rivoluzione. Una nuova raccolta di testi di Plinio Corr\u00eaa de Oliveira<\/em>, in <em>Cristianit\u00e0. Organo ufficiale di Alleanza Cattolica<\/em>, anno XXXVII, n. 351, gennaio-marzo 2009, pp. 23-38.<\/p>\n<p style=\"text-align: justify;\"><strong>[59]<\/strong> Benedetto XVI, <em>La Cattedrale dall\u2019architettura romanica a quella gotica, il retroterra teologico<\/em>, <em>Udienza Generale<\/em>, del 18-11-2009.<\/p>\n<p style=\"text-align: justify;\"><strong>[60]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[61]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[62]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[63]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[64]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[65]<\/strong> <em>Ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[66]<\/strong> Idem, <em>Udienza generale sul<\/em> <em>Viaggio Apostolico nella Repubblica Ceca<\/em>, del 30-9-2009.<\/p>\n<p style=\"text-align: justify;\"><strong>[67]<\/strong> Idem, <em>Incontro con le Autorit\u00e0 Politiche e Civili e con il Corpo Diplomatico<\/em>, Palazzo Presidenziale di Praga, 26-9-2009.<\/p>\n<p style=\"text-align: justify;\"><strong>[68]<\/strong> Idem, <em>Udienza generale sul<\/em> <em>Viaggio Apostolico nella Repubblica Ceca<\/em>, del 30-9-2009, cit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 21 novembre 2009, all\u2019Augustinianum &#8211; a pochi passi dal Vaticano &#8211; , si sono incontrati tutti gli esponenti, italiani e non, di Alleanza Cattolica e di Tradizione Famiglia Propriet\u00e0 (TFP). L&#8217;occasione dell&#8217;incontro \u00e8 stato l&#8217;anniversario del cinquantenario dell\u2019uscita della principale opera di Plinio Correa de Oliveira, \u201cRivoluzione e Contro-Rivoluzione\u201d . Proponiamo di seguito la &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29633,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[462,386],"class_list":["post-3585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rivoluzione-e-controrivoluzione","tag-controrivoluzione","tag-rivoluzione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959. - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959. - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-12-02T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-22T13:08:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/Plinio_Correa_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"186\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"38 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959.\",\"datePublished\":\"2009-12-02T23:00:00+00:00\",\"dateModified\":\"2016-01-22T13:08:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/\"},\"wordCount\":7665,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/Plinio_Correa_cover.jpg\",\"keywords\":[\"controrivoluzione\",\"Rivoluzione\"],\"articleSection\":[\"Rivoluzione e controrivoluzione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/\",\"name\":\"Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959. - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/Plinio_Correa_cover.jpg\",\"datePublished\":\"2009-12-02T23:00:00+00:00\",\"dateModified\":\"2016-01-22T13:08:32+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/Plinio_Correa_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/Plinio_Correa_cover.jpg\",\"width\":186,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959. - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/","og_locale":"it_IT","og_type":"article","og_title":"Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959. - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-12-02T23:00:00+00:00","article_modified_time":"2016-01-22T13:08:32+00:00","og_image":[{"width":186,"height":270,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/Plinio_Correa_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"38 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959.","datePublished":"2009-12-02T23:00:00+00:00","dateModified":"2016-01-22T13:08:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/"},"wordCount":7665,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/Plinio_Correa_cover.jpg","keywords":["controrivoluzione","Rivoluzione"],"articleSection":["Rivoluzione e controrivoluzione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/","name":"Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959. - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/Plinio_Correa_cover.jpg","datePublished":"2009-12-02T23:00:00+00:00","dateModified":"2016-01-22T13:08:32+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/Plinio_Correa_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/12\/Plinio_Correa_cover.jpg","width":186,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/rivoluzione-e-contro-rivoluzione-nel-contesto-brasiliano-del-1959\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Rivoluzione e Contro-Rivoluzione nel contesto brasiliano del 1959."}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3585"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3585\/revisions"}],"predecessor-version":[{"id":29634,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3585\/revisions\/29634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29633"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}