{"id":35730,"date":"2016-07-14T00:00:22","date_gmt":"2016-07-13T22:00:22","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=35730"},"modified":"2016-07-06T10:39:44","modified_gmt":"2016-07-06T08:39:44","slug":"tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/","title":{"rendered":"Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-35731\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/07\/Hobbyt_party.jpg\" alt=\"Hobbyt_party\" width=\"147\" height=\"200\" \/>La Croce quotidiano<\/strong> 6 luglio 2016<\/p>\n<p style=\"text-align: justify;\"><em>\u00c8 <\/em><em>uscito per i tipi D\u2019Ettoris \u201c<\/em><em>Hobbit Party\u201d, un <\/em><em>libro per <\/em><em>rendere gli uomini \u00abpi\u00f9 consapevoli del monito biblico: la nostra battaglia non \u00e8 solo contro la carne e il sangue, ma anche contro Principati e Potenze (Ef 6,12). Prefazione di James V. Schall, S.J.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Giuseppe Brienza<\/strong><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Ogni uomo, nella sua esperienza pi\u00f9 intima, \u00e8 alla ricerca nelle modalit\u00e0 pi\u00f9 varie per riconoscere e rendere culto a Dio o, in altre parole, per gioire dell\u2019ideale e della bellezza della realt\u00e0 che lo circonda. Lo scrittore, filologo, e linguista britannico John Ronald Reuel Tolkien (1892-1973), in tutte le sue opere, ha narrativamente espresso nel modo pi\u00f9 efficace, con parole di epica e immagini e personaggi insuperati, questo concetto che, essenzialmente, riguarda il tentativo di ciascun essere creato di raggiungere la verit\u00e0 e, con essa, la gioia e la realizzazione di s\u00e9.<\/p>\n<p style=\"text-align: justify;\">Il costante tentativo della persona umano, che \u00e8 \u201canimale sociale\u201d come insegna la filosofia greca, di trovare un rapporto autentico con la natura e le \u201ccose pi\u00f9 alte\u201d, sfocia anche nella vita comunitaria e nella politica, quando essa naturalmente \u00e8 guidata dalla ragione e dal diritto naturale, non certo quando mira a sostituire o trovare in s\u00e9 un\u2019alternativa a Dio.<\/p>\n<p style=\"text-align: justify;\">L\u2019analisi tolkeniana del rapporto fra verit\u00e0, bellezza e politica \u00e8 svolta nell\u2019ultimo libro uscito sul grande scrittore nel nostro Paese, scritto da due studiosi americani, Jonathan Witt e Jay W. Richards, e intitolato \u201cHobbit Party. Tolkien e la visione della libert\u00e0 che l&#8217;Occidente ha dimenticato\u201d (a cura di Maurizio Brunetti, D\u2019Ettoris Editori, pp. 352, \u20ac. 23,90).<\/p>\n<p style=\"text-align: justify;\">Gi\u00e0 il titolo di questo volume, rileva James V. Schall, S. J. nella \u201cPrefazione\u201d (pp. 9-13), meriterebbe un commento. Il gesuita statunitense, che \u00e8 un tolkeniano convinto anche se un po&#8217; \u201ctardivo\u201d (ne ha scoperto le opere solo a sessant\u2019anni), ha sempre sostenuto infatti che la filosofia, e in particolare la filosofia politica, pu\u00f2 arrivare alla verit\u00e0 solo se si apre alle verit\u00e0 della Rivelazione offerte dalla teologia. E allora leggere Tolkien permette egregiamente di rendere gli uomini \u00ab<em>pi\u00f9 consapevoli del monito biblico:<\/em> la nostra battaglia non \u00e8 solo contro la carne e il sangue, ma anche contro Principati e Potenze<em> (Ef 6,12). Il padre della menzogna si sente a casa in un mondo in cui mentiamo a noi stessi sulla natura delle cose per continuare a fare quello che vogliamo<\/em>\u00bb (p. 10).<\/p>\n<p style=\"text-align: justify;\">Padre Schall, che \u00e8 professore emerito presso il Dipartimento di Diritto Pubblico della Georgetown University, addita sulla stessa scia di Witt e Richards nella \u201cvisione del mondo\u201d di Tolkien un modo coerente di risposta ai doni divini della ragione e della volont\u00e0. \u00ab<em>Un mondo del genere<\/em> \u2013 annota il gesuita &#8211; <em>non esclude la tragedia e la sofferenza, anche degli innocenti. Le sue radici, nondimeno, rimangono ben piantate nella gioia, che \u00e8 l\u2019esito finale della scelta del bene, anche se, nel medio termine, tale scelta pu\u00f2 implicare sofferenze<\/em>\u00bb (p. 13).<\/p>\n<p style=\"text-align: justify;\">Il titolo \u201cHobbit Party\u201d, quindi potrebbe far pensare a giusto titolo ad un movimento ideale, di azione civica anche se non un vero e proprio partito politico. Distributisti, ecologisti, reazionari, anti-moderni, e persino marxisti e atei, alla stregua dei cattolici e di altri credenti e pensatori, hanno provato ad arruolare Tolkien per la propria causa. Le vicende che leggiamo nei suoi libri narrano in effetti di viaggi e di lotte, di lunghe marce verso l\u2019Alba e della scelta del Bene.<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Se molto \u00e8 stato scritto sul rilievo religioso de \u201cIl Signore degli Anelli\u201d<\/em>\u00bb, attesta lo studioso Joseph Pearce nel suo\u00a0\u201cCatholic Literary Giants\u201d, \u00ab<em>meno \u00e8 stato pubblicato su quello politico, e quel poco che c\u2019\u00e8 spesso \u00e8 erroneo nelle conclusioni e all\u2019oscuro circa le finalit\u00e0 che Tolkien si prefiggeva<\/em>\u00bb. Jonathan Witt e Jay W. Richards hanno provato con \u201cHobbit Party\u201d a colmare questa lacuna. Entrambi texani, sono uomini di cultura a tutto tondo. Witt, docente di letteratura inglese e attivo nel campo del giornalismo oltre che sceneggiatore di documentari, \u00e8 attualmente caporedattore dell\u2019agenzia di stampa online \u201cThe Stream\u201d. Richards, invece, insegna presso la \u201cSchool of Business and Economics\u201d della Catholic University of America, a Washington D.C., ed \u00e8 Senior Fellow presso il \u201cDiscovery Institute\u201d.<\/p>\n<p style=\"text-align: justify;\">In un tempo in cui molti sono preoccupati che l\u2019Occidente stia scivolando verso una bancarotta non solo economica, ma anche morale e politica, entrambi gli autori cercano di dimostrare come Tolkien \u2013 che si descriveva come uno Hobbit\u00a0\u00abin tutto tranne che nella statura\u00bb\u00a0\u2013 abbia tracciato, con le sue amate storie della Terra di Mezzo, una mappa verso la libert\u00e0. A tal fine attingono alla loro combinata esperienza in letteratura, scienze politiche, economia, filosofia e teologia per descrivere la visione tolkieniana dell\u2019uomo, creato appunto per la libert\u00e0, eppure sviabile cos\u00ec tanto facilmente dalla brama di potere.<\/p>\n<p style=\"text-align: justify;\">L\u2019universo fantastico de \u201cIl Signore degli Anelli\u201d, del resto, non \u00e8 stato creato da Tolkien per fornire ai suoi lettori una via di fuga dalla realt\u00e0. Del nostro mondo, la Terra di Mezzo \u00e8 piuttosto un ritratto impressionista. Uomini, Elfi, Nani e Hobbit diventano l\u2019occasione narrativa per mettere a fuoco alcuni dei grandi temi del nostro tempo: i limiti dello Stato; il valore della propriet\u00e0 privata; il libero arbitrio e la tentazione del potere; la dottrina della guerra giusta; l\u2019ecologia; l\u2019amore e la morte.<\/p>\n<p style=\"text-align: justify;\">\u201cHobbit Party\u201d \u00e8 il nome della festa che celebra le virt\u00f9 di Frodo e della Contea: la nobilt\u00e0 d\u2019animo, la verit\u00e0 e la bellezza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Croce quotidiano 6 luglio 2016 \u00c8 uscito per i tipi D\u2019Ettoris \u201cHobbit Party\u201d, un libro per rendere gli uomini \u00abpi\u00f9 consapevoli del monito biblico: la nostra battaglia non \u00e8 solo contro la carne e il sangue, ma anche contro Principati e Potenze (Ef 6,12). Prefazione di James V. Schall, S.J. di Giuseppe Brienza<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":35731,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[645],"class_list":["post-35730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri","tag-j-r-r-tolkien","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-13T22:00:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/07\/Hobbyt_party.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"192\" \/>\n\t<meta property=\"og:image:height\" content=\"262\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato\",\"datePublished\":\"2016-07-13T22:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/\"},\"wordCount\":897,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Hobbyt_party.jpg\",\"keywords\":[\"J.R.R.Tolkien\"],\"articleSection\":[\"Libri\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/\",\"name\":\"Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Hobbyt_party.jpg\",\"datePublished\":\"2016-07-13T22:00:22+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Hobbyt_party.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/Hobbyt_party.jpg\",\"width\":192,\"height\":262},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/","og_locale":"it_IT","og_type":"article","og_title":"Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2016-07-13T22:00:22+00:00","og_image":[{"width":192,"height":262,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/07\/Hobbyt_party.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato","datePublished":"2016-07-13T22:00:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/"},"wordCount":897,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/07\/Hobbyt_party.jpg","keywords":["J.R.R.Tolkien"],"articleSection":["Libri"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/","name":"Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/07\/Hobbyt_party.jpg","datePublished":"2016-07-13T22:00:22+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/07\/Hobbyt_party.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/07\/Hobbyt_party.jpg","width":192,"height":262},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tolkien-e-la-visione-della-liberta-che-loccidente-ha-dimenticato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Tolkien e la visione della libert\u00e0 che l\u2019Occidente ha dimenticato"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=35730"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35730\/revisions"}],"predecessor-version":[{"id":35732,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35730\/revisions\/35732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/35731"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=35730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=35730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=35730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}