{"id":3572,"date":"2009-11-26T00:00:00","date_gmt":"2009-11-25T23:00:00","guid":{"rendered":""},"modified":"2016-07-20T17:26:54","modified_gmt":"2016-07-20T15:26:54","slug":"del-noce-il-liberale-solitario","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/","title":{"rendered":"Del Noce il liberale solitario"},"content":{"rendered":"<div style=\"text-align: center;\">\n<div id=\"attachment_36123\" style=\"width: 145px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36123\" class=\"wp-image-36123\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/11\/Del-Noce.jpg\" alt=\"Del Noce\" width=\"145\" height=\"200\" \/><p id=\"caption-attachment-36123\" class=\"wp-caption-text\">Augusto Del Noce<\/p><\/div>\n<p><strong>Avvenire.it<\/strong> 19 Novembre 2009<\/div>\n<p style=\"text-align: center;\">di <strong>Giovanni Tassani<\/strong><\/p>\n<p style=\"text-align: justify;\">Nell&#8217;Italia del dopoguerra con le famiglie politiche rinasce la volont\u00e0 di accompagnare culturalmente lo sviluppo della democrazia. I giovani si organizzano per vivere l\u2019esperienza della libert\u00e0 sia pur in uno scenario di recente distruzione e dolore. Si \u00e8 potuto parlare di una \u00abet\u00e0 delle autonomie giovanili\u00bb nei campi della scuola, dell\u2019universit\u00e0, del lavoro.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">I \u00abgruppi giovanili\u00bb della Dc saranno un esempio traente di tale attitudine: essi si consideravano la \u00abterza generazione\u00bb presente sulla scena politica, dopo la prima, formatasi nel pre-fascismo, e la seconda, cresciuta nel Ventennio, senza esperienza di libert\u00e0.<\/div>\n<p style=\"text-align: justify;\">Augusto Del Noce, gi\u00e0 adulto all\u2019epoca, pu\u00f2 essere considerato un influente su questa generazione, proiettata a vivere il futuro italiano. Il suo pensiero scorre in parallelo, e alternativo, a quello di due amici cattolici schieratisi a sinistra: Felice Balbo e Franco Rodano.<\/p>\n<p style=\"text-align: justify;\">Per Del Noce, studioso precoce del marxismo, questo \u00e8 incompatibile con il principio di libert\u00e0; per Balbo va relativizzato e usato laicamente come mezzo per dirimere le questioni sociali; per Rodano va mantenuta una fedelt\u00e0 ai lavoratori organizzati, tentando di disinnescare il meccanismo ideologico dall\u2019interno del Pci.<\/p>\n<p style=\"text-align: justify;\">Quando Dossetti, che aveva suscitato le speranze dei giovani Dc in un grande cambiamento, nel \u201951 rinuncia alla politica, Balbo, a sua volta uscito dal Pci, svolge un\u2019opera maieutica su quegli stessi giovani, trattenendoli dal disimpegno e tentando di affrontare i temi della crisi che il mondo diviso in due dalla guerra fredda stava vivendo.<\/p>\n<p style=\"text-align: justify;\">Del Noce \u00e8 vicino a Balbo, e lavora su alcuni concetti chiave: totalitarismo, post-fascismo, risorgimento. Se nell\u2019Ottocento il contrasto era tra reazione e progresso, nel Novecento questo diviene per Del Noce contrasto tra totalitarismo e libert\u00e0. Una libert\u00e0 oltre Croce, non immanentista, altrimenti a rischio di divenire integralismo laicista, ma aperta alla trascendenza, contro un totalitarismo, di destra o di sinistra, che ingloba i valori e diviene controreligione, con la pretesa di esaurire la storia.<\/p>\n<p style=\"text-align: justify;\">A Bologna a pi\u00f9 riprese negli anni cinquanta, distaccato presso il Centro fondato da Dossetti, col quale per\u00f2, come prima di lui Balbo, non riesce a intendersi, Del Noce frequenta i giovani del Mulino, con i quali converge, tra \u201957 e \u201959, scrivendo saggi impegnativi sulla loro rivista. Anche loro si considerano \u00abterza generazione\u00bb sulla scena italiana e rifiutano massimalismo e neo-azionismo, per una linea realista, da Cavour a De Gasperi, diversa da una linea Gobetti-Gramsci, che sta invece divenendo dominante tra gli intellettuali italiani.<\/p>\n<p style=\"text-align: justify;\">Per Del Noce occorre proseguire De Gasperi, fortificando l\u2019intesa tra cattolici non integralisti, liberali non laicisti, socialisti non marxisti. Essere liberali, ossia non radicali. \u00c8 una necessaria revisione non solo politica, ma filosofica, un lavoro sui principi. Ma quando i giovani Dc, dopo anni di crisi che li ha visti opporsi o sfuggire al segretario Fanfani, chiamano Del Noce al loro convegno di studi al Sestri\u00e8re, agosto \u201957, la linea \u00e8 gi\u00e0 stata segnata, un mese prima a Vallombrosa, dallo stesso Fanfani: e non potr\u00e0 che sfociare a sinistra.<\/p>\n<p style=\"text-align: justify;\">Del Noce non sar\u00e0 capito; la \u00abterza generazione\u00bb Dc \u00e8 ormai divisa: o inserita nel partito adulto, senza pi\u00f9 problemi culturali, o, pur cresciuta in Universit\u00e0 Cattolica, con la corrente di sinistra di Base teorizza tesi laiche che si confondono con quelle neo-azioniste del Mondo o del Ponte, ben al di l\u00e0 della distinzione dei piani di Maritain, o infine, oltrepassando gli stessi intenti dell\u2019ispiratore Rodano, ha lasciato la Dc per il Pci.<\/p>\n<p style=\"text-align: justify;\">Del Noce incontra in questa fase Gianni Baget Bozzo, gi\u00e0 protagonista della \u00abterza generazione\u00bb, che ora anima una rivista critica dell\u2019apertura a sinistra, L\u2019Ordine Civile, e vi scriver\u00e0 alcuni saggi pregnanti, uno dei quali, Idee per l\u2019interpretazione del fascismo, sar\u00e0 all\u2019origine delle future revisioni storiografiche di De Felice e Nolte. Il fascismo \u00e8 fenomeno del passato: occorre essere obiettivamente post-fascisti (cio\u00e8 antifascisti, ma senza caricare ideologicamente sull\u2019oggi tale giudizio storico).<\/p>\n<p style=\"text-align: justify;\">Ma sono i tempi dell\u2019avvento di De Gaulle oltralpe e, in Italia, dell\u2019incidente Tambroni: e il \u00abmostro\u00bb fascista viene dato ancora per vivo. E si mobilitano le piazze, come a Genova. Ritorna l\u2019antitesi, per Del Noce ottocentesca, tra progresso e reazione, che consente di vedere nel mito fascista il nemico \u00abborghese\u00bb e nel comunismo invece una fase necessaria nella storia del progresso umano. La gran corsa degli anni sessanta sul piano inclinato a sinistra \u00e8 iniziata.<\/p>\n<p style=\"text-align: justify;\">Magistero sfortunato per Del Noce in anni in cui il senso della libert\u00e0 \u00e8 sottovalutato rispetto a quello di giustizia. Non a caso i liberali vengono isolati a destra, per volont\u00e0 dei loro concorrenti radical-repubblicani e socialisti ex azionisti. Se poi Del Noce, nel centenario dell\u2019Unit\u00e0 d\u2019Italia, prover\u00e0 a evocare la figura di Gioberti come filosofo politico della nazione atto a interpretare il risorgimento come \u00abrestaurazione creatrice\u00bb anzich\u00e9 \u00abrivoluzione\u00bb, pi\u00f9 o meno compiuta, trover\u00e0 solo critiche e dissensi.<\/p>\n<p style=\"text-align: justify;\">La \u00abterza generazione\u00bb, sensibile a questi temi di identit\u00e0 nazionale, si \u00e8 ormai scomposta o dissolta: una \u00abquarta generazione\u00bb non ci sar\u00e0, o almeno non riuscir\u00e0 a darsi forma e credibilit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avvenire.it 19 Novembre 2009 di Giovanni Tassani Nell&#8217;Italia del dopoguerra con le famiglie politiche rinasce la volont\u00e0 di accompagnare culturalmente lo sviluppo della democrazia. I giovani si organizzano per vivere l\u2019esperienza della libert\u00e0 sia pur in uno scenario di recente distruzione e dolore. Si \u00e8 potuto parlare di una \u00abet\u00e0 delle autonomie giovanili\u00bb nei campi &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":36123,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[1695],"class_list":["post-3572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personaggi","tag-augusto-del-noce","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Del Noce il liberale solitario - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Del Noce il liberale solitario - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-11-25T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T15:26:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/11\/Del-Noce.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"191\" \/>\n\t<meta property=\"og:image:height\" content=\"264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Del Noce il liberale solitario\",\"datePublished\":\"2009-11-25T23:00:00+00:00\",\"dateModified\":\"2016-07-20T15:26:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/\"},\"wordCount\":839,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/Del-Noce.jpg\",\"keywords\":[\"Augusto Del Noce\"],\"articleSection\":[\"Personaggi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/\",\"name\":\"Del Noce il liberale solitario - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/Del-Noce.jpg\",\"datePublished\":\"2009-11-25T23:00:00+00:00\",\"dateModified\":\"2016-07-20T15:26:54+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/Del-Noce.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/Del-Noce.jpg\",\"width\":191,\"height\":264},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/del-noce-il-liberale-solitario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Del Noce il liberale solitario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Del Noce il liberale solitario - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/","og_locale":"it_IT","og_type":"article","og_title":"Del Noce il liberale solitario - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-11-25T23:00:00+00:00","article_modified_time":"2016-07-20T15:26:54+00:00","og_image":[{"width":191,"height":264,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/11\/Del-Noce.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Del Noce il liberale solitario","datePublished":"2009-11-25T23:00:00+00:00","dateModified":"2016-07-20T15:26:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/"},"wordCount":839,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/11\/Del-Noce.jpg","keywords":["Augusto Del Noce"],"articleSection":["Personaggi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/","name":"Del Noce il liberale solitario - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/11\/Del-Noce.jpg","datePublished":"2009-11-25T23:00:00+00:00","dateModified":"2016-07-20T15:26:54+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/11\/Del-Noce.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/11\/Del-Noce.jpg","width":191,"height":264},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/del-noce-il-liberale-solitario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Del Noce il liberale solitario"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3572"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3572\/revisions"}],"predecessor-version":[{"id":36124,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3572\/revisions\/36124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/36123"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}