{"id":35393,"date":"2016-06-30T00:00:43","date_gmt":"2016-06-29T22:00:43","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=35393"},"modified":"2016-06-28T10:18:40","modified_gmt":"2016-06-28T08:18:40","slug":"chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/","title":{"rendered":"Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"http:\/\/www.matchman-news.com\/\">Matchman<\/a><a href=\"http:\/\/www.matchman-news.com\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-35394 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/anti_gender.jpg\" alt=\"anti_gender\" width=\"206\" height=\"200\" \/><\/a><\/strong> \u2013 26 giugno 2016<\/p>\n<p style=\"text-align: justify;\">I pastori e sacerdoti di tutta Europa sono sempre pi\u00f9 ostacolati nel loro compito e nella loro opera di evangelizzazione, a causa di interpretazioni nazionali del \u201cprincipio di crimini legati all\u2019odio\u201d, lo dimostra con il suo recentissimo libro-ricerca il responsabile europeo di ADF Paul Coleman.<\/p>\n<p style=\"text-align: justify;\">L\u2019ADF International afferma che da parte dei governi nazionali, in tutto il continente europeo, stanno crescendo gli ostacoli verso i cristiani accusati di crimini d\u2019odio, quando presentano le loro ragioni in materia di sessualit\u00e0 e precetti evangelici. Si mette in evidenza la legge del Regno Unito, sul \u201crazzismo e l\u2019odio religioso\u201d del 2006, il Communications Act (2003) e il moltiplicarsi dei \u201creati di ordine pubblico\u201d, tutti strumenti usati per restringere la libert\u00e0 di parola dei cristiani nella sfera pubblica.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Il libro denuncia di Paul Coleman ne traccia l\u2019evoluzione preoccupante.<\/p>\n<p style=\"text-align: justify;\">L\u2019Adf ha anche messo in guardia per i pericoli legati ai nuovi provvedimenti sull\u2019estremismo che sono stati presentati nel Discorso della Regina nel maggio 2016, i quali potrebbero avere lo stesso effetto restrittivo nei confronti della libert\u00e0 religiosa e di opinione per i cristiani del Regno Unito. ADF internazionale riporta nella ricerca anche i numerosi incidenti in cui diversi leaders delle chiese e predicatori di tutta Europa stanno affrontando indagini e accuse legate alla espressione della loro opinione o in relazione alla loro opera evangelizzatrice.<\/p>\n<p style=\"text-align: justify;\">Paul Coleman in una recente intervista a canale <em>Premier.uk<\/em> ha rilasciato interessanti commenti su ci\u00f2 che sta avvenendo in Europa. \u201cQuando iniziamo a limitare il discorso dei cittadini, in realt\u00e0, nessuno \u00e8 pi\u00f9 al sicuro\u201d. Coleman ha dato esempi di questo atteggiamento, quello di un pastore che comprendeva uno svedese perseguito per il suo discorso di \u201codio sulla sessualit\u00e0\u201d, quello di vescovi cattolici oggetto di indagine da parte della polizia a causa di commenti sul matrimonio e la famiglia e di \u201cpredicatori di strada\u201d nel Regno Unito arrestati.<\/p>\n<p style=\"text-align: justify;\">Paul Coleman ha aggiunto: \u201cI cristiani dovrebbero essere in prima linea di difendere la libert\u00e0 di parola . Credo che la libert\u00e0 di parola sia necessaria per tutti i cittadini e molto importante per i cristiani perch\u00e9 tutti i cristiani hanno il mandato di condividere la Buona Novella. La nostra missione \u00e8 quella di raccontare agli altri della nostra fede\u201d.<\/p>\n<p style=\"text-align: justify;\">Il recentissimo caso delle accuse e del tentativo di denuncia istituzionale da parte dei partiti socialisti e di sinistra di Valencia contro il Cardinale e Vescovo Canizares, anche grazie alla ferma contrariet\u00e0 del Partido Popular e alla raccolta di ben pi\u00f9 di 150.000 firme di sostegno al Cardinale da parte della organizzazione CitizenGo, aprirebbe un altro scenario ancor pi\u00f9 drammatico. Infatti, I partiti di estrema sinistra hanno tentato di ottenere una dichiarazione ufficiale del Parlamento valenciano contro il cardinale.<\/p>\n<p style=\"text-align: justify;\">Per l\u2019opposizione di altri partiti, la proposta dovr\u00e0 ora essere ripresentata. Se il cardinale sar\u00e0 riconosciuto colpevole di crimini d\u2019odio, rischia fino a tre anni di carcere. Il libro denuncia di Adf \u00e8 disponibile su tutti i bookstores on line.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Matchman \u2013 26 giugno 2016 I pastori e sacerdoti di tutta Europa sono sempre pi\u00f9 ostacolati nel loro compito e nella loro opera di evangelizzazione, a causa di interpretazioni nazionali del \u201cprincipio di crimini legati all\u2019odio\u201d, lo dimostra con il suo recentissimo libro-ricerca il responsabile europeo di ADF Paul Coleman. L\u2019ADF International afferma che da &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":35394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[1543],"class_list":["post-35393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ideologia-del-gender","tag-repressione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-29T22:00:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/anti_gender.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"228\" \/>\n\t<meta property=\"og:image:height\" content=\"221\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d\",\"datePublished\":\"2016-06-29T22:00:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/\"},\"wordCount\":502,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/anti_gender.jpg\",\"keywords\":[\"repressione\"],\"articleSection\":[\"Ideologia del gender\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/\",\"name\":\"Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/anti_gender.jpg\",\"datePublished\":\"2016-06-29T22:00:43+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/anti_gender.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/anti_gender.jpg\",\"width\":228,\"height\":221},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/","og_locale":"it_IT","og_type":"article","og_title":"Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2016-06-29T22:00:43+00:00","og_image":[{"width":228,"height":221,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/anti_gender.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d","datePublished":"2016-06-29T22:00:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/"},"wordCount":502,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/anti_gender.jpg","keywords":["repressione"],"articleSection":["Ideologia del gender"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/","name":"Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/anti_gender.jpg","datePublished":"2016-06-29T22:00:43+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/anti_gender.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/anti_gender.jpg","width":228,"height":221},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/chiese-in-europa-indagate-ai-sensi-delle-leggi-sui-crimini-dodio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Chiese in Europa : \u201cindagate ai sensi delle leggi sui crimini d\u2019odio\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=35393"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35393\/revisions"}],"predecessor-version":[{"id":35395,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35393\/revisions\/35395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/35394"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=35393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=35393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=35393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}