{"id":35093,"date":"2016-06-23T00:00:21","date_gmt":"2016-06-22T22:00:21","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=35093"},"modified":"2016-06-20T08:47:12","modified_gmt":"2016-06-20T06:47:12","slug":"perche-lafrica-e-sempre-innocente-e-loccidente-no","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/","title":{"rendered":"Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-35094 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/miniera_Africa.jpg\" alt=\"miniera_Africa\" width=\"248\" height=\"184\" \/>La Nuova bussola quotidiana<\/strong><\/p>\n<p style=\"text-align: center;\">20 giugno 2016<\/p>\n<p style=\"text-align: center;\"><strong>Anna Bono<\/strong><\/p>\n<p style=\"text-align: justify;\">Nei cellulari c\u2019\u00e8 il coltan, un minerale che arriva quasi tutto dalla Repubblica democratica del Congo. Ma, invece di essere fonte di benessere per il Paese e per i suoi abitanti gi\u00e0 tanto martoriati, averlo \u00e8 una disgrazia: le condizioni di lavoro sono insalubri e pericolose, i minatori, anche bambini, lavorano spesso in condizione di schiavit\u00f9, dei gruppi armati se lo contendono per contrabbandarlo e la popolazione civile ne fa le spese. Ecco perch\u00e9 da qualche anno se ne parla come di una maledizione.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>Il coltan non \u00e8 l\u2019unica risorsa naturale a essere considerata <\/strong><strong>una<\/strong> maledizione in Africa. Per primo \u00e8 stato il rame a essere \u201cmaledetto\u201d. Lo Zambia negli Anni \u201860 era il secondo maggior produttore di rame del mondo dopo il Cile e anche adesso figura tra i primi dieci. Dopo l\u2019indipendenza ottenuta nel 1964, tutti avevano previsto per il Paese un rapido sviluppo proprio grazie al rame: tutti tranne l\u2019agronomo Ren\u00e9 Dumont, di tutt\u2019altro avviso. Ma pochi gli diedero retta allora, malgrado la sua fama, perch\u00e9 nel clima di quegli anni, esaltato per la fine della colonizzazione europea, un suo libro pubblicato nel 1962 lo aveva screditato: si intitolava\u00a0<em>L\u2019Afrique noire est mal partie<\/em>,(L\u2019Africa nera \u00e8 partita male), ed elencava i fattori negativi che avrebbero impedito agli africani di godersi l\u2019indipendenza.<\/p>\n<p style=\"text-align: justify;\"><strong>Purtroppo aveva ragione Dumont e lo si \u00e8 capito presto, fin dagli Anni \u201870. Le guerre di liberazione <\/strong>erano state anche guerre civili, tribali, per la supremazia. I vincitori non ebbero piet\u00e0 dei vinti e, una volta insediati, iniziarono il saccheggio dei beni nazionali. Fu allora che, a proposito dello Zambia, qualcuno invent\u00f2 l\u2019espressione \u201cla maledizione del rame\u201d: per dire che il Paese era sempre pi\u00f9 povero e proprio a causa della nuova ricchezza, sprecata, usata male e ferocemente contesa. Per le stesse ragioni, la maledizione della Costa d\u2019Avorio \u00e8 il cacao, quella della Nigeria il petrolio, della Sierra Leone i diamanti, per i quali si \u00e8 combattuta una guerra tanto atroce da far coniare una nuova espressione: diamanti insanguinati.<\/p>\n<p style=\"text-align: justify;\"><strong>Dumont in un suo saggio spiegava come e quanto lo Zambia stesse dilapidando senza farsi scrupoli <\/strong><strong>la<\/strong> propria ricchezza, ipotecando il futuro: vistosi beni di lusso personali, palazzi ministeriali faraonici, patrimoni profusi per ostentare simboli di status e di modernit\u00e0 privati e pubblici \u2013 per anni dopo l\u2019indipendenza lo Zambia \u00e8 stato il maggior consumatore al mondo di champagne Veuve Cliquot \u2013 il tutto attingendo alle casse dello Stato e indebitando il Paese. Ren\u00e9 Dumont, e con lui altri affermati studiosi del continente africano, avevano chiaro che il problema dello Zambia era l\u2019avidit\u00e0 dei suoi leader decisi a far bottino delle sue risorse e a spartirlo con le rispettive etnie.<\/p>\n<p style=\"text-align: justify;\"><strong>Lo storico Basil Davidson, ad esempio, definiva i leader africani, tutti senza eccezione, corrotti, <\/strong>irresponsabili e criminali. Bench\u00e9 gi\u00e0 negli Anni \u201870 stesse prendendo forma l\u2019ideologia terzomondista con le sue teorie sul neocolonialismo e il neoimperialismo, ancora nessuno allora organizzava campagne contro l\u2019acquisto del rame incolpando dei problemi dello Zambia chi metteva grondaie di rame a casa sua. Ma 40 anni di campagne antioccidentali hanno lasciato il segno. Ormai tutti dicono che ci sono le guerre perch\u00e9 noi occidentali fabbrichiamo armi, il coltan alimenta conflitti, e corruzione, perch\u00e9 noi occidentali abbiamo inventato i cellulari.<\/p>\n<p style=\"text-align: justify;\"><strong>Il Congo \u00e8 uscito nel 1996 da 30 anni di dittatura sotto Sese Seko Mobutu solo per piombare in una <\/strong>guerra dopo l\u2019altra, con pi\u00f9 di quattro milioni di vittime civili, e adesso \u00e8 in mano a un capo di Stato, Joseph Kabila, che pensa solo a restare in carica in qualche modo, oltre i limiti previsti dalla costituzione. I leader politici sono talmente corrotti da rivendicare addirittura apertamente il diritto di razziare le ricchezze nazionali (se no, che senso avrebbe arrivare al potere?). Eppure quasi nessuno li accusa di sprecare i proventi della vendita del coltan \u2013 e di ogni altra risorsa mineraria di cui il Congo \u00e8 incredibilmente ricco \u2013 e di permettere che i gruppi armati lo contrabbandino e minaccino la popolazione. C\u2019\u00e8 persino chi li difende: \u00abil Paese \u00e8 grande, il territorio \u00e8 troppo vasto e non dispongono dei fondi necessari per gestirlo e controllarlo\u00bb, \u00abla distanza da questa regione (dove ci sono le miniere di coltan) dalla capitale rende quasi impossibile controllarla\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Se si digita \u201ccoltan\u201d su Google compaiono infiniti elenchi di blog, riviste e siti web con titoli come <\/strong><strong>\u201cLa<\/strong> maledizione del coltan. Che tutti abbiamo negli smartphone\u201d, \u201cIl sangue nel nostro smartphone\u201d, \u201cIl diamante insanguinato dell\u2019hi-tech\u201d. Nei testi il livore contro \u00abnoi che usiamo gli smartphone\u00bb fa paura: \u00absiamo tutti assassini diretti o indiretti della popolazione del Congo\u00bb, \u00abuno smartphone nuovo corrisponde alla schiavit\u00f9 di un altro bambino del Congo\u2026 La cui madre o sorella saranno state stuprate e trucidate\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Gli smartphone li usano anche i cinesi e gli indiani. Li usano anche gli africani: pi\u00f9 di 400 milioni <\/strong><strong>di <\/strong>utenti in Africa e un mercato in crescita. Ma la colpa resta nostra, siamo noi occidentali ad aver suscitato il bisogno di comunicare via cellulare. Per millenni gli Africani ne hanno fatto a meno. E gli immigrati illegali che arrivano tutti con lo smartphone? In quell\u2019apparecchio che si portano appresso c\u2019\u00e8 tutta la loro vita: fotografie, ricordi, le loro radici, l\u2019unico rapporto con la famiglia lontana. Come potrebbero farne a meno?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Nuova bussola quotidiana 20 giugno 2016 Anna Bono Nei cellulari c\u2019\u00e8 il coltan, un minerale che arriva quasi tutto dalla Repubblica democratica del Congo. Ma, invece di essere fonte di benessere per il Paese e per i suoi abitanti gi\u00e0 tanto martoriati, averlo \u00e8 una disgrazia: le condizioni di lavoro sono insalubri e pericolose, &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":35094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[2465],"class_list":["post-35093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","tag-coltan","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-22T22:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/miniera_Africa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"248\" \/>\n\t<meta property=\"og:image:height\" content=\"184\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no\",\"datePublished\":\"2016-06-22T22:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/\"},\"wordCount\":884,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/miniera_Africa.jpg\",\"keywords\":[\"coltan\"],\"articleSection\":[\"Africa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/\",\"name\":\"Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/miniera_Africa.jpg\",\"datePublished\":\"2016-06-22T22:00:21+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/miniera_Africa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/miniera_Africa.jpg\",\"width\":248,\"height\":184},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perche-lafrica-e-sempre-innocente-e-loccidente-no\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/","og_locale":"it_IT","og_type":"article","og_title":"Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2016-06-22T22:00:21+00:00","og_image":[{"width":248,"height":184,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/miniera_Africa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no","datePublished":"2016-06-22T22:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/"},"wordCount":884,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/miniera_Africa.jpg","keywords":["coltan"],"articleSection":["Africa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/","name":"Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/miniera_Africa.jpg","datePublished":"2016-06-22T22:00:21+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/miniera_Africa.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/miniera_Africa.jpg","width":248,"height":184},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perche-lafrica-e-sempre-innocente-e-loccidente-no\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Perch\u00e9 l\u2019Africa \u00e8 sempre innocente e l\u2019Occidente no"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=35093"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35093\/revisions"}],"predecessor-version":[{"id":35095,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35093\/revisions\/35095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/35094"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=35093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=35093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=35093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}