{"id":3504,"date":"2009-10-28T08:38:10","date_gmt":"2009-10-28T07:38:10","guid":{"rendered":""},"modified":"2016-02-04T15:57:41","modified_gmt":"2016-02-04T14:57:41","slug":"lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/","title":{"rendered":"Lo sviluppo dell&#8217;Africa passa anche attraverso gli Ogm"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/agricolt_Africa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30309\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/agricolt_Africa.jpg\" alt=\"agricolt_Africa\" width=\"250\" height=\"166\" \/><\/a>ragionpolitica.it<\/strong> venerd\u00ec 25 settembre 2009<\/div>\n<p style=\"text-align: center;\">di <strong>Antonio Gaspari<\/strong><\/p>\n<p style=\"text-align: justify;\">Si fa un gran parlare del problema dell&#8217;immigrazione, per lo pi\u00f9 in maniera ideologica, ma solo pochi sottolineano il fatto che l&#8217;unica vera soluzione risiede nello sviluppo dell&#8217;Africa, cio\u00e8 nella possibilit\u00e0 di aiutare gli africani a conoscere e utilizzare le moderne tecniche agricole per vincere fame e degrado.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Sono pochi anche coloro che comprendono come la fuga dei giovani dai paesi di origine impoverisca la societ\u00e0 e renda ancora pi\u00f9 difficile la battaglia contro il sottosviluppo. Lo sviluppo dell&#8217;Africa \u00e8 dunque un bene per tutti, porterebbe benefici enormi anche per il mondo industrializzato, perch\u00e9 aprirebbe nuovi e grandi mercati nel contesto di un processo di progresso globale.<\/div>\n<p style=\"text-align: justify;\">In prossimit\u00e0 del secondo Sinodo per l&#8217;Africa, che si aprir\u00e0 a Roma il 5 ottobre, l&#8217;Ateneo Pontificio Regina Apostolorum, insieme all&#8217;Universit\u00e0 Europea di Roma, ha organizzato una giornata di studio internazionale sul tema \u00abPer una rivoluzione verde in Africa. Lo sviluppo \u00e8 il nuovo nome della pace\u00bb.<\/p>\n<p style=\"text-align: justify;\">Intervenendo al convegno, monsignor Giampaolo Crepaldi, arcivescovo di Trieste e segretario uscente del Pontificio Consiglio per la Giustizia e la Pace, ha sottolineato che \u00abl&#8217;Africa \u00e8 un continente colpevolmente dimenticato\u00bb e per la Chiesa \u00e8 una grossa sfida pastorale: \u00abO il cattolicesimo ce la fa in Africa oppure rischia qualche sofferenza di troppo\u00bb.<\/p>\n<p style=\"text-align: justify;\">Dopo aver ricordato che seppure l&#8217;Africa sia il continente pi\u00f9 ricco al mondo per materie prime, tra i 50 paesi pi\u00f9 poveri del mondo 35 sono africani, monsignor Crepaldi ha sottolineato che \u00abper la soluzione di problemi cos\u00ec complessi e profondi come quelli che affliggono l&#8217;Africa non ci sono soluzioni univoche e semplicistiche.<\/p>\n<p style=\"text-align: justify;\">Ma non possiamo ignorare i tanti benefici che deriverebbero dall&#8217;impiego di tecniche di produzione agricola innovative, capaci di stimolare e sostenere gli agricoltori africani. Gi\u00e0 oggi &#8211; ha affermato l&#8217;arcivescovo di Trieste &#8211; l&#8217;utilizzo delle sementi opportunamente migliorate tramite tecniche che intervengono sul loro patrimonio genetico sta promuovendo un crescente e diffuso progresso, come dimostrato da interessanti studi\u00bb. Secondo monsignor Crepaldi, \u00abla biotecnologia non deve essere divinizzata n\u00e9 demonizzata.<\/p>\n<p style=\"text-align: justify;\">La tecnica e, di conseguenza, la biotecnologia \u00e8 una cosa buona, ma pu\u00f2 essere usata male\u00bb; \u00e8 dunque necessario che, come ogni attivit\u00e0 umana, \u00abessa sia guidata dalla morale\u00bb. Per il presule \u00abla biotecnologia ha prodotto concretamente un grande sviluppo in molti settori, come la medicina, la farmacologia, la zootecnia ecc&#8230;, che, se correttamente utilizzato, potr\u00e0 risolvere molte delle questioni sociali del mondo odierno\u00bb.<\/p>\n<p style=\"text-align: justify;\">Monsignor Crepaldi ha ricordato anche che \u00abvi sono gruppi, non gruppetti piccoli, ma in certo senso dominanti, che mossi da una certa ideologia antiumanistica propongono misure restrittive per la manipolazione delle specie vegetali ed animali mentre favoriscono la manipolazione della persona umana\u00bb.<\/p>\n<p style=\"text-align: justify;\">Per spiegare i benef\u00ecci dell&#8217;uso delle biotecnologie sono intervenuti scienziati e agricoltori africani. Sylvester Oikeh, di AATF (African Agricoltural Technology Foundation), ente non profit che si batte per la sicurezza alimentare e la riduzione della povert\u00e0 nell&#8217;Africa sub sahariana, ha affermato che \u00abin Africa i benef\u00ecci prodotti dalle tecnologie OGM sono gi\u00e0 stati dimostrati\u00bb.<\/p>\n<p style=\"text-align: justify;\">In Sud Africa, in condizioni in cui l&#8217;acqua piovana \u00e8 la sola fonte di irrigazione, il mais modificato geneticamente ha aumentato le rese dell&#8217;11%, con un guadagno di 35 dollari in pi\u00f9 per ettaro (che per un agricoltore africano \u00e8 una cifra smolto significativa). Nel Burkina Faso, prove sul campo con il cotone modificato hanno ridotto di due terzi la quantit\u00e0 di antiparassitari utilizzati e hanno aumentato le rese del 15%, promuovendo il benessere degli agricoltori e dell&#8217;ambiente e favorendo la prosperit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Motlatsi Musi, agricoltore del Sud Africa, ha raccontato che \u00abcon le sementi convenzionali riuscivo ad ottenere 5 tonnellate di mais per ettaro. Ma gli agricoltori che non hanno la possibilit\u00e0 di utilizzare i trattori con i semi convenzionali hanno una resa media di circa 1,5 tonnellate per ettaro soltanto. Ora, con le sementi OGM, io ottengo 7 tonnellate per ettaro; e in pi\u00f9 si abbattono i costi di produzione, grazie alla diminuzione dei tempi di manodopera e del costo dei pesticidi.<\/p>\n<p style=\"text-align: justify;\">Anche nell&#8217;eventualit\u00e0 di un&#8217;oscillazione dei prezzi di mercato &#8211; ha proseguito Musi &#8211; il vantaggio economico della coltivazione di sementi OGM sarebbe comunque assicurato\u00bb. Dal Burkina Faso, Fran\u00e7ois Traor\u00e8, presidente dell&#8217;Unione Nazionale dei produttori di cotone, padre di sette figli, ha spiegato: \u00abNella regione del Burkina Faso circa il 90% della popolazione vive di agricoltura.<\/p>\n<p style=\"text-align: justify;\">La produzione di cotone contribuisce da sola al sostentamento di circa 3 milioni di persone (pi\u00f9 del 20% della popolazione) assicurando ai piccoli produttori le risorse primarie per vivere e garantire l&#8217;istruzione di base ai propri figli\u00bb.<\/p>\n<p style=\"text-align: justify;\">Nel 2003 \u00abil Burkina Faso ha iniziato le sperimentazioni in campo sul cotone OGM per verificarne l&#8217;efficacia e l&#8217;impatto ambientale e nel 2007 sono stati resi noti i primi risultati: un aumento della produzione dal 35% al 48%, una riduzione dei trattamenti (da 6 a 2 per anno) e una riduzione del costi del 62%\u00bb.<\/p>\n<p style=\"text-align: justify;\">Traor\u00e8 ha concluso affermando che \u00abnon permettere agli africani di utilizzare sementi OGM \u00e8 un crimine contro l&#8217;umanit\u00e0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ragionpolitica.it venerd\u00ec 25 settembre 2009 di Antonio Gaspari Si fa un gran parlare del problema dell&#8217;immigrazione, per lo pi\u00f9 in maniera ideologica, ma solo pochi sottolineano il fatto che l&#8217;unica vera soluzione risiede nello sviluppo dell&#8217;Africa, cio\u00e8 nella possibilit\u00e0 di aiutare gli africani a conoscere e utilizzare le moderne tecniche agricole per vincere fame e &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30309,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,3],"tags":[274],"class_list":["post-3504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-ambientalismo","tag-ogm","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo sviluppo dell&#039;Africa passa anche attraverso gli Ogm - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo sviluppo dell&#039;Africa passa anche attraverso gli Ogm - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-28T07:38:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-04T14:57:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/agricolt_Africa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Lo sviluppo dell&#8217;Africa passa anche attraverso gli Ogm\",\"datePublished\":\"2009-10-28T07:38:10+00:00\",\"dateModified\":\"2016-02-04T14:57:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/\"},\"wordCount\":833,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/agricolt_Africa.jpg\",\"keywords\":[\"ogm\"],\"articleSection\":[\"Africa\",\"Ambientalismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/\",\"name\":\"Lo sviluppo dell'Africa passa anche attraverso gli Ogm - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/agricolt_Africa.jpg\",\"datePublished\":\"2009-10-28T07:38:10+00:00\",\"dateModified\":\"2016-02-04T14:57:41+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/agricolt_Africa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/agricolt_Africa.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo sviluppo dell&#8217;Africa passa anche attraverso gli Ogm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo sviluppo dell'Africa passa anche attraverso gli Ogm - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/","og_locale":"it_IT","og_type":"article","og_title":"Lo sviluppo dell'Africa passa anche attraverso gli Ogm - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-10-28T07:38:10+00:00","article_modified_time":"2016-02-04T14:57:41+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/agricolt_Africa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Lo sviluppo dell&#8217;Africa passa anche attraverso gli Ogm","datePublished":"2009-10-28T07:38:10+00:00","dateModified":"2016-02-04T14:57:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/"},"wordCount":833,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/agricolt_Africa.jpg","keywords":["ogm"],"articleSection":["Africa","Ambientalismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/","name":"Lo sviluppo dell'Africa passa anche attraverso gli Ogm - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/agricolt_Africa.jpg","datePublished":"2009-10-28T07:38:10+00:00","dateModified":"2016-02-04T14:57:41+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/agricolt_Africa.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/agricolt_Africa.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-sviluppo-dellafrica-passa-anche-attraverso-gli-ogm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Lo sviluppo dell&#8217;Africa passa anche attraverso gli Ogm"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3504"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3504\/revisions"}],"predecessor-version":[{"id":30310,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3504\/revisions\/30310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30309"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}