{"id":35,"date":"2004-11-03T13:36:51","date_gmt":"2004-11-03T12:36:51","guid":{"rendered":""},"modified":"2024-01-05T12:42:35","modified_gmt":"2024-01-05T11:42:35","slug":"protocollo-di-kyoto-e-co2-un-falso-allarme","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/","title":{"rendered":"Protocollo di Kyoto e CO2, un falso allarme"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"center\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35796 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Kyoto.jpg\" alt=\"\" width=\"208\" height=\"243\" \/>Abstract: <\/strong><span style=\"color: #000000;\"><em>il Protocollo di Kyoto sulla riduzione della CO2 \u00e8 il frutto di un falso allarme.<\/em> <em>Che il clima sia instabile \u00e8 un dato di fatto. Ma le cause delle irregolarit\u00e0 sono incerte. E molte sono le perplessit\u00e0 che suscita il protocollo di Kyoto. <\/em>In ogni caso la riduzione delle emissioni di CO2\u00a0 risulta molto costosa\u00a0 a fronte di risultati irrisori. In Europa a dispetto del fondamentalismo ambientalista\u00a0 solo pochissimi Paesi sono riusciti a ridurre le emissioni mentre altri, tra cui l&#8217;Italia le hanno aumentate. Allo stato attuale delle conoscenze il bilancio della CO2 nell&#8217;atmosfera\u00a0 \u00e8 molto incerto.<\/span><\/p>\n<p align=\"center\"><!--more--><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"color: #000000;\">Articolo pubblicato su<b>\u00a0<\/b><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.tempi.it\/\" target=\"_blank\" rel=\"noopener\"><strong>Tempi<\/strong><\/a><\/span>\u00a0N. 43 &#8211; 24 Ottobre 2002<\/span><\/p>\n<h3 align=\"center\"><span style=\"color: #000000;\">Kyoto, un protocollo o un falso allarme?<\/span><\/h3>\n<p><span style=\"color: #000000;\"><em>Che il clima sia instabile \u00e8 un dato di fatto. Ma le cause delle irregolarit\u00e0 sono incerte. E molte sono le perplessit\u00e0 che suscita il protocollo di Kyoto. Che abbia ragione Bush<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di\u00a0<strong>Pedrocchi Ernesto<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il clima della terra non \u00e8 mai stato stabile. Non solo nel periodo delle ere glaciali ma anche negli ultimi millenni ci sono state variazioni importanti, ma \u00e8 probabile che ora sia in atto un processo di cambiamento forse pi\u00f9 veloce di quanto la storia dell\u2019uomo ricordi. La temperatura media superficiale del pianeta terra \u00e8 cresciuta nell\u2019ultimo secolo di circa 0,6\u00b0C, in modo molto irregolare nel tempo e nello spazio; ancora pi\u00f9 incerto e irregolare \u00e8 l\u2019aumento del livello dei mari<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Queste incertezze, il legame difficilissimo da quantificare tra l\u2019aumento dei gas serra nell\u2019atmosfera e le condizioni climatiche, l\u2019influenza sul clima di altri fattori poco noti sono elementi pi\u00f9 che sufficienti per dimostrare quanto complessi e difficili siano questi fenomeni fisici e quanto poco l\u2019uomo li conosca. A fronte di questo grave stato di incertezza, stanno affermazioni avventate che danno per scontato che il clima cambi a causa dell\u2019immissione antropica di gas serra nell\u2019atmosfera. E che accentuano ogni evento climatico e ne attribuiscono la causa all\u2019uomo.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>La sua efficacia e la relativa evoluzione<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In base a un generico principio di precauzione, malgrado fosse molto difficile varare provvedimenti precauzionali senza basi scientifiche, dopo un dibattito pi\u00f9 politico che scientifico, l\u2019Onu ha promosso un\u2019azione per contenere l\u2019aumento di concentrazione in atmosfera di gas ad effetto serra di natura antropica. Le vie a priori perseguibili sono due: ridurre le emissioni antropogeniche di gas ad effetto serra o aumentare l\u2019assorbimento di questi gas nella biosfera. Si sono scontrate due posizioni: una favorevole a imporre ai vari Paesi delle limitazioni alle emissioni antropogeniche di gas serra o ad aumentarne le capacit\u00e0 di assorbimento e un\u2019altra che, prima di intraprendere azioni incerte e costose, chiedeva si raggiungessero delle conoscenze pi\u00f9 sicure<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La prima posizione, sostenuta prevalentemente dai paesi europei, non \u00e8 stata attentamente vagliata sul piano economico e su quello giuridico. La seconda, sostenuta dagli Usa, presenta il grave problema dei tempi necessari per raggiungere conoscenze pi\u00f9 certe. La combustione di tutti i combustibili produce CO2 a pari energia liberata il carbone ne produce pi\u00f9 dei derivati del petrolio (~1,25%) e ancor pi\u00f9 del gas naturale (~1,40%). L\u2019energia utilizzata dall\u2019umanit\u00e0 per pi\u00f9 dell\u201980% proviene dai combustibili fossili e non \u00e8 assolutamente ipotizzabile che tale frazione possa ridursi se non in tempi lunghi (almeno qualche decina d\u2019anni).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Produrre energia dai combustibili fossili riducendo le emissioni in atmosfera di CO2 rispetto alla modalit\u00e0 di semplice combustione tradizionale comporta un costo aggiuntivo che, grossolanamente, si pu\u00f2 stimare dell\u2019ordine del 30%. Dato per scontato che fosse molto difficile richiedere ai Paesi in via di sviluppo (Pvs) di produrre energia a costi maggiori, si \u00e8 proposto che all\u2019inizio solo i Paesi sviluppati, che sono stati finora maggiormente responsabili delle emissioni di gas serra, si facessero carico della riduzione.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00c8 facile intuire come i Pvs si siano in generale schierati a favore della prima soluzione; ma si tenga presente che fra pochi anni saranno proprio loro i maggiori emettitori di gas ad effetto serra. Da questo dibattito \u00e8 nato il protocollo di Kyoto che \u00e8 stato sottoscritto da 84 Paesi, ma per entrare in vigore \u00e8 necessario che sia ratificato da almeno 55 Paesi (questo \u00e8 facilmente realizzabile) purch\u00e8 le loro emissioni rappresentino almeno il 55% delle emissioni del 1990 (questo \u00e8 invece molto difficile, specialmente dopo la rinuncia degli Usa, confermata a Johannesburg).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Semplificando: il protocollo di Kyoto prevede per il complesso dei paesi sviluppati la riduzione entro il 2012 del 5% delle emissioni di CO2 rispetto ai valori del 1990, ogni paese ha poi una sua aliquota in base alla particolare situazione energetica. \u00c8 opportuno fare subito un banale calcolo. La riduzione del 5% delle emissioni dei paesi sviluppati \u00e8 pari a circa 0,6 miliardi di tonnellate di CO2 che corrisponde al 2,5% delle emissioni totali antropiche, ma solo a meno dello 0,1% del totale di CO2 immesso nell\u2019atmosfera. Sembra facile dedurre che anche una piccolissima variazione delle emissioni o degli assorbimenti naturali possa mascherare o contrastare la riduzione delle emissioni antropiche<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">I Pvs richiedono sempre pi\u00f9 energia e immettono in atmosfera sempre pi\u00f9 CO2 e questo aumento non pu\u00f2 essere compensato dalla non sicura riduzione delle emissioni dei paesi sviluppati. In ogni caso l\u2019immissione antropica di CO2 nell\u2019atmosfera continuer\u00e0 ad aumentare e si prospettano due possibilit\u00e0: o i cambiamenti climatici non dipendono da queste immissioni antropiche, ma da fattori naturali e l\u2019uomo non pu\u00f2 che subirli, o essi sono la conseguenza delle emissioni antropiche, ma il rispetto del protocollo di Kyoto risulta del tutto inefficace.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Anche interventi molto pi\u00f9 incisivi (e l\u2019unico praticabile sarebbe la copertura di una frazione importante di produzione di energia elettrica con la fonte nucleare) non riuscirebbero a contrastare il fenomeno. Si sostiene ora la necessit\u00e0 di uno \u201cshock tecnologico\u201d nel sistema di copertura del fabbisogno energetico, ma ci\u00f2 \u00e8 imprevedibile, tenuto conto della mancanza di potenzialit\u00e0 delle fonti di energia rinnovabile e del rifiuto preconcetto all\u2019energia nucleare.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Allarmismo ingiustificato<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">I Paesi della Ue, sotto la spinta del fondamentalismo ambientale, hanno prima favorito la promulgazione e poi spinto per l\u2019adesione al protocollo di Kyoto e hanno avviato, pi\u00f9 sulla carta che nei fatti, degli interventi di contenimento delle emissioni di gas serra. Subito ci si \u00e8 resi conto che il rispetto dei pur poco efficaci limiti imposti risultava difficile e costoso. Il protocollo di Kyoto \u00e8 del 1997 ma salvo pochi paesi (Francia, Germania e Regno Unito) tutti gli altri fino ad ora non sono riusciti a diminuire le emissioni rispetto al 1990, anzi molti, tra cui l\u2019Italia, le hanno aumentate significativamente<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La posizione dell\u2019Italia \u00e8 emblematica: a parole ci siamo sempre schierati su una linea favorevole al protocollo di Kyoto, ma nei fatti \u00e8 evidente dai numeri (tra il 1990 ed ora le emissioni sono aumentate di pi\u00f9 del 6% mentre al 2012 dovremmo riuscire a ridurle del 6,5% rispetto al valore del 1990) la difficolt\u00e0 se non l\u2019impossibilit\u00e0 di traguardare i limiti che ci imporrebbe. Gli Usa si erano subito resi conto di questa situazione e con la nuova amministrazione nel marzo 2001 hanno disdetto l\u2019adesione al protocollo di Kyoto. Certamente la nuova filosofia del protocollo di Kyoto facilita il raggiungimento degli obiettivi per i Paesi sviluppati mediante il coinvolgimento dei Pvs, ma probabilmente ne riduce ancora l\u2019efficacia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Con questa impostazione il protocollo di Kyoto, che era nato velleitariamente come un\u2019azione determinata e irrinunciabile per il bene del pianeta terra viene derubricato a una funzione psicologica e di esercizio propedeutico a nuovi interventi di difficile immaginazione. I pi\u00f9 avveduti tra i promotori riconoscono la difficolt\u00e0 di attuarlo e la non efficacia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tuttavia il grande e infondato allarmismo sviluppato sui cambiamenti climatici ha alimentato un emotivit\u00e0 sociale generalizzata favorevole al protocollo di Kyoto che rende molto difficile un dibattito scientificamente ed economicamente corretto e pacato. Forse alcuni ambiti culturali desiderano mantenere questa equivoca commistione fra scienza incerta e finalit\u00e0 sociale, ma invece di dare contributi per chiarire il problema promuovono solo disinformazione ed emotivit\u00e0 oscurantista. Anche la conferenza di Johannesburg non ha portato chiarezza su questo problema, si \u00e8 rimasti vincolati al protocollo di Kyoto come fosse il toccasana di tutti i mali, senza chiarire che \u00e8 praticamente inefficace<\/span>.<\/p>\n<p style=\"text-align: center;\"><strong>Il bilancio della CO2 nell&#8217;atmosfera<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Allo stato attuale delle conoscenze il bilancio della CO2 nell&#8217;atmosfera (vedi figura 1) \u00e8 molto incerto; in base ai pi\u00f9 recenti dati scientifici, le immissioni, per un totale di circa 720 miliardi di tonnellate, provengono<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; <span style=\"color: #000000;\">per circa 367 miliardi di tonnellate dalla biosfera<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; <span style=\"color: #000000;\">per circa 325 miliardi di tonnellate dai mari<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; <span style=\"color: #000000;\">per circa 22 miliardi di tonnellate dai combustibili fossili<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; <span style=\"color: #000000;\">per circa 6 miliardi di tonnellate dagli incendi di boschi e foreste<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Gli assorbimenti per un totale di 708 miliardi di tonnellate avvengono:<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; <span style=\"color: #000000;\">nella biosfera per circa 375 miliardi di tonnellate<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; <span style=\"color: #000000;\">nei mari per circa 333 miliardi di tonnellate<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L&#8217;eccedenza di immissioni, in media circa 12 miliardi di tonnellate annue, si accumula nell&#8217;atmosfera e ne fa aumentare la concentrazione di circa a 1,5ppm (parti per milione) all\u2019anno. Questa concentrazione \u00e8 aumentata dal valore di circa 250 ppm nel periodo pre industriale al valore di 380 ppm attuali. L&#8217;aumento \u00e8 per\u00f2 molto irregolare, bench\u00e9 il contributo dovuto ai combustibili fossili sia l&#8217;unico contributo abbastanza stabile e regolare. Esso varia da anno in anno anche significativamente senza che si riesca a capirne le cause: nel 1997 \u00e8 stato di meno di 1ppm mentre nel 1998 \u00e8 stato di pi\u00f9 di 3ppm.<\/span><\/p>\n<p style=\"text-align: justify;\">________________________________________<\/p>\n<p><strong>Sul Protocollo di Kyoto, la CO&#8221; e il falso allarme climatico :<\/strong><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-inutile-comunque\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Protocollo di Kyoto, inutile comunque<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/requiem-per-il-protocollo-di-kyoto\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Requiem per il Protocollo di Kyoto<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/energia-e-ambiente-dopo-kyoto\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Energia ambientale dopo Kyoto<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: il Protocollo di Kyoto sulla riduzione della CO2 \u00e8 il frutto di un falso allarme. Che il clima sia instabile \u00e8 un dato di fatto. Ma le cause delle irregolarit\u00e0 sono incerte. E molte sono le perplessit\u00e0 che suscita il protocollo di Kyoto. In ogni caso la riduzione delle emissioni di CO2\u00a0 risulta molto &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":35796,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[2387,514],"class_list":["post-35","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambientalismo","tag-ambientalismo","tag-kyoto","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protocollo di Kyoto e CO2, un falso allarme - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Il Protocollo di Kyoto \u00e8 motivato da un false allarme. La riduzione della CO2 \u00e8 molto costosa a fronte di risultati irrisori per l&#039;ambiente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protocollo di Kyoto e CO2, un falso allarme - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Il Protocollo di Kyoto \u00e8 motivato da un false allarme. La riduzione della CO2 \u00e8 molto costosa a fronte di risultati irrisori per l&#039;ambiente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2004-11-03T12:36:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-05T11:42:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Kyoto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"208\" \/>\n\t<meta property=\"og:image:height\" content=\"243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Protocollo di Kyoto e CO2, un falso allarme\",\"datePublished\":\"2004-11-03T12:36:51+00:00\",\"dateModified\":\"2024-01-05T11:42:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/\"},\"wordCount\":1551,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/Kyoto.jpg\",\"keywords\":[\"Ambientalismo\",\"Kyoto\"],\"articleSection\":[\"Ambientalismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/\",\"name\":\"Protocollo di Kyoto e CO2, un falso allarme - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/Kyoto.jpg\",\"datePublished\":\"2004-11-03T12:36:51+00:00\",\"dateModified\":\"2024-01-05T11:42:35+00:00\",\"description\":\"Il Protocollo di Kyoto \u00e8 motivato da un false allarme. La riduzione della CO2 \u00e8 molto costosa a fronte di risultati irrisori per l'ambiente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/Kyoto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/Kyoto.jpg\",\"width\":208,\"height\":243},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/protocollo-di-kyoto-e-co2-un-falso-allarme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protocollo di Kyoto e CO2, un falso allarme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protocollo di Kyoto e CO2, un falso allarme - Rassegna Stampa Cattolica","description":"Il Protocollo di Kyoto \u00e8 motivato da un false allarme. La riduzione della CO2 \u00e8 molto costosa a fronte di risultati irrisori per l'ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/","og_locale":"it_IT","og_type":"article","og_title":"Protocollo di Kyoto e CO2, un falso allarme - Rassegna Stampa Cattolica","og_description":"Il Protocollo di Kyoto \u00e8 motivato da un false allarme. La riduzione della CO2 \u00e8 molto costosa a fronte di risultati irrisori per l'ambiente","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2004-11-03T12:36:51+00:00","article_modified_time":"2024-01-05T11:42:35+00:00","og_image":[{"width":208,"height":243,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Kyoto.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Protocollo di Kyoto e CO2, un falso allarme","datePublished":"2004-11-03T12:36:51+00:00","dateModified":"2024-01-05T11:42:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/"},"wordCount":1551,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Kyoto.jpg","keywords":["Ambientalismo","Kyoto"],"articleSection":["Ambientalismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/","name":"Protocollo di Kyoto e CO2, un falso allarme - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Kyoto.jpg","datePublished":"2004-11-03T12:36:51+00:00","dateModified":"2024-01-05T11:42:35+00:00","description":"Il Protocollo di Kyoto \u00e8 motivato da un false allarme. La riduzione della CO2 \u00e8 molto costosa a fronte di risultati irrisori per l'ambiente","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Kyoto.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Kyoto.jpg","width":208,"height":243},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/protocollo-di-kyoto-e-co2-un-falso-allarme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Protocollo di Kyoto e CO2, un falso allarme"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":9,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35\/revisions"}],"predecessor-version":[{"id":58837,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/35\/revisions\/58837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/35796"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=35"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=35"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}