{"id":3484,"date":"2009-10-22T00:00:00","date_gmt":"2009-10-21T22:00:00","guid":{"rendered":""},"modified":"2019-06-13T10:06:35","modified_gmt":"2019-06-13T08:06:35","slug":"raphael-lemkin-il-genocidio-sovietico-in-ucraina","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/","title":{"rendered":"Raphael Lemkin (*) Il genocidio sovietico in Ucraina"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/Ucraina.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29649\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/Ucraina.jpg\" alt=\"Ucraina\" width=\"250\" height=\"159\"><\/a>Contemporanea<\/strong> n.3 luglio 2009<\/div>\n<p style=\"text-align: right;\">&nbsp;<em>Sosyura \u00abAma l\u2019Ucraina\u00bb<br \/>\n<\/em><em>Non puoi amare altri popoli<br \/>\n<\/em><em>se non ami l\u2019Ucraina (1)<\/em><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">L&#8217;uccisione in massa di popolazioni e nazioni che ha caratterizzato l&#8217;avanzata dell&#8217;Unione Sovietica in Europa non costituisce un tratto nuovo della loro politica espansionista, non \u00e8 un\u2019innovazione concepita unicamente per far nascere l&#8217;uniformit\u00e0 dalla diversit\u00e0 di polacchi, ungheresi, baltici, rumeni &#8211; che ora scompare tra le frange dell&#8217;impero. Essa, anzi, \u00e8 stata a lungo una caratteristica anche nella politica interna del Cremlino &#8211; una caratteristica per la quale gli attuali padroni avevano abbondanti precedenti nelle operazioni della Russia zarista.<\/div>\n<p style=\"text-align: justify;\">Essa costituisce infatti una tappa indispensabile nel processo di \u00abunione\u00bb che ingenuamente i leader sovietici sperano produrr\u00e0 l&#8217;\u00abuomo sovietico\u00bb, la \u00abnazione sovietica\u00bb e, per raggiungere questa meta, per unificare la nazione, i leader del Cremlino saranno disposti a distruggere le nazioni e le culture che hanno abitato per lungo tempo l&#8217;Europa orientale.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 (2) di cui voglio parlare \u00e8 forse l&#8217;esempio classico di genocidio sovietico, il suo pi\u00f9 ampio e duraturo esperimento di russificazione &#8211; la distruzione della nazione ucraina. Essa rappresenta solamente, come ho detto, l&#8217;erede di analoghi crimini zaristi come l&#8217;annegamento di 10.000 tartari della Crimea per ordine di Caterina la Grande, le uccisioni di massa da parte delle \u00abSS\u00bb di Ivan il Terribile \u2013 l\u2019 <em>Oprichnina<\/em>; lo sterminio dei leader nazionali polacchi e dei cattolici ucraini da parte di Nicola I; e le serie di pogrom di ebrei che hanno periodicamente macchiato la storia russa.<\/p>\n<p style=\"text-align: justify;\">Ed essa ha avuto i suoi omologhi all&#8217;interno dell&#8217;Unione Sovietica nell&#8217;annientamento della nazione ingrica, dei cosacchi del Don e del Kuban, delle Repubbliche tartare della Crimea, delle nazioni baltiche di Lituania, Estonia e Lettonia. Ciascuno di essi costituisce un esempio della prolungata politica di liquidazione delle popolazioni non russe mediante l&#8217;eliminazione di loro parti selezionate.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Ucraina forma una porzione dell&#8217;Urss sud-orientale equivalente al territorio di Francia e Italia ed \u00e8 abitata da circa 30 milioni di persone (3). Granaio della Russia in se stessa, la geografia l&#8217;ha resa una chiave strategica per il petrolio del Caucaso e dell&#8217;Iran e per l&#8217;intero mondo arabo.<\/p>\n<p style=\"text-align: justify;\">A nord, essa confina proprio con la Russia. Finch\u00e9 l&#8217;Ucraina conserva la sua unit\u00e0 nazionale, finch\u00e9 i suoi abitanti continuano a concepirsi come ucraini e a perseguire l&#8217;indipendenza, fino ad allora l&#8217;Ucraina rappresenta una grave minaccia nel cuore stesso del regime sovietico. Non sorprende che i leader comunisti abbiano attribuito un&#8217;importanza fondamentale alla russificazione di questo membro [dallo spirito] indipendente della loro \u00abUnione di Repubbliche\u00bb, e che abbiano deciso di rifarlo daccapo affinch\u00e8 si conformi al loro modello di un&#8217;unica nazione russa.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 l&#8217;ucraino non \u00e8 e non \u00e8 mai stato un russo. La sua cultura, il suo temperamento, la sua lingua, la sua religione &#8211; sono tutti diversi.<\/p>\n<p style=\"text-align: justify;\">Sulla porta laterale per Mosca, egli ha rifiutato di essere collettivizzato, accettando la deportazione e persino la morte. E dunque per questo \u00e8 particolarmente importante che l&#8217;ucraino sia adattato al modello procustiano dell&#8217;uomo sovietico ideale.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Ucraina \u00e8 particolarmente predisposta all&#8217;omicidio razziale per gruppi selezionati, per cui qui la tattica comunista non ha seguito lo schema adottato nelle offensive tedesche contro gli ebrei. La nazione \u00e8 troppo popolosa per essere sterminata completamente con una qualche efficacia. La sua leadership religiosa, intellettuale, politica, le sue \u00e9lite sono per\u00f2 molto ristrette e dunque sono state facilmente eliminate ed \u00e8 particolarmente su questi gruppi che si \u00e8 abbattuta tutta la potenza della scure sovietica, con la solita strumentazione fatta di omicidi di massa, deportazioni e lavoro forzato, esilio e affamamento.<\/p>\n<p style=\"text-align: justify;\">L\u2019aggressione ha mostrato una modalit\u00e0 sistematica, con l\u2019intero iter ripetuto&nbsp; di continuo per affrontare&nbsp; ogni nuova esplosione dello spirito nazionale. Il primo colpo&nbsp; fu inferto all\u2019intellighenzia, il cervello della nazione, in modo tale da paralizzare il resto del corpo. Nel 1920, nel 1926 e ancora nel 1930-33 insegnanti, scrittori, artisti, pensatori, leader politici furono liquidati, imprigionati o deportati.<\/p>\n<p style=\"text-align: justify;\">Secondo l\u2019<em>Ukrainian Quarterly <\/em>dell\u2019autunno 1948, nel solo 1931 furono spediti in Siberia 51.713 intellettuali. Almeno 114 dei maggiori poeti, scrittori e artisti, i pi\u00f9 illustri rappresentanti&nbsp; culturali della nazione, hanno conosciuto la stessa sorte. Secondo stime prudenti almeno il 75% degli intellettuali e dei professionisti ucraini nell\u2019Ucraina occidentale, nell\u2019Ucraina carpatica e nella Bucovina sono stati sterminati brutalmente dai russi. (<em>Ibid<\/em>., estate 1949).<\/p>\n<p style=\"text-align: justify;\">Assieme a questo attacco all\u2019intellighenzia ci fu un\u2019offensiva contro le Chiese, i sacerdoti e la gerarchia ecclesiastica, l\u2019\u00abanima\u00bb dell\u2019Ucraina. Tra il 1926 e il 1932, la Chiesa ortodossa autocefala ucraina, il suo Metropolita (Lypkivsky) e 10.000 membri del clero furono liquidati. Nel 1945, quando i sovietici s\u2019istallarono nell\u2019Ucraina occidentale, una sorte analoga tocc\u00f2 alla Chiesa cattolica ucraina. Che si trattasse unicamente di una politica di russificazione \u00e8 chiaramente dimostrato dal fatto che, prima della sua liquidazione, alla Chiesa fu offerta l\u2019opportunit\u00e0 di fondersi con il Patriarca[to] russo di Mosca, strumento politico del Cremino.<\/p>\n<p style=\"text-align: justify;\">L\u201911 aprile 1945, solo due settimane prima della conferenza di San Francisco, un distaccamento dell\u2019Nkvd circond\u00f2 la cattedrale di S. Giorgio a Leopoli e arrest\u00f2 il Metropolita Slipyj, 2 vescovi, 2 prelati e diversi sacerdoti (4). Tutti gli studenti del seminario teologico della citt\u00e0 furono trascinati fuori dalla scuola, mentre ai loro professori veniva comunicato che la Chiesa greco-cattolica ucraina aveva cessato di esistere, che il metropolita era in stato di arresto e che il suo posto sarebbe stato preso da un vescovo designato dal soviet. Azioni di questo tipo furono ripetute in tutta l\u2019Ucraina occidentale e in Polonia, al di la della Linea Curzon (5).<\/p>\n<p style=\"text-align: justify;\">Almeno sette vescovi furono arrestati o non se ne ebbe pi\u00f9 notizie. Nell\u2019area non c\u2019\u00e8 pi\u00f9 alcun vescovo della Chiesa cattolica ucraina in libert\u00e0. Cinquecento membri del clero che si erano riuniti per protestare contro l\u2019operato dei sovietici furono passati per le armi o arrestati. In tutta la regione esponenti del clero e del laicato furono uccisi a centinaia, mentre il numero di quelli man dati ai lavori forzali ascendeva a diverse migliaia. Interi villaggi furono spopolati.<\/p>\n<p style=\"text-align: justify;\">Durarle la deportazione, le famiglie furono deliberatamente separate, i padri inviati in Siberia, le madri nelle case di mattoni del Turkestan e i figli presso le case comuniste per essere \u00abeducati\u00bb. La Chiesa stessa, per il crimine di essere ucraina, fu dichiarata un&#8217;associazione nociva per il benessere dello stato sovietico, i suoi membri vennero schedali dalla polizia sovietica come potenziali \u00abnemici del popolo\u00bb. In effetti, fatta eccezione per 150.000 membri in Slovacchia, la Chiesa cattolica ucraina \u00e8 stata ufficialmente liquidata, la sua gerarchia imprigionata, il suo clero disperso e deportato.<\/p>\n<p style=\"text-align: justify;\">Queste aggressioni all&#8217;anima hanno avuto e continueranno ad avere gravi effetti sul cervello dell&#8217;Ucraina, poich\u00e9 sono le famiglie del clero che hanno tradizionalmente fornito gran parte degli intellettuali, mentre gli stessi prelati sono stati i leader dei villaggi, le loro mogli hanno presieduto le organizzazioni caritatevoli. Gli ordini religiosi dirigevano scuole, si prendevano cura della maggior parte delle opere di carit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Il terzo pilastro del piano sovietico riguardava gli agricoltori, la grande massa di contadini indipendenti che sono i depositari della tradizione, del folclore e della musica, della lingua e letteratura nazionale, dello spirito nazionale dell&#8217;Ucraina. L&#8217;arma utilizzala contro questo gruppo e forse la pi\u00f9 i terribile di tutte &#8211; la fame. Tra il 1932 e il 1933 cinque milioni di ucraini morirono di fame, una crudelt\u00e0 disumana che il 73<em>esimo<\/em> <em>, <\/em>Congresso condann\u00f2 il 28 maggio 1933 (6). Si \u00e8 cercato di liquidare questo apice della crudelt\u00e0 sovietica come una politica economica connessa alla&nbsp; collettivizzazione delle terre coltivate a grano e all&#8217;eliminazione dei kulaki, i contadini indipendenti, che era pertanto necessaria.<\/p>\n<p style=\"text-align: justify;\">II fatto, per\u00f2, \u00e8 che in Ucraina i grandi coltivatori erano pochi e rarissimi. Come dichiar\u00f2 lo scrittore sovietico Kossior sull\u2019 \u00abIzvestiia\u00bb del 2 dicembre 1933, \u00abil nazionalismo ucraino \u00e8 la nostra principale minaccia\u00bb, e fu per eliminare quel nazionalismo, per instaurare la spaventosa uniformit\u00e0 dello stile sovietico che i contadini ucraini furono sacrificati (7).<\/p>\n<p style=\"text-align: justify;\">Il metodo utilizzato in questa parte del piano non fu limitata a qualche gruppo particolare. Tutti patirono &#8211; uomini, donne, bambini. Il raccolto quell&#8217;anno fu pi\u00f9 che sufficiente a nutrire la popolazione e il bestiame dell&#8217;Ucraina, anche se era stato inferiore rispetto all&#8217;anno precedente, una diminuzione in larga parte dovuta probabilmente agli sforzi per la collettivizzazione.<\/p>\n<p style=\"text-align: justify;\">Ai sovietici, per\u00f2, serviva una carestia e cos\u00ec dovettero predisporne una, intenzionalmente, attraverso un prelievo di grano da parte dello stato insolitamente elevato sotto forma di tasse. In aggiunta a ci\u00f2, migliaia di acri di grano non furono mai mietuti, furono lasciati marcire nei campi. II resto fu inviato ai granai governativi per esservi immagazzinati fino a che le autorit\u00e0 non ne avessero deciso la destinazione. Gran parte d\u00ec questo raccolto, cos\u00ec vitale per la sopravvivenza dei cittadini ucraini, fin\u00ec come esportazione per ottenere crediti all&#8217;estero.<\/p>\n<p style=\"text-align: justify;\">Di fronte alla carestia nelle aziende agricole, in migliaia abbandonarono le aree rurali e si diressero verso le citt\u00e0 per chiedere cibo. Colti qui e rimandati nelle campagne, abbandonarono i loro figli nella speranza che almeno loro riuscissero a sopravvivere. In questo modo a Charkiv furono lasciati soli diciottomila bambini. In villaggi con una popolazione di mille abitanti ne sopravvissero cento; in altri, ne mor\u00ec la met\u00e0 e le morti oscillavano tra le venti e le trenta al giorno. Il cannibalismo divenne la normalit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Come scriveva nel 1933 W. Henry Chamberlain, il corrispondente da Mosca per il <em>Christian Science Monitor <\/em>(8):<\/p>\n<p style=\"text-align: justify;\"><em>I comunisti videro <\/em><em>in<\/em><em> questa apatia e in questo sconforto sabotaggio e controrivoluzione e, non la crudelt\u00e0 tipica degli idealisti sicuri di stare nel giusto, decisero di lasciare che la fame facesse il suo corso con l&#8217;idea che questo avrebbe dato una lezione ai contadini<\/em>.<\/p>\n<p style=\"text-align: justify;\"><em>I soccorsi furono distribuiti con parsimonia alle aziende agricolo collettive, ma in quantit\u00e0 inadeguata e cosi in ritardo che ormai si erano perse molte vite. Si lasci\u00f2 che i contadini singoli si arrangiassero da soli; e il pi\u00f9 alto tasso di mortalit\u00e0 tra questa categoria forn\u00ec un argomento molto convincente per confluire nelle aziende collettive.<\/em><\/p>\n<p style=\"text-align: justify;\">La quarta fase del processo consisteva nella frammentazione del popolo ucraino attraverso l&#8217;introduzione in Ucraina di popolazione straniera e, allo stesso tempo, la dispersione degli ucraini in tutta l&#8217;Europa orientale. In questo modo, l&#8217;unit\u00e0 etnica sarebbe stata distrutta e le nazionalit\u00e0 mescolate. Tra il 1920 e il 1939 la percentuale della popolazione di etnia ucraina in Ucraina pass\u00f2 dall&#8217;80% al 63% (9).<\/p>\n<p style=\"text-align: justify;\">Di fronte alla carestia e alla deportazione, la popolazione ucraina era diminuita in termini assoluti passando da 23,2 a 19,6 milioni, mentre la popolazione non ucraina era aumentata di 5,6 milioni. Se si considera che l&#8217;Ucraina un tempo aveva il pi\u00f9 alto tasso d&#8217;incremento demografico d&#8217;Europa, circa 800 unit\u00e0 l&#8217;anno, \u00e8 facile vedere che la politica russa era stata portata a termine.<\/p>\n<p style=\"text-align: justify;\">Sono state queste le tappe principali della distruzione sistematica della nazione ucraina, nel suo progressivo assorbimento nella nuova nazione sovietica. Significativamente, non c&#8217;\u00e8 stato alcun tentativo di annientamento totale, che fu il metodo adottato nell&#8217;aggressione tedesca agli ebrei. Eppure, se il programma sovietico ha pieno successo, se si riescono ad eliminare l&#8217;intellighenzia, i sacerdoti e i contadini, l&#8217;Ucraina morir\u00e0 come se fosse stato ucciso ogni singolo ucraino, perch\u00e9 avr\u00e0 perso quella sua parte che ha conservato e sviluppato la sua cultura, le sue credenze, le sue opinioni comuni, che l&#8217;avevano condotta e gli avevano dato un&#8217;anima, che, in breve, l&#8217;ha resa una nazione piuttosto che una moltitudine di persone.<\/p>\n<p style=\"text-align: justify;\">Non sono per\u00f2 mancate le stragi indiscriminate &#8211; semplicemente non sono state parti integranti del piano, ma solo varianti accidentali. In migliaia sono stati giustiziati, in diverse migliaia sono stati risucchiati dalla morte certa dei campi di lavoro siberiani. La citt\u00e0 di Vinnitsa potrebbe essere tranquillamente definita come la Dachau ucraina.<\/p>\n<p style=\"text-align: justify;\">In 91 fosse vi giacciono i corpi di 9.432 vittime della tirannia sovietica, fucilate dall&#8217;Nkvd durante il 1937 o il 1938. Tra le lapidi dei cimiteri veri e propri, nei boschi, con spaventosa ironia, sotto una pista da ballo, i corpi sono rimasti dal 1937 fino alla loro scoperta da parte dei tedeschi nel 1943. Molte delle vittime erano state dichiarate esiliate in Siberia dai sovietici.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Ucraina ha anche la sua Lidice, la citt\u00e0 di Zavadka, distrutta dai satelliti polacchi del Cremlino nel 1946 (10). Per tre volte la Seconda Divisione polacca attacc\u00f2 la citt\u00e0, uccidendo uomini, donne e bambini, bruciando le case e sequestrando il bestiame. Durante il secondo raid, il comandante comunista disse a quel che era rimasto della popolazione della citt\u00e0: \u00abLa stessa sorte toccher\u00e0 a chiunque rifiuti di andare in Ucraina. Ordino pertanto che entro tre giorni il villaggio sia evacuato; altrimenti passer\u00f2 per le armi ciascuno di voi\u00bb [da Walter Dushnyck <em>Death and devastation the Curzon line, <\/em>New York, Committee against Mass Expulsion in cooperation with the Ukrainian Congress Committee of America, 1948].<\/p>\n<p style=\"text-align: justify;\">Quando la citt\u00e0 fu finalmente evacuata con la forza, rimanevano solo 4 uomini tra i 78 sopravvissuti. Durante il marzo dello stesso anno, altre 9 citt\u00e0 ucraine furono assaltate dalla stessa unit\u00e0 comunista e, pi\u00f9 o meno, ricevettero lo stesso trattamento. Quanto si \u00e8 detto sin qui non riguarda solo l&#8217;Ucraina. Il piano messo in atto dai sovietici in quel paese \u00e8 stato e continua ad essere ripetuto.<\/p>\n<p style=\"text-align: justify;\">Esso \u00e8 una componente fondamentale del programma sovietico di espansione poich\u00e9 offre il modo pi\u00f9 rapido per far sgorgare l&#8217;unit\u00e0 dalla diversit\u00e0 di culture e nazioni di cui si compone l&#8217;Impero sovietico. Il fatto che questo metodo porti con s\u00e9 indescrivibili soffierete per milioni di persone non li ha fatti desistere dalla strada imboccata.<\/p>\n<p style=\"text-align: justify;\">Anche solo per questa sofferenza umana, si dovrebbe condannare come crimine questa via d&#8217;unificazione. Ma c&#8217;\u00e8 di pi\u00f9 della sola sofferenza. Non si tratta semplicemente di un caso di strage di massa [<em>mass murder<\/em>] Si tratta di un caso genocidio, della distruzione non solo dei singoli ma di una cultura e di una nazione. Anche se fosse stato possibile realizzarla senza sofferenze dovremmo essere portati a condannarla, perch\u00e9 la comunit\u00e0 di spiriti, l&#8217;unit\u00e0 d&#8217;intenti, di lingua e d\u00ec costumi che formano ci\u00f2 che chiamano nazione costituiscono uno dei pi\u00f9 importanti mezzi di civilizzazione e progresso a nostra disposizione.<\/p>\n<p style=\"text-align: justify;\">\u00c8 vero che le nazioni s\u00ec mescolano e Formano nuove nazioni &#8211; un esempio di questo processo ci viene dal nostro paese (11),- ma tale mescolanza consiste nel mettere in comune i vantaggi delle qualit\u00e0 migliori possedute da ciascuna cultura. Ed \u00e8 in questo modo che il mondo progredisce. E poi, a prescindere dalle importantissime questioni relative alla sofferenza umane e ai diritti umani, quel che \u00e8 riprovevole nei piani sovietici \u00e8 la criminale distruzione della civilt\u00e0 e della cultura. Perch\u00e9 l&#8217;unit\u00e0 nazionale sovietica non s\u00ec sta creando attraverso l&#8217;unificazione di opinioni e culture, bens\u00ec mediante la distruzione completa di tutte le culture e di tutte le opinioni eccetto una &#8211; quella sovietica.<\/p>\n<p style=\"text-align: justify;\"><strong>Note<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(*) <\/strong>Raphael Lemkin nacque il 24 giugno 1900 da una famiglia ebraica di agricoltori di Bezwodne, un villaggio nei pressi dell\u2019antica citt\u00e0 di Volkovysk, nella regione di Grondo. All\u2019inizio degli anni Venti Lemkin s\u2019iscrisse all\u2019Universit\u00e0 Jan Kazimierz di leopoli \u2013 un\u2019istituzione polacca, all\u2019epoca \u2013 per studiare in un primo momento linguistica e, successivamente, legge. Il passaggio alle materie giuridiche fu stimolato dall\u2019assassinio nel 1921, di Talaat Pasha, uno dei leader turchi responsabile dei massacri degli armeni. Lemkin giudic\u00f2 l\u2019atto dello studente armeno Sogomon Tehlirian una pena giusta per il crimine commesso ma costat\u00f2 con rammarico che non esisteva alcuna norma internazionale che punisse i responsabili di atti di distruzione di massa. Egli si propose quindi di dedicarsi&nbsp; all\u2019istituzione di una tale normativa<\/p>\n<p style=\"text-align: justify;\"><strong>1)<\/strong> Versi di Volodymyr Sosiura aggiunto a matita. Sosiura scrisse il componimento nel 1944, durame la guerra sovietico-tedesca. In principio le autorit\u00e0 lodarono la poesia per il suo spirito nazionale ma, nel 1948, lo condannarono come nazionalismo ucraino.<br \/>\n<strong>2) <\/strong>prima della parola \u00abCi\u00f2\u00bb [\u00abWhat\u00bb] \u00e8 stato aggiunto a matita \u00abCominciare da qui\u00bb [\u00abBegin here\u00bb].<br \/>\n<strong>3)<\/strong> All\u2019epoca dello scritto di Lemkin, negli anni Cinquanta, la popolazione dell\u2019Ucraina era di circa quaranta milioni di persone.<br \/>\n<strong>4)<\/strong> la carta istitutiva delle nazioni Unite fu firmata alla Conferenza tenutasi il 25 e 26 aprile 1945 dai delegati di cinquanta nazioni, compresa l\u2019Urss e la repubblica socialista sovietica di Ucraina.<br \/>\n<strong>5) <\/strong>La Linea Curzon fu proposta dagli inglesi, dopo la prima guerra mondiale, come linea di confine tra la Polonia e lo stato sovietico. Alla fine essa venne utilizzata come base per tracciare il confine tra Polonia e Urss nel secondo dopoguerra. Il confine lasciava una consistente minoranza ucraina all\u2019interno dello stato polacco.<br \/>\n<strong>6) <\/strong>II 28 maggio 1934 il deputato di New York Hamilton Fish present\u00f2 una Risoluzione <em>(H. Res. 309) <\/em>alla camera dei Rappresentanti. II documento affermava che \u00abdiversi milioni di cittadini della Repubblica socialista sovietica ucraina sono morti di fame nel 1932 e nel 1933\u00bb e pi\u00f9 avanti proponeva:<br \/>\n\u00abche la Camera dei Rappresentanti esprima la sua compassione per tutti coloro che hanno patito per la grande carestia in Ucraina, che ha causato miseria, sofferenza e morte a milioni di cittadini ucraini pacifici e rispettosi della legge: che [&#8230;] il Governo dell&#8217;Unione delle Repubbliche Socialiste Solletiche [&#8230;| compia passi immediati ed efficaci per alleviare le conseguenze terribili derivanti da questa carestia; che [&#8230;] il Governo dell&#8217;Unione delle Repubbliche Socialiste Sovietiche [&#8230;] non ostacoli in alcun modo i cittadini americani che cercano di inviare aiuti nelle regioni dell\u2019Ucraina colpite dalla carestia sotto forma di denaro, generi alimentari e beni di prima necessit\u00e0\u00bb. La risoluzione fu inviata alla Commissione per le relazioni estere, \u00e8 riprodotta in \u00abThe Ukrainian Quarterly\u00bb, 1978, 4, pp, 416-41 7.<br \/>\n<strong>7)<\/strong> Nel testo il nome \u00e8 \u00abKossies\u00bb, un evidente errore di ortografia. Slanislav Kossior non era uno scrittore ma un segretario generale del Comitato centrale del Partito comunista (bolscevico) dell&#8217;Ucraina &#8211; il capo politico della repubblica. II numero del 2 dicembre dell&#8217; \u00abIzvestia\u00bb contiene un discorso di tre pagine di Kosior. intitolato <em>Itogi i blizhaishie zadachi provedeniia natsional\u2019noi politiki na Ucraine <\/em>[<em>Conseguenze e compiti immediati nella realizzazione della politica nazionale in <\/em>Ucraina] La citazione esatta, presa da una risoluzione approvata dal plenum congiunto del Comitato centrale e del Comitato centrale di controllo del Partito comunista (bolscevico) dell&#8217;Ucraina, recita: \u00abAl momento attuale, la minaccia principale in Ucraina viene dal locale nazionalismo ucraino, , legato a interessi imperialistici\u00bb.<em><br \/>\n<\/em><strong>8)<\/strong> Il riferimento \u00e8 a William Henry Chamberlain, erroneamente identificato nel testo con C. Henry Chamberlain.<br \/>\n<strong>9)<\/strong> Non ci fu alcun censimentonel 1920. Si tratta probabilmente di un errore di battitura per 1926, anno del primo censimento sovietico. Nel 1926 c\u2019erano 22,9 milioni di cittadini di etnia ucraina nella Repubblica socialista sovietica ucraina, l\u201981% della popolazione. I dati falsificati del 1939 riportano la cifra di 23,3 milioni di ucraini, circa il 75% dei 31 milioni di abitanti della Rss ucraina.<br \/>\n<strong>10) <\/strong>II 10 giugno 1942 172 uomini maggiori di sedici anni furono uccisi, le donne e i bambini vennero deportati e il villaggio di Lidice fu raso al suolo come rappresaglia per l&#8217;omicidio del dittatore nazista della Moravia, R. Heydrich. Si trattava della cittadina Zavadka Morokhivs&#8217;ka,nella contea di Stanits&#8217;ky, nella regione Lemkishcyna: ora porta il nome di Zawadka-Morochowska e si trova nella contesa di Sanok, in Polonia<br \/>\n<strong>11) <\/strong>Lemkin fa riferimento agli Stati Uniti<\/p>\n<p style=\"text-align: justify;\">_______________________<\/p>\n<p style=\"text-align: justify;\"><strong>Sullo stesso argomento:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=43242\" data-wplink-edit=\"true\">&#8220;Raccolto di dolore&#8221;, storia della carestia terroristica (Ucraina \u201932)<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=43236\">Ucraina: voci dal silenzio di uno sterminio<\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=2203\" data-wplink-edit=\"true\">La carestia terroristica in Ucraina (1932)<\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=2204\" data-wplink-edit=\"true\">La dekulakizzazione in URSS nei rapporti della polizia<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Video:&nbsp;<\/strong><a href=\"https:\/\/www.youtube.com\/watch?v=fe5HsMEZzCU\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.youtube.com\/watch?v=fe5HsMEZzCU<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contemporanea n.3 luglio 2009 &nbsp;Sosyura \u00abAma l\u2019Ucraina\u00bb Non puoi amare altri popoli se non ami l\u2019Ucraina (1)<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29649,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,84],"tags":[147],"class_list":["post-3484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filosofia-del-comunismo","category-urss","tag-ucraina","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raphael Lemkin (*) Il genocidio sovietico in Ucraina - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raphael Lemkin (*) Il genocidio sovietico in Ucraina - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-21T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-13T08:06:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/Ucraina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"281\" \/>\n\t<meta property=\"og:image:height\" content=\"179\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Raphael Lemkin (*) Il genocidio sovietico in Ucraina\",\"datePublished\":\"2009-10-21T22:00:00+00:00\",\"dateModified\":\"2019-06-13T08:06:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/\"},\"wordCount\":3188,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/Ucraina.jpg\",\"keywords\":[\"Ucraina\"],\"articleSection\":[\"Comunismo\",\"URSS\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/\",\"name\":\"Raphael Lemkin (*) Il genocidio sovietico in Ucraina - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/Ucraina.jpg\",\"datePublished\":\"2009-10-21T22:00:00+00:00\",\"dateModified\":\"2019-06-13T08:06:35+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/Ucraina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/Ucraina.jpg\",\"width\":281,\"height\":179},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raphael Lemkin (*) Il genocidio sovietico in Ucraina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raphael Lemkin (*) Il genocidio sovietico in Ucraina - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/","og_locale":"it_IT","og_type":"article","og_title":"Raphael Lemkin (*) Il genocidio sovietico in Ucraina - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-10-21T22:00:00+00:00","article_modified_time":"2019-06-13T08:06:35+00:00","og_image":[{"width":281,"height":179,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/Ucraina.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"16 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Raphael Lemkin (*) Il genocidio sovietico in Ucraina","datePublished":"2009-10-21T22:00:00+00:00","dateModified":"2019-06-13T08:06:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/"},"wordCount":3188,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/Ucraina.jpg","keywords":["Ucraina"],"articleSection":["Comunismo","URSS"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/","name":"Raphael Lemkin (*) Il genocidio sovietico in Ucraina - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/Ucraina.jpg","datePublished":"2009-10-21T22:00:00+00:00","dateModified":"2019-06-13T08:06:35+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/Ucraina.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/Ucraina.jpg","width":281,"height":179},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/raphael-lemkin-il-genocidio-sovietico-in-ucraina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Raphael Lemkin (*) Il genocidio sovietico in Ucraina"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3484"}],"version-history":[{"count":6,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3484\/revisions"}],"predecessor-version":[{"id":43254,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3484\/revisions\/43254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29649"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}