{"id":3472,"date":"2009-10-15T00:00:00","date_gmt":"2009-10-14T22:00:00","guid":{"rendered":""},"modified":"2015-11-13T13:19:39","modified_gmt":"2015-11-13T12:19:39","slug":"i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/","title":{"rendered":"I 60 anni della Repubblica popolare cinese: il Partito contro il popolo"},"content":{"rendered":"<div style=\"text-align: center;\"><span class=\"articolodossier\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/60_pcc.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-27740\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/60_pcc.jpg\" alt=\"60_pcc\" width=\"227\" height=\"171\" \/><\/a>Asianews<\/strong> 29 settembre 2009<\/span><\/div>\n<p style=\"text-align: justify;\"><em>Le cerimonie del 1\u00b0 ottobre vogliono celebrare la grandezza della Cina e la supremazia del partito comunista. Ma i pechinesi sono \u201cinvitati\u201d a rimanere in casa. La paranoia della sicurezza e 800 mila persone reclutate per spiare, investigare, controllare. Studi storici obbiettivi sui 60 anni sono proibiti. Prima parte di un dossier sulla Cina a 60 anni dalla fondazione della Repubblica popolare cinese.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Bernardo Cervellera<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Roma (AsiaNews) &#8211; Il 1\u00b0 ottobre 2009 la Repubblica popolare cinese compie 60 anni dalla sua fondazione. Per la cultura dell\u2019estremo oriente, compiere 60 anni riveste uno speciale significato: i sei decenni racchiudono un ciclo completo del calendario lunare e sono considerati il momento in cui un uomo raggiunge la piena maturit\u00e0. Essi sono pure un tempo per riflettere sui risultati ottenuti e un augurio per nuove sfide future.<\/div>\n<p style=\"text-align: justify;\">Noi ci auguriamo che anche i 60 anni della Cina popolare abbiano questo spirito, ma da ci\u00f2 che vediamo, la festa rischia di essere usata solo per dare un\u2019immagine grandiosa del potere di Pechino, nascondendo i problemi. Un po\u2019 come per le Olimpiadi dello scorso anno, anche le celebrazioni in programma dal 1\u00b0 ottobre vogliono mostrare al mondo la maturit\u00e0 raggiunta dalla Cina sotto la guida del Partito comunista cinese (Pcc), gli splendidi risultati economici, che la vedono come una superpotenza, il suo potere disteso ormai su tutta l\u2019Asia e il mondo.<\/p>\n<p style=\"text-align: justify;\">Mancano ormai pochi giorni al 1\u00b0 ottobre, ma da quello che si sa, tutta la macchina pubblicitaria del Partito \u00e8 all\u2019opera per rendere indimenticabile l\u2019avvenimento. Ma indimenticabile per chi? Le celebrazioni sembrano infatti puntare\u00a0 soprattutto sull\u2019esibizione della forza militare del Partito, ma riguarda poco la gente. La cerimonia in piazza Tiananmen prevede un discorso del presidente Hu Jintao ed una mastodontica parata militare che vuole dimostrare quanto avanzati siano gli armamenti e le tecnologie missilistiche nel Paese, divenuto un grande esportatore di armi all\u2019estero, verso Paesi come il Sudan e il Myanmar.<\/p>\n<p style=\"text-align: justify;\">Per il resto, la popolazione di Pechino non avr\u00e0 nemmeno la possibilit\u00e0 di ammirare con senso patriottico tutta la parata. Come per le Olimpiadi l\u2019anno scorso, i pechinesi sono \u201cinvitati\u201d a restare in casa. Le persone residenti nell\u2019area di Tiananmen e i viali vicini hanno ricevuto indicazioni di come comportarsi durante la cerimonia: \u201cnon aprire le finestre o i balconi che danno sulla Changan dajie [il viale che incrocia la piazza]\u201d; \u201cnon stare la balcone per guardare la cerimonia\u201d; \u201cnon invitare amici o altre persone\u201d in quella giornata.<\/p>\n<p style=\"text-align: justify;\">Per mostrare la sua potenza, il Pcc elimina sempre la popolazione, timoroso che qualcosa danneggi l\u2019immagine tersa e perfetta che si vuol dare al mondo. Gi\u00e0 nelle settimane prima dell\u2019evento, la sicurezza \u00e8 stata aumentata ovunque nel Paese. Per la capitale, si \u00e8 stabilito che 7 province e regioni attorno a Pechino costruiscano un filtro per controllare l\u2019entrata e l\u2019uscita dalla citt\u00e0, prevenendo possibili dimostrazioni. Gli abitanti di Pechino hanno ricevuto il divieto di far volare nel cielo piccioni addomesticati, aquiloni, palloni.<\/p>\n<p style=\"text-align: justify;\">Un esercito di oltre 800 mila persone \u00e8 stato reclutato per spiare il vicinato e lavorare in stretto contatto con la polizia per denunciare ogni irregolarit\u00e0 o crimine. Per evitare possibili rischi di incendi \u2013 e bombe molotov \u2013 le stazioni di servizio non devono servire benzina in recipienti di plastica o bottiglie. Fino a dopo il 1\u00b0 ottobre \u00e8 proibito perfino vendere coltelli, anche quelli da cucina, dopo che 2 uomini &#8211; in due diversi episodi &#8211; hanno accoltellato alcuni passanti.<\/p>\n<p style=\"text-align: justify;\">La paranoia della sicurezza \u2013 accresciuta dalle minacce di scontri interetnici dopo le rivolte nel Xinjiang\u00a0 &#8211; domina ogni aspetto. Per questo il Pcc ha decretato che nel resto della Cina non vi siano altre parate, concentrando le forze dell\u2019ordine nella capitale.<\/p>\n<p style=\"text-align: justify;\">La paranoia della sicurezza \u00e8 il sintomo di una malattia pi\u00f9 profonda: il Partito non \u00e8 amato dalla sua popolazione e se vi sono ancora 76 milioni di cinesi iscritti (cooptati) questo \u00e8 solo per un motivo: trarre dall\u2019appartenenza a questa oligarchia politica ed economica il massimo dei vantaggi. A Shanghai, Pechino, Guangzhou \u00e8 facile incontrare giovani rampanti che ti confessano con candore il loro disprezzo per la leadership e per il Partito, ma che sono iscritti \u201cper soldi\u201d.<\/p>\n<p style=\"text-align: justify;\">Il motivo per cui si entra nel Partito sta proprio nel fatto che ai membri viene dato un pacchetto di <em>benefits <\/em>da cui \u00e8 escluso il resto della popolazione: un lavoro stabile, pensione, facili possibilit\u00e0 di viaggiare, un appartamento moderno e soprattutto una protezione legale e sociale se per caso hai dei guai con la giustizia. Ormai il Pcc, da avanguardia sociale, \u00e8 divenuto oppressore; i suoi membri sono un\u2019oligarchia che usa l\u2019economia per mantenere il dominio politico e usa quest\u2019ultimo per accrescere i suoi benefici economici.<\/p>\n<p style=\"text-align: justify;\">Come tutto ci\u00f2 sia avvenuto, fa parte di una lettura storica che in Cina nessuno osa fare con onest\u00e0 almeno scientifica.\u00a0 Coloro che hanno osato si trovano agli arresti domiciliari o vengono estromessi dalle istituzioni.<\/p>\n<p style=\"text-align: justify;\">L\u2019ultimo in ordine di tempo \u00e8 Xiao Jiansheng, 54 anni, dell\u2019Hunan. Per 20 anni ha fatto ricerche sulla storia e la cultura cinese, producendo un volume di 450 pagine dal titolo <em>Rivisitare la storia della Cina<\/em>. Sebbene due anni fa l\u2019Accademia delle Scienze sociali gli avesse dato l\u2019ok per la pubblicazione, le autorit\u00e0 glielo hanno negato. Lui si \u00e8 rivolto ad Hong Kong e le autorit\u00e0 lo hanno diffidato dal farlo anche ad Hong Kong. Il motivo?<\/p>\n<p style=\"text-align: justify;\">Il libro critica la concezione del potere assoluto presente nella Cina tradizionale, che la leadership ha assunto in proprio, celebrando la supremazia del Partito comunista cinese. Il volume di Xiao \u00e8 visto come un attentato anti-patriottico alle celebrazioni del 60\u00b0 anniversario della Repubblica popolare. <em>(Fine prima parte).<\/em><\/p>\n<p style=\"text-align: center;\">* * *<\/p>\n<p style=\"text-align: center;\"><strong>Asianews<\/strong> 29 settembre 2009<\/p>\n<p style=\"text-align: center;\"><strong>I 60 anni della Rpc: Da Mao ad oggi, la corruzione al potere<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>La storia del comunismo in Cina \u00e8 una delle pi\u00f9 orribili. Fra purghe ideologiche, carestie, repressione, non si \u00e8 mai data voce alla democrazia (la quinta modernizzazione). Deng Xiaoping ha fatto della supremazia del Partito l\u2019ideale a cui sacrificare tutta la societ\u00e0, aprendo alla valanga del sopruso e della corruzione. I 100 mila \u201cincidenti di massa\u201d in un anno dicono che il popolo vuole contare. La societ\u00e0 civile \u00e8 l\u2019unica speranza per la stabilit\u00e0 della Cina. Seconda parte di un dossier dedicato ai 60 anni della fondazione della Repubblica popolare cinese.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Bernardo Cervellera<\/strong><\/p>\n<p style=\"text-align: justify;\">Roma (AsiaNews) \u2013 La Cina grande e potente che vuole celebrare i suoi 60 anni il 1\u00b0 ottobre non vuole fare i conti con la sua storia. Molti vorrebbero verificare quanto degli ideali del \u201949 \u00e8 stato realizzato e quanto costituisce un tradimento.<\/p>\n<p style=\"text-align: justify;\">Zhu Houze, che prima della liberazione era un membro sotterraneo del Partito comunista a Guiyang, intervistato dal <em>South China Morning Post<\/em> ( 22\/09\/2009) ricorda cos\u00ec la fondazione della Repubblica salutata col discorso di Mao Zedong in piazza Tiananmen: \u201cPensavamo che saremmo stati subito liberi e avremmo cominciato a costruire un Paese nuovo, libero, democratico e prospero\u201d. Negli anni \u201980 Zhu \u00e8 stato anche ministro del dipartimento di propaganda del Comitato centrale, ma ormai \u00e8 uno dei \u201cdelusi\u201d dagli sviluppi del Partito. Vale la pena ripercorrere alcune tappe dei \u201csuccessi\u201d, ma anche dei \u201cfallimenti\u201d di questi 60 anni.<\/p>\n<p style=\"text-align: justify;\">Considerando soltanto gli aspetti economici e politici, si pu\u00f2 dire che nei primi anni il Partito si guadagna la stima della popolazione: niente corruzione o divisioni come ai tempi di Chiang Kai-shek; inflazione bassissima; industria pesante ricostruita (su modello sovietico); agricoltura in abbondante produzione. Ma la caparbiet\u00e0 di Mao e la sua incompetenza economica portano al Grande Balzo in avanti (1958-1961) che causa la morte per fame di circa 50 milioni di persone. Le storie della gente parlano di contadini disperati nella ricerca di cibo; di gente che muore ai lati delle strade; di affamati che si cibano delle carni dei cadaveri.<\/p>\n<p style=\"text-align: justify;\">Per frenare le critiche del partito contro di lui (che gli vogliono togliere il potere), Mao lancia nel \u201966 la Rivoluzione culturale, che dura fino alla sua morte, nel 1976. La Rivoluzione culturale, che viene ancora oggi ricordata come il periodo del \u201cgrande caos\u201d, divide la societ\u00e0, distrugge famiglie, uccide milioni di persone, divise fra \u201cgiovani\u201d e \u201cvecchi\u201d del Partito; Guardie rosse e esercito; genitori e figli.<\/p>\n<p style=\"text-align: justify;\">Le aperture di Deng Xiaoping, alla fine degli anni \u201970, considerate l\u2019ide brillante del \u201criformatore\u201d, sono state in realt\u00e0 una necessit\u00e0. Per salvare la Cina dalla fame e rialzare le sorti di un\u2019economia distrutta, Deng ha aperto il Paese agli investimenti stranieri e ha cominciato quelle riforme economiche che hanno portato la Cina agli splendori attuali.<\/p>\n<p style=\"text-align: justify;\">Il problema con Deng \u00e8 che le sue modernizzazioni (dell\u2019esercito, della scienza, dell\u2019agricoltura e dell\u2019industria) mancano di una quinta: la democrazia. A causa di ci\u00f2, il Paese gode attualmente di uno status invidiabile dal punto di vista economico (in generale), ma continua ad essere un paria dal punto di vista dei diritti umani. Ancora dopo 30 anni dalle sue riforme, il Paese infatti non gode di libert\u00e0 di stampa, di associazione, di parola, di religione; i poteri esecutivo, giudiziario, legislativo sono tutti sotto il controllo del Pcc.<\/p>\n<p style=\"text-align: justify;\"><strong>La societ\u00e0 cinese sacrificata al Partito<\/strong><\/p>\n<p style=\"text-align: justify;\">Bao Tong \u00e8 un ex leader del Partito, caduto in disgrazia per aver simpatizzato con i giovani di Tiananmen nell\u201989. Ha subito per questo 7 anni di carcere e tuttora vive agli arresti domiciliari. In una lunga conversazione sulle modernizzazioni di Deng (in <em>Radio Free Asia<\/em>, 5\/1\/2009), egli fa notare che si deve proprio a Deng Xiaoping un cambiamento epocale rispetto a Mao.<\/p>\n<p style=\"text-align: justify;\">Pur con tutta la sua enfasi imperiale, il Grande timoniere aveva a cuore \u201cil socialismo\u201d come ideale del partito e del Paese. Invece Deng afferma che tutto in Cina deve servire a \u201cmantenere la leadership del Partito\u201d. Difendere il partito diviene la cosa pi\u00f9 importante; difendere i diritti dei cittadini diviene un fatto secondario. In tal modo \u2013 Bao Tong spiega \u2013 l\u2019esistenza del Pcc diviene lo stesso ideale a cui sacrificare la societ\u00e0 cinese.<\/p>\n<p style=\"text-align: justify;\">La Cina di Hu Jintao continua a favorire e migliorare l\u2019economia in modo sorprendente: Pechino sembra aver perfino superato prima di tutti la grande crisi economica (se non si contano i circa 60 milioni di disoccupati). Ma la stabilit\u00e0 della societ\u00e0 e l\u2019egemonia del partito rimangono i punti fermi anche per la Quarta generazione della leadership.<\/p>\n<p style=\"text-align: justify;\"><strong>I fallimenti e la corruzione<\/strong><\/p>\n<p style=\"text-align: justify;\">All\u2019interno del Partito vi sono richieste di maggior democrazia e di riforme politiche. Lo stesso Zhu Houze, ora 78enne, insieme ad altri membri in pensione ha scritto varie volte alla leadership criticando la mancanza di controllo nei poteri del Partito, che genera la piaga della corruzione, domandando democrazia e una stampa libera. Ma non ha mai ricevuto alcuna risposta. \u201cDobbiamo superare \u2013 dice Zhu \u2013 la percezione ristretta del solo sviluppo economico del mercato e del mantenimento del partito unico. Dobbiamo iniziare la riforma del sistema politico\u201d.<\/p>\n<p style=\"text-align: justify;\">All\u2019ultimo plenum del Comitato centrale (15-18 settembre 2009) si doveva parlare della lotta alla corruzione e della democrazia interna nel Pcc. Ma non \u00e8 emersa alcuna indicazione concreta. In compenso, in uno dei tanti incontri per celebrare i 60 anni, Hu Jintao ha predicato sul suo slogan preferito: \u201cl\u2019armonia fra gruppi etnici e religiosi\u201d, \u201crafforzare la solidariet\u00e0\u201d \u201crisolvere le contraddizioni\u201d, \u201cportare avanti la democrazia\u201d. Ma ha subito precisato che non si tratta di \u201ccopiare i modelli occidentali\u201d, bens\u00ec di attuare un sistema con \u201ccaratteristiche cinesi\u201d, in cui \u00e8 sempre salva la \u201csupremazia del partito comunista\u201d.<\/p>\n<p style=\"text-align: justify;\">Eppure davanti agli occhi di tutti sono evidenti i grandi successi, ma anche i grandi fallimenti della Cina: una societ\u00e0 in cui lo Stato controlla oltre il 70% dell\u2019economia, frenando la creativit\u00e0 e garantendo promozioni e favori senza alcun merito; rampante corruzione che arriva a sottrarre allo Stato fino al 3% del Prodotto interno lordo; mancanza di sostegno sociale a poveri, pensionati, disoccupati; strutture sanitarie ed educative allo sfacelo; genitori che mettono in vendita i loro organi per pagare l\u2019universit\u00e0 ai figli; inquinamento, soprusi, sequestri di terre e di case da parte di membri del Partito. A causa di tutto ci\u00f2, ormai il Partito viene visto come sinonimo di \u201ccorruzione\u201d.<\/p>\n<p style=\"text-align: justify;\">Un fatto citato da <em>Asia Times<\/em> (23 settembre 2009) racconta che una bambina di 6 anni a Guangzhou, rispondendo alla domanda \u201cCosa vuoi fare da grande?\u201d ha detto: \u201cVoglio diventare un funzionario corrotto. La mamma dice sempre che un funzionario corrotto pu\u00f2 avere molte, molte cose a casa sua\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Gli \u201cincidenti di massa\u201d e la societ\u00e0 civile<\/strong><\/p>\n<p style=\"text-align: justify;\">Diversi analisti si domandano se una Cina cos\u00ec, gigantesca nelle prestazioni economiche, ma zoppa nelle riforme politiche, potr\u00e0 continuare, o se prima o poi sar\u00e0 cos\u00ec vulnerabile da soccombere.<\/p>\n<p style=\"text-align: justify;\">Gi\u00e0 oggi i segni di inquietudine aumentano di pari passo con gli apparenti risultati economici.<\/p>\n<p style=\"text-align: justify;\">Secondo le ultime stime apparse sulla stampa cinese, lo scorso anno vi sono stati oltre 100 mila \u201cincidenti di massa\u201d (almeno uno ogni 4-5 minuti), ossia proteste di centinaia o migliaia di persone che chiedono giustizia per i soprusi, o per paghe non pagate, o per avvelenamenti o sequestri di terreni. La cifra \u00e8 superiore del 16% ai casi ufficialmente registrati dal Ministero della pubblica sicurezza nel 2006 (87 mila incidenti). Tali \u201cincidenti\u201d hanno anche portato a incendi delle sedi di partito, delle sedi di polizia, a scontri a fuoco fra polizia e manifestanti, a morti su entrambi i fronti.<\/p>\n<p style=\"text-align: justify;\">Il Partito continua\u00a0 a predicare\u00a0 \u201cla stabilit\u00e0 innanzi a tutto\u201d ed \u00e8 pronto \u2013 come nei giorni precedenti alla festa dei 60 anni \u2013 ad arrestare persone (circa 6500), disseminare carri armati, spie e poliziotti.<\/p>\n<p style=\"text-align: justify;\">Per salvare la sua supremazia, il Partito continua a far morire il popolo, proprio quel \u201cpopolo\u201d a cui appartiene la \u201cRepubblica popolare cinese\u201d fondata 60 anni fa.<\/p>\n<p style=\"text-align: justify;\">Ma il tempo non passa invano. Il fatto pi\u00f9 sorprendente \u00e8 che in tutti questi decenni \u00e8 cresciuto proprio \u201cfra il popolo\u201d una societ\u00e0 civile sempre pi\u00f9 attenta ai propri diritti. Fra di loro vi sono attivisti, giornalisti, avvocati, consumatori, madri, impiegati, imprenditori, burocrati. Nella stretta non violenza essi denunciano le malefatte dei quadri del partito; si appellano per la salute dei loro figli avvelenati (come nel caso del latte alla melamina); difendono i loro diritti sulla terra e sulla propriet\u00e0; affermano il diritto alla libert\u00e0 religiosa; esigono di poter votare per esprimere la loro preferenza per uno o l\u2019altro leader.<\/p>\n<p style=\"text-align: justify;\">Secondo Bao Tong, la riforma della societ\u00e0 cinese sar\u00e0 compiuta da questo \u201cmovimento per i diritti civili\u201d. \u201cSe la gente pu\u00f2 difendere i loro diritti e viene dato loro ci\u00f2 che \u00e8 loro dovuto; se lo Stato si piega davanti all\u2019opinione pubblica e i funzionari si mettono a servirla; se la gente pu\u00f2 verificare il lavoro dei burocrati, che gettano via il loro cosiddetto \u2018diritto divino\u2019 di governare; allora c\u2019\u00e8 speranza per la Cina\u2026 Le speranze per la Cina si basano su un pacifico, pronto, persistente movimento per i diritti civili, che user\u00e0 l\u2019attivismo per attuare la Costituzione e salvare questa nazione e il suo popolo\u201d. (Fine seconda parte).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asianews 29 settembre 2009 Le cerimonie del 1\u00b0 ottobre vogliono celebrare la grandezza della Cina e la supremazia del partito comunista. Ma i pechinesi sono \u201cinvitati\u201d a rimanere in casa. La paranoia della sicurezza e 800 mila persone reclutate per spiare, investigare, controllare. Studi storici obbiettivi sui 60 anni sono proibiti. Prima parte di un &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27740,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,32,108],"tags":[2395],"class_list":["post-3472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cina","category-filosofia-del-comunismo","category-paesi-e-continenti","tag-cina","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I 60 anni della Repubblica popolare cinese: il Partito contro il popolo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I 60 anni della Repubblica popolare cinese: il Partito contro il popolo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-14T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-13T12:19:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/60_pcc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"195\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I 60 anni della Repubblica popolare cinese: il Partito contro il popolo\",\"datePublished\":\"2009-10-14T22:00:00+00:00\",\"dateModified\":\"2015-11-13T12:19:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/\"},\"wordCount\":2431,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/60_pcc.jpg\",\"keywords\":[\"Cina\"],\"articleSection\":[\"Cina\",\"Comunismo\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/\",\"name\":\"I 60 anni della Repubblica popolare cinese: il Partito contro il popolo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/60_pcc.jpg\",\"datePublished\":\"2009-10-14T22:00:00+00:00\",\"dateModified\":\"2015-11-13T12:19:39+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/60_pcc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/60_pcc.jpg\",\"width\":259,\"height\":195},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I 60 anni della Repubblica popolare cinese: il Partito contro il popolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I 60 anni della Repubblica popolare cinese: il Partito contro il popolo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/","og_locale":"it_IT","og_type":"article","og_title":"I 60 anni della Repubblica popolare cinese: il Partito contro il popolo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-10-14T22:00:00+00:00","article_modified_time":"2015-11-13T12:19:39+00:00","og_image":[{"width":259,"height":195,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/60_pcc.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I 60 anni della Repubblica popolare cinese: il Partito contro il popolo","datePublished":"2009-10-14T22:00:00+00:00","dateModified":"2015-11-13T12:19:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/"},"wordCount":2431,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/60_pcc.jpg","keywords":["Cina"],"articleSection":["Cina","Comunismo","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/","name":"I 60 anni della Repubblica popolare cinese: il Partito contro il popolo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/60_pcc.jpg","datePublished":"2009-10-14T22:00:00+00:00","dateModified":"2015-11-13T12:19:39+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/60_pcc.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/10\/60_pcc.jpg","width":259,"height":195},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-60-anni-della-repubblica-popolare-cinese-il-partito-contro-il-popolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I 60 anni della Repubblica popolare cinese: il Partito contro il popolo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3472"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3472\/revisions"}],"predecessor-version":[{"id":27741,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3472\/revisions\/27741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27740"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}