{"id":347,"date":"2005-02-01T15:25:30","date_gmt":"2005-02-01T14:25:30","guid":{"rendered":""},"modified":"2025-07-08T15:07:13","modified_gmt":"2025-07-08T13:07:13","slug":"toghe-verdi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/","title":{"rendered":"Toghe verdi"},"content":{"rendered":"\n<p class=\"has-text-align-center\">Il<a href=\"http:\/\/www.ilgiornale.it\/\" target=\"_blank\" rel=\"noreferrer noopener\"> <strong>Giornale<\/strong><\/a><strong> <\/strong>26 gennaio 2005<\/p>\n\n\n\n<p><em>La decisione del GUP di Milano Forleo che ha mandato assolti imputati che organizzavano il reclutamento di terroristi per Ansar al Islam, la componente curda di Al Qaida, \u00e8 del tutto aberrante ma non \u00e8 purtroppo isolata. Viene dopo analoghe sentenze del 2004 con le quali il Tribunale di Napoli aveva mandato liberi membri del GIA e del GSPC algerini \u2013 organizzazioni responsabili di almeno centomila morti nel loro paese \u2013 e il TAR del Lazio aveva revocato l\u2019espulsione dall\u2019Italia del sedicente imam di Carmagnola Mamur, affermando che il possesso e la distribuzione di letteratura di Al Qaida non costituiscono reato trattandosi di \u201cmateriale di notevole interesse storico e sociologico\u201d.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">di <strong>Massimo Introvigne<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/02\/processo.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"299\" height=\"168\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/02\/processo.jpg\" alt=\"\" class=\"wp-image-32819\" style=\"width:385px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<!--more-->\n\n\n\n<p>La decisione del GUP di Milano Forleo che ha mandato assolti imputati che organizzavano il reclutamento di terroristi per Ansar al Islam, la componente curda di Al Qaida, \u00e8 del tutto aberrante ma non \u00e8 purtroppo isolata. Viene dopo analoghe sentenze del 2004 con le quali il Tribunale di Napoli aveva mandato liberi membri del GIA e del GSPC algerini \u2013 organizzazioni responsabili di almeno centomila morti nel loro paese \u2013 e il TAR del Lazio aveva revocato l\u2019espulsione dall\u2019Italia del sedicente imam di Carmagnola Mamur, affermando che il possesso e la distribuzione di letteratura di Al Qaida non costituiscono reato trattandosi di \u201cmateriale di notevole interesse storico e sociologico\u201d.<\/p>\n\n\n\n<p>La dottoressa Forleo ammette che il reclutamento per Ansar al-Islam in Italia \u00e8 iniziato prima dell\u2019invasione americana dell\u2019Irak. Tuttavia \u2013 volendo concludere che non si tratta di terrorismo ma di legittima \u201cresistenza\u201d \u2013 afferma che gi\u00e0 nel 2002 un attacco americano all\u2019Irak poteva essere \u201cnotoriamente previsto come altamente probabile\u201d. Si tratterebbe dunque non di terrorismo ma di legittime attivit\u00e0 compiute &#8221;nell&#8217;ambito di contesti bellici&#8221;, anche se \u201cda forze armate diverse da quelle istituzionali\u201d.<\/p>\n\n\n\n<p>Ma in realt\u00e0 l\u2019articolo 2 della Convenzione internazionale per l\u2019eliminazione dei finanziamenti al terrorismo delle Nazioni Unite (del 1999, di cui pure l\u2019ordinanza milanese dice di tenere conto) definisce come \u201cterrorismo\u201d le attivit\u00e0 non compiute da Stati o da governi che \u201cintendono causare la morte o un grave danno fisico a un civile o comunque a chi non prenda parte attiva alle ostilit\u00e0 in una situazione di conflitto armato\u201d allo scopo \u201cdi intimidire la popolazione, o di costringere un governo a porre in essere o a non porre in essere un determinato comportamento\u201d.<\/p>\n\n\n\n<p>Dunque, per sfuggire alla definizione di terrorismo, si deve provare o che Ansar al Islam \u00e8 una struttura che, per quanto \u201cnon istituzionale\u201d, non \u00e8 privata ma \u00e8 riferibile a un governo, oppure che le sue attivit\u00e0 non colpiscono la popolazione civile. Che Ansar fosse un braccio clandestino del governo di Saddam Hussein lo hanno sempre sostenuto gli americani, ma negato gli stessi terroristi. In ogni caso, prima dell\u2019invasione americana, Ansar era un gruppo non di difesa militare ma inteso semmai a terrorizzare la popolazione civile del suo stesso paese; dopo la caduta di Saddam non \u00e8 pi\u00f9 un gruppo riferibile \u201ca uno Stato o a un governo\u201d e dunque si tratta di terrorismo, tanto pi\u00f9 che taglia teste quasi solo di civili.<\/p>\n\n\n\n<p>\u00c8 poi noto a chiunque legga i giornali che Ansar al Islam non si occupa di terrorismo solo in Irak ma anche altrove: per esempio, secondo i giudici spagnoli, ha partecipato alla preparazione dell\u2019attentato dell\u201911 marzo 2004 a Madrid. Da mesi \u00e8 anche noto, e dichiarato dai suoi stessi leader, che Ansar \u00e8 integrata nella rete di Al Qaida. &nbsp;Pi\u00f9 grave ancora, tuttavia, \u00e8 la decisione di Milano sul piano politico. La frase secondo cui i risultati della nostra intelligence sono \u201cpatologicamente inutilizzabili\u201d dai giudici aumenter\u00e0 la frustrazione delle nostre forze dell\u2019ordine, tra le migliori del mondo quando si tratta di scoprire terroristi.<\/p>\n\n\n\n<p>Ma questi sono poi sistematicamente liberati da \u201ctoghe verdi\u201d afflitte da un anti-americanismo questo s\u00ec patologico, per cui perseguire i terroristi sarebbe \u2013 cos\u00ec recita la sentenza di Milano \u2013 una \u201cingiustificata presa di posizione per una delle forze in campo\u201d nella guerra fra Stati Uniti e terrorismo internazionale, quasi che in questa guerra l\u2019Italia fosse neutrale.<\/p>\n\n\n\n<p>________________<\/p>\n\n\n\n<p><strong>Sullo stesso argomento:&nbsp;<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=348\" target=\"_blank\" rel=\"noreferrer noopener\">Il Gup Forleo sbaglia&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Giornale 26 gennaio 2005 La decisione del GUP di Milano Forleo che ha mandato assolti imputati che organizzavano il reclutamento di terroristi per Ansar al Islam, la componente curda di Al Qaida, \u00e8 del tutto aberrante ma non \u00e8 purtroppo isolata. Viene dopo analoghe sentenze del 2004 con le quali il Tribunale di Napoli &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[1315],"class_list":["post-347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam-in-italia","tag-magistratura","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Toghe verdi - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Toghe verdi. I magistrati mandano assolti imputati che organizzano il reclutamento dei terroristi combattenti dell&#039;Islam\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toghe verdi - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Toghe verdi. I magistrati mandano assolti imputati che organizzano il reclutamento dei terroristi combattenti dell&#039;Islam\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-02-01T14:25:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T13:07:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/02\/processo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"299\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Toghe verdi\",\"datePublished\":\"2005-02-01T14:25:30+00:00\",\"dateModified\":\"2025-07-08T13:07:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/\"},\"wordCount\":674,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/02\\\/processo.jpg\",\"keywords\":[\"magistratura\"],\"articleSection\":[\"Islam in Italia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/\",\"name\":\"Toghe verdi - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/02\\\/processo.jpg\",\"datePublished\":\"2005-02-01T14:25:30+00:00\",\"dateModified\":\"2025-07-08T13:07:13+00:00\",\"description\":\"Toghe verdi. I magistrati mandano assolti imputati che organizzano il reclutamento dei terroristi combattenti dell'Islam\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/02\\\/processo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/02\\\/processo.jpg\",\"width\":299,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/toghe-verdi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toghe verdi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toghe verdi - Rassegna Stampa Cattolica","description":"Toghe verdi. I magistrati mandano assolti imputati che organizzano il reclutamento dei terroristi combattenti dell'Islam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/","og_locale":"it_IT","og_type":"article","og_title":"Toghe verdi - Rassegna Stampa Cattolica","og_description":"Toghe verdi. I magistrati mandano assolti imputati che organizzano il reclutamento dei terroristi combattenti dell'Islam","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-02-01T14:25:30+00:00","article_modified_time":"2025-07-08T13:07:13+00:00","og_image":[{"width":299,"height":168,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/02\/processo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Toghe verdi","datePublished":"2005-02-01T14:25:30+00:00","dateModified":"2025-07-08T13:07:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/"},"wordCount":674,"commentCount":0,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/02\/processo.jpg","keywords":["magistratura"],"articleSection":["Islam in Italia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/","name":"Toghe verdi - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/02\/processo.jpg","datePublished":"2005-02-01T14:25:30+00:00","dateModified":"2025-07-08T13:07:13+00:00","description":"Toghe verdi. I magistrati mandano assolti imputati che organizzano il reclutamento dei terroristi combattenti dell'Islam","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/02\/processo.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/02\/processo.jpg","width":299,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/toghe-verdi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Toghe verdi"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=347"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/347\/revisions"}],"predecessor-version":[{"id":63073,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/347\/revisions\/63073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32819"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}