{"id":3430,"date":"2009-09-17T00:00:00","date_gmt":"2009-09-16T22:00:00","guid":{"rendered":""},"modified":"2015-02-26T12:54:22","modified_gmt":"2015-02-26T11:54:22","slug":"karl-rahner-un-cristianesimo-senza-radici","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/","title":{"rendered":"Karl Rahner, un cristianesimo senza radici"},"content":{"rendered":"<div style=\"text-align: center;\">\n<div id=\"attachment_19995\" style=\"width: 154px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Karl_Rahner.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19995\" class=\"wp-image-19995\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Karl_Rahner.jpg\" alt=\"Karl_Rahner\" width=\"154\" height=\"180\" \/><\/a><p id=\"caption-attachment-19995\" class=\"wp-caption-text\">Karl Rahner<\/p><\/div>\n<p><strong>Radici Cristiane<\/strong> n.47 settembre 2009<\/div>\n<p style=\"text-align: justify;\"><em>Un noto teologo odierno ci chiarisce gli errori fondamentali di uno dei maggiori esponenti di quella teologia eversiva che nel XX secolo ha afflitto la Chiesa al suo interno, e le cui nefaste influenze sono dinanzi agli occhi di tutti noi cattolici.<\/em><\/p>\n<p style=\"text-align: center;\">Fr <strong>Giovanni Cavalcoli<\/strong>, op<\/p>\n<p style=\"text-align: justify;\">Sappiamo come di recente il Papa, parlando dell&#8217;interpretazione degli insegnamenti del Concilio Vaticano II, ha rilevato l&#8217;esistenza di un&#8217; \u201cermeneutica della rottura&#8221;, da lui giudicata fuorviante, e l&#8217;ha contrapposta all&#8217;ermeneutica giusta che ha chiamato &#8220;della continuit\u00e0&#8221;.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Il teologo gesuita Karl Rahner (1904-1984), secondo quanto sta apparendo con sempre maggiore chiarezza da uno studio critico di molte delle sue opere condotto ormai da decenni, \u00e8 forse l&#8217;esponente maggiore di tale ermeneutica della rottura, che da quarantenni ha attirato e continua ad attrarre schiere di teologi e pastori in tutto il mondo.<\/p>\n<p style=\"text-align: justify;\">L&#8217;ermeneutica della rottura \u00e8 una caratteristica di gran parte della teologia di Rahner, una teologia che enfatizza il nuovo, il moderno assolutizzato, fine a se stesso e senza discernimento, in modo tale da portarlo a una rottura con quel passato nel quale si trovano quelle radici cristiane, dalle quali soltanto pu\u00f2 sorgere una sana modernit\u00e0, che non pu\u00f2 essere sana se non in continuit\u00e0 con quelle radici, che contengono valori divini, perenni e immortali.<\/p>\n<p style=\"text-align: justify;\"><strong>La modernit\u00e0 secondo Rahner<\/strong><\/p>\n<p style=\"text-align: justify;\">Rahner ha avuto la buona idea di cercare di ammodernare il cristianesimo, di creare un dialogo del cristianesimo con la modernit\u00e0. Ma ha sbagliato nel concepire il moderno. \u00c8 rimasto vittima del mito idealista tedesco della &#8220;filosofia moderna&#8221;. Non \u00e8 sbagliato di per se aspirare a una filosofia moderna, apprezzare una filosofia moderna, perch\u00e9 si suppone che sia meglio informata, pi\u00f9 sapiente, pi\u00f9 solida e pi\u00f9 intelligente dell&#8217;antica. Esiste un tomismo moderno certo migliore di quello del Sei o Settecento.<\/p>\n<p style=\"text-align: justify;\">L&#8217;errore di Rahner \u00e8 stato quello di optare per una filosofia &#8220;moderna&#8221;, la quale \u00e8 stata s\u00ec moderna nel senso temporale, ma non nel senso qualitativo. Che cosa conta che una filosofia sia temporalmente moderna se poi di fatto ricade in antichi errori pagani, che gi\u00e0 erano stati corretti dalla filosofia cristiana medievale, autrice delle radici cristiane dell&#8217;Europa? Che &#8220;moderno&#8221; \u00e8 quel moderno che distrugge un passato, quale quello delle radici cristiane dell&#8217;Europa, legato all&#8217;immutabilit\u00e0 della parola di Dio, quella parola della quale Cristo ha detto: \u00ab<em>Cielo e terra passeranno, ma le mie parole non passeranno?<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Rahner ha concepito il progresso come rottura, come contraddizione col passalo di una tradizione cristiana sacra e perenne, quella che appunto si chiama sacra Tradizione, sorgente della divina rivelazione insieme con la Sacra Scrittura, come da sempre insegna la Chiesa Cattolica. Questa rottura \u00e8 nata dal fatto che Rahner non si \u00e8 accorto della perenne validit\u00e0 di tale Tradizione, come condizione di vero progresso.<\/p>\n<p style=\"text-align: justify;\">Da che cosa sorge, da quali radici sorge la modernit\u00e0 rahneriana? Da un idealismo come quello che &#8211; per sua espressa dichiarazione &#8211; trae origine da Cartesio, passa per Kant. Fichte. Schelling ed Hegel e giunge ad Heidegger. Ma la tanto declamata novit\u00e0 cartesiana, come dimostrano gli storici del pensiero, in realt\u00e0 riprende le fila dell&#8217;antico pensiero greco presocratico dei parmenidei, degli eraclitei, dei sofisti e degli scettici. Anche la continuit\u00e0 non \u00e8 un valore, se \u00e8 la continuit\u00e0 di un vizio perenne della ragione, come quello che si trascina da Protagora ad Heidegger.<\/p>\n<p style=\"text-align: justify;\"><strong>Continuit\u00e0 ed evoluzione<\/strong><\/p>\n<p style=\"text-align: justify;\">Rahner non ha capito qual \u00e8 la legge dell&#8217;evoluzione dogmatica. La vera evoluzione non \u00e8 rottura, ma esplicitazione nella continuit\u00e0. Non suppone l&#8217;equivocit\u00e0, ma la continuit\u00e0 analogica. Il dogma di Calcedonia contiene la stessa verit\u00e0 della cristologia del Vaticano II, solo che nel corso di quattordici secoli la Chiesa ha conosciuto meglio (e come diversamente avrebbe dovuto accadere?) quel medesimo mistero di Cristo che gi\u00e0 \u00e8 immutabilmente e definitivamente enunciato dal dogma calcedonese.<\/p>\n<p style=\"text-align: justify;\">Rahner ha inteso gli insegnamenti del Concilio come rottura con la Tradizione. Egli distrugge la Tradizione e quindi non opera in nome di una sana modernit\u00e0, ma di un rinnovato modernismo peggiore di quello dei tempi di san Pio X. Per Rahner la verit\u00e0 cristiana comincia col Vaticano II da lui interpretato peraltro in modo modernistico. Prima c&#8217;\u00e8 la barbarie, il vuoto, il nulla. Nessuna radice. Nessuna sorgente, nessuna base o nessun principio. Ma tutto comincia con Cartesio per finire con Heidegger. L&#8217;idealismo tedesco poi si sposa in Rahner con l&#8217;influsso luterano.<\/p>\n<p style=\"text-align: justify;\">Tuttavia uno potrebbe obbiettare: ma in fin dei conti, anche Rahner ha rispetto per il passato e per la Tradizione, giacch\u00e9 anch&#8217;egli, almeno a quanto pare, basa la tua teologia sulla Sacra Scrittura e sulla storia del Cristianesimo e della teologia cattolica.<\/p>\n<p style=\"text-align: justify;\">S\u00ec, ma con quale impostazione? Non con l&#8217;impostazione del vero cattolico, il quale accoglie docilmente e fiduciosamente tutti i pronunciamenti dottrinali o dogmatici del Magistero della Chiesa e dei concili ecumenici, quali pepite d&#8217;oro che appaiono via via nel fiume della storia, ma con l&#8217;atteggiamento tipicamente luterano del &#8220;libero esame&#8221; (con la scusa dell&#8217; &#8220;esegesi storico-critica&#8221;), che di volta in volta, con diversi pretesti, si permette di stabilire in questo preziosissimo e ricchissimo patrimonio della Tradizione, quello che gli garba o non gli garba alla luce di quella che egli chiama &#8220;filosofia moderna&#8221;.<\/p>\n<p style=\"text-align: justify;\">Qual \u00e8 il risultato? Un puro e semplice gnosticismo (come rivelano chiaramente gli studi di don Ennio Innocenti), come \u00e8 stato quello dell&#8217;idealismo tedesco fino ad Heidegger. Dove va finire la fede? Non e pi\u00f9 virt\u00f9 teologale soprannaturale con la quale si accoglie per vero quanto Dio ha rivelato e la Chiesa ci propone a credere, ma la famosa \u00ab<em>esperienza trascendentale aprioristica ed atematica<\/em>\u00bb, ispirata all&#8217;ermetismo, alla teosofia, a Schleiermacher e ad Heidegger. Insomma. un rinnovato gnosticismo, col quale Rahner crede di conoscere Dio e Cristo meglio di quanto gli insegna la Chiesa Cattolica.<\/p>\n<p style=\"text-align: justify;\">Rahner non \u00e8 capace di unire l&#8217;immutabile col mutevole sul piano dei concetti. Immutabile e universale \u00e8 soltanto l\u2019 \u201cesperienza trascendentale&#8221;, ma essa \u00e8 ineffabile (&#8220;Mistero assoluto&#8221;) e non concettualizzabile; viceversa il concetto (il &#8220;categoriale&#8221;), anche quello dogmatico, \u00e8 privo di universalit\u00e0 e immutabilit\u00e0. Ne viene la conseguenza incresciosa che la verit\u00e0 teologica esiste, ma \u00e8 inesprimibile; mentre ci\u00f2 che pu\u00f2 essere espresso appartiene solo al campo del particolare, del mutevole e dell&#8217;incerto.<\/p>\n<p style=\"text-align: justify;\"><strong>Divinizzazione dell\u2019uomo<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;etica rahneriana. come sempre avviene, \u00e8 conseguenza logica dei suoi princ\u00ecpi metafisici, gnoseologici e antropologici. La base fondamentale di tutto, come fu acutamente denunciato a suo tempo da Cornelio Fabro. \u00e8 l&#8217;identificazione dell&#8217;essere col pensiero, identificazione che perla verit\u00e0, \u00e8 propria solo dell&#8217;essenza divina, ma che invece Rahner pone come principio di tutto il reale. Da qui il panteismo in metafisica e l&#8217;idealismo in gnoseologia.<\/p>\n<p style=\"text-align: justify;\">Da qui viene anche l&#8217;identificazione dell&#8217;essere con l&#8217;agire e col divenire e la tendenza monistica che non distingue pi\u00f9 adeguatamente il vero dal falso, il bene dal male, l&#8217;eterno dal temporale, il finito dall&#8217;infinito. Dio dal mondo. Ci\u00f2 non gli impedisce peraltro di cadere in dualismi irresolubili, che qui non \u00e8 il caso di esaminare. Per distinguere egli separa, e per unire, confonde.<\/p>\n<p style=\"text-align: justify;\">Da questi principi fondamentali discende la sua concezione del rapporto dell&#8217;uomo con Dio: la ragione umana non dimostra l&#8217;esistenza di Dio partendo dagli effetti creati, come insegna san Paolo (<em>Rm<\/em>. 1,20) e il libro biblico della <em>Sapienza<\/em> (<em>Sap<\/em>. 13,5), ma possiede originariamente ed atematicamente un&#8217;\u00ab<em>esperienza preconcettuale dell&#8217;essere<\/em>\u00bb (\u201cVorgriff\u201d). nella quale legge immediatamente la propria autocoscienza e l&#8217;esistenza di Dio. Come nella conoscenza divina, non si passa dalle cose a Dio, ma da Dio alle cose. Rahner confonde il sapere umano col sapere divino.<\/p>\n<p style=\"text-align: justify;\">L&#8217;uomo dunque \u00e8 gi\u00e0 di per s\u00e9 originariamente, bench\u00e9 &#8220;atematicamente&#8221;. potenzialmente Dio; Dio non \u00e8 che la piena attuazione dell&#8217;uomo (Dio \u00e8 l&#8217; \u00ab<em>orizzonte trascendentale dell\u2019autotrascendenza umana<\/em>\u00bb). Dunque nessuna reale distinzione tra natura umana e grazia. L&#8217;uomo \u00e8 per essenza in grazia, la natura umana \u00e8 definita dalla grazia, senza la grazia \u00e8 nulla, \u00e8 pura &#8220;astrazione&#8221;, pura &#8220;possibilit\u00e0&#8221; (polemica contro la &#8220;natura pura&#8221;).<\/p>\n<p style=\"text-align: justify;\">La quale grazia poi non \u00e8 un dono di Dio, o un accidente (qualit\u00e0) dell&#8217;anima, ma \u00e8 Dio stesso, che cos\u00ec diventa il costitutivo sostanziale dell&#8217;uomo (&#8220;causa formale&#8221; dell&#8217;uomo), confodendo cos\u00ec Dio con l&#8217;anima umana. La grazia dunque \u00e8 inammissibile, cos\u00ec come l&#8217;uomo non pu\u00f2 perdere la sua essenza. Da qui l&#8217;estrema difficolt\u00e0 con la quale Rahner cerca di spiegare l&#8217;esistenza del peccato.<\/p>\n<p style=\"text-align: justify;\"><strong>La distruzione del cristianesimo<\/strong><\/p>\n<p style=\"text-align: justify;\">Da qui la tesi secondo la quale tutti per essenza tendono a Dio, tutti sono sempre in grazia, tutti si salvano (&#8220;buonismo&#8221;), il peccato diventa impossibile oppure \u00e8 un costituivo irrilevante della natura perch\u00e9 sempre perdonato da Dio (Lutero), da qui la negazione della redenzione di Cristo come sacrificio espiativo e riparatore del peccato (e quindi la crisi del sacerdozio, della Messa e della Liturgia).<\/p>\n<p style=\"text-align: justify;\">Da qui la negazione d\u00ec una natura umana oggettiva. universale e immutabile (difetto dell&#8217;esistenzialismo), dell&#8217;immortalit\u00e0 dell&#8217;anima (col rischio del materialismo), della legge naturale (con conseguente relativismo morale), dell&#8217;oggettivit\u00e0 della conoscenza concettuale-razionale (con la conseguenza del relativismo dogmatico) e del libero arbitrio (con la conseguenza di un&#8217;etica spontaneistica, antiascetica e schiava delle passioni: Freud), la negazione della Parusia futura di Cristo (Parusia adesso), dei privilegi mariani (niente verginit\u00e0), dell&#8217;esistenza degli angeli (sono solo &#8220;possibili&#8221;), di dannati nell&#8217;inferno (non c&#8217;\u00e8 nessuno) e la tesi secondo la quale anche l&#8217;ateo \u00e8 credente (&#8220;cristianesimo anonimo&#8221;).<\/p>\n<p style=\"text-align: justify;\">La cristologia \u00e8 concepita hegelianamente in modo evolutivo-dialettico come passaggio dall&#8217;umano al divino e viceversa (riappare l&#8217;eresia di Eutiche), sicch\u00e9 Rahner giunge alla conclusione che antropologia, teologia e cristologia sono la stessa cosa (effetto del panteismo). Le tre Persone divine non sono tre relazioni sussistenti ovvero tre sussistenze, ma tre &#8220;modi di sussistenza&#8221; di un&#8217;unica persona-natura-sussistente (modalismo), mentre l&#8217;essenza della Trinit\u00e0 si risolve nel suo manifestarsi al mondo (\u00ab<em>la Trinit\u00e0 immanente \u00e8 la Trinit\u00e0 economica<\/em>\u00bb). Allora Dio \u00e8 obbligato a creare? \u00c8 obbligato a incarnarsi? A manifestarsi all&#8217;uomo? Qui si vede l&#8217;influsso della fenomenologia di Husserl e viene anche in mente Hegel: \u00ab<em>Senza il mondo. Dio non \u00e8 Dio<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">In particolare, in morale, la persona appare come soggetto meramente spirituale (cf. la <em>res cogitans<\/em> di Cartesio), che liberamente (come in Fichte, Gentile e Sartre) pone o progetta la propria essenza e quindi la legge morale, la quale quindi non \u00e8 posta da Dio nella natura umana, ma il soggetto liberamente la pone da s\u00e9 onde porre la propria essenza e la propria natura. Salvo poi a porre la persona come emergente dalla materia, per il fatto che viene negata la distinzione fra anima e corpo.<\/p>\n<p style=\"text-align: justify;\">La persona non appare come \u00ab<em>individua substantia rationalis naturae<\/em>\u00bb, ma alla maniera idealistica, come autocoscienza e libert\u00e0, come una specie di relazione sussistente in atto, sicch\u00e9 c&#8217;\u00e8 poi da chiedersi come potranno essere persone quei soggetti i quali per vari motivi non possono o non vogliano relazionarsi a Dio ed agli altri.<\/p>\n<p style=\"text-align: justify;\"><strong>Figlio dell&#8217;orgoglio moderno<\/strong><\/p>\n<p style=\"text-align: justify;\">I princ\u00ecpi di fondo possono riassumersi in una divinizzazione gnostica dell&#8217;uomo e in una secolarizzazione del soprannaturale, si fanno sentire in vari modi: nel suo stesso metodo di pensare e di argomentare, dettato spesso da presunzione nei confronti delle massime autorit\u00e0 nel campo della filosofia come della religione, nell&#8217;aver sempre ignorato le osservazioni e le critiche che gli sono state fatte per decenni da eccellenti studiosi e teologi, nel sollecitare o suggerire una condotta morale improntata a un esagerato amore per la libert\u00e0 personale, nel disprezzo dei valori oggettivi, eterni e universali, insomma un&#8217;esaltazione dell&#8217;io che ben poco ha a che vedere con un sano amore di s\u00e9 riconosciuto dal cristianesimo, ma assomiglia molto di pi\u00f9 al soggettivismo e alla presunzione tipici della religiosit\u00e0 luterana e al limite alla spropositata esaltazione dell&#8217;io propria dell\u2019etica fichtiana.<\/p>\n<p style=\"text-align: justify;\">Appare l&#8217;ombra sinistra di Nietzsche. Siamo ancora nel Cristianesimo? \u00c8 questa l&#8217;interpretazione del Concilio?<\/p>\n<p style=\"text-align: justify;\">_______________________<\/p>\n<p style=\"text-align: justify;\"><strong>Leggi anche:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=3368\" target=\"_blank\">Karl Rahner maestro del Concilio, di Martini e della coscienza relativa<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=3340\" target=\"_blank\">Un&#8217;analisi critica su Karl Rahner<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=3283\" target=\"_blank\">&#8220;Modesnismo&#8221;. S\u00ec, fu un&#8217;eresia e il suo erede \u00e8 il progressismo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Radici Cristiane n.47 settembre 2009 Un noto teologo odierno ci chiarisce gli errori fondamentali di uno dei maggiori esponenti di quella teologia eversiva che nel XX secolo ha afflitto la Chiesa al suo interno, e le cui nefaste influenze sono dinanzi agli occhi di tutti noi cattolici. Fr Giovanni Cavalcoli, op Sappiamo come di recente &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":19995,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,45],"tags":[344,1664,789],"class_list":["post-3430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-progressismo-cattolico","tag-concilio-vaticano-ii","tag-karl-rahner","tag-progressismo-cattolico-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Karl Rahner, un cristianesimo senza radici - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karl Rahner, un cristianesimo senza radici - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-16T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-02-26T11:54:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Karl_Rahner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"208\" \/>\n\t<meta property=\"og:image:height\" content=\"243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Karl Rahner, un cristianesimo senza radici\",\"datePublished\":\"2009-09-16T22:00:00+00:00\",\"dateModified\":\"2015-02-26T11:54:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/\"},\"wordCount\":1996,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/09\\\/Karl_Rahner.jpg\",\"keywords\":[\"Concilio Vaticano II\",\"Karl Rahner\",\"progressismo cattolico\"],\"articleSection\":[\"Chiesa\",\"Progressismo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/\",\"name\":\"Karl Rahner, un cristianesimo senza radici - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/09\\\/Karl_Rahner.jpg\",\"datePublished\":\"2009-09-16T22:00:00+00:00\",\"dateModified\":\"2015-02-26T11:54:22+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/09\\\/Karl_Rahner.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/09\\\/Karl_Rahner.jpg\",\"width\":208,\"height\":243},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/karl-rahner-un-cristianesimo-senza-radici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karl Rahner, un cristianesimo senza radici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karl Rahner, un cristianesimo senza radici - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/","og_locale":"it_IT","og_type":"article","og_title":"Karl Rahner, un cristianesimo senza radici - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-09-16T22:00:00+00:00","article_modified_time":"2015-02-26T11:54:22+00:00","og_image":[{"width":208,"height":243,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Karl_Rahner.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Karl Rahner, un cristianesimo senza radici","datePublished":"2009-09-16T22:00:00+00:00","dateModified":"2015-02-26T11:54:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/"},"wordCount":1996,"commentCount":0,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Karl_Rahner.jpg","keywords":["Concilio Vaticano II","Karl Rahner","progressismo cattolico"],"articleSection":["Chiesa","Progressismo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/","name":"Karl Rahner, un cristianesimo senza radici - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Karl_Rahner.jpg","datePublished":"2009-09-16T22:00:00+00:00","dateModified":"2015-02-26T11:54:22+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Karl_Rahner.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/Karl_Rahner.jpg","width":208,"height":243},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/karl-rahner-un-cristianesimo-senza-radici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Karl Rahner, un cristianesimo senza radici"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3430"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3430\/revisions"}],"predecessor-version":[{"id":19996,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3430\/revisions\/19996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/19995"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}