{"id":34056,"date":"2016-05-19T00:00:59","date_gmt":"2016-05-18T22:00:59","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=34056"},"modified":"2016-05-12T16:09:23","modified_gmt":"2016-05-12T14:09:23","slug":"i-principi-non-negoziabili-e-la-funzione-della-bioetica","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/","title":{"rendered":"I principi non negoziabili e la funzione della bioetica"},"content":{"rendered":"<div id=\"attachment_34057\" style=\"width: 250px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-34057\" class=\"wp-image-34057\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/05\/The-doctor-di-Luke-Fildes.jpg\" alt=\"The doctor di Luke Fildes\" width=\"250\" height=\"166\" \/><p id=\"caption-attachment-34057\" class=\"wp-caption-text\">&#8220;The doctor&#8221; di Luke Fildes<\/p><\/div>\n<p style=\"text-align: center;\"><strong>La Ruota<\/strong> Periodico del Centro per la Vita di Pisa \u00a0fondato nell\u2019ottobre del 1996 da Massimo Ermini &#8211;\u00a0Anno XX &#8211; 1<\/p>\n<p style=\"text-align: justify;\"><em>Una riflessione biogiuridica sull\u2019emergenza antropologica a fronte di un approccio frammentario ai temi etici<\/em><\/p>\n<p style=\"text-align: center;\"><strong>Giuseppe Mazzotta<\/strong><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Nonostante i quasi venti anni trascorsi, continua ad essere assai vicina, nel tempo, una tiepida mattina del mese di ottobre del 1996, quando, nel corso di un incontro presso la sede del Centro di Bioetica dell\u2019Universit\u00e0 di Pisa, il Prof. Massimo Ermini, uomo e medico, come amava definirsi, pens\u00f2 di fondare questa rivista trimestrale che oggi, come egli direbbe scherzando, ha ampiamente raggiunto la maggiore et\u00e0.<\/p>\n<p style=\"text-align: justify;\">Il titolo, La Ruota, prendendo a prestito l\u2019immagine della Ruota degli Esposti: si tratta di un noto sistema costituito da un tamburo rotante di legno posto all\u2019esterno dell\u2019edificio davanti ad una finestra con una grata, sul quale veniva adagiato il bambino; una volta fatta girare era possibile recuperare il neonato all\u2019interno della struttura. La Ruota, uno strumento semplice ed essenziale, discreto, mediante il quale, da un lato, una madre in difficolt\u00e0 nel continuare ad assistere il proprio bambino e, dall\u2019altro, una persona disposta ad aiutare senza chiedere, mossa dalla pietas e dalla corresponsabilit\u00e0 per madre e figlio, si incontravano, accomunate dall\u2019indiscutibile interesse del bambino a conservare il bene pi\u00f9 grande ossia la sua vita, evitando che chicchessia si arrogasse il diritto di decidere arbitrariamente in relazione ad essa.<\/p>\n<p style=\"text-align: justify;\">Quando ne parlavamo, insieme al Professore, restavamo colpiti dal fatto che in, molte narrazioni, i bambini adagiati nella Ruota recassero piccoli segni di riconoscimento, nastri, minuti oggetti di vario tipo, di transizione si direbbe oggi, e con la funzione di permettere, nell\u2019eventuale futuro ritorno della madre, di effettuare un semplice ma sicuro, riconoscimento del bambino.<\/p>\n<p style=\"text-align: justify;\">Mosso dalla curiosit\u00e0 ero stato personalmente a visitare la sede dell\u2019ospedale degli Innocenti di Firenze, sito di una storica Ruota degli Esposti, dove era iniziata la vicenda umana, giunta sino ai giorni nostri, della pur breve vita di Agata Smeralda, la prima bambina abbandonata nella pila dell&#8217;acqua benedetta della Chiesa dello \u201cSpedale degli Innocenti\u201d di Firenze nel lontano 5 febbraio 1445.<\/p>\n<p style=\"text-align: justify;\">Il contatto con questi oggetti ha la forza delicata e invincibile dell\u2019esperienza che si consuma nella vita quotidiana e, per questo, attraversa le epoche storiche trasversalmente, riportando ai giorni nostri fin quasi il suo rumore, come in quell\u2019affresco che abbiamo scelto per la prima pagina del nostra rivista, perch\u00e9 realizzato da un artista come Masaccio, che porta \u00abdentro la pittura il rumore della vita, il senso di qualcosa che esiste, che si muove e finisce per coinvolgere persino gli spettatori, personaggi degli episodi, tanto quanto le figure dipinte (Vittorio Sgarbi \u2013 <em>Nel nome del figlio<\/em>)\u00bb.<\/p>\n<p style=\"text-align: justify;\">E nel corso di questi anni, in pi\u00f9 occasioni, la cura per la vita nascente, si \u00e8 intrecciata alla riflessione bioetica, anche sulle colonne di questa rivista trimestrale, nella quale ci si \u00e8 pi\u00f9 volte e da pi\u00f9 parti espressi sulla pericolosit\u00e0 della frammentazione di tanti approcci bioetici quante sono le tematiche che interpellano il pensiero bioetico, il quale dovrebbe sempre svolgersi attraverso principi che, proprio nella differenza delle tematiche trattate, trovano conferma della loro unicit\u00e0. Il principio del non uccidere e quello dell\u2019eguale dignit\u00e0 di ogni essere umano a prescindere dalla sua condizione, portano, ad es., a considerare inaccettabile l\u2019aborto volontario cos\u00ec come la fecondazione eterologa, ma anche a ritenere improponibile un intervento nei confronti di una persona sofferente e malata che radicalizzi, divaricandola, l\u2019asimmetria rispetto a coloro che, nel pieno delle proprie capacit\u00e0 psicofisiche e decisionali, giungono sino al punto di negargli la vita, il pi\u00f9 grande e basilare bene condiviso da entrambe.<\/p>\n<p style=\"text-align: justify;\">Una legge, quale, ad esempio, quella da poco meno di due anni approvata in Belgio, e l\u2019intento che la pervade, certamente ci interpellano sulla necessit\u00e0 di orientare la confutazione degli argomenti che la sostengono, dentro e fuori il Parlamento che l\u2019ha adottata, evitando di disperdersi nei mille rivoli delle, invero, assai poco strategiche differenziazioni di rilevanza delle attribuzioni giuridiche riservate a chi opera nei differenti settori oggetto delle problematiche bioetiche, occorrendo, invece, previamente affermare e sviluppare l\u2019unicit\u00e0 del principio dell\u2019eguale ed intangibile dignit\u00e0 che fonda la vita di ogni uomo dal concepimento alla morte naturale.<\/p>\n<p style=\"text-align: justify;\">La legge approvata permette l\u2019eutanasia per i minori di diciotto anni, in tal modo legalizzando la possibilit\u00e0 di interrompere la vita dei bambini sottoposti a cure per malattie, spesso particolarmente gravi, ed in una condizione sulla quale proprio questa legge consente un arbitrario giudizio sul fatto se quella vita meriti o meno di essere proseguita.<\/p>\n<p style=\"text-align: justify;\">Sono facilmente intuibili i riflessi di una normativa che legittima il comportamento mediante il quale si ponga fine alla vita di un essere umano, sul presupposto, da solo sufficiente, che esso sia gravemente malato ed in uno stato di particolare sofferenza. Il contesto nel quale maturano atti e giudizi connessi alle legge citata \u00e8 come offuscato da una patina di pietismo con cui si giustifica l\u2019atto di chi intenderebbe, con l\u2019interruzione della vita stessa, porre fine ad insopportabili sofferenze.<\/p>\n<p style=\"text-align: justify;\">E il pietismo esplicita un\u2019intrinseca differenza rispetto alla \u201cpietas\u201d: quest\u2019ultima esita in un atteggiamento verso la condizione del sofferente del quale non sia possibile la guarigione e che pu\u00f2 manifestarsi, evidentemente anche in ambito medico, mediante atti tesi a curare il paziente, a lenire la sofferenza stessa, ad aiutare chi la prova a viverne l\u2019esperienza, ove possibile, senza rinunciare a percepire ed esperire la presenza degli altri, a condividerla con chi vi si accosta, tutti atti che entrano nella relazione con il malato connotando eticamente e umanamente l\u2019uso dei mezzi diretti alla realizzazione degli scopi anzidetti: insomma molto di ci\u00f2 che, in ambito medico, si esprime attraverso le cure palliative e, pi\u00f9 in generale, le terapie di supporto, ossia tutti quegli interventi che, per loro intrinseca natura e per la loro oggettiva finalit\u00e0, tendono a restituire alla persona la capacit\u00e0 di essere presente nel mondo anche oltre la sofferenza che la opprime e, comunque, ad attenuare la sofferenza quanto pi\u00f9 possibile al di sotto della soglia che impedisce di essere con e in mezzo agli altri: cure che tendono a restituire la vita alle persone e le persone alla vita, ossia esattamente il contrario di quanto accade con l\u2019intervento eutanasico che bypassa totalmente tutto questo per determinare la fine della vita del sofferente, sul quale umanamente, ci si dovrebbe, invece, chinare.<\/p>\n<p style=\"text-align: justify;\">La cultura \u201cdello scarto\u201d, come recentemente l&#8217;ha definita Papa Francesco, al contrario, in certo qual modo alzandosi, in maniera fredda e neutrale, dal sofferente, propone, addirittura anche a livello legislativo, la soluzione eutanasica, e si esplicita al di fuori della logica della presa in carico del paziente, all\u2019interno della quale \u00e8 auspicabilmente presente il possibile, o probabile, esito della guarigione, ma nella quale \u00e8, comunque, sempre presente la cura del malato anche quando esso non sia guaribile, in tal modo includendo, nella relazione, la dignit\u00e0 propria di chi viene accettato per il suo essere creatura personale e individuo irripetibile e non per gli attributi che a ci\u00f2 si aggiungano per definirne competenze ed attitudini, le quali, invece, sono indistintamente proprie di una molteplicit\u00e0 indifferenziata di soggetti oltre che intrinsecamente precarie.<\/p>\n<p style=\"text-align: justify;\">La prospettiva nella quale allora si iscrive il rapporto con il sofferente \u00e8 quella di una relazione corresponsabile che, come tale, non pu\u00f2 prescindere dalla garanzia, per ciascuno di coloro che la stabiliscono, del bene in assoluto pi\u00f9 grande ossia la vita stessa, altrimenti perdendo questa relazione qualunque prospettiva di senso.<\/p>\n<p style=\"text-align: justify;\">Riaffiorano alla memoria le recentissime parole, pronunciate da Papa Francesco dinanzi alla Pontificia Accademia per la Vita il 19 febbraio 2015: \u00abAlla base delle discriminazioni e delle esclusioni vi \u00e8 per\u00f2 una questione antropologica: quanto vale l\u2019uomo e su che cosa si basa questo suo valore. La salute \u00e8 certamente un valore importante, ma non determina il valore della persona. La salute inoltre non \u00e8 di per s\u00e9 garanzia di felicit\u00e0: questa, infatti, pu\u00f2 verificarsi anche in presenza di una salute precaria. La pienezza a cui tende ogni vita umana non \u00e8 in contraddizione con una condizione di malattia e di sofferenza. Pertanto, la mancanza di salute e la disabilit\u00e0 non sono mai una buona ragione per escludere o, peggio, per eliminare una persona; e la pi\u00f9 grave privazione che le persone anziane subiscono non \u00e8 l\u2019indebolimento dell\u2019organismo e la disabilit\u00e0 che ne pu\u00f2 conseguire, ma l\u2019abbandono, l\u2019esclusione, la privazione di amore\u00bb.<\/p>\n<p style=\"text-align: justify;\">Peraltro quanti pensassero di poter circoscrivere il confine di una prospettiva ideale, magari derivante da quella che, con una certa frequente approssimazione, si sente definire la \u201ccultura cattolica\u201d, assai difficilmente potrebbero conciliare questa affermazione con l\u2019indiscutibile presenza della pietas anche in culture presenti in epoca largamente precristiana, come, ad es., si riscontra, tra le moltissime, nelle opere di Sofocle; di queste ve ne \u00e8 una, particolarmente interessante da ricordare in questo contesto, il Filottete, composta nel 409 A.C. la quale narra di un uomo, Filottete, appunto, abbandonato dai suoi compagni di viaggio, per la guerra contro Troia, sull&#8217;isola di Lemno, a causa di una ferita grave ed infetta: l\u2019abbandono \u00e8 determinato dall\u2019asserita necessit\u00e0 di evitare che le truppe si deprimano per la sofferenza di quest\u2019uomo, il quale si lamenta per il dolore e la malattia: un oracolo, tuttavia, svela ai Greci che, senza l&#8217;arco posseduto da Filottete, Troia non cadr\u00e0 mai e la guerra non potr\u00e0 esser vinta. Vengono allora incaricati Odisseo e Neottolemo (figlio di Achille) di andare sull&#8217;isola e recuperare ad ogni costo l&#8217;arco di Filottete.<\/p>\n<p style=\"text-align: justify;\">Odisseo, che in questa tragedia risulta meschino e crudele, ordisce un piano per sottrarre l\u2019arco a Filottete: Neottolemo avrebbe dovuto fingere di essere in contrasto con i capi greci e, carpita la fiducia di Filottete, farsi consegnare l&#8217;arco, che altrimenti sarebbe stato preso con la forza. L&#8217;inganno riesce e Filottete consegna l\u2019arco all&#8217;amico Neottolemo, il quale, all&#8217;ultimo momento, per\u00f2, pentendosi del suo gesto, mediante il quale ha guadagnato e tradito la fiducia di un uomo malato e sofferente, prova compassione per Filottete e gli riconsegna l\u2019arco.<\/p>\n<p style=\"text-align: justify;\">Questa tragedia mette in scena, \u00e8 proprio il caso di dire, il tema della compassione, un sentimento, s\u00ec, ma anche un\u2019opzione etica, attraverso cui le persone condividono, sia pure da piani diversi, la condizione di una sofferenza della quale ci si sente corresponsabili in quanto tutti membri di una medesima famiglia umana che non consente di rifiutarla senza tradire la propria identit\u00e0 di creatura: \u00e8 per questo che nel comportamento del protagonista della storia c\u2019\u00e8 un\u2019immediatezza del sapere, del sentire e dell\u2019agire, dal carattere cristallino che si oppone naturalmente all\u2019opacit\u00e0 delle definizioni e delle teorizzazioni, orientate in funzione, spesso, di precostituite, pi\u00f9 o meno consapevoli, personali visioni del mondo. Verrebbe da dire \u2026 torniamo al presente!<\/p>\n<p style=\"text-align: justify;\">Ma \u00e8 forse proprio questo il punto che pone l\u2019evento giuridico citato, oggi avvolto nel silenzio di un processo di normalizzazione che da queste umilissime righe si incoraggia a contrastare, si \u00e8 prodotto nel cuore di una pur sedicente civilissima Europa: se dalla storia non apprendiamo quanto dovremmo o potremmo, probabilmente questo dipende anche dalla ridotta misura in cui da essa ci si lascia provocare e dall\u2019inadeguatezza delle domande che ad essa poniamo.<\/p>\n<p style=\"text-align: justify;\">La scienza bioetica, o etica della vita, prende forma nella storia, nel quadro di una riflessione interdisciplinare che abbraccia le ragioni, intrinseche alla vita stessa, le quali pongono l\u2019esigenza originaria del suo rispetto e della sua tutela. Attraverso questo percorso la bioetica si esprime mediante gli strumenti della riflessione filosofica, dell\u2019indagine della buona pratica medica, della regolamentazione giuridica, in tutti questi settori orientandosi mediante l\u2019indagine antropologica.<\/p>\n<p style=\"text-align: justify;\">E\u2019 per questo che in bioetica rinveniamo principi, pi\u00f9 propriamente che valori, quali, ad es., <em>primum non nocere, neminem laedere<\/em>, che interpellano, senza distinzione, tutti coloro che interagiscono con la vita di chicchessia. Se questa \u00e8 l\u2019intrinseca e logica identit\u00e0 della bioetica, risulta fatalmente critico e involuto l\u2019approccio di chi svolga una riflessione particolaristica, magari volendo individuare caso per caso i principi regolatori della tutela della vita umana, una volta rispetto alla fase iniziale di essa, come nel caso dell\u2019aborto o della fecondazione artificiale, un\u2019altra volta in ordine alla fase finale, come avviene rispetto all\u2019eutanasia, o ancora, ad es., rispetto alla cura dell\u2019ambiente nel quale viviamo.<\/p>\n<p style=\"text-align: justify;\">In questa prospettiva risulta assolutamente condivisibile la conclusione di chi ritiene che la bioetica non abbia interamente svolto la propria funzione, che non \u00e8 quella di propugnare o difendere valori, prodotto delle culture e delle epoche storiche di riferimento, ma quella di identificare ed esplicitare principi ordinatori della vita ossia gli elementi discriminanti della sua struttura antropologica originaria, essendone l\u2019uomo, indiscutibilmente e pacificamente tra tutte le culture, anche nelle diverse epoche storiche, il custode creato e non certamente l\u2019artefice creatore.<\/p>\n<p style=\"text-align: justify;\">La prospettiva dei valori \u00e8 quella, ad es., stabilita con la legge 40 del 2004 sulla procreazione medicalmente assistita che, all\u2019art. 1, recita \u00abal fine di favorire la soluzione dei problemi riproduttivi derivanti dalla sterilit\u00e0 o dalla infertilit\u00e0 umana \u00e8 consentito il ricorso alla procreazione medicalmente assistita, alle condizioni e secondo le modalit\u00e0 previste dalla presente legge, che assicura i diritti di tutti i soggetti coinvolti, compreso il concepito\u00bb.<\/p>\n<p style=\"text-align: justify;\">La prospettiva nella quale si coglie il principio \u00e8 quella del \u201cnon uccidere\u201d, un principio comune anche a tutti gli altri variegati campi della bioetica e che si sono, solo in parte, prima citati; ma il principio \u00e8 anche l\u2019uguaglianza, quella che permette di escludere la fecondazione eterologa, quale procedimento governato da alcuni soggetti con la conseguente condizione di orfano di colui per il quale viene predeterminata, prima ancora del suo concepimento, la mancanza di un genitore che non si potr\u00e0 mai conoscere; e sui principi del non uccidere e dell\u2019uguaglianza deve evidentemente fondarsi il divieto di una decisione che legittimi di porre termine alla vita propria o a quella di altre persone tacciate come indegne di essere vissute.<\/p>\n<p style=\"text-align: justify;\">Si percepisce la conseguente scarsa incisivit\u00e0, sotto il profilo bioetico, di un\u2019indagine ermeneutica tesa a valutare, ad es., limiti ed oggetto della responsabilit\u00e0 genitoria nei confronti del minore di et\u00e0, o la capacit\u00e0 di discernimento di quest\u2019ultimo, restandosi nell\u2019ambito di ci\u00f2 che si propone come valore di riferimento per le relazioni tra genitori e figli, le quali, peraltro, sono solo in parte regolabili in base alla legge.<\/p>\n<p style=\"text-align: justify;\">E l&#8217;uguaglianza viene compromessa anche da leggi che, neutralizzando la struttura altruistica e gratuita delle relazioni in seno alla famiglia secondo il disegno tracciato dall&#8217;art. 29 della Costituzione propongono la c.d. <em>stepchild adoption,<\/em> ossia l\u2019istituto dell\u2019adozione dei figli del partner esteso a coppie dello stesso sesso, che semplifica riduzionisticamente la complessit\u00e0 personale, antropologica, psicologica ed educativa delle relazioni interpersonali tra genitori e figli, sacrificandola alla finalit\u00e0 individualistica e ad un desiderio che si vuole trasformare in diritto.<\/p>\n<p style=\"text-align: justify;\">L\u2019equivoco descritto priva la riflessione bioetica della possibilit\u00e0 di esercitare la funzione sua propria, determinandosi anzi il suo potenziale uso arbitrario, in funzione dell\u2019esigenza di legittimare condotte altrimenti improponibili per la loro palese etica inammissibilit\u00e0, come nel caso in cui si propugna come eticamente ammissibile la ricerca scientifica sugli embrioni umani, sulla scorta di un\u2019asserita finalit\u00e0 di cercare la cura per alcune malattie, in tal modo tuttavia dimenticando che l\u2019obiettivo della scienza medica \u00e8 quello di curare l\u2019uomo, il malato, e non, in modo semplice e materialistico la malattia, la qual cosa \u00e8 intrinsecamente impossibile quando, per curare un essere umano, si programmano lo sfruttamento e la soppressione di un altro essere umano.<\/p>\n<p style=\"text-align: justify;\">Da tutto ci\u00f2 si ricava che contrapporre valori e principi sarebbe un\u2019operazione improponibile per chiunque, anche da posizioni contrapposte, auspichi che i primi si sovrappongano ai secondi fino a corrispondervi, ma anche che \u00e8 necessario ed assai \u201cprudente\u201d riaffermare l\u2019esistenza di ci\u00f2 che non \u00e8 determinato storicamente e che non subisce il periodico condizionamento della cultura corrente nelle varie epoche di riferimento.<\/p>\n<p style=\"text-align: justify;\">La bioetica si interroga nella storia, verificando il rapporto di essa con i principi, i quali divengono, cos\u00ec, sempre pi\u00f9 ragionevolmente innegoziabili, ogni qual volta risultino messi in discussione. E, in tal senso, le risposte, provenienti dalla storia e dal tempo presente, non vengono dal succedersi di eventi dei quali la collettivit\u00e0 sarebbe il precario e fisiologicamente ridondante risultato, ma originano dalla realt\u00e0 della quale l\u2019uomo \u00e8 il soggetto che stabilisce una relazione corresponsabile con altri soggetti, dei quali riconosce l\u2019eguale dignit\u00e0: come potrebbero esserci i diritti umani se ciascuno pensasse di avere diritto a vedersi riconosciuto indiscriminatamente, anche ad evidente danno del prossimo, ogni diritto che rivendica?<\/p>\n<p style=\"text-align: justify;\">La percezione dell\u2019orizzonte nichilista attraverso il quale l\u2019uomo esce dal mondo, \u00e8 descritta, nella Grande Bellezza\u201d del regista Paolo Sorrentino come un trucco, che il protagonista del film sembra accontentarsi di svelare, peraltro accorgendosi, appena in tempo, che la risposta alla sua esigenza di vivere in pienezza scaturisce dall\u2019entrare in contatto con la bellezza che, nella quotidianit\u00e0, intreccia gioia e sofferenza, conquista e perdita, aspettativa e delusione, nel quadro di un\u2019identit\u00e0 personale che alcuni personaggi dello stesso film, attraverso molte risposte e senza nessuna domanda, tentano di ignorare, con l\u2019unico effetto di restare prigionieri di un\u2019opaca e malinconica caricatura di se stessi.<\/p>\n<p style=\"text-align: justify;\">Tutto ci\u00f2 mentre scorre la storia, e non la cronaca, esprimendo la non negoziabilit\u00e0 di taluni principi. E proprio con una domanda chiuderei questo editoriale, gratissimo a chi ha avuto la pazienza di leggerlo: male, davvero, non sarebbe tentare di cogliere i riflessi di una legislazione cos\u00ec recente, meditando sulle tracce che ci lascia la storia, anche attraverso la sue pi\u00f9 nobili espressioni, come ad es., quella artistica: quale \u00e8 il punto in cui si riassume e compendia tutta la drammaticit\u00e0 di un dipinto come \u201cThe doctor\u201d di Luke Fildes, un\u2019opera di oltre un secolo addietro?<\/p>\n<p style=\"text-align: justify;\">Senza dubbio il volto del medico, che si sente responsabile per la sofferenza del bambino esanime affidato alle sue cure e che sembra domandarsi \u201cche cosa\u201d di ragionevole ed utile possa ancora tentare di fare per il bambino di fronte a lui. La persona ritratta da Fildes in primo piano \u00e8 un uomo del mondo che abitiamo e non di quello che potremmo immaginare, \u00e8 un medico, in carne ed ossa, umile e sensato, la cui attenzione \u00e8 integralmente assorbita dalle necessit\u00e0 di un bambino gravemente malato che, forse, non riuscir\u00e0 a guarire, ma al quale potr\u00e0 continuare ad offrire le sue cure, come si fa con il prossimo, che, secondo quanto suggerisce la stessa etimologia di questa parola, \u00e8 colui che sta \u2018vicino\u2019, in quanto condivide la medesima condizione e l\u2019identica intangibile dignit\u00e0 di chi se ne prende cura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Ruota Periodico del Centro per la Vita di Pisa \u00a0fondato nell\u2019ottobre del 1996 da Massimo Ermini &#8211;\u00a0Anno XX &#8211; 1 Una riflessione biogiuridica sull\u2019emergenza antropologica a fronte di un approccio frammentario ai temi etici Giuseppe Mazzotta<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2456,372],"class_list":["post-34056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioetica","tag-emergenza-antropologica","tag-principi-non-negoziabili","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I principi non negoziabili e la funzione della bioetica - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I principi non negoziabili e la funzione della bioetica - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-18T22:00:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/05\/The-doctor-di-Luke-Fildes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I principi non negoziabili e la funzione della bioetica\",\"datePublished\":\"2016-05-18T22:00:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/\"},\"wordCount\":3109,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/The-doctor-di-Luke-Fildes.jpg\",\"keywords\":[\"emergenza antropologica\",\"principi non negoziabili\"],\"articleSection\":[\"Bioetica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/\",\"name\":\"I principi non negoziabili e la funzione della bioetica - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/The-doctor-di-Luke-Fildes.jpg\",\"datePublished\":\"2016-05-18T22:00:59+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/The-doctor-di-Luke-Fildes.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/The-doctor-di-Luke-Fildes.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I principi non negoziabili e la funzione della bioetica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I principi non negoziabili e la funzione della bioetica - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/","og_locale":"it_IT","og_type":"article","og_title":"I principi non negoziabili e la funzione della bioetica - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2016-05-18T22:00:59+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/05\/The-doctor-di-Luke-Fildes.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I principi non negoziabili e la funzione della bioetica","datePublished":"2016-05-18T22:00:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/"},"wordCount":3109,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/05\/The-doctor-di-Luke-Fildes.jpg","keywords":["emergenza antropologica","principi non negoziabili"],"articleSection":["Bioetica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/","name":"I principi non negoziabili e la funzione della bioetica - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/05\/The-doctor-di-Luke-Fildes.jpg","datePublished":"2016-05-18T22:00:59+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/05\/The-doctor-di-Luke-Fildes.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/05\/The-doctor-di-Luke-Fildes.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-principi-non-negoziabili-e-la-funzione-della-bioetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I principi non negoziabili e la funzione della bioetica"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/34056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=34056"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/34056\/revisions"}],"predecessor-version":[{"id":34058,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/34056\/revisions\/34058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34057"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=34056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=34056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=34056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}