{"id":3393,"date":"2009-07-29T11:03:15","date_gmt":"2009-07-29T09:03:15","guid":{"rendered":""},"modified":"2015-11-10T15:05:10","modified_gmt":"2015-11-10T14:05:10","slug":"tra-i-sussurri-e-le-grida-la-verit-della-storia","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/","title":{"rendered":"Tra i sussurri e le grida la verit&agrave; della storia"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/ragioni_cover.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-27350\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/ragioni_cover.jpg\" alt=\"ragioni_cover\" width=\"114\" height=\"200\" \/><\/a>L\u2019Osservatore Romano<\/strong> luned\u00ec-marted\u00ec 27-28 luglio 2009<\/div>\n<p style=\"text-align: center;\">di <strong>Roberto Pertici<\/strong><\/p>\n<p style=\"text-align: center;\"><em>(Universit\u00e0 di Bergamo) <\/em><\/p>\n<p style=\"text-align: justify;\">Un problema percorre molti saggi compresi nel volume <em>In difesa di Pio XII. Le ragioni della storia<\/em> (a cura di Giovanni Maria Vian, Venezia, Marsilio, 2009, pagine 168, euro 13): il mutamento di giudizio sulla figura di Pio XII, sul suo atteggiamento durante il secondo conflitto mondiale e di fronte allo sterminio degli ebrei europei, che si verific\u00f2 intorno al 1960.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Il punto di svolta \u00e8 costituito dalla rappresentazione berlinese di <em>Der Stellvertreter <\/em>di Rolf Hochhuth, il 20 febbraio 1963: il dramma sarebbe stato in seguito messo in scena a Londra il 25 settembre, a New York il 26 febbraio 1964 e a Roma il 13 febbraio 1965 e poi pubblicato un po&#8217; in tutte le lingue.<\/div>\n<p style=\"text-align: justify;\">Fino ad allora \u2014 si ripete \u2014 i giudizi erano stati generalmente positivi, spesso molto positivi, anche da parte dei principali esponenti dell&#8217;ebraismo internazionale e dello Stato d&#8217;Israele. \u00c8 vero: chi, per fare solo un esempio, ripercorra i dibattiti dell&#8217;Assemblea costituente italiana, si imbatte di continuo in ampi riconoscimenti all&#8217;operato della Chiesa cattolica negli ultimi anni del fascismo, in quelli della guerra e poi dell&#8217;occupazione nazista: \u00abPerch\u00e9 in Italia c&#8217;\u00e8 la pace religiosa? \u2014 si chiedeva forse il massimo esponente del laicismo italiano di allora, l&#8217;azionista Piero Calamandrei nel suo discorso del 20 marzo 1947 contro l&#8217;articolo 7 \u2014<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 a un certo momento, negli anni della maggiore oppressione ci siamo accorti che l&#8217;unico giornale nel quale si poteva ancora trovare qualche accenno di libert\u00e0, della nostra libert\u00e0, della libert\u00e0 comune a tutti gli uomini liberi, era \u201cL&#8217;Osservatore Romano\u201d; perch\u00e9 abbiamo sperimentato che chi comprava \u201cL&#8217;Osservatore Romano\u201d era esposto ad essere bastonato; perch\u00e9 una voce libera si trovava negli \u201cActa diurna\u201d dell&#8217;amico Gonella; perch\u00e9, quando sono cominciate le persecuzioni razziali, la Chiesa si \u00e8 schierata contro gli oppressori (<em>Approvazioni<\/em>) in difesa degli oppressi; perch\u00e9 quando i tedeschi ricercavano i nostri figliuoli per torturarli e fucilarli, essi, qualunque fosse il loro partito, hanno trovato rifugio \u2014 ve lo attesta un babbo \u2014 nelle canoniche e nei conventi\u00bb.<\/p>\n<p style=\"text-align: justify;\">Tuttavia gi\u00e0 in quegli anni si erano introdotte note dissonanti: molto attiva in tal senso fu la propaganda sovietica, che aveva iniziato a produrre decine di opuscoli contro la politica vaticana degli anni Venti e Trenta e durante il conflitto appena trascorso, presentandola tutta in blocco come connivente con i fascismi e poi in qualche modo complice della progettata egemonia nazista.<\/p>\n<p style=\"text-align: justify;\">Sembra che la maggior parte delle tesi poi drammatizzate ne <em>Il vicario <\/em>fossero rinvenute da Hochhuth nel volume dello storico sovietico Mikhail Marcovich Scheinmann, <em>Der Vatikan im zweiten Weltkrieg<\/em>, pubblicato in russo dall&#8217;Istituto storico dell&#8217;Accademia sovietica delle scienze e tradotto poi in tedesco (1954) e anche inglese (1955). Scheinmann non era ignoto al pubblico italiano: la sua opera precedente, <em>Il Vaticano tra due guerre<\/em>, era stata pubblicata dalle Edizioni di cultura sociale \u2014 una delle case editrici del Pci \u2014 nel 1951, con una prefazione dello storico Giorgio Candeloro, che allora era militante comunista.<\/p>\n<p style=\"text-align: justify;\">A cosa era dovuta questa massiccia campagna antivaticana? I dirigenti dell&#8217;Urss avvertivano nell&#8217;anticomunismo di Pio XII uno dei principali ostacoli alla loro politica, al tempo stesso minacciosa e suadente, verso l&#8217;Europa occidentale; ma sicuramente c&#8217;era anche dell&#8217;altro.<\/p>\n<p style=\"text-align: justify;\">Nel suo saggio, Paolo Mieli parla di \u00abcattiva coscienza\u00bb, cio\u00e8 del tentativo da parte della dirigenza sovietica di occultare le proprie gravi responsabilit\u00e0 di fronte alla politica di sterminio portata avanti dai nazisti, in primo luogo nell&#8217;Europa orientale.<\/p>\n<p style=\"text-align: justify;\">\u00c8 ormai stato documentato che in tutti i discorsi pubblici da lui pronunziati durante la guerra, Stalin cit\u00f2 gli ebrei una sola volta, ignorando in modo sistematico le violenze dei nazisti nei loro confronti. Nei quasi due anni che vanno dall&#8217;invasione tedesca della Polonia all&#8217;inizio dell&#8217;operazione Barbarossa nel giugno del 1941, la stampa sovietica \u2014 in questo periodo l&#8217;Urss era praticamente alleata con Hitler \u2014 evit\u00f2 qualsiasi resoconto su ci\u00f2 che stava accadendo agli ebrei nella Polonia occupata dai nazisti. In questo modo gli ebrei sovietici restarono nella pi\u00f9 completa ignoranza sul destino che sarebbe toccato loro in sorte e la natura specifica della violenza razziale \u2014 anche nel momento in cui dilagava sul territorio sovietico \u2014 fu minimizzata.<\/p>\n<p style=\"text-align: justify;\">Di recente un acuto storico inglese come Michael Burleigh ha sottolineato la trascuratezza della storiografia nei confronti delle risposte sovietiche alla Shoah, se paragonata alla vastit\u00e0 della letteratura dedicata alle nazioni neutrali e alle democrazie occidentali \u2014 e, possiamo aggiungere, alla Santa Sede. Ancora Mieli aggiunge che la \u00ableggenda nera\u00bb di Pio XII non \u00e8 nata nell&#8217;ambiente ebraico, ma in quello anglosassone e protestante: anch&#8217;esso aveva tardato a prendere coscienza di quanto stava accadendo in Europa.<\/p>\n<p style=\"text-align: justify;\">Il cosiddetto telegramma Riegner dell&#8217;8 agosto 1942, che forniva le prime informazioni \u2014 sia pure in modo ancora ipotetico \u2014 sulla \u00absoluzione finale\u00bb fu accolto con grande scetticismo dall&#8217;establishment americano, che solo nel dicembre successivo si decise a una prima dichiarazione nel merito.<\/p>\n<p style=\"text-align: justify;\">Ma mi \u00e8 capitato di leggere di recente l&#8217;autobiografia di uno dei pi\u00f9 diretti collaboratori di John Fitzgerald Kennedy negli anni della sua presidenza, lo storico Arthur M. Schlesinger jr., che conferma tali incomprensioni: l&#8217;Office of Strategic Service, presso cui lavorava dopo il 1943 in qualit\u00e0 di analista politico, si pose il problema di cosa fosse la \u00absoluzione finale\u00bb, senza arrivare a vere conclusioni e limitandosi ad una considerazione in termini di semplice \u00abpersecuzione\u00bb e non di \u00absterminio\u00bb: \u00abForse \u2014 ricorda Schlesinger \u2014 eravamo talmente assorbiti dalla sordida minaccia della guerra, che non ci focalizzammo su questo inesprimibile abominio. \u00c8 anche possibile che l&#8217;idea di uno sterminio di massa fosse cos\u00ec al di l\u00e0 della normale capacit\u00e0 di comprensione degli americani di impedirci istintivamente di credere alla sua esistenza\u00bb.<\/p>\n<p style=\"text-align: justify;\">Se ormai \u00e8 abbastanza noto il ruolo che ha svolto del denunziare i cosiddetti \u00absilenzi\u00bb di Pio XII una serie di cattolici \u00abinquieti\u00bb nei primi anni del dopoguerra \u2014 esiste in merito un saggio di Giovanni Maria Vian che documenta le posizioni di Mounier e di Mauriac in Francia, in Italia di Carlo Bo \u2014 va ricordato che tali temi emersero largamente anche nelle grandi polemiche anticlericali che si svilupparono in Italia negli ultimi anni del pontificato pacelliano: le ritroviamo, per esempio, nel noto volume di Ernesto Rossi, <em>Il manganello e l&#8217;aspersorio <\/em>del 1957.<\/p>\n<p style=\"text-align: justify;\">Ma perch\u00e9 questi \u00absussurri\u00bb diventarono \u00abgrida\u00bb dopo il 1963? Il dramma di Hochhuth \u00e8 di lettura impervia e, se rappresentato integralmente, di una durata sterminata \u2014 in Italia, Gian Maria Volont\u00e9 dovette operare numerosi tagli per renderlo digeribile. In un dibattito parlamentare del marzo del 1965, un laico come il liberale Giovanni Malagodi ebbe a definirlo \u00abun dramma teatrale grossolano nella sua natura\u00bb. Come mai allora il suo impatto fu cos\u00ec devastante? Perch\u00e9 nel frattempo si era verificato un decisivo mutamento di sfondo culturale, che avrebbe condizionato tutto il dibattito successivo.<\/p>\n<p style=\"text-align: justify;\">Non c&#8217;\u00e8 dubbio che il processo Eichmann, svoltosi negli anni immediatamente precedenti, aveva riproposto di fronte a tutta l&#8217;opinione pubblica internazionale \u2014 specialmente alle generazioni che non avevano conosciuto la guerra \u2014 la tragedia dello sterminio e quindi dato una nuova centralit\u00e0 alla Shoah. Ma soprattutto si stava allora affermando nei Paesi dell&#8217;Europa occidentale e negli Usa una cultura che possiamo definire \u2014 con mille virgolette \u2014 \u00abprogressista\u00bb, che tracciava una determinata linea di progresso nella storia, individuando nel contempo le forze che premevano in quella direzione e quelle che vi facevano resistenza.<\/p>\n<p style=\"text-align: justify;\">Questa nuova cultura si basava essenzialmente su un giudizio intorno alla storia contemporanea, che possiamo cos\u00ec sintetizzare: tutto il vecchio mondo \u00e8 confluito nei fascismi; la loro liquidazione definitiva comporta anche una resa dei conti con quei valori e con quelle strutture \u00abtradizionali\u00bb che ad essi hanno dato appoggio o, comunque, ne hanno favorito l&#8217;ascesa. In questo contesto <em>Il vicario <\/em>di Hochhuth finiva per non riguardare soltanto Pio XII: esso metteva in discussione il ruolo svolto dalla Chiesa cattolica nell&#8217;intera storia del Novecento, contribuendo potentemente a mutare l&#8217;opinione fino ad allora prevalente.<\/p>\n<p style=\"text-align: justify;\">Negli stessi anni \u2014 ci sono in merito osservazioni importanti nei saggi di Andrea Riccardi e dello stesso Vian \u2014 un&#8217;operazione parallela a questa veniva svolta da alcuni ambienti che potremmo chiamare \u2014 anche qui le virgolette sono d&#8217;obbligo \u2014 di \u00abprogressismo cattolico\u00bb: il problema dei \u00absilenzi\u00bb di Pio XII rientrava nella pi\u00f9 generale questione costituita \u2014 a giudizio di questi ambienti \u2014 dal favore che la Chiesa avrebbe accordato ai movimenti fascisti.<\/p>\n<p style=\"text-align: justify;\">Esso non poteva essere considerato \u2014 si sosteneva \u2014 come un fatto accidentale, senza ragioni lontane. Ne emergeva una visione critica della storia della Chiesa in et\u00e0 moderna, nella quale si cominciava a vedere essenzialmente un limite: l&#8217;istituzione ecclesiastica si sarebbe posta generalmente dalla parte della \u00abreazione\u00bb, per cui le sue illusioni rispetto al fascismo altro non sarebbero state che la conclusione di un lungo processo.<\/p>\n<p style=\"text-align: justify;\">Questo errore corrispondeva, nelle sue radici ultime, a un difetto teologico che risaliva alla riforma cattolica e al concilio di Trento: da qui la necessit\u00e0 di una complessiva rifondazione teologica ed ecclesiale e le speranze nel concilio Vaticano II. Anche su queste basi nasce quell&#8217;\u00abermeneutica della discontinuit\u00e0\u00bb nella valutazione del concilio, di cui tanto si \u00e8 discusso in questi ultimi anni. Insomma la posta in gioco nei dibattiti su Pio XII \u00e8 \u2014 come si vede \u2014 assai rilevante: s&#8217;intende perch\u00e9 da allora la bibliografia sulla sua figura sia diventata sterminata e difficilmente controllabile da qualunque studioso.<\/p>\n<p style=\"text-align: justify;\">Quale contributo fornisce, allora, questo volume? Innanzitutto sarebbe fuor di luogo chiedergli nuova documentazione o prospettive di ricerca radicalmente innovative: si tratta \u2014 come ha dichiarato il suo curatore \u2014 di una raccolta di testi di alta divulgazione pubblicati precedentemente su \u00abL&#8217;Osservatore Romano\u00bb e poi spesso riscritti o rielaborati dai diversi autori \u2014 a essi sono aggiunti alcuni importanti interventi di Benedetto XVI sulla figura di Papa Pacelli e sul suo ruolo nella storia del Novecento.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 non toglie che ne emergano tutta una serie di suggestioni degne di nota: nell&#8217;attivit\u00e0 storiografica, il corretto ragionamento \u00e8 altrettanto importante del momento della ricerca documentaria. Il saggio di Andrea Riccardi offre un&#8217;ampia riflessione sulle varie fasi dell&#8217;attivit\u00e0 e del magistero di Eugenio Pacelli prima e poi di Pio XII, accennando a un tema da lui sviluppato anche altrove \u2014 per esempio nell&#8217;introduzione al suo ultimo libro <em>L&#8217;inverno pi\u00f9 lungo. 1943-44: Pio <\/em><em>XII<\/em><em>, gli ebrei e i nazisti a Roma <\/em>\u2014 e che a me pare assai rilevante nel nostro discorso: quello della debolezza \u00abpolitica\u00bb della Chiesa in un mondo di Stati, lacerato dai nazionalismi.<\/p>\n<p style=\"text-align: justify;\">Una Chiesa solo apparentemente forte, ma politicamente non \u00e8 mai tale, poich\u00e9 non controlla nessun territorio e deve fare i conti con poteri in loco, spesso di carattere autoritario o totalitario. Questa \u2014 per lo storico \u2014 \u00e8 la sua realt\u00e0 nel lungo periodo, oltre i miti in un senso o nell&#8217;altro.<\/p>\n<p style=\"text-align: justify;\">Chi ragiona della politica di Pio XII dal 1939 al 1945 non pu\u00f2 prescindere da questo sfondo: deve condurre un&#8217;analisi differenziata dei vari contesti europei, in relazione ai vari episcopati, alle personalit\u00e0 dei nunzi e alla natura dei governi di fronte ai quali ebbe a trovarsi l&#8217;azione della Santa Sede.<\/p>\n<p style=\"text-align: justify;\">Mentre per il Vaticano fu praticamente impossibile esercitare una qualche forma di influenza laddove i nazisti avevano un dominio diretto \u2014 quindi in Olanda, in Belgio, nella Francia occupata, in Polonia, in Ucraina, nella Russia conquistata, oltre che naturalmente in Germania \u2014 in alcuni degli Stati satelliti del Terzo Reich \u2014 specie se dichiaratamente confessionali \u2014 e in alcuni degli Stati alleati di Hitler, i suoi interventi un qualche risultato lo ottennero: talora riuscirono a posporre o a ritardare la deportazione di centinaia di migliaia di ebrei una parte dei quali nel frattempo pot\u00e9 essere salvata.<\/p>\n<p style=\"text-align: justify;\">Nella Slovacchia governata dal discusso monsignor Jozef Tiso, fra l&#8217;ottobre 1942 e l&#8217;autunno 1944 la deportazione venne sospesa per le continue pressioni del nunzio Giuseppe Burzio e della segreteria di Stato vaticana: si tratta di un caso pressoch\u00e9 unico nella storia della Shoah. Discriminati ma non deportati furono anche gli ebrei ungheresi, almeno finch\u00e9 rest\u00f2 al governo il protestante Mikl\u00f3s Horthy (cio\u00e8 sino al 23 marzo 1944) e anche qui \u00e8 nota l&#8217;azione svolta, prima e dopo quella data, dal nunzio monsignor Angelo Rotta.<\/p>\n<p style=\"text-align: justify;\">Minore smalto ebbe probabilmente l&#8217;intervento della Santa Sede nella Francia di Vichy, ma resta il fatto che l&#8217;ebraismo francese \u2014 con quello italiano \u2014 \u00e8 stato uno di quelli che percentualmente sono stati meno devastati dalla persecuzione nazista e che questo fu dovuto a un \u00abcontesto\u00bb, in cui la presenza ecclesiastica ebbe un notevole peso.<\/p>\n<p style=\"text-align: justify;\">\u00c8 merito di una serie di contributi quello di ricercare un approccio \u00abtotale\u00bb alla figura di Pio XII, la cui attivit\u00e0 e il cui pensiero non possono essere limitati agli anni del secondo conflitto mondiale, ma valutati in tutta la loro complessit\u00e0, dai primi passi del giovane monsignore romano fino alla fine degli anni Cinquanta \u2014 una prospettiva aperta da Riccardi negli anni Ottanta e continuata, per esempio, da Philippe Chenaux nella sua biografia del 2003.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec l&#8217;arcivescovo Rino Fisichella cerca di sintetizzare la risposta pacelliana alle sfide della \u00abmodernit\u00e0\u00bb, nella consapevolezza che essa non \u00e8 un valore in s\u00e9, ma appunto una sfida a cui rispondere in modo articolato e consapevole di una tradizione, che non pu\u00f2 essere dismessa. La \u00abcultura\u00bb \u2014 compatta ed enciclopedica \u2014 di Pio XII \u00e8 saggiata da diverse prospettive dall&#8217;arcivescovo Gianfranco Ravasi, che ricorda \u2014 fra i tanti spunti del suo saggio \u2014 il discorso del 6 dicembre 1953 all&#8217;Unione dei giuristi cattolici italiani, in cui offr\u00ec una teorizzazione della tolleranza religiosa, che prelude in qualche modo ai documenti conciliari.<\/p>\n<p style=\"text-align: justify;\">Il cardinale Tarcisio Bertone ripercorre l&#8217;azione diplomatica di Pacelli nunzio, segretario di Stato e romano pontefice. Anche qui mi limito a un&#8217;osservazione: Bertone sottolinea l&#8217;importanza del viaggio negli Stati Uniti che il cardinale Pacelli comp\u00ec nell&#8217;autunno del 1936 (<em>Carissimo Cardinali suo Transatlantico Panamerico Eugenio Pacelli feliciter redenti<\/em>: questa fu la dedica che Pio XI gli fece al suo ritorno).<\/p>\n<p style=\"text-align: justify;\">Nonostante la massa documentaria messa a disposizione dal volume di Ennio Di Nolfo del 1978, forse non si \u00e8 ancora messa del tutto a fuoco l&#8217;importanza del precoce vincolo fra Pacelli e gli Usa \u2014 Chenaux parla di \u00aballeanza morale\u00bb fra la Santa Sede e gli Stati Uniti nel decennio successivo. Non \u00e8 un problema indifferente al nostro discorso: gli Usa di Roosevelt sono un altro mondo rispetto alla Germania di Hitler e \u2014 direi \u2014 all&#8217;Europa continentale per lo pi\u00f9 in mano a Stati autoritari.<\/p>\n<p style=\"text-align: justify;\">Qualcosa cambia nelle coordinate di fondo del cardinale romano, nella sua complessiva visione dei problemi mondiali. Il segretario di Stato ricav\u00f2 una forte impressione dalla realt\u00e0 americana, dal suo \u00abdinamismo\u00bb e dalle sue potenzialit\u00e0: cominci\u00f2 a prender coscienza di un modello di societ\u00e0 diverso da quello tedesco, con cui aveva avuto, da sempre, profonda familiarit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Dopo la guerra, Pio XII non divenne \u2014 lo si ripete anche in questo volume \u2014il \u00abcappellano dell&#8217;Occidente\u00bb, ma indubbiamente fu una delle voce pi\u00f9 notevoli del vario anticomunismo europeo. Anche a questo proposito credo che ci si debba liberare da un certo anti-anticomunismo, residuo culturale degli anni Sessanta e Settanta.<\/p>\n<p style=\"text-align: justify;\">L&#8217;anticomunismo \u2014 come d&#8217;altronde l&#8217;antifascismo \u2014 fu un movimento estremamente variegato nei temi, nei punti di riferimento culturale e nelle prospettive politiche: esso quindi deve essere disaggregato e valutato nelle sue varie componenti. Ma riprendendo il titolo di un noto libro di John Lewis Gaddis, <em>We now know<\/em>: dopo l&#8217;apertura degli archivi sovietici, \u00e8 difficile imputare \u2014 per fare solo un esempio \u2014 ai vescovi tedeschi di avere fortemente sostenuto la politica atlantica ed europeista di Adenauer, resistendo alle sirene neutraliste e pacifiste di Stalin \u2014 e ci\u00f2 in piena sintonia con le indicazioni del Papa. Infine questo volume testimonia la possibilit\u00e0 di un fecondo incontro fra la cultura cattolica e quella ebraica anche su questi temi spinosi.<\/p>\n<p style=\"text-align: justify;\">Particolarmente toccanti sono le pagine di Saul Israel che vi vengono ripubblicate: si tratta di riflessioni e ricordi dell&#8217;\u00abebreo di Salonicco\u00bb, come lo chiamava Arturo Carlo Jemolo, nate nel convento di Sant&#8217;Antonio in via Merulana nell&#8217;aprile del 1944, dove riusc\u00ec a salvarsi dalla persecuzione nazista.<\/p>\n<p style=\"text-align: justify;\">Ancora Israel aveva rievocato, in un saggio apparso su \u00abStudium\u00bb, nell&#8217;ottobre 1950, la figura di Giulio Salvadori e il suo rapporto aperto e simpatetico con la tradizione ebraica: il poeta dell&#8217;\u00abumile Italia\u00bb fa parte di una linea di filosemitismo, che \u2014 sia pure minoritaria \u2014 \u00e8 presente nel cattolicesimo italiano degli ultimi due secoli e che deve essere ricuperata e adeguatamente valutata.<\/p>\n<p style=\"text-align: justify;\">Si \u00e8 cominciato a farlo col recente volume di Valerio De Cesaris, <em>Pro Judaeis<\/em>, ma molte figure devono essere ancora recuperate: senza questo retroterra, \u00e8 difficile capire fino in fondo lo \u00abSpiritualmente siamo tutti semiti\u00bb del lombardo e manzoniano Achille Ratti.<\/p>\n<p style=\"text-align: center;\">\u00a0<strong>E nel 1939 l&#8217;ebreo Emanuel Celler scrisse al Congresso<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;impegno della Santa Sede e di Pio XII per la giustizia e la pace nel mondo ebbe significativi riconoscimenti da parte ebraica anche prima dello scoppio della seconda guerra mondiale. \u00abPio XII si sta attivando per portare la pace in un mondo minacciato dalla guerra. Egli ci ha teso una mano di amicizia. Afferriamola e ristabiliamo quindi le relazioni diplomatiche\u00bb.<\/p>\n<p style=\"text-align: justify;\">Con questi toni inequivocabili Emanuel Celler, membro del Congresso statunitense e rappresentante della comunit\u00e0 ebraica di New York, si rivolgeva al segretario di Stato americano Cordell Hull in una lettera del 24 luglio del 1939. Lo ha ricordato, in un&#8217;intervista rilasciata ad Amedeo Lomonaco della Radio Vaticana, don Giovanni Caputa vicedirettore dell&#8217;Istituto teologico salesiano Ratisbonne di Gerusalemme nonch\u00e9 segretario della delegazione vaticana nella Commissione bilaterale Santa Sede &#8211; Israele.<\/p>\n<p style=\"text-align: justify;\">Nel documento risaltano l&#8217;importanza della religione \u00abnel preservare la democrazia contro le spietate incursioni di fascismo, nazismo e comunismo\u00bb e l&#8217;alto valore riposto dalla Santa Sede in valori quali la giustizia e la carit\u00e0. La lettera di Celler caldeggia anche il ristabilimento delle relazioni diplomatiche tra la Sede apostolica e gli Stati Uniti; relazioni che erano state stabilite il 15 dicembre 1784 sotto Pio VI, ed erano quindi state interrotte con la presa di Roma del 20 settembre 1870. Significativa qui risulta anche l&#8217;asserzione di Celler sull&#8217;antisemitismo che egli sa non essere mai stato condiviso dai \u00abrappresentanti della Chiesa cattolica\u00bb.<\/p>\n<p style=\"text-align: right;\">(<em>raffaele alessandrini<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Osservatore Romano luned\u00ec-marted\u00ec 27-28 luglio 2009 di Roberto Pertici (Universit\u00e0 di Bergamo) Un problema percorre molti saggi compresi nel volume In difesa di Pio XII. Le ragioni della storia (a cura di Giovanni Maria Vian, Venezia, Marsilio, 2009, pagine 168, euro 13): il mutamento di giudizio sulla figura di Pio XII, sul suo atteggiamento durante &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27350,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,24],"tags":[890],"class_list":["post-3393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa-ed-ebrei","category-storia","tag-pio-xii","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tra i sussurri e le grida la verit&agrave; della storia - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tra i sussurri e le grida la verit&agrave; della storia - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-29T09:03:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-10T14:05:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/ragioni_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"136\" \/>\n\t<meta property=\"og:image:height\" content=\"238\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Tra i sussurri e le grida la verit&agrave; della storia\",\"datePublished\":\"2009-07-29T09:03:15+00:00\",\"dateModified\":\"2015-11-10T14:05:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/\"},\"wordCount\":2962,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/ragioni_cover.jpg\",\"keywords\":[\"Pio XII\"],\"articleSection\":[\"Chiesa ed ebrei\",\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/\",\"name\":\"Tra i sussurri e le grida la verit&agrave; della storia - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/ragioni_cover.jpg\",\"datePublished\":\"2009-07-29T09:03:15+00:00\",\"dateModified\":\"2015-11-10T14:05:10+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/ragioni_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/ragioni_cover.jpg\",\"width\":136,\"height\":238},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tra-i-sussurri-e-le-grida-la-verit-della-storia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tra i sussurri e le grida la verit&agrave; della storia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tra i sussurri e le grida la verit&agrave; della storia - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/","og_locale":"it_IT","og_type":"article","og_title":"Tra i sussurri e le grida la verit&agrave; della storia - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-07-29T09:03:15+00:00","article_modified_time":"2015-11-10T14:05:10+00:00","og_image":[{"width":136,"height":238,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/ragioni_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"14 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Tra i sussurri e le grida la verit&agrave; della storia","datePublished":"2009-07-29T09:03:15+00:00","dateModified":"2015-11-10T14:05:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/"},"wordCount":2962,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/ragioni_cover.jpg","keywords":["Pio XII"],"articleSection":["Chiesa ed ebrei","Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/","name":"Tra i sussurri e le grida la verit&agrave; della storia - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/ragioni_cover.jpg","datePublished":"2009-07-29T09:03:15+00:00","dateModified":"2015-11-10T14:05:10+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/ragioni_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/07\/ragioni_cover.jpg","width":136,"height":238},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tra-i-sussurri-e-le-grida-la-verit-della-storia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Tra i sussurri e le grida la verit&agrave; della storia"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3393"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3393\/revisions"}],"predecessor-version":[{"id":27351,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3393\/revisions\/27351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27350"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}