{"id":33470,"date":"2016-04-28T00:00:50","date_gmt":"2016-04-27T22:00:50","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=33470"},"modified":"2016-04-26T17:04:49","modified_gmt":"2016-04-26T15:04:49","slug":"guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/","title":{"rendered":"Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33472 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/04\/Rapporto_VanThuan.jpg\" alt=\"Rapporto_VanThuan\" width=\"116\" height=\"169\" \/>Osservatorio Cardinale Van Thuan <strong>Newsletter<\/strong><\/p>\n<p style=\"text-align: center;\">n.690 del 26 aprile 2016<\/p>\n<p style=\"text-align: center;\"><strong>\u00a0<\/strong>di <strong>Stefano Fontana<\/strong> [1]<\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Il lettore che esamini nel dettaglio tutti i fatti di cronaca che riportiamo in appendice a questo Rapporto, rimarr\u00e0 colpito dalla grande quantit\u00e0 di atti di violenza e di persecuzione messi in atto da <em>Boko Haram<\/em> in Nigeria lungo tutto il 2014. Sono state fatte esplodere chiese cristiane con uccisione di un gran numero di fedeli, sono state rapite ragazze cristiane, sono stati uccisi molti fedeli. Si tratta di un evidente ritorno delle guerre di religione. Si sa che dietro, o sotto, ci sono anche altre cause, ma rimane indubbio che oggi, in questi casi acuti, il fattore religioso \u00e8 quello che fa da sintesi a tutti gli altri.<\/p>\n<p style=\"text-align: justify;\">Quando si parla di guerre di religione non si vuole infatti sostenere che il fattore religioso sia l\u2019unico in campo, ma che \u00e8 quello che riassume tutti gli altri, coordinandoli data la sua supremazia quanto a capacit\u00e0 di mobilitare le persone. Anche nel Cinquecento o nel Seicento le guerre di religione non erano solo di religione, ma ciononostante il fattore religioso faceva da coagulo per tutti gli altri. Cos\u00ec accade oggi in questi drammatici rigurgiti di guerre di religione.<\/p>\n<p style=\"text-align: justify;\">Se poi il lettore passa ad esaminare la cronaca dall\u2019America Latina, in modo particolare dall\u2019Argentina, o dalla Francia, o dalla Polonia, oppure scorre il capitolo sui principali avvenimenti di biopolitica nel 2014, si accorge che \u00e8 ben presente anche una guerra alla religione e, in particolare, alla religione cattolica. Non si tratta di una guerra dichiarata, convenzionale, con uso di armi e strategie militari. E\u2019 possibile chiamarla guerra solo in senso traslato. E\u2019 un conflitto, una lotta tramite leggi, licenziamenti, intimidazioni, l\u2019uso dei media, la destinazione di ingenti risorse alla propaganda contro la religione cattolica e i suoi presupposti.<\/p>\n<p style=\"text-align: justify;\">Mentre le guerre di religione sono dislocate nelle aree caratterizzate dai Califfati, questa guerra alla religione \u00e8 attuata soprattutto nell\u2019Occidente e, in particolare, in Europa. Il vecchio continente, tuttavia, \u00e8 anche interessato alle ripercussioni dentro i propri confini delle guerre di religione, dato il fenomeno del terrorismo e il reclutamento delle milizie islamiste nei sobborghi delle grandi citt\u00e0 europee, tra gli immigrati di seconda o di terza generazione. L\u2019Europa \u00e8 l\u2019epicentro di ambedue le tendenze di cui stiamo parlando.<\/p>\n<p style=\"text-align: justify;\">E\u2019 nostra convinzione che tra i due volti di Giano ci siano profondi collegamenti e che qualcosa di molto profondo e sottile colleghi tra loro le guerre di religione e la guerra alla religione. Di pi\u00f9: pensiamo che questo collegamento sia, pi\u00f9 che in ogni altra epoca passata, molto stretto nel nostro tempo, di cui rappresenta un segno inconfondibile.<\/p>\n<p style=\"text-align: justify;\">L\u2019Occidente \u00e8 troppo preso dalla sua guerra interna alla religione per potersi occupare delle guerre di religione in Siria o in Nigeria. E\u2019 troppo preoccupato di recidere i propri legami con la religione proclamando l\u2019indifferenza alle religioni, indebolendosi e rendendosi non pi\u00f9 capace di difendere nel mondo nemmeno il diritto alla libert\u00e0 di religione, che in un certo senso \u00e8 una sua creazione. L\u2019Occidente non dice una parola sulle le persecuzioni dei cristiani che raggiungono ormai cifre da genocidio e non ha trovato finora la spinta morale per intervenire a proteggere le popolazioni vittime dei Califfati o dei regimi dispotici a fondamento religioso.<\/p>\n<p style=\"text-align: justify;\">L\u2019Occidente \u00e8 sempre pi\u00f9 stanco, e l\u2019Europa in particolare, dissanguato nel morale dalla sua ostinata guerra contro la religione. Questa stanchezza si estende con grande velocit\u00e0 ai Paesi Latinoamericani che, al Cairo (1994) e a Pechino (1995), difendevano ancora \u2013 seppure in modo gi\u00e0 allora non cos\u00ec fermo \u2013 gli autentici diritti umani, fondati sulla legge morale naturale che aveva il suo garante nel Creatore, mentre il nostro Rapporto nota una certa positiva inversione di tendenza nei Paesi dell\u2019Europa orientale.<\/p>\n<p style=\"text-align: justify;\">Questi, dopo il lungo gelo del comunismo, ritornano, in modo ancora incerto e confuso, non solo all\u2019etica ma anche alla religione. E\u2019 questo un fenomeno che lascia ben sperare, se adeguatamente convogliato. Ed infatti, proprio in questi Paesi emergono atteggiamenti di intervento nella grande arena internazionale fuori dagli schemi ingessati delle convenienze della politica istituzionale con una rinnovata capacit\u00e0 di guardare in faccia la religione e le religioni, senza metterle tutte sullo steso piano, che vorrebbe dire privarle della loro diversa rilevanza pubblica.<\/p>\n<p style=\"text-align: justify;\">L\u2019Occidente \u00e8 ancora troppo legato al suo proprio concetto di libert\u00e0 religiosa, un concetto riduttivo, individualista, che valuta nelle religioni solo il sentimento dell\u2019adesione individuale e non il significato oggettivo delle loro credenze. Un concetto relativista, che non permette di individuare, nelle religioni, aspetti rifiutare e combattere o, almeno, da contenere, in nome della ragione e della vera religione. E che non permette, quindi, di trovare la forza di intervenire quando in nome della religione si producono violenze disumane e si negano gli stessi diritti umani fondamentali su cui si basa lo stesso diritto alla libert\u00e0 religiosa, nato in Occidente.<\/p>\n<p style=\"text-align: justify;\">I Paesi occidentali importano religioni ed esportano relativismo. Gli altri lo percepiscono come un ambito in cui entrare ma dal quale non imparare nulla. Se un Paese come l\u2019Inghilterra, di cos\u00ec lunga ed alta tradizione giuridica occidentale, ammette istituti giuridici propri della sharia islamica, compresa la presenza di tribunali islamici, significa che l\u2019Occidente ha disimparato l\u2019uso della ragione cui il Cristianesimo lo aveva educato.<\/p>\n<p style=\"text-align: justify;\">Queste considerazioni riguardano anche la gestione delle immigrazioni. Le guerre di religione, che penetrano fin nelle strade delle citt\u00e0 occidentali, come dimostrano gli attentati terroristici che purtroppo l\u2019opinione pubblica dimentica troppo velocemente, trovano un terreno favorevole in quanto proprio l\u00ec \u00e8 stata fatta una guerra alla religione.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 permesso prevedere oggi se le religioni presenti in Occidente si alleeranno tra loro contro la guerra alla religione, o se vi si accomoderanno, cercando di lucrare propri vantaggi di corporativismo religioso. Questo potrebbe essere anche il disegno dell\u2019Islam in Occidente. Come non si pu\u00f2 ancora prevedere se sulle religioni prevarr\u00e0 il secolarismo della guerra alla religione o il contrario. Molto dipender\u00e0 da un altro aspetto di queste nuove guerre, l\u2019aspetto demografico. L\u2019indice di natalit\u00e0 degli immigrati in Occidente ancora legati alla loro religione \u00e8 molto pi\u00f9 alto di quello dei Paesi occidentali.<\/p>\n<p style=\"text-align: justify;\">Tra qualche decennio in qualche Paese europeo ci sar\u00e0 il sorpasso. E\u2019 vero che, a contatto con la vita occidentale, anche la natalit\u00e0 delle famiglie islamiche \u2013 per fare l\u2019esempio pi\u00f9 interessante \u2013 tende a diminuire e forse certe previsioni di un sorpasso massiccio e precoce dovranno essere corrette, ma il divario rimane comunque molto significativo. La vita non pu\u00f2 essere una forma di guerra. Eppure, come nelle guerre ad alta identit\u00e0 religiosa ci sono i tristi fenomeni degli stupri di massa, anche la procreazione pu\u00f2 avere uno scopo competitivo. Molti musulmani europei non lo nascondono: si tratta di un conflitto portato avanti anche in quella forma.<\/p>\n<p style=\"text-align: justify;\">Di fronte a questi complessi problemi, la Dottrina sociale della Chiesa deve dare un contributo non generico, moralistico, semplicistico, ma realistico. I termini pace, accoglienza, solidariet\u00e0 possono essere caricati di deformazioni ideologiche se non tengono conto della verit\u00e0 e della realt\u00e0 delle cose. La politica dell\u2019integrazione non pu\u00f2 fingere di non vedere che molte comunit\u00e0 ospitate in Occidente non vogliono integrarsi, costituiscono una societ\u00e0 parallela e sistematicamente si contrappongono ai nuclei originari cercando di prevaricarli.<\/p>\n<p style=\"text-align: justify;\">L\u2019accoglienza non pu\u00f2 essere indiscriminata, perch\u00e9 in questo caso si favorirebbe l\u2019ingresso delle guerre di religione nel mondo occidentale. Il dovere di proteggere va riscoperto, anche nei confronti dei cittadini della propria nazione, dato che lo Stato mantiene nei loro confronti un dovere primario di provvedere al bene comune, ed anche nei confronti delle situazioni in cui nel mondo regimi confessionali volenti perpetuano massacri indiscriminati e fanno fuggire i loro abitanti in cerca di rifugio e di pace. Nei confronti di Boko Haram in Nigeria purtroppo non c\u2019\u00e8 stato nessun tipo di intervento internazionale.<\/p>\n<p style=\"text-align: justify;\">La Dottrina sociale della Chiesa non \u00e8 un sapere astratto. Esso \u00e8 concreto non solo perch\u00e9 offre anche piste di soluzione, ma prima di tutto perch\u00e9 \u00e8 realista, vede l\u2019uomo nella luce di Cristo, concreto in tutti i suoi veri bisogni, mentre le ideologie, comprese quelle del pacifismo, lo deformano secondo schemi calati dall\u2019altro e funzionali a qualche interesse.<\/p>\n<p style=\"text-align: justify;\">La via d\u2019uscita dalle guerre di religione e dalla guerra alla religione \u00e8 che, una volta colto il nesso tra le due dimensioni, si operi per una revisione sostanziale di come l\u2019Occidente vuole guardare alla religione e in particolare alla religione cristiana, perch\u00e9 da questo dipende anche il modo con cui esso guarder\u00e0 alle altre religioni e come queste guarderanno ad esso, all\u2019Occidente.<\/p>\n<p style=\"text-align: justify;\"><strong>[1] <\/strong>Direttore dell\u2019Osservatorio Cardinale van Thu\u00e2n sulla Dottrina sociale della Chiesa. Sottoscrivono la Sintesi introduttiva:<em>Fernando Fuentes Alcantara, <\/em>Direttore della Fundaci\u00f3n Pablo VI, Madrid; <em>Daniel Passaniti, <\/em>Direttore esecutivo CIES-Fundaci\u00f3n Aletheia, Buenos Aires; <em>Manuel Ugarte Cornejo, <\/em>Direttore del Centro de Pensamiento Social Cat\u00f3lico della Universidad San Pablo di Arequipa, Per\u00f9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Osservatorio Cardinale Van Thuan Newsletter n.690 del 26 aprile 2016 \u00a0di Stefano Fontana [1]<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33472,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,44],"tags":[2429],"class_list":["post-33470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-cristiani-perseguitati","tag-guerra-alla-religione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-27T22:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/04\/Rapporto_VanThuan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"116\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo\",\"datePublished\":\"2016-04-27T22:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/\"},\"wordCount\":1483,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Rapporto_VanThuan.jpg\",\"keywords\":[\"guerra alla religione\"],\"articleSection\":[\"Chiesa\",\"Cristiani perseguitati\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/\",\"name\":\"Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Rapporto_VanThuan.jpg\",\"datePublished\":\"2016-04-27T22:00:50+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Rapporto_VanThuan.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Rapporto_VanThuan.jpg\",\"width\":116,\"height\":169},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/","og_locale":"it_IT","og_type":"article","og_title":"Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2016-04-27T22:00:50+00:00","og_image":[{"width":116,"height":169,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/04\/Rapporto_VanThuan.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo","datePublished":"2016-04-27T22:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/"},"wordCount":1483,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/04\/Rapporto_VanThuan.jpg","keywords":["guerra alla religione"],"articleSection":["Chiesa","Cristiani perseguitati"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/","name":"Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/04\/Rapporto_VanThuan.jpg","datePublished":"2016-04-27T22:00:50+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/04\/Rapporto_VanThuan.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/04\/Rapporto_VanThuan.jpg","width":116,"height":169},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guerre-di-religione-guerre-alla-religione-sintesi-introduttiva-al-vii-rapporto-sulla-dottrina-sociale-della-chiesa-nel-mondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Guerre di religione, guerre alla religione. Sintesi introduttiva al VII Rapporto sulla dottrina sociale della chiesa nel mondo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/33470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=33470"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/33470\/revisions"}],"predecessor-version":[{"id":33473,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/33470\/revisions\/33473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33472"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=33470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=33470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=33470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}