{"id":3340,"date":"2009-06-04T00:00:00","date_gmt":"2009-06-03T22:00:00","guid":{"rendered":""},"modified":"2015-02-24T17:09:25","modified_gmt":"2015-02-24T16:09:25","slug":"unanalisi-critica-su-karl-rahner","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/","title":{"rendered":"Un\u2019analisi critica su Karl Rahner"},"content":{"rendered":"<div style=\"text-align: center;\"><strong>Corrispondenza Romana<\/strong> n.1092 del 16 maggio 2009<\/div>\n<p style=\"text-align: justify;\">L\u2019Istituto religioso dei Francescani dell\u2019Immacolata, fondato nel 1970 da due sacerdoti conventuali, \u00e8, con quasi mille membri tra frati, suore e religiose clarisse, uno dei pi\u00f9 recenti e dei pi\u00f9 promettenti virgulti dell\u2019immane piantagione dovuta al Serafico Padre san Francesco.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Da alcuni anni i loro teologi e docenti producono riviste o a grande divulgazione popolare (come il \u201cSettimanale di Padre Pio\u201d) oppure di rigoroso taglio teologico, storico e dottrinale (\u201cImmaculata Mediatrix\u201d, \u201cFides Catholica\u201d, \u201cAnnales Franciscani\u201d, i \u201cQuaderni di studi scotisti\u201d, etc.).<\/div>\n<p style=\"text-align: justify;\">Per loro iniziativa presso il Cenacolo del Ghirlandaio a Firenze il 22 e 23 novembre 2007 \u00e8 stato organizzato un importante convegno sulla figura sempre attuale e sempre controversa del teologo gesuita Karl Rahner (1904-1984), convegno presieduto da padre Serafino M. Lanzetta.<\/p>\n<p style=\"text-align: justify;\">Ora che gli atti del convegno sono di pubblico dominio (AA. VV., Karl Rahner. Un\u2019analisi critica, Cantagalli, Siena 2009, 18 \u20ac), speriamo che si apra un dibattito vasto e interessato sull\u2019apporto alla teologia e alla filosofia del massimo teorico contemporaneo della \u201csvolta antropologica\u201d.<\/p>\n<p style=\"text-align: justify;\">Gli autori dell\u2019opera, teologi sicuri e saldamente fondati nel Magistero della Chiesa, si collocano in aperta continuit\u00e0 con le riserve che furono gi\u00e0 espresse tanti anni fa verso il teologo badense da autori del calibro di Antonio Piolanti, Cornelio Fabro, Giuseppe Siri e Leo Scheffczyk.<\/p>\n<p style=\"text-align: justify;\">Il contesto teologico in cui si inserisce l\u2019analisi \u00e8 quello della radicale secolarizzazione e parcellizzazione della teologia dogmatica e morale che ha fatto seguito al Concilio Vaticano II (1962-1965): il novum conciliare, come lo chiam\u00f2 Giovanni Paolo II, sembr\u00f2 ad alcuni prestigiosi e altolocati uomini di Chiesa giustificare una ripresa delle istanze dell\u2019antico modernismo cattolico, nella versione ultima, post-heideggeriana e post-bultmaniana, della Nouvelle Th\u00e9ologie degli anni \u201950.<\/p>\n<p style=\"text-align: justify;\">Essendo impossibile ripercorrere qui la serrata critica dei validi autori alla Weltanschauung del gesuita, ci limitiamo a segnalare, come tipico tratto eterodosso, la tecnica eversiva rahneriana. Nel suo splendido saggio sulla virginitas in partu di Maria, il mariologo p. Alessandro Apollonio nota che \u00abil metodo di Rahner andrebbe paragonato ad uno stillicidio corrosivo: corrodere la fede genuina nella Verit\u00e0 rivelata, instillando progressivamente, goccia dopo goccia, piccoli e insidiosi dubbi, mescolati in una massa sostanzialmente buona in s\u00e9\u00bb (p. 223).<\/p>\n<p style=\"text-align: justify;\">Questa affermazione, purtroppo, potrebbe essere applicata al rinnovamento post-conciliare in genere in cui, una massa di idee e opere sostanzialmente buone in s\u00e9, \u00e8 stata per\u00f2 non gi\u00e0 fermentata da uno spirito cattolico puro, cristallino e scevro da compromessi, ma corrotta, ove pi\u00f9 ove meno, dallo spirito di adattamento della Rivelazione Divina alla cultura, sempre mutevole ed effimera, dell\u2019astratto e inconsistente \u201cuomo di oggi\u201d.<\/p>\n<p style=\"text-align: justify;\">Prima che correggere le espressioni ambigue che compaiono qua e l\u00e0 in documenti episcopali, iniziative pastorali e sperimentazioni liturgiche, bisognerebbe allora correggere l\u2019intenzione che li ha animati, rinsaldando la pastorale dell\u2019aggiornamento alla dogmatica, l\u2019antropologia e la sociologia semi-cattoliche alla teologia tradizionale, e insinuando nel cuore dei fedeli lo zelo per l\u2019evangelizzazione, la meditazione, la formazione culturale, l\u2019ascesi e la propagazione della fede.<\/p>\n<p style=\"text-align: justify;\">\u00abPer dare un\u2019idea della mens teologica rahneriana, si potrebbe usare anche l\u2019immagine del piano inclinato: Rahner non ha certo toccato il fondo della teologia, ma ha cominciato a inclinare il piano e a muovere i primi passi (\u2026). Si sa, basta un millesimo di grado e la retta inclinata porter\u00e0 all\u2019infinito una distanza infinita dal piano orizzontale.<\/p>\n<p style=\"text-align: justify;\">Ora, il piano inclinato \u00e8 quello di una filosofia sbagliata, una filosofia che potremmo definire, parafrasando san Pio X, la sintesi di tutto l\u2019immanentismo moderno\u00bb (p. 224).<\/p>\n<p style=\"text-align: justify;\">______________________<\/p>\n<p style=\"text-align: justify;\"><strong>Leggi anche:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=3368\" target=\"_blank\">Karl Rahner maestro del Concilio, di martini e della coscienza relativa<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=3283\" target=\"_blank\">&#8220;Modesnismo&#8221;. S\u00ec, fu un&#8217;eresia e il suo erede \u00e8 il progressismo<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=3430\" target=\"_blank\">Karl Rahner un cristianesimo senza radici<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corrispondenza Romana n.1092 del 16 maggio 2009 L\u2019Istituto religioso dei Francescani dell\u2019Immacolata, fondato nel 1970 da due sacerdoti conventuali, \u00e8, con quasi mille membri tra frati, suore e religiose clarisse, uno dei pi\u00f9 recenti e dei pi\u00f9 promettenti virgulti dell\u2019immane piantagione dovuta al Serafico Padre san Francesco.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,45],"tags":[789],"class_list":["post-3340","post","type-post","status-publish","format-standard","hentry","category-chiesa","category-progressismo-cattolico","tag-progressismo-cattolico-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un\u2019analisi critica su Karl Rahner - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un\u2019analisi critica su Karl Rahner - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-03T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-02-24T16:09:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"163\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unanalisi-critica-su-karl-rahner\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unanalisi-critica-su-karl-rahner\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Un\u2019analisi critica su Karl Rahner\",\"datePublished\":\"2009-06-03T22:00:00+00:00\",\"dateModified\":\"2015-02-24T16:09:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unanalisi-critica-su-karl-rahner\\\/\"},\"wordCount\":611,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"keywords\":[\"progressismo cattolico\"],\"articleSection\":[\"Chiesa\",\"Progressismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unanalisi-critica-su-karl-rahner\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unanalisi-critica-su-karl-rahner\\\/\",\"name\":\"Un\u2019analisi critica su Karl Rahner - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"datePublished\":\"2009-06-03T22:00:00+00:00\",\"dateModified\":\"2015-02-24T16:09:25+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unanalisi-critica-su-karl-rahner\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unanalisi-critica-su-karl-rahner\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unanalisi-critica-su-karl-rahner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un\u2019analisi critica su Karl Rahner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un\u2019analisi critica su Karl Rahner - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/","og_locale":"it_IT","og_type":"article","og_title":"Un\u2019analisi critica su Karl Rahner - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-06-03T22:00:00+00:00","article_modified_time":"2015-02-24T16:09:25+00:00","og_image":[{"width":600,"height":163,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna.gif","type":"image\/gif"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Un\u2019analisi critica su Karl Rahner","datePublished":"2009-06-03T22:00:00+00:00","dateModified":"2015-02-24T16:09:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/"},"wordCount":611,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"keywords":["progressismo cattolico"],"articleSection":["Chiesa","Progressismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/","name":"Un\u2019analisi critica su Karl Rahner - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"datePublished":"2009-06-03T22:00:00+00:00","dateModified":"2015-02-24T16:09:25+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unanalisi-critica-su-karl-rahner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Un\u2019analisi critica su Karl Rahner"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3340"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3340\/revisions"}],"predecessor-version":[{"id":19806,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3340\/revisions\/19806"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}