{"id":331,"date":"2005-01-21T13:59:39","date_gmt":"2005-01-21T12:59:39","guid":{"rendered":""},"modified":"2025-07-07T11:56:30","modified_gmt":"2025-07-07T09:56:30","slug":"il-dissenso-teologico-aggiornato","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/","title":{"rendered":"Il dissenso teologico aggiornato"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><br><strong><a href=\"https:\/\/alleanzacattolica.org\/indici-cristianita\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cristianit\u00e0<\/a><\/strong> n. 204 (1992)&lt;\/div<\/p>\n\n\n\n<p><em>&#8220;mentre <\/em>[&#8230;]<em> una teologia radicata nella parola di Dio e aderente al magistero della Chiesa \u00e8 sommamente utile per il compito dell\u2019evangelizzazione, si deve riconoscere che il &#8220;dissenso&#8221; teologico costituisce un ostacolo per l\u2019opera evangelizzatrice, in primo luogo per quella che si deve attuare continuamente all\u2019interno della Chiesa stessa&#8221;<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">di<strong> Giovanni Cantoni<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/Concilium_cover.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"280\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/Concilium_cover.jpg\" alt=\"\" class=\"wp-image-35672\" style=\"width:224px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<!--more-->\n\n\n\n<p><strong>1.<\/strong> Nella dichiarazione <em>Siamo testimoni di Cristo che ci ha liberato<\/em>, i presuli partecipanti all\u2019Assemblea Speciale per l\u2019Europa del Sinodo dei Vescovi &#8211; svoltasi in Vaticano dal 28 novembre al 14 dicembre 1991 &#8211; affermano che, <em>&#8220;mentre <\/em>[&#8230;]<em> una teologia radicata nella parola di Dio e aderente al magistero della Chiesa \u00e8 sommamente utile per il compito dell\u2019evangelizzazione, si deve riconoscere che il &#8220;dissenso&#8221; teologico costituisce un ostacolo per l\u2019opera evangelizzatrice, in primo luogo per quella che si deve attuare continuamente all\u2019interno della Chiesa stessa&#8221;<\/em> (1).<\/p>\n\n\n\n<p><strong>2.<\/strong> A chi ha ritenuto il monito espressione di <em>routine<\/em> ecclesiastica e come tale lo ha accolto, offre prova certa della sua puntualit\u00e0 un\u2019intervista allo scolopio toscano padre Ernesto Balducci, raccolta a met\u00e0 febbraio del 1992 da Carlo Formenti per il supplemento settimanale del <em>Corriere della Sera<\/em> (2). Le affermazioni in essa contenute contrastano in modo tanto evidente con l\u2019ortodossia e con l\u2019ortoprassi cattoliche da non necessitare di commento; ma \u00e8 di qualche importanza conoscerle sia per il loro carattere esplicito, sia perch\u00e9 il &#8220;pulpito&#8221; messo a disposizione da chi le pronuncia le qualifica in modo inequivoco come funzionali al progetto di secolarizzazione, <em>&#8220;<\/em>[&#8230;]<em> cio\u00e8 di estromissione della motivazione e della finalit\u00e0 religiosa da ogni atto della vita umana&#8221;<\/em> (3), quindi come autentico ostacolo all\u2019evangelizzazione.<\/p>\n\n\n\n<p><strong>3.<\/strong> Dunque, secondo padre Ernesto Balducci <em>&#8220;il cristianesimo in quanto religione \u00e8 in crisi irreversibile&#8221;<\/em>, <em>&#8220;<\/em>[&#8230;]<em> \u00e8 attraversato da una scissione: in quanto profezia messianica, esso predice l\u2019avvento di un uomo che non \u00e8 mai stato, un uomo futuro che realizzer\u00e0 quelle possibilit\u00e0 che non hanno ancora trovato attuazione<\/em>[&#8230;]<em>. In questo senso la fede cristiana non \u00e8 una &#8220;religione&#8221;. Essa si \u00e8 trasformata in religione in quanto ha assunto delle forme culturali particolaristiche, che coincidono con la storia dell\u2019Occidente. Giovanni Paolo II \u00e8 interno a questo cristianesimo storico che ha avuto la sua formulazione pi\u00f9 rigorosa nel Concilio di Trento, e che \u00e8 vissuto condannando tutte le conquiste politiche e scientifiche dell\u2019umanit\u00e0&#8221;<\/em>; egli \u00e8 <em>&#8220;<\/em>[&#8230;]<em> un <\/em>vir catholicus <em>nel senso tridentino-polacco, <\/em>[quindi]<em> torna ora ad affermare che la Chiesa \u00e8 l\u2019anima dell\u2019Europa. Un Iuogo comune ormai privo di senso, che legittima una cultura che ha anche espresso i roghi contro gli eretici&#8221;<\/em>.<\/p>\n\n\n\n<p><strong>4.<\/strong> Ma la situazione attuale \u00e8 ancipite, nota lo scolopio: infatti, <em>&#8220;oggi viviamo nell\u2019evento della dissociazione fra la forma culturale, relativa, e la potenzialit\u00e0 messianico-profetica del cristianesimo&#8221;<\/em>. <em>&#8220;Gi\u00e0 nel 1871 Darwin diceva che, di fronte alla scoperta che la Terra \u00e8 l\u2019unico ambiente vitale comune a tutta la specie, i vincoli di &#8220;simpatia&#8221; che nel passato legavano fra loro i membri di una stessa trib\u00f9, citt\u00e0 o nazione avrebbero dovuto abbracciare tutti gli abitanti del pianeta. Oggi siamo arrivati a questa soglia&#8221;<\/em>; <em>&#8220;ma per affrontare la sfida dell\u2019et\u00e0 planetaria <\/em>[&#8230;]<em> bisogna capire qual \u00e8 l\u2019attuale fase evolutiva della nostra specie. La prima fase \u00e8 stata quella dell\u2019ominazione: uscendo dalla lotta per la vita basata sulla selezione naturale, l\u2019homo sapiens entr\u00f2 nella fase culturale, in cui l\u2019evoluzione non \u00e8 pi\u00f9 il risultato della selezione ma di un &#8220;progetto&#8221; evolutivo. Un progetto, tuttavia, sempre dominato dalle strutture psichiche e sociali dell\u2019antagonismo, dalla legge della &#8220;guerra madre di tutte le cose&#8221; di cui parlava Eraclito. Io per\u00f2 <\/em>&#8211; tiene a precisare l\u2019intervistato &#8211;<em> non sono d\u2019accordo con chi vede nel passato solo conflitti: oltre alle pulsioni aggressive, l\u2019uomo ha sempre avvertito l\u2019impulso opposto all\u2019amicizia; per dirla con Freud: non c\u2019\u00e8 solo Thanatos, c\u2019\u00e8 anche Eros. Cos\u00ec come non sono d\u2019accordo con chi ritiene che la natura umana sia immutabile, segnata dal &#8220;peccato originale&#8221;: la nostra storia evolutiva dimostra al contrario che l\u2019uomo \u00e8 un essere plastico, modificabile&#8221;<\/em>.<\/p>\n\n\n\n<p><strong>5.<\/strong> Passando dalla dottrina, e dalla cultura in cui si incarna, alla morale, lo stesso scolopio afferma che, mentre <em>&#8220;il problema demografico \u00e8 la pi\u00f9 grande sfida epocale <\/em>[&#8230;]<em> il messaggio che arriva alla gente comune \u00e8 solo questo: la Chiesa \u00e8 contraria ai metodi contraccettivi, e cio\u00e8 un messaggio che non tiene conto della responsabilit\u00e0 nei confronti dell\u2019umanit\u00e0 intera. Su questi temi il cristianesimo storico sar\u00e0 sbaragliato. <\/em>[&#8230;]<em> Cos\u00ec come il cattolicesimo \u00e8 la fede cristiana incarnata nella filosofia platonica, spesso fino a identificarsi con essa, dovr\u00e0 incarnarsi nelle idee della nuova scienza&#8221;<\/em>.<\/p>\n\n\n\n<p><strong>6.<\/strong>&nbsp;<em>Rebus sic stantibus<\/em>, emerge finalmente il problema del &#8220;che fare&#8221;, anche a fronte di chi, come Hans K\u00fcng, ritiene che il dissenso sia in regresso e la <em>&#8220;restaurazione&#8221;<\/em> avanzi. In proposito, padre Ernesto Balducci afferma che <em>&#8220;K\u00fcng \u00e8 rimasto troppo &#8220;cattolico&#8221;: interpreta il fatto che sono diminuiti i fenomeni di contestazione della Chiesa dall\u2019alto come una restaurazione del potere gerarchico&#8221;<\/em>; quindi periodizza significativamente: <em>&#8220;Nella fase dell\u2019integrismo preconciliare chi dissentiva diventava spretato, eretico, reietto; poi \u00e8 venuta la fase dell\u2019antagonismo fra Chiesa conciliare e Chiesa apparato; oggi stiamo vivendo una terza fase: c\u2019\u00e8 la Chiesa apparato e poi c\u2019\u00e8 una forma comunitaria che progredisce autonomamente senza confrontarsi con la prima, che non ne tiene semplicemente conto. Facciamo l\u2019esempio dell\u2019America Latina: \u00e8 vero che la teologia della liberazione \u00e8 vessata, che Roma impone vescovi allineati all\u2019Opus Dei, ma poi succede che, quando si insediano, non dispongono di strutture su cui far presa, di preti che condividono le loro idee. C\u2019\u00e8 una &#8220;Chiesa duale&#8221;, c\u2019\u00e8 un dimorfismo evolutivo per cui mi viene a volte di dire provocatoriamente che il Vaticano rischia di diventare un gruppo del dissenso&#8221;<\/em>.<\/p>\n\n\n\n<p><strong>7.<\/strong> Dunque, secondo l\u2019esponente del dissenso, <em>&#8220;<\/em>[&#8230;]<em> \u00e8 giunta l\u2019ora di un nuovo adattamento della specie al suo ambiente <\/em>[&#8230;]<em>. <\/em>[I nuovi scienziati]<em> ci hanno fatto capire la necessit\u00e0 di costruire una &#8220;comunit\u00e0 creaturale&#8221;: noi abbiamo sempre parlato di una comunit\u00e0 fra gli uomini, ma la nuova comunit\u00e0 dev\u2019essere quella fra tutte le creature. La nuova etica si rivela come una &#8220;religione naturale&#8221; con cui dovranno misurarsi le religioni positive, la cui origine \u00e8 nella comunione fra tutte le creature che si rivela alla coscienza che ha preso atto delle interconnessioni che legano l\u2019uomo all\u2019uomo e gli uomini alle cose. Nel coincidere con questo substrato materiale e biologico la necessit\u00e0 etica non muore: ritrova il suo senso profondo che \u00e8, a dispetto di tutti gli spiritualismi, la custodia del fuoco della vita su questo pianeta&#8221;<\/em>.<\/p>\n\n\n\n<p><strong>8.<\/strong> Quanto alla politica, <em>&#8220;<\/em>[&#8230;]<em> pi\u00f9 grave dell\u2019inaffidabilit\u00e0 morale dei partiti \u00e8 la loro impotenza &#8211; che coincide con l\u2019impotenza del moderno Stato-nazione &#8211; ad affrontare le sfide dell\u2019et\u00e0 planetaria, i problemi che io definisco &#8220;assoluti&#8221;, come quelli dell\u2019ecologia, dell\u2019immigrazione, della droga&#8221;<\/em>. Per esempio, relativamente alla droga, <em>&#8220;la legge del \u201991 ha trasformato nuovamente il tossicodipendente in un criminale. Le carceri sono piene di detenuti condannati per questo tipo di reati, e i sieropositivi aumentano continuamente perch\u00e9 una siringa costa mezzo milione al mercato nero e, ovviamente, la usano in decine di persone. \u00c8 il punto d\u2019arrivo di una catena causale mondiale che mobilita enormi interessi contro i quali solo quella che io chiamo la &#8220;cosmopoli&#8221;, il nucleo costitutivo di una comunit\u00e0 politica mondiale, pu\u00f2 prevalere. O arriveremo a creare questa autorit\u00e0 politica mondiale o andremo sempre di pi\u00f9 verso la disgregazione e la crisi&#8221;<\/em>.<\/p>\n\n\n\n<p><strong>9.<\/strong> Dunque, il vecchio progressismo catto-comunista si &#8220;aggiorna&#8221;, si rivela anche catto-mondialista e, se non propone pi\u00f9 di &#8220;battezzare&#8221; Karl Marx razionalista, richiama Karl Marx romantico, &#8220;letto&#8221; da Ernst Bloch (4) e all\u2019interno di una <em>fili\u00e8re<\/em> che da Charles Robert Darwin passa attraverso Sigmund Freud: <em>&#8220;La qualifica di cristiano <\/em>&#8211; afferma esplicitamente padre Ernesto Balducci &#8211;<em>, in quanto mi differenzia dagli altri, mi pesa. Il termine \u00e8 nato ad Antiochia, nel 43 d. C., coniato da burocrati romani per &#8220;schedare&#8221; quelle comunit\u00e0 poco conformi alle regole sociali.<\/em>[&#8230;]<em> \u00c8 vicino il giorno in cui capiremo che Ges\u00f9 non intese dar vita a una nuova &#8220;religione&#8221;, ma abbattere tutte le barriere che impediscono all\u2019uomo di essere fratello all\u2019uomo. Se voglio sapere se uno \u00e8 cristiano non gli chiedo se crede, ma come assume la responsabilit\u00e0 del prossimo. Bloch diceva che solo un ateo pu\u00f2 essere un vero cristiano, e solo un vero cristiano pu\u00f2 essere ateo nel senso che nega il &#8220;dio della trib\u00f9&#8221;&#8221;<\/em>.<\/p>\n\n\n\n<p>Quanto all\u2019azione, il <em>new look<\/em> del dissenso pratica la disattenzione organizzata nei confronti della Chiesa gerarchica, cio\u00e8 la trasformazione del dissenso dottrinale in dissenso sociologico, inteso a ridurre lo stesso <em>&#8220;Vaticano&#8221;<\/em>, in una prospettiva appunto sociologica e quantitativa, a un <em>&#8220;gruppo del dissenso&#8221;<\/em>. Mentre devo registrare con dispiacere il fatto che padre Ernesto Balducci possa esternare quanto riportato senza incorrere in nessuna censura ecclesiastica, utile in tesi anche a lui, ma, in tesi e in ipotesi, certamente profittevole al popolo di Dio che lo incontra sui <em>mass media<\/em>, medito e propongo di meditare le parole del Signore Ges\u00f9 relativamente al <em>&#8220;piccolo gregge&#8221;<\/em> (5) e una tesi di san Bonaventura secondo cui <em>&#8220;il Sommo <\/em>[&#8230;]<em> Pontefice <\/em>[&#8230;]<em> \u00e8 vicario di Cristo sulla terra; perci\u00f2, anche se fosse solo, e tutto nella Chiesa fosse distrutto, potrebbe restaurare tutto&#8221;<\/em> (6).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Note:<\/strong><\/h4>\n\n\n\n<p><strong>1)<\/strong> Sinodo dei Vescovi. Assemblea Speciale per l\u2019Europa, Dichiarazione <em>Siamo testimoni di Cristo che ci ha liberato<\/em>, n. 5; a esposizione e a commento cfr. il mio <em>Per la &#8220;nuova evangelizzazione&#8221; dell\u2019Europa<\/em>, in <em>Cristianit\u00e0<\/em>, anno XIX, n. 200, dicembre 1991.<br><strong>2)<\/strong> Cfr. Ernesto Balducci S.P., <em>Dalla crisi delle religioni alla rinascita della fede<\/em>, intervista a cura di Carlo Formenti, in <em>7 Supplemento del Corriere della Sera<\/em>, n. 7, s.i.d. ma 15-2-1992, pp. 23-30. Tutte le citazioni senza rimando sono tratte da questo testo, che si presenta implicitamente come esposizione sintetica delle tesi dell\u2019opera dello stesso padre scolopio <em>La terra del tramonto. Saggio sulla transizione<\/em>, Edizioni Cultura della Pace, San Domenico di Fiesole (FI) 1992.<strong><br>3)<\/strong> Giovanni Paolo II, <em>Annunciare il valore religioso della vita umana. Discorso &#8220;Sono lieto&#8221;<\/em>, del 1\u00b0-3-1991, n. 1, Cristianit\u00e0, Piacenza 1991, p. 5.<br><strong>4)<\/strong> Cfr. il mio <em>Fra crisi e &#8220;ristrutturazione&#8221;: ipotesi sul futuro dell\u2019impero socialcomunista<\/em>, in <em>Cristianit\u00e0<\/em>, anno XVIII, n. 187-188, novembre-dicembre 1990.<br><strong>5)<\/strong> Cfr. <em>Lc<\/em>. 12, 32.<br><strong>6)<\/strong> San Bonaventura, <em>Quaestiones disputatae de perfectione evangelica<\/em>, q. 4, a. 3, ad 15, in <em>Obras de San Buenaventura<\/em>, ed. bilingue, vol. VI, Biblioteca de Autores Cristianos, Madrid 1972, p. 330.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cristianit\u00e0 n. 204 (1992)&lt;\/div &#8220;mentre [&#8230;] una teologia radicata nella parola di Dio e aderente al magistero della Chiesa \u00e8 sommamente utile per il compito dell\u2019evangelizzazione, si deve riconoscere che il &#8220;dissenso&#8221; teologico costituisce un ostacolo per l\u2019opera evangelizzatrice, in primo luogo per quella che si deve attuare continuamente all\u2019interno della Chiesa stessa&#8221; di Giovanni &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":35672,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,45],"tags":[1263,1847],"class_list":["post-331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-progressismo-cattolico","tag-concilium","tag-teologia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il dissenso teologico aggiornato - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Il dissenso teologico aggiornato \u00e8 un ostacolo per l\u2019opera evangelizzatrice, in primo luogo per quella che si deve attuare nella Chiesa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il dissenso teologico aggiornato - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Il dissenso teologico aggiornato \u00e8 un ostacolo per l\u2019opera evangelizzatrice, in primo luogo per quella che si deve attuare nella Chiesa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-01-21T12:59:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T09:56:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/Concilium_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"180\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il dissenso teologico aggiornato\",\"datePublished\":\"2005-01-21T12:59:39+00:00\",\"dateModified\":\"2025-07-07T09:56:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/\"},\"wordCount\":1684,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/01\\\/Concilium_cover.jpg\",\"keywords\":[\"concilium\",\"teologia\"],\"articleSection\":[\"Chiesa\",\"Progressismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/\",\"name\":\"Il dissenso teologico aggiornato - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/01\\\/Concilium_cover.jpg\",\"datePublished\":\"2005-01-21T12:59:39+00:00\",\"dateModified\":\"2025-07-07T09:56:30+00:00\",\"description\":\"Il dissenso teologico aggiornato \u00e8 un ostacolo per l\u2019opera evangelizzatrice, in primo luogo per quella che si deve attuare nella Chiesa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/01\\\/Concilium_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/01\\\/Concilium_cover.jpg\",\"width\":180,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-dissenso-teologico-aggiornato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il dissenso teologico aggiornato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il dissenso teologico aggiornato - Rassegna Stampa Cattolica","description":"Il dissenso teologico aggiornato \u00e8 un ostacolo per l\u2019opera evangelizzatrice, in primo luogo per quella che si deve attuare nella Chiesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/","og_locale":"it_IT","og_type":"article","og_title":"Il dissenso teologico aggiornato - Rassegna Stampa Cattolica","og_description":"Il dissenso teologico aggiornato \u00e8 un ostacolo per l\u2019opera evangelizzatrice, in primo luogo per quella che si deve attuare nella Chiesa","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-01-21T12:59:39+00:00","article_modified_time":"2025-07-07T09:56:30+00:00","og_image":[{"width":180,"height":280,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/Concilium_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il dissenso teologico aggiornato","datePublished":"2005-01-21T12:59:39+00:00","dateModified":"2025-07-07T09:56:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/"},"wordCount":1684,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/Concilium_cover.jpg","keywords":["concilium","teologia"],"articleSection":["Chiesa","Progressismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/","name":"Il dissenso teologico aggiornato - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/Concilium_cover.jpg","datePublished":"2005-01-21T12:59:39+00:00","dateModified":"2025-07-07T09:56:30+00:00","description":"Il dissenso teologico aggiornato \u00e8 un ostacolo per l\u2019opera evangelizzatrice, in primo luogo per quella che si deve attuare nella Chiesa","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/Concilium_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/Concilium_cover.jpg","width":180,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-dissenso-teologico-aggiornato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il dissenso teologico aggiornato"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=331"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/331\/revisions"}],"predecessor-version":[{"id":63023,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/331\/revisions\/63023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/35672"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}