{"id":3285,"date":"2009-05-06T15:54:44","date_gmt":"2009-05-06T13:54:44","guid":{"rendered":""},"modified":"2016-02-22T09:48:20","modified_gmt":"2016-02-22T08:48:20","slug":"religione-e-rivoluzione-francese-2","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/","title":{"rendered":"Religione e Rivoluzione francese (2)"},"content":{"rendered":"<div style=\"text-align: center;\">dal sito di <strong><a href=\"http:\/\/www.alleanzacattolica.org\/temi\/rivoluzione_francese\/introvignem.htm\" target=\"_blank\">Alleanza Cattolica<\/a><\/strong><\/div>\n<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/preti_refrattari.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-30785\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/preti_refrattari.jpg\" alt=\"preti_refrattari\" width=\"250\" height=\"166\" \/><\/a><\/div>\n<p style=\"text-align: center;\">\u00a0di<strong> Massimo Introvigne<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: center;\"><strong>II. I cattolici e la Rivoluzione: sguardi retrospettivi nell&#8217;Ottocento e nel Novecento<\/strong><\/div>\n<p style=\"text-align: justify;\"><strong>1. I cattolici e le grandi correnti storiografiche dell&#8217;Ottocento<\/strong><\/p>\n<p style=\"text-align: justify;\">Nell&#8217;Ottocento e fino alla prima guerra mondiale &#8211; in un&#8217;epoca in cui le passioni suscitate dalla Rivoluzione continuano a rimanere presenti e attuali sulla scena politica della Francia e dell&#8217;Europa &#8211; tre teorie si contendono il campo fra gli storici e gli intellettuali quando si tratta di spiegare e di interpretare la Rivoluzione francese, vista di volta in volta come &#8220;fenomeno divino&#8221;, come &#8220;meccanismo sociale&#8221; oppure come &#8220;complotto&#8221; o &#8220;disegno&#8221; (39).<\/p>\n<p style=\"text-align: justify;\">Naturalmente ciascuna di queste teorie viene proposta con un segno o un&#8217;intonazione diversa dai sostenitori e, rispettivamente, dagli avversari della Rivoluzione; nel secondo campo si colloca, per tutto l&#8217;Ottocento, la maggioranza dei cattolici che esercitano la professione di storico. Fenomeno divino, meccanismo sociale oppure disegno preordinato?<\/p>\n<p style=\"text-align: justify;\">Agli inizi del nostro secolo gli storici cattolici anti-rivoluzionari si apprestavano a proporre un&#8217;interpretazione sintetica, secondo cui il piano o progetto della Rivoluzione sarebbe nato come un disegno in una serie di circoli e di minoranze, che operavano in parte autonomamente, in parte in modo coordinato. Una volta avviato, il fenomeno rivoluzionario presentava tutta una serie di aspetti meccanici e poteva essere descritto esattamente anche come una &#8220;macchina&#8221;.<\/p>\n<p style=\"text-align: justify;\">Tuttavia si trattava di una macchina che aveva un orientamento e un significato: un orientamento &#8220;filosofico&#8221;, per cui si rimandava all&#8217;illuminismo, e un significato che non poteva essere compreso nella sua profondit\u00e0 senza fare riferimento anche a categorie teologiche, per cui non si mancava di riprendere in esame le teorie che vedevano nella Rivoluzione francese un &#8220;fenomeno divino&#8221;.<\/p>\n<p style=\"text-align: justify;\">Ma &#8211; nel momento in cui ponevano mano alla sintesi &#8211; gli storici cattolici anti-rivoluzionari si accorgevano che nel mondo cattolico era cominciato a crescere un altro tipo di percezione della Rivoluzione francese, che si sforzava di metterne in luce &#8211; talora con cautela, altre volte con entusiasmo &#8211; anche aspetti che giudicava positivi.<\/p>\n<p style=\"text-align: justify;\"><strong>2. &#8220;Rivalutazioni&#8221; cattoliche della Rivoluzione francese<\/strong><\/p>\n<p style=\"text-align: justify;\">La storia della rivalutazione, da parte di storici cattolici, di aspetti giudicati positivi della Rivoluzione francese coincide con la storia della corrente di pensiero chiamata comunemente cattolico-democratica, che costituisce uno dei filoni pi\u00f9 importanti, anche se non l&#8217;unico, del movimento che si \u00e8 affermato sul piano politico con il nome di democratico-cristiano.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 questa la sede per tracciarne la storia, neppure limitatamente agli interpreti della Rivoluzione, dai precursori ottocenteschi fino agli autori che hanno cominciato a scrivere o si sono affermati durante il pontificato di Papa Pio XII come Henri Daniel-Rops, Adrien Dansette, Maurice Vaussard e a contemporanei come Bernard Plongeron.<\/p>\n<p style=\"text-align: justify;\">Pu\u00f2 valere la pena, per contro, di esaminare tre tesi &#8211; o, pi\u00f9 esattamente, miti &#8211; principali, diffuse in particolare negli anni Cinquanta del nostro secolo: il carattere principalmente politico delle persecuzioni religiose rivoluzionarie; una certa rivalutazione della Chiesa Costituzionale; la sottolineatura della partecipazione popolare &#8211; e non solo borghese &#8211; agli avvenimenti rivoluzionari.<\/p>\n<p style=\"text-align: justify;\">Sui primi due aspetti il lavoro analitico di storici recenti sembra chiudere definitivamente le strade per cui si era incamminata la storiografia cattolico-democratica a partire dagli anni Cinquanta.<\/p>\n<p style=\"text-align: justify;\">La tesi secondo cui la Chiesa sarebbe stata perseguitata per ragioni politiche &#8211; cio\u00e8 in quanto &#8220;infeudata&#8221; allo Stato aristocratico-monarchico &#8211; e non per ragioni propriamente religiose &#8211; tesi tuttora diffusa nella letteratura divulgativa &#8211; \u00e8 stata mostrata come semplicemente falsa dall&#8217;analisi della mentalit\u00e0 effettivamente anticristiana e antireligiosa dei grandi promotori delle persecuzioni, e &#8211; sul piano di uno sguardo pi\u00f9 sintetico sul Settecento &#8211; dalla constatazione secondo cui i rapporti fra Stato e Chiesa nel regno di Luigi XVI erano tutt&#8217;altro che idilliaci, tanto da rendere improbabile che le due forze venissero percepite come cos\u00ec indissolubilmente unite nel caso concreto che, per stroncare l&#8217;una, era indispensabile perseguitare l&#8217;altra.<\/p>\n<p style=\"text-align: justify;\">Come abbiamo visto, anche la rivalutazione della Chiesa Costituzionale scismatica &#8211; fenomeno un tempo poco conosciuto, e oggi meglio noto grazie a una serie di studi recenti &#8211; si \u00e8 rivelata un&#8217;operazione totalmente mistificante. Al di l\u00e0 dei dati storici, la &#8220;rivalutazione&#8221; cattolico-democratica rivelava piuttosto esigenze e mentalit\u00e0 tuttora purtroppo presenti nel mondo cattolico: e anche di queste cercher\u00f2 di decifrare il significato. Ma il significato talora emerge a fatica per il calore delle polemiche, che da qualche decennio si agitano anche all&#8217;interno del mondo cattolico.<\/p>\n<p style=\"text-align: justify;\">La polemica ha investito soprattutto il terzo aspetto della &#8220;rivalutazione&#8221;, l&#8217;affermazione di un carattere in qualche modo &#8220;popolare&#8221; della Rivoluzione francese. Da un punto di vista generale, &#8220;popolare&#8221; e &#8220;borghese&#8221; sono etichette tanto vaghe da poter facilmente assumere un carattere pi\u00f9 ideologico che storico.<\/p>\n<p style=\"text-align: justify;\">Scendendo nel dettaglio, la polemica ha investito soprattutto un episodio storicamente minuto ma dal grande significato simbolico, la presa della Bastiglia, e una vicenda ampia e complessa come la guerra di Vandea. La presa della Bastiglia avrebbe dovuto attestare il carattere almeno parzialmente &#8220;popolare&#8221; della Rivoluzione fin dai suoi primi episodi.<\/p>\n<p style=\"text-align: justify;\">Per la sua grande carica simbolica l&#8217;episodio, specie in anni recenti, \u00e8 stato studiato, analizzato, sezionato nei suoi dettagli, e non sono mancate accese discussioni. Si pu\u00f2 credere che, in occasione del bicentenario, le polemiche non mancheranno di riproporsi, anche se in anni recenti sono parse in qualche modo sopite da un buon numero di documenti, che riducono il famosissimo episodio al <em>&#8220;colpo di mano di bande di vagabondi, evasi e disertori&#8221;<\/em> &#8211; fra cui disertori stranieri &#8211; <em>&#8220;alla ricerca di armi&#8221;<\/em> da usare per imprese non necessariamente politiche (40).<\/p>\n<p style=\"text-align: justify;\">Se l&#8217;ultima citazione \u00e8 di uno storico cattolico anti-rivoluzionario, Jean Dumont, nessuno oggi mette in dubbio che la porta della fortezza fu aperta spontaneamente dal governatore, dopo una trattativa, e che nella Bastiglia non si trovava alcun &#8220;prigioniero politico&#8221; da liberare; si discute su chi esattamente abbia partecipato all&#8217;impresa, ma anche un difensore del suo valore simbolico come Jacques Godechot &#8211; uno storico liberale filo-rivoluzionario &#8211; ammetteva, gi\u00e0 in un&#8217;opera del 1965, che il nucleo duro degli assalitori era formato da <em>&#8220;vagabondi, persone senza scrupoli e delinquenti&#8221;<\/em> che, quando successivamente si parl\u00f2 di conferire onori ai <em>&#8220;vincitori della Bastiglia&#8221;<\/em>, <em>&#8220;si guardarono bene <\/em>&#8211; scrive &#8211; <em>di rivendicare il titolo di &#8220;vincitori&#8221; perch\u00e9 rivendicandolo si sarebbero resi noti alla polizia&#8221;<\/em> (41).<\/p>\n<p style=\"text-align: justify;\">Questo non toglie nulla al simbolo &#8211; il cui rapporto con la realt\u00e0 storica \u00e8 di vaga analogia pi\u00f9 spesso di quanto non si creda -, e al genio sinistro dei propagandisti rivoluzionari che trasformano un episodio modesto e ambiguo in un mito nel giro di due giorni; ma toglie tutto al valore della presa della Bastiglia come argomento di prova della partecipazione del &#8220;popolo&#8221; alla Rivoluzione.<\/p>\n<p style=\"text-align: justify;\">Dal punto di vista della mentalit\u00e0, la polemica sulla presa della Bastiglia mostra &#8211; in un modo che non potrebbe essere pi\u00f9 caratteristico &#8211; come i fatti, attraverso un&#8217;interpretazione simbolica, si trasformano in miti che, come ha scritto Alice G\u00e9rard, rispondono soprattutto a un <em>&#8220;bisogno di credere per agire&#8221;<\/em> (42).<\/p>\n<p style=\"text-align: justify;\">Il secondo grande tema polemico, la Vandea, \u00e8 stato rialimentato da episodi recentissimi: senza ricordarle in dettaglio, mi limiter\u00f2 a una brevissima cronologia delle polemiche che hanno preceduto il bicentenario.<\/p>\n<p style=\"text-align: justify;\"><strong>3. La polemica sulla Vandea<\/strong><\/p>\n<p style=\"text-align: justify;\">La nuova letteratura cattolica anti-rivoluzionaria &#8211; che si distingue, per molti versi, da quella ottocentesca, e che tiene conto delle critiche rivolte alla Rivoluzione da autori di tutt&#8217;altra estrazione come Fran\u00e7ois Furet &#8211; trova un primo punto di riferimento significativo nel 1984 con il volume di Jean Dumont, <em>La Rivoluzione francese o i prodigi del sacrilegio<\/em>.<\/p>\n<p style=\"text-align: justify;\">Nel 1986 segue la ricerca universitaria di Fr\u00e9d\u00e9ric Bluche sui massacri che segnano l&#8217;inizio della grande persecuzione: <em>Settembre 1792, logiche di un massacro<\/em>, con la prefazione di uno dei pi\u00f9 noti storici francesi, Jean Tulard, tutt&#8217;altro che anti-rivoluzionario ma pronto a dichiarare che <em>&#8220;era un bene far saltare un altro &#8220;tab\u00f9&#8221; della storia della Rivoluzione francese&#8221;<\/em> (43).<\/p>\n<p style=\"text-align: justify;\">Ma il 1986 \u00e8 soprattutto l&#8217;anno di un altro volume di provenienza universitaria, su cui le polemiche non si sono ancora spente: <em>Il genocidio franco-francese: la Vandea, dipartimento della vendetta<\/em>, di Reynald Secher, pubblicato dalle autorevoli Presses Universitaires de France, e con introduzioni di due storici autorevolissimi come Jean Mayer e Pierre Chaunu (44).<\/p>\n<p style=\"text-align: justify;\">Reynald Secher e Pierre Chaunu sono stati protagonisti dell&#8217;ampia polemica sulla Vandea che ne \u00e8 seguita e che tutt&#8217;ora continua anche all&#8217;interno del mondo cattolico, dove chi rimane attaccato alla tesi della &#8220;rivalutazione&#8221; &#8211; come Bernard Plongeron &#8211; si chiede se fosse opportuno riaprire antiche ferite. Certo, avere riaperto questo capitolo della storia rivoluzionaria non poteva non suscitare passioni accese.<\/p>\n<p style=\"text-align: justify;\">Forse l&#8217;esperienza pi\u00f9 profonda, al di l\u00e0 delle polemiche, \u00e8 quella che cerca di mettersi dalla parte delle vittime, e di comprendere il perch\u00e9 della disperata resistenza vandeana. Da questo punto di vista \u00e8 interessante un intervento nel dibattito, nel 1986, del cardinale Paul Poupard, presidente del Pontificio Consiglio per la Cultura.<\/p>\n<p style=\"text-align: justify;\"><em>&#8220;Contrariamente a quanto la storia ufficiale afferma<\/em> &#8211; scrive il cardinale a proposito della Vandea &#8211; <em>non furono i nobili a sollevarsi e a radunare i contadini, ma furono al contrario i contadini a rifiutarsi di tradire la loro fede e a stanare qualche titubante nobile per chiedergli di porsi alla guida di quella lotta per la fede e per la libert\u00e0&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify;\">Dopo avere cos\u00ec identificato l&#8217;esperienza tragica del popolo vandeano come un&#8217;esperienza religiosa &#8211; anche se non tutto dev&#8217;essere idealizzato, e non mancarono elementi di altro genere e comportamenti non sempre perfetti &#8211; il cardinale non si astiene dall&#8217;elogiare un&#8217;affermazione di mons. Chappoulie, allora vescovo di Angers, che nel 1959 scriveva che se altri celebrano gli eroi rivoluzionari <em>&#8220;i cattolici hanno come eroi della religione i vandeani che affrontarono i soldati della Convenzione&#8221;<\/em>. Dopo aver elogiato il <em>&#8220;magnifico sacrificio&#8221;<\/em> della Vandea, il cardinale Poupard ne mette in luce il significato pi\u00f9 profondo: <em>&#8220;i nostri padri nella fede preferirono perdere la vita piuttosto che rinunciare alle loro ragioni per viverla&#8221;<\/em> (45).<\/p>\n<p style=\"text-align: justify;\"><strong>4. Altre ierofanie: le esperienze religiose degli studiosi cattolici della Rivoluzione<\/strong><\/p>\n<p style=\"text-align: justify;\">Qual&#8217;\u00e8 &#8211; o com&#8217;\u00e8 &#8211; l&#8217;esperienza religiosa degli storici e degli intellettuali cattolici che, in quanto tali, affrontano lo studio ed esprimono giudizi sulla Rivoluzione francese?<\/p>\n<p style=\"text-align: justify;\">Alla luce di questa domanda diventa interessante prendere in considerazione anche le polemiche che oggi si agitano intorno al secondo centenario della Rivoluzione, importanti in Francia dove &#8211; occorre ricordarlo &#8211; da anni non \u00e8 pi\u00f9 presente un partito democristiano per cui la polemica sul cattolicesimo democratico e le sue correnti, che in altri paesi assume un tono direttamente politico, pi\u00f9 frequentemente si svolge sul piano culturale e storico.<\/p>\n<p style=\"text-align: justify;\">Una prima esperienza religiosa da esaminare \u00e8 quella degli storici cattolico-democratici che, soprattutto negli anni Cinquanta, hanno intrapreso una certa &#8220;rivalutazione&#8221; della Rivoluzione, e la cui influenza culturale arriva fino ai nostri giorni. Anzitutto va segnalato il carattere cruciale del giudizio sulla Rivoluzione nel loro modo di percepire la religione, la cultura e l&#8217;intera storia europea moderna.<\/p>\n<p style=\"text-align: justify;\">Per questo tipo di intellettuale cattolico-democratico un certo giudizio sulla Rivoluzione rappresenta non un elemento accessorio o secondario, ma l&#8217;essenziale. La cultura liberale pu\u00f2 fare a meno della Rivoluzione francese e ricordare &#8211; come faceva in Italia uno storico antifascista, Maranini &#8211; che il patrimonio dei liberali punta spesso pi\u00f9 sulle <em>&#8220;vere libert\u00e0 anglosassoni&#8221; <\/em>che sulle <em>&#8220;false libert\u00e0 francesi&#8221;<\/em> (46).<\/p>\n<p style=\"text-align: justify;\">Finiti i tempi romantici in cui il regista Jean Renoir faceva finanziare il suo <em>film<\/em> <em>La Marsigliese<\/em> da una sottoscrizione pubblica del sindacato socialcomunista CGT, nel 1937, oggi anche la cultura di origine marxista sembra talora &#8211; non sempre &#8211; poter fare a meno della Rivoluzione.<\/p>\n<p style=\"text-align: justify;\">Dopo tutto, pu\u00f2 sempre ricordare che Gracco Babeuf, il &#8220;grande antenato&#8221; dei marxisti nella Rivoluzione, fu fra i pochi &#8211; in un testo ripubblicato proprio da Reynald Secher &#8211; a levarsi contro la repressione in Vandea, denunciandola, di fronte ai suoi stessi responsabili, nel 1794, come un autentico genocidio. Dal punto di vista culturale \u00e8 stato uno storico di origine socialista, Fran\u00e7ois Furet, forse il maggiore conoscitore attuale del periodo rivoluzionario, a iniziare un riesame severamente critico della Rivoluzione francese (47).<\/p>\n<p style=\"text-align: justify;\">La Rivoluzione francese sembra quindi pi\u00f9 essenziale all&#8217;immaginario cattolico-democratico di quanto non sia, rispettivamente, all&#8217;immaginario liberale e socialista. Lo storico del cattolicesimo democratico Maurice Vaussard &#8211; egli stesso interprete della Rivoluzione &#8211; trova il precursore di questa corrente in Philippe-Joseph-Benjamin Buchez, un autore che si era spinto fino a sostenere l&#8217;identit\u00e0 fra princ\u00ecpi della Rivoluzione e princ\u00ecpi del Vangelo (48).<\/p>\n<p style=\"text-align: justify;\">Gli autori della scuola cattolico-democratica comprendono la loro esperienza della Rivoluzione nei termini di quello che l&#8217;antropologia classica della religione chiamerebbe un rito di passaggio: una parte non sufficientemente matura della trib\u00f9 \u2014 i cattolici \u2014 \u00e8 esclusa simbolicamente dal gruppo sociale \u2014 il mondo moderno \u2014 per esservi pi\u00f9 tardi \u2014 e sempre simbolicamente \u2014 riammessa a pieno titolo, una volta riconosciuta la sua maturazione.<\/p>\n<p style=\"text-align: justify;\">Questa percezione della Rivoluzione costituisce il nucleo dell&#8217;esperienza dei cattolico-democratici, ma la differenza con il rito di passaggio classico \u00e8 che in quest&#8217;ultimo la violenza su chi deve &#8220;maturare&#8221; \u00e8 puramente simbolica, mentre orrori come quelli della repressione in Vandea ricordano il carattere tutt&#8217;altro che simbolico della violenza che la Rivoluzione ha esercitato sui credenti.<\/p>\n<p style=\"text-align: justify;\">Pi\u00f9 che un <em>rito di passaggio<\/em>, la Rivoluzione francese pare allora per i cattolici-democratici un <em>mito di origine<\/em>, una potente risposta a quel bisogno di <em>&#8220;credere per agire&#8221;<\/em> a cui ho fatto cenno. Al cuore di questo bisogno si situa un desiderio fuorviato di unit\u00e0 e di riconciliazione. Nel citato discorso al Parlamento Europeo a Strasburgo, Papa Giovanni Paolo II descrive la <em>&#8220;tensione costante&#8221;<\/em> fra la fede e le sue manifestazioni pubbliche, e l&#8217;irreligione e le sue manifestazioni non meno pubbliche, che si \u00e8 venuta a determinare nell&#8217;Europa moderna.<\/p>\n<p style=\"text-align: justify;\">Questa tensione, che trova una parte importante delle sue origini nella Rivoluzione francese, pu\u00f2 essere facilmente avvertita come eccessiva o anche come intollerabile. Il desiderio di unit\u00e0 \u2014 che ha come sfondo l&#8217;unit\u00e0 originaria e ultima del genere umano \u2014 \u00e8 del resto una componente genuina dell&#8217;esperienza religiosa.<\/p>\n<p style=\"text-align: justify;\">Ma, per chi assume la rivalutazione della Rivoluzione come mito di origine, il desiderio di unit\u00e0 diventa ricerca di presunti <em>&#8220;valori comuni&#8221;<\/em>, che dovrebbero poter unire tutti gli uomini al di l\u00e0 delle loro persuasioni filosofiche o religiose e superare il dramma della <em>&#8220;tensione costante&#8221;<\/em>. Altri obbiettano giustamente che \u2014 precisamente dopo la Rivoluzione francese \u2014 i <em>&#8220;valori comuni&#8221;<\/em> non ci sono pi\u00f9, perch\u00e9 la Rivoluzione con la sua radicalit\u00e0 li ha distrutti oppure sono talmente generici da essere ormai scarsamente significativi.<\/p>\n<p style=\"text-align: justify;\">Per comprendere, in ogni caso, l&#8217;esperienza dei cattolici-democratici e le sue contraddizioni, che oggi ne determinano la crisi, \u00e8 importante cercare di coglierne il nucleo essenziale: superare la tensione \u2014 che si manifesta nella Rivoluzione in modo eminente \u2014 cercando di &#8220;sdrammatizzare&#8221; la storia, cio\u00e8 \u2014 letteralmente \u2014 di sottolinearne il meno possibile il carattere drammatico.<\/p>\n<p style=\"text-align: justify;\">Se esaminiamo l&#8217;<em>altra<\/em> esperienza, quella degli storici e degli intellettuali cattolici tenden-zialmente critici nei confronti della Rivoluzione e anti-rivoluzionari \u2014 non sempre contro-rivoluzionari, questa seconda espressione avendo assunto un significato tecnico per designare una scuola particolare \u2014, ci troviamo di fronte a un atteggiamento esattamente opposto proprio quanto alla drammaticit\u00e0 della storia.<\/p>\n<p style=\"text-align: justify;\">Chi sottolinea i contrasti \u2014 talora pi\u00f9 che le sfumature \u2014 nel mondo della Rivoluzione francese muove, in genere, da una visione storica che assume il dramma e lo integra in un&#8217;esperienza religiosa, secondo la teologia della storia della due citt\u00e0 di sant&#8217;Agostino, delle due bandiere di sant&#8217;Ignazio di Loyola, delle due stirpi di uomini di san Luigi Maria Grignion di Montfort, un santo di cui si dice spesso che prepar\u00f2 la resistenza della Vandea, dove predic\u00f2 a lungo, pur essendo morto prima della Rivoluzione.<\/p>\n<p style=\"text-align: justify;\">Si tratta di una risposta tutt&#8217;altro che sorprendente alla <em>&#8220;tensione costante&#8221;<\/em> che percorre ogni epoca storica, ma che si rivela particolarmente nel mondo moderno, dove anche il Magistero sottolinea \u2014 per usare un&#8217;espressione di Papa Giovanni Paolo II \u2014 l&#8217;<em>&#8220;innegabile contrasto di posizioni radicalmente opposte&#8221; <\/em>(49).<\/p>\n<p style=\"text-align: justify;\">Si tratta, ancora, di un modo di atteggiarsi di fronte al fenomeno del pluralismo dottrinale, la cui rilevanza ho gi\u00e0 pi\u00f9 volte ricordato. Non si tratta di un rifiuto di prendere in considerazione il pluralismo come fatto: rifiuto che caratterizza un atteggiamento &#8220;integralista&#8221; \u2014 ancora nel senso definito da Papa Giovanni Paolo II nel ricordato discorso 1988 a Strasburgo \u2014 che si comporta, e chiede alla Chiesa di comportarsi, come se il pluralismo dottrinale non esistesse, e spesso \u2014 contemporaneamente \u2014 idealizza in modo romantico il periodo immediatamente precedente alla Rivoluzione, creando a sua volta altri miti.<\/p>\n<p style=\"text-align: justify;\">Questa posizione \u2014 che era stata della Petite \u00c9glise \u2014 si ritrova nell&#8217;atteggiamento, anche a proposito della storia, dei seguaci del comportamento scismatico lefebvriano, di cui la Rivoluzione francese costituisce spesso un cavallo di battaglia. Ma \u00e8 un atteggiamento che non appartiene certamente al cuore dell&#8217;esperienza religiosa della parte maggiore dei cattolici che, guardando verso il passato e verso la Rivoluzione francese, la leggono in modo duramente critico.<\/p>\n<p style=\"text-align: justify;\">Essi non rifiutano di assumere la modernit\u00e0 \u2014 il cui elemento essenziale \u00e8 il pluralismo dottrinale \u2014 come fatto; rifiutano piuttosto di fare della modernit\u00e0 un ideale. Rifiutare il fatto vorrebbe dire, anzi, togliere vigore al dramma, che in questo caso \u00e8 elemento centrale di un&#8217;esperienza religiosa che non &#8220;sdrammatizza&#8221; la storia ma che, al contrario, ritiene che solo assumendo il dramma e prendendo atto della sua esistenza sia possibile reperire soluzioni per vivere \u2014 e collaborare con gli altri uomini \u2014 nella situazione di <em>&#8220;tensione costante&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify;\">La diversit\u00e0 di interpretazioni della Rivoluzione francese proposte dai cattolici svela dunque il significato di diverse esperienze religiose, e da ultimo l&#8217;alternativa fra due possibili teologie della storia. In questo contesto togliere alla storia \u2014 e in particolare alla storia moderna, che ha il suo momento emblematico nella Rivoluzione francese \u2014 il suo carattere drammatico e alternativo significa, semplicemente, rinunciare a quella teologia cristiana della storia che fonda, fra l&#8217;altro, la dottrina sociale della Chiesa.<\/p>\n<p style=\"text-align: justify;\">Ci aiuta a capire, conclusivamente, tutta la forza del dramma storico un passo, non recentissimo, del Magistero: <em>&#8220;Il grande problema posto davanti al mondo<\/em> \u2014 secondo questo testo \u2014 <em>dopo quasi due millenni, resta immutato. Il Cristo, sempre splendente \u00e8 al centro della storia e della vita; gli uomini o sono con Lui e con la Sua Chiesa, e allora godono della luce, della bont\u00e0, dell&#8217;ordine e della pace;<\/em> oppure<em> sono senza di Lui, o contro di Lui, e deliberatamente contro la Sua Chiesa: divengono motivo di confusione, causando asprezza di umani rapporti e persistenti pericoli di guerre fratricide&#8221;<\/em>. L&#8217;autore di questo testo \u00e8 Papa Giovanni XXIII, l&#8217;occasione l&#8217;<em>&#8220;allocuzione nel solennissimo rito di apertura del Concilio Ecumenico Vaticano II&#8221;<\/em> (50).<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=3898\" target=\"_blank\"><strong>vai alle note<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=1034\" target=\"_blank\"><strong>torna all&#8217;indice<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>dal sito di Alleanza Cattolica \u00a0di Massimo Introvigne<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,44,37,24],"tags":[157,264,457,162],"class_list":["post-3285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-cristiani-perseguitati","category-rivoluzione-francese","category-storia","tag-chiesa-2","tag-persecuzioni","tag-rivoluzione-francese-2","tag-storia-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Religione e Rivoluzione francese (2) - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Religione e Rivoluzione francese (2) - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-06T13:54:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-22T08:48:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/Rivol_Fr_preti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"176\" \/>\n\t<meta property=\"og:image:height\" content=\"173\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Religione e Rivoluzione francese (2)\",\"datePublished\":\"2009-05-06T13:54:44+00:00\",\"dateModified\":\"2016-02-22T08:48:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/\"},\"wordCount\":3051,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/Rivol_Fr_preti.jpg\",\"keywords\":[\"chiesa\",\"persecuzioni\",\"Rivoluzione Francese\",\"storia\"],\"articleSection\":[\"Chiesa\",\"Cristiani perseguitati\",\"Rivoluzione francese\",\"Storia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/\",\"name\":\"Religione e Rivoluzione francese (2) - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/Rivol_Fr_preti.jpg\",\"datePublished\":\"2009-05-06T13:54:44+00:00\",\"dateModified\":\"2016-02-22T08:48:20+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/Rivol_Fr_preti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/Rivol_Fr_preti.jpg\",\"width\":176,\"height\":173},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/religione-e-rivoluzione-francese-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Religione e Rivoluzione francese (2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Religione e Rivoluzione francese (2) - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/","og_locale":"it_IT","og_type":"article","og_title":"Religione e Rivoluzione francese (2) - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-05-06T13:54:44+00:00","article_modified_time":"2016-02-22T08:48:20+00:00","og_image":[{"width":176,"height":173,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/Rivol_Fr_preti.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Religione e Rivoluzione francese (2)","datePublished":"2009-05-06T13:54:44+00:00","dateModified":"2016-02-22T08:48:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/"},"wordCount":3051,"commentCount":0,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/Rivol_Fr_preti.jpg","keywords":["chiesa","persecuzioni","Rivoluzione Francese","storia"],"articleSection":["Chiesa","Cristiani perseguitati","Rivoluzione francese","Storia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/","name":"Religione e Rivoluzione francese (2) - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/Rivol_Fr_preti.jpg","datePublished":"2009-05-06T13:54:44+00:00","dateModified":"2016-02-22T08:48:20+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/Rivol_Fr_preti.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/Rivol_Fr_preti.jpg","width":176,"height":173},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/religione-e-rivoluzione-francese-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Religione e Rivoluzione francese (2)"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3285"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3285\/revisions"}],"predecessor-version":[{"id":30786,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3285\/revisions\/30786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30782"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}