{"id":3264,"date":"2009-05-06T09:03:11","date_gmt":"2009-05-06T07:03:11","guid":{"rendered":""},"modified":"2015-12-21T13:55:03","modified_gmt":"2015-12-21T12:55:03","slug":"quellansia-nichilistica-di-negare-padre-e-madre","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/","title":{"rendered":"Quell\u2019ansia nichilistica di negare &#8220;padre&#8221; e &#8220;madre&#8221;"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/genitore-1-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-28966\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/genitore-1-2.jpg\" alt=\"genitore 1-2\" width=\"200\" height=\"120\" \/><\/a>Avvenire,<\/strong> 1 febbraio 2008<\/div>\n<p style=\"text-align: center;\"><em>Le ultime dall&#8217;Inghilterra degli esperimenti<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Marina Corradi<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Nelle scuole britanniche non si potr\u00e0 pi\u00f9 dire &#8216;mamma&#8217; e &#8216;pap\u00e0. Il ministero della Istruzione prepara una direttiva in questo senso. Si potr\u00e0 dire soltanto &#8216;genitori&#8217;, per rispetto di quegli alunni che si trovino ad avere a casa una coppia di madri lesbiche, o una coppia di padri gay, o ogni altra di quelle declinazioni di &#8216;famiglie&#8217;, rigorosamente al plurale, di cui la Gran Bretagna \u00e8 antesignana e maestra.<\/div>\n<p style=\"text-align: justify;\">Due anni fa and\u00f2 sui tabloid inglesi la storia di una coppia gay in cui un partner, in procinto di diventare chirurgicamente donna, congel\u00f2 il proprio seme per potere essere biologicamente padre grazie a una donna che &#8216;prestasse&#8217; il suo utero. Una situazione ingarbugliata per il nascituro: pap\u00e0 e la donna che lui chiama mamma erano la stessa persona. Per evitare, in questa crescente complessit\u00e0, traumi ai ragazzini dunque il Ministero taglia la testa al toro: di dice &#8216;genitori&#8217;, e basta, mai pi\u00f9 padre e madre.<\/p>\n<p style=\"text-align: justify;\">Ricordarsi di Huxley \u00e8 inevitabile: quella parola, &#8216;mamma&#8217;, che ne &#8216;Il mondo nuovo&#8217; genera pudichi gridolini di orrore &#8211; come di dame vittoriane davanti a qualcosa di sconveniente \u00adperch\u00e9 quel mondo nuovo i figli li fabbrica con una catena di montaggio, e l\u2019idea di una procreazione carnale s\u2019\u00e8 fatta indecente. Ma l\u2019editto del Ministero non ce l\u2019ha solo o tanto con la mamma, ma anche e altrettanto con il pap\u00e0.<\/p>\n<p style=\"text-align: justify;\">Anzi, forse di pi\u00f9. Il padre, alla cultura del &#8216;gender&#8217; &#8211; cio\u00e8 della identit\u00e0 sessuale definita come pura scelta culturale, e non come dato originario &#8211; risulta ancora pi\u00f9 antipatico della mamma. Il padre \u00e8 archetipo di autorit\u00e0 e autorevolezza, e dunque di maschilismo.<\/p>\n<p style=\"text-align: justify;\">Il padre va spazzato via: concretamente &#8211; come in quel sito web inglese &#8216;Man not included&#8217;, &#8216;Uomo non incluso&#8217;, che vendeva on line seme anonimo per aspiranti madri autarchiche; e anche culturalmente, e perfino spiritualmente. La nuova versione del Nuovo testamento dell\u2019Universit\u00e0 di Oxford, &#8211; il faro della cultura occidentale &#8211; cos\u00ec trascrive il Padre Nostro: &#8216;Padre\/Madre nostra che sei nei cieli&#8217;.<\/p>\n<p style=\"text-align: justify;\">Oppure, Ges\u00f9 ai genitori, nel Tempio: &#8216;Perch\u00e9 mi cercate? Non sapevate che io ero nella casa del Padre\/Madre?&#8217; La &#8216;grida&#8217; del Ministero per l\u2019Istruzione britannico pu\u00f2 fare sorridere. E per\u00f2, dietro l\u2019idiozia di pensare di proibire ai ragazzi di dire &#8216;mamma&#8217;, sta, sotto le garbate apparenze del politically correct, una pretesa dura e brutale.<\/p>\n<p style=\"text-align: justify;\">Non dite madre, non dite padre, questi sono stereotipi, ruoli imposti da una tradizione oscurantista. Nel nuovo mondo la cultura del &#8216;gender&#8217; disfa tutto: le madri non sono necessariamente donne, i padri non sono obbligatoriamente uomini, e di padri se ne pu\u00f2 avere due e di madri nessuna, o viceversa, a piacere &#8211; a piacere, si intende, non dei figli, ma di chi pi\u00f9 o meno naturalmente li mette al mondo.<\/p>\n<p style=\"text-align: justify;\">Dall\u2019articolo 124 comma k della Piattaforma di Pechino: &#8216;Adottare tutte le misure appropriate, soprattutto nel campo della istruzione, per modificare i modelli di comportamento di uomini e donne, e per eliminare i pregiudizi e le pratiche tradizionali&#8217;, &#8216;basate su ruoli stereotipati maschili e femminili&#8217;.<\/p>\n<p style=\"text-align: justify;\">E ci siamo, il Pechino-pensiero s\u2019affaccia nelle scuole. Il nemico vero da abbattere \u00e8 l\u2019idea che uomo e donna, e dunque padre e madre siano identit\u00e0 originarie e anteriori. Qualcosa di &#8216;dato&#8217; da un ordine creatore. Che ci sia un &#8216;prima&#8217; a definirci, e non solo la cultura e la storia e le scelte personali.<\/p>\n<p style=\"text-align: justify;\">L\u2019ostilit\u00e0 al &#8216;dato&#8217;, scrisse Hannah Arendt, \u00e8 un segno distintivo della modernit\u00e0. E quindi l\u2019ansia rancorosa di negare quel &#8216;Maschio e femmina li cre\u00f2&#8217;. Ora istruiscono i bambini: mamma e pap\u00e0, non si dice. Sar\u00e0 difficile per\u00f2 educarli bene fin da piccoli. A cinque anni, hanno ancora scritta addosso chiara una domanda. Di una madre, di un padre, di un disegno, di crescere &#8211; di continuare.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avvenire, 1 febbraio 2008 Le ultime dall&#8217;Inghilterra degli esperimenti di Marina Corradi<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":28966,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[437],"class_list":["post-3264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ideologia-del-gender","tag-ideologia-del-gender-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quell\u2019ansia nichilistica di negare &quot;padre&quot; e &quot;madre&quot; - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quell\u2019ansia nichilistica di negare &quot;padre&quot; e &quot;madre&quot; - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-06T07:03:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-21T12:55:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/genitore-1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"290\" \/>\n\t<meta property=\"og:image:height\" content=\"174\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Quell\u2019ansia nichilistica di negare &#8220;padre&#8221; e &#8220;madre&#8221;\",\"datePublished\":\"2009-05-06T07:03:11+00:00\",\"dateModified\":\"2015-12-21T12:55:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/\"},\"wordCount\":650,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/genitore-1-2.jpg\",\"keywords\":[\"ideologia del gender\"],\"articleSection\":[\"Ideologia del gender\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/\",\"name\":\"Quell\u2019ansia nichilistica di negare \\\"padre\\\" e \\\"madre\\\" - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/genitore-1-2.jpg\",\"datePublished\":\"2009-05-06T07:03:11+00:00\",\"dateModified\":\"2015-12-21T12:55:03+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/genitore-1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/genitore-1-2.jpg\",\"width\":290,\"height\":174},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quellansia-nichilistica-di-negare-padre-e-madre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quell\u2019ansia nichilistica di negare &#8220;padre&#8221; e &#8220;madre&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quell\u2019ansia nichilistica di negare \"padre\" e \"madre\" - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/","og_locale":"it_IT","og_type":"article","og_title":"Quell\u2019ansia nichilistica di negare \"padre\" e \"madre\" - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-05-06T07:03:11+00:00","article_modified_time":"2015-12-21T12:55:03+00:00","og_image":[{"width":290,"height":174,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/genitore-1-2.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Quell\u2019ansia nichilistica di negare &#8220;padre&#8221; e &#8220;madre&#8221;","datePublished":"2009-05-06T07:03:11+00:00","dateModified":"2015-12-21T12:55:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/"},"wordCount":650,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/genitore-1-2.jpg","keywords":["ideologia del gender"],"articleSection":["Ideologia del gender"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/","name":"Quell\u2019ansia nichilistica di negare \"padre\" e \"madre\" - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/genitore-1-2.jpg","datePublished":"2009-05-06T07:03:11+00:00","dateModified":"2015-12-21T12:55:03+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/genitore-1-2.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/genitore-1-2.jpg","width":290,"height":174},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quellansia-nichilistica-di-negare-padre-e-madre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Quell\u2019ansia nichilistica di negare &#8220;padre&#8221; e &#8220;madre&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3264"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3264\/revisions"}],"predecessor-version":[{"id":28967,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3264\/revisions\/28967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/28966"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}