{"id":3247,"date":"2009-05-05T16:10:51","date_gmt":"2009-05-05T14:10:51","guid":{"rendered":""},"modified":"2015-11-17T15:45:23","modified_gmt":"2015-11-17T14:45:23","slug":"perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/","title":{"rendered":"Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no?"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/prematuro.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-27788\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/prematuro.jpg\" alt=\"prematuro\" width=\"240\" height=\"180\" \/><\/a>L\u2019Occidentale<\/strong>,\u00a0 5 Febbraio 2008<\/div>\n<p style=\"text-align: center;\">di <strong>Carlo Bellieni<\/strong><\/p>\n<p style=\"text-align: justify;\">Il documento dei ginecologi di Roma non fa altro che riaffermare un semplice principio, condiviso da tutti: se un bambino nasce, va curato. Punto. Non \u00e8 una cosa rivoluzionaria, dato che lo diceva Ippocrate 3000 anni fa. Non \u00e8 nemmeno una forzatura, dato che i medici continuano a farlo tutti i giorni. Eppure scandalizza: perch\u00e9?<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Perch\u00e9 in qualche caso si tratta di gravidanze volontariamente interrotte? Ma il documento non parla di queste che marginalmente e la possibilit\u00e0 che un bambino nasca vivo e rianimabile da aborto non \u00e8 permessa dalla legge 194 (tranne ristretti casi di aborto per pericolo di vita), dunque non \u00e8 questo il punto. In realt\u00e0 il documento afferma il principio che con il progresso medico aumenta il numero di bambini che si pu\u00f2 tentare di curare. E che non si possono mettere paletti dettati da nostri criteri soggettivi per decidere chi pu\u00f2 ricevere assistenza.<\/div>\n<p style=\"text-align: justify;\">I ginecologi romani non hanno fatto altro che applicare l\u2019antica e attuale deontologia medica, consci che in alcuni Paesi si tende a limitare\u00a0 la possibilit\u00e0 di assistere i neonati sotto una certa soglia di tempo dal concepimento, senza che questa coincida con le possibilit\u00e0 offerte dalla medicina di sopravvivere (oggi fissata a 22 settimane di gestazione).<\/p>\n<p style=\"text-align: justify;\">Qualcuno potrebbe dire: accudendo certi bambini in alcuni casi si va contro l\u2019autodeterminazione della coppia. Ma fin dove arriva l\u2019autodeterminazione, se il bambino dal primo respiro diventa un cittadino italiano con pari diritti di ciascun altro cittadino?<\/p>\n<p style=\"text-align: justify;\">Qualcun altro dir\u00e0: il bambino avr\u00e0 serie possibilit\u00e0 di non sopravvivere essendo estremamente prematuro, o di riportare disabilit\u00e0. Su questo dobbiamo essere molto chiari, perch\u00e9 la scienza sta facendo passi da gigante in questo settore e cose che sembravano impossibili vent\u2019anni fa oggi non lo sono.<\/p>\n<p style=\"text-align: justify;\">A 22 settimane di gestazione sopravvive circa 1 bambino su 10, e a 23 ne sopravvive 1 su 4. Non ci sembrano percentuali basse per non dare una chance, per non provarci. Al massimo si tratta di uno sforzo inutile. Ma, dato che \u2013si badi bene- alla nascita non abbiamo assolutamente strumenti n\u00e9 clinici n\u00e9 tecnici per capire se quel singolo bambino che abbiamo davanti \u00e8 quello che si salver\u00e0 o quello che non ce la far\u00e0, dalle 22 settimane di gestazione dobbiamo dare una chance a tutti.<\/p>\n<p style=\"text-align: justify;\">La stessa indeterminazione vale per l\u2019handicap, che potr\u00e0 colpire o non colpire, che sar\u00e0 \u2013quando presente- di varie entit\u00e0, e\u00a0 soprattutto che alla nascita non abbiamo mezzi per prevedere. E togliamoci dalla testa che la vita dei disabili sia una vita \u201cingiusta\u201d, che non merita di essere vissuta, perch\u00e9 seri studi mostrano che la qualit\u00e0 di vita riferita dai disabili (per esempio dagli ex prematuri o dai portatori di spina bifida) \u00e8 pari a quella degli altri: sembra paradossale, ma \u00e8 proprio cos\u00ec: la felicit\u00e0 personale non dipende dalla malattia o dal successo civile, ma dall\u2019ambiente, da come siamo amati.<\/p>\n<p style=\"text-align: justify;\">Certo, la malattia \u00e8 fatica e dolore; ma a fatica e dolore la societ\u00e0 non pu\u00f2 rispondere lasciando le donne sole di fronte alla scelta tra vita e morte\u2026 e arrivederci. Ed \u00e8 singolare che in questi giorni sui giornali si sia tanto discusso su chi deve vivere e poco su cosa fare per accogliere, per le famiglie, per i disabili, per le barriere architettoniche, pregiudizi, bullismo.<\/p>\n<p style=\"text-align: justify;\">Ha da poco compiuto 18 anni James Gill un ragazzo nato dopo 22 settimane di gestazione; in Giappone la legge, visti i progressi scientifici, si \u00e8 adeguata spostando gi\u00e0 negli anni \u201890 il limite per l\u2019aborto da 24 a 22 settimane. Non ci sembra di chiedere molto: adeguarsi alla medicina, dare una chance a tutti, non dare ai genitori la croce di una decisione che non spetta a considerazioni soggettive prendere.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Occidentale,\u00a0 5 Febbraio 2008 di Carlo Bellieni Il documento dei ginecologi di Roma non fa altro che riaffermare un semplice principio, condiviso da tutti: se un bambino nasce, va curato. Punto. Non \u00e8 una cosa rivoluzionaria, dato che lo diceva Ippocrate 3000 anni fa. Non \u00e8 nemmeno una forzatura, dato che i medici continuano a &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27788,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,4],"tags":[1246],"class_list":["post-3247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","category-bioetica","tag-cure-neonatali","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no? - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no? - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-05T14:10:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-17T14:45:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/prematuro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no?\",\"datePublished\":\"2009-05-05T14:10:51+00:00\",\"dateModified\":\"2015-11-17T14:45:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/\"},\"wordCount\":615,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/prematuro.jpg\",\"keywords\":[\"cure neonatali\"],\"articleSection\":[\"Aborto\",\"Bioetica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/\",\"name\":\"Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no? - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/prematuro.jpg\",\"datePublished\":\"2009-05-05T14:10:51+00:00\",\"dateModified\":\"2015-11-17T14:45:23+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/prematuro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/prematuro.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no? - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/","og_locale":"it_IT","og_type":"article","og_title":"Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no? - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-05-05T14:10:51+00:00","article_modified_time":"2015-11-17T14:45:23+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/prematuro.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no?","datePublished":"2009-05-05T14:10:51+00:00","dateModified":"2015-11-17T14:45:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/"},"wordCount":615,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/prematuro.jpg","keywords":["cure neonatali"],"articleSection":["Aborto","Bioetica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/","name":"Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no? - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/prematuro.jpg","datePublished":"2009-05-05T14:10:51+00:00","dateModified":"2015-11-17T14:45:23+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/prematuro.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/prematuro.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-alcuni-bimbi-hanno-diritto-alla-vita-e-altri-no\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Perch&eacute; alcuni bimbi hanno diritto alla vita e altri no?"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3247"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3247\/revisions"}],"predecessor-version":[{"id":27789,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3247\/revisions\/27789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27788"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}